{"id":79342,"date":"2020-07-13T12:09:24","date_gmt":"2020-07-13T12:09:24","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2020\/07\/13\/covid19-et-la-rebellion-du-temps\/"},"modified":"2020-07-13T12:09:24","modified_gmt":"2020-07-13T12:09:24","slug":"covid19-et-la-rebellion-du-temps","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2020\/07\/13\/covid19-et-la-rebellion-du-temps\/","title":{"rendered":"Covid19 et la \u201cr\u00e9bellion du temps\u201d"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Covid19 et la \u00ab\u00a0r\u00e9bellion du temps\u00a0\u00bb<\/h2>\n<\/p>\n<p><p>13 juillet 2020 &ndash; Jeudi dernier, sur CNN, le maire de New York City, Bill de Blasio, fit &laquo; <em><a href=\"https:\/\/www.zerohedge.com\/political\/de-blasio-says-blm-protests-can-continue-while-canceling-all-other-large-events\">quelques remarques surprenantes<\/a>, d\u00e9clarant que les manifestations de protestation dans les rues<\/em> [attention, uniquement des BLM] <em>sont parfaitement autoris\u00e9es, tout en annon\u00e7ant l&rsquo;interdiction des \u00e9v\u00e9nements de foule jusqu&rsquo;en septembre<\/em> &raquo;. Bien entendu, il s&rsquo;agit de la <a href=\"https:\/\/fr.wikipedia.org\/wiki\/D\u00e9fense_en_h\u00e9risson\">d\u00e9fense en h\u00e9risson<\/a> contre Covid19, qui est le producteur et le manufacturier-complotiste d&rsquo;une relance particuli\u00e8rement forte de la pand\u00e9mie du coronavirus aux USA, depuis autour de deux semaines.<\/p>\n<\/p>\n<p><p>C&rsquo;est aussi aux USA que la crise du Covid19 est le plus radicalement \u00ab\u00a0politis\u00e9e\u00a0\u00bb sinon \u00ab\u00a0id\u00e9ologis\u00e9e\u00a0\u00bb, comme le montre la d\u00e9cision de Blasio impliquant que parce que l&rsquo;on proteste contre le racisme au nom des <em>Black Lives Matter<\/em>, on est immunis\u00e9 contre le virus. Cette id\u00e9e devrait d&rsquo;ailleurs \u00eatre plus r\u00e9pandue, permettant de lutter contre deux fl\u00e9aux \u00ab\u00a0de Dieu &#038; Compagnie\u00a0\u00bb \u00e0 la fois : la pand\u00e9mie et le racisme. Cette \u00ab\u00a0politisation\u00a0\u00bb\/\u00a0\u00bbid\u00e9ologisation\u00a0\u00bb est bien r\u00e9sum\u00e9e par Alexis Toulet dans <em><a href=\"https:\/\/lesakerfrancophone.fr\/coronavirus-etats-unis-vers-une-extension-de-la-catastrophe-ou-le-refus-de-regarder-la-realite-en-face\">Le Sakerfrancophone<\/a><\/em> :<\/p>\n<\/p>\n<p><p>&laquo; <em>En caricaturant \u00e0 peine, si l&rsquo;on parle de confinement et de distanciation :<\/em><\/p>\n<p>&raquo; <em>&bull; Une partie des gens de droite r\u00e9pondra \u00ab\u00a0Pas question, \u00e7a interf\u00e8re avec la libert\u00e9, et d&rsquo;ailleurs \u00e0 quoi serviraient masques et gel contre ce virus transmis par la 5G comme chacun sait, tout \u00e7a est antipatriotique<\/em> <em>!\u00a0\u00bb<\/em><\/p>\n<p>&raquo; <em>&bull; Pendant qu&rsquo;une partie des gens de gauche r\u00e9pondra \u00ab\u00a0Pas question, \u00e7a interf\u00e8re avec la justice raciale, et d&rsquo;ailleurs vous \u00eates coupable vous aussi, venez manifester et vous repentir avec nous, sinon c&rsquo;est que vous devez \u00eatre raciste\u00a0\u00bb.<\/em><\/p>\n<p>&raquo; <em>On objectera peut-\u00eatre que ce sont l\u00e0 des positions extr\u00eames et extr\u00e9mistes. Peut-\u00eatre, mais tout se passe comme si c&rsquo;\u00e9taient celles-l\u00e0 qui avaient droit de cit\u00e9 les premi\u00e8res, et qui d\u00e9terminaient l&rsquo;action &ndash; ou plut\u00f4t l&rsquo;inaction &ndash; des politiques.<\/em><\/p>\n<p>&raquo; <em>Comment lutter contre une \u00e9pid\u00e9mie<\/em> <em>? Solution de la gauche am\u00e9ricaine : des manifestations de masse \u00e0 r\u00e9p\u00e9tition dans tout le pays. Solution de la droite am\u00e9ricaine : meeting de campagne dans un endroit ferm\u00e9 et les masques c&rsquo;est antipatriotique<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>D&rsquo;une fa\u00e7on plus g\u00e9n\u00e9rale, on peut appr\u00e9cier, je crois, que la pand\u00e9mie Covid19 est l&rsquo;\u00e9v\u00e9nement qui est l&rsquo;objet du plus grand nombre de th\u00e8mes diff\u00e9rents du complotisme, et venant de tous les horizons, du Syst\u00e8me et de soi-disant antiSyst\u00e8me, de d\u00e9nonciateurs du complotisme comme de croyants du complotisme, etc. L\u00e0 aussi, il y a une \u00ab\u00a0politisation\u00a0\u00bb et une id\u00e9ologisation\u00a0\u00bb qui d\u00e9passent largement, pour le coup, celles qu&rsquo;on identifie aux USA (et cela, bien entendu, avec le fait que les USA restent les plus gros consommateurs de complotisme dans tous les sens).<\/p>\n<\/p>\n<p><p>L&rsquo;effet obtenu est une sorte de tourbillon crisique acc\u00e9l\u00e9r\u00e9 et prenant des formes diff\u00e9rentes, sem\u00e9 de fractures (un \u00ab\u00a0<a href=\"https:\/\/www.dedefensa.org\/article\/un-temps-fractal\">temps fractal<\/a>\u00ab\u00a0) et suscitant dans la psychologie un \u00ab\u00a0vertige crisique\u00a0\u00bb. Le d\u00e9sordre a fait sauter les \u00ab\u00a0cloisonnements crisiques\u00a0\u00bb (entre les crises) et m\u00e9lange les diverses fractures. Ainsi le maire de New York City peut-il proclamer qu&rsquo;il est sain de se tenir hors-&lsquo;distanciation sociale&rsquo; si c&rsquo;est pour d\u00e9noncer le racisme selon la formule-BLM, car c&rsquo;est comme une incantation qui foudroie le virus, &ndash; croyez-moi, c&rsquo;est simple il n&rsquo;oserait pas ! &ndash; je veux dire, infecter les gens qui se pressent h\u00e9ro\u00efquement, au coude-\u00e0-coude, contre le racisme, tant de vertus diverses, n&rsquo;est-ce pas&#8230; Tout de m\u00eame, il faudrait raison garder, n&rsquo;est-il pas ? Quoi qu&rsquo;il en soit, ainsi les fractures crisiques se m\u00e9langent-elles en une incroyable sarabande, comme s&rsquo;il s&rsquo;agissait de rien de moins que <em><a href=\"https:\/\/www.dedefensa.org\/article\/verdun-ou-la-java-du-diable\">La java du diable<\/a>.<\/em><\/p>\n<\/p>\n<p><p>Plus que jamais il a sa place dans les hypoth\u00e8ses intuitives, ce commentaire d\u00a0\u00bbavant-Covid19&prime; (<a href=\"https:\/\/www.dedefensa.org\/article\/le-temps-et-la-rebellion-du-temps\">du 12 janvier<\/a> de cette terrible ann\u00e9e) ; je veux dire qu&rsquo;on doit reconna&icirc;tre qu&rsquo;il est compl\u00e8tement du &lsquo;temps pr\u00e9sent&rsquo; comme du Temps en g\u00e9n\u00e9ral et en majest\u00e9. Le mouvement d\u00e9crit ici n&rsquo;a fait qu&rsquo;acc\u00e9l\u00e9rer du fait de Covid19 et de la Grande-Emeute2020.<\/p>\n<\/p>\n<p><p>&laquo; <em>Le Temps n&rsquo;accorde plus \u00e0 personne le temps de la r\u00e9flexion pour mieux situer sa position, pour bien juger d&rsquo;un \u00e9v\u00e9nement et de ses implications. Le Temps a d\u00e9cid\u00e9 d&rsquo;agir en suscitant la \u00ab\u00a0r\u00e9bellion du temps\u00a0\u00bb, de notre temps-courant, et nous allons devoir nous en accommoder, accepter de juger sans comprendre et de comprendre sans en rien conna&icirc;tre, appuy\u00e9s sur une volont\u00e9 d&rsquo;<a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-linconnaissance\">inconnaissance<\/a> qui rend accessoire tout ce qui ne fait pas l&rsquo;essentiel de la bataille. Le Temps ne me laisse plus qu&rsquo;un interstice de temps pour situer en un \u00e9clair o&ugrave; se trouve le Syst\u00e8me par rapport \u00e0 moi, dans cet \u00e9v\u00e9nement qui vient \u00e0 peine d&rsquo;\u00e9clater et qui d\u00e9j\u00e0 s&rsquo;ach\u00e8ve, et me situer contre le Syst\u00e8me dans cet \u00e9clair de temps.<\/em><\/p>\n<p>&raquo; <em>Le Temps nous prend \u00e0 notre propre pi\u00e8ge, selon l&rsquo;orientation transcendantale de l'\u00a0\u00bb<a href=\"https:\/\/www.dedefensa.org\/article\/un-assassinat-metahistorique\">assassinat m\u00e9tahistorique<\/a>\u00ab\u00a0. Nous, &ndash; c&rsquo;est-\u00e0-dire les zombies du Syst\u00e8me, les modernes, les d\u00e9constructeurs, &ndash; nous avons organis\u00e9 le d\u00e9sordre-chaos pour faire jaillir ce qui devait n\u00e9cessairement complaire \u00e0 notre raison et \u00e0 notre belle conscience, dans le sillon triomphant de la modernit\u00e9 que nous tra\u00e7ons depuis quatre-cinq si\u00e8cles. La riposte du Temps, c&rsquo;est d&rsquo;acc\u00e9l\u00e9rer le temps pour acc\u00e9l\u00e9rer le d\u00e9sordre et nous faire nous y perdre sans ne plus rien y comprendre<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Il faut bien accepter l&rsquo;id\u00e9e que, de ce point de vue et \u00e0 cette lumi\u00e8re, Covid19 est un formidable acc\u00e9l\u00e9rateur et un garde-chiourme de la Grande Crise d&rsquo;Effondrement du Syst\u00e8me (<a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-la-gces\">GCES<\/a>). Il emp\u00eache, par ses all\u00e9es et venues, sa persistance, sa redondance et son opini\u00e2tret\u00e9, la moindre tentative de dissimulation de cette GCES, et encore plus, la moindre tentative de r\u00e9paration de l&rsquo;usine \u00e0 gaz gigantesque o&ugrave; nous errons et nous d\u00e9battons sans tr\u00eave.<\/p>\n<\/p>\n<p><p>Croyez-vous que <a href=\"https:\/\/www.aier.org\/article\/when-will-the-madness-end\/\">l&rsquo;article<\/a> du 10 juillet (traduction le 12 juillet de <em><a href=\"https:\/\/www.aubedigitale.com\/quand-est-ce-que-la-folie-sarretera-t-elle\/\">Aube Digitale<\/a><\/em>) de Jeffrey A. Tucker, directeur \u00e9ditorial de l&rsquo;<em>American Institute for Economic Research<\/em>, soit fait pour concerner le Covid, les \u00e9pid\u00e9mies, voire les troubles conformes et contr\u00f4l\u00e9s de la psychologie humaine, lorsqu&rsquo;il d\u00e9crit une rencontre fortuite avec un psychiatre, le 12 mars dernier ? Et qu&rsquo;il nous introduit cette anecdote dans cet article dont le la question &laquo; <em>Quand la folie s&rsquo;arr\u00eatera-t-elle ? <\/em>&raquo; fait office de titre ?<\/p>\n<\/p>\n<p><p>&laquo; <em>Ce jour-l\u00e0<\/em> [le 12 mars]<em>, tout le monde savait ce qui allait arriver. Il y avait une panique sanitaire dans l&rsquo;air, foment\u00e9e principalement par les m\u00e9dias et les personnalit\u00e9s politiques<\/em>. [&#8230;]<\/p>\n<p>&raquo; <em>Un homme mince et sage, barbu, avec des lunettes \u00e0 la Freud, s&rsquo;est assis en face de moi, venant de quitter le studio. Il reprenait certes son souffle apr\u00e8s l&rsquo;interview, mais il paraissait \u00e9galement, profond\u00e9ment troubl\u00e9 et d\u00e9sempar\u00e9.<\/em><\/p>\n<p>&raquo; <em>&mdash; Il y a de la peur dans l&rsquo;air, dis-je, rompant le silence.<\/em><\/p>\n<p>&raquo; <em>&mdash; La folie est autour de nous. Le public est touch\u00e9 par un trouble de la personnalit\u00e9 que j&rsquo;ai trait\u00e9 toute ma carri\u00e8re.<\/em><\/p>\n<p>&raquo; <em>&mdash; Quel est votre m\u00e9tier ? demandai-je.<\/em><\/p>\n<p>&raquo; <em>&mdash; Je suis un psychiatre praticien sp\u00e9cialis\u00e9 dans les troubles de l&rsquo;anxi\u00e9t\u00e9, les d\u00e9lires parano\u00efaques et la peur irrationnelle. Je traite ces troubles chez les individus en tant que sp\u00e9cialiste. Il est d\u00e9j\u00e0 assez difficile de contenir ces probl\u00e8mes en temps normal. Ce qui se passe maintenant, c&rsquo;est une propagation de cette grave maladie \u00e0 l&rsquo;ensemble de la population. Cela peut arriver avec n&rsquo;importe quoi, mais ici nous voyons une peur primaire de la maladie se transformer en panique de masse. Cela semble presque d\u00e9lib\u00e9r\u00e9. C&rsquo;est tragique. Une fois que cela commence, cela pourrait prendre des ann\u00e9es pour r\u00e9parer les dommages psychologiques.<\/em>.. &raquo;<\/p>\n<\/p>\n<p><p>En un sens, tout \u00e0 fait d&rsquo;accord, \u00ab\u00a0la folie autour de nous\u00a0\u00bb ; mais pas dans le sens qu&rsquo;on croirait, car dans certains cas ce qui para&icirc;t folie selon le jugement que nous imposent les r\u00e9f\u00e9rences qui nous bornent, c&rsquo;est une fa\u00e7on d&rsquo;\u00eatre en paraissant, pour s&rsquo;en sortir.<\/p>\n<\/p>\n<p><p>Autrement dit, &ndash; non, absolument pas, je ne suis pas en train de vous sugg\u00e9rer un complot en vous rapportant cette anecdote, bien au contraire ; je suis en train de vous sugg\u00e9rer une description compl\u00e8tement hors du domaine sanitaire de la fragilit\u00e9 des psychologies calfeutr\u00e9es depuis si longtemps dans la bulle-simulacre o&ugrave; le Syst\u00e8me les avait enferm\u00e9es, et cette bulle crev\u00e9e par un virus, et le simulacre dispers\u00e9 aux quatre vents, montrant combien il est monstrueux, ridicule, risible, difforme et odieux. Cela \u00ab\u00a0prendra des ann\u00e9es\u00a0\u00bb, dit-il ? Eh bien, cela permettra \u00e0 la vigilance antiSyst\u00e8me install\u00e9e par la r\u00e9bellion du temps de repousser toute tentative du Syst\u00e8me de reconstituer un simulacre, pour lui donner le temps, rapide mais efficace, d&rsquo;agoniser enfin, &ndash; toi, le Syst\u00e8me, comme l&rsquo;on dit \u00ab\u00a0Toi, le venin\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>En ce sens, on comprendra que je tiens le virus Covid19, non pour un produit du diable-comploteur, mais bien pour un envoy\u00e9 du Ciel. Amen, mes bien-chers-fr\u00e8res et comploteurs divers comme d&rsquo;\u00e9t\u00e9.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Covid19 et la \u00ab\u00a0r\u00e9bellion du temps\u00a0\u00bb 13 juillet 2020 &ndash; Jeudi dernier, sur CNN, le maire de New York City, Bill de Blasio, fit &laquo; quelques remarques surprenantes, d\u00e9clarant que les manifestations de protestation dans les rues [attention, uniquement des BLM] sont parfaitement autoris\u00e9es, tout en annon\u00e7ant l&rsquo;interdiction des \u00e9v\u00e9nements de foule jusqu&rsquo;en septembre &raquo;.&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[6041,3126,20031,5513,2631,4020,13053,17429,17391,3256,6320,3965,12514,8746,3257],"class_list":["post-79342","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-bill","tag-black","tag-blasio","tag-city","tag-de","tag-folie","tag-gces","tag-lives","tag-matter","tag-new","tag-pandemie","tag-simulacre","tag-toulet","tag-tucker","tag-york"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79342","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79342"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79342\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79342"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79342"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}