{"id":79359,"date":"2020-07-27T12:47:27","date_gmt":"2020-07-27T12:47:27","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2020\/07\/27\/cancelled-lesprit\/"},"modified":"2020-07-27T12:47:27","modified_gmt":"2020-07-27T12:47:27","slug":"cancelled-lesprit","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2020\/07\/27\/cancelled-lesprit\/","title":{"rendered":"<em>Cancelled<\/em>, l&rsquo;Esprit\u00a0?"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\"><em>Cancelled<\/em>, l&rsquo;Esprit ?<\/h2>\n<\/p>\n<p><p>D&rsquo;une certaine fa\u00e7on ais\u00e9ment compr\u00e9hensible, un tel texte accompagnant un commentaire de Howard James Kunstler, aurait d&ucirc; figurer dans la &lsquo;rubrique&rsquo;, ou dans la s\u00e9rie disons, des textes <em>RapSit-USA2020<\/em>. (Dans tous les cas, on pourra l&rsquo;en rapprocher.) Mais c&rsquo;est qu&rsquo;il s&rsquo;agit d&rsquo;une r\u00e9flexion qui, si elle vaut pour les USA, vaut finalement pour toute notre civilisation dans le sens o&ugrave; elle met moins en proc\u00e8s un parti, une id\u00e9ologie, un engagement, etc., et tout cela au niveau d&rsquo;un pays, &ndash; que le processus d&rsquo;abrutissement et de r\u00e9duction de la psychologie, d&rsquo;abdication et de d\u00e9mission du caract\u00e8re, d&rsquo;abaissement de ce qui nous reste d&rsquo;ontologie, et ce processus pr\u00e9sentement \u00e0 l&rsquo;&oelig;uvre dans une civilisation d\u00e9clinant de plus en plus rapidement jusqu&rsquo;\u00e0 ce qui pourrait \u00eatre identifi\u00e9 comme une chute dans l&rsquo;effondrement.<\/p>\n<\/p>\n<p><p>Le \u00ab\u00a0<em>Cancel<\/em>\u00a0\u00bb du titre renvoie \u00e9videmment au verbe <em>to cancel<\/em> (que nous nous permettons de transcrire par &lsquo;liquider&rsquo; pour ce cas) et au slogan \u00ab\u00a0<em>Cancel Culture<\/em>\u00a0\u00bb que certains ont adopt\u00e9 dans les rangs d\u00e9ferlants des manifestations officiellement attribu\u00e9es aux BLM (<em>Black Lives Matter<\/em>) pour d\u00e9battre du racisme anti-<em>blacks<\/em> aux USA. Il est \u00e9vident pour Kunstler, et cela vaut \u00e9galement pour nous et pour tout jugement qui n&rsquo;est pas emport\u00e9 par la <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Le_Joueur_de_fl\u00fbte_de_Hamelin\">fl&ucirc;te<\/a> du simulacre, que l&rsquo;argument (racisme anti-<em>blacks<\/em>) est loin d&rsquo;\u00eatre le seul sujet en jeu aujourd&rsquo;hui, sinon comme faux-nez pour nombre de desseins cach\u00e9s.<\/p>\n<\/p>\n<p><p>On voit tr\u00e8s vite que Kunstler parle de la situation US <em>as a whole. <\/em>C&rsquo;est elle qui est ici consid\u00e9r\u00e9e, puisqu&rsquo;apr\u00e8s tout Kunstler n&rsquo;est pas loin d&rsquo;attribuer la responsabilit\u00e9 directe de tout ce d\u00e9sordre \u00e0 l&rsquo;absence de r\u00e9action l\u00e9gale et souveraine de l&rsquo;administration Trump, sinon de Trump lui-m\u00eame, \u00e0 de multiples infractions commises pour le mettre en cause, sinon pour l&rsquo;abattre. Ainsi, \u00e0 c\u00f4t\u00e9 de la responsabilit\u00e9 \u00e9vidente des d\u00e9mocrates et de leurs multiples courroies de transmission et autres comploteurs venus aussi bien du FBI que de la CIA, se trouve la responsabilit\u00e9 de celui qui est investi de l&rsquo;autorit\u00e9 et qui n&rsquo;en use pas alors que cette autorit\u00e9 a pour fonction premi\u00e8re d&rsquo;affirmer la l\u00e9galit\u00e9 et d&rsquo;agir en cons\u00e9quence, &ndash; ce qui est la mission de Trump, &ndash; s&rsquo;il l&rsquo;apprenait, quelle ne serait pas sa surprise effray\u00e9e, voire paniqu\u00e9e !<\/p>\n<\/p>\n<p><p>Ainsi, au-del\u00e0 de Trump-d\u00e9mocrates, le proc\u00e8s que fait Kunstler va \u00e0 toute une \u00e9poque, toute une civilisation, celle du pi\u00e8tre <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-bloc-bao-1\">bloc-BAO<\/a> qui est compl\u00e8tement sous l&#8217;emprise des divers simulacres qu&rsquo;elle monte elle-m\u00eame pour r\u00e9pondre \u00e0 cette \u00ab\u00a0soci\u00e9t\u00e9 du spectacle\u00a0\u00bb dont on croit encore qu&rsquo;elle est une arme pour nous asservir. Les premiers asservis, les premiers abrutis, les premiers dont la pens\u00e9e libre est directement d\u00e9sint\u00e9gr\u00e9e, ce sont les directions et les \u00e9lites qui ne peuvent \u00e9chapper aux rets du Syst\u00e8me (d&rsquo;o&ugrave; les \u00e9lites-Syst\u00e8me) ; ce Syst\u00e8me qui, dans son immense stupidit\u00e9 de la force brute, les emprisonne pour qu&rsquo;elles le servent mieux alors qu&rsquo;ainsi emprisonn\u00e9es elles deviennent inefficaces, pitoyables, ridicules.<\/p>\n<\/p>\n<p><p>Trump, l&rsquo;homme improbable, le bouffon ridicule qui a \u00ab\u00a0os\u00e9\u00a0\u00bb d\u00e9pouiller Hillary de son pi\u00e8tre vernis de vertu pour qu&rsquo;on puisse sentir toute la corruption dont elle est charg\u00e9e, n&rsquo;a pas \u00ab\u00a0os\u00e9\u00a0\u00bb comprendre qu&rsquo;en jouant le jeu de l&rsquo;autorit\u00e9 au poste o&ugrave; il se trouvait, il affirmait sa stature et acqu\u00e9rait une l\u00e9gitimit\u00e9 irr\u00e9fragable ; et dire qu&rsquo;on fait de lui un dictateur, un \u00ab\u00a0nouveau Hitler\u00a0\u00bb ! Bien entendu et l\u00e0 encore, ces reproches peuvent \u00eatre \u00e9gren\u00e9s, adapt\u00e9s aux d\u00e9tails, pour la plupart des chefs d&rsquo;&Eacute;tat et de gouvernement, c&rsquo;est-\u00e0-dire tous ceux du bloc-BAO sauf accident ais\u00e9ment identifiable. De m\u00eame glosera-t-on sur la l\u00e2chet\u00e9 stup\u00e9fiante des m\u00eames \u00e9lites-Syst\u00e8me devant les montages et simulacres que leur font les diverses repentances, accusations soci\u00e9tales, r\u00e9clamations \u00ab\u00a0droitdel&rsquo;hommistes\u00a0\u00bb et \u00ab\u00a0droitdegenriste\u00a0\u00bb qui geignent sans fin des foules-simulacres circulant dans les r\u00e9seaux-sociaux et les <a href=\"https:\/\/www.dedefensa.org\/article\/comment-echapper-au-rhizome\">rhizomes-soci\u00e9taux<\/a> que Deleuze, s&rsquo;il \u00e9tait encore parmi nous, regarderait avec un grand attendrissement. Il s&rsquo;agit de la marque de cette \u00ab\u00a0civilisation d\u00e9clinant de plus en plus rapidement jusqu&rsquo;\u00e0 ce qui pourrait \u00eatre identifi\u00e9 comme une chute dans l&rsquo;effondrement\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>Plus de \u00ab\u00a0pens\u00e9e libre\u00a0\u00bb, plus d'\u00a0\u00bbEsprit\u00a0\u00bb, plus de \u00ab\u00a0<em>thinking<\/em>\u00a0\u00bb (&laquo; <em>Is Thinking Cancelled?<\/em> &raquo;, titre original de l&rsquo;article de Kunstler), etc., quelle horrible occurrence ? Eh bien, nous avons les contestataires, les protestataires et les \u00ab\u00a0r\u00e9volutions culturelles\u00a0\u00bb que nous m\u00e9ritons : au ras des p\u00e2querettes, certes, pendant que la \u00ab\u00a0<em>fucked<\/em>\u00a0\u00bb civilisation en chute libre d&rsquo;effondrement se goinfre de pissenlits par la racine. &laquo; <em>Y a-t-il quelque chose \u00e0 propos de cette <\/em>[civilisation] <em>qui m\u00e9rite d&rsquo;\u00eatre d\u00e9fendue ? Est-ce que le fait de penser est <a href=\"https:\/\/fr.wiktionary.org\/wiki\/cancel_culture\">liquid\u00e9<\/a> ?<\/em> &raquo;<\/p>\n<\/p>\n<p><p>Le texte ci-dessous, du <a href=\"https:\/\/kunstler.com\/clusterfuck-nation\/is-thinking-cancelled\/\">20 juillet 2020<\/a> sur le site de Kunstler, est mis en ligne en traduction fran\u00e7aise par le<em> Sakerfrancophone <\/em>le <a href=\"https:\/\/lesakerfrancophone.fr\/penser-est-ce-annule\">25 juillet 2020<\/a>.<\/p>\n<\/p>\n<p><h4><em>dde.org<\/em><\/h4>\n<\/p>\n<p><p>______________________<\/p>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_a.deepgreen\" style=\"color:#75714d; font-size:2em\">Liquid\u00e9e, la pens\u00e9e !<\/h2>\n<\/p>\n<p><p>Tout est en jeu maintenant. La r\u00e9alit\u00e9 consensuelle est en fuite &ndash; les vieilles certitudes de l&rsquo;histoire am\u00e9ricaine et les promesses d&rsquo;avenir qui s&rsquo;\u00e9loignent s&rsquo;enfoncent dans la boue ardente du virus corona. Les choses se passent sans cons\u00e9quence apparente. L&rsquo;autorit\u00e9 est en d\u00e9route. La coercition quadrille le pays pour \u00e9radiquer le crime de la pens\u00e9e libre. Les fantasmes et les illusions se pr\u00e9cipitent dans l&rsquo;espace que la raison a quitt\u00e9 par peur pour son existence. Il serait pr\u00e9f\u00e9rable de ne pas penser du tout. Mais vous ne pouvez pas vous en emp\u00eacher, n&rsquo;est-ce pas ? &Ecirc;tre humain, c&rsquo;est \u00eatre obnubil\u00e9 par sa propre pens\u00e9e.<\/p>\n<\/p>\n<p><p>Je ne peux m&#8217;emp\u00eacher de penser que l&rsquo;incapacit\u00e9 \u00e0 r\u00e9soudre les op\u00e9rations malhonn\u00eates du RussiaGate est en grande partie responsable de l&rsquo;absence d&rsquo;autorit\u00e9 et de responsabilit\u00e9, ces deux sentinelles de la raison. Les crimes des agents du FBI, du DOJ, de la CIA et d&rsquo;autres agences ne sont pas jug\u00e9s alors que des preuves claires de leurs m\u00e9faits s\u00e9ditieux ont \u00e9t\u00e9 publiquement document\u00e9es et largement publi\u00e9es. Il semble que cette grande affaire de tentative de renversement du pr\u00e9sident se r\u00e9sume \u00e0 la seule volont\u00e9 de William Barr et de John Durham qui ont os\u00e9 mettre le feu aux poudres, et on se demande s&rsquo;ils ont la moindre id\u00e9e des dommages que leur retard cause \u00e0 la psych\u00e9 nationale.<\/p>\n<\/p>\n<p><p>Le g\u00e9n\u00e9ral Flynn, le Dreyfus Am\u00e9ricain, continue de se tordre lentement dans le vent malgr\u00e9 l&rsquo;abandon des charges retenues contre lui par le DOJ. Le juge Emmet Sullivan est occup\u00e9 \u00e0 d\u00e9truire la cr\u00e9dibilit\u00e9 et l&rsquo;autorit\u00e9 f\u00e9d\u00e9rale avec des manigances proc\u00e9durales de mauvaise foi, soutenues par la claque des escrocs de Washington comme Ben Wittes qui man&oelig;uvrent en arri\u00e8re-plan pour prot\u00e9ger Barack Obama et Hillary Clinton. N&rsquo;est-il pas temps que la Cour d&rsquo;appel de Washington oblige le juge Sullivan \u00e0 mettre fin \u00e0 l&rsquo;affaire, ou qu&rsquo;elle le r\u00e9primande et le d\u00e9mette de ses fonctions ?<\/p>\n<\/p>\n<p><p>Au-del\u00e0 de toutes les conneries juridiques, la vie d&rsquo;un homme innocent est injustement bloqu\u00e9e dans les limbes apr\u00e8s trois ans de poursuites malveillantes. Pourquoi le procureur g\u00e9n\u00e9ral n&rsquo;a-t-il pas pr\u00e9f\u00e9r\u00e9 porter des accusations contre le principal accusateur du g\u00e9n\u00e9ral Flynn, le procureur en chef Brandon Van Crack &ndash; ou, d&rsquo;ailleurs, contre Robert Mueller, Andrew Weissmann et tout le personnel du conseil sp\u00e9cial &ndash; pour dissimulation de preuves et bien d&rsquo;autres m\u00e9faits \u00e9vidents li\u00e9s aux poursuites ? Barr a clairement d\u00e9clar\u00e9 plus d&rsquo;une fois que le minist\u00e8re dont il a pris la charge en 2019 &laquo;<em> a utilis\u00e9 le processus de justice p\u00e9nale comme une arme politique <\/em>&raquo;. Est-ce ill\u00e9gal ou non ? Est-ce que cela porte pr\u00e9judice \u00e0 la soci\u00e9t\u00e9 de laisser cette question sans r\u00e9ponse, mois apr\u00e8s mois ?<\/p>\n<\/p>\n<p><p>Dans une soci\u00e9t\u00e9 meilleure, les journaux se seraient pr\u00e9cipit\u00e9s \u00e0 la d\u00e9fense du G\u00e9n\u00e9ral Flynn. Sauf que nos principaux journaux sont tellement investis par des ann\u00e9es de leur propre mensionges et <em>narrative <\/em>qu&rsquo;ils n&rsquo;osent pas couvrir l&rsquo;histoire. Quelles sont les cons\u00e9quences pour Dean Baquet, r\u00e9dacteur en chef du <em>New York Times<\/em>, depuis que Bari Weiss, membre du personnel du <em>Times<\/em>, a r\u00e9v\u00e9l\u00e9 son incapacit\u00e9 \u00e0 supporter plus longtemps les brimades id\u00e9ologiques, la coercition et l&rsquo;hostilit\u00e9 sociale dans sa salle de r\u00e9daction ? Baquet n&rsquo;a pas seulement d\u00e9truit une institution ; il a transform\u00e9 sa mission professionnelle de rendre compte de la r\u00e9alit\u00e9 en une arnaque minable. Le conseil d&rsquo;administration du <em>New York Times<\/em> ne se pr\u00e9occupe-t-il pas de sa r\u00e9putation ? Le sign,ification de leur attitude est peut-\u00eatre la suivante : pourquoi se soucier de sa r\u00e9putation ? Alors, \u00e0 quel genre de culture s&rsquo;attendre \u00e0 partir de telles attitudes ?<\/p>\n<\/p>\n<p><p>Les maires de New York, Chicago, Seattle, Los Angeles, New York, Minneapolis, Portland, Atlanta et Washington DC ont tous autoris\u00e9 des \u00e9meutes, des pillages, des destructions de biens et des incendies criminels dans leurs rues, et ont pris des mesures pour sous-financer et retenir la police, voire l&rsquo;abolir compl\u00e8tement. Ce sont toutes des villes contr\u00f4l\u00e9es par le Parti D\u00e9mocrate et dot\u00e9es de maires D\u00e9mocrates.<\/p>\n<\/p>\n<p><p>Pensez-vous que les \u00e9lecteurs ont bien regard\u00e9 ces sc\u00e8nes et en ont conclu que le Parti D\u00e9mocrate n&rsquo;est peut-\u00eatre pas int\u00e9ress\u00e9 par l&rsquo;ordre civil ? Et dans quel but, exactement ? Le fait que le taux d&rsquo;homicides sous les mandats de Bill de Blasio et de Lori Lightfoot soit soudainement hors normes alors qu&rsquo;ils sont occup\u00e9s \u00e0 saper l&rsquo;autorit\u00e9 de la police et sa capacit\u00e9 \u00e0 prot\u00e9ger le public va-t-il d\u00e9grader l&rsquo;image du pr\u00e9sident Trump ? Que pensez-vous du fait que le procureur en chef de St Louis Kim Gardner ait d\u00e9cid\u00e9 de poursuivre Mark et Patricia McCloskey pour avoir d\u00e9fendu leur maison contre une foule qui mena\u00e7ait de la br&ucirc;ler ? Le gouverneur du Missouri, Mike Parson, a d\u00e9clar\u00e9 ce week-end qu&rsquo;il gracierait rapidement le couple s&rsquo;il \u00e9tait inculp\u00e9 &ndash; au moins, voil\u00e0 une action sans \u00e9quivoque et d\u00e9cisive en faveur de la sant\u00e9 mentale.<\/p>\n<\/p>\n<p><p>Dans les mois \u00e0 venir, il y aura beaucoup plus de probl\u00e8mes r\u00e9els pour rendre fou le peuple am\u00e9ricain. Nous n&rsquo;avons m\u00eame pas effac\u00e9 les affronts \u00e0 la d\u00e9cence et \u00e0 la raison qui se sont produits avant que le virus corona ne d\u00e9barque et commence \u00e0 d\u00e9truire des millions de vies et de moyens de subsistance. Le cri de sir\u00e8ne de l&rsquo;anarchie retentit d\u00e9j\u00e0. Y a-t-il quelque chose \u00e0 propos de cette r\u00e9publique qui m\u00e9rite d&rsquo;\u00eatre d\u00e9fendue ? Est-ce que le fait de penser est <a href=\"https:\/\/fr.wiktionary.org\/wiki\/cancel_culture\">liquid\u00e9<\/a> ?<\/p>\n<\/p>\n<p><h4>James Howard Kunstler<\/h4><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cancelled, l&rsquo;Esprit ? D&rsquo;une certaine fa\u00e7on ais\u00e9ment compr\u00e9hensible, un tel texte accompagnant un commentaire de Howard James Kunstler, aurait d&ucirc; figurer dans la &lsquo;rubrique&rsquo;, ou dans la s\u00e9rie disons, des textes RapSit-USA2020. (Dans tous les cas, on pourra l&rsquo;en rapprocher.) Mais c&rsquo;est qu&rsquo;il s&rsquo;agit d&rsquo;une r\u00e9flexion qui, si elle vaut pour les USA, vaut finalement&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[19283,17431,20066,934,3163,19927,2801,18919,13022,2639],"class_list":["post-79359","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-barr","tag-blm","tag-cancelled","tag-clinton","tag-culture","tag-grande-emeute2020","tag-kunstler","tag-rhizome","tag-russiagate","tag-trump"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79359"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79359\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}