{"id":79361,"date":"2020-07-28T15:07:12","date_gmt":"2020-07-28T15:07:12","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2020\/07\/28\/la-vertueuse-sequence-de-leffondrement\/"},"modified":"2020-07-28T15:07:12","modified_gmt":"2020-07-28T15:07:12","slug":"la-vertueuse-sequence-de-leffondrement","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2020\/07\/28\/la-vertueuse-sequence-de-leffondrement\/","title":{"rendered":"La vertueuse s\u00e9quence de l&rsquo;effondrement"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">La vertueuse s\u00e9quence de l&rsquo;effondrement<\/h2>\n<\/p>\n<p><p>Cela fait douze ans que j&rsquo;ai publi\u00e9 mon essai &laquo; <a href=\"https:\/\/lesakerfrancophone.fr\/les-cinq-etapes-de-leffondrement-mise-a-jour-2019\">Les cinq stades de l&rsquo;effondrement<\/a> &raquo; dans lequel j&rsquo;ai propos\u00e9 pour la premi\u00e8re fois une taxonomie de l&rsquo;effondrement, en la d\u00e9composant en effondrements financiers, commerciaux, politiques, sociaux et culturels, ainsi que ce que j&rsquo;ai con\u00e7u comme une s\u00e9quence d&rsquo;effondrement canonique, o&ugrave; chaque \u00e9tape de l&rsquo;effondrement d\u00e9clenche la suivante. Cela a assez bien fonctionn\u00e9, avec le recul, pour l&rsquo;URSS et, en tant qu&rsquo;exp\u00e9rience de pens\u00e9e, pour les &Eacute;tats-Unis, mais maintenant, en 2020, \u00e0 la lumi\u00e8re de l&rsquo;effondrement r\u00e9el qui se produit dans de nombreuses r\u00e9gions de l&rsquo;Occident et en particulier dans les anciens &Eacute;tats-Unis, il semble que mon \u00e9valuation initiale \u00e9tait fond\u00e9e sur une vision trop positive de la nature humaine, du moins en ce qui concerne la nature des humains qui habitent ces r\u00e9gions.<\/p>\n<\/p>\n<p><p>Vue \u00e0 travers des lunettes roses, ma s\u00e9quence d&rsquo;effondrement canonique a commenc\u00e9 par des financiers avec une visi\u00e8re verte, gentiment assis en rond pour d\u00e9lib\u00e9rer tranquille et d\u00e9cidant sagement \u00e0 l&rsquo;unisson que, compte tenu de facteurs tels que l&rsquo;\u00e9puisement des ressources, une catastrophe climatique, une pand\u00e9mie ou une autre combinaison de circonstances de force majeure, il ne fallait pas accorder de nouveaux cr\u00e9dits commerciaux ou \u00e0 la consommation et financer les d\u00e9ficits budg\u00e9taires, car la probabilit\u00e9 que cette nouvelle dette soit int\u00e9gralement rembours\u00e9e serait trop faible. En retour, les capitaines d&rsquo;industrie r\u00e9duiraient prudemment la production et le personnel, en se concentrant sur la production de produits de premi\u00e8re n\u00e9cessit\u00e9 (tels que les pi\u00e8ces d\u00e9tach\u00e9es) plut\u00f4t que sur des fioritures (telles que des mises \u00e0 niveau non essentielles). &Agrave; son tour, le manque de recettes fiscales d&ucirc; au ralentissement du commerce et au ch\u00f4mage des travailleurs, associ\u00e9 \u00e0 l&rsquo;incapacit\u00e9 de financer les d\u00e9ficits budg\u00e9taires, am\u00e8nerait le gouvernement \u00e0 r\u00e9duire les d\u00e9penses et \u00e0 limiter ses activit\u00e9s au strict n\u00e9cessaire afin d&rsquo;\u00e9viter, ou du moins de conjurer, la faillite nationale.<\/p>\n<\/p>\n<p><p>La soci\u00e9t\u00e9 civile, compos\u00e9e d&rsquo;organisations civiques et de personnes charitables qui se soucient du bien commun, tenterait alors de pallier le manque de services gouvernementaux, en redistribuant les maigres ressources afin de r\u00e9pondre aux besoins les plus urgents et d&rsquo;\u00e9viter l&rsquo;effondrement de la soci\u00e9t\u00e9, mais n&rsquo;y parviendrait pas faute de moyens. Une fois que la soci\u00e9t\u00e9 civile s&rsquo;av\u00e9rerait trop faible pour remplir cette fonction, les gens se rabattraient sur leurs familles et leurs amis qui, \u00e9tant li\u00e9s par une culture forte et coh\u00e9sive de relations humaines, continuent d&rsquo;insister sur le maintien de normes essentielles de bien-\u00eatre. Si la famine, la violence et la maladie prennent une ampleur telle qu&rsquo;il est impossible de maintenir la continuit\u00e9 g\u00e9n\u00e9rationnelle, les enfants deviennent sauvages et cessent de ressembler aux humains. Mais si l&rsquo;on \u00e9vite ce r\u00e9sultat, une \u00e9ventuelle reprise partielle \u00e0 un niveau inf\u00e9rieur d&rsquo;expansion des ressources et de diminution de la population reste possible. Si l&rsquo;effondrement financier, commercial et politique peut \u00eatre in\u00e9vitable, l&rsquo;effondrement social et culturel ne l&rsquo;est peut-\u00eatre pas.<\/p>\n<\/p>\n<p><p>Si les conditions devaient s&rsquo;am\u00e9liorer par la suite, les familles \u00e9largies et les groupes familiaux isol\u00e9s, ayant soigneusement pr\u00e9serv\u00e9 leur culture et leurs traditions, les transmettant de parents \u00e0 enfants et de grands-parents \u00e0 petits-enfants, pourraient alors se relever ensemble, reconstituer une soci\u00e9t\u00e9 et choisir des dirigeants qui formeraient de nouvelles politiques. Le commerce ferait son retour et, si les conditions restent suffisamment stables et favorables, le concept d&rsquo;\u00e9mission de dette (emprunter prudemment \u00e0 l&rsquo;avenir pour acc\u00e9l\u00e9rer le rythme de la reprise) pourrait \u00e9ventuellement \u00eatre \u00e9voqu\u00e9. Et si les conditions devaient se d\u00e9t\u00e9riorer \u00e0 jamais, jusqu&rsquo;\u00e0 l&rsquo;extinction biologique, cette civilisation laisserait derri\u00e8re elle des ruines majestueuses, de splendides &oelig;uvres d&rsquo;art et des biblioth\u00e8ques de joyaux litt\u00e9raires et savants pour inspirer et \u00e9tonner les civilisations du futur.<\/p>\n<\/p>\n<p><p>L&rsquo;effondrement est une cons\u00e9quence in\u00e9vitable pour toutes les \u00e9conomies capitalistes et toutes les \u00e9conomies socialistes ax\u00e9es sur la croissance. L&rsquo;expansion \u00e9conomique infinie dans un environnement physique fini est un concept qui n&rsquo;est valable que pour les imb\u00e9ciles, les fous et les \u00e9conomistes laur\u00e9ats du prix Nobel. Le sc\u00e9nario d&rsquo;effondrement d\u00e9crit ci-dessus est le meilleur sc\u00e9nario d&rsquo;effondrement. H\u00e9las, ce n&rsquo;est pas le sc\u00e9nario que nous voyons actuellement se d\u00e9rouler dans le grand pays d\u00e9velopp\u00e9 qui est de loin le plus avanc\u00e9 sur la trajectoire de l&rsquo;effondrement &ndash; les &Eacute;tats-Unis. Il est donc temps de jeter les lunettes roses et d&rsquo;envisager le pire des sc\u00e9narios, en se basant sur une vision plus r\u00e9aliste des \u00eatres humains concern\u00e9s, car m\u00eame si nous essayons de les voir avec beaucoup de sympathie, ils ne semblent pas \u00eatre le genre de parangons de vertu qui rendrait possible le meilleur des sc\u00e9narios d&rsquo;effondrement.<\/p>\n<\/p>\n<p><p>Depuis <a href=\"https:\/\/www.fromthewilderness.net\/free\/ww3\/060105_soviet_lessons.shtml\">2006<\/a>, je pr\u00e9vois que les &Eacute;tats-Unis suivront la m\u00eame trajectoire d&rsquo;effondrement que l&rsquo;URSS, et j&rsquo;ai fait des analogies entre les deux afin de faire des pr\u00e9dictions sp\u00e9cifiques et <a href=\"https:\/\/www.resilience.org\/stories\/2006-12-04\/closing-collapse-gap-ussr-was-better-prepared-collapse-us\">d\u00e9taill\u00e9es<\/a> sur l&rsquo;effondrement des &Eacute;tats-Unis. &Agrave; la lumi\u00e8re des \u00e9v\u00e9nements actuels, ma m\u00e9thode a \u00e9t\u00e9 justifi\u00e9e et mes pr\u00e9dictions \u00e9taient pr\u00e9monitoires. Cependant, il y a un domaine o&ugrave; je dois apporter une correction : la s\u00e9quence d&rsquo;effondrement canonique ne s&rsquo;applique pas aux &Eacute;tats-Unis, et elle peut ne s&rsquo;appliquer que partiellement ou pas du tout aux autres pays occidentaux.<\/p>\n<\/p>\n<p><p>J&rsquo;ai eu l&rsquo;intuition que ce serait le cas il y a deux ans, en mai 2018, lorsque j&rsquo;ai publi\u00e9 l&rsquo;article &laquo; <em><a href=\"https:\/\/lesakerfrancophone.fr\/leffondrement-culturel-est-deja-la\">L&rsquo;effondrement culturel est d\u00e9j\u00e0 l\u00e0<\/a><\/em> &raquo;. Dans cet essai, j&rsquo;ai \u00e9num\u00e9r\u00e9 les nombreuses techniques utilis\u00e9es pour d\u00e9truire la culture en Occident, les &Eacute;tats-Unis \u00e9tant de loin en t\u00eate, et j&rsquo;ai d\u00e9crit &laquo; <em>&hellip;une tentative de miner et de d\u00e9truire la coh\u00e9sion de la soci\u00e9t\u00e9 et la culture commune avant l&rsquo;effondrement financier, commercial et politique \u00e0 venir <\/em>&raquo; :<\/p>\n<\/p>\n<blockquote>\n<p><p>Cela peut sembler \u00e9trange de s&rsquo;efforcer d&rsquo;atteindre cet objectif, mais consid\u00e9rez ceci : si la soci\u00e9t\u00e9 et la culture sont d\u00e9truites \u00e0 l&rsquo;avance alors, lorsque l&rsquo;effondrement se produit, il n&rsquo;y a plus de communaut\u00e9 humaine intacte pour l&rsquo;observer et comprendre ce qui se passe. Les capacit\u00e9s de raisonnement de chacun \u00e9tant suffisamment entrav\u00e9es, il sera trivial de diffuser les reproches lorsque le reste de la s\u00e9quence d&rsquo;effondrement se produira, d&rsquo;amener les gens \u00e0 s&rsquo;accuser eux-m\u00eames ou mutuellement pour faire des voisins des boucs \u00e9missaires, ou de les ignorer tout simplement parce que la plupart des gens ont des probl\u00e8mes plus importants que l&rsquo;effondrement, que ce soit leurs familles dysfonctionnelles, leurs diverses d\u00e9pendances, leur fanatisme religieux ou leur politique extr\u00e9miste.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Cela s&rsquo;est av\u00e9r\u00e9 suffisamment vrai : Actuellement, de nombreuses personnes aux &Eacute;tats-Unis courent partout en bl\u00e2mant pour leur effondrement ce virus terriblement non-mortel (\u00e0 peu pr\u00e8s sans effets pour ceux qui n&rsquo;ont pas atteint l&rsquo;\u00e2ge de la retraite) ou le racisme (qui est une caract\u00e9ristique de la vie am\u00e9ricaine depuis des si\u00e8cles, jusqu&rsquo;\u00e0 pr\u00e9sent avec peu d&rsquo;effets n\u00e9gatifs pour les blancs) ou Donald Trump (qui, bien s&ucirc;r, n&rsquo;a gu\u00e8re d&rsquo;autres comp\u00e9tences que de monopoliser les feux de la rampe), ou les Russes, ou les Chinois, ou&hellip; Rien de ce bl\u00e2mothon ridicule n&rsquo;aurait \u00e9t\u00e9 possible si une culture forte et coh\u00e9sive \u00e9tait rest\u00e9e en place. Mais elle a disparu, et cela emp\u00eache le peuple am\u00e9ricain de rejeter la faute l\u00e0 o&ugrave; elle est due en se bl\u00e2mant&hellip; lui-m\u00eame parce que, voyez-vous, \u00ab\u00a0ils\u00a0\u00bb n&rsquo;existent plus comme une unit\u00e9 reconnaissable. Ainsi, en tant que nation unifi\u00e9e, les Am\u00e9ricains ne peuvent pas accuser, ou accepter, ou expier, ou se pardonner pour ce qui s&rsquo;est pass\u00e9, et passer \u00e0 autre chose.<\/p>\n<\/p>\n<p><p>Offrir comme motif de destruction culturelle l&rsquo;objectif de diffuser la responsabilit\u00e9 de l&rsquo;effondrement naissant \u00e9tait le mieux que je pouvais faire \u00e0 l&rsquo;\u00e9poque, mais maintenant je peux aller plus loin et offrir une explication plus approfondie des raisons pour lesquelles l&rsquo;URSS s&rsquo;est effondr\u00e9e financi\u00e8rement, commercialement et politiquement alors que pourtant la Russie ne s&rsquo;est pas (compl\u00e8tement) effondr\u00e9e socialement et ne s&rsquo;est pas effondr\u00e9e culturellement, et a pu rena&icirc;tre de ses cendres comme le ph\u00e9nix alors que les &Eacute;tats-Unis se sont d\u00e9j\u00e0 effondr\u00e9s socialement et culturellement, qu&rsquo;ils sont politiquement un &Eacute;tat zombie, qu&rsquo;ils ont c\u00e9d\u00e9 pratiquement tout leur commerce aux soci\u00e9t\u00e9s transnationales, mais qu&rsquo;ils ont miraculeusement r\u00e9ussi \u00e0 maintenir un domaine financier fonctionnel et une bourse bouillonnante.<\/p>\n<\/p>\n<p><p>Cette diff\u00e9rence, je m&rsquo;en suis rendu compte, repose sur une diff\u00e9rence de civilisation entre l&rsquo;ancienne URSS et les &Eacute;tats-Unis. Il s&rsquo;agit en fait d&rsquo;une question d&rsquo;amour. Et, non, je n&rsquo;ai pas perdu la t\u00eate. Sans entrer dans la taxinomie de l&rsquo;amour de la Gr\u00e8ce antique, qui comprend l&rsquo;agap\u00e8, l&rsquo;eros, la philia et le reste, j&rsquo;entends par l\u00e0 quelque chose qui va dans le sens d&rsquo;une d\u00e9votion inconditionnelle, d&rsquo;une compulsion ou d&rsquo;un abandon \u00e0 une force sup\u00e9rieure \u00e0 soi-m\u00eame, et l&rsquo;objet de cet amour est ce que l&rsquo;on ch\u00e9rit comme valeur ultime, source de fiert\u00e9 et de sentiment de soi.<\/p>\n<\/p>\n<p><p>Les Russes et les Am\u00e9ricains sont tous deux dot\u00e9s d&rsquo;un tel amour, mais ils aiment des choses diff\u00e9rentes. Les Russes aiment ce qu&rsquo;ils appellent R&oacute;dina (toujours avec une majuscule). Bien qu&rsquo;on puisse la traduire par \u00ab\u00a0m\u00e8re patrie\u00a0\u00bb, \u00ab\u00a0patrie\u00a0\u00bb, \u00ab\u00a0terre natale\u00a0\u00bb, etc., ce sont toutes des traductions erron\u00e9es car la Russie est trop grande pour \u00eatre appel\u00e9e \u00ab\u00a0terre\u00a0\u00bb .<\/p>\n<\/p>\n<p><p>La Bavi\u00e8re est un <em>Land<\/em> (aux c\u00f4t\u00e9s d&rsquo;autres <em>L&auml;nder <\/em>allemands, qui entreraient physiquement tous dans une seule r\u00e9gion russe de taille moyenne). L&rsquo;objet de cet amour comprend environ un sixi\u00e8me de la surface \u00e9merg\u00e9e de la Terre et il serait plus correct de l&rsquo;identifier comme la partie russe enti\u00e8re de la plan\u00e8te et tout ce qui s&rsquo;y trouve.<\/p>\n<\/p>\n<p><p>Je suppose qu&rsquo;une bonne fa\u00e7on d&rsquo;expliquer cet amour est un po\u00e8me qui figurait dans le film <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Le_Fr%C3%A8re_2\">Brother-2<\/a> qui est devenu un classique culte des ann\u00e9es 1990.<\/p>\n<\/p>\n<p><p>Voici ma traduction libre de ce po\u00e8me. (Je ne suis pas po\u00e8te, je vous l&rsquo;assure !)<\/p>\n<\/p>\n<p><p><em>Vous mes Proches<\/em><\/p>\n<p><em>J&rsquo;ai d\u00e9couvert que j&rsquo;ai<\/em><\/p>\n<p><em>Une famille gigantesque :<\/em><\/p>\n<p><em>Le sentier, la for\u00eat,<\/em><\/p>\n<p><em>Chaque t\u00eate de bl\u00e9 dans le champ,<\/em><\/p>\n<p><em>Animaux, oiseaux et col\u00e9opt\u00e8res,<\/em><\/p>\n<p><em>Fourmis et papillons de nuit&hellip;<\/em><\/p>\n<p><em>Tout ce qui est proche de moi<\/em><\/p>\n<p><em>C&rsquo;est toute ma R&oacute;dina !<\/em><\/p>\n<p><em>Alors comment puis-je, l\u00e0 ou je me tiens, <\/em><\/p>\n<p><em>Ne pas m&rsquo;en soucier ?<\/em><\/p>\n<\/p>\n<p><\/p>\n<p>Ce po\u00e8me est de Nikola\u00ef Kourilov, un yakout de la r\u00e9gion de Kolyma qui l&rsquo;a \u00e9crit en yukagir, une langue sib\u00e9rienne qui compte quelques centaines de locuteurs. Sa traduction russe publi\u00e9e est de Mikhail Yasnov, et je l&rsquo;ai \u00e0 mon tour traduit du russe. Je ne suis pas enti\u00e8rement satisfait de ma traduction car elle utilise des mots tels que \u00ab\u00a0avoir\u00a0\u00bbet  \u00ab\u00a0poss\u00e9der\u00a0\u00bb qui ne sont pas pr\u00e9sents dans l&rsquo;original. Mais il n&rsquo;y a pas moyen de contourner ce probl\u00e8me : la langue anglaise est cribl\u00e9e de possessivit\u00e9 gratuite au niveau de la grammaire. (Il n&rsquo;est pas possible de souffrir du rhume sans l&rsquo;avoir ; il n&rsquo;est pas non plus possible de se laver les dents sans indiquer que ce sont les v\u00f4tres et non celles de votre voisin, par exemple). Cette nuance est importante, car il est ridicule de revendiquer la propri\u00e9t\u00e9 ou la possession de R&oacute;dina. R&oacute;dina n&rsquo;appartient \u00e0 personne, on lui appartient, ou plut\u00f4t, elle appartient \u00e0 son c&oelig;ur.<\/p>\n<\/p>\n<p><p>Ce po\u00e8me illustre deux aspects importants du ph\u00e9nom\u00e8ne R&oacute;dina. Premi\u00e8rement, bien qu&rsquo;il soit sp\u00e9cifiquement russe, ce n&rsquo;est pas une d\u00e9signation ethnique, mais une d\u00e9signation superethnique. La Russie est compos\u00e9e de centaines de groupes ethniques, mais tous sont russes et tous sont li\u00e9s par la langue et la culture russes et partagent le droit d&rsquo;habiter tout le territoire russe. Les amendements r\u00e9cemment adopt\u00e9s \u00e0 la constitution russe d\u00e9finissent la langue russe comme &laquo;<em> la langue du peuple formant l&rsquo;&Eacute;tat <\/em>&raquo; sans nommer explicitement ce peuple formant l&rsquo;&Eacute;tat car il inclut tout le monde, de l&rsquo;Abaza \u00e0 l&rsquo;Azeri (et cela ne concerne que la lettre A), \u00e0 condition qu&rsquo;ils parlent russe et soient donc culturellement russes. Selon la loi russe, le fait d&rsquo;\u00eatre reconnu comme &laquo;<em> porteur de la langue russe <\/em>&raquo; donne le droit de demander la citoyennet\u00e9 russe.<\/p>\n<\/p>\n<p><p>Deuxi\u00e8mement, cette entit\u00e9 superethnique au sein de son vaste domaine g\u00e9ographique qui est l&rsquo;objet de l&rsquo;amour des Russes ne peut pas \u00eatre analys\u00e9e en termes de politique, d&rsquo;\u00e9conomie, de sociologie ou de religion. Il est tout aussi significatif, ou insignifiant, de l&rsquo;analyser en termes de sentiers, de for\u00eats, d&rsquo;\u00e9pis de bl\u00e9, de fourmis et de papillons de nuit. R&oacute;dina est simplement, comme le soleil et la lune, et son amour ne peut \u00eatre sap\u00e9 par des bouleversements politiques, un dysfonctionnement soci\u00e9tal, un effondrement \u00e9conomique ou toute autre calamit\u00e9. Cet amour n&rsquo;est pas non plus consid\u00e9r\u00e9 comme facultatif : inculquer &laquo;<em> l&rsquo;amour de R&oacute;dina <\/em>&raquo; est une fonction explicite et d\u00e9clar\u00e9e de l&rsquo;\u00e9ducation publique russe.<\/p>\n<\/p>\n<p><p>Le ph\u00e9nom\u00e8ne R&oacute;dina explique pourquoi, apr\u00e8s l&rsquo;effondrement financier, commercial et politique de l&rsquo;URSS, la Russie a pu arr\u00eater et inverser le processus \u00e0 l&rsquo;effondrement social, n&rsquo;a jamais couru de grand danger d&rsquo;effondrement culturel et a pu tout r\u00e9cup\u00e9rer et m\u00eame un peu plus. C&rsquo;est parce que R&oacute;dina n&rsquo;a rien \u00e0 voir avec la finance, le commerce ou la politique. Sa place est dans le c&oelig;ur, et aucune vicissitude de la fortune ne peut la d\u00e9loger.<\/p>\n<\/p>\n<p><p>Pour en venir aux &Eacute;tats-Unis, quel est l&rsquo;int\u00e9r\u00eat amoureux quintessentiel de l&rsquo;Am\u00e9ricain ? Les &Eacute;tats-Unis sont une nation d&rsquo;immigrants (un clich\u00e9 certes, mais d\u00e9crivant une vraie r\u00e9alit\u00e9) qui ne sont pas venus l\u00e0 pour former un superethnos harmonieux avec les Am\u00e9rindiens et les rejoindre dans leur amour de leur terre natale. La plupart des gens sont venus dans l&rsquo;espoir de revendiquer un morceau de cette terre et y faire fortune, ou du moins d&rsquo;avoir une chance de monter son propre business. Ils sont venus pour coloniser, pour exploiter et pour faire du profit. Une paraphrase am\u00e9ricaine de Marc-Aur\u00e8le se lirait : &laquo;<em> De chaque chose en particulier, demandez : est-ce rentable ? <\/em>&raquo; &Agrave; la place des princes, des ducs, des comtes et des barons &ndash; les rangs aristocratiques de l&rsquo;Ancien Monde -, le Nouveau Monde compte des millionnaires, des multimillionnaires, des milliardaires et des multimilliardaires et le reste des malchanceux qui, selon les mots de Ronald Wright, &laquo;<em> se voient non pas comme un prol\u00e9tariat exploit\u00e9 mais comme des millionnaires temporairement g\u00ean\u00e9s <\/em>&raquo;. En Am\u00e9rique, la possession et la propri\u00e9t\u00e9 sont tout. Le premier et l&rsquo;ultime amour d&rsquo;un Am\u00e9ricain est&hellip; l&rsquo;argent.<\/p>\n<\/p>\n<p><p>La culture et la soci\u00e9t\u00e9 am\u00e9ricaines sont en option et ont \u00e9t\u00e9 largement laiss\u00e9es pour compte. La culture a surtout \u00e9t\u00e9 remplac\u00e9e par diverses offres commerciales, tandis que l&rsquo;histoire &ndash; bien que tr\u00e8s courte et souvent honteuse, elle reste une composante essentielle de la culture &ndash; est activement effac\u00e9e par la mise \u00e0 bas des statues publiques. La soci\u00e9t\u00e9 am\u00e9ricaine est tellement en conflit interne que les gens insistent pour \u00eatre arm\u00e9s jusqu&rsquo;aux dents et sont connus pour se tirer dessus \u00e0 la moindre provocation. La politique est un rago&ucirc;t toxique de r\u00e9criminations mutuelles \u00e0 travers un clivage partisan si vaste qu&rsquo;il ressemble souvent \u00e0 une guerre civile de faible intensit\u00e9. Le commerce a \u00e9t\u00e9 rel\u00e9gu\u00e9 aux mains de multinationales qui n&rsquo;ont aucun int\u00e9r\u00eat sp\u00e9cifique aux &Eacute;tats-Unis, si ce n&rsquo;est comme source de consommateurs et d&rsquo;argent gratuit, et il est actuellement en train de s&rsquo;effondrer, la demande des consommateurs chutant et les cha&icirc;nes de magasins fermant \u00e0 un rythme effr\u00e9n\u00e9. Une fois qu&rsquo;il n&rsquo;y aura plus de profits \u00e0 faire, les multinationales partiront tout simplement.<\/p>\n<\/p>\n<p><p>Mais il y a aussi un domaine magique o&ugrave; tout va comme par magie : la finance. Bien que tout le reste soit en difficult\u00e9, la bourse se porte bien et les banques restent solvables gr\u00e2ce \u00e0 l&rsquo;imprimerie miraculeuse de la R\u00e9serve f\u00e9d\u00e9rale. Une part de plus en plus importante de l&rsquo;\u00e9conomie est engloutie par un domaine financier d\u00e9j\u00e0 sur-gonfl\u00e9, sp\u00e9cialis\u00e9 dans la g\u00e9n\u00e9ration, puis la dissimulation, de cr\u00e9ances douteuses. Une grande partie des entreprises sont des zombies accros \u00e0 l&rsquo;argent gratuit avec lequel ils peuvent faire grimper le prix de leurs actions en rachetant leurs titres. Pendant ce temps, une grande partie de la population est confront\u00e9e au d\u00e9nuement.<\/p>\n<\/p>\n<p><p>L&rsquo;amour de l&rsquo;argent par-dessus tout explique clairement pourquoi les &Eacute;tats-Unis s&rsquo;effondrent dans l&rsquo;ordre inverse de l&rsquo;ordre canonique, la finance &ndash; qui devrait \u00eatre le premier pilier \u00e0 s&rsquo;effondrer &ndash; \u00e9tant pour ainsi dire le seul \u00e0 rester intact (pour l&rsquo;instant). C&rsquo;est Aristote qui, le premier, a d\u00e9fini l&rsquo;\u00e9conomie comme l&rsquo;\u00e9change de biens et de services contre de l&rsquo;argent, le commerce comme un parasite de l&rsquo;\u00e9conomie (o&ugrave; ceux qui ne cr\u00e9ent rien en extraient une part par le commerce) et la finance comme un parasite du commerce (qui extrait une part quand la monnaie passe d&rsquo;une main \u00e0 l&rsquo;autre). Ainsi, la finance est un parasite sur un parasite et ne peut exister sans un h\u00f4te qui est lui-m\u00eame un parasite. Et cet h\u00f4te est en train de mourir.<\/p>\n<\/p>\n<p><p>En attendant, la richesse personnelle et priv\u00e9e reste la condition sine<em> qua non<\/em> de ce que signifie \u00eatre un Am\u00e9ricain &ndash; synonyme de dignit\u00e9 et de libert\u00e9. Nassim Nicholas Taleb a donn\u00e9 \u00e0 la condition d&rsquo;avoir une fortune personnelle suffisante le nom \u00e9vocateur de <em>&laquo; fuck-you-money &raquo;<\/em>. Ce que Taleb a omis d&rsquo;indiquer, c&rsquo;est qui, en fin de compte, finira par \u00eatre bais\u00e9. Mais il ne faut pas beaucoup d&rsquo;imagination pour savoir qui ce sera. D&rsquo;une certaine mani\u00e8re, je doute qu&rsquo;une fois que ce sera le cas, il y aura beaucoup d&rsquo;amour \u00e0 faire circuler.<\/p>\n<\/p>\n<p><p>Le 23 juillet 2020, <a href=\"http:\/\/cluborlov.blogspot.com\/2020\/07\/the-virtuous-collapse-sequence.html\">Club Orlov<\/a>, &ndash; Traduction du <em><a href=\"https:\/\/lesakerfrancophone.fr\/la-vertueuse-sequence-deffondrement\">Sakerfrancophone<\/a><\/em><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La vertueuse s\u00e9quence de l&rsquo;effondrement Cela fait douze ans que j&rsquo;ai publi\u00e9 mon essai &laquo; Les cinq stades de l&rsquo;effondrement &raquo; dans lequel j&rsquo;ai propos\u00e9 pour la premi\u00e8re fois une taxonomie de l&rsquo;effondrement, en la d\u00e9composant en effondrements financiers, commerciaux, politiques, sociaux et culturels, ainsi que ce que j&rsquo;ai con\u00e7u comme une s\u00e9quence d&rsquo;effondrement canonique,&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[29],"tags":[3163,2631,2803,8118,2668,15340,2730,963,2804],"class_list":["post-79361","post","type-post","status-publish","format-standard","hentry","category-les-carnets-de-dimitri-orlov-1","tag-culture","tag-de","tag-effondrement","tag-lamericanisme","tag-orlov","tag-rodina","tag-russie","tag-urss","tag-usa"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79361"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79361\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}