{"id":79365,"date":"2020-08-01T16:14:32","date_gmt":"2020-08-01T16:14:32","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2020\/08\/01\/ainsi-soit-il-approximativement-en-tout-cas\/"},"modified":"2020-08-01T16:14:32","modified_gmt":"2020-08-01T16:14:32","slug":"ainsi-soit-il-approximativement-en-tout-cas","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2020\/08\/01\/ainsi-soit-il-approximativement-en-tout-cas\/","title":{"rendered":"\u201cAinsi soit-il\u201d, \u2013 approximativement, en tout cas"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">\u00ab\u00a0Ainsi soit-il\u00a0\u00bb, &ndash; approximativement, en tout cas<\/h2>\n<\/p>\n<p><p>1<sup>er<\/sup> ao&ucirc;t 2020 &ndash; Les caprices de l&rsquo;actualit\u00e9 mettent en \u00e9vidence combien cette actualit\u00e9 peut s&rsquo;arranger pour nous donner des signaux nous permettant de lire en elle comme \u00e0 livre ouvert et hors des simulacres, c&rsquo;est-\u00e0-dire hors de toute contrainte de sa hi\u00e9rarchie de surveillance, tournant les interdits du dogme comme si l&rsquo;on s&rsquo;en jouait. Elle s&rsquo;appuie pourtant sur une <em>narrative <\/em>pleine de d\u00e9votion religieuse dans sa forme, un conformisme dont on craint de d\u00e9vier comme l&rsquo;on craint l&rsquo;excommunication d&rsquo;une religion qu&rsquo;on v\u00e9n\u00e8re et qu&rsquo;on craint \u00e0 la fois.<\/p>\n<\/p>\n<p><p>Madame Chantal Delsol r\u00e9sume comme ceci la conformation du simulacre du temps dans &laquo; <em>Le cr\u00e9puscule de l&rsquo;universel<\/em> &raquo;, son dernier ouvrage de f\u00e9vrier 2020 : &laquo; <em>La morale des droits de l&rsquo;homme a acquis pour son compte le caract\u00e8re sacr\u00e9 autrefois port\u00e9 par la religion originelle. Notre morale est, litt\u00e9ralement, devenue une religion, la seule religion qui nous reste apr\u00e8s la fin de la chr\u00e9tient\u00e9. La ferveur qu&rsquo;elle suscite, l&rsquo;organisation de ses rites par l&rsquo;interm\u00e9diaire de ses pr\u00eatres, ne laisse aucun doute l\u00e0-dessus. Que s&rsquo;est-il pass\u00e9 ? Arendt et Voegelin avaient montr\u00e9 l&rsquo;aspect religieux des totalitarismes du XX\u00e8me si\u00e8cle. Probablement nous trouvons-nous, avec l&rsquo;humanitarisme, devant une nouvelle expression religieuse. <\/em>&raquo;<\/p>\n<\/p>\n<p><p>Sans aucun doute tout cela, sauf qu&rsquo;il y a, comme je l&rsquo;\u00e9crivais plus haut, \u00ab\u00a0les caprices de l&rsquo;actualit\u00e9\u00a0\u00bb dus \u00e0 la toute-puissance de la communication ; en effet, la communication a permis tout ce qui se passe aujourd&rsquo;hui mais a en m\u00eame temps d\u00e9velopp\u00e9 son double antagoniste, sous la forme de l'\u00a0\u00bb<a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-technologisme-versus-communication-1\">effet-<em>Janus<\/em><\/a>\u00ab\u00a0&#8230; Il s&rsquo;agit d&rsquo;un r\u00e9jouissant accident pour mon compte, o&ugrave; l&rsquo;inversion r\u00e9gnant sur ce temps devient vertueuse, selon le point de vue antiSyst\u00e8me, lorsqu&rsquo;il s&rsquo;exerce sur une communication acquise au Syst\u00e8me mais produisant des effets invertis qui lui sont absolument d\u00e9favorables. Lorsque madame Delsol d\u00e9signe notre temps comme &laquo; <em>apr\u00e8s la fin du christianisme <\/em>&raquo;, elle a tout \u00e0 fait raison sauf que la <em>narrative <\/em>officielle de &laquo; <em>Notre morale, litt\u00e9ralement, devenue une religion<\/em> &raquo;, continue, elle, \u00e0 proclamer que le christianisme existe bel et bien. La <em>narrative <\/em>officielle se d\u00e9ploie effectivement selon les n\u00e9cessit\u00e9s de son simulacre des libert\u00e9s diverses (libert\u00e9 du culte, libert\u00e9 d&rsquo;expression, etc., aux c\u00f4t\u00e9s de la libert\u00e9 des genres, de la libert\u00e9 des sexes, de la libert\u00e9 des libert\u00e9s et de la libert\u00e9 des apparences de l&rsquo;enfermement, de la libert\u00e9 des tout-et-rien et de la libert\u00e9 des riens-du-tout, etc.)&#8230;<\/p>\n<\/p>\n<p><p>(On verra plus loin que je plaide, moi, pour une complicit\u00e9 et un accord tactique mais aussi strat\u00e9gique entre le christianisme et le Syst\u00e8me pour que ces deux mort-vivants zombifi\u00e9s s&rsquo;entr&rsquo;aident et tentent de faire leur chute commune moins rude qu&rsquo;elle ne menace, &ndash; avec \u00e9chec garanti dans le cas de cette alliance pas si contre-nature qu&rsquo;on croit&#8230; Ce qui, en l&rsquo;occurrence, revient \u00e0 plaider que le christianisme, s&rsquo;il est mort en tant que tel, continue \u00e0 exister sous une forme simulacre et \u00e0 jouer son r\u00f4le pour ne pas d\u00e9sesp\u00e9rer Notre-Dame-de-Paris.)<\/p>\n<\/p>\n<p><p>Venons-en au principal de la circonstance. J&rsquo;ai parl\u00e9 des \u00ab\u00a0caprices de l&rsquo;actualit\u00e9\u00a0\u00bb : que veut-il dire, PhG ? Il s&rsquo;agit de deux \u00e9v\u00e9nements apparemment assez secondaires au regard des crises \u00e9normes dans le cadre desquelles ils s&rsquo;inscrivent, mais pourtant bien significatifs pour notre propos. Voici&#8230;<\/p>\n<\/p>\n<p><p>&bull; D&rsquo;abord une nouvelle publi\u00e9e <a href=\"https:\/\/www.breitbart.com\/2020-election\/2020\/07\/28\/national-catholic-reporter-aoc-is-the-future-of-the-catholic-church\/\">par <em>Breitbart.News<\/em><\/a>, site violemment antid\u00e9mocrate-US, et bien entendu adversaire tr\u00e8s-critique de AOC (Alexandria Ocasio-Cortez) ; il s&rsquo;agit de la d\u00e9put\u00e9e d\u00e9mocrate de l&rsquo;ultragauche, \u00e0 qui l&rsquo;on fait une r\u00e9putation de &lsquo;marxiste culturelle&rsquo; (gramscisme) et qui, \u00f4 surprise (\u00f4 simulacre de surprise, veux-je dire) se retrouve encens\u00e9e par une revue catholique. AOC devient ainsi, dans ce jugement plein d&rsquo;optimisme et de confiance dans l&rsquo;avenir, dans le cadre existant, \u00ab\u00a0le futur de la religion catholique aux &Eacute;tats-Unis.<\/p>\n<\/p>\n<p><p>&laquo; <em>Dans un article publi\u00e9 lundi<\/em> [27 juillet]<em>, la r\u00e9dactrice en chef de National Catholic Reporter, Heidi Schlumpf, a fait l&rsquo;\u00e9loge de la d\u00e9put\u00e9e Ocasio-Cortez (D-NY) en la qualifiant de \u00ab\u00a0rock-star millenium, leader de la gauche\u00a0\u00bb, qui \u00ab\u00a0a grandi dans la religion catholique et a m\u00eame \u00e9crit pour un magazine catholique sur la mani\u00e8re dont sa foi influence ses opinions sur les politiques publiques telles que l&rsquo;incarc\u00e9ration de masse\u00a0\u00bb.<\/em><\/p>\n<p>&raquo; <em>En \u00e9coutant son \u00ab\u00a0discours \u00e9tonnant\u00a0\u00bb \u00e0 la Chambre des Repr\u00e9sentants la semaine derni\u00e8re, \u00ab\u00a0j&rsquo;ai \u00e9t\u00e9 frapp\u00e9e par le nombre de fois o&ugrave; elle a fait r\u00e9f\u00e9rence aux valeurs catholiques\u00a0\u00bb, a \u00e9crit Mme Schlumpf<\/em>.  [&#8230;]<\/p>\n<p>&raquo; <em>S&rsquo;il doit y avoir un avenir pour l&rsquo;&Eacute;glise catholique aux &Eacute;tats-Unis, \u00e9crit Schlumpf, il doit \u00ab\u00a0ressembler \u00e0 Ocasio-Cortez dans sa passion pour la justice et la dignit\u00e9 humaine, et dans son courage et son int\u00e9grit\u00e9, m\u00eame face \u00e0 des attaques vulgaires\u00a0\u00bb.<\/em><\/p>\n<\/p>\n<p><p>&bull; Le <a href=\"https:\/\/www.youtube.com\/watch?time_continue=1&#038;v=txl6l5ORhzo&#038;feature=emb_logo\">17 juillet 2020<\/a>, Michel Onfray \u00e9tait l&rsquo;interview\u00e9 de la s\u00e9rie du site <em>Thinkerview<\/em>, soit deux bonnes heures et demie de questions\/interruptions-r\u00e9ponses. L\u00e0-dedans, Onfray a beaucoup de choses dites et montr\u00e9es, et <em>Valeurs Actuelles <\/em>y a trouv\u00e9 une p\u00e9pite pass\u00e9e inaper\u00e7ue aux diverses auditions : Onfray jugeant l&rsquo;Occident en train de dispara&icirc;tre essentiellement \u00e0 cause de la mort du christianisme. L&rsquo;ensemble a \u00e9t\u00e9 repris dans une courte nouvelle <a href=\"https:\/\/fr.sputniknews.com\/france\/202007301044178082-loccident-va-disparaitre-michel-onfray-prononce-sa-sombre-prediction-et-fournit-des-explications--\/\">du 30 juillet<\/a> par <em>Spoutnik-<\/em>fran\u00e7ais.<\/p>\n<\/p>\n<p><p>&laquo; <em>Dans un entretien accord\u00e9 le 17 juillet sur le plateau du web TV Thinkerview et rep\u00e9r\u00e9 par Valeurs actuelles, Michel Onfray a pr\u00e9dit la disparition de la <a href=\"https:\/\/fr.sputniknews.com\/france\/202007281044170478-quel-est-notre-avenir-sarkozy-inquiet-au-sujet-de-lidentite-francaise\/\" target=\"_blank\">civilisation europ\u00e9enne<\/a>. \u00ab\u00a0Nous allons dispara&icirc;tre, l&rsquo;Occident va dispara&icirc;tre. Il n&rsquo;y a aucune raison pour qu&rsquo;il puisse continuer \u00e0 durer\u00a0\u00bb, mart\u00e8le-t-il.<\/em><\/p>\n<p>&raquo; <em>Pour le philosophe, la d\u00e9christianisation est l&rsquo;un des vecteurs du d\u00e9clin occidental. \u00ab\u00a0Le christianisme ne fonctionne plus chez les chr\u00e9tiens: ils ne croient plus au purgatoire, \u00e0 l&rsquo;Enfer, \u00e0 la parousie, \u00e0 Satan, \u00e0 l&rsquo;eucharistie, \u00e0 la virginit\u00e9 de Marie&hellip;\u00a0\u00bb, explique-t-il, ajoutant que \u00ab\u00a0tout ce qui \u00e9tait dogmatique, tout ce qui supposait une foi a disparu\u00a0\u00bb.<\/em><\/p>\n<p>&raquo; <em>Mais la d\u00e9christianisation n&rsquo;est pas la seule raison du d\u00e9clin de l&rsquo;Occident. Selon le philosophe, l&rsquo;app\u00e9tence contemporaine pour la d\u00e9construction serait \u00e0 l&rsquo;origine du ph\u00e9nom\u00e8ne. \u00ab\u00a0Nous sommes dans une civilisation de l&rsquo;\u00e9puisement. Nous n&rsquo;aimons que ce qui nous d\u00e9teste, tout ce qui nous d\u00e9truit est<\/em> [per\u00e7u comme] <em>formidable\u00a0\u00bb. \u00ab\u00a0Il y a une <a href=\"https:\/\/fr.sputniknews.com\/france\/202007301044178048-touche-pas-a-mon-histoire-alain-finkielkraut-reagit-au-phenomene-du-deboulonnage-de-statues\/\" target=\"_blank\">passion pour la d\u00e9construction<\/a>. Il faut d\u00e9truire la v\u00e9rit\u00e9, l&rsquo;Histoire\u00a0\u00bb. <\/em>&raquo;<\/p>\n<\/p>\n<p><p>Vous voyez le genre des discours, n&rsquo;est-ce pas. D&rsquo;un c\u00f4t\u00e9, la catho-simulacre, tr\u00e8s moderne, tr\u00e8s optimiste, qui s&rsquo;enthousiasme pour la petite AOC, universaliste de la diversit\u00e9 et mentor[e ?] de l&rsquo;ultra-gauche nourrie, \u00e9g\u00e9rie des d\u00e9mocrates US, ce parti Clinton-Soros-BLM \u00e0 la fois corrompu, globaliste et d\u00e9licieusement \u00e9brou\u00e9 dans les rets du Syst\u00e8me. (Au reste, j&rsquo;aime bien AOC, car je crois que son extr\u00e9misme d\u00e9crit comme hyper-Syst\u00e8me et hyper-catho-postmoderniste, est tellement &lsquo;<em>hyper hip-hop<\/em>&lsquo; contribue \u00e0 entretenir fout une belle pagaille au sein du syst\u00e8me de l&rsquo;am\u00e9ricanisme, d\u00e9mocrates et Clinton-Epstein compris. Elle va si loin, la r\u00e9volutionnaire-Syst\u00e8me, qu&rsquo;elle fait comme toutes les r\u00e9volutions, &ndash; retour \u00e0 son point de d\u00e9part dans une ellipse finalement antiSyst\u00e8me.)<\/p>\n<\/p>\n<p><p>De l&rsquo;autre c\u00f4t\u00e9 et du c\u00f4t\u00e9 de Onfray, l&rsquo;ath\u00e9e, souverainiste de gauche, incroyant affirm\u00e9 et gaulliste, proclamant la fin de l&rsquo;Occident puisque le christianisme est mort, crev\u00e9, <em>kaput <\/em>; ce qui revient dans le chef de l&rsquo;ath\u00e9e-incroyant, \u00e0 faire du christianisme la poutre-ma&icirc;tresse d\u00e9sormais pourrie et v\u00e9rol\u00e9e de notre civilisation devenue contre-civilisation. En cela, Onfray est bien dans la tradition des \u00ab\u00a0cathos-du-dehors\u00a0\u00bb pratiquant l'\u00a0\u00bbath\u00e9isme catholique\u00a0\u00bb, incroyants jugeant essentiel le christianisme\/le catholicisme, pour la dur\u00e9e structurelle de la France et pour sa puissance spirituelle propre.<\/p>\n<\/p>\n<p><p>(Les \u00ab\u00a0cathos-du-dehors\u00a0\u00bb ? On en a d\u00e9j\u00e0 parl\u00e9 ici et l\u00e0, et notamment <a href=\"https:\/\/www.dedefensa.org\/article\/le-facteur-catholique-et-lexemple-de-michael-moore\">de cette fa\u00e7on<\/a>, du temps o&ugrave; il \u00e9tait encore envisageable d&rsquo;utiliser le catholicisme, non comme religion mais, si bien manipul\u00e9 par des antiSyst\u00e8me, comme machine anticapitaliste : &laquo; &#8230; <em>Ces intellectuels, selon Gustave Thibaudet en 1927: \u00ab\u00a0Chateaubriand, le Sainte-Beuve de Port-Royal, Auguste Comte, Barbey d&rsquo;Aurevilly, Barr\u00e8s, Maurras, P\u00e9guy, Montherlant\u00a0\u00bb ; ou bien encore, selon le mot de l&rsquo;Allemand Curtius: \u00ab\u00a0L\u00a0\u00bbath\u00e9isme catholique&rsquo; est un ph\u00e9nom\u00e8ne exclusivement fran\u00e7ais\u00a0\u00bb.&raquo;<\/em>)<\/p>\n<\/p>\n<p><p>Bref, si l&rsquo;on me passe les d\u00e9tails pour aller \u00e0 l&rsquo;essentiel, on admettra que le dialogue AOC-Onfray est \u00e9difiant au moins sur un point : la mort par pourriture gangren\u00e9e de l&rsquo;&Eacute;glise, entre ses trahisons et ses d\u00e9magogies incroyables de servilit\u00e9, comme r\u00e9f\u00e9rence civilisationnelle de la religion. Entre l&rsquo;aventurisme gauchiste-droitdel&rsquo;hommiste et le m\u00e9pris souverainiste, cette religion n&rsquo;a plus aucune existence spirituelle et devient une des roues dent\u00e9es de la machine broyeuse de la structuration sociale et civilisationnelle qu&rsquo;elle (cette religion) avait contribu\u00e9e largement \u00e0 mettre en place. De ce point de vue, pour moi la connivence de la religion chr\u00e9tienne\/du catholicisme d&rsquo;une part, du Syst\u00e8me d&rsquo;autre part, est av\u00e9r\u00e9e, et il est bon que la chose apparaisse d&rsquo;une fa\u00e7on aussi \u00e9vidente au travers des d\u00e9clarations, observations, engagements, etc., qu&rsquo;on rencontre ici ou l\u00e0, aujourd&rsquo;hui o&ugrave; l&rsquo;on ne dissimule plus rien, ni de sa folie utopiste, ni de son pessimisme roboratif.<\/p>\n<\/p>\n<p><p>Sur ce sujet, il m&rsquo;est arriv\u00e9 de m&rsquo;attarder, comme dans l&rsquo;extrait suivant, extrait d&rsquo;un autre extrait que je m\u00e9dite d&rsquo;offrir aux plus endurants de mes lecteurs, &ndash; comme je m&rsquo;en explique apr\u00e8s ce texte qui date (bouclage) de 2014.<\/p>\n<\/p>\n<p><p>&laquo; <em>Il y a une troublante similitude entre le sort de cette &Eacute;glise emport\u00e9e dans une crise de dissolution qui fait craindre l&rsquo;effondrement, cette situation qui semble \u00eatre devenue finalement sa fa\u00e7on d&rsquo;\u00eatre sinon sa raison d&rsquo;\u00eatre et plus du tout une cause effroyable et d\u00e9testable, et le Syst\u00e8me lui-m\u00eame, lanc\u00e9 sur une course similaire. On ne peut se d\u00e9partirlib\u00e9rer d&rsquo;un malaise, une fois qu&rsquo;il vous a saisi dans ses griffes, devant cette occurrence qui semblerait <strong>rassembler <\/strong>ces deux entit\u00e9s fondamentales, comme si m\u00eame un march\u00e9 pouvait avoir \u00e9t\u00e9 conclu entre les deux, je dirais presque \u00ab\u00a0comme deux marchands de tapis\u00a0\u00bb ; ce march\u00e9, pour tenter de freiner cette chute effrayante en additionnant et combinant ce qui leur reste de forces. L&rsquo;&Eacute;glise apporterait au Syst\u00e8me repr\u00e9sentatif de notre contre-civilisation, ce qu&rsquo;on nomme lestement \u00ab\u00a0un suppl\u00e9ment d&rsquo;\u00e2me\u00a0\u00bb, ou d&rsquo;apparence d&rsquo;\u00e2me, comme on donne une caution, comme pour sembler lui donner un sens ; le Syst\u00e8me offrirait \u00e0 l&rsquo;&Eacute;glise une pseudo-s&ucirc;ret\u00e9 en lui reconnaissant une sorte de magist\u00e8re moral, exprim\u00e9 essentiellement dans le vacarme du syst\u00e8me de la communication, par le prestige de l&rsquo;institution papale, par la fascination \u00e9prouv\u00e9e pour l&rsquo;institution papale, si \u00e9vidente lors de l&rsquo;\u00e9lection d&rsquo;un nouveau pape (cas de mars 2013 justement, apr\u00e8s les circonstances inhabituelles et n\u00e9cessairement troublantes de la d\u00e9mission de Beno&icirc;t XVI)&hellip; Les deux s&rsquo;adoubant ainsi l&rsquo;un l&rsquo;autre feraient de cette hypoth\u00e8se d&rsquo;une sorte de march\u00e9 une chose malheureuse, qu&rsquo;on pourrait juger \u00e0 juste titre d&rsquo;une extr\u00eame bassesse. Il n&rsquo;est pas question d&rsquo;ajouter ici une critique de circonstance port\u00e9e contre le Christianisme ; il est question d&rsquo;observer en approchant par des incidences significatives que le Christianisme, qui a sembl\u00e9 se contracter dans l&rsquo;&Eacute;glise elle-m\u00eame, n&rsquo;oppose aucune r\u00e9sistance s\u00e9rieuse \u00e0 un courant qui met en cause l&rsquo;essence m\u00eame de son origine, &ndash; ce courant qu&rsquo;il<\/em> [le Christianisme]<em> a lui-m\u00eame contribu\u00e9 \u00e0 cr\u00e9er, d&rsquo;une fa\u00e7on si regrettable ; au contraire, il continuerait \u00e0 y contribuer par souci de tactique sans la moindre \u00e9laboration, mais quoi, persevere diabolicum quoi qu&rsquo;il en soit. Cela nous conduit \u00e0 une remarque d&rsquo;importance, encore plus en y ajoutant le constat de la longue p\u00e9riode que nous avons observ\u00e9e et en consid\u00e9rant ce qu&rsquo;a \u00e9t\u00e9 le combat constant de l&rsquo;&Eacute;glise.<\/em><\/p>\n<p>&raquo; <em>L&rsquo;hypoth\u00e8se th\u00e9orique et sp\u00e9culative du rapprochement du Christianisme avec la force du Syst\u00e8me qui est n\u00e9cessairement ath\u00e9e par rapport \u00e0 la spiritualit\u00e9 renvoyant au Principe et \u00e0 l&rsquo;Unique, cette hypoth\u00e8se qui devrait \u00eatre qualifi\u00e9e de \u00ab\u00a0satanique\u00a0\u00bb du point de vue de l&rsquo;&Eacute;glise ne se d\u00e9ment pas d&rsquo;elle-m\u00eame parce que nous percevons d&rsquo;une fa\u00e7on assez \u00e9vidente cette chose inattendue et terrible que ce rapprochement n&rsquo;est pas n\u00e9cessairement contre-nature. De l\u00e0 notre conclusion, pour nos futures r\u00e9flexions, \u00e0 propos de ce destin terrestre de l&rsquo;&Eacute;glise, passant par son manquement \u00e0 l&rsquo;accomplissement de sa Mission au Temps des Ccath\u00e9drales, puis ce qui a suivi, &ndash; conclusion suivant laquelle l&rsquo;&Eacute;glise s&rsquo;est bien plus pr\u00e9occup\u00e9e des croyances, des religions et des particularit\u00e9s y compris et m\u00eame surtout internes concurrentes d&rsquo;elle-m\u00eame telle qu&rsquo;elle se con\u00e7oit, qu&rsquo;elle a constamment soup\u00e7onn\u00e9es, combattues, d\u00e9nonc\u00e9es, tent\u00e9 d&rsquo;amadouer \u00e0 son avantage, etc., que des forces anti-spirituelles et modernistes engag\u00e9es pourtant dans la furieuse et hurlante bataille contre le Principe qui a accompagn\u00e9 le \u00ab\u00a0d\u00e9cha&icirc;nement de la Mati\u00e8re\u00a0\u00bb. On en d\u00e9duirait effectivement que l&rsquo;alliance \u00e9voqu\u00e9e ici est moins \u00ab\u00a0contre-nature\u00a0\u00bb qu&rsquo;elle ne para&icirc;t, et alors son principe (en r\u00e9alit\u00e9 anti-principe, si l&rsquo;on peut dire)  qui ne serait pas rejet\u00e9 accomplirait compl\u00e8tement le destin catastrophique du<\/em> <em>Christianisme en rendant compte<\/em> [pour les justifier]<em> de l&rsquo;acceptabilit\u00e9 des soup\u00e7ons les plus profonds<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Cet extrait fait partie d&rsquo;un extrait plus important qui cl\u00f4t la Deuxi\u00e8me Partie du Tome-II de <em>La Gr\u00e2ce de l&rsquo;Histoire<\/em>, &ndash; &laquo; <em>La passerelle eschatologique <\/em>&raquo;. Cette finale concerne essentiellement une analyse de la situation du christianisme, essentiellement le catholicisme, \u00e0 l&rsquo;heure actuelle.<\/p>\n<\/p>\n<p><p>Il ne s&rsquo;agit pas tout \u00e0 fait du texte figurant dans le livre parce qu&rsquo;entre ce bouclage de la r\u00e9daction apr\u00e8s relectures et corrections, et l&rsquo;impression du livre, il y a eu des relectures suppl\u00e9mentaires et donc quelques changements dont je pense qu&rsquo;ils \u00e9taient mineurs. (Difficile d&rsquo;en avoir le souvenir exact, entre ces relectures et ces corrections diverses.)<\/p>\n<\/p>\n<p><p>Ceux qui veulent tenter l&rsquo;aventure peuvent donc s&rsquo;y mettre.<\/p>\n<\/p>\n<p><p>____________________________<\/p>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Conclusion de &laquo; <em>La passerelle de l&rsquo;eschatologie <\/em>&raquo;<\/h2>\n<\/p>\n<p><h2 class=\"titleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">A-parte du temps courant&hellip;<\/h2>\n<\/p>\n<p><p>En effet, ce passage du r\u00e9cit portant sur la \u00ab\u00a0passerelle eschatologique\u00a0\u00bb entre le XVII\u00e8me si\u00e8cle et notre XXI\u00e8me si\u00e8cle, de ce si\u00e8cle au n\u00f4tre selon un rapprochement inattendu alors qu&rsquo;il pla&icirc;t tant \u00e0 l&rsquo;esprit courant de se croire exclusivement enfant du XVIII\u00e8me, il n&rsquo;est pas illogique de mentionner une appr\u00e9ciation succincte sur ce XXI\u00e8me si\u00e8cle, du point de vue du Christianisme comme nous l&rsquo;avons \u00e9voqu\u00e9, c&rsquo;est-\u00e0-dire par rapport \u00e0 la progression du Mal. Parcourant ces lignes \u00e0 nouveau, avant la premi\u00e8re publication dite \u00ab\u00a0en ligne\u00a0\u00bb, \u00e0 l&rsquo;\u00e9t\u00e9 2013, puis les ajouts \u00e0 mesure des corrections et relectures successives, la tentation s&rsquo;est ajout\u00e9e \u00e0 la logique d&rsquo;y mettre quelques consid\u00e9rations sur les \u00e9v\u00e9nements les plus r\u00e9cents, les plus conjoncturels, les plus \u00e9loign\u00e9s de la r\u00e9flexion qui cherche profondeur et dur\u00e9e plut\u00f4t qu&rsquo;\u00e9clat et fugacit\u00e9 ; et ceci, sans nul doute, nullement pour d\u00e9florer cela, bien entendu&#8230; La tentation existe parce que ces \u00e9v\u00e9nements ne contredisent en rien le <strong>fait central<\/strong> du propos de cette partie du r\u00e9cit ; malheureusement, ils le renforcent, l&rsquo;\u00e9clairent d&rsquo;une lumi\u00e8re sinistre et suscitent un jugement de la plus grande bassesse sur le sort de l&rsquo;&Eacute;glise de Rome ; et leur \u00e9clairage est d&rsquo;autant plus \u00e0 prendre en consid\u00e9ration que ces temps du XXI\u00e8me si\u00e8cle sont de facture m\u00e9tahistorique, et que les \u00e9v\u00e9nements le sont n\u00e9cessairement avec eux d&rsquo;une fa\u00e7on telle qu&rsquo;ils en ont acquis un autonomie qui les fait grandioses et sublimes.<\/p>\n<\/p>\n<p><p>Il y a une troublante similitude entre le sort de cette &Eacute;glise emport\u00e9e dans une crise de dissolution qui fait craindre l&rsquo;effondrement, cette situation qui semble \u00eatre devenue finalement sa fa\u00e7on d&rsquo;\u00eatre sinon sa raison d&rsquo;\u00eatre et plus du tout une cause effroyable et d\u00e9testable, et le Syst\u00e8me lui-m\u00eame, lanc\u00e9 sur une course similaire. On ne peut se d\u00e9partir d&rsquo;un malaise, une fois qu&rsquo;il vous a saisi dans ses griffes, devant cette occurrence qui semblerait <strong>rassembler<\/strong> ces deux entit\u00e9s fondamentales, comme si m\u00eame un march\u00e9 pouvait avoir \u00e9t\u00e9 conclu entre les deux, je dirais presque \u00ab\u00a0comme deux marchands de tapis\u00a0\u00bb ; ce march\u00e9, pour tenter de freiner cette chute effrayante en additionnant et combinant ce qui leur reste de forces. L&rsquo;&Eacute;glise apporterait au Syst\u00e8me repr\u00e9sentatif de notre contre-civilisation, ce qu&rsquo;on nomme lestement \u00ab\u00a0un suppl\u00e9ment d&rsquo;\u00e2me\u00a0\u00bb, ou d&rsquo;apparence d&rsquo;\u00e2me, comme on donne une caution, comme pour sembler lui donner un sens ; le Syst\u00e8me offrirait \u00e0 l&rsquo;&Eacute;glise une pseudo-s&ucirc;ret\u00e9 en lui reconnaissant une sorte de magist\u00e8re moral, exprim\u00e9 essentiellement dans le vacarme du syst\u00e8me de la communication, par le prestige de l&rsquo;institution papale, par la fascination \u00e9prouv\u00e9e pour l&rsquo;institution papale, si \u00e9vidente lors de l&rsquo;\u00e9lection d&rsquo;un nouveau pape (cas de mars 2013 justement, apr\u00e8s les circonstances inhabituelles et n\u00e9cessairement troublantes de la d\u00e9mission de Beno&icirc;t XVI)&hellip; Les deux s&rsquo;adoubant ainsi l&rsquo;un l&rsquo;autre feraient de cette hypoth\u00e8se d&rsquo;une sorte de march\u00e9 une chose malheureuse, qu&rsquo;on pourrait juger \u00e0 juste titre d&rsquo;une extr\u00eame bassesse. Il n&rsquo;est pas question d&rsquo;ajouter ici une critique de circonstance port\u00e9e contre le Christianisme ; il est question d&rsquo;observer en approchant par des incidences significatives que le Christianisme, qui a sembl\u00e9 se contracter dans l&rsquo;&Eacute;glise elle-m\u00eame, n&rsquo;oppose aucune r\u00e9sistance s\u00e9rieuse \u00e0 un courant qui met en cause l&rsquo;essence m\u00eame de son origine, &ndash; ce courant qu&rsquo;il a lui-m\u00eame contribu\u00e9 \u00e0 cr\u00e9er, d&rsquo;une fa\u00e7on si regrettable ; au contraire, il continuerait \u00e0 y contribuer par souci de tactique sans la moindre \u00e9laboration, mais quoi, <em>persevere diabolicum<\/em> quoi qu&rsquo;il en soit. Cela nous conduit \u00e0 une remarque d&rsquo;importance, encore plus en y ajoutant le constat de la longue p\u00e9riode que nous avons observ\u00e9e et en consid\u00e9rant ce qu&rsquo;a \u00e9t\u00e9 le combat constant de l&rsquo;&Eacute;glise.<\/p>\n<\/p>\n<p><p>L&rsquo;hypoth\u00e8se th\u00e9orique et sp\u00e9culative du rapprochement du Christianisme avec la force du Syst\u00e8me qui est n\u00e9cessairement ath\u00e9e par rapport \u00e0 la spiritualit\u00e9 renvoyant au Principe et \u00e0 l&rsquo;Unique, cette hypoth\u00e8se qui devrait \u00eatre qualifi\u00e9e de \u00ab\u00a0satanique\u00a0\u00bb du point de vue de l&rsquo;&Eacute;glise ne se d\u00e9ment pas d&rsquo;elle-m\u00eame parce que nous percevons d&rsquo;une fa\u00e7on assez \u00e9vidente cette chose inattendue et terrible que ce rapprochement n&rsquo;est pas n\u00e9cessairement contre-nature. De l\u00e0 notre conclusion, pour nos futures r\u00e9flexions, \u00e0 propos de ce destin terrestre de l&rsquo;&Eacute;glise, passant par son manquement \u00e0 l&rsquo;accomplissement de sa Mission au Temps des Cath\u00e9drales, puis ce qui a suivi, &ndash; conclusion suivant laquelle l&rsquo;&Eacute;glise s&rsquo;est bien plus pr\u00e9occup\u00e9e des croyances, des religions et des particularit\u00e9s y compris et m\u00eame surtout internes concurrentes d&rsquo;elle-m\u00eame telle qu&rsquo;elle se con\u00e7oit, qu&rsquo;elle a constamment soup\u00e7onn\u00e9es, combattues, d\u00e9nonc\u00e9es, etc., que des forces anti-spirituelles et modernistes engag\u00e9es pourtant dans la furieuse et hurlante bataille contre le Principe qui a accompagn\u00e9 le \u00ab\u00a0d\u00e9cha&icirc;nement de la Mati\u00e8re\u00a0\u00bb. On en d\u00e9duirait effectivement que l&rsquo;alliance \u00e9voqu\u00e9e ici est moins \u00ab\u00a0contre-nature\u00a0\u00bb qu&rsquo;elle ne para&icirc;t, et alors son principe (en r\u00e9alit\u00e9 anti-principe, si l&rsquo;on peut dire) qui ne serait pas rejet\u00e9 accomplirait compl\u00e8tement le destin catastrophique du Christianisme en rendant compte de l&rsquo;acceptabilit\u00e9 [pour les justifier] des soup\u00e7ons les plus profonds.<\/p>\n<\/p>\n<p><p>Le cas de l&rsquo;art est extr\u00eamement illustrateur et tr\u00e8s r\u00e9v\u00e9lateur. Nous employons le mot avec la minuscule de l&#8217;emploi courant, l\u00e0 o&ugrave; nous pourrions l&rsquo;orner d&rsquo;une majuscule plus solennelle et pleine d&rsquo;un chaleureux respect ; et nous faisons cela pour signifier que nous sommes \u00e9galement et singuli\u00e8rement dans la d\u00e9monstration, le d\u00e9veloppement et l&rsquo;usage courants de la chose, sans aucune exaltation esth\u00e9tique, sans passion pour le Beau qui n&rsquo;existe plus, sans rien du tout enfin qu&rsquo;un relev\u00e9 de comptable&#8230; Dans ce cas il s&rsquo;agit plus pr\u00e9cis\u00e9ment de ce qu&rsquo;on nomme \u00ab\u00a0Art Contemporain\u00a0\u00bb ou AC, dont la caract\u00e9ristique malgr\u00e9 l&rsquo;usage imp\u00e9ratif des majuscules dans ce cas, est de refuser les crit\u00e8res esth\u00e9tiques de l&rsquo;Art et de repousser l&rsquo;h\u00e9ritage mill\u00e9naire \u00e0 cet \u00e9gard. Il y a dans cette d\u00e9marche une volont\u00e9 d\u00e9mocratique et universaliste d&rsquo;\u00e9galitarisme qui se traduit par la suppression de l&rsquo;intol\u00e9rable privil\u00e8ge de l'\u00a0\u00bbaristocratie de l&rsquo;artiste\u00a0\u00bb (c&rsquo;est le spectacteur-voyeur qui d\u00e9finit l&rsquo;&oelig;uvre en la regardant, transgressant les barri\u00e8res sociales et culturelles). Cette volont\u00e9 de suppression, d&rsquo;annihilation et m\u00eame d&rsquo;an\u00e9antissement qu&rsquo;on go&ucirc;te comme le fruit du tranchant de la guillotine doit \u00eatre inscrite dans le caract\u00e8re \u00e9volution-r\u00e9volution soci\u00e9tales (les deux en m\u00eame temps, &ndash; deux progr\u00e8s pour le prix d&rsquo;un) de la postmodernit\u00e9 ; il y a aussi le but d&rsquo;atteindre \u00e0 une sorte d&rsquo;absolu-universel, qui serait le non-art selon le sens classique ou plut\u00f4t imm\u00e9morial et pr\u00e9tendant \u00e0 l&rsquo;unicit\u00e9 primordiale que l&rsquo;on donne au concept d'\u00a0\u00bbart\u00a0\u00bb ; il y aurait encore l&rsquo;absence de forme esth\u00e9tique dans le sens de l&rsquo;absence de structuration. (Dans ce cas, entendons l&rsquo;id\u00e9e de \u00ab\u00a0structuration\u00a0\u00bb selon une d\u00e9marche sur laquelle nous reviendrons, selon les crit\u00e8res \u00e0 rencontrer de l&rsquo;\u00e9quilibre, de l&rsquo;ordre et de l&rsquo;harmonie.)<\/p>\n<\/p>\n<p><p>&#8230;Mais il y a bien mieux parce qu&rsquo;il y a dans l&rsquo;AC une pr\u00e9tention de l&rsquo;ordre du transcendantal sinon du  divin qui instaure cet \u00ab\u00a0art\u00a0\u00bb dans une dimension effectivement ou pseudo-divine (Daniel Sibony, cit\u00e9 par Aude de Kerros dans <em>Sacr\u00e9 art contemporain<\/em> : &laquo; <em>Avec l&rsquo;art actuel, c&rsquo;est le narcissisme qui fait religion, c&rsquo;est-\u00e0-dire \u00ab\u00a0art collectif\u00a0\u00bb, incluant une transcendance, celle de soi-m\u00eame comme Dieu, ou celle de Dieu que l&rsquo;on s&rsquo;est donn\u00e9 et qui est en soi<\/em>. &raquo;) L&rsquo;int\u00e9r\u00eat du propos ici est \u00e9videmment que l&rsquo;&Eacute;glise, retrouvant une forme d&rsquo;activit\u00e9 qui la conna&icirc;t puisque Dieu est de la partie, joue un r\u00f4le majeur dans ce processus ; dans de telles conditions de dialectique transcendantale, elle est partie prenante de l&rsquo;AC dans sa hi\u00e9rarchie elle-m\u00eame, et progresse, main dans la main avec l&rsquo;&Eacute;tat, dans la promotion et le soutien \u00e9conomique, culturel, et surtout spirituel de l&rsquo;entreprise. L&rsquo;attitude de l&rsquo;&Eacute;glise est si fondamentale qu&rsquo;elle affirme sans en dissimuler une seconde, on dirait m\u00eame en l&rsquo;affirmant avec une sorte d&rsquo;exaltation \u00e0 part sous-jacente, l&rsquo;acceptation d&rsquo;une dimension spirituelle sinon <strong>religieuse<\/strong> pour son compte (religieuse, c&rsquo;est-\u00e0-dire catholique ?), de cette activit\u00e9 postmoderne, absolument invertie et n\u00e9cessairement nihiliste de ce point de vue. Bien entendu, tout cela est inversion pure, &ndash; mais tout semble aller, dans ce monde \u00e9trange, c&rsquo;est-\u00e0-dire dans ce monde de l&rsquo;existence possible du bout du monde, comme si de telles bagatelles (inversion, nihilisme, etc.) n&rsquo;importaient pas vraiment, n&rsquo;importaient plus du tout, &ndash; l\u00e0 aussi autre terme, comme si l&rsquo;on approchait du terme m\u00eame du langage, plus tr\u00e8s loin de ce point o&ugrave; le langage ne signifie plus rien et atteint lui aussi cet au-del\u00e0 o&ugrave; son existence n&rsquo;est plus concevable &hellip; On trouve ais\u00e9ment chez les uns et les autres (Jean Baudrillard, Aude de Kerros) des r\u00e9f\u00e9rences \u00e0 une dimension lucif\u00e9rienne de l&rsquo;AC qu&rsquo;on peut distinguer ais\u00e9ment dans les conditions o&ugrave; il est d\u00e9velopp\u00e9, o&ugrave; il est exploit\u00e9, o&ugrave; il est promu et expos\u00e9, o&ugrave; il se pr\u00e9tend transcendance alors qu&rsquo;il en est l&rsquo;inversion pure. (&laquo; <em>Il y a une forme initiatique du Rien ou une forme initiatique du Mal<\/em> &raquo;, \u00e9crit Baudrillard \u00e0 son propos.) Ce constat n&rsquo;est l&rsquo;enfant d&rsquo;aucune exag\u00e9ration particuli\u00e8re ni m\u00eame de la moindre \u00e9motion emport\u00e9e dans le chef de ceux qui le font ; l&rsquo;\u00e9vidence du regard et de la plume suffit.<\/p>\n<\/p>\n<p><p>Sur ce point pr\u00e9cis pris comme un exemple, ne nous attardons pas \u00e0 une approche critique, \u00e0 un jugement, \u00e0 une digression \u00e9ventuellement enflamm\u00e9e ; en v\u00e9rit\u00e9, il n&rsquo;est pas n\u00e9cessaire de juger et de critiquer, encore moins de s&rsquo;enflammer comme j&rsquo;ai failli faire dans les lignes qui pr\u00e9c\u00e9daient, barrant et supprimant d\u00e9cid\u00e9ment tel ou tel mot de fureur ; cela n&rsquo;est pas n\u00e9cessaire tant ce ph\u00e9nom\u00e8ne de l&rsquo;AC avec ses liens avec l&rsquo;&Eacute;glise est <strong>dans la norme d&rsquo;une \u00e9poque<\/strong> et qu&rsquo;il s&rsquo;y inscrit si normalement dans son imposture tranquille. Le point important pour notre int\u00e9r\u00eat dans ce cas est bien que tout se passe comme si ce ph\u00e9nom\u00e8ne qu&rsquo;on d\u00e9crit \u00e9tait \u00e9galement <strong>dans la norme de l&rsquo;&Eacute;glise \u00ab\u00a0dans son temps\u00a0\u00bb<\/strong>, et cela d&rsquo;autant plus, il faut le r\u00e9p\u00e9ter, que l&rsquo;AC n&rsquo;est pas l&rsquo;objet et le moyen d&rsquo;une dissidence, d&rsquo;une contestation au sein de l&rsquo;&Eacute;glise mais qu&rsquo;il re\u00e7oit l&rsquo;onction sans r\u00e9serve de la hi\u00e9rarchie. (Ici, il est opportun de signaler que nous parlons de la France, &ndash; encore une fois cas embl\u00e9matique, &ndash; essentiellement parce que l&rsquo;&Eacute;tat joue un r\u00f4le central dans la culture dans ce pays et que le \u00ab\u00a0partenariat\u00a0\u00bb, le \u00ab\u00a0sponsoring\u00a0\u00bb &Eacute;tat-&Eacute;glise est un facteur clef du statut de l&rsquo;AC comme ce ph\u00e9nom\u00e8ne que nous voulons d\u00e9crire ici comme exemplaire.) Ainsi l&rsquo;AC dans ses rapports avec l&rsquo;&Eacute;glise, avec la religion catholique en tant qu&rsquo;institution, par cons\u00e9quent avec le Christianisme, constitue une situation arch\u00e9typique de la postmodernit\u00e9, dans un domaine essentiel qui est le sujet de notre r\u00e9flexion.<\/p>\n<\/p>\n<p><p>Cette situation postmoderniste de l&rsquo;&Eacute;glise montre que l&rsquo;&Eacute;glise entend plus que jamais, selon l&rsquo;expression d\u00e9j\u00e0 offerte et tant de fois <strong>d\u00e9ploy\u00e9e plut\u00f4t qu&#8217;employ\u00e9e<\/strong> d'\u00a0\u00bb\u00eatre de son temps\u00a0\u00bb, m\u00eame si ce temps pourrait \u00eatre, <strong>devrait \u00eatre d\u00e9fini<\/strong> selon son point de vue et selon son langage \u00e0 la fois th\u00e9ologique et symbolique comme compl\u00e8tement \u00ab\u00a0le temps de Satan\u00a0\u00bb. Cette proposition, sous forme sloganique comme l&rsquo;on serait tent\u00e9 d\u00e9sormais de dire \u00ab\u00a0satanique\u00a0\u00bb, &ndash; \u00ab\u00a0\u00eatre de son temps\u00a0\u00bb, c&rsquo;est \u00eatre satanique\u00a0\u00bb, &ndash; si elle r\u00e9pond \u00e0 ce souci pr\u00e9sent\u00e9 comme honorable et n\u00e9cessaire d&rsquo;incarnation qui a toujours caract\u00e9ris\u00e9 le Christianisme \u00e0 partir de son apparition au c&oelig;ur de l&#8217;empire de Rome, d\u00e9montre d\u00e9sormais, dans ces conditions pr\u00e9cis\u00e9ment, le risque r\u00e9alis\u00e9 et \u00e9galement incarn\u00e9 d&rsquo;en accepter, d&rsquo;en int\u00e9grer tous les caract\u00e8res jusqu&rsquo;\u00e0 l&rsquo;inversion finale plut\u00f4t que de les influencer. Le r\u00e9sultat est celui de la fusion et de l&rsquo;int\u00e9gration, ce moment de la chimie intellectuelle de la modernit\u00e9 agissant comme peut le faire la pression d&rsquo;une addiction indescriptible et d&rsquo;une fascination extraordinaire, o&ugrave; la cause devient cons\u00e9quence ; et la cause du \u00ab\u00a0vouloir \u00eatre de son temps\u00a0\u00bb, c&rsquo;est, \u00e0 ce moment accept\u00e9 puis int\u00e9gr\u00e9, d&rsquo;abandonner toute vision critique de son temps pour \u00eatre effectivement \u00ab\u00a0de son temps\u00a0\u00bb ; c&rsquo;est-\u00e0-dire, pour l&rsquo;&Eacute;glise et malgr\u00e9 sa tournure v\u00e9n\u00e9rable et ses ors d&rsquo;au-del\u00e0 du mill\u00e9naire, compl\u00e8tement model\u00e9e par son temps et devenue cons\u00e9quence de son temps et accouch\u00e9e par son temps ; \u00e9videmment, il ne peut \u00eatre question de porter quelque critique que ce soit contre les augustes entrailles desquelles on est n\u00e9. L&rsquo;aventure de l&rsquo;\u00e9trange mariage de fascination entre l&rsquo;&Eacute;glise et l&rsquo;AC vue comme exemplaire montre que nous y sommes, et m\u00eame au-del\u00e0&hellip; M\u00eame si les dimensions des \u00e9v\u00e8nements diff\u00e8rent immens\u00e9ment, l&rsquo;esprit est commun et l&rsquo;on peut avancer l&rsquo;image que l&rsquo;AC est comme une seconde Renaissance pour l&rsquo;&Eacute;glise, une fa\u00e7on postmoderne de jeter sa gourme, sans \u00e9clat certes mais cette fois d\u00e9finitivement&#8230;<\/p>\n<\/p>\n<p><p>D&rsquo;une fa\u00e7on encore plus g\u00e9n\u00e9rale, nous sommes conduits \u00e0 une autre conclusion, certes \u00e0 la lumi\u00e8re de l&rsquo;aventure chr\u00e9tienne mais avec le Christianisme consid\u00e9r\u00e9 comme les autres religions telles qu&rsquo;elles existent au sein du Syst\u00e8me, pour la situation de ce d\u00e9but du XXI\u00e8me si\u00e8cle o&ugrave; la religion d&rsquo;une fa\u00e7on g\u00e9n\u00e9rale est brandie partout comme acteur principal, \u00e0 proscrire et \u00e0 d\u00e9truire, ou \u00e0 magnifier c&rsquo;est selon. Cette conclusion nous d\u00e9tourne de l&rsquo;id\u00e9e g\u00e9n\u00e9rale de la religion consid\u00e9r\u00e9e comme \u00ab\u00a0acteur principal\u00a0\u00bb du temps courant, mais devenue <strong>au contraire<\/strong> un outil dans un gigantesque \u00e9branlement du monde qui la d\u00e9passe ; et nous disons, certes, <strong>bien plus<\/strong> \u00e9branlement du monde qu&rsquo;affrontement ; et la religion outil et rien d&rsquo;autre, et certainement pas acteur sinon par inversion ; et la religion outil de l&rsquo;\u00e9branlement du monde, c&rsquo;est-\u00e0-dire outil du d\u00e9sordre, au contraire de ce qu&rsquo;elle pr\u00e9tend \u00eatre et de ce qu&rsquo;elle devrait \u00eatre&#8230; En un sens, si l&rsquo;on inclut dans notre d\u00e9veloppement sur le Christianisme et dans ce bref coup d&rsquo;&oelig;il sur la situation \u00ab\u00a0actuelle\u00a0\u00bb les agitations des autres grandes religions monoth\u00e9istes, ce \u00e0 quoi l&rsquo;on assiste aujourd&rsquo;hui ne serait nullement tout ceci qu&rsquo;on agite pour l&rsquo;illusion de l'\u00a0\u00bb\u00eatre de son temps\u00a0\u00bb, rien de tous ces arguments de publiciste, de sp\u00e9cialiste de la communication comme il en pullule, &ndash; ni un affrontement de religions [de \u00ab\u00a0civilisations\u00a0\u00bb, moins encore !], ni une affirmation des religions, &ndash; <strong>mais au contraire une  d\u00e9route compl\u00e8te<\/strong> des religions monoth\u00e9istes qui ont toutes plus ou moins eu un r\u00f4le, et surtout le r\u00f4le exclusif du spirituel, dans l&rsquo;accouchement de notre civilisation devenue contre-civilisation ; et les religions en faisant le pendant et devenant, parall\u00e8lement \u00e0 la civilisation dont elles ont accouch\u00e9 ou qu&rsquo;elles ont accept\u00e9e et du point de vue de la transcendance, rien de moins que contre-religions. Cette d\u00e9route compl\u00e8te accompagne celle du Syst\u00e8me que ces religions ont contribu\u00e9 \u00e0 cr\u00e9er, sans doute le plus involontairement qui soit, par le seul fait de leur affirmation monoth\u00e9iste ; parce que, selon cette approche, cette affirmation monoth\u00e9iste appara&icirc;t m\u00e9thodologiquement inspiratrice de l&rsquo;exclusivisme herm\u00e9tique du Syst\u00e8me et m\u00eame de la source dont il proc\u00e8de (le d\u00e9cha&icirc;nement de la Mati\u00e8re grosse de lui d\u00e8s qu&rsquo;elle se manifeste)&hellip;<\/p>\n<\/p>\n<p><p>Alors, par la nature m\u00eame de la situation que nous d\u00e9crivons, vient \u00e0 l&rsquo;esprit le constat que le sacr\u00e9 a perdu tout droit et tout espace o&ugrave; il pourrait pr\u00e9tendre \u00e0 la hauteur qu&rsquo;on lui pr\u00eate. Conduit \u00e0 \u00eatre l&rsquo;adversaire de l&rsquo;initiation et de la religion qui, s&rsquo;exhibant \u00e0 ciel ouvert dans cette p\u00e9riode qui est celle du triomphe du Mal, ne peuvent \u00eatre par cons\u00e9quent qu&rsquo;initiation et religion tomb\u00e9es sous l&#8217;empire affreux du Mal, le sacr\u00e9 se trouve, comme dans les temps terribles de l&rsquo;occupation des nations envahies, comme la France elle-m\u00eame, dans la n\u00e9cessit\u00e9 devenue glorieuse de prendre le maquis, d&rsquo;entrer dans la clandestinit\u00e9. Ainsi extrait \u00ab\u00a0de son temps\u00a0\u00bb alors que l&rsquo;&Eacute;glise s&rsquo;y compla&icirc;t, le sacr\u00e9 est partout (n\u00e9cessairement, puisqu&rsquo;il s&rsquo;agit du sacr\u00e9) et nulle part (sa plong\u00e9e dans la clandestinit\u00e9). <strong>Il peut \u00eatre rencontr\u00e9, par surprise ou par inadvertance, dans les situations et les choses les plus modernes, tout en en \u00e9tant compl\u00e8tement \u00e9tranger<\/strong>. Le sacr\u00e9 peut-\u00eatre rencontr\u00e9 dans la s\u00e9quence d&rsquo;un film, dans un regard \u00e9tranger, dans une connivence de circonstance, parce que l&rsquo;omnipr\u00e9sence du Mal ne laisse d&rsquo;autre possibilit\u00e9 que cette impr\u00e9visibilit\u00e9. Le sacr\u00e9 est diffus, partout et nulle part, et c&rsquo;est \u00e0 l&rsquo;individu qui se trouve dans sa qu\u00eate de le reconna&icirc;tre. Dans ce tableau absolument boulevers\u00e9, qui ne r\u00e9pond \u00e0 aucune coh\u00e9rence ni coh\u00e9sion, la religion n&rsquo;est plus une garantie en rien, elle est devenue une sorte de pi\u00e8ge que l&rsquo;\u00eatre en qu\u00eate de sacr\u00e9 doit \u00e9viter de toutes les fa\u00e7ons. Ainsi en sommes-nous arriv\u00e9s \u00e0 la ruse ultime du Mal qui est de rendre impossible la reconnaissance du sacr\u00e9 selon les voies courantes du sacr\u00e9 ; pire encore, pour aller au bout de cette ruse du Mal dans cette \u00e9poque o&ugrave; r\u00e8gne le Mal, le sacr\u00e9 est devenu un hors-du-monde et un hors-du-mode des vies, indigne selon les autorit\u00e9s officielles et les autorit\u00e9s spirituelles non seulement de respect mais d&rsquo;attention, d&rsquo;int\u00e9r\u00eat, rejet\u00e9 qu&rsquo;il est de la simple citoyennet\u00e9 du monde. Ainsi en est-il de la situation de notre temps, &ndash; notre \u00ab\u00a0temps courant\u00a0\u00bb&hellip;<\/p>\n<\/p>\n<p><p>Nous nous en tenons l\u00e0 dans cette incursion dans notre \u00ab\u00a0temps courant\u00a0\u00bb, avec quelques questions et des remarques qui laissent \u00e0 penser, qui nous solliciteront par cons\u00e9quent \u00e0 nouveau, non sans noter combien cette \u00ab\u00a0passerelle eschatologique\u00a0\u00bb qui a fait le th\u00e8me de circonstance de cette partie du r\u00e9cit poss\u00e8de de bien diverses facettes, et diverses fa\u00e7ons de s&rsquo;affirmer. Effectivement, elle vient jusqu&rsquo;\u00e0 nous pour nous interpeller \u00e0 propos de son propre destin.<\/p>\n<\/p>\n<p><h2 class=\"titleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Justification du propos<\/h2>\n<\/p>\n<p><p>Allons plus avant en retrouvant notre chronologie qui, paradoxalement, nous ram\u00e8ne en arri\u00e8re. Ce qui nous a guid\u00e9 dans cette partie du r\u00e9cit en proposant, comme nous l&rsquo;\u00e9crivons \u00e0 son d\u00e9but, \u00ab\u00a0de penser le Christianisme <strong>comme si<\/strong> la divine origine de ce ph\u00e9nom\u00e8ne constituait une v\u00e9rit\u00e9 acquise et admise sans \u00e9nervement de l&rsquo;esprit\u00a0\u00bb, c&rsquo;est notre inqui\u00e9tude et notre incompr\u00e9hension originelle \u00e0 propos des conditions extraordinaires de ce que nous estimons \u00eatre une catastrophe affectant le destin du Christianisme. Comment une entit\u00e9 de si haute intelligence et de spiritualit\u00e9 si fervente, manifestement inspir\u00e9e par une injonction divine, si puissante, si admirablement construite, si incontestable dans son magist\u00e8re de la civilisation inspir\u00e9e par elle, par cons\u00e9quent \u00e0 la fois ma&icirc;tresse et responsable des \u00e9v\u00e8nements se d\u00e9veloppant sous son empire, comment le Christianisme a-t-il pu laisser se d\u00e9velopper la modernit\u00e9, parfois jusqu&rsquo;\u00e0 s&rsquo;en r\u00e9jouir pour mieux confondre ses soi-disant adversaires et diffamateurs, parfois m\u00eame semblant s&rsquo;y complaire apr\u00e8s tout ? Notre r\u00e9ponse est que le Mal, qui est pour nous \u00e0 la fois la modernit\u00e9 et le d\u00e9cha&icirc;nement de la Mati\u00e8re qui a obtenu cette transformation (la modernit\u00e9) d\u00e9cisivement sous la forme d&rsquo;une entit\u00e9, le Mal qui a manifestement exerc\u00e9 toute son influence pour permettre cette d\u00e9viation vient pour une part de lui-m\u00eame, du Christianisme ; non pas le Mal comme cr\u00e9ation du Christianisme pr\u00e9cipit\u00e9 dans sa d\u00e9cadence jusqu&rsquo;\u00e0 l&rsquo;inversion certes, mais comme proximit\u00e9 du Christianisme conduisant, pour les \u00e2mes les plus inqui\u00e8tes et contre les esp\u00e9rances sans fin mises dans cette c\u00e9l\u00e9bration du divin, jusqu&rsquo;\u00e0 sa confusion avec le Christianisme lui-m\u00eame. (Plotin : &laquo; &hellip;[M]<em>ais les autres, ceux qui participeraient de lui<\/em> [du Mal] <em>et s&rsquo;y assimileraient, deviennent mauvais, n&rsquo;\u00e9tant pas mauvais en soi <\/em>&raquo;&hellip; Le Christianisme, conduit par ses errements terrestres \u00e0 s&rsquo;assimiler au Mal, \u00ab\u00a0sans \u00eatre mauvais en soi\u00a0\u00bb mais ayant agi terrestrement de cette fa\u00e7on que tout s&rsquo;est pass\u00e9 comme si le Mal jaillissait de lui-m\u00eame [du Christianisme]. On reconna&icirc;t la ruse centrale du Mal et son efficacit\u00e9 sans cesse renouvel\u00e9e.)<\/p>\n<\/p>\n<p><p>Le Christianisme, dans son op\u00e9rationnalit\u00e9 terrestre et au contraire de son essence purement accord\u00e9e \u00e0 la transcendance, s&rsquo;est r\u00e9v\u00e9l\u00e9 perm\u00e9able au Mal op\u00e9rant sous sa repr\u00e9sentation de la modernit\u00e9 par\u00e9e des atours du progressisme, o&ugrave; la vertu s\u00e9culi\u00e8re se paie du sacrifice, sinon de la liquidation pure et simple (le mot plus rude est mieux \u00e0 sa place) des principes transcendantaux. Cela fut essentiellement accompli par le biais d&rsquo;une psychologie complexe, imp\u00e9tueuse et s&ucirc;re d&rsquo;elle-m\u00eame, extraordinairement efficace mais trop ma&icirc;tresse de ses effets jusqu&rsquo;\u00e0 la passion pour eux, pour voir que son brio l&rsquo;entra&icirc;nait \u00e0 favoriser les germes de ce qui deviendrait, pour le Christianisme, l&rsquo;inversion de lui-m\u00eame. Ce brio \u00e9tait paradoxalement la faiblesse m\u00eame, et cette psychologie d&rsquo;apparence si puissante dissimulait cette faiblesse effectivement mortelle pour la destin\u00e9e envisag\u00e9e, sa vuln\u00e9rabilit\u00e9 \u00e0 la pression et \u00e0 la p\u00e9n\u00e9tration du Mal. Le Christianisme terrestre se jugeait peut-\u00eatre de trop belle extraction, de trop haute lign\u00e9e et de transcendance trop affirm\u00e9e pour mener \u00e0 bien sa fortune terrestre sans pr\u00eater imprudemment le flanc aux entreprises d&rsquo;un M\u00e9phistoph\u00e9l\u00e8s habile \u00e0 se dissimuler ; pour entreprendre ses op\u00e9rations terrestres, c&rsquo;est comme s&rsquo;il \u00e9tait venu de trop haut ; emport\u00e9 par la s&ucirc;ret\u00e9 de son origine, il tr\u00e9bucha. Par cons\u00e9quent et pire encore, le Christianisme chuta&hellip; Sans doute faut-il songer \u00e0 lui pardonner, tant son origine semble marqu\u00e9e de vertus superbes, mais pour autant on se retiendra de le f\u00e9liciter car les grandes vertus ont leurs responsabilit\u00e9s dans la conduite indigne de leur destin o&ugrave; elles se fourvoient parfois, et elles doivent \u00eatre pr\u00eates, s&rsquo;il est n\u00e9cessaire, \u00e0 en r\u00e9pondre d&rsquo;une certaine fa\u00e7on. Le Christianisme reste l&rsquo;enfant de ses origines magnifiques mais l&rsquo;on ne peut s&#8217;emp\u00eacher d&rsquo;avancer l&rsquo;hypoth\u00e8se qu&rsquo;il ne fut pas insensible \u00e0 l&rsquo;orgueil dont il sait pourtant, lui le premier semble-t-il nous dire, qu&rsquo;il est un p\u00each\u00e9. Lui qui sut prendre chez les Anciens ce qui lui importait pour r\u00e9ussir ses entreprises et installer son esprit au plus haut possible, il aurait pu s&rsquo;inspirer d&rsquo;eux en toute confiance, sinon en tout humilit\u00e9, pour se garder de l&rsquo;<em>hybris<\/em>. Il ne l&rsquo;a pas fait et, pour cette raison, il a trahi les Anciens et ses origines, installant une d\u00e9viation catastrophique et unique dans l&rsquo;histoire du monde, unique dans tous les cas pour le cycle en cours de l&rsquo;Histoire-haute, la m\u00e9tahistoire qui nous conduit ; tant pis pour lui&#8230;<\/p>\n<\/p>\n<p><p>D&rsquo;un point de vue plus g\u00e9n\u00e9ral, que l&rsquo;on pourrait qualifier de cyclique justement, ce destin malheureux et fautif du Christianisme doit finir par trouver sa place dans l&rsquo;arrangement g\u00e9n\u00e9ral des choses et du monde. On peut en effet observer que, selon notre approche, le Christianisme prend, <em>volens nolens<\/em>, une part fondamentale au d\u00e9veloppement des choses de cette fa\u00e7on que le Mal sous la forme du Syst\u00e8me prenne sa place en pleine lumi\u00e8re et nous apparaisse dans toute sa puissance mal\u00e9fique, avec le \u00ab\u00a0d\u00e9cha&icirc;nement de la Mati\u00e8re\u00a0\u00bb, sans plus rien dissimuler de sa surpuissance de dissolution et ainsi pr\u00e9parant sa course autodestructrice ; en favorisant involontairement mais d\u00e9cid\u00e9ment le d\u00e9veloppement du modernisme, qui donne un cadre historique coh\u00e9rent \u00e0 l&rsquo;\u00e9volution consid\u00e9r\u00e9e avec le \u00ab\u00a0d\u00e9cha&icirc;nement de la Mati\u00e8re\u00a0\u00bb ; en imposant par les conditions de sa propre Chute une dimension m\u00e9tahistorique promise \u00e0 transformer le destin que nous vivons de l&rsquo;apparente promesse moderniste transform\u00e9e en impasse de la modernit\u00e9, en l&rsquo;in\u00e9luctable issue eschatologique que nous devinons ; enfin, en nous d\u00e9livrant, par sa d\u00e9viation sinon son inversion m\u00eame, de son exclusivit\u00e9 parfois dictatoriale de la repr\u00e9sentation terrestre des accointances divines par lui-m\u00eame, et en ouvrant le champ par cons\u00e9quent \u00e0 une nouvelle libert\u00e9 dans la qu\u00eate de l&rsquo;ineffable, du moins pour ceux que la chose int\u00e9resse. Pour admettre ce sch\u00e9ma, effectivement, il faut admettre d\u00e9cid\u00e9ment la s\u00e9paration du Christianisme de ses origines glorieuses et si hautes, pour consid\u00e9rer sa branche terrestre devenue tronc central, son aventure purement exot\u00e9rique et s\u00e9culi\u00e8re, comme un destin promis \u00e0 se g\u00e2ter au contact des aventures terrestres, un destin sacrifi\u00e9 \u00e0 la mise en \u00e9vidence du Mal, pour assurer son identification puis sa destruction. <strong>A la lumi\u00e8re de notre enqu\u00eate, il nous semble que le Christianisme accomplit parfaitement cette mission-l\u00e0 (qui n&rsquo;a tout de m\u00eame nul besoin de majuscule). Plus qu&rsquo;aucune autre dynamique historique, il a su mettre en \u00e9vidence les ambitions du Mal autant que le Mal lui-m\u00eame, avec sa repr\u00e9sentation principale qu&rsquo;est la modernit\u00e9, et y r\u00e9pondant par sa propre Chute conduisant \u00e0 l&rsquo;issue eschatologique<\/strong>.<\/p>\n<\/p>\n<p><p>Ce constat entra&icirc;ne aussit\u00f4t le propos \u00e0 ajouter, au simple encha&icirc;nement de notre chronologie retrouv\u00e9e, l&rsquo;encha&icirc;nement de la progression du Mal. Nous passons de cette partie o&ugrave; l&rsquo;on embrasse le Christianisme \u00e0 celle que je nomme \u00ab\u00a0la Partie du persiflage\u00a0\u00bb principalement au XVIII\u00e8me si\u00e8cle, qui est aussi celle d&rsquo;une des offensives majeures du Mal ; celle o&ugrave; le Mal mit enfin en place sa tactique magistrale de p\u00e9n\u00e9trer les esprit, de les affaiblir, de les pervertir et de les asservir, non par les id\u00e9es ni par quelque autre chose intelligible que ce soit o&ugrave; la raison garde la possibilit\u00e9 de l&rsquo;affronter, mais <strong>par le chemin tortueux et vicieux de l&rsquo;infection de la psychologie<\/strong>, auparavant pervertie, amollie, dissoute, ouverte comme une fille qui s&rsquo;offre.<\/p>\n<\/p>\n<p><p>Ce que l&rsquo;on est conduit \u00e0 constater, c&rsquo;est qu&rsquo;il (le Mal) peut ainsi op\u00e9rer avec la plus grande efficacit\u00e9, non seulement parce que la d\u00e9cadence du Christianisme a pr\u00e9par\u00e9 les Lumi\u00e8res avec quelle minutie, avec quelle efficacit\u00e9, mais surtout parce que cette d\u00e9cadence a compl\u00e8tement ressuscit\u00e9 la psychologie du Christianisme des premiers \u00e2ges historiques, du temps de l&rsquo;Empire ; la psychologie qui s&rsquo;ouvre \u00e0 la subversion et \u00e0 la dissolution en pr\u00e9tendant \u00e0 la fois \u00e0 l&rsquo;inculpabilit\u00e9 et \u00e0 l&rsquo;ind\u00e9fectibilit\u00e9 qui donnent une illustre vertu ; la psychologie de cette force diffuse et dissolue qui tient toutes les responsabilit\u00e9s des autorit\u00e9s dans ses rets et qui pr\u00e9tend ne pr\u00e9tendre \u00e0 rien en fait de responsabilit\u00e9&hellip; Le fait est qu&rsquo;elle servit, cette force, \u00e0 assurer le plus grand triomphe terrestre qu&rsquo;on put jamais imaginer pour un mouvement de cette apparente humilit\u00e9, avec la seule puissance de l&rsquo;onction Tr\u00e8s-Haute elle-m\u00eame, qui est le Christianisme, et qu&rsquo;elle conduit aussi s&ucirc;rement \u00e0 son effondrement. La d\u00e9marche qui doit nous importer d\u00e9sormais est d&rsquo;observer ce qui s&rsquo;est pass\u00e9 dans l&rsquo;encha&icirc;nement qui suit, dans les effets conduits par des chemins incertains et indirects, que permit et m\u00eame favorisa cette religion \u00e9videmment ennemie du Mal, devenant par ces catastrophiques circonstances son plus grand alli\u00e9 en lui garantissant l&rsquo;investissement de l&rsquo;esprit humain&hellip; Ainsi s&rsquo;avance vers nous, non le Si\u00e8cle des Lumi\u00e8res mais \u00ab\u00a0Le Si\u00e8cle du persiflage\u00a0\u00bb.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab\u00a0Ainsi soit-il\u00a0\u00bb, &ndash; approximativement, en tout cas 1er ao&ucirc;t 2020 &ndash; Les caprices de l&rsquo;actualit\u00e9 mettent en \u00e9vidence combien cette actualit\u00e9 peut s&rsquo;arranger pour nous donner des signaux nous permettant de lire en elle comme \u00e0 livre ouvert et hors des simulacres, c&rsquo;est-\u00e0-dire hors de toute contrainte de sa hi\u00e9rarchie de surveillance, tournant les interdits&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[13314,18827,2654,2963,3423,2631,5185,2651,4484,2985,3969,8386,2622,3582,16011,2842],"class_list":["post-79365","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-ac","tag-aoc","tag-catholicisme","tag-christianisme","tag-civilisation","tag-de","tag-decadence","tag-du","tag-eglise","tag-fin","tag-grace","tag-lhistoire","tag-la","tag-michel","tag-onfray","tag-trahison"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79365","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79365"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79365\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79365"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79365"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79365"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}