{"id":79411,"date":"2020-09-04T09:43:16","date_gmt":"2020-09-04T09:43:16","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2020\/09\/04\/nos-technologies-pourrait-detruire-lhumanite\/"},"modified":"2020-09-04T09:43:16","modified_gmt":"2020-09-04T09:43:16","slug":"nos-technologies-pourrait-detruire-lhumanite","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2020\/09\/04\/nos-technologies-pourrait-detruire-lhumanite\/","title":{"rendered":"Nos technologies pourrait d\u00e9truire l&rsquo;humanit\u00e9"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Nos technologies pourrait d\u00e9truire l&rsquo;humanit\u00e9<\/h2>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Interview pour Sputnik Allemagne<\/h3>\n<\/p>\n<p><p><strong><em>Sputnik<\/em><\/strong><em> : M. Orlov, nous voulons aujourd&rsquo;hui discuter de votre dernier livre, &lsquo;Shrinking the Technosphere&rsquo; <\/em>[\u00e9dit\u00e9 en allemand]<em>, mais avant de commencer, j&rsquo;aimerais approfondir une de vos r\u00e9ponses de notre premi\u00e8re interview sur Sputnik Allemagne.<\/em><\/p>\n<\/p>\n<p><p><em>Vous avez dit que la banque centrale am\u00e9ricaine (la R\u00e9serve f\u00e9d\u00e9rale) a cr\u00e9\u00e9 de nouvelles garanties dans le cadre de la crise dites des &lsquo;repo&rsquo; bancaires de 2019. Je voudrais ajouter deux autres questions : Comment d\u00e9finiriez-vous le terme &lsquo;garantie&rsquo; ? Et vous avez dit que le dollar am\u00e9ricain allait perdre \u00e9norm\u00e9ment de valeur au cours des prochains mois ; qu&rsquo;est-ce qui vous rend si s&ucirc;r de cela ?<\/em><\/p>\n<\/p>\n<p><p><strong>Dimitri Orlov <\/strong>: Eh bien, pour r\u00e9pondre \u00e0 la premi\u00e8re question, je me suis peut-\u00eatre mal exprim\u00e9 lors de la premi\u00e8re interview. La Fed n&rsquo;a pas tant cr\u00e9\u00e9 des garanties que rachet\u00e9 des bons du Tr\u00e9sor am\u00e9ricain et d&rsquo;autres instruments de dette en tant que garanties parce que les banques ont cess\u00e9 d&rsquo;\u00eatre dispos\u00e9es \u00e0 les honorer en tant que garanties pour les pr\u00eats au jour le jour entre banques <em>[march\u00e9 repo, Ndt]<\/em>, et la Fed a donc d&ucirc; intervenir et fournir ces pr\u00eats, fournir les liquidit\u00e9s pour ces pr\u00eats \u00e0 hauteur de centaines de milliards de dollars d&rsquo;argent frais qui ont \u00e9t\u00e9 mis en circulation &ndash; entre les banques, pas dans l&rsquo;\u00e9conomie au sens large.<\/p>\n<\/p>\n<p><p>Cela montre donc que la foi dans la dette am\u00e9ricaine (et le dollar am\u00e9ricain est constitu\u00e9 de la dette am\u00e9ricaine \u00e0 ce stade), que cette foi n&rsquo;\u00e9tait pas aussi solide que certains voudraient le croire.<\/p>\n<\/p>\n<p><p>Maintenant, en ce qui concerne la deuxi\u00e8me question, pourquoi le dollar est susceptible de perdre de la valeur : si vous regardez la valeur d&rsquo;une monnaie, vous devez le faire par rapport \u00e0 la capacit\u00e9 de production qui la sous-tend. L&rsquo;argent est un moyen de payer les biens et les services. L&rsquo;offre d&rsquo;argent a connu une augmentation drastique. Actuellement, le gouvernement am\u00e9ricain est en voie de financer la moiti\u00e9 de son budget en utilisant de nouvelles dettes &ndash; c&rsquo;est-\u00e0-dire que le d\u00e9ficit budg\u00e9taire repr\u00e9sente en gros 50% du budget f\u00e9d\u00e9ral. Mais nous ne voyons pas d&rsquo;augmentation de la capacit\u00e9 de production des &Eacute;tats-Unis pour accompagner cette vaste augmentation de la masse mon\u00e9taire. En fait, l&rsquo;\u00e9conomie am\u00e9ricaine s&rsquo;est fortement contract\u00e9e, et il est absolument incertain qu&rsquo;elle se redresse de sit\u00f4t.<\/p>\n<\/p>\n<p><p>Donc, en gros, nous avons plus d&rsquo;argent, nous avons moins de choses \u00e0 acheter avec cet argent, et le r\u00e9sultat est que l&rsquo;argent va avoir moins de valeur. La logique de cette situation est extr\u00eamement simple.<\/p>\n<\/p>\n<p><p><strong><em>Sputnik<\/em><\/strong><em> : D&rsquo;accord, merci beaucoup. M. Orlov, votre dernier livre s&rsquo;intitule &lsquo;<a href=\"https:\/\/lesakerfrancophone.fr\/reduire-la-technosphere-note-de-lecture\">Shrinking the Technosphere<\/a>&lsquo;. Mes questions : qu&rsquo;est-ce que la technosph\u00e8re, et pourquoi devrait-elle ou va-t-elle se r\u00e9tr\u00e9cir ? Quelle est votre approche dans ce domaine ? Et pour notre public, vous pouvez vous-m\u00eame \u00eatre consid\u00e9r\u00e9 comme un technophile, comme un informaticien. Quel est votre point de vue sur tout ce sujet ?<\/em><\/p>\n<\/p>\n<p><p><strong>Dimitri Orlov <\/strong>: Eh bien, le terme &laquo; technosph\u00e8re &raquo; a \u00e9t\u00e9 plus ou moins invent\u00e9 par <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Vladimir_Vernadski\">Vladimir Vernadsky<\/a>, et il \u00e9tait un grand partisan de l&rsquo;id\u00e9e de la biosph\u00e8re, de la Terre vivante en tant qu&rsquo;organisme, avant m\u00eame la Gaia de <a href=\"https:\/\/fr.wikipedia.org\/wiki\/James_Lovelock\">Lovelock<\/a>  et tout \u00e7a. Il a ensuite invent\u00e9 le terme <em>&laquo; <a href=\"https:\/\/lesakerfrancophone.fr\/la-troisieme-voie-de-poutine-vue-a-travers-le-nooscope\">noosph\u00e8re<\/a>&laquo; <\/em>, qui \u00e9tait essentiellement la connaissance, la connaissance humaine, de la biosph\u00e8re et du monde physique qui nous permettait de l&rsquo;\u00e9tendre de diverses mani\u00e8res. C&rsquo;\u00e9tait un v\u00e9ritable optimiste scientifique : il pensait que les connaissances scientifiques nous permettraient d&rsquo;am\u00e9liorer consid\u00e9rablement la fa\u00e7on dont la vie sur terre est v\u00e9cue par les humains et par tout le monde.<\/p>\n<\/p>\n<p><p>Et il a \u00e9galement dit qu&rsquo;il existe une chose appel\u00e9e la <a href=\"https:\/\/lesakerfrancophone.fr\/le-hoquet-de-la-technosphere\">technosph\u00e8re<\/a>, et ce terme est en circulation depuis, dans une certaine mesure. Mais il s&rsquo;est av\u00e9r\u00e9 que la noosph\u00e8re est en r\u00e9alit\u00e9 fractur\u00e9e et incertaine. Il n&rsquo;est pas certain que la science soit utilis\u00e9e pour le bien ou le mal : la pr\u00e9valence des armes nucl\u00e9aires, par exemple, montrerait que la noosph\u00e8re n&rsquo;est pas une chose aussi bienveillante.<\/p>\n<\/p>\n<p><p>Au lieu de cela, nous assistons \u00e0 l&rsquo;\u00e9mergence d&rsquo;une technosph\u00e8re, qui est un domaine technologique unique, int\u00e9gr\u00e9 et mondial, que personne n&rsquo;est en mesure de contr\u00f4ler. C&rsquo;est-\u00e0-dire qu&rsquo;il s&rsquo;agit d&rsquo;une entit\u00e9 dont on peut dire qu&rsquo;elle a un esprit propre, ou du moins un programme propre, et qu&rsquo;elle a ses propres m\u00e9thodes. Elle utilise les humains, par opposition aux humains qui l&rsquo;utilisent elle. Nous n&rsquo;avons pas beaucoup de pouvoir sur elle. Tout ce que nous pouvons faire, c&rsquo;est essayer de l&rsquo;enfermer dans notre propre vie.<\/p>\n<\/p>\n<p><p>Pour l&rsquo;instant, elle est dans une p\u00e9riode de transition. Elle essaie de s&rsquo;\u00e9tendre continuellement, mais cela augmente l&rsquo;utilisation des ressources naturelles et cela ne peut pas durer \u00e9ternellement car la quantit\u00e9 de ressources naturelles disponibles est limit\u00e9e. &Agrave; l&rsquo;heure actuelle, la technosph\u00e8re se divise en zones de d\u00e9veloppement technologique \u00e9lev\u00e9 et en zones de d\u00e9veloppement technologique faible, avec des zones tampons entre ces parties \u00e9mergentes de la technosph\u00e8re. C&rsquo;est un processus tr\u00e8s int\u00e9ressant, tr\u00e8s important \u00e0 reconna&icirc;tre car il ne se r\u00e9sume pas vraiment \u00e0 une strat\u00e9gie politique, \u00e9conomique ou financi\u00e8re. Parce que, comme je l&rsquo;ai dit, la technosph\u00e8re a son propre agenda, et pour comprendre ce qu&rsquo;elle fait, il est important de commencer \u00e0 penser comme une machine, ce qui n&rsquo;est pas quelque chose que nous faisons normalement. Et nous devons \u00e9galement abandonner toute notion de moralit\u00e9, parce que la technosph\u00e8re n&rsquo;a absolument aucun sens de la moralit\u00e9. Elle peut nous rendre heureux, si cela sert ses int\u00e9r\u00eats, ou elle peut nous tuer si cela sert ses int\u00e9r\u00eats. Ou quelque chose entre les deux.<\/p>\n<\/p>\n<p><p><strong><em>Sputnik<\/em><\/strong><em> : Donc si je vous comprends bien, la crise actuelle du coronavirus o&ugrave; les gens travaillent \u00e0 domicile et font des conf\u00e9rences en ligne &ndash; ce n&rsquo;est pas vraiment la technologie dont vous parlez ? Vous donnez une vision plus large sur tout ce sujet ?<\/em><\/p>\n<\/p>\n<p><p><strong>Dimitri Orlov <\/strong>: Eh bien, la crise du coronavirus a \u00e9t\u00e9 tr\u00e8s utile \u00e0 la technosph\u00e8re en lui permettant de prendre plus de contr\u00f4le, de s&#8217;emparer du contr\u00f4le m\u00eame. Parce que l&rsquo;une des contraintes de la technosph\u00e8re est d&rsquo;accro&icirc;tre \u00e0 jamais son contr\u00f4le sur nous, les humains. Elle n&rsquo;aime pas les \u00eatres vivants, elle pr\u00e9f\u00e8re les robots et les machines. Elle pr\u00e9f\u00e8re que les humains agissent comme des machines dans toute la mesure du possible, donc elle essaie de d\u00e9finir des fonctions techniques pour tout le monde et de faire en sorte que chacun suive certains protocoles. Et bien s&ucirc;r, elle essaie de garder un &oelig;il sur tout le monde, de sorte que d\u00e8s que quelqu&rsquo;un sort du rang, une alarme se d\u00e9clenche quelque part, et un technicien s&rsquo;occupe du probl\u00e8me. Fondamentalement, pour la technosph\u00e8re, les humains sont un probl\u00e8me technique \u00e0 r\u00e9soudre, et la fa\u00e7on de le r\u00e9soudre est de remplacer les fonctions humaines par des fonctions automatis\u00e9es &ndash; intelligence artificielle, robots, etc. Et le coronavirus, en obligeant les gens \u00e0 garder une distance entre eux, et en s&rsquo;appuyant sur les techniques de communication \u00e9lectronique plut\u00f4t que sur les contacts face \u00e0 face, a permis \u00e0 la technosph\u00e8re de perturber au maximum les relations humaines, et de nous amener \u00e0 nous comporter comme des robots dans la plus grande mesure possible, ce qui est une victoire pour elle.<\/p>\n<\/p>\n<p><p>Elle a donc saisi l&rsquo;occasion offerte par un virus pas particuli\u00e8rement mortel pour \u00e9tendre sa sph\u00e8re de contr\u00f4le.<\/p>\n<\/p>\n<p><p><strong><em>Sputnik<\/em><\/strong><em> : M. Orlov, vous avez \u00e9crit dans votre nouveau livre \u00ab\u00a0La plupart des gens sont satisfaits des produits de remplacement de haute technologie, des fours \u00e0 micro-ondes, des smartphones, etc. Les appareils ont r\u00e9duit l&rsquo;\u00e9criture \u00e9l\u00e9gante \u00e0 une insignifiance d\u00e9pass\u00e9e\u00a0\u00bb. Donc, si je peux me permettre de me montrer assez na\u00eff, quel est le probl\u00e8me alors ?<\/em><\/p>\n<\/p>\n<p><p><strong>Dimitri Orlov <\/strong>: Eh bien, ces choses fonctionnent pendant un certain temps : un four \u00e0 micro-ondes fonctionne pendant, disons, trois ou cinq ans, puis il cesse de fonctionner. Et ensuite, que faites-vous ? Vous sortez et vous en achetez un autre ? Et si vous n&rsquo;avez pas d&rsquo;argent ? Et s&rsquo;ils ne fabriquent plus de fours \u00e0 micro-ondes parce que les ressources pour en fabriquer sont \u00e9puis\u00e9es ? Et si votre pays ne peut plus importer de fours \u00e0 micro-ondes parce qu&rsquo;il est fauch\u00e9 et que les pays exportateurs ne veulent pas vendre de fours \u00e0 micro-ondes \u00e0 cr\u00e9dit ? Dans ce cas, vous \u00eates coinc\u00e9 parce que vous avez oubli\u00e9 comment cuisiner et vous mourrez de faim. C&rsquo;est le probl\u00e8me avec la technologie : c&rsquo;est comme si vous montiez sur une \u00e9chelle en d\u00e9coupant et en br&ucirc;lant les barreaux de l&rsquo;\u00e9chelle qui se trouve en dessous de vous. Vous ne pouvez que monter, vous ne pouvez pas descendre. Tout ce que vous pouvez faire, c&rsquo;est tomber et mourir.<\/p>\n<\/p>\n<p><p><strong><em>Sputnik<\/em><\/strong><em> : R\u00e9ponse int\u00e9ressante ; merci beaucoup. Autre partie int\u00e9ressante, vous \u00e9crivez : \u00ab\u00a0Tout d&rsquo;abord, la question de savoir ce qui est si efficace dans ces nouvelles installations n&rsquo;est gu\u00e8re examin\u00e9e&hellip;\u00a0\u00bb Je vais le r\u00e9sumer un peu : en gros, ce que vous avez \u00e9crit me rappelle Rudy Dutschke. C&rsquo;\u00e9tait un sociologue, un militant politique et un leader \u00e9tudiant c\u00e9l\u00e8bre dans les ann\u00e9es 60 en Allemagne de l&rsquo;Ouest. Il a ensuite \u00e9t\u00e9 abattu. Dans une ancienne interview \u00e0 la t\u00e9l\u00e9vision allemande, il a dit, en gros, que compte tenu des progr\u00e8s technologiques, l&rsquo;humanit\u00e9 ne devrait pas avoir \u00e0 travailler. &Agrave; l&rsquo;avenir, les solutions techniques aideront l&rsquo;humanit\u00e9 \u00e0 accomplir des t\u00e2ches et lui apporteront plus de temps libre. Ma question est la suivante : pourquoi cela n&rsquo;a-t-il pas fonctionn\u00e9 ? Pourquoi cette promesse n&rsquo;a-t-elle pas \u00e9t\u00e9 tenue ?<\/em><\/p>\n<\/p>\n<p><p><strong>Dimitri Orlov <\/strong>: Parce que le but de la technologie n&rsquo;est pas de profiter aux humains, mais \u00e0 la technosph\u00e8re. La technosph\u00e8re utilise les humains comme des pi\u00e8ces mobiles, en les payant le moins possible pour leurs services afin d&rsquo;\u00e9tendre son contr\u00f4le aussi rapidement et radicalement que possible. Il n&rsquo;y a donc vraiment aucun espoir que nous puissions un jour gagner en libert\u00e9 en \u00e9largissant notre utilisation de la technologie. Nous pouvons gagner une certaine libert\u00e9 en limitant nos choix technologiques aux \u00e9l\u00e9ments essentiels que nous pouvons produire et entretenir nous-m\u00eames dans la plus grande mesure possible. Mais nous ne pouvons pas nous contenter de suivre le programme et de nous attendre \u00e0 ce qu&rsquo;il fonctionne pour nous.<\/p>\n<\/p>\n<p><p><strong><em>Sputnik<\/em><\/strong><em> : Int\u00e9ressant. Pourquoi la technologie d\u00e9truit-elle des emplois ?<\/em><\/p>\n<\/p>\n<p><p><strong>Dimitri Orlov <\/strong>: Parce que les humains sont d\u00e9sordonn\u00e9s. Ce qu&rsquo;il y a de bien avec les humains, c&rsquo;est que, laiss\u00e9s \u00e0 eux-m\u00eames, ils font plus d&rsquo;humains ; ils se reproduisent. Les machines ne se reproduisent pas, il faut les fabriquer. D&rsquo;un autre c\u00f4t\u00e9, vous devez continuer \u00e0 loger et \u00e0 nourrir les humains m\u00eame apr\u00e8s qu&rsquo;ils aient cess\u00e9 de travailler. C&rsquo;est ce qu&rsquo;on appelle la retraite. Vous ne pouvez pas les mettre \u00e0 la casse comme vous le feriez pour des machines. Il y a donc des avantages et des inconv\u00e9nients. De plus, les humains s&rsquo;attendent \u00e0 une semaine de travail : ils ne peuvent pas travailler 24 heures sur 24, 7 jours sur 7. D&rsquo;un autre c\u00f4t\u00e9, il est plus facile de cultiver de la nourriture que de produire de l&rsquo;\u00e9lectricit\u00e9, dans une certaine mesure, et les humains peuvent cultiver leur propre nourriture dans une certaine mesure. Il y a donc des avantages et des inconv\u00e9nients, mais dans l&rsquo;ensemble, la technosph\u00e8re n&rsquo;aime pas les humains. Elle veut nous remplacer par des robots et de l&rsquo;intelligence artificielle dans la plus grande mesure possible.<\/p>\n<\/p>\n<p><p><strong><em>Sputnik<\/em><\/strong><em> : OK. M. Orlov, vous \u00e9crivez \u00e9galement dans votre nouveau livre que la technologie peut \u00eatre un f\u00e9tiche et asservir les gens&hellip; les rendant d\u00e9pendants, disons, des smartphones. Est-ce le terme f\u00e9tiche invent\u00e9 par Karl Marx, ou que voulez-vous dire exactement ?<\/em><\/p>\n<\/p>\n<p><p><strong>Dimitri Orlov <\/strong>: Non. Je veux dire f\u00e9tichisme comme dans f\u00e9tichisme sexuel. Les gens qui aiment les chaussures, ou les bas, ou le cuir, des choses comme \u00e7a. C&rsquo;est \u00e0 ce niveau-l\u00e0. Vous voyez les gens, disons dans les transports publics, s&rsquo;accrocher \u00e0 leur smartphone comme si c&rsquo;\u00e9tait une sorte de talisman pour conjurer le mal. Vous voyez des gens caresser leur smartphone, et c&rsquo;est essentiellement le sympt\u00f4me d&rsquo;un trouble psychologique, d&rsquo;une d\u00e9pendance, d&rsquo;un trouble de l&rsquo;attachement en quelque sorte. Si les gens se font retirer leur smartphone, ou m\u00eame s&rsquo;ils doivent survivre sans acc\u00e8s wifi pendant quelques jours, ils risquent de devenir catatoniques et de s&rsquo;asseoir l\u00e0 et de se balancer d&rsquo;un c\u00f4t\u00e9 \u00e0 l&rsquo;autre. Ils auront besoin d&rsquo;un traitement psychiatrique apr\u00e8s cela. Les gens commencent donc \u00e0 s&rsquo;en rendre compte et l&rsquo;acc\u00e8s \u00e0 Internet est trait\u00e9 comme un droit de l&rsquo;homme. Du point de vue de la technosph\u00e8re, c&rsquo;est parfait. Cela rend les humains parfaitement contr\u00f4lables. Tout ce que vous avez \u00e0 faire pour qu&rsquo;ils restent en ligne, c&rsquo;est de les menacer de leur couper l&rsquo;acc\u00e8s \u00e0 Internet. C&rsquo;est tout ce que vous avez \u00e0 faire. Vous n&rsquo;avez pas besoin de les emprisonner, vous n&rsquo;avez pas besoin de les fouetter, vous n&rsquo;avez pas besoin de les punir du tout. Tout ce que vous avez \u00e0 faire, c&rsquo;est de menacer de leur couper l&rsquo;acc\u00e8s \u00e0 l&rsquo;internet.<\/p>\n<\/p>\n<p><p><strong><em>Sputnik<\/em><\/strong><em> : Cela m&rsquo;am\u00e8ne \u00e0 ma prochaine question, car en allemand, nous avons un mot pour ce que vous d\u00e9crivez dans votre dernier livre. Cela s&rsquo;appelle &lsquo;technologie gl&auml;ubigkeit ou wissenschaft gl&auml;ubigkeit&rsquo;. Cela signifie la tendance \u00e0 n\u00e9gliger les cons\u00e9quences sociales n\u00e9gatives, ou \u00e0 d\u00e9clarer la technologie sacro-sainte. C&rsquo;est ce que vous voulez dire ?<\/em><\/p>\n<\/p>\n<p><p><strong>Dimitri Orlov <\/strong>: Eh bien, oui. C&rsquo;est un article de foi que personne n&rsquo;est autoris\u00e9 \u00e0 remettre en question, que la technologie est bonne ; que la technologie moderne est meilleure que la technologie d\u00e9pass\u00e9e ; que plus de technologie c&rsquo;est mieux que moins de technologie ; et que chaque probl\u00e8me que vous pouvez imaginer a une sorte de solution technologique. Ou, si ce n&rsquo;est pas le cas, alors la t\u00e2che consiste \u00e0 inventer cette solution technologique. On ne discute jamais du fait qu&rsquo;il y a d\u00e9j\u00e0 trop de technologie, trop de d\u00e9pendance \u00e0 son \u00e9gard, que nous devrions nous rabattre sur des strat\u00e9gies qui ont fonctionn\u00e9 pendant des centaines, peut-\u00eatre des milliers, peut-\u00eatre des millions d&rsquo;ann\u00e9es auparavant, parce que ces technologies ancestrales ne nous ont certainement pas fait de mal \u00e0 long terme, alors que les technologies que nous utilisons aujourd&rsquo;hui &ndash; parce qu&rsquo;elles sont modernes, elles n&rsquo;ont pas \u00e9t\u00e9 test\u00e9es sur le long terme &ndash; pourraient \u00eatre fatales. Elles pourraient \u00eatre tr\u00e8s dommageables et elles pourraient \u00eatre extr\u00eamement nocives.<\/p>\n<\/p>\n<p><p><strong><em>Sputnik<\/em><\/strong><em> : Vous parlez aussi indirectement de l&rsquo;espionnage et du secteur militaire parce que vous mentionnez aussi l&rsquo;utilisation de la technologie \u00e0 des fins de surveillance, par exemple. &Ecirc;tes-vous, comme Julian Assange ou Edward Snowden, un critique de ces technologies de surveillance, ou quel est votre avis \u00e0 ce sujet ?<\/em><\/p>\n<\/p>\n<p><p><strong>Dimitri Orlov <\/strong>: Eh bien, il y a des avantages et des inconv\u00e9nients. Si vous vivez dans un petit village o&ugrave; tout le monde se conna&icirc;t et o&ugrave; tout le monde est pr\u00eat \u00e0 se d\u00e9fendre, vous avez un faible taux de criminalit\u00e9 et les enfants jouent dans la rue et tout le monde est content. Si vous m\u00e9langez les gens, si vous les forcez \u00e0 vivre aux c\u00f4t\u00e9s d&rsquo;\u00e9trangers dans les grandes villes, il y a beaucoup d&rsquo;ali\u00e9nation, et \u00e0 cause de cela, il y a beaucoup de criminalit\u00e9 &ndash; juste \u00e0 cause de cela, parce que les gens ne se traitent pas tr\u00e8s bien face \u00e0 face dans ces circonstances. La solution est d&rsquo;introduire la surveillance. Ce n&rsquo;est pas une aussi bonne solution que de faire vivre tout le monde dans des communaut\u00e9s tr\u00e8s unies, mais c&rsquo;est une solution. Ainsi, les cam\u00e9ras de s\u00e9curit\u00e9 partout dans le monde sauvent des vies, emp\u00eachent les crimes d&rsquo;\u00eatre commis dans de mauvaises circonstances. C&rsquo;est fondamentalement une mauvaise solution \u00e0 un mauvais probl\u00e8me.<\/p>\n<\/p>\n<p><p>Mais en termes de contr\u00f4le de la population, de technologies de surveillance, de suppression de la libert\u00e9 d&rsquo;expression, par exemple, en termes de traitement des dissidents et de leur neutralisation, ces technologies sont horribles. Ainsi, par exemple, toute la censure qui est perp\u00e9tr\u00e9e par le biais des m\u00e9dias sociaux, o&ugrave; \u00e0 peu pr\u00e8s tout ce que quelqu&rsquo;un n&rsquo;aime pas peut \u00eatre qualifi\u00e9 de discours de haine, ou d&rsquo;intimidation, ou d&rsquo;abus, simplement parce que quelqu&rsquo;un n&rsquo;aime pas \u00e7a, simplement parce que c&rsquo;est contre l&rsquo;id\u00e9ologie de quelqu&rsquo;un. C&rsquo;est tr\u00e8s dangereux et tr\u00e8s mauvais.<\/p>\n<\/p>\n<p><p><strong><em>Sputnik<\/em><\/strong><em> : Question suivante : Qui profite de la technologie ?<\/em><\/p>\n<\/p>\n<p><p><strong>Dimitri Orlov <\/strong>: Eh bien, tout d&rsquo;abord, le principal b\u00e9n\u00e9ficiaire de la technologie est la technosph\u00e8re elle-m\u00eame. Elle perp\u00e9tue son propre programme de croissance infinie et de contr\u00f4le toujours plus grand. Les humains b\u00e9n\u00e9ficient de la technologie dans la mesure o&ugrave; la technosph\u00e8re les trouve utiles, donc les ing\u00e9nieurs et les techniciens sont certainement privil\u00e9gi\u00e9s. Divers autres professionnels sont certainement privil\u00e9gi\u00e9s. M\u00eame les travailleurs manuels qui occupent des emplois qui ne peuvent pas \u00eatre automatis\u00e9s ou remplac\u00e9s par des robots peuvent \u00eatre privil\u00e9gi\u00e9s, mais une fois qu&rsquo;ils sont remplac\u00e9s par des robots, ils sont pratiquement inutiles, de sorte que la technosph\u00e8re peut s&rsquo;en occuper en leur fournissant de l&rsquo;alcool et des drogues, par exemple, pour s&rsquo;assurer qu&rsquo;ils meurent plus t\u00f4t, et c&rsquo;est le sch\u00e9ma typique.<\/p>\n<\/p>\n<p><p><strong><em>Sputnik<\/em><\/strong><em> : Donc, M. Orlov, la prochaine question, dont vous m&rsquo;avez dit avant l&rsquo;entretien qu&rsquo;elle recevrait une r\u00e9ponse large. Quel r\u00f4le la technologie joue-t-elle dans l&rsquo;\u00e9conomie et le commerce ?<\/em><\/p>\n<\/p>\n<p><p><strong>Dimitri Orlov <\/strong>: Elle joue un r\u00f4le \u00e9norme, car \u00e0 l&rsquo;heure actuelle, il y a tr\u00e8s peu d&rsquo;activit\u00e9 \u00e9conomique qui se fait sans, par exemple, l&rsquo;utilisation de produits d\u00e9riv\u00e9s du p\u00e9trole brut. Rien ne se fait sans les produits d\u00e9riv\u00e9s du p\u00e9trole brut. Il n&rsquo;y a vraiment rien de vert l\u00e0-dedans et il n&rsquo;y aura jamais rien de vert. Il s&rsquo;agit donc d&rsquo;un processus technologique. La technosph\u00e8re a vraiment pris son envol apr\u00e8s la d\u00e9couverte des combustibles fossiles : d&rsquo;abord le charbon, puis le p\u00e9trole, le gaz naturel, le nucl\u00e9aire ; et elle ne continuera que dans la mesure o&ugrave; elle le pourra tant que ces ressources pourront \u00eatre exploit\u00e9es. Et maintenant qu&rsquo;elles s&rsquo;\u00e9puisent dans la plupart des r\u00e9gions du monde, la technosph\u00e8re doit s&rsquo;isoler et se confiner dans diverses zones prometteuses qui disposent encore de suffisamment de ressources pour la maintenir en vie pour le moment. Ainsi, si vous regardez le commerce mondial, il se fera entre les parties du monde que la technosph\u00e8re peut encore habiter. Et diverses parties du monde que la technosph\u00e8re trouve inutiles \u00e0 ses fins se retrouveront coup\u00e9es du reste.<\/p>\n<\/p>\n<p><p><strong><em>Sputnik<\/em><\/strong><em> : M. Orlov, que pensez-vous de la technologie nucl\u00e9aire en g\u00e9n\u00e9ral ?<\/em><\/p>\n<\/p>\n<p><p><strong>Dimitri Orlov <\/strong>: Malheureusement, la technologie nucl\u00e9aire en g\u00e9n\u00e9ral n&rsquo;existe pas. Il existe, par exemple, une technologie nucl\u00e9aire aux &Eacute;tats-Unis. Il y a une centaine de centrales nucl\u00e9aires. Beaucoup d&rsquo;entre elles sont encore en service. Beaucoup d&rsquo;entre elles sont tr\u00e8s anciennes. &Agrave; l&rsquo;heure actuelle, les &Eacute;tats-Unis ne disposent pas de la technologie n\u00e9cessaire pour les d\u00e9manteler en toute s\u00e9curit\u00e9, ni des fonds pour le faire. En ce qui concerne le remplacement de ces centrales nucl\u00e9aires, ils n&rsquo;ont plus l&rsquo;expertise technique pour le faire, et leur derni\u00e8re tentative de construire un r\u00e9acteur nucl\u00e9aire a \u00e9t\u00e9 un fiasco.<\/p>\n<\/p>\n<p><p>D&rsquo;autre part, si vous regardez Rosatom, la corporation nucl\u00e9aire russe, elle est en bonne voie de d\u00e9velopper le cycle nucl\u00e9aire ferm\u00e9 qui r\u00e9soudra le probl\u00e8me des d\u00e9chets nucl\u00e9aires de haute activit\u00e9. Cela permettra de br&ucirc;ler les d\u00e9chets nucl\u00e9aires de haute activit\u00e9 dans des r\u00e9acteurs nucl\u00e9aires jusqu&rsquo;\u00e0 ce qu&rsquo;ils deviennent des d\u00e9chets nucl\u00e9aires de faible activit\u00e9 qui pourront \u00eatre \u00e9limin\u00e9s en toute s\u00e9curit\u00e9. Et d&rsquo;autre part, cela permettra d&rsquo;utiliser l&rsquo;uranium 238 comme combustible. Actuellement, on l&rsquo;appelle uranium appauvri et il est consid\u00e9r\u00e9 comme inutile pour la plupart des usages, sauf peut-\u00eatre pour la fabrication d&rsquo;armements am\u00e9ricains, car c&rsquo;est un m\u00e9tal tr\u00e8s lourd, dense et dur. Mais s&rsquo;il est utilis\u00e9 comme combustible, alors il y a litt\u00e9ralement des milliers d&rsquo;ann\u00e9es de combustible disponible.<\/p>\n<\/p>\n<p><p>Les Russes d\u00e9veloppent donc cette technologie, et pas seulement en Russie mais dans d&rsquo;autres pays du monde &ndash; en Iran, en &Eacute;gypte et dans bien d&rsquo;autres pays. La Chine suit \u00e0 peu pr\u00e8s le m\u00eame programme avec un certain retard, mais elle peut solliciter une licence pour la technologie russe. Et tous les autres pays sont \u00e0 peu pr\u00e8s laiss\u00e9s pour compte. Donc si vous regardez la technologie nucl\u00e9aire, c&rsquo;est \u00e0 peu pr\u00e8s la Russie, la Chine, et peut-\u00eatre que la France a encore une certaine capacit\u00e9 restante. Certainement pas les &Eacute;tats-Unis. L&rsquo;Allemagne a d\u00e9cid\u00e9 de se d\u00e9barrasser de toute la technologie nucl\u00e9aire et d&rsquo;adopter les \u00e9nergies renouvelables, si bien que son \u00e9lectricit\u00e9 est aujourd&rsquo;hui six fois plus ch\u00e8re qu&rsquo;en Russie, ce qui fait qu&rsquo;il est en pratique devenu futile de fabriquer quoi que ce soit en Allemagne. D&rsquo;autres pays ont peut-\u00eatre la possibilit\u00e9, comme l&rsquo;&Eacute;gypte, d&rsquo;adh\u00e9rer au programme nucl\u00e9aire russe, mais, s&rsquo;ils sont hostiles \u00e0 la Russie, comme la Grande-Bretagne par exemple, ils n&rsquo;auront pas la possibilit\u00e9 de le faire.<\/p>\n<\/p>\n<p><p><strong><em>Sputnik<\/em><\/strong><em> : Question suivante, M. Orlov. Vous avez \u00e9crit sur la corr\u00e9lation entre la technologie et la m\u00e9decine. Je vous cite : \u00ab\u00a0L&rsquo;Ukraine, pour ne citer qu&rsquo;un exemple, est aujourd&rsquo;hui le terreau europ\u00e9en de la polio et de la rougeole, qui avaient \u00e9t\u00e9 \u00e9radiqu\u00e9es alors que l&rsquo;Ukraine appartenait \u00e0 l&rsquo;ex-URSS\u00a0\u00bb. Pouvez-vous nous en dire plus ?<\/em><\/p>\n<\/p>\n<p><p><strong>Dimitri Orlov <\/strong>: Oui. L&rsquo;Union sovi\u00e9tique a fait un investissement majeur dans la sant\u00e9 publique, et a \u00e9radiqu\u00e9 de nombreuses maladies infectieuses. Son h\u00e9ritage est toujours utilis\u00e9. Par exemple, en ce moment, la peste, la peste bubonique, est revenue en Mongolie et dans une r\u00e9gion voisine de la F\u00e9d\u00e9ration de Russie, \u00e0 Tuva. Et le vaccin qui a \u00e9t\u00e9 d\u00e9velopp\u00e9 par les scientifiques sovi\u00e9tiques est utilis\u00e9 aujourd&rsquo;hui pour vacciner la population et arr\u00eater cette \u00e9pid\u00e9mie. Et il existe des exemples similaires. Par exemple, le vaccin Sputnik V contre le coronavirus a \u00e9t\u00e9 mis au point en Union sovi\u00e9tique dans les ann\u00e9es 80, et il a maintenant \u00e9t\u00e9 r\u00e9utilis\u00e9, avec une charge utile diff\u00e9rente, pour d\u00e9velopper l&rsquo;immunit\u00e9 contre le coronavirus.<\/p>\n<\/p>\n<p><p>Il existe de nombreux exemples similaires de technologies utilis\u00e9es pour sauver des vies humaines, et une grande partie de cette utilisation a \u00e9t\u00e9 faite dans le cadre d&rsquo;une politique publique par opposition \u00e0 une m\u00e9decine commerciale et privatis\u00e9e, ce que les Am\u00e9ricains, par exemple, tentent de faire, mais sans succ\u00e8s.<\/p>\n<\/p>\n<p><p><strong><em>Sputnik<\/em><\/strong><em> : Donc, la question suivante, et je voudrais demander une chose de plus concernant le vaccin Sputnik V. Vous avez dit qu&rsquo;il \u00e9tait d\u00e9j\u00e0 d\u00e9velopp\u00e9 en Union sovi\u00e9tique. Il est maintenant remodel\u00e9, ou une nouvelle version, mais la formule est plus ancienne, de l&rsquo;\u00e9poque sovi\u00e9tique ?<\/em><\/p>\n<\/p>\n<p><p><strong>Dimitri Orlov <\/strong>: Oui, la technique. Elle utilise l&rsquo;ad\u00e9novirus, une version modifi\u00e9e de celui-ci qui n&rsquo;a pas la capacit\u00e9 de se r\u00e9pliquer dans le corps humain. Le vaccin utilise l&rsquo;ad\u00e9novirus comme vecteur. C&rsquo;est en grande partie ce qu&rsquo;est cette technologie, et elle a fait ses preuves, elle est efficace, etc. Et la charge utile est une petite partie du g\u00e9nome du coronavirus qui a \u00e9t\u00e9 sp\u00e9cifiquement isol\u00e9. C&rsquo;est la partie qui g\u00e9n\u00e8re la prot\u00e9ine de pointe qui permet au virus de p\u00e9n\u00e9trer les cellules humaines. Ainsi, l&rsquo;ad\u00e9novirus est introduit dans le corps, p\u00e9n\u00e8tre dans les cellules et lib\u00e8re sa charge utile. Les cellules produisent alors la prot\u00e9ine &ndash; \u00e0 ce stade, cela n&rsquo;a pas beaucoup \u00e0 voir avec le coronavirus lui-m\u00eame, \u00e0 l&rsquo;exception de cette prot\u00e9ine de pointe. Cette prot\u00e9ine r\u00e9agit alors avec le syst\u00e8me immunitaire et des anticorps sont g\u00e9n\u00e9r\u00e9s, ce qui est le r\u00e9sultat final de tout le processus. Et comme l&rsquo;ad\u00e9novirus n&rsquo;a pas la capacit\u00e9 de se r\u00e9pliquer, il est simplement expuls\u00e9 du syst\u00e8me. Le seul nouvel ingr\u00e9dient est donc la prot\u00e9ine de pointe. Elle n&rsquo;est pas toxique en soi ; elle ne fait rien d&rsquo;autre que de d\u00e9clencher une r\u00e9ponse immunitaire, parce que le corps ne la reconna&icirc;t pas, ce qu&rsquo;il doit faire. C&rsquo;est donc la raison pour laquelle les Russes ont pu le faire si rapidement et avec tant de succ\u00e8s. Parce qu&rsquo;il s&rsquo;agit en fait de r\u00e9utiliser une technique existante avec une l\u00e9g\u00e8re modification.<\/p>\n<\/p>\n<p><p><strong><em>Sputnik<\/em><\/strong><em> : D&rsquo;accord. Merci beaucoup. Pour en revenir \u00e0 votre livre, vous avez \u00e9crit que la capacit\u00e9 de d\u00e9loger puis d&rsquo;exploiter les gens est un ingr\u00e9dient cl\u00e9 du succ\u00e8s de la technosph\u00e8re. Pourquoi en est-il ainsi ?<\/em><\/p>\n<\/p>\n<p><p><strong>Dimitri Orlov <\/strong>: Eh bien, parce que si vous avez des soci\u00e9t\u00e9s humaines coh\u00e9sives qui prennent soin de leurs propres membres, elles sont plut\u00f4t difficiles \u00e0 exploiter. Elles ont tendance \u00e0 \u00eatre pointilleuses dans le choix des emplois qu&rsquo;elles choisissent ; elles s&rsquo;attendent \u00e0 \u00eatre bien r\u00e9mun\u00e9r\u00e9es pour leurs efforts et elles ont beaucoup de points de repli. Par exemple, si les temps sont durs, ils peuvent retourner \u00e0 la terre, vivre avec leurs parents, avec leur clan, cultiver leur propre nourriture et se sentir parfaitement en s\u00e9curit\u00e9. Et si les conditions s&rsquo;am\u00e9liorent, ils peuvent aller dans les villes, chercher du travail, etc. Mais si vous chassez les gens de leurs terres, si vous perturbez les communaut\u00e9s, si vous introduisez dans la communaut\u00e9 des \u00e9trangers totalement incompatibles parlant une langue \u00e9trang\u00e8re, si vous faites en sorte que les gens aient peur les uns des autres, si vous introduisez un certain niveau de violence &ndash; par exemple, si vous prenez des gens dans des zones de guerre et les introduisez dans des communaut\u00e9s habitu\u00e9es \u00e0 des circonstances tr\u00e8s pacifiques, vous rendrez les gens si d\u00e9sesp\u00e9r\u00e9s qu&rsquo;ils feront n&rsquo;importe quoi pour survivre parce qu&rsquo;ils n&rsquo;ont pas de repli, qu&rsquo;ils n&rsquo;ont pas le soutien de la communaut\u00e9, qu&rsquo;ils sont entour\u00e9s d&rsquo;\u00e9trangers &ndash; ils sont d\u00e9sesp\u00e9r\u00e9s et ils accepteront n&rsquo;importe quoi. Voil\u00e0 donc l&rsquo;astuce de la technosph\u00e8re pour exploiter les gens. Perturber et d\u00e9truire les communaut\u00e9s en introduisant des \u00e9trangers, et faire en sorte que cette communaut\u00e9 se comporte non pas comme une communaut\u00e9 mais comme des individus ali\u00e9n\u00e9s et d\u00e9sesp\u00e9r\u00e9s.<\/p>\n<\/p>\n<p><p><strong><em>Sputnik<\/em><\/strong><em> : M. Orlov, quelle est votre conclusion et \u00e0 quoi ressemblera l&rsquo;avenir technologique en ce qui concerne<\/em> [inintelligible],<em> l&rsquo;IA<\/em> [inintelligible],<em> la num\u00e9risation <\/em>[inintelligible] <em>de la conscience. Quelle est votre opinion \u00e0 ce sujet ?<\/em><\/p>\n<\/p>\n<p><p><strong>Dimitri Orlov <\/strong>: Eh bien, je pense qu&rsquo;il s&rsquo;agit en grande partie de poudre aux yeux. Une grande partie de cette nouvelle technologie fantaisiste n&rsquo;est rien. Je pense que l&rsquo;IA et la programmation des r\u00e9seaux neuronaux sont utiles pour un certain nombre d&#8217;emplois sp\u00e9cifiques. En ce qui concerne les versions num\u00e9riques de vos parents \u00e2g\u00e9s, etc., c&rsquo;est un peu de la science-fiction pour l&rsquo;instant. Je pense que dans l&rsquo;ensemble, beaucoup de gens seront oblig\u00e9s de r\u00e9duire leur utilisation de la technologie dans une certaine mesure. Les circonstances \u00e9conomiques les obligeront \u00e0 le faire. D&rsquo;un autre c\u00f4t\u00e9, c&rsquo;est une technique tr\u00e8s puissante : l&rsquo;internet et les smartphones sont des techniques tr\u00e8s puissantes pour garder les gens au calme et les contr\u00f4ler. Je pense donc qu&rsquo;ils seront toujours utilis\u00e9s, mais je ne pense pas qu&rsquo;il y ait quoi que ce soit de particuli\u00e8rement \u00e9trange dans l&rsquo;utilisation quotidienne par les gens ordinaires. Je pense qu&rsquo;une grande partie de ce mat\u00e9riel restera de la propagande, de la propagande technologique, techno-utopienne. Il y a toujours beaucoup de cela : on parle toujours de missions spatiales vers Mars, de voitures volantes et de tout ce qui s&rsquo;y rapporte. C&rsquo;est un barrage constant, mais ce n&rsquo;est que de la propagande.<\/p>\n<\/p>\n<p><p><strong><em>Sputnik<\/em><\/strong><em> :<\/em> <em>Merci beaucoup. Ma derni\u00e8re question : avez-vous un sc\u00e9nario positif ou voyez-vous un sc\u00e9nario n\u00e9gatif pour l&rsquo;avenir ? Est-ce que ce sera comme dans le film The Terminator, ou est-ce que la technologie donnera \u00e0 l&rsquo;humanit\u00e9 une image positive, disons comme dans Startrek ?<\/em><\/p>\n<\/p>\n<p><p><strong>Dimitri Orlov <\/strong>: Eh bien, je pense que ce n&rsquo;est rien de tout cela. Nous n&rsquo;avons pas d&rsquo;autre choix que d&rsquo;utiliser la technologie. La cuisson des aliments, par exemple, est une forme de technologie. Fabriquer des v\u00eatements \u00e0 partir d&rsquo;\u00e9corces d&rsquo;arbres, c&rsquo;est toujours de la technologie. Nous aurons donc toujours une sorte de technologie. La question est de savoir quel type de technologie ce sera. Dans quelle mesure sera-t-elle sous notre contr\u00f4le ou non ? Je pense que nous vivrons dans un monde de plus en plus agraire. La quantit\u00e9 d&rsquo;\u00e9nergie n\u00e9cessaire \u00e0 l&rsquo;entretien des grandes villes ne sera tout simplement pas disponible dans la plupart des endroits du monde. Le monde sera donc de plus en plus local et agraire, mais je pense qu&rsquo;il y aura encore des gadgets tr\u00e8s utiles. Ainsi, par exemple, le fait qu&rsquo;il soit possible de conserver toute une biblioth\u00e8que de documents sur une seule carte SD constitue une avanc\u00e9e majeure par rapport au support papier pour les livres. Cela pourrait durer encore un certain temps. Le probl\u00e8me est que de telles utilisations de la technologie n\u00e9cessitent des centres technologiques qui peuvent la produire et l&rsquo;entretenir, et la question est de savoir dans quelles parties du monde ces centres technologiques peuvent \u00eatre maintenues. Si vous regardez, ce sont des endroits qui ont toute la cha&icirc;ne technologique, en commen\u00e7ant par l&rsquo;exploitation mini\u00e8re et la production de combustibles fossiles, en passant par la production de combustibles nucl\u00e9aires, jusqu&rsquo;\u00e0 tout ce qui est n\u00e9cessaire pour maintenir un r\u00e9seau \u00e9lectrique, tout ce qui est n\u00e9cessaire pour \u00e9duquer et former les personnes qui produiront des semi-conducteurs et \u00e9criront des logiciels, et tout le soutien n\u00e9cessaire pour cela. Il n&rsquo;y a que quelques endroits dans le monde o&ugrave; il est possible d&rsquo;imaginer que quelque chose comme cela va persister pendant de nombreuses d\u00e9cennies, voire des si\u00e8cles.<\/p>\n<\/p>\n<p><p>Le 25 ao&ucirc;t 2020, <a href=\"http:\/\/cluborlov.blogspot.com\/2020\/08\/our-technologies-could-destroy-humanity.html\">Club Orlov<\/a> &ndash; Traduction du <em><a href=\"https:\/\/lesakerfrancophone.fr\/nos-technologies-pourrait-detruire-lhumanite\">Sakerfrancophone<\/a><\/em><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nos technologies pourrait d\u00e9truire l&rsquo;humanit\u00e9 Interview pour Sputnik Allemagne Sputnik : M. Orlov, nous voulons aujourd&rsquo;hui discuter de votre dernier livre, &lsquo;Shrinking the Technosphere&rsquo; [\u00e9dit\u00e9 en allemand], mais avant de commencer, j&rsquo;aimerais approfondir une de vos r\u00e9ponses de notre premi\u00e8re interview sur Sputnik Allemagne. Vous avez dit que la banque centrale am\u00e9ricaine (la R\u00e9serve f\u00e9d\u00e9rale)&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[29],"tags":[12153,4008,3475,2668,3309,17069,3519],"class_list":["post-79411","post","type-post","status-publish","format-standard","hentry","category-les-carnets-de-dimitri-orlov-1","tag-artificielle","tag-intelligence","tag-marx","tag-orlov","tag-postmodernite","tag-spoutnik","tag-technologie"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79411"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79411\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79411"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79411"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}