{"id":79422,"date":"2023-10-12T13:19:54","date_gmt":"2023-10-12T13:19:54","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2023\/10\/12\/le-desordre-des-choses-du-monde\/"},"modified":"2023-10-12T13:19:54","modified_gmt":"2023-10-12T13:19:54","slug":"le-desordre-des-choses-du-monde","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2023\/10\/12\/le-desordre-des-choses-du-monde\/","title":{"rendered":"Le d\u00e9sordre des choses du monde"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Le d\u00e9sordre des choses du monde<\/h2>\n<\/p>\n<p><p>12 octobre 2023 (13H20) &ndash; On fait un petit tour d&rsquo;horizon, petit mais vertigineux parce que l&rsquo;horizon lui-m\u00eame est vertigineux, &ndash; vous-m\u00eame et moi-m\u00eame, nous pouvons en t\u00e9moigner. On ne dira pas qu&rsquo;Isra\u00ebl-Hamas a chang\u00e9 la donne parce qu&rsquo;il n&rsquo;y a pas \u00ab\u00a0une donne\u00a0\u00bb. Les cartes, &ndash; les crises en r\u00e9alit\u00e9, ou &lsquo;sous-crises&rsquo; comme j&rsquo;aime \u00e0 les d\u00e9signer pour leur rabaisser leur caquet, &ndash; se d\u00e9couvrent les unes apr\u00e8s les autres, s&rsquo;additionnent, s&#8217;empilent, forment une masse crisique d&rsquo;une puissance dynamique \u00e9poustouflante. C&rsquo;est la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-la-gces\">GrandeCrise<\/a>, bien s&ucirc;r.<\/p>\n<\/p>\n<p><p>Nous n&rsquo;allons pas d\u00e9tailler parce que nous chevauchons l&rsquo;<a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-linconnaissance\">inconnaissance<\/a>, qui nous permet d&rsquo;aller plus vite, plus loin et surtout plus haut. Sur cette crise devenue paroxystique depuis samedi, deux choses, directement et indirectement.<\/p>\n<\/p>\n<p><p>&bull; Directement, il faut \u00e9couter l&rsquo;intervention tr\u00e8s longue (les vingt premi\u00e8res minutes) d&rsquo;Alastair Crooke dans <a href=\"https:\/\/theduran.com\/extremist-politics-in-israel-and-ukraine-alastair-crooke-alexander-mercouris-and-glenn-diesen\/\">une vid\u00e9o<\/a> avec Alexander Mercouris et Glenn Diesen. Crooke d\u00e9crit en d\u00e9tail l&rsquo;actuel affrontement autour de la mosqu\u00e9e <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Mosqu\u00e9e_al-Aqsa\">al-Aqsa et de son destin<\/a> ; affrontement entrer l&rsquo;aile extr\u00e9miste juives du gouvernement et les forces qu&rsquo;elle repr\u00e9sente contre le bloc la\u00efc juif (opposition). Bien entendu, le destin d&rsquo;al-Aqsar et le projet de reconstruction du Temple est au centre de l&rsquo;affrontement avec le Hamas, &ndash; mais il ne faut surtout pas oublier cette division en Isra\u00ebl qui fracture irr\u00e9m\u00e9diablement le pays depuis des mois. L&rsquo;expos\u00e9 de Crooke, jusqu&rsquo;aux perspectives actuelles, est fascinant ; les perspectives de la situation sur le terrain, elles, sont effrayantes.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Solitude de Mister Z (suite)<\/h3>\n<\/p>\n<p><p>&bull; Le deuxi\u00e8me point est indirect mais imm\u00e9diatement op\u00e9rationnel. Il s&rsquo;agit de la confirmation de <a href=\"https:\/\/www.dedefensa.org\/article\/un-noeud-crisique-comme-un-serpent\">la d\u00e9b\u00e2cle de l&rsquo;Ukraine<\/a> dans l&rsquo;intelligence occidentale r\u00e9duite depuis des ann\u00e9es, cette intelligence-l\u00e0, \u00e0 un album d&rsquo;images et de clich\u00e9s.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Pour &lsquo;Ukrisis&rsquo;, la crise ukrainienne, c&rsquo;est la premi\u00e8re fois depuis le 24 f\u00e9vrier 2022 que les Russes sont compl\u00e8tement lib\u00e9r\u00e9s, &ndash; temporairement, en principe, &ndash; de la main de fer de la communication antirusse qui s&rsquo;est d\u00e9cha&icirc;n\u00e9e contre eux. Cela ne signifie pas que l&rsquo;on ne parle plus de l&rsquo;Ukraine mais que l&rsquo;Ukraine n&rsquo;est plus l&rsquo;\u00e9picentre de la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-la-gces\">GrandeCrise<\/a>. Pour la Russie, c&rsquo;est une opportunit\u00e9, voire une victoire strat\u00e9gique inesp\u00e9r\u00e9e et nous verrons ce qu&rsquo;ils en font et en feront, &ndash; ce pourquoi l&rsquo;on dit ce que l&rsquo;on dit \u00e0 propos de leur pouss\u00e9e sur le front<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>La cons\u00e9quence de cette d\u00e9faite strat\u00e9gique de l&rsquo;image, c&rsquo;est pour la Russie la porte ouverte aux avanc\u00e9es sur tous les fronts face \u00e0 une direction ukrainienne compl\u00e8tement d\u00e9sorient\u00e9e et aux abois puisque priv\u00e9e d&rsquo;images et de clich\u00e9s. <a href=\"https:\/\/sonar21.com\/russia-closing-the-noose-on-ukrainian-troops\/\">Larry Johnson<\/a> se charge du travail en mettant en \u00e9vidence le point le plus important : le changement de mode, du kaki de combat au noir fun\u00e8bre, des v\u00eatements de Zelenski.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Il est \u00e9tonnant de voir \u00e0 quelle vitesse l&rsquo;attention de l&rsquo;Occident est pass\u00e9e de la guerre en Ukraine \u00e0 la guerre en Isra\u00ebl. Comme je l&rsquo;ai not\u00e9 dans des interviews r\u00e9centes, le pr\u00e9sident ukrainien Zelensky est effray\u00e9 et stup\u00e9fait par ce revirement et tente d\u00e9sesp\u00e9r\u00e9ment de rester pertinent et d&rsquo;attirer l&rsquo;attention de l&rsquo;Occident. Bonne chance. Les m\u00e9dias pr\u00e9f\u00e8rent se concentrer sur le nouveau r\u00e9cit des hordes arabes s&rsquo;abattant sur les civils isra\u00e9liens plut\u00f4t que d&rsquo;essayer de trouver des excuses \u00e0 l&rsquo;\u00e9chec de l&rsquo;Ukraine, qui n&rsquo;a m\u00eame pas r\u00e9ussi \u00e0 franchir la premi\u00e8re ligne de d\u00e9fense de Sourovikine. Un signe visible de la panique de Zelenski est qu&rsquo;il a chang\u00e9 sa garde-robe. D\u00e9sormais, lorsqu&rsquo;il appara&icirc;t en public, au lieu de porter son costume de Fidel Castro (c&rsquo;est-\u00e0-dire un t-shirt ou un sweat-shirt vert militaire et un pantalon tactique), il est maintenant habill\u00e9 comme une version plus jeune et plus courte de Johnny Cash. Le noir est la nouvelle couleur \u00e0 la mode.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Alors que l&rsquo;Occident a les yeux riv\u00e9s sur le Moyen-Orient, la Russie passe \u00e0 l&rsquo;offensive et repousse les Ukrainiens tout au long de la ligne de contact. Le correspondant de guerre russe Marat nous en parle.<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Une vision de l&rsquo;inconnaissance<\/h3>\n<\/p>\n<p><p>Ce qu&rsquo;il nous faut, c&rsquo;est une vision globale, g\u00e9n\u00e9rale, marqu\u00e9e par l&rsquo;<a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-linconnaissance\">inconnaissance<\/a>, c&rsquo;est-\u00e0-dire le refus de prendre syst\u00e9matiquement en compte les \u00e9v\u00e8nements tactiques et m\u00eame strat\u00e9giques dans nos espaces si satisfaits d&rsquo;eux-m\u00eames \u00e0 partir du moment o&ugrave; ces \u00e9v\u00e8nements sont en cours et sollicitent tel ou tel engagement terrestre de nos esprits infest\u00e9s d&rsquo;images et de clich\u00e9s.<\/p>\n<\/p>\n<p><p>Il me semble rencontrer incontestablement cette d\u00e9marche que je cherche moi-m\u00eame \u00e0 suivre, dans ces quelques remarques si pr\u00e9cises et si large d&rsquo;un <a href=\"http:\/\/euro-synergies.hautetfort.com\/archive\/2023\/10\/11\/la-civilisation-judeo-chretienne-n-existe-pas-en-occident.html\">court texte<\/a> d&rsquo;Alexander Douguine. Il faut donc les lire en s&rsquo;\u00f4tant de l&rsquo;esprit selon que l&rsquo;on est, si c&rsquo;est le cas, pro-Isra\u00ebl ou pro-Hamas, hors de toutes ces conceptions morales et <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-laffectivisme-postmoderne\">affectivistes<\/a> in\u00e9vitables vu l&rsquo;ampleur et l&rsquo;horreur du drame, mais qui ne nous disent rien de l&rsquo;essentiel. Il faut les lire en faisant l&rsquo;effort de n&rsquo;\u00eatre plus des \u00ab\u00a0civilis\u00e9s\u00a0\u00bb tels que nous sommes devenus, rago&ucirc;t de moutons, tra&icirc;tres \u00e0 nos origines, indiff\u00e9rents \u00e0 nos croyances, civilis\u00e9s comme des &lsquo;<em>barbares int\u00e9rieurs<\/em>&lsquo; (Mattei), &ndash; extr\u00eamement s\u00e9lectifs, voire sophistiqu\u00e9s dans nos indignations, comme en peuvent t\u00e9moigner quelques amis reconnaissants, des Afghans aux Irakiens.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>La Russie est un p\u00f4le d&rsquo;un monde multipolaire.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>L&rsquo;islam est un p\u00f4le d&rsquo;un monde multipolaire.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Ces deux p\u00f4les s&rsquo;opposent aux tentatives d\u00e9sesp\u00e9r\u00e9es de l&rsquo;Occident pour sauver l&rsquo;unipolarit\u00e9 et sa domination mondiale \u00e0 tout prix &#8211; m\u00eame au prix d&rsquo;une guerre mondiale. Le conflit palestinien avec Isra\u00ebl n&rsquo;\u00e9tait pas la ligne de front du conflit des civilisations. Aujourd&rsquo;hui, c&rsquo;est le cas. Tout comme les frictions entre la Russie et l&rsquo;Ukraine \u00e9taient r\u00e9gionales jusqu&rsquo;\u00e0 ce que l&rsquo;Occident soutienne les nazis de Kiev. La guerre en Ukraine est alors devenue la ligne de front de la confrontation mondiale entre la multipolarit\u00e9 et l&rsquo;unipolarit\u00e9.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>L&rsquo;ampleur de cette confrontation ne cesse de cro&icirc;tre. La situation devient de plus en plus inqui\u00e9tante. Des milliards de personnes sur la plan\u00e8te sont d\u00e9j\u00e0 convaincues que l&rsquo;Occident collectif et ses alli\u00e9s sont le mal absolu et la civilisation de l&rsquo;Ant\u00e9christ<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Retour dans notre Occident-compulsif<\/h3>\n<\/p>\n<p><p>&#8230; C&rsquo;est-\u00e0-dire, apr\u00e8s s&rsquo;en \u00eatre extraits, que s&rsquo;impose un \u00ab\u00a0retour\u00a0\u00bb aux \u00e9v\u00e8nements courants une fois l&rsquo;esprit lav\u00e9 par l&rsquo;inconnaissance. Alors, leur signification appara&icirc;t, beaucoup plus lumineuse, celle de nos mortelles contradictions, de nos n&oelig;uds gordiens de notre moraline sans fin, nous les si-importants et les si contents-de-nous. Ce que le conflit paroxystique Isra\u00ebl-Hamas met en lumi\u00e8re d&rsquo;une mani\u00e8re absolument tragique, ce sont les pi\u00e8ces pesantes, &ndash; fa\u00e7on howitzer 155mm, &ndash; du long et lourd d\u00e9fil\u00e9 des contradictions frontales de nos vertus innombrables.<\/p>\n<\/p>\n<p><p>Incontestablement, il y a du nouveau. En France l&rsquo;on parle beaucoup, et avec grand d\u00e9go&ucirc;t, de cette extr\u00eame-gauche, de LFI aux indig\u00e9nistes et autres wokenistes, qui soutient Hamas, &ndash; c&rsquo;est-\u00e0-dire, logique impitoyablement induite, Hamas et ses massacres. Mais c&rsquo;est aux USA que le ph\u00e9nom\u00e8ne est le plus important : les &lsquo;<em>Black Lives Matter<\/em>&lsquo;, nombre d&rsquo;organisations genristes et soci\u00e9tales ont ouvertement pris position pour Hamas et l&rsquo;ont fait savoir pendant deux-trois jours par le canal de &lsquo;X&rsquo;, ex-Tweeter. L&rsquo;ampleur du massacre en Isra\u00ebl a r\u00e9v\u00e9l\u00e9 \u00e0 beaucoup l&rsquo;inconfort de la cohabitation avec ces organisations, y compris quelques gros donateurs dont, \u00e9videmment, un certain nombre de juifs am\u00e9ricains fortun\u00e9s jusqu&rsquo;alors aveugl\u00e9ment progressistes et qui r\u00e9visent leurs copies.<\/p>\n<\/p>\n<p><p>&lsquo;<em><a href=\"https:\/\/www.zerohedge.com\/news\/2023-10-11\/siding-hamas-has-left-finally-gone-too-far\">ZeroHedge.com<\/a><\/em>&lsquo; ne manque pas de nous donner un vaste \u00e9chantillon de messages-X, avec \u00e0 peine quelques commentaires tant les choses vont d&rsquo;elles-m\u00eames.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Comme l&rsquo;a fait remarquer notre ami Isaac Simpson, ce type de messages pro-Hamas aurait peut-\u00eatre rencontr\u00e9 moins de r\u00e9sistance s&rsquo;il s&rsquo;\u00e9tait agi d&rsquo;une attaque terroriste typiquement inefficace, mais l&rsquo;ampleur et la sauvagerie de celle-ci ont finalement amen\u00e9 certaines \u00e9lites am\u00e9ricaines \u00e0 repenser leur tol\u00e9rance \u00e0 l&rsquo;\u00e9gard de l&rsquo;approbation de la violence politique par la gauche<\/em>. [&#8230;]<\/p>\n<\/p>\n<p><p>&raquo; <em>Malheureusement pour les gauchistes des universit\u00e9s et des grandes \u00e9coles, leurs messages pro-Hamas ont \u00e9galement attir\u00e9 l&rsquo;attention de leurs futurs employeurs. <\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Le gestionnaire de fonds sp\u00e9culatifs Bill Ackman et d&rsquo;autres ont commenc\u00e9 \u00e0 demander les noms des \u00e9tudiants \u00e0 l&rsquo;origine des organisations de Harvard qui ont publi\u00e9 des d\u00e9clarations pro-Hamas<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Si la gauche extr\u00eame se trouve en grandes difficult\u00e9s, la droite peut se retrouver \u00e9gale \u00e0 elle-m\u00eame, couteau entre les dents et \u00ab\u00a0Sus aux infid\u00e8les !\u00a0\u00bb. Cette avanc\u00e9e ne donne pas beaucoup plus de cr\u00e9dit \u00e0 ce champ politique qui a toujours vant\u00e9 la tradition tout en favorisant le capitalisme hypermoderniste et globaliste ; de ce c\u00f4t\u00e9, moins d&rsquo;erreurs parce que moins d&rsquo;actes, juste quelques poussi\u00e8res, d\u00e9bris d&rsquo;autres temps plus heureux qu&rsquo;un peu de sable efface.<\/p>\n<\/p>\n<p><p>O&ugrave; faire son choix, entre cette droite et ses anath\u00e8me, et cette gauche et son hyst\u00e9rie ? Je pr\u00e9f\u00e8re ne pas m&rsquo;attarder dans les d\u00e9dales et l&rsquo;on passe son chemin en comptant les points qui sont marqu\u00e9s dans le grand sablier conduisant \u00e0 la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-la-gces\">GrandeCrise<\/a>. C&rsquo;est possible mais il faut se raviser et tout de m\u00eame sacrifier \u00e0 un choix s\u00e9lectif selon des r\u00e9f\u00e9rences connues de notre \u00ab\u00a0<a href=\"https:\/\/www.dedefensa.org\/article\/lame-poetique-et-notre-finitude\">\u00e2me po\u00e9tique<\/a>\u00a0\u00bb seule, car les \u00e9v\u00e8nements du temps, eux, d\u00e9signent la victime sacrificielle de la crise dans l&rsquo;Occident-compulsif. Le progressisme-social, dit \u00ab\u00a0de gauche\u00a0\u00bb et wokenisme inclus, est beaucoup, beaucoup plus expos\u00e9 et vuln\u00e9rable que la droite qui a peur de son ombre et croit encore \u00e0 la Sainte-Am\u00e9rique et sa prot\u00e9g\u00e9e <a href=\"https:\/\/www.dedefensa.org\/article\/un-ete-meurtrier\">n\u00e9e du Pentagone<\/a>, &lsquo;<em>Tsahal<\/em>&lsquo; repeint aux couleurs modernistes et devenu IDF (&lsquo;<em>Israel Defense Force<\/em>&lsquo;). Justement, la susdite Sainte est dans un bel embarras \u00e0 avoir soutenu, par sa \u00ab\u00a0gauche-chic\u00a0\u00bb de l&rsquo;antiracisme aux folies de tous les genres, Hamas comme elle le fit et, par \u00ab\u00a0logique impitoyablement induite\u00a0\u00bb, les massacres qui en r\u00e9sultent.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Des \u00e9cumes de temp\u00eate<\/h3>\n<\/p>\n<p><p>Voil\u00e0 donc comment nous d\u00e9chirent impitoyablement ces sous-crises terribles. Tout ce que nous avons d\u00e9crit d&rsquo;op\u00e9rationnel est n\u00e9cessairement accessoire et n&rsquo;engage rien d&rsquo;assur\u00e9. Disons que c&rsquo;est l&rsquo;\u00e9cume de la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-la-gces\">GrandeCrise<\/a> ; mais parfois, lorsque l&rsquo;\u00e9cume est bouillonnante et tr\u00e8s haute, nous avons l&rsquo;indication certaine, &ndash; c&rsquo;est un vieux loup de mer reclus et coutur\u00e9 de temp\u00eates qui vous le dit, &ndash;que les vagues peuvent \u00eatre monstrueuses, comme si l&rsquo;on se trouvait, vent debout,<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>entre les  \u00ab\u00a0<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Quaranti%C3%A8mes_rugissants\">Quaranti\u00e8mes rugissants<\/a>\u00a0\u00bb  et les \u00ab\u00a0<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Cinquanti\u00e8mes_hurlants\">Cinquanti\u00e8mes hurlants<\/a>\u00a0\u00bb des latitudes correspondantes vers le Sud extr\u00eame des \u00e9tendues glac\u00e9es o&ugrave; jamais le vent ne s&rsquo;arr\u00eate de souffler et la mer de d\u00e9ferler, o&ugrave; les marins disent qu&rsquo;au-del\u00e0 vers l&rsquo;au-del\u00e0 du Sud Dieu n&rsquo;est plus<\/em>.[&#8230;]<\/p>\n<\/p>\n<p><p>&raquo; &#8230;<em>un vieux dicton des vieux marins des Temps Anciens disait de ces terribles latitudes d&rsquo;un Sud ressemblant \u00e0 l&rsquo;Enfer glac\u00e9 : <\/em>\u00ab\u00a0<em>Sous les 40 degr\u00e9s, il n&rsquo;y a plus de loi, mais sous les 50 degr\u00e9s, il n&rsquo;y a plus de Dieu\u00a0\u00bb.<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Isra\u00ebl-Hamas, apr\u00e8s &lsquo;<em>Ukrisis<\/em>&lsquo; qui continue bien s&ucirc;r, porte un nouveau coup de b\u00e9lier \u00e0 notre forteresse assi\u00e9g\u00e9e.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le d\u00e9sordre des choses du monde 12 octobre 2023 (13H20) &ndash; On fait un petit tour d&rsquo;horizon, petit mais vertigineux parce que l&rsquo;horizon lui-m\u00eame est vertigineux, &ndash; vous-m\u00eame et moi-m\u00eame, nous pouvons en t\u00e9moigner. On ne dira pas qu&rsquo;Isra\u00ebl-Hamas a chang\u00e9 la donne parce qu&rsquo;il n&rsquo;y a pas \u00ab\u00a0une donne\u00a0\u00bb. Les cartes, &ndash; les crises&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[20204,2719,5111,11201,2774,2866,2622,2906,19719,20205,13670,2829],"class_list":["post-79422","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-gauche-hamas","tag-grandecrise","tag-hamas","tag-inconnaissance","tag-israel","tag-johnson","tag-la","tag-larry","tag-quarantiemes","tag-rugissants","tag-ukrisis","tag-zelenski"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79422","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79422"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79422\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79422"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79422"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}