{"id":79442,"date":"2020-09-26T01:53:49","date_gmt":"2020-09-26T01:53:49","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2020\/09\/26\/les-chauffeurs-de-taxi-savent-tout\/"},"modified":"2020-09-26T01:53:49","modified_gmt":"2020-09-26T01:53:49","slug":"les-chauffeurs-de-taxi-savent-tout","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2020\/09\/26\/les-chauffeurs-de-taxi-savent-tout\/","title":{"rendered":"Les chauffeurs de taxi savent tout"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d;font-size:1.65em;font-variant:small-caps;\">Les chauffeurs de taxi savent tout<\/h2>\n<\/p>\n<p><p>Il se trouve qu&rsquo;hier, je rentrais chez moi en taxi. Le chauffeur de taxi, qui ressemblait \u00e0 <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Bill_Murray\">Bill Murray<\/a>, s&rsquo;est r\u00e9v\u00e9l\u00e9 tr\u00e8s bavard. Pendant le trajet, comme cela arrive souvent, nous avons abord\u00e9 tous les sujets, du temps qu&rsquo;il fait aux blondes au volant.<\/p>\n<\/p>\n<p><p>&Agrave; un moment donn\u00e9, en guise de bruit de fond, la radio diffusait les nouvelles. Apr\u00e8s le reportage sur l&#8217;empoisonnement d&rsquo;Alexei Navalny, le <em>NordStream 2<\/em> et les \u00e9ventuelles sanctions de l&rsquo;UE, le chauffeur de taxi a secou\u00e9 la t\u00eate et a fait une d\u00e9claration r\u00e9fl\u00e9chie : &laquo;<em> Ce coup-ci, maman est coinc\u00e9e&hellip; <\/em>&raquo;<\/p>\n<\/p>\n<p><p>&laquo;<em> Quelle maman ? <\/em>&raquo; Me suis-je renseign\u00e9.<\/p>\n<\/p>\n<p><p>&laquo;<em> Quelle maman ? <\/em>&raquo; a r\u00e9p\u00e9t\u00e9 le chauffeur de taxi. &laquo;<em> Toujours la m\u00eame, Angela Merkel. Vous savez pourquoi Navalny a \u00e9t\u00e9 livr\u00e9 \u00e0 l&rsquo;Allemagne ? Laissez-moi vous expliquer<\/em>. &raquo; Et puis, pendant un quart d&rsquo;heure, le chauffeur de taxi a pr\u00e9sent\u00e9 une th\u00e9orie coh\u00e9rente de ce qui s&rsquo;est pass\u00e9, digne d&rsquo;\u00eatre \u00e9tudi\u00e9e au minist\u00e8re des Affaires \u00e9trang\u00e8res, qui r\u00e9pondait \u00e0 toutes les questions qui me pr\u00e9occupaient.<\/p>\n<\/p>\n<p><p>Voici l&rsquo;histoire.<\/p>\n<\/p>\n<p><p>Au d\u00e9but du mois d&rsquo;ao&ucirc;t, tout le monde se pr\u00e9parait aux \u00e9lections en Bi\u00e9lorussie, dans le pays lui-m\u00eame, ainsi qu&rsquo;en Russie et dans les pays de l&rsquo;UE. C&rsquo;\u00e9tait un jeu passionnant dans lequel chacun pariait sur son propre candidat. Mais je dois imm\u00e9diatement vous avertir que ce que nous observions n&rsquo;\u00e9tait que la partie visible de l&rsquo;iceberg, alors que les courants sous-marins n&rsquo;\u00e9taient connus que de quelques-uns.<\/p>\n<\/p>\n<p><p>Moscou et Minsk \u00e9taient en train de casser la vaisselle de mani\u00e8re d\u00e9monstrative, en se criant dessus et en se tirant par les cheveux, cr\u00e9ant l&rsquo;illusion d&rsquo;une rupture totale des relations. C&rsquo;\u00e9tait l&rsquo;intention !<\/p>\n<\/p>\n<p><p>L&rsquo;Europe, contente et d\u00e9tendue, se frottait les mains et voyait d\u00e9j\u00e0 comment elle allait tr\u00e8s bient\u00f4t chasser &laquo;<em> le dernier dictateur d&rsquo;Europe <\/em>&raquo; et installer un clone Bi\u00e9lorusse de <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Juan_Guaid%C3%B3\">Juan Guaid&oacute;<\/a> \u00e0 Minsk, s&#8217;emparant de cette d\u00e9licieuse pi\u00e8ce de l&rsquo;\u00e9chiquier.<\/p>\n<\/p>\n<p><p>Les \u00e9lections ont eu lieu. Tout le monde s&rsquo;est fig\u00e9. Sans se soucier d&rsquo;attendre les r\u00e9sultats des \u00e9lections, sur ordre du m\u00e9dia provocateur polonais <em>Nexta<\/em>, l&rsquo;opposition bi\u00e9lorusse blanc-rouge-blanc [le drapeau de l&rsquo;occupant nazi] s&rsquo;est mise en ordre de bataille.<\/p>\n<\/p>\n<p><p>Au d\u00e9but, tout se passait comme pr\u00e9vu. Des foules de blanc-rouge-blanc excit\u00e9s inond\u00e8rent les rues et commenc\u00e8rent \u00e0 menacer la police, les fonctionnaires et les journalistes, d\u00e9clenchant des escarmouches et des gr\u00e8ves. Les ambassadeurs slovaques et espagnols en Bi\u00e9lorussie se sont prononc\u00e9s en faveur des manifestants et \u00ab\u00a0se sont rang\u00e9s du c\u00f4t\u00e9 du peuple\u00a0\u00bb. Cela se passait \u00e9galement comme pr\u00e9vu. Il semblait que Loukachenko \u00e9tait \u00e0 deux doigts de tomber.<\/p>\n<\/p>\n<p><p>Mais ensuite, Moscou est entr\u00e9 dans le jeu. Elle a reconnu le r\u00e9sultat des \u00e9lections [que Loukachenko a gagn\u00e9es] et a commenc\u00e9 \u00e0 le soutenir sur le plan organisationnel, informationnel et financier. L&rsquo;Europe devait augmenter la pression. Mais comment ?<\/p>\n<\/p>\n<p><p><em>Nexta<\/em> faisait des pieds et des mains et exhortait les militants blanc-rouge-blanc \u00e0 \u00eatre plus actifs, mais ils n&rsquo;arrivaient pas \u00e0 prendre le dessus dans leurs tentatives de prise de pouvoir. Ils se sont r\u00e9v\u00e9l\u00e9s trop faibles, en comparaison avec leur propre peuple. Et puis, heureusement, Navalny a \u00e9t\u00e9 empoisonn\u00e9. En tout cas, c&rsquo;est ce que certains ont imagin\u00e9.<\/p>\n<\/p>\n<p><p>Des agents du minist\u00e8re allemand des Affaires internationales, qui ont sympathis\u00e9 avec le SPD de Schr\u00f6der, ont pris contact avec Yulia Navalny (sa femme) et lui ont propos\u00e9 de l&rsquo;hospitaliser dans une clinique en Allemagne. Yulia a accept\u00e9 et a fait appel \u00e0 Poutine.<\/p>\n<\/p>\n<p><p>Puis le ministre allemand des affaires \u00e9trang\u00e8res est entr\u00e9 dans le bureau de la Chanceli\u00e8re allemande et a pos\u00e9 son joker sur la table : &laquo;<em> Nous pouvons aller chercher Navalny pour le faire soigner. Si Moscou tente d&#8217;emp\u00eacher cela, nous provoquerons un scandale retentissant. Nous aurons son corps et nous d\u00e9ciderons ensuite de la mani\u00e8re de jouer <\/em>&raquo;. Merkel a trouv\u00e9 cette proposition s\u00e9duisante et, n&rsquo;y r\u00e9fl\u00e9chissant pas trop longtemps, a accept\u00e9. Moscou ne s&rsquo;est pas oppos\u00e9 au transfert de Navalny.<\/p>\n<\/p>\n<p><p>Apr\u00e8s que Navalny a \u00e9t\u00e9 amen\u00e9 en Allemagne et d\u00e9pos\u00e9 \u00e0 la clinique de la Charit\u00e9 dans un cort\u00e8ge compos\u00e9 de 12 voitures, maman Angela a appel\u00e9 Moscou et a exig\u00e9 : la Russie doit cesser de soutenir Loukachenko, sinon nous annoncerons que Navalny a \u00e9t\u00e9 empoisonn\u00e9 avec du <em>Novichok<\/em>. Moscou a refus\u00e9 et a augment\u00e9 son soutien \u00e0 Loukachenko, d\u00e9clarant qu&rsquo;elle avait organis\u00e9 une r\u00e9serve de forces sp\u00e9ciales pr\u00eate \u00e0 \u00eatre envoy\u00e9e en Bi\u00e9lorussie pour en prendre le contr\u00f4le &ndash; juste au cas o&ugrave; quelqu&rsquo;un ferait un geste soudain.<\/p>\n<\/p>\n<p><p>Le lendemain, Berlin a annonc\u00e9 que les r\u00e9sultats d&rsquo;analyses montraient un empoisonnement avec un inhibiteur de la cholinest\u00e9rase. C&rsquo;\u00e9tait son dernier coup de semonce. Puis il y a eu un autre appel t\u00e9l\u00e9phonique, pour pr\u00e9venir que la prochaine fois du <em>Novichok <\/em>sera trouv\u00e9. Moscou a refus\u00e9, et a promis \u00e0 Minsk un milliard de dollars le jour m\u00eame.<\/p>\n<\/p>\n<p><p>&Agrave; ce moment-l\u00e0, la patience de Berlin s&rsquo;est \u00e9puis\u00e9e. Navalny fut imm\u00e9diatement transf\u00e9r\u00e9 dans un h\u00f4pital militaire, o&ugrave; l&rsquo;on \u00ab\u00a0d\u00e9couvrit\u00a0\u00bb sans d\u00e9lai qu&rsquo;il avait \u00e9t\u00e9 empoisonn\u00e9 avec du <em>Novichok<\/em>. Il n&rsquo;a pas \u00e9t\u00e9 possible de trouver le <em>Novichok <\/em>pendant qu&rsquo;il \u00e9tait \u00e0 la Charit\u00e9, car les journalistes et les fonctionnaires pouvaient exiger de voir les r\u00e9sultats des tests, alors que dans un h\u00f4pital militaire, de telles demandes seraient refus\u00e9es : l&rsquo;information est secr\u00e8te. Mais m\u00eame le <em>Novichok <\/em>n&rsquo;a pas pu forcer Moscou \u00e0 cesser de soutenir Minsk. Le premier ministre russe Mikha\u00efl Michoustine a \u00e9t\u00e9 d\u00e9p\u00each\u00e9 \u00e0 Minsk avec une mallette remplie de papiers \u00e0 signer.<\/p>\n<\/p>\n<p><p>Il s&rsquo;ensuivit une tentative de Fritz Merz, l&rsquo;adjoint d&rsquo;Angela Merkel \u00e0 la CDU, de faire pression sur Merkel pour fermer <em>NordStream 2<\/em>, mais il se fit rapidement tirer les oreilles par le lobby des entreprises allemandes qui avaient investi dans ce pipeline et, en g\u00e9missant et en pleurnichant, il replongea dans son trou.<\/p>\n<\/p>\n<p><p>Puis Loukachenko, \u00e9tant un dur \u00e0 cuire, a pr\u00e9sent\u00e9 une interception, avec un profil amateur intentionnel, de communications diplomatiques secr\u00e8tes entre la Pologne et l&rsquo;Allemagne dans laquelle ils discutaient de leurs plans d&#8217;empoisonnement de Navalny. Aujourd&rsquo;hui, ils sont assis \u00e0 Varsovie et \u00e0 Berlin et ne savent pas comment r\u00e9agir \u00e0 ce film, nier ou pr\u00e9tendre ne rien avoir remarqu\u00e9. Quel dilemme !<\/p>\n<\/p>\n<p><p>Le r\u00e9sultat interm\u00e9diaire est donc le suivant : Navalny est bien vivant, tranquillement install\u00e9 dans un h\u00f4pital militaire allemand et se demandant p\u00e9riodiquement quand il sera autoris\u00e9 \u00e0 rentrer chez lui. Mais il ne sera pas autoris\u00e9 \u00e0 rentrer chez lui de sit\u00f4t.<\/p>\n<\/p>\n<p><p>Maintenant, \u00e0 l&rsquo;approche des \u00e9lections, alors que la campagne \u00e9lectorale parlementaire commence en Allemagne, la coalition CDU\/CSU de Merkel n&rsquo;a pas beaucoup de soutien populaire. Certaines personnes sont m\u00eame pr\u00eates \u00e0 prendre le Reichstag \u00e0 mains nues et \u00e0 y apposer leur propre drapeau. Et puis nous avons cette histoire toxique avec le <em>Novichok <\/em>!<\/p>\n<\/p>\n<p><p>Si Merkel annonce que c&rsquo;est le crime du si\u00e8cle o&ugrave; une grande figure de l&rsquo;opposition russe a \u00e9t\u00e9 diaboliquement empoisonn\u00e9e avec du <em>Novichok<\/em>, alors elle sera oblig\u00e9e de rompre toute relation avec le r\u00e9gime sanguinaire et de pr\u00e9senter des preuves. Mais il n&rsquo;y aura aucune preuve \u00e0 pr\u00e9senter. Et personne ne lui permettra de geler l&rsquo;ach\u00e8vement du gazoduc. Sinon, les entreprises allemandes, qui ont investi dans <em>NordStream 2<\/em>, prendront d&rsquo;assaut le Reichstag avant m\u00eame les citoyens allemands furieux. Dans les deux cas, la coalition CDU\/CSU sera confront\u00e9e \u00e0 une d\u00e9faite.<\/p>\n<\/p>\n<p><p>Mais si elle fait marche arri\u00e8re, pr\u00e9sente des excuses et renvoie Navalny en Russie, en pr\u00e9tendant que ce qui s&rsquo;est pass\u00e9 \u00e9tait une malheureuse s\u00e9rie d&rsquo;erreurs, et punit tous ceux qui l&rsquo;ont mise dans cette situation dans toute la mesure du droit allemand, cela ne sauvera pas la situation non plus. Les \u00e9lecteurs allemands ne pardonneront pas \u00e0 Merkel la perte de l&rsquo;autorit\u00e9 internationale de l&rsquo;Allemagne, la perte d&rsquo;influence en Europe et l&rsquo;incomp\u00e9tence totale dans la gestion des affaires \u00e9trang\u00e8res, et la puniront quand m\u00eame dans les urnes.<\/p>\n<\/p>\n<p><p>Par cons\u00e9quent, son seul choix est d&rsquo;attendre son heure, assise avec une fesse sur chacune des deux chaises &ndash; bl\u00e2mant la Russie pour le d\u00e9ploiement du <em>Novichok <\/em>et soutenant simultan\u00e9ment l&rsquo;ach\u00e8vement de <em>NordStream 2<\/em>. Mais nous sommes sur le point de voir un flot de rapports de t\u00e9moins oculaires, de photographies et de documents provenant des diff\u00e9rents h\u00f4pitaux o&ugrave; le patient VIP a \u00e9t\u00e9 trait\u00e9, envoyant bouler une des deux chaises. Il ne faut donc pas \u00e9carter la possibilit\u00e9 du retrait de Mme Merkel avant la fin de son mandat. Dans ce cas, elle ne battra pas le record de Helmut Kohl, 16 ans comme Chancelier.<\/p>\n<\/p>\n<p><p>Mais qu&rsquo;en est-il de l&rsquo;ami de la Russie, <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Gerhard_Schr%C3%B6der\">Gerhard Schr\u00f6der<\/a> ? En tant que pr\u00e9sident du conseil d&rsquo;administration de la soci\u00e9t\u00e9 <em>NordStream 2<\/em> et ancien chef du SPD, il envisage l&rsquo;avenir avec confiance et optimisme. Dans tous les cas, la coalition CDU\/CSU sera d\u00e9gonfl\u00e9e et le SPD renforcera sa position au Bundestag et, soit ind\u00e9pendamment, soit en coalition avec d&rsquo;autres partis, installera son propre leader en tant que Chancelier. Le <em>NordStream 2<\/em>, qui a \u00e9t\u00e9 dans les limbes politiques pendant quelques ann\u00e9es, sera achev\u00e9 et entrera en service \u00e0 pleine capacit\u00e9 tr\u00e8s rapidement.<\/p>\n<\/p>\n<p><p>Quand nous sommes arriv\u00e9s chez moi, le chauffeur de taxi a demand\u00e9 : &laquo;<em> Jouez-vous aux \u00e9checs ? <\/em>&raquo;<\/p>\n<\/p>\n<p><p>&laquo;<em> Parfois <\/em>&raquo;, r\u00e9pondis-je avec un signe de t\u00eate.<\/p>\n<\/p>\n<p><p>Aux \u00e9checs, il existe une tactique appel\u00e9e \u00ab\u00a0pion empoisonn\u00e9\u00a0\u00bb. Votre adversaire, cherchant \u00e0 obtenir un avantage mat\u00e9riel, prend ce pion, se retrouve pi\u00e9g\u00e9 et perd in\u00e9vitablement.<\/p>\n<\/p>\n<p><p>En sortant du taxi, quelque peu perplexe, j&rsquo;ai demand\u00e9 au chauffeur de taxi d&rsquo;o&ugrave; il tenait toutes ces informations. Il m&rsquo;a r\u00e9pondu avec un triste sourire \u00e0 la Bill Murray : &laquo;<em> De mon fr\u00e8re. Il vit en Allemagne et travaille \u00e9galement comme chauffeur de taxi <\/em>&raquo;. C&rsquo;est \u00e0 ce moment que j&rsquo;ai r\u00e9alis\u00e9 que les chauffeurs de taxi savent tout.<\/p>\n<\/p>\n<p><p>12 septembre 2020, <a href=\"http:\/\/cluborlov.blogspot.com\/2020\/09\/taxi-drivers-know-everything.html\">Club Orlov<\/a> via <a href=\"https:\/\/aftershock.news\/?q=user\/1826\">SKonst<\/a> &ndash; Traduction du <em><a href=\"https:\/\/lesakerfrancophone.fr\/les-chauffeurs-de-taxi-savent-tout\">Sakerfrancophone<\/a><\/em><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les chauffeurs de taxi savent tout Il se trouve qu&rsquo;hier, je rentrais chez moi en taxi. Le chauffeur de taxi, qui ressemblait \u00e0 Bill Murray, s&rsquo;est r\u00e9v\u00e9l\u00e9 tr\u00e8s bavard. Pendant le trajet, comme cela arrive souvent, nous avons abord\u00e9 tous les sujets, du temps qu&rsquo;il fait aux blondes au volant. &Agrave; un moment donn\u00e9, en&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[29],"tags":[2748,4633,19302,20252,2668],"class_list":["post-79442","post","type-post","status-publish","format-standard","hentry","category-les-carnets-de-dimitri-orlov-1","tag-allemagne","tag-merkel","tag-navalny","tag-nordstream-2","tag-orlov"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79442","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79442"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79442\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79442"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79442"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}