{"id":79464,"date":"2020-10-10T15:20:45","date_gmt":"2020-10-10T15:20:45","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2020\/10\/10\/rapsit-usa2020-la-g5g-metahistorique\/"},"modified":"2020-10-10T15:20:45","modified_gmt":"2020-10-10T15:20:45","slug":"rapsit-usa2020-la-g5g-metahistorique","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2020\/10\/10\/rapsit-usa2020-la-g5g-metahistorique\/","title":{"rendered":"RapSit-USA2020\u00a0: La G5G m\u00e9tahistorique"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">RapSit-USA2020 : La G5G m\u00e9tahistorique<\/h2>\n<\/p>\n<p><p>Nous connaissons William S. Lind depuis longtemps, &ndash; homme d&rsquo;\u00e9glise, conservateur proche de la tradition, citoyen am\u00e9ricain qui se situe politiquement comme un &lsquo;royaliste-fran\u00e7ais&rsquo;, expert militaire respect\u00e9 proche du Corps des Marines et th\u00e9oricien de la Guerre de 4<sup>\u00e8me<\/sup> G\u00e9n\u00e9ration (G4G), \u00e9galement historien de la Grande Guerre. Il s&rsquo;est fait tr\u00e8s discret depuis dix-15 ans, apr\u00e8s avoir beaucoup &oelig;uvr\u00e9 pour son concept-G4G. Il garde tout de m\u00eame un contact avec la vie publique, par le biais d&rsquo;une chronique irr\u00e9guli\u00e8re sur le site <em>TraditionalRight.com<\/em>.<\/p>\n<\/p>\n<p><p>La derni\u00e8re fois que nous l&rsquo;avons cit\u00e9 longuement, c&rsquo;\u00e9tait il y a quatre ans, le <a href=\"https:\/\/www.dedefensa.org\/article\/vision-de-william-s-lind\">5 d\u00e9cembre 2016<\/a>, lorsqu&rsquo;il semblait s&rsquo;orienter vers une doctrine nouvelle pour prot\u00e9ger les &Eacute;tats face aux pouss\u00e9es dissolvantes et n\u00e9antissantes des organisations transnationales, soci\u00e9tales et progressistes, au travers de concepts nouveaux depuis largement repr\u00e9sent\u00e9s par les concepts dits LGTBQ et, plus r\u00e9cemment, au concept-&lsquo;<em>woke<\/em>&lsquo; aux USA&#8230; Nous parlions alors, tentativement pas plus puisque Lind lui-m\u00eame ne le fait pas, de G5G, en donnant \u00e0 ce concept un tour nettement antiSyst\u00e8me ; \u00e0 cette occasion, en plus de pr\u00e9senter le nouvelle orientation de Lind, nous rappelions nos liens avec lui :<\/p>\n<\/p>\n<p><p>&laquo; <em>Nous-m\u00eame connaissons bien William S. Lind (premi\u00e8re citation et r\u00e9f\u00e9rence \u00e0 Lind <a href=\"http:\/\/www.dedefensa.org\/redaction\/articles\/list\">le 3 mars 2003<\/a>) et son concept de G4G (premi\u00e8re citation et r\u00e9f\u00e9rence <a href=\"http:\/\/www.dedefensa.org\/article\/la-g4g-et-la-legitimite\">le 30 juillet 2006<\/a>). Le concept de Lind, que nous avons souvent interpr\u00e9t\u00e9 de diff\u00e9rentes fa\u00e7ons op\u00e9rationnelles nous int\u00e9resse parce qu&rsquo;il est si proche des conceptions gaullistes (voir <a href=\"http:\/\/www.dedefensa.org\/article\/la-g4g-est-elle-gaulliste\">le 23 janvier 2009<\/a>), c&rsquo;est-\u00e0-dire d&rsquo;une conception principielle du monde bas\u00e9e sur la souverainet\u00e9 et la l\u00e9gitimit\u00e9.<\/em><\/p>\n<p>&raquo; <em>Nous-m\u00eames avons la perception que les \u00e9v\u00e9nements, tout en ne d\u00e9classant en rien la G4G telle qu&rsquo;elle est pr\u00e9sent\u00e9e, surtout selon sa r\u00e9f\u00e9rence \u00e0 la Grande Strat\u00e9gie, doit donner \u00e0 un nouveau prolongement, que nous nommons G5G, <a href=\"http:\/\/www.dedefensa.org\/article\/we-the-people-a-transmute-le-concept-dinsurrection-1\">d\u00e9j\u00e0 r\u00e9f\u00e9renc\u00e9e<\/a> pour introduire une analyse plus profonde<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Du concept G5G, mentionn\u00e9 dans l&rsquo;extrait \u00e0 partir d&rsquo;une r\u00e9f\u00e9rence, nous disions ceci, \u00e0 partir <a href=\"http:\/\/www.dedefensa.org\/article\/we-the-people-a-transmute-le-concept-dinsurrection-1\">de la r\u00e9f\u00e9rence cit\u00e9e<\/a>. Il s&rsquo;agissait d&rsquo;identifier et de conceptualiser ce nouveau type d&rsquo;action, &ndash; en g\u00e9n\u00e9ral sommairement identifi\u00e9e comme &lsquo;populisme&rsquo;, mais qui m\u00e9rite \u00e0 notre sens beaucoup plus de pr\u00e9cision et d&rsquo;attention \u00e0 cause des moyens employ\u00e9s, de la puissance de la communication utilis\u00e9e comme une arme, etc. L\u00a0\u00bbid\u00e9ologisation&rsquo; ou approchant, sous le nom de &lsquo;populisme&rsquo;, ne suffit certainement pas \u00e0 d\u00e9finir le ph\u00e9nom\u00e8ne. Nous parlions donc, d\u00e9j\u00e0, de G5G (qui rejoint \u00e9videmment, en lui donnant une nouvelle d\u00e9nomination de meilleure convenance, \u00e0 la <a href=\"https:\/\/www.dedefensa.org\/article\/rapsit-usa2020-une-guerre-civile-gc4g\">GC4G<\/a> [&lsquo;Guerre Civile de 4\u00e8me G\u00e9n\u00e9ration&rsquo;] dont nous avons parl\u00e9 depuis sans revenir sur la G5G) :<\/p>\n<\/p>\n<p><p>&laquo; <em>Le th\u00e9oricien strat\u00e8ge William S. Lind avait d\u00e9fini et d\u00e9velopp\u00e9 le concept de G4G (\u00ab\u00a0Guerre de 4<sup>\u00e8me<\/sup> G\u00e9n\u00e9ration\u00a0\u00bb) pour d\u00e9finir ces attaques de violence et de contraintes diverses par d\u00e9structuration et dissolution d&rsquo;entit\u00e9s transnationales, type organisations terroristes ou\/et du crime organis\u00e9e, et surtout finalement cette attaque g\u00e9n\u00e9ralis\u00e9e de la globalisation-Syst\u00e8me contre les structures principielles dans un but quasiment reconnu de destruction du monde. L&rsquo;antiSyst\u00e8me est en train d&rsquo;inventer la G5G, en gestation depuis un certain temps dans <a href=\"http:\/\/www.dedefensa.org\/article\/la-g4g-est-elle-gaulliste\">la G4G elle-m\u00eame<\/a><\/em> <em>et qui emploie des m\u00e9thodes de la G4G adapt\u00e9es \u00e0 ses moyens (la d\u00e9mocratie !) pour les retourner contre ses v\u00e9ritables adversaires. Les choses vont si vite : le \u00ab\u00a0commencement de la fin\u00a0\u00bb (\u00ab\u00a0The Beginning of the End\u00a0\u00bb) n&rsquo;est plus tr\u00e8s loin de la \u00ab\u00a0fin du commencement\u00a0\u00bb (\u00ab\u00a0The End of the Beginning\u00a0\u00bb) qu&rsquo;on a d\u00e9j\u00e0 identifi\u00e9 ces derni\u00e8res semaines avec l&rsquo;\u00e9lection de Trump<\/em>. &raquo;<\/p>\n<\/p>\n<blockquote>\n<p><p>Par ailleurs, et aussit\u00f4t apr\u00e8s le texte r\u00e9f\u00e9renc\u00e9 sur la G5G, nous tentions de donner une approche plus conceptuelle et plus d\u00e9cisive de ce &lsquo;n\u00e9o-concept&rsquo; accouch\u00e9 de la G4G : &laquo; <em>Ce qui fait le principal caract\u00e8re qui apparente le G5G \u00e0 la G4G, et qui donne \u00e0 cette nouvelle forme d&rsquo;affrontement une actualit\u00e9 et une l\u00e9gitimit\u00e9 exceptionnelles, c&rsquo;est que son action porte finalement, au bout de la cha&icirc;ne des effets &#038; cons\u00e9quences, sur des principes qu&rsquo;il s&rsquo;agit de r\u00e9tablir ou de renforcer. En quelque sorte, il s&rsquo;agit de la v\u00e9ritable \u00ab\u00a0Grande Strat\u00e9gie\u00a0\u00bb des deux conflits, effectivement \u00ab\u00a0strat\u00e9gie sublime\u00a0\u00bb \u00e0 un point o&ugrave; l&rsquo;adjectif prend le pas sur le sujet, o&ugrave; ce qui importe avant tout <strong>c&rsquo;est la sublimit\u00e9 de la d\u00e9marche, qui fait passer cette d\u00e9marche du champ historique au champ m\u00e9tahistorique<\/strong>. En quelque sorte, le G5G, enfant\u00e9e par la G4G, l&rsquo;est en haussant d\u00e9cisivement son champ d&rsquo;action et, par-l\u00e0 m\u00eame, <strong>\u00e9l\u00e8ve \u00e9galement la G4G dans ce m\u00eame champ<\/strong><\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Dans le texte ci-dessous, qui date d&rsquo;hier <a href=\"https:\/\/www.traditionalright.com\/quoth-the-maven-nevermore\/\">9 octobre 2020<\/a>, et suivant un autre <a href=\"https:\/\/www.traditionalright.com\/mawa\/\">texte du 5 octobre<\/a> sur le m\u00eame sujet, sous le titre de &laquo; <em>MAWA : Make America White Again<\/em> &raquo;, Lind aborde \u00e9videmment la question crisique de l&rsquo;\u00e9lection du 3 novembre. Il y a longtemps que Lind n&rsquo;avait plus eu une telle activit\u00e9 \u00e9ditoriale, et pour nous et parmi d&rsquo;autres indications, il s&rsquo;agit d&rsquo;une mesure pr\u00e9cise de la gravit\u00e9 de la situation. D&rsquo;une fa\u00e7on g\u00e9n\u00e9rale, Lind juge que Trump remportera l&rsquo;\u00e9lection et que c&rsquo;est certainement la moins mauvaise chose puisqu&rsquo;il s&rsquo;agit d&rsquo;un obstacle brutalement \u00e9rig\u00e9 devant la pouss\u00e9e marxiste-gramsciste qui s&rsquo;est brusquement d\u00e9velopp\u00e9e \u00e0 visage d\u00e9couvert ces derniers mois, selon Lind comme selon l&rsquo;\u00e9vidence du constat.<\/p>\n<\/p>\n<p><p>La vari\u00e9t\u00e9 d&rsquo;opinion sur les r\u00e9sultats de l&rsquo;\u00e9lection du mois prochain est tr\u00e8s grande, notamment chez ces conservateurs traditionnistes, pal\u00e9oconservateurs ou libertariens selon la classification-USA, et en g\u00e9n\u00e9ral personnalit\u00e9s tr\u00e8s inform\u00e9es et producteurs de positions politiques extr\u00eamement \u00e9labor\u00e9es. (Tous, sans \u00eatre, et de tr\u00e8s loin, des soutiens de Trump, sont des adversaires affirm\u00e9s de la pouss\u00e9e marxiste-culturelle\/LGTBQ\/progressiste-soci\u00e9tale des d\u00e9mocrates.) Ainsi, et contrairement \u00e0 Lind, le colonel Lang, que l&rsquo;on peut classer dans cette cat\u00e9gorie, entretient l&rsquo;opinion exactement inverse, dans <a href=\"https:\/\/turcopolier.typepad.com\/sic_semper_tyrannis\/2020\/10\/hes-a-blue-trump-tara-reade.html\">plusieurs<\/a> <a href=\"https:\/\/turcopolier.typepad.com\/sic_semper_tyrannis\/2020\/10\/biden-is-a-doorway-not-a-destination.html\">messages<\/a> de ces <a href=\"https:\/\/turcopolier.typepad.com\/sic_semper_tyrannis\/2020\/10\/hoping-and-praying.html\">derniers jours<\/a>, accompagn\u00e9s de nombreux messages int\u00e9ressants des lecteurs de son site :<\/p>\n<\/p>\n<p><p>&laquo; <em>J&rsquo;estime que l'\u00a0\u00bb\u00e9quipe\u00a0\u00bb Harris\/Biden va gagner les \u00e9lections et les deux chambres du Congr\u00e8s.  Cela se produira en raison de l&rsquo;hyst\u00e9rie de beaucoup de gens qui pensent avec leur \u00e9motion plut\u00f4t qu&rsquo;avec leur t\u00eate et pr\u00e9f\u00e8rent ce qu&rsquo;ils consid\u00e8rent comme des &lsquo;gentils&rsquo; par-dessus tout.  Les d\u00e9mocrates et leurs alli\u00e9s marxistes et bient\u00f4t ma&icirc;tres de la situation vont alors s&rsquo;orienter vers la bolchevisation de ce qui a \u00e9t\u00e9 connu sous le nom de &lsquo;United States&rsquo;<\/em>. &raquo;<\/p>\n<p>[&#8230;]<\/p>\n<p>&laquo; <em>La route de l&rsquo;enfer est pav\u00e9e de bonnes intentions.  Des gens qui n&rsquo;ont jamais dirig\u00e9 une organisation importante, qui n&rsquo;ont jamais gagn\u00e9 d&rsquo;argent qui ne leur ait \u00e9t\u00e9 donn\u00e9 et qui pensent que tout ce qui importe pour cr\u00e9er une utopie est de la ferveur et de l&rsquo;enthousiasme doivent s&rsquo;attendre \u00e0 \u00eatre men\u00e9s par le bout du nez par Old Joe. Les cadres combattants de rue des marxistes purs et durs prendront in\u00e9vitablement le contr\u00f4le du processus et derri\u00e8re eux se trouveront les ploutocrates de gauche qui jugent que c&rsquo;est leur chance de tout diriger, &ndash; TOUT !<\/em> &raquo;<\/p>\n<p>[&#8230;]<\/p>\n<p>&laquo; <em>Je tiens \u00e0 pr\u00e9ciser que, bien que mon jugement analytique me dit que les d\u00e9mocrates vont \u00e0 une nette victoire gr\u00e2ce aux femmes, j&rsquo;esp\u00e8re d\u00e9sesp\u00e9r\u00e9ment le r\u00e9sultat inverse. La mienne me dit qu&rsquo;elle va voter pour Trump et moi aussi<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>On voit ainsi \u00e0 quel degr\u00e9 d&rsquo;angoisse et d&rsquo;appr\u00e9hension se trouve aujourd&rsquo;hui le sentiment politique aux USA. Si le texte de Lind commence et se termine par sa croyance dans la victoire de Trump, l&rsquo;essentiel se trouve \u00eatre une analyse de \u00ab\u00a0que se passera-t-il si&#8230; Trump perdait\u00a0\u00bb ?<\/p>\n<\/p>\n<p><p>Manifestement, pour Lind c&rsquo;est le pire des cas, et un cas o&ugrave; effectivement la nouvelle G5G se d\u00e9ploierait dans toute sa violence. Pour lui, la situation basculerait imm\u00e9diatement dans le mode insurrectionnel d&rsquo;affrontement de guerre civile, selon divers sc\u00e9narios possibles, &ndash; soit l&rsquo;interdiction et la saisie des armes individuelles ; soit l&rsquo;interdiction des \u00ab\u00a0discours de haine\u00a0\u00bb (comprendre \u00ab\u00a0des paroles antimarxistes\u00a0\u00bb), impliquant des arrestations arbitraires de masse conduisant directement \u00e0 une insurrection ; soit l&rsquo;ouverture des fronti\u00e8res du Sud qui conduiraient certains &Eacute;tats comme le Texas \u00e0 refuser les ordres du centre, \u00e0 faire <em>de facto <\/em>s\u00e9cession et \u00e0 boucler leurs fronti\u00e8res, tandis que l&rsquo;administration centrale de Washington D.C. se d\u00e9sagr\u00e9gerait.<\/p>\n<\/p>\n<p><p>Partout dans ces textes appara&icirc;t comme une chose acquise le fait qu&rsquo;en cas de victoire d\u00e9mocrate, Biden ne fera pas long feu. Cette perspective semble quasiment assur\u00e9e par la <a href=\"https:\/\/www.dedefensa.org\/article\/rapsit-usa2020-plot-against-america\">d\u00e9cision de Pelosi<\/a> d&rsquo;installer une &lsquo;commission sur le 25<sup>\u00e8me<\/sup> Amendement&rsquo;, charg\u00e9 d&rsquo;examiner le cas de cette disposition de la Constitution (le 25<sup>\u00e8me<\/sup> Amendement examine le cas de la destitution du pr\u00e9sident pour incapacit\u00e9 sanitaire ou mentale de porter sa charge). Interpr\u00e9t\u00e9e d&rsquo;abord comme une disposition concernant Trump et son Covid, l&rsquo;interpr\u00e9tation, men\u00e9e d&rsquo;ailleurs <a href=\"https:\/\/www.rt.com\/usa\/503083-pelosi-amendment-trump-biden-harris\/\">par Trump lui-m\u00eame<\/a>, s&rsquo;est d\u00e9plac\u00e9e et port\u00e9e vers Biden lui-m\u00eame. Les rumeurs \u00e0 cet \u00e9gard disent que Pelosi entend obtenir la destitution de Biden pour incapacit\u00e9 sanitaire d\u00e8s le printemps 2021 en cas de victoire d\u00e9mocrate, ce qui conduirait quasi-automatiquement \u00e0 un &lsquo;gauchissement&rsquo; et une &lsquo;marxisation&rsquo; extr\u00eame du pouvoir sous la direction de Harris.<\/p>\n<\/p>\n<p><p>Voici le texte de William S. Lind, du <a href=\"https:\/\/www.traditionalright.com\/quoth-the-maven-nevermore\/\">9 octobre 2020<\/a>. Il faut noter que Lind n&rsquo;envisage qu&rsquo;un seul sc\u00e9nario de troubles : le cas de la victoire des d\u00e9mocrates. Il semble consid\u00e9rer qu&rsquo;une victoire de Trump \u00e9viterait ces troubles sp\u00e9cifiques jusqu&rsquo;\u00e0 la d\u00e9sagr\u00e9gation des &Eacute;tats-Unis mais il n&rsquo;\u00e9labore pas sur la situation interne dans ce cas. Entre BLM, Antifas et marxisme-culturel, il nous semble que la crise serait \u00e9videmment tr\u00e8s loin d&rsquo;\u00eatre finie et qu&rsquo;il faut envisager d&rsquo;autres sc\u00e9narios tout aussi d\u00e9structurants ; cela, sans parler de la situation interm\u00e9diaire d&rsquo;une \u00e9lection non concluante en raison de la proximit\u00e9 des r\u00e9sultats et du refus probable des candidats, &ndash; porte ouverte \u00e0 un chaos g\u00e9n\u00e9ral.<\/p>\n<\/p>\n<p><h2 class=\"titleset_c.deepblue\" style=\"color:#0f3955; font-size:1.25em\">&laquo; Plus jamais \u00e7a<\/h2>\n<\/p>\n<p><p>&raquo; Je m&rsquo;attends \u00e0 ce que le pr\u00e9sident Trump soit r\u00e9\u00e9lu, probablement par une large majorit\u00e9, et \u00e0 ce que les r\u00e9publicains tiennent le S\u00e9nat et  reprennent la Chambre.  Pourquoi ?  Parce qu&rsquo;\u00e0 ce stade, le nombre d&rsquo;Am\u00e9ricains qui sont en col\u00e8re est plus important que le nombre de ceux qui ont peur. Les d\u00e9mocrates sont le parti de la peur et les r\u00e9publicains celui de la col\u00e8re. Ce sont donc ces derniers qui vont gagner. <\/p>\n<\/p>\n<p><p>&raquo; Mais que se passera-t-il si la peur l&#8217;emportait et que Biden devenait pr\u00e9sident alors que les d\u00e9mocrates tiendraient la Chambre et s&#8217;empareraient du S\u00e9nat ?  Biden est un politicien de l&rsquo;establishment de la vieille \u00e9cole qui ne fera probablement rien de radical de sa propre initiative.  Mais il sera soumis \u00e0 la pression de la gauche gauche \u00ab\u00a0\u00e9veill\u00e9e\u00a0\u00bb [<em>woke<\/em>], des radicaux de la Chambre et de sa propre vice-pr\u00e9sidente pour faire des choses tr\u00e8s stupides.  S&rsquo;il c\u00e8de, ou si nous nous retrouvons soudain avec une femme de gauche dure de Californie \u00e0 la pr\u00e9sidence, les d\u00e9mocrates pourraient prendre des mesures qui d\u00e9chireraient le pays.<\/p>\n<\/p>\n<p><p>&raquo; La plus \u00e9vidente est une tentative de confisquer leurs armes aux citoyens am\u00e9ricains.  Un espoir d\u00e9mocrate qui a fait long feu en d\u00e9but de campagne, Beto O&rsquo;Rourke, a dit : &laquo; Allons-nous vous retirer vos armes ?  Absolument ! &raquo;  Il s&rsquo;est effac\u00e9 mais ce projet reste tr\u00e8s cher \u00e0 de nombreux d\u00e9mocrates.  S&rsquo;ils le d\u00e9cident, peut-\u00eatre apr\u00e8s avoir \u00e9largi le coll\u00e8ge des Juges de la Cour Supr\u00eame et obtenu qu&rsquo;ils statuent pour changer l&rsquo;interpr\u00e9tation du Deuxi\u00e8me Amendement, nous assisterions \u00e0 une scission massive entre les villes et les campagnes.  Un signe que la guerre de la quatri\u00e8me g\u00e9n\u00e9ration se propage serait la mise en place de points de contr\u00f4le arm\u00e9s dans les campagnes, avec des volontaires locaux.  Un signe plus important encore serait un mouvement de policiers et de militaires pour passer du c\u00f4t\u00e9 des r\u00e9fractaires. Dans cette hypoth\u00e8se, je surveillerais ces deux champs d&rsquo;action.<\/p>\n<\/p>\n<p><p>&raquo; Une deuxi\u00e8me possibilit\u00e9 serait d&rsquo;amener la Cour Supr\u00eame \u00e0 annuler la libert\u00e9 d&rsquo;expression selon l&rsquo;id\u00e9e que le \u00ab\u00a0discours de haine\u00a0\u00bb n&rsquo;est pas prot\u00e9g\u00e9 par la Constitution.  La \u00ab\u00a0haine\u00a0\u00bb est le terme utilis\u00e9 par les marxistes culturels pour d\u00e9signer tout d\u00e9fi au marxisme culturel.  Ainsi, quiconque critiquerait leur id\u00e9ologie ou ne s&rsquo;inclinerait pas devant elle serait en route pour le goulag.  Cela s&rsquo;est d\u00e9j\u00e0 produit dans d&rsquo;autres pays soi-disant \u00ab\u00a0libres\u00a0\u00bb, dont le Canada, la Grande-Bretagne et la France.  En Grande-Bretagne, un homme a \u00e9t\u00e9 arr\u00eat\u00e9 pour avoir critiqu\u00e9 l&rsquo;Islam.  Lors de son proc\u00e8s, il a prouv\u00e9 que tout ce qu&rsquo;il disait \u00e9tait tir\u00e9 du Coran.  Le juge l&rsquo;a envoy\u00e9 en prison, d\u00e9clarant que &laquo; la v\u00e9rit\u00e9 n&rsquo;est pas une d\u00e9fense &raquo;.  La v\u00e9rit\u00e9 n&rsquo;est pas une d\u00e9fense dans le pays o&ugrave; nos libert\u00e9s sont n\u00e9es ?  Les g\u00e9n\u00e9rations pr\u00e9c\u00e9dentes de Britanniques auraient conduit ce juge hors de la ville \u00e0 coups de pied dans le train.  Les Am\u00e9ricains ne seraient pas aussi doux, je suppose, et la r\u00e9sistance \u00e0 la perte de la libert\u00e9 d&rsquo;expression pourrait devenir violente.<\/p>\n<\/p>\n<p><p>&raquo; L&rsquo;action la plus susceptible de briser le pays serait d&rsquo;ouvrir la fronti\u00e8re sud et de dire : \u00ab\u00a0Venez, Venez tous !\u00a0\u00bb La surveillance frontali\u00e8re serait abolie, les forces de surveillance verrait leur mission transform\u00e9e en sauvegarde des immigrants ill\u00e9gaux perdus, et plus du tout de les expulser. En Am\u00e9rique Centrale, des millions de personnes se formeraient en caravanes vers le nord.  Les d\u00e9mocrates ne cachent pas leur strat\u00e9gie visant \u00e0 noyer les votes des Am\u00e9ricains de souche dans ceux des immigr\u00e9s d&rsquo;autres cultures, se garantissant ainsi une majorit\u00e9 permanente et faisant de nous des \u00e9trangers dans notre propre pays.<\/p>\n<\/p>\n<p><p>&raquo; S&rsquo;ils font cela, je m&rsquo;attends \u00e0 ce qu&rsquo;au moins le Texas et l&rsquo;Arizona mobilisent leur Garde Nationale et l&rsquo;envoient \u00e0 la fronti\u00e8re pour les interdire aux envahisseurs.  Un pr\u00e9sident d\u00e9mocrate d\u00e9ciderait la &lsquo;f\u00e9d\u00e9ralisation&rsquo; de la Garde et ordonnerait sa d\u00e9mobilisation. Les gouverneurs du Texas et de l&rsquo;Arizona, ainsi que les adjudants g\u00e9n\u00e9raux commandants les Gardes de leurs &Eacute;tats, pourraient refuser l&rsquo;ordre pr\u00e9sidentiel.  &Agrave; ce moment-l\u00e0, Washington se trouverait au bord du gouffre.  Si le pr\u00e9sident acceptait que son ordre de f\u00e9d\u00e9ralisation soit annul\u00e9 au niveau de l&rsquo;&Eacute;tat, il se r\u00e9v\u00e9lerait d\u00e9l\u00e9gitim\u00e9 et impuissant.  S&rsquo;il ordonnait \u00e0 l&rsquo;arm\u00e9e r\u00e9guli\u00e8re de combattre la Garde, je pense que les forces refuseraient. Si les g\u00e9n\u00e9raux, dont l&#8217;emploi est en jeu, ordonnaient \u00e0 leurs troupes d&rsquo;attaquer la Garde Nationale, l&rsquo;arm\u00e9e elle-m\u00eame pourrait se fracturer, probablement selon des lignes ethniques. &Agrave; ce moment-l\u00e0, le sc\u00e9nario du roman de Thomas Hobbes, <em><a href=\"http:\/\/traditionalright.com\/victoria\">Victoria<\/a><\/em>, serait devenu r\u00e9alit\u00e9 ; le gouvernement f\u00e9d\u00e9ral devrait laisser son marxisme culturel d\u00e9l\u00e9gitimer l&rsquo;&Eacute;tat au point que l&rsquo;Am\u00e9rique se d\u00e9sagr\u00e9gerait. La guerre de la quatri\u00e8me g\u00e9n\u00e9ration ne serait plus une construction intellectuelle mais une r\u00e9alit\u00e9 irr\u00e9sistible.<\/p>\n<\/p>\n<p><p>&raquo; Je ne m&rsquo;attends pas \u00e0 ce que tout cela se produise, car je pense que le pr\u00e9sident Trump sera r\u00e9\u00e9lu triomphalement et que la col\u00e8re l&#8217;emportera sur la peur. Mais si je me trompe, l&rsquo;histoire dira alors \u00e0 notre vieille devise &lsquo;E Pluribus Unum&rsquo; : \u00ab\u00a0Plus jamais \u00e7a !\u00a0\u00bb &raquo;<\/p>\n<\/p>\n<p><h4>William S. Lind<\/h4>\n<\/p>\n<p><p>Mis en ligne le 10 octobre 2020 \u00e0 15H20<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>RapSit-USA2020 : La G5G m\u00e9tahistorique Nous connaissons William S. Lind depuis longtemps, &ndash; homme d&rsquo;\u00e9glise, conservateur proche de la tradition, citoyen am\u00e9ricain qui se situe politiquement comme un &lsquo;royaliste-fran\u00e7ais&rsquo;, expert militaire respect\u00e9 proche du Corps des Marines et th\u00e9oricien de la Guerre de 4\u00e8me G\u00e9n\u00e9ration (G4G), \u00e9galement historien de la Grande Guerre. Il s&rsquo;est fait&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[21],"tags":[831,3992,1235,9578,5786,5701,2936,4385,1012,18499,2937,3866,3421,2639,2804,2860,3865],"class_list":["post-79464","post","type-post","status-publish","format-standard","hentry","category-breves-de-crise","tag-a","tag-armes","tag-biden","tag-desagregation","tag-feu","tag-g4g","tag-garde","tag-harris","tag-lind","tag-marxistes-culturels","tag-nationale","tag-s","tag-texas","tag-trump","tag-usa","tag-victoire","tag-william"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79464"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79464\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}