{"id":79471,"date":"2020-10-15T09:12:33","date_gmt":"2020-10-15T09:12:33","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2020\/10\/15\/retour-sur-un-futur-bancal\/"},"modified":"2020-10-15T09:12:33","modified_gmt":"2020-10-15T09:12:33","slug":"retour-sur-un-futur-bancal","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2020\/10\/15\/retour-sur-un-futur-bancal\/","title":{"rendered":"Retour sur un futur bancal"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepgreen\" style=\"color:#75714d; font-size:2em\">Retour sur un futur bancal<\/h2>\n<\/p>\n<p><p>Guillaume Travers est un \u00e9conomiste original, et donc int\u00e9ressant selon les pratiques si conformistes-PC du temps courant autant que selon les habitudes pseudo-p\u00e9rennes de cette mati\u00e8re (l&rsquo;\u00e9conomie). Il semble bien qu&rsquo;il ne place pas, surtout pas, l&rsquo;\u00e9conomie au centre de tout. Il semble bien qu&rsquo;il consid\u00e8re l&rsquo;\u00e9conomie comme une mati\u00e8re disons &lsquo;secondaire&rsquo; en ceci qu&rsquo;elle soit d\u00e9pendante du domaine auquel elle s&rsquo;applique. Il constate dans tous les cas que ce fut la situation jusqu&rsquo;\u00e0 l&rsquo;\u00e9poque de la modernit\u00e9 consid\u00e9r\u00e9e dans sa chronologie la plus profonde et la plus significatives. Il dit, pour illustrer cette appr\u00e9ciation :<\/p>\n<\/p>\n<p><p>&laquo; <em>Jusqu&rsquo;\u00e0 la p\u00e9riode moderne, l&rsquo;\u00e9conomie n&rsquo;a jamais exist\u00e9 comme domaine autonome. Les activit\u00e9s \u00e9conomiques \u00e9taient toujours &lsquo;encastr\u00e9es&rsquo; dans des relations sociales, politiques, communautaires.<\/em> &raquo;<\/p>\n<\/p>\n<p><p>&#8230; Et pour suivre, il cite le Moyen-\u00e2ge, notamment dans l&rsquo;interview que nous reprenons ci-dessus (reprise par nous-m\u00eames \u00e0 partir d&rsquo;une reprise du <a href=\"https:\/\/www.revue-elements.com\/economie-pour-un-retour-au-moyen-age\/\">8 octobre 2020<\/a> par <em>&Eacute;l\u00e9ments<\/em>, dont Travers est un collaborateur r\u00e9gulier, d&rsquo;une publication dans <em>Pr\u00e9sent <\/em>du 7 octobre 2020). Il y avait une continuit\u00e9 entre l&rsquo;Antiquit\u00e9, ou disons \u00ab\u00a0ce qui venait de la nature du monde\u00a0\u00bb, et le Moyen-&Acirc;ge, m\u00eame si cette continuit\u00e9 pouvait traverser des \u00e9pisodes catastrophique comme fut la chute de l&rsquo;Empire Romain. Il y a eu sans aucun doute une rupture compl\u00e8tement fondamentale, une rupture ontologique, une d\u00e9-naturation du monde, avec l&rsquo;arriv\u00e9e de la modernit\u00e9 dont on recueille les premiers signes, les avant-coureurs, \u00e0 l&rsquo;or\u00e9e du XIV\u00e8me si\u00e8cle, apr\u00e8s &lsquo;<em>Le Temps des Cath\u00e9drales<\/em>&lsquo;.<\/p>\n<\/p>\n<p><p>L\u00e0-dessus et puisque cette \u00e9vocation chronologique nous y invite, on fera une remarque qui est \u00e9galement tr\u00e8s pertinente pour le temps pr\u00e9sent, pour l&rsquo;actualit\u00e9 la plus pressante (y compris celle du &lsquo;couvre-feu&rsquo;) : l&rsquo;\u00e9pid\u00e9mie de &lsquo;<em>La Mort Noire<\/em>&lsquo;, de la peste d\u00e9vastatrice dans les ann\u00e9es 1340 de ce XIV\u00e8me si\u00e8cle, qui frappa le monde en frappant l&rsquo;Europe, acc\u00e9l\u00e9ra fondamentalement l\u00a0\u00bboccasion&rsquo; et la profondeur tellurique de cette rupture, &ndash; en l&rsquo;op\u00e9rationnalisant, dira-t-on, par sa puissance de destruction de l&rsquo;ordre ancien. C&rsquo;est une id\u00e9e qui a tout son int\u00e9r\u00eat et toute son actualit\u00e9, aujourd&rsquo;hui, dans le temps de la pand\u00e9mie Covid19.<\/p>\n<\/p>\n<p><p>Les circonstances, les d\u00e9vastations, les souffrances entre les deux \u00e9v\u00e9nements sont incomparables tant la peste du XIV\u00e8me si\u00e8cle fut chose affreuse, mais les opportunit\u00e9s rupturielles sont assez proches en intensit\u00e9 accomplie et potentielle, et peut-\u00eatre m\u00eame celle de Covid19 est-elle, \u00e0 l&rsquo;inverse du cataclysme qu&rsquo;elle fut, plus importante que celle de &lsquo;<em>La Mort Noire<\/em>&lsquo;, \u00e0 cause du syst\u00e8me de la communication ; et peut-\u00eatre m\u00eame [bis] est-elle la possibilit\u00e9 d&rsquo;une rupture d&rsquo;inversion justement, renversant celle du XIV\u00e8me si\u00e8cle. Cela rencontre bien entendu l&rsquo;id\u00e9e de Travers, parlant bien entendu en fonction de l\u00a0\u00bbactualit\u00e9 pressante&rsquo; qui, comme nous l&rsquo;a confirm\u00e9 <a href=\"https:\/\/www.dedefensa.org\/article\/constat-de-finkielkraut\">Finkielkraut<\/a>, est directement m\u00e9tahistorique.<\/p>\n<\/p>\n<p><p>Les arguments que d\u00e9veloppe Travers sont certes \u00e9conomiques, mais selon une logique qui rencontre sa propre perception de l&rsquo;\u00e9conomie. On y trouve alors des dimensions culturelle, politique, psychologique, et par-dessus tout, philosophique et m\u00e9taphysique, et pour les meilleures raisons du monde : &laquo; <em>On ne comprend rien \u00e0 l&rsquo;\u00e9conomie si on ne la replace pas dans un contexte plus large<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Le travail de Travers renvoie \u00e9videmment \u00e0 une approche holistique de l&rsquo;\u00e9conomie, selon une perception li\u00e9e \u00e0 la Tradition dans le sens le plus large du concept. Il s&rsquo;attache notamment \u00e0 critiquer l&rsquo;aveuglement moderniste pour les techniques et les technologies, qui est un caract\u00e8re moderniste fondamental et une des clefs de l&rsquo;orientation \u00e9conomique catastrophique que nous suivons.<\/p>\n<\/p>\n<p><p>Il rejoint la th\u00e8se que pr\u00e9sente PhG dans son <a href=\"https:\/\/www.amazon.fr\/gp\/product\/2874022004\/ref=dbs_a_def_rwt_bibl_vppi_i3\">Tome-II<\/a> de <em>La Gr\u00e2ce de l&rsquo;Histoire<\/em>, notamment en attaquant frontalement les conceptions absolument modernistes et conformistes de l&rsquo;historien-\u00e9conomiste <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Aldo_Schiavone\">Aldo Schiavone<\/a>, parfait reflet du Syst\u00e8me et parfaitement int\u00e9gr\u00e9 au Syst\u00e8me. (Le livre de Schiavone impliqu\u00e9e est <em>L&rsquo;Histoire bris\u00e9e : la Rome antique et l&rsquo;Occident moderne<\/em>, publi\u00e9 en 1996 [traduction fran\u00e7aise publi\u00e9e en 2003].)<\/p>\n<\/p>\n<p><p> &laquo; <em>\u00ab\u00a0On ne possede rien rationnellement, que l&rsquo;on n&rsquo;ait directement produit\u00a0\u00bb, ecrit Aldo Schiavone, qui pose alors cet axiome fondamental pour son parti : \u00ab\u00a0le vrai est seulement ce que l&rsquo;on a fait\u00a0\u00bb, cela qu&rsquo;il termine par ce commentaire etablissant effectivement la difference antagoniste fondamentale entre les civilisations de l&rsquo;Antiquite et de la modernite \u00ab\u00a0<\/em>[Ces] <em>enonces<\/em> [traversant] <em>l&rsquo;aventure cognitive de l&rsquo;Occident, de Vigo aux physiciens de la toute fin du vingtieme siecle, <\/em>[&#8230;] <em>aucune conscience antique n&rsquo;aurait pu<\/em> [les] <em>formuler.\u00a0\u00bb<\/em><\/p>\n<p>[&#8230;]<\/p>\n<p>&raquo; <em>Quoi qu&rsquo;il en soit mais en rassemblant les diverses donnees essen- tielles de la reflexion qui precede, c&rsquo;est bien autour de cette question de la volonte de la modernite de maitriser et de modifier la nature pour \u00ab\u00a0etre\u00a0\u00bb pleinement, &ndash; et puisque l&rsquo;etre, c&rsquo;est-a-dire \u00ab\u00a0le vrai\u00a0\u00bb, ne peut etre concu que dans ce qu&rsquo;il fait et rien d&rsquo;autre, &ndash; qu&rsquo;il faut se compter et se mesurer en progressant dans son jugement. Dans la logique du jugement de Schiavone, qui rejoint completement l&rsquo;esprit de la modernite et l&rsquo;esprit scientiste, la question de l&rsquo;absence de sens de notre civilisation de la modernite posee implicitement par Toynbee, jusqu&rsquo;a empecher toute autre civilisation de se poser en alternative, &ndash; cette question n&rsquo;a litteralement pas de sens. La puissance, c&rsquo;est-a-dire les technologies pour s&rsquo;exprimer d&rsquo;une facon concrete, voila qui non seulement fait sens, mais fait le seul sens acceptable et concevable pour la civilisation de la modernite, c&rsquo;est-a-dire pour la modernite tout court, c&rsquo;est-a-dire pour la seule civilisation acceptable (celle apres laquelle plus aucune autre n&rsquo;est possible, sinon concevable), c&rsquo;est-a-dire pour le monde tel qu&rsquo;il doit etre et tel qu&rsquo;il ne peut etre autrement (\u00ab\u00a0Les Lumieres, c&rsquo;est desormais l&rsquo;industrie\u00a0\u00bb)&#8230; Clic ! Clac ! Entendez les verrous claquer, porte verrouillee, prison hermetiquement assuree : Monsieur Schiavone, apres tant d&rsquo;autres, vient de nous confirmer que, pour le sens, le Systeme s&rsquo;occupe de tout&#8230; Voyez d&rsquo;ailleurs le resultat en l&rsquo;an de grace 2016.<\/em><\/p>\n<p>&raquo; <em>&#8230; En effet, l&rsquo;on peut alors se compter et, surtout, compter ce que nous sommes puisque nous sommes ce que nous avons fait, que nous avons fait ce que la puissance des technologies nous a permis de faire, et que le moment est bon pour mesurer ce qui a ete fait. L&rsquo;incertaine et grandissante perplexite a mesure que defilent tres vite nos annees de ce debut de XXIe siecle, pour tous les Schiavone du monde, c&rsquo;est que cette necessite de bilan, encore d&rsquo;un risque acceptable en 1994-1995 quand fut ecrit l&rsquo;ouvrage, est aujourd&rsquo;hui obscurci d&rsquo;un risque considerable pas loin de l&rsquo;inacceptable et du risque metahistorique de l&rsquo;indicible eschatologique pour acter du triomphe de la raison scientifique, de la modernite, de ce que les trois-cinq derniers siecles ont fait de nous. Il est en effet impossible d&rsquo;ecarter cette terrible relativite du \u00ab\u00a0vrai que nous sommes\u00a0\u00bb lorsque le temps va si vite et que la signification et le penchant de \u00ab\u00a0ce que nous avons fait\u00a0\u00bb changent avec une telle rapidite et une telle radicalite qu&rsquo;il nous conduit en un gros demi-siecle du rassurant Capitole a l&rsquo;effrayante Roche Tarpeienne. C&rsquo;est-a-dire que nous pouvons poser aujourd&rsquo;hui (ces lignes sont ecrites, de leur premier jet a leur confirmation, d&rsquo;octobre 2013 a mai 2016) qu&rsquo;il existe une possibilite considerable, en considerant que \u00ab\u00a0nous sommes ce que nous faisons\u00a0\u00bb (et \u00ab\u00a0ce que nous avons fait\u00a0\u00bb, par consequent), que nous soyons tout ensemble et d&rsquo;un seul trait, a la fois destruction du monde, destruction de l&rsquo;esprit, destruction de toute esperance d&rsquo;harmonie, destruction de ce qu&rsquo;il reste en nous du Principe. Et cela se fait dans une civilisation que nous n&rsquo;hesitons plus a qualifier de \u00ab\u00a0contre-civilisation\u00a0\u00bb, dont la puissance meme, que nous designons comme une \u00ab\u00a0surpuissance\u00a0\u00bb et qui est nee du developpement des technologies, empeche toute alternative civilisationnelle autre que la voie qui nous est tracee, et produit ultimement une effrayante dynamique d&rsquo;autodestruction. Nous voila confirme, pour notre compte, sur toutes les observations que nous suggere notre intuition sur le &lsquo;dechainement de la Matiere&rsquo; et sur tout ce qu&rsquo;elle enfante, et sur la modernite telle qu&rsquo;elle s&rsquo;est developpee, et sur tout ce que nous ont apportes les technologies, cette operationnalisation de la puissance dont nous poursuivons la quete pour dominer et changer la nature du monde, sur cette ambition meme de dominer et de changer le monde que nous n&rsquo;hesitons plus a ressentir au plus profond de nous comme essentiellement sinon profondement malefique dans le sens metaphysique de l&rsquo;Enfer lui- meme, atteignant a l&rsquo;entropisation ardemment poursuivie<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Travers ne pense \u00e9videmment pas que l&rsquo;on puisse ais\u00e9ment, si cela est possible et si l&rsquo;on pouvait m\u00eame y songer de fa\u00e7on s\u00e9rieuse, \u00ab\u00a0revenir au Moyen-&Acirc;ge\u00a0\u00bb, c&rsquo;est-\u00e0-dire en fait retrouver des conceptions et des pratiques de cette \u00e9poque, ou plut\u00f4t de la plupart des \u00e9poques avant la modernit\u00e9. &laquo; <em>Cela suppose une r\u00e9volution mentale<\/em> &raquo;, bien entendu et avec toute chose ; et une r\u00e9volution dont on ne sait d&rsquo;o&ugrave; elle viendra et comment. Cela suppose, finalement, une attention essentielle port\u00e9e au domaine de la psychologie, comme nous aimons souvent \u00e0 le r\u00e9p\u00e9ter.<\/p>\n<\/p>\n<p><p>Quelle psychologie peut pr\u00e9tendre envisager une telle \u00e9volution ? &laquo; <em>La plupart de nos contemporains sont aujourd&rsquo;hui asservis \u00e0 la technique, aux \u00e9crans, avec des cons\u00e9quences mentales et intellectuelles d\u00e9sastreuses. Je ne vois malheureusement pas de &lsquo;solution&rsquo; simple \u00e0 court terme, mais un espoir \u00e0 plus long terme : aujourd&rsquo;hui, une petite \u00e9lite \u00e9l\u00e8ve ses enfants loin de toute d\u00e9pendance technologique trop forte. Ils seront un jour ceux qui reb\u00e2tiront notre civilisation<\/em>&#8230; &raquo;<\/p>\n<\/p>\n<p><p>La perspective consid\u00e9r\u00e9e constitue certainement une voie possible, une partie du &lsquo;comment&rsquo; (en sortir), et &lsquo;pour quoi&rsquo; (mettre \u00e0 la place). Pour autant, il reste l&rsquo;\u00e9nigme g\u00e9n\u00e9rale et totale de d\u00e9terminer pour quelle cause fondamentale et selon quelle impulsion une telle \u00e9volution porterait ses fruits, quelle puissance serait assez grande pour entra&icirc;ner tous les esprits apr\u00e8s avoir impressionn\u00e9 (comme la photographie impressionnait la pellicule <em>in illo tempore<u>)<\/u><\/em> la psychologie dans le sens vertueux qui importe. Nous sommes l\u00e0 dans le domaine d&rsquo;en-dehors de la raison (heureusement d&rsquo;ailleurs), dans le domaine de l&rsquo;au-del\u00e0 de &lsquo;<a href=\"https:\/\/www.dedefensa.org\/article\/rapsit-usa2020-lhorizon-du-terrible-evenement\">l&rsquo;Horizon de l&rsquo;&Eacute;v\u00e9nement<\/a>&lsquo;. Pour autant, c&rsquo;est notre conviction essentiellement sinon exclusivement d&rsquo;ordre intuitif, l&rsquo;\u00e9v\u00e9nement est en marche.<\/p>\n<\/p>\n<p><p>Voici donc l&rsquo;interview de Guillaume Travers par Pierre Saint-Servant, \u00e0 partir d&rsquo;une reprise du <a href=\"https:\/\/www.revue-elements.com\/economie-pour-un-retour-au-moyen-age\/\">8 octobre 2020<\/a> par <em>&Eacute;l\u00e9ments<\/em> d&rsquo;une publication dans <em>Pr\u00e9sent <\/em>du 7 octobre 2020.<\/p>\n<\/p>\n<p><h4><em>dedefensa.org<\/em><\/h4>\n<\/p>\n<p><p>________________________<\/p>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Pour un retour au Moyen &Acirc;ge ?<\/h2>\n<\/p>\n<p><p><strong><em>Pierre Saint-Servant<\/em><\/strong> : <em>Telle qu&rsquo;elle est trait\u00e9e m\u00e9diatiquement et politiquement, l&rsquo;\u00e9conomie est r\u00e9duite \u00e0 des querelles techniques. Vous faites au contraire le choix de la ramener \u00e0 la philosophie. Pourquoi ?<\/em><\/p>\n<\/p>\n<p><p><strong>Guillaume Travers<\/strong> : Jusqu&rsquo;\u00e0 la p\u00e9riode moderne, l&rsquo;\u00e9conomie n&rsquo;a jamais exist\u00e9 comme domaine autonome. Les activit\u00e9s \u00e9conomiques \u00e9taient toujours &lsquo;encastr\u00e9es&rsquo; dans des relations sociales, politiques, communautaires. Le Moyen &Acirc;ge nous en donne maints exemples : les foires \u00e9taient l&rsquo;occasion de c\u00e9l\u00e9brations religieuses (feria), les communaut\u00e9s de m\u00e9tiers organisaient toute la vie urbaine, bien au-del\u00e0 des seules activit\u00e9s productives. On ne comprend rien \u00e0 l&rsquo;\u00e9conomie si on ne la replace pas dans un contexte plus large.<\/p>\n<\/p>\n<p><p><strong><em>Pierre Saint-Servant<\/em><\/strong> : <em>Le Moyen &Acirc;ge fait figure d&rsquo;\u00e2ge sombre pour les progressistes de tous poils, qu&rsquo;\u00eates-vous all\u00e9 y puiser ? Pourquoi devrait-on y avoir recours ?<\/em><\/p>\n<\/p>\n<p><p><strong>Guillaume Travers<\/strong> : Le Moyen &Acirc;ge offre un contre-mod\u00e8le \u00e0 la pens\u00e9e moderne, individualiste et progressiste. C&rsquo;est pourquoi il a \u00e9t\u00e9 tellement attaqu\u00e9. Par bonheur, de nombreux travaux d&rsquo;historiens depuis un si\u00e8cle ont permis de le r\u00e9habiliter. Dans une p\u00e9riode de crise profonde, le Moyen &Acirc;ge peut nous inspirer : il est un monde de communaut\u00e9s plus que d&rsquo;individus, un monde enracin\u00e9, ancr\u00e9 dans la terre, et assez largement autarcique. Ainsi, les solutions &lsquo;localistes&rsquo; que l&rsquo;on peut aujourd&rsquo;hui envisager ont d\u00e9j\u00e0 exist\u00e9 par le pass\u00e9. Le Moyen &Acirc;ge est aussi un monde qui ne fait pas de l&rsquo;accumulation mon\u00e9taire l&rsquo;alpha et l&rsquo;om\u00e9ga de l&rsquo;existence. Il est un monde de limitation, o&ugrave; les exc\u00e8s de richesse sont consacr\u00e9s \u00e0 des fins plus hautes, par exemple la construction des cath\u00e9drales. Notons enfin que les structures f\u00e9odales sont celles qui se sont mises en place au cours d&rsquo;une autre p\u00e9riode tr\u00e8s troubl\u00e9e, \u00e0 savoir la fin de l&rsquo;Empire romain. Ce sont autant de raisons d&rsquo;y \u00eatre sensible.<\/p>\n<\/p>\n<p><p><strong><em>Pierre Saint-Servant<\/em><\/strong> : <em>Vous opposez \u00e0 l&rsquo;individualisme et \u00e0 l&rsquo;utilitarisme la notion de &lsquo;commun&rsquo;. Que d\u00e9signe-t-elle ?<\/em><\/p>\n<\/p>\n<p><p><strong>Guillaume Travers<\/strong> : Au Moyen &Acirc;ge, le concept de propri\u00e9t\u00e9 priv\u00e9e est tr\u00e8s largement absent. Dire que le seigneur est &lsquo;propri\u00e9taire&rsquo; de terres est une description tr\u00e8s imparfaite. En v\u00e9rit\u00e9, il y a un enchev\u00eatrement de droits r\u00e9ciproques, issus de serments pass\u00e9s et de la coutume. Par exemple, un seigneur ne peut pas vendre des terres sur lesquelles des paysans ont obtenu le droit de cultiver. Dans ce syst\u00e8me, les &lsquo;communs&rsquo; sont tous les espaces dont l&rsquo;usage n&rsquo;est pas limit\u00e9 \u00e0 une seule famille : c&rsquo;est par exemple un champ o&ugrave; certains peuvent faire pa&icirc;tre du b\u00e9tail, d&rsquo;autres ramasser des baies, d&rsquo;autres du bois, etc. Le terme de &lsquo;commun&rsquo; est \u00e9loquent : le monde m\u00e9di\u00e9val, on l&rsquo;a dit, \u00e9tait un monde de communaut\u00e9s. Toute l&rsquo;organisation sociale est donc subordonn\u00e9e \u00e0 une vision du bien de ces communaut\u00e9s, au bien commun. L&rsquo;abandon des &lsquo;communs&rsquo; (notamment par le &lsquo;mouvement des enclosures&rsquo; en Angleterre) fut \u00e0 l&rsquo;inverse un moment cl\u00e9 dans l&rsquo;essor de l&rsquo;individualisme moderne.<\/p>\n<\/p>\n<p><p><strong><em>Pierre Saint-Servant<\/em><\/strong> : <em>L&rsquo;\u00e9cologie sera incontestablement au c&oelig;ur des luttes id\u00e9ologiques de demain. Le moins que l&rsquo;on puisse dire est que celle qui domine le paysage m\u00e9diatique est une \u00e9cologie &lsquo;\u00e0 l&rsquo;envers&rsquo;. Que faut-il pour la remettre \u00e0 l&rsquo;endroit ?<\/em><\/p>\n<\/p>\n<p><p><strong>Guillaume Travers<\/strong> : L&rsquo;\u00e9cologie, \u00e9tymologiquement, touche \u00e0 ce qui est proche (oikos, &lsquo;maison&rsquo;) ; l&rsquo;environnement, c&rsquo;est d&rsquo;abord ce qui nous environne. Pour remettre l&rsquo;\u00e9cologie \u00e0 l&rsquo;endroit, il faut se r\u00e9-enraciner, retrouver un rapport de co-appartenance avec la nature proche. On ne respecte jamais autant une for\u00eat ou une rivi\u00e8re que quand on s&rsquo;y prom\u00e8ne chaque jour. Ce qui tue l&rsquo;environnement, c&rsquo;est le mouvement g\u00e9n\u00e9ralis\u00e9 des biens et des personnes, qui d\u00e9vaste tous les milieux encore sauvages. Mais c&rsquo;est aussi une maladie de l&rsquo;\u00e2me : l&rsquo;homme priv\u00e9 de racines n&rsquo;est bien nulle part, il n&rsquo;a pas la s\u00e9r\u00e9nit\u00e9 n\u00e9cessaire \u00e0 l&rsquo;immobilit\u00e9, \u00e0 la contemplation. Il multiplie les occasions de prendre l&rsquo;avion pour tenter (en vain) de voir mieux ailleurs. Si l&rsquo;homme moderne veut se &lsquo;d\u00e9payser&rsquo;, c&rsquo;est parce qu&rsquo;il ne supporte pas les paysages qui l&rsquo;entourent. Concr\u00e8tement, il faut donc \u00e9videmment faire obstacle au libre-\u00e9change g\u00e9n\u00e9ralis\u00e9. Mais c&rsquo;est aussi toute une culture qu&rsquo;il faut reb\u00e2tir : retrouver des modes de vie plus sains, une plus grande sensibilit\u00e9 \u00e0 la nature.<\/p>\n<\/p>\n<p><p><strong><em>Pierre Saint-Servant<\/em><\/strong> : <em>La pr\u00e9servation de ce qui fait la dignit\u00e9 de l&rsquo;homme nous pousserait \u00e0 freiner la course en avant technologique : 5G, robotisation, virtualisation de toute la vie humaine&hellip; Pourtant, cela nous ferait imm\u00e9diatement d\u00e9crocher dans la comp\u00e9tition mondiale, comment r\u00e9soudre cette \u00e9quation ?<\/em><\/p>\n<\/p>\n<p><p><strong>Guillaume Travers<\/strong> : C&rsquo;est une question \u00e9pineuse. Jusqu&rsquo;\u00e0 la p\u00e9riode moderne, les techniques ont \u00e9volu\u00e9 de mani\u00e8re presque continue, mais dans un esprit tr\u00e8s diff\u00e9rent. Le progr\u00e8s technique n&rsquo;\u00e9tait pas consid\u00e9r\u00e9 comme une fin en soi, ni comme purement instrumental : pour gagner plus d&rsquo;argent, pour satisfaire des fins individuelles. L&rsquo;\u00e9conomiste allemand Werner Sombart nous donne un exemple. Les artisans m\u00e9di\u00e9vaux ma&icirc;trisaient des techniques pointues. Celles-ci se transmettaient par le compagnonnage et, en les employant, un artisan perp\u00e9tuait une tradition. &Agrave; la p\u00e9riode moderne, on se met \u00e0 appliquer une technique \u00ab\u00a0parce que \u00e7a marche\u00a0\u00bb, \u00ab\u00a0parce que c&rsquo;est moins co&ucirc;teux\u00a0\u00bb. Les gestes perdent leur dimension traditionnelle. Que cela nous dit-il ? Que la technique peut \u00eatre \u00e9volu\u00e9e et ne pas poser probl\u00e8me, d\u00e8s lors qu&rsquo;elle n&rsquo;est pas une fin en soi. Cela suppose une r\u00e9volution mentale. La plupart de nos contemporains sont aujourd&rsquo;hui asservis \u00e0 la technique, aux \u00e9crans, avec des cons\u00e9quences mentales et intellectuelles d\u00e9sastreuses. Je ne vois malheureusement pas de &lsquo;solution&rsquo; simple \u00e0 court terme, mais un espoir \u00e0 plus long terme : aujourd&rsquo;hui, une petite \u00e9lite \u00e9l\u00e8ve ses enfants loin de toute d\u00e9pendance technologique trop forte. Ils seront un jour ceux qui reb\u00e2tiront notre civilisation. Je ne vois donc pas de salut global mais, pour en revenir une derni\u00e8re fois au Moyen &Acirc;ge, l&rsquo;\u00e9mergence de petites communaut\u00e9s qui pr\u00e9serveront notre h\u00e9ritage et joueront un jour un r\u00f4le de premier plan.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Retour sur un futur bancal Guillaume Travers est un \u00e9conomiste original, et donc int\u00e9ressant selon les pratiques si conformistes-PC du temps courant autant que selon les habitudes pseudo-p\u00e9rennes de cette mati\u00e8re (l&rsquo;\u00e9conomie). Il semble bien qu&rsquo;il ne place pas, surtout pas, l&rsquo;\u00e9conomie au centre de tout. Il semble bien qu&rsquo;il consid\u00e8re l&rsquo;\u00e9conomie comme une mati\u00e8re&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[9478,3482,17879,2631,2604,2633,2986,2655,2650,2888,4226,3716,6750,19956,19730],"class_list":["post-79471","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-cathedrale","tag-chute","tag-covid19","tag-de","tag-des","tag-guillaume","tag-lempire","tag-modernite","tag-mort","tag-noire","tag-schiavone","tag-siecle","tag-temps","tag-travers","tag-xiveme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79471","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79471"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79471\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79471"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79471"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79471"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}