{"id":79493,"date":"2020-11-02T10:47:54","date_gmt":"2020-11-02T10:47:54","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2020\/11\/02\/rapsit-usa2020-see-you-in-hell-brother\/"},"modified":"2020-11-02T10:47:54","modified_gmt":"2020-11-02T10:47:54","slug":"rapsit-usa2020-see-you-in-hell-brother","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2020\/11\/02\/rapsit-usa2020-see-you-in-hell-brother\/","title":{"rendered":"RapSit-USA2020\u00a0: <em>See You in Hell, Brother !<\/em>"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">RapSit-USA2020 : <em>See You in Hell, Brother !<\/em><\/h2>\n<\/p>\n<p><p>La question centrale aujourd&rsquo;hui, encore inexprim\u00e9e hier, peut-\u00eatre transform\u00e9e en ultimatum cosmique demain, est de d\u00e9terminer la mesure de l&rsquo;\u00e9v\u00e9nement du 3 novembre. La folle \u00e9lection USA2020 est en train de morpher dans nos esprits en un \u00e9norme affrontement de la globalisation, avec les pour et les contre en ordre de bataille, o&ugrave; chacun des deux camps qui regroupent de tr\u00e8s-singuliers alli\u00e9s de circonstance, voient de plus en plus son existence m\u00eame engag\u00e9e. Des alarmes et des d\u00e9clarations pressantes sonnent partout, comme <a href=\"https:\/\/twitter.com\/GenFlynn\/status\/1322494419073933314\">ce Tweet<\/a> du g\u00e9n\u00e9ral Flynn, &ndash; simple illustration de l&rsquo;\u00e9tat de l&rsquo;esprit, &ndash; d\u00e9crivant un \u00e9v\u00e9nement \u00e9quivalent au D\u00e9luge, avec une forte connotation biblique bien entendu. Nous croyons sans le moindre doute que le G\u00e9n\u00e9ral Flynn ne monte pas un spectacle dans cette courte communication, qu&rsquo;il laisse au contraire parler son jugement.<\/p>\n<\/p>\n<p><p>L\u00e0 o&ugrave; il n&rsquo;y avait, hier encore, qu&rsquo;une \u00e9tape cruciale dans le torrent crisique qui nous emporte, on distingue d\u00e9sormais un pic hyst\u00e9rique de premi\u00e8re importance, &ndash; sans bien entendu qu&rsquo;il soit question d&rsquo;un prolongement d\u00e9cisif, mais en sous-entendant qu&rsquo;il s&rsquo;agit de quelque chose qui pourrait aussi \u00eatre un prolongement d\u00e9cisif, &ndash; qui donc reconna&icirc;tra les siens pour nous donner quelque assurance o&ugrave; la trag\u00e9die v\u00e9ridique appara&icirc;trait presque comme un apaisement ?<\/p>\n<\/p>\n<p><p>A propos de Guillaume II confront\u00e9 \u00e0 la d\u00e9faire de l&rsquo;Empire en novembre 1918, Gustave Thibon (dans <em>Entretiens avec Gustave Thibon<\/em>, de Philippe Barthelet) distingue une r\u00e9action hyst\u00e9rique du personnage, &laquo; <em>le vide int\u00e9rieur <\/em>[de l&#8217;empereur Guillaume dans ce cas] <em>ayant toujours besoin d&rsquo;\u00eatre combl\u00e9 par d&rsquo;innombrables sensations factices&#8230; <\/em>&raquo;, &ndash; ce qui implique un appel \u00e0 la r\u00e9action du simulacre, renvoyant \u00e0 la d\u00e9finition de l&rsquo;hyst\u00e9rie que propose le philosophe allemand Klages cit\u00e9 par Thibon, comme une &laquo; <em>r\u00e9action du besoin de repr\u00e9sentation sur le sentiment de l&rsquo;impuissance<\/em> &raquo;. Nous avons absolument besoin d&rsquo;une capacit\u00e9 colossale de repr\u00e9sentation, tant l&rsquo;\u00e9v\u00e9nement est pressenti comme colossal.<\/p>\n<\/p>\n<p><p>(S&rsquo;il n&rsquo;en est rien, la ridicule montagne aura accouch\u00e9 d&rsquo;une rachitique souris, et le simulacre sera piteux, &ndash; ce qui ne peut \u00eatre en v\u00e9rit\u00e9, d&rsquo;o&ugrave; la n\u00e9cessit\u00e9 de l&rsquo;\u00e9v\u00e9nement catastrophique, car sans lui la chose est catastrophique&#8230;.)<\/p>\n<\/p>\n<p><p>Ce qui est absolument remarquable dans l&rsquo;\u00e9pisode que nous vivons, et d&rsquo;ailleurs comme une illustration un peu plus piquante d&rsquo;une situation g\u00e9n\u00e9rale, c&rsquo;est qu&rsquo;il n&rsquo;y a pas vraiment d&rsquo;agresseurs, mais des accusations qui volent de tous les c\u00f4t\u00e9s, faisant de l&rsquo;adversaire un comploteur en marche pour briser la l\u00e9gitimit\u00e9 des peuples. Il n&rsquo;y a pas une menace de coup d&rsquo;&Eacute;tat contre laquelle pr\u00e9tend se d\u00e9fendre l&rsquo;agress\u00e9, mais partout des accusations d&rsquo;attaque ill\u00e9gale contre l&rsquo;autre. Chaque concurrent se pare d&rsquo;avoir le droit et la l\u00e9gitimit\u00e9 pour lui, face \u00e0 la menace brutale de l&rsquo;imposteur tentant de prendre le pouvoir par la force ; d&rsquo;une part, la d\u00e9nonciation du danger fasciste, d&rsquo;autre part la mise en \u00e9vidence du danger marxiste-l\u00e9niniste ; d&rsquo;une part, Trump-Hitler en marche en mars-1933, d&rsquo;autre part les marxistes-l\u00e9ninistes regroup\u00e9s pour un nouvel Octobre-1917.<\/p>\n<\/p>\n<p><p>Bien qu&rsquo;il se fasse \u00e0 coup de r\u00e9f\u00e9rences vieilles d&rsquo;autour du si\u00e8cle, l&rsquo;affrontement est bien de ces heures sombres du mois de novembre 2020, compl\u00e8tement et tout \u00e0 fait d&rsquo;actualit\u00e9. Pire encore, il se fait en compl\u00e8te \u00e9tat de conscience, car les regroupements faits autour de l&rsquo;un et de l&rsquo;autre parti (Trump &#038; Biden, pour faire bref, puisqu&rsquo;il s&rsquo;agit de USA2020 pour le coup, en attendant les r\u00e9pliques d&rsquo;extension) concerne des dizaines de millions de personnes, ou de citoyens si vous voulez, qui agissent non pas manipul\u00e9s ou tromp\u00e9s, non pas sans la sensation d&rsquo;une conscience de l&rsquo;enjeu, mais au contraire proclamant qu&rsquo;ils ont une conscience claire et nette de l&rsquo;enjeu ; proclamant qu&rsquo;ils ont une conscience claire et nette des causes de leur position et de leur action&#8230; M\u00eame si l&rsquo;on peut, dans tous les cas envisag\u00e9s, r\u00e9ciproquement et antagonistement mais sans la moindre certitude de la justesse du jugement, douter de la justesse de ces positions et de ces actions, il n&rsquo;est en rien assur\u00e9 que cela ou autre chose soit, &ndash; d&rsquo;accord ? L&rsquo;incertitude r\u00e8gne absolument, mais ne d\u00e9courage en aucun cas, ni la rage, ni la haine, ni la volont\u00e9 d&rsquo;agir.<\/p>\n<\/p>\n<p><p>C&rsquo;est dans cette circonstance, dans ce contexte, dans cette crise profonde de l&rsquo;environnement psychologique et politique, qu&rsquo;a lieu demain l&rsquo;\u00e9lection du 3 novembre. La seule chose qu&rsquo;on peut affirmer sans le moindre risque, c&rsquo;est qu&rsquo;il s&rsquo;agira d&rsquo;un \u00e9v\u00e9nement historique, m\u00eame si l&rsquo;\u00e9v\u00e9nement s&rsquo;av\u00e8re faussaire et simulacre ; m\u00eame si ceux qui d\u00e9montrent qu&rsquo;il y a du faussaire et du simulacre dans l&rsquo;\u00e9v\u00e9nement, peuvent eux-m\u00eames \u00eatre mis en cause comme faussaire et du simulacre&#8230; Nous vivons une v\u00e9ritable (r)\u00e9volution, au sens spatial que signalait infatigablement Hannah Arendt : une \u00e9lipse qui fait retour \u00e0 son point de d\u00e9part. Partis d&rsquo;un d\u00e9sordre innommable que constitue l&rsquo;histoire en devenir, le <em>Khaos<\/em> originel, nous aboutissions \u00e0 un d\u00e9sordre innommable qui caract\u00e9rise la m\u00e9taHistoire que nous avons cru conduire \u00e0 bon port, et qui r\u00e9pond en fait \u00e0 d&rsquo;autres suggestions, \u00e0 d&rsquo;autres consignes, \u00e0 d&rsquo;autres impulsions, qui r\u00e8gne de beaucoup plus haut.<\/p>\n<\/p>\n<p><p>D&rsquo;o&ugrave; et plus que jamais, notre repli sur une conception transcendantale du ph\u00e9nom\u00e8ne de l&rsquo;\u00e9v\u00e9nementiel, supposant une posture d&rsquo;humilit\u00e9, d&rsquo;une courageuse humilit\u00e9, face aux \u00e9v\u00e9nements incompr\u00e9hensibles que nous affrontons et dont nous sommes les jouets autant que les acteurs consentants et bern\u00e9s d&rsquo;une part ; les jouets autant que les acteurs furieux et haineux d&rsquo;autre part. Le d\u00e9doublement, la schizophr\u00e9nie des perceptions et des actes sont g\u00e9n\u00e9rales et irr\u00e9sistibles. Tout cela nous permet, \u00e0 nous les <em>Happy Few <\/em>qui pratiquons le sport favori de l&rsquo;homme qu&rsquo;est l&rsquo;ironie, d&rsquo;annoncer avec une joyeuse ironie jouant ironiquement \u00e0 figurer la pompe de la Grande Histoire, notre compl\u00e8te ignorance de ce que sera la situation le 3 novembre au soir, le 4 novembre au matin et ainsi de suite&#8230;<\/p>\n<\/p>\n<p><p>(On observera pourtant une certaine coh\u00e9rence dans le suivi des choses : le 4 novembre succ\u00e9dant au 3 novembre, et ainsi de suite.)<\/p>\n<\/p>\n<blockquote>\n<p><p>Ainsi en est-il de la derni\u00e8re r\u00e9plique du film <a href=\"https:\/\/en.wikipedia.org\/wiki\/Elmer_Gantry_(film)\"><em>Elmer Gantry<\/em><\/a> de 1960, d&rsquo;apr\u00e8s le livre de Upton Sinclair, o&ugrave; Lancaster-Gantry salue le narrateur-t\u00e9moin pour qui il a une sorte d&rsquo;estime, de cette aventure de la manipulation humaine et de la foi myst\u00e9rieuse et grossi\u00e8re dont l&rsquo;intrigue semble \u00eatre un complet simulacre parsem\u00e9 peut-\u00eatre de v\u00e9rit\u00e9s profondes, dont personne ne pourra dire jamais quelle en fut la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-verite-de-situation-verite\">v\u00e9rit\u00e9-de-situation<\/a> sinon en s&rsquo;en remettant \u00e0 quelque intuition salutaire (et \u00e0 moins que nous en sachions nous-m\u00eames l\u00e0-dessus, plus que nous ne voulons en \u00e9crire) :<\/p>\n<\/p>\n<p><p>&ndash; <em>See You in Hell, Brother<\/em> <em>!<\/em><\/p>\n<\/p>\n<\/blockquote>\n<p><p>.. Si tant est, effectivement, qu&rsquo;il y a un lendemain apr\u00e8s le 3 novembre, et si, apr\u00e8s tout, l&rsquo;enfer existe vraiment. M\u00eame Elmer Gantry, <em>alias <\/em>Donald Trump ou Joe Biden, ne saurait nous le dire ; ce n&rsquo;est pas pour rien qu&rsquo;il existe aux USA une Cour Supr\u00eame (SCOTUS) toute neuve.<\/p>\n<\/p>\n<p><p>Mis en ligne le 2 novembre 2020 \u00e0 10H45<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>RapSit-USA2020 : See You in Hell, Brother ! La question centrale aujourd&rsquo;hui, encore inexprim\u00e9e hier, peut-\u00eatre transform\u00e9e en ultimatum cosmique demain, est de d\u00e9terminer la mesure de l&rsquo;\u00e9v\u00e9nement du 3 novembre. La folle \u00e9lection USA2020 est en train de morpher dans nos esprits en un \u00e9norme affrontement de la globalisation, avec les pour et les&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[21],"tags":[1235,20352,2926,18837,5135,7408,2879,3965,17241,2639],"class_list":["post-79493","post","type-post","status-publish","format-standard","hentry","category-breves-de-crise","tag-biden","tag-elmer","tag-flynn","tag-gantry","tag-hysterie","tag-incertitude","tag-revolution","tag-simulacre","tag-thibon","tag-trump"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79493","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79493"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79493\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79493"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79493"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79493"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}