{"id":79498,"date":"2020-10-28T03:43:52","date_gmt":"2020-10-28T03:43:52","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2020\/10\/28\/plongee-tout-schuss-dans-le-cloaque-francais\/"},"modified":"2020-10-28T03:43:52","modified_gmt":"2020-10-28T03:43:52","slug":"plongee-tout-schuss-dans-le-cloaque-francais","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2020\/10\/28\/plongee-tout-schuss-dans-le-cloaque-francais\/","title":{"rendered":"Plong\u00e9e \u201ctout <em>schuss<\/em>\u201d dans le cloaque fran\u00e7ais"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Plong\u00e9e \u00ab\u00a0tout <em>schuss<\/em>\u00a0\u00bb dans le cloaque fran\u00e7ais<\/h2>\n<\/p>\n<p><p>28 octobre 2020 &ndash; Rassurez-vous, je ne vais pas parler de Codiv19, je veux dire : pas ici, pas pour l&rsquo;instant, pas pour ce cas, pas dissimul\u00e9 pour autant qu&rsquo;on y viendra, et vite&#8230; Je vais parler de cet ensemble <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-bloc-bao-1\">BlocBAO<\/a>-UE-France, avec France soi-m\u00eame en bout de cha&icirc;ne, pas du tout cha&icirc;non manquant pour autant ; en &lsquo;posture verticale&rsquo; comme ils disent, c&rsquo;est-\u00e0-dire souverainet\u00e9 retrouv\u00e9e et resplendissante, Macron <em>regnante<\/em>, salons et plateaux (TV) bourdonnant d&rsquo;avis p\u00e9remptoires et tenus avec une main de fer dans les bornes bien calibr\u00e9es de la tr\u00e8s-sage parole politique-correcte selon les normes ; sous l&rsquo;observation tr\u00e8s parisienne et plong\u00e9es dans les jeux dr\u00f4les, de r\u00f4le et d&rsquo;esprit, affectionn\u00e9s dans les divers petits postes de \u00ab\u00a0d\u00e9sintox\u00a0\u00bb et autres <em>Fact-Cheking<\/em>, sentinelles avec portables tr\u00e8s chouettes et directement d\u00e9nonciateur, du type-Yann Barth\u00e8s (excellent et sympathique gar\u00e7on), install\u00e9s dans les courants doucereux-ricanants de la moraline masqu\u00e9e dot\u00e9e de la vivacit\u00e9 superbe dite du ruissellement ; en plus postes favoris des gros cahiers de pub en dizaines voire centaines de &euro;millions d&rsquo;annonce, des belles vertus du <em><a href=\"https:\/\/www.dedefensa.org\/article\/gauchistes-de-tous-les-pays-friquez-vous-systeme\">Corporate Socialism<\/a> <\/em>et des grands esprits de la <em>Woke-Ideology<\/em>&#8230;<\/p>\n<\/p>\n<p><p>Et puis, de l&rsquo;autre c\u00f4t\u00e9, les ricanants, les complotistes-perdus-d&rsquo;avance, les haineux du troupeau fran\u00e7ais qu&rsquo;on exhorte \u00e0 se d\u00e9fendre contre la Modernit\u00e9 d\u00e9vorante, en lui crachant face rectal qu&rsquo;il n&rsquo;a aucune chance de se d\u00e9fendre parce que des pauvres \u00eatres, moutons pas moins, des perdus d&rsquo;avance, et les mauvais bergers qui continuent \u00e0 fulminer, \u00e0 m\u00e9priser le troupeau de ces moutons du type-La Bo\u00e9tie, qu&rsquo;il pourrait au moins avoir le reste de correction raidie de se d\u00e9fendre, qu&rsquo;il n&rsquo;a aucune chance parce qu&rsquo;il pue et qu&rsquo;\u00e0 cause de \u00e7a il doit tenter sa chance, qu&rsquo;il g&icirc;t l\u00e0, b\u00ealant et sans espoir. Ceux-l\u00e0 aussi, ces entra&icirc;neurs de causes perdues (le troupeau moutonier) dont on prend garde \u00e0 leur maintenir la t\u00eate sous l&rsquo;eau en les insultant parce qu&rsquo;ils ne resopirent pas, ceux-l\u00e0 aussi, et encore plus, ils tra&icirc;nent leur paquet de fiante sifflante, Yann Barth\u00e8s invertis mais aussi bien aiguis\u00e9s&#8230;<\/p>\n<\/p>\n<p><p>Mais bon, partie-bile en partie recrach\u00e9e, je pr\u00e9cise que ce dont je vous parle est d&rsquo;ordre assez g\u00e9n\u00e9ral, concerne quelques points bien pr\u00e9cis, dont le dernier sera un excellent texte de Bruno Guigue, faisant bilan de l&rsquo;action civilisatrice, postmoderne, d\u00e9constructrice \u00e0 la mode, concernant la malheureuse Syrie. J&rsquo;ajouterai sur le chemin quelques pr\u00e9cisions venues directement du Syst\u00e8me dont les h\u00e9ro\u00efques r\u00e9sistants qui disent s&rsquo;opposer \u00e0 lui ne cessent de d\u00e9crire l&rsquo;impossibilit\u00e9 inh\u00e9rente de l&rsquo;arr\u00eater, tant sa muflerie hurlante est terrifiante, partout identifi\u00e9e et calibr\u00e9e, se r\u00e9v\u00e8le incroyablement efficace dans son incapacit\u00e9 suppos\u00e9e. Ils m\u00e9prisent les moutons qui ne font rien et eux-m\u00eames, flambards comme pas deux, ne font rien en s&rsquo;en glorifiant. Plus on est de paradoxes plus on rit, surtout quand les paradoxes permettent de se d\u00e9filer.<\/p>\n<\/p>\n<p><p>Vous contant tout cela, j&rsquo;ai l&rsquo;impression de faire rapport d&rsquo;un r\u00eave, ce qui pourrait \u00eatre le cas vu mon r\u00e9veil soudain et si matinal, au c&oelig;ur de la nuit&#8230; Revenons \u00e0 nos moutons.<\/p>\n<\/p>\n<p><p>Ainsi de tel autrefois-fonctionnaire de l&rsquo;UE, un pied fran\u00e7ais l&rsquo;autre bruxellois, avec lequel j&rsquo;ai des relations affectueuses qu&rsquo;entretiennent nos pr\u00e9occupations et orientations communes ; je l&rsquo;appelle X pour la commodit\u00e9 et la clart\u00e9 du propos, parce que ce que je veux vous confier est s\u00e9rieux, c&rsquo;est-\u00e0-dire \u00e9veill\u00e9, et non l&rsquo;objet d&rsquo;un r\u00eave&#8230; X donc, me rapporte qu&rsquo;il a re\u00e7u un t\u00e9l\u00e9phone, son interlocuteur, de l&rsquo;UE justement, interrogeant en X une relation qu&rsquo;il juge plut\u00f4t ind\u00e9pendante donc assez libre, mais bien au fait des choses fran\u00e7aises, pour l&rsquo;informer de certaines initiatives ou autres fran\u00e7aises.<\/p>\n<\/p>\n<p><p>\u00ab\u00a0Mais qu&rsquo;est-ce donc que la France a \u00e0 voir avec l&rsquo;affaire Navalny, qu&rsquo;elle poursuit f\u00e9rocement en d\u00e9non\u00e7ant les Russes et Poutine, alors que par ailleurs mais pas si loin et m\u00eame urgemment avec les terroristes tch\u00e9tch\u00e8nes, elle a des choses importantes \u00e0 demander aux Russes et \u00e0 Poutine ?\u00a0\u00bb R\u00e9ponse, je crois assez ironique, de X :<\/p>\n<\/p>\n<p><p>\u00ab\u00a0&#8230; Eh ben &#8230; \u00ab\u00a0, &ndash; ce qui ne se discute pas.<\/p>\n<\/p>\n<p><p>Le m\u00eame interlocuteur de X, le brave fonctionnaire UE et bip\u00e8de, me dit X mon aimable source, est lui-m\u00eame engag\u00e9 dans le vaste processus de la jungle kafka\u00efenne des sanctions antirusses du fait de l&rsquo;UE bien s&ucirc;r, notamment \u00e0 propos de ce type, ce Navalny, dont on ne sait pas tr\u00e8s bien ce qu&rsquo;il faut penser de tout ce qu&rsquo;il raconte, mais qui est la meilleure raison du monde pour un nouveau TGV de sanctions contre la Russie et Poutine. En retour de sa question, X l&rsquo;interroge \u00e0 propos des causes de la politique-UE \u00e0 l&rsquo;encontre de la Russie, \u00e0 propos de Navalny et du reste qu&rsquo;importe&#8230; R\u00e9ponse \u00e0 ma source-X de son interlocuteur UE-bip\u00e8de \u00e0 ce propos :<\/p>\n<\/p>\n<p><p>\u00ab\u00a0&#8230; Eh ben, Eh ben &#8230; \u00ab\u00a0, &ndash; on ne peut \u00eatre plus clair.<\/p>\n<\/p>\n<p><p>Et l\u00e0-dessus, je vous dis que j&rsquo;en ai une autre de cette m\u00eame source, encore plus r\u00e9cente et plus chaudasse. Suite \u00e0 l&rsquo;attentat terrible que vous savez, vous n&rsquo;ignorez donc pas que Darmanin, Secr\u00e9taire du plus haut degr\u00e9 de l&rsquo;&Eacute;tat, tr\u00e8s logiquement puisqu&rsquo;il est question de terroristes tch\u00e9tch\u00e8nes que les Russes connaissent sacr\u00e9ment bien, a demand\u00e9 \u00e0 son &Eacute;minence-pr\u00e9sident l&rsquo;autorisation de contacter la partie Russie, tr\u00e8s-amie vous savez finalement, pour lui demander son aide. Le Pr\u00e9sident-&Eacute;minence ne se tient plus de joie : il juge l&rsquo;initiative audacieuse, fort heureuse, et son ministre-Secr\u00e9taire de Grand &Eacute;tat des plus avis\u00e9s, et en bonne marche pour incorporer dans son Duch\u00e9 quasiment royal des provinces d\u00e9cevantes, qu&rsquo;elles soient celles de la Loi-d&rsquo;I-Ritz et des all\u00e9es du Comt\u00e9 de Vend\u00f4me, et m\u00eame des Magistrats de la Cit\u00e9 qui se croient juges de tout, ceux-l\u00e0. Quant aux plumitifs, ils plumitiveront, et ils s&rsquo;y feront. L&rsquo;&Eacute;minence pr\u00e9sidentielle l&rsquo;affirme, il t\u00e9l\u00e9phone lui-m\u00eame et derechef \u00e0 son tr\u00e8s-grand ami Poutine, de son boudoir-secret du <em>Soft<\/em>-Palace.<\/p>\n<\/p>\n<p><p>Je poursuis donc avec ma source qui, par divers bruissements, chuchotements d&rsquo;eau claire et limpide quoique tr\u00e8s vive, a poursuivi ses investigations et re\u00e7u des t\u00e9moignages de convenance. Je croirais bien que, du c\u00f4t\u00e9 des Russes, m\u00eame si discr\u00e8tement, on ne s&rsquo;est pas retenu pour s&rsquo;\u00e9pancher&#8230; L&rsquo;on rit bien, sous les perspectives du Palais d&rsquo;Hiver et dans l&rsquo;ombre de la Forteresse Pierre-et-Paul.<\/p>\n<\/p>\n<p><p>Bref, les Fran\u00e7ais, par les Voix que vous savez terriblement herm\u00e9tiques, interviennent aupr\u00e8s des Russes, en passant par Sa Grandeur, Poutine lui-m\u00eame. Lui, tout sucre tout miel : \u00ab\u00a0Mais bien s&ucirc;r, mon Dieu et par Saint-George, certes qu&rsquo;on vous aidera contre l&rsquo;ignominie terroriste tch\u00e9tch\u00e8ne, vous pensez !\u00a0\u00bb<\/p>\n<\/p>\n<p><p>L\u00e0, on pense du c\u00f4t\u00e9 fran\u00e7ais, on se dit que c&rsquo;est une affaire qui marche, que la dimension internationale, et en plus avec la puissante et respectable Russie, quel beau coup ! Contre le terrorisme, certes, et pour Macron soi-m\u00eame, devenue le <em>Lider Maximo<\/em> antiterroriste de la civilisation &#8230; (Fin de la note de synth\u00e8se.)<\/p>\n<\/p>\n<p><p>Maintenant, on revient aux petites voix d\u00e9j\u00e0 cit\u00e9es puisqu&rsquo;on en vient aux d\u00e9tails du voyage de Darmanin. (Je ne sais quand : hier, sans doute, arriv\u00e9e \u00e0 Moscou, pour voir les amis l\u00e0-bas, non ?) \u00ab\u00a0D\u00e9tails\u00a0\u00bb, \u00ab\u00a0d\u00e9tails\u00a0\u00bb, vous savez bien : &lsquo;<em>The Devil in the detail<\/em>&lsquo; disent les Anglais, et les Fran\u00e7ais : &lsquo;Le Bon Dieu est dans les d\u00e9tails&rsquo;&#8230; Bref.<\/p>\n<\/p>\n<p><p>L\u00e0-bas, \u00e0 Moscou, dit la petite voix, \u00ab\u00a0la chose a \u00e9t\u00e9 et continue \u00e0 \u00eatre compliqu\u00e9e. Oh, \u00e0 mon avis, Darmanin aura ce qu&rsquo;il veut, parce que les Russes savent qu&rsquo;il y a des choses s\u00e9rieuses. Mais en attendant, on a bien ri. Il para&icirc;t qu&rsquo;il y a eu l&rsquo;id\u00e9e, pour les Fran\u00e7ais, de rencontrer le directeur du FSB, le chef du contre-espionnage charg\u00e9 de la lutte anti-terroriste&#8230; Mais aussi, de la lutte anti-Navalny, vous savez ?<\/p>\n<\/p>\n<p><p>\u00ab\u00a0Alors, les Russes, suaves, ont fait savoir : mais ce type, l\u00e0, Alexandre Vassilievitch, ce sp\u00e9cialiste, vous savez il vient d&rsquo;\u00eatre mis par vos soins sous le r\u00e9gime inf\u00e2mant de vos sanctions, les fran\u00e7aises, et peut-\u00eatre bien aussi les UE, peut-\u00eatre Trump, on ne sait plus tr\u00e8s bien. Alors, il est tr\u00e8s d\u00e9pressif, il est plein d&rsquo;angoisses, il se dit qu&rsquo;on lui en veut&#8230; Est-il encore op\u00e9rationnel, oh l\u00e0 l\u00e0 ? Vous sera-t-il d&rsquo;un grand secours, oh mon Dieu&#8230; Pauvre Alexandre Vassilievitch ! Oh, \u00e9coutez, on va vous arranger une rencontre, tout de m\u00eame, des pieds et des mains on va faire ! Mais attention, en l&rsquo;approchant, il est sous sanctions ; certes, d&rsquo;est pas tout \u00e0 fait contagieux, pas vraiment Covid, mais tout de m\u00eame, hein ! Ah, heureusement que \u00e7a existe, les sanctions, pour d\u00e9fendre la civilisation, vous et nous &lsquo;partenaires&rsquo; et chers &lsquo;coll\u00e8gues&rsquo;&#8230;\u00a0\u00bb<\/p>\n<\/p>\n<p><p>Bref, des tas de choses de cette sorte, aimablement dites sans nul doute, souvent un innocent sourire d&rsquo;ironie, parfois un qui ne peut pas s&#8217;emp\u00eacher de pouffer. Mais je suis s&ucirc;r que tout cela va bien se passer, parce qu&rsquo;on est entre gens de bonne compagnie, qui m\u00e8nent des politiques claires et compr\u00e9hensibles, qui laissent toutes un espace pour le compromis, voil\u00e0 que \u00e7a marche dans notre \u00e9poque postmoderne.<\/p>\n<\/p>\n<blockquote>\n<p><p>Ah, je vais m\u00eame dire un mot de la derni\u00e8re que m&rsquo;a fil\u00e9 la petite voix doucereuse&#8230;  &#8230; Je ne vais m\u00eame pas donner trop d&rsquo;importance \u00e0 cette derni\u00e8re confidence-hypoth\u00e8se, qui n&rsquo;est d&rsquo;ailleurs pas mal et pour cette raison, eh bien au contraire je vous la donne tout de m\u00eame : \u00ab\u00a0Certains disent m\u00eame que si on avait \u00e9vit\u00e9 l&rsquo;une ou l&rsquo;autre affaire de montage type-Navalny, suivie aussit\u00f4t de sanctions antirusses, le FSB aurait pu filer \u00e0 la DGSI fran\u00e7aise quelques pr\u00e9cieuses indications concernant de terroristes-touristes tch\u00e9tch\u00e8nes en balade en France&#8230; On dit tant de choses.\u00a0\u00bb<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Et puis, je rappellerais bien \u00e0 mon interlocuteur avec sa voix tant\u00f4t si aimable, tant\u00f4t doucereuse, tant\u00f4t un tantinet moqueuse, &ndash; eh bien je lui rappellerais si c&rsquo;\u00e9tait moi le ma&icirc;tre de la diplomatie glorieuse h\u00e9rit\u00e9e de Vergennes et de Talleyrand, si l&rsquo;historiette est vraie, je lui rappellerais, hein !, que le comportement russe  \u00e0 l&rsquo;\u00e9gard des minorit\u00e9s opprim\u00e9es tch\u00e9tch\u00e8nes ne fut pas glorieux, alors hein&#8230; (On pourrait envisager de nouvelles-anciennes sanctions r\u00e9trospectives, non ?) Je trouve qu&rsquo;avec beaucoup d&rsquo;intelligence comme j&rsquo;ai \u00e0 profusion, on parvient \u00e0 \u00eatre aussi b\u00eate et aussi coimpl\u00e8tement vain.<\/p>\n<\/p>\n<blockquote>\n<p><p>Eh bien ! C&rsquo;est \u00e0 ce moment, pr\u00e9cis\u00e9ment, que je me suis dis \u00e0 moi-m\u00eame, mais confidentiellement, <em>off-the-record <\/em>quoi, que c&rsquo;\u00e9tait pour moi un devoir en m\u00eame temps que la raison pr\u00e9cise de cette longue digression qui vous permet tout de m\u00eame de prendre connaissance de ceci qui, si elles sont d\u00e9crites sous une plume all\u00e8gre et un peu farceuse, de confidences tr\u00e8s s\u00e9rieuses, qui vous parlent du vrai des pr\u00e9occupations, r\u00e9flexions et actes des grands de ce monde (UE, France) en train de se faire se transformer (le monde), passant de sa rondeur presque parfaite, satisfaisant les sachants qui g\u00e8rent, en une entit\u00e9 remarquable de platitude, une terre-plate comme le disait l&rsquo;antique sagesse&#8230;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>(Vous savez que, tous comptes faits, je trouve l&rsquo;id\u00e9e d&rsquo;une terreplate et le reste s&rsquo;arrangeant pour tourner autour, eh bien pas si b\u00eate que cela.)<\/p>\n<\/p>\n<p><p>C&rsquo;est \u00e0 ce moment, pr\u00e9cis\u00e9ment, que je me suis dis \u00e0 moi-m\u00eame de laisser tomber et laisser toute la place \u00e0 l&rsquo;excellent Bruno Guigue, collaborateur de RT-France, dont il nous est dit ceci pr\u00e9cis\u00e9ment :<\/p>\n<\/p>\n<p><p>&laquo; <em>Ex-haut fonctionnaire, Bruno Guigue est un ancien \u00e9l\u00e8ve de l&rsquo;&Eacute;cole normale sup\u00e9rieure (Ulm) et de l&rsquo;&Eacute;cole nationale d&rsquo;administration. Chercheur en philosophie politique, analyste politique et observateur de la vie internationale, il est l&rsquo;auteur de plusieurs ouvrages et de nombreux articles. Il est actuellement enseignant \u00e0 l&rsquo;Universit\u00e9 de La R\u00e9union. Dernier titre paru : &lsquo;La fable du lib\u00e9ralisme qui sauve le monde&rsquo;, publi\u00e9 aux &Eacute;ditions Delga en 2019<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Place donc \u00e0 son texte du <a href=\"https:\/\/francais.rt.com\/opinions\/auteurs\/bruno-guigue\">22 octobre 2020<\/a> sur l&rsquo;action de longues ann\u00e9es d&rsquo;infamie, de cruaut\u00e9, de mensonges et de trahison, du bloc-BAO en Syrie. Cette mal\u00e9diction syrienne tra&icirc;nera sur ce qu&rsquo;il reste d&rsquo;\u00e2me au bloc-BAO, et surtout \u00e0 la France, et participera, je crois fermement et je l&rsquo;esp\u00e8re ardemment, au processus de d\u00e9sint\u00e9gration de ce qu&rsquo;il en reste, &ndash; du bloc-BAO et de la France. J&rsquo;esp\u00e8re que les moutons d\u00e9voreront les bergers antiSyst\u00e8me et feront leur office.<\/p>\n<\/p>\n<p><h4><em>Semper Phi<\/em><\/h4>\n<\/p>\n<p><p>(Un ami qui vous veut plut\u00f4t du bien.)<\/p>\n<\/p>\n<p><p>_________________________<\/p>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Le th\u00e9or\u00e8me de Bachar Al-Assad<\/h2>\n<\/p>\n<p><p>Selon l&rsquo;analyste politique et chercheur en philosophie politique Bruno Guigue, le jeu trouble des Occidentaux \u00e0 l&rsquo;\u00e9gard de forces djihadistes en Syrie a non seulement contribu\u00e9 \u00e0 prolonger la guerre, mais pourrait \u00e9galement se retourner contre eux.<\/p>\n<\/p>\n<p><p>Prolong\u00e9e par un acharnement criminel dont Erdogan n&rsquo;est que l&rsquo;instrument, la guerre qui s\u00e9vit en Syrie depuis dix ans a fait l&rsquo;effet d&rsquo;un r\u00e9v\u00e9lateur chimique. Protagonistes embusqu\u00e9s de ce bain de sang, les gouvernements am\u00e9ricain, britannique, fran\u00e7ais, turc, saoudien et qatari passeront \u00e0 la post\u00e9rit\u00e9 pour ce qu&rsquo;ils sont : les bourreaux d&rsquo;un peuple qui ne leur a rien fait. La trag\u00e9die syrienne a dissip\u00e9 leurs faux-semblants. Elle a expos\u00e9 au grand jour leurs strat\u00e9gies les plus retorses. Mais la pire de toutes a consist\u00e9 \u00e0 blanchir le terrorisme chez les autres.<\/p>\n<\/p>\n<p><p>Comment r\u00e9sister \u00e0 la naus\u00e9e devant la viscosit\u00e9 de ces politiciens qui, \u00e0 chaque attentat sur le sol fran\u00e7ais, se r\u00e9pandent en condamnations indign\u00e9es d&rsquo;une violence terroriste qu&rsquo;ils ont nourrie et encens\u00e9e ailleurs ? On se souvient qu&rsquo;il n&rsquo;y a pas si longtemps, la m\u00e9diasph\u00e8re occidentale d\u00e9ployait sa fausse dialectique pour faire de la branche syrienne d&rsquo;Al-Qa\u00efda une respectable organisation combattante. On nous disait que le Front Al-Nosra, c&rsquo;est ainsi qu&rsquo;il se nommait, finirait par se &laquo;normaliser&raquo;. Et il faudrait, sugg\u00e9rait Fran\u00e7ois Burgat sur une cha&icirc;ne publique, n\u00e9gocier pour de bon avec cette organisation destin\u00e9e \u00e0 faire partie du &laquo;futur de la Syrie&raquo;.<\/p>\n<\/p>\n<p><p>Son affiliation revendiqu\u00e9e \u00e0 Al-Qa\u00efda, son id\u00e9ologie haineuse et sectaire, sa pratique r\u00e9p\u00e9t\u00e9e des attentats aveugles frappant les civils, le r\u00e9gime de terreur obscurantiste qu&rsquo;elle r\u00e9pandait comme la peste partout o&ugrave; ses coupeurs de t\u00eate avaient l&rsquo;opportunit\u00e9 de s\u00e9vir ? Peccadilles. Une sorte de mutation g\u00e9n\u00e9tique devait valoir \u00e0 l&rsquo;organisation djihadiste concurrente de Daech, pour r\u00e9tribution de ses services rendus contre Damas, un v\u00e9ritable brevet de respectabilit\u00e9. C&rsquo;est ainsi que la diplomatie occidentale faisait des miracles. De son chapeau de magicien, elle sortait des terroristes mod\u00e9r\u00e9s, des extr\u00e9mistes d\u00e9mocrates, des coupeurs de t\u00eate humanistes, des mangeurs de foie philanthropes.<\/p>\n<\/p>\n<p><p>Cette op\u00e9ration de blanchiment de la branche syrienne d&rsquo;Al-Qa\u00efda, en effet, se d\u00e9roulait au moment o&ugrave; cette organisation confortait son h\u00e9g\u00e9monie politique et militaire dans le nord de la Syrie. La pr\u00e9destinant \u00e0 jouer un r\u00f4le majeur au lendemain de l&rsquo;effondrement attendu de l&rsquo;Etat syrien, ce succ\u00e8s lui valait les faveurs des puissances occidentales et r\u00e9gionales d\u00e9cid\u00e9es \u00e0 abattre le dernier Etat la\u00efc et progressiste du Moyen-Orient. Peu importaient alors le co&ucirc;t humain et le prix politique de ce consentement anticip\u00e9 \u00e0 l&rsquo;instauration en Syrie d&rsquo;un pouvoir sectaire et mafieux. La chute de Bachar el-Assad \u00e9tait un jeu, disait-on, qui en valait la chandelle.<\/p>\n<\/p>\n<p><p>Le terrorisme remaquill\u00e9 pour les besoins de la cause rendait &minus; et il rend encore &minus; des services inesp\u00e9r\u00e9s \u00e0 la vaste coalition contre la Syrie souveraine. Cette connivence des &Eacute;tats occidentaux et des monarchies p\u00e9troli\u00e8res avec les rejetons frelat\u00e9s d&rsquo;Al-Qa\u00efda signait la r\u00e9inscription simultan\u00e9e des deux avatars du terrorisme takfiriste dans l&rsquo;agenda strat\u00e9gique occidental. La destruction de l&rsquo;Etat syrien, objectif num\u00e9ro un de l&rsquo;axe Washington-Riyad-Paris-Londres-Ankara-Doha, second\u00e9 en coulisses par Tel-Aviv, \u00e9tait une fin qui justifiait tous les moyens, et la perspective d&rsquo;un \u00e9mirat extr\u00e9miste faisait clairement partie du plan.<\/p>\n<\/p>\n<p><p>Pour le faire aboutir, les puissances \u00e9trang\u00e8res coalis\u00e9es contre le dernier r\u00e9gime nationaliste arabe se r\u00e9partissaient cyniquement les r\u00f4les. Dans son combat sans merci contre la Syrie, les tueurs d&rsquo;Al-Qa\u00efda pouvaient ainsi compter sur leurs pr\u00e9cieux amis : la Turquie leur livrait des armes, Isra\u00ebl soignait leurs bless\u00e9s, le Qatar leur versait un ch\u00e8que \u00e0 la fin du mois, et le quotidien <em>Le Monde<\/em> les faisait passer pour des enfants de ch&oelig;ur. Qui se souvient qu&rsquo;en 2013, lorsque le Front Al-Nosra s&rsquo;est empar\u00e9 du village chr\u00e9tien de Maaloula, <a href=\"https:\/\/www.lemonde.fr\/blog\/syrie\/2013\/09\/19\/syrie-lattaque-de-maaloula-moins-dangereuse-pour-les-chretiens-que-certaines-couvertures-mediatiques\/\">ce quotidien osait nier<\/a> que les extr\u00e9mistes aient tu\u00e9 le moindre civil, alors qu&rsquo;on pouvait voir sur la BBC, au m\u00eame moment, les obs\u00e8ques religieuses des victimes de cette agression ?<\/p>\n<\/p>\n<p><p>C&rsquo;\u00e9tait l&rsquo;\u00e9poque o&ugrave; la pr\u00e9tendue &laquo;coalition internationale&raquo;, lors de l&rsquo;offensive de Daech vers Palmyre, s&rsquo;abstenait de tirer la moindre cartouche, ce sauf-conduit offert aux terroristes illustrant la parfaite duplicit\u00e9 de l&rsquo;antiterrorisme proclam\u00e9 \u00e0 Washington et \u00e0 Paris. Entre la pouss\u00e9e du pseudo-Etat islamique sur l&rsquo;axe Palmyre-Damas et celle du Front Al-Nosra sur l&rsquo;axe Alep-Damas, le r\u00eave des ennemis de Bachar el-Assad semblait alors se r\u00e9aliser. Mais c&rsquo;\u00e9tait sans compter sur la r\u00e9sistance du peuple syrien et la loyaut\u00e9 de son arm\u00e9e. La mobilisation g\u00e9n\u00e9rale de la pi\u00e9taille takfiriste devait co&ucirc;ter un milliard de dollars par an aux p\u00e9tromonarchies du Golfe. Achemin\u00e9e aux organisations terroristes par l&rsquo;interm\u00e9diaire de la CIA, cette manne n&rsquo;a pourtant pas suffi \u00e0 provoquer la chute de Damas.<\/p>\n<\/p>\n<p><p>Car c&rsquo;\u00e9tait sans compter, non plus, sur la capacit\u00e9 du gouvernement syrien \u00e0 nouer les alliances n\u00e9cessaires avec des partenaires fiables. Afin de desserrer l&rsquo;\u00e9treinte mortif\u00e8re des sponsors de la terreur, Damas a obtenu le pr\u00e9cieux concours de T\u00e9h\u00e9ran, Moscou et P\u00e9kin. En r\u00e9alit\u00e9, il n&rsquo;y a jamais eu de guerre civile en Syrie : d\u00e9clench\u00e9e par les puissances imp\u00e9rialistes, cette guerre est d&#8217;embl\u00e9e un conflit international de grande ampleur o&ugrave; une coalition s&rsquo;est form\u00e9e pour vaincre la coalition adverse. Sur le th\u00e9\u00e2tre des op\u00e9rations, aujourd&rsquo;hui encore, les seules forces en pr\u00e9sence sont les bandes arm\u00e9es du takfir sponsoris\u00e9 d&rsquo;un c\u00f4t\u00e9, agr\u00e9ment\u00e9es de quelques forces sp\u00e9ciales occidentales en vadrouille ; et les forces militaires de l&rsquo;Etat syrien soutenues par leurs alli\u00e9s russes, iraniens et libanais, de l&rsquo;autre.<\/p>\n<\/p>\n<p><p>Devant ce constat, tout le reste n&rsquo;est que litt\u00e9rature. Les distinctions entre rebelles &laquo;d\u00e9mocrates&raquo;, &laquo;mod\u00e9r\u00e9s&raquo;, &laquo;la\u00efcs&raquo;, &laquo;islamistes&raquo; ou &laquo;djihadistes&raquo; sont des stupidit\u00e9s sans nom, dont le seul effet est de jeter un voile pudique sur une n\u00e9buleuse terroriste dont l&rsquo;intention est parfaitement claire : imposer par la force un pouvoir sectaire et collaborateur de l&rsquo;imp\u00e9rialisme. Si les puissances occidentales et r\u00e9gionales qui ont aliment\u00e9 ce brasier avaient cru aux soi-disant rebelles mod\u00e9r\u00e9s, elles n&rsquo;auraient pas blanchi le Front Al-Nosra, accr\u00e9dit\u00e9 au tournant de 2014 comme successeur potentiel du r\u00e9gime \u00e0 abattre, tout en s&rsquo;interdisant de combattre Daech lorsque cette organisation affrontait l&rsquo;arm\u00e9e syrienne.<\/p>\n<\/p>\n<p><p>Aujourd&rsquo;hui encore, les milliers de terroristes qui contr\u00f4lent la poche d&rsquo;Idleb appartiennent au dernier avatar d&rsquo;Al-Qa\u00efda, Hayat Tahrir Al-Cham, plac\u00e9 sous perfusion militaire turque. Les rotatives de la propagande ont longtemps accr\u00e9dit\u00e9 la fable d&rsquo;une guerre civile opposant un r\u00e9gime sanguinaire \u00e0 une opposition d\u00e9mocratique. Mais tout le monde a compris que la r\u00e9alit\u00e9 du conflit syrien, depuis dix ans, c&rsquo;est la lutte qui oppose un conglom\u00e9rat terroriste sponsoris\u00e9 et une arm\u00e9e nationale qui d\u00e9fend son pays contre l&rsquo;invasion \u00e9trang\u00e8re.<\/p>\n<\/p>\n<p><p>Depuis 2011, les avatars successifs de la filiale semi-clandestine de la CIA qui porte la d\u00e9nomination d&rsquo;Al-Qa\u00efda ont accueilli en Syrie un flux incessant de mercenaires lobotomis\u00e9s, avides d&rsquo;en d\u00e9coudre avec les m\u00e9cr\u00e9ants et les apostats. Cette injection massive de fanatisme mortif\u00e8re a eu pour effet de prolonger une guerre qui n&rsquo;en finit pas. Mais elle a aussi r\u00e9pandu ses miasmes aux quatre coins du globe. Revenant comme un boomerang, elle a frapp\u00e9 partout. Bachar el-Assad avait averti les Europ\u00e9ens que leur duplicit\u00e9 finirait par se retourner contre eux. L&rsquo;ignorance de ce th\u00e9or\u00e8me n&rsquo;en finit pas de pr\u00e9senter l&rsquo;addition.<\/p>\n<\/p>\n<p><h4>Bruno Guigue<\/h4><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Plong\u00e9e \u00ab\u00a0tout schuss\u00a0\u00bb dans le cloaque fran\u00e7ais 28 octobre 2020 &ndash; Rassurez-vous, je ne vais pas parler de Codiv19, je veux dire : pas ici, pas pour l&rsquo;instant, pas pour ce cas, pas dissimul\u00e9 pour autant qu&rsquo;on y viendra, et vite&#8230; Je vais parler de cet ensemble BlocBAO-UE-France, avec France soi-m\u00eame en bout de cha&icirc;ne,&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[831,19263,20360,18721,13767,19495,2617,2707,20359,916,5646,3867],"class_list":["post-79498","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-a","tag-bruno","tag-darmanin","tag-dgsi","tag-fsb","tag-guigue","tag-macron","tag-moscou","tag-novolny","tag-poutine","tag-sanctions","tag-syrie"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79498"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79498\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}