{"id":79509,"date":"2020-11-05T17:16:00","date_gmt":"2020-11-05T17:16:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2020\/11\/05\/la-belle-fureur-de-jhk\/"},"modified":"2020-11-05T17:16:00","modified_gmt":"2020-11-05T17:16:00","slug":"la-belle-fureur-de-jhk","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2020\/11\/05\/la-belle-fureur-de-jhk\/","title":{"rendered":"La Belle-Fureur de JHK"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">La Belle-Fureur de JHK<\/h2>\n<\/p>\n<p><p>Comme les Qu\u00e9b\u00e9cois aiment \u00e0 se voir li\u00e9s \u00e0 ce qu&rsquo;ils nomment la Belle-Province, nous nommerions volontiers nommer le sentiment que l&rsquo;on distingue chez James Howard Kunstler, ou JHK, et qui le lie \u00e0 sa perception du temps : la belle-Fureur. Les stupides Parisiens qui se situent progressistes-soci\u00e9taux et de l&rsquo;univers postmoderniste du simulacre de communication, se plaignent aupr\u00e8s d&rsquo;eux-m\u00eames de ne pas comprendre grand&rsquo;chose aux USA-qui-votent-Trump, comme si, d\u00e9cid\u00e9ment, les USA \u00e9taient peupl\u00e9s de ces <em><a href=\"https:\/\/www.dedefensa.org\/article\/french-touch-nous-sommes-tous-les-deplorables\">Deplorables<\/a> <\/em>que la grossi\u00e8re et puante Hillary ex\u00e9cutaient en octobre 2016 d&rsquo;un ricanant m\u00e9pris.<\/p>\n<\/p>\n<p><p>Cette ann\u00e9e 2020, c&rsquo;est Joe Biden qui l&rsquo;a remplac\u00e9e \u00e0 la manouvre, personnage d\u00e9c\u00e9r\u00e9br\u00e9 par tant de corruption, automate fr\u00f4leur et peloteur, idole des salons parisiens puisqu&rsquo;ennemi de Trump. Les Parisiens ne comprennent rien \u00e0 la profondeur sans fin et sans fond de la corruption qu&rsquo;est l&rsquo;Am\u00e9rique, donc ils ne comprennent rien \u00e0 James Howard Kunstler, qui est une sorte d&rsquo;impr\u00e9cateur \u00e9crasant de son ironie revigorant, comme une sorte de un Jack London d\u00e9signant avec fureur l&rsquo;Am\u00e9rique corrompue qu&rsquo;il accable de ce que nous d\u00e9signons d\u00e9cid\u00e9ment comme la Belle-Fureur, comme les Qu\u00e9b\u00e9cois disent la Belle-Province.<\/p>\n<\/p>\n<p><p>Kunstler est de ces Am\u00e9ricains qui ne laissent rien passer \u00e0 l&rsquo;Am\u00e9rique am\u00e9ricaniste dont il hume l&rsquo;imposture et le simulacre, r\u00e9guli\u00e8rement et librement, depuis tant d&rsquo;ann\u00e9es. Sociologue autodidacte et auteur de renom sur les questions urbaines et de civilisation, Kunstler s&rsquo;est fait tout seul depuis les nombreux emplois divers de son adolescence, jusqu&rsquo;\u00e0 b\u00e2tir une renomm\u00e9e d&rsquo;auteur de th\u00e9\u00e2tre et de brillant commentateur ind\u00e9pendant du monde acad\u00e9mique, d&rsquo;abord votant d\u00e9mocrate et soutenant les causes progressistes ; puis Kunstler a, depuis ce temps, navigu\u00e9 vers une sorte de droite ind\u00e9pendante, presque de l&rsquo;anarchisme de droite \u00ab\u00a0\u00e0-la-fran\u00e7aise\u00a0\u00bb, pour mieux d\u00e9noncer les corruptions, les arnaques, &laquo; <em>les copains et les coquins<\/em> &raquo; qui s&rsquo;en donnent \u00e0 c&oelig;ur joie dans le mar\u00e9cage du Syst\u00e8me. Son aversion pour Biden, qu&rsquo;il per\u00e7oit en tant que cr\u00e9ature puante du Syst\u00e8me, personnage totalement priv\u00e9 d&rsquo;existence et d&rsquo;essence, transparent, mati\u00e8re sans mati\u00e8re litt\u00e9ralement, gouvernent son jugement impitoyable et sa Belle-Fureur.<\/p>\n<\/p>\n<p><p>On peut et l&rsquo;on doit suivre Kunstler, JHK, dans ses attaques bihebdomadaires contre un Syst\u00e8me qui nous \u00e9crase et nous oppresse. S&rsquo;il est assez retenu contre Trump, c&rsquo;est parce que Trump doit \u00eatre \u00e9cras\u00e9 par le Syst\u00e8me, parce qu&rsquo;ainsi le veut le Syst\u00e8me, et que par cons\u00e9quent ainsi devons-nous avoir un certain devoir d&rsquo;indulgence par humanit\u00e9 trop insister, pour Donald Trump. Ainsi pense JHK, sans tendresse particuli\u00e8re pour Trump donc, mais bon connaisseur de l&rsquo;infamie dont Biden est le clone infiniment triste. Voici l&rsquo;\u00e9lection vue par Kunstler, la veille de l&rsquo;\u00e9lection, le jour de l&rsquo;\u00e9lection, les perspectives de l&rsquo;\u00e9lection, au milieu du chaudron bouillonnant de Washington D.C. parodiant \u00ab\u00a0D.C.-la-folle\u00a0\u00bb. Si les Parisiens et les salons pouvaient avoir une ligne par page de leurs pens\u00e9es, une minute par heure de leur temps qui s&rsquo;inspirassent de Kunstler, ce serait d\u00e9j\u00e0 une bonne \u00e9quip\u00e9e de l&rsquo;esprit.<\/p>\n<\/p>\n<p><p>Le <em>Sakerfrancophone<\/em>, qui manque rarement une chronique de JHK, a fait diligence cette fois. Il nous donne en traduction les textes des <a href=\"https:\/\/lesakerfrancophone.fr\/laffreuse-confrontation\">2 et 3 novembre 2020<\/a> (dates aux USA) du site <a href=\"https:\/\/kunstler.com\/clusterfuck-nation\/the-awful-reckoning\/\">Kunstler.com<\/a> de JHK, du spectateur en fureur qu&rsquo;est James Howard Kunstler.<\/p>\n<\/p>\n<p><h4><em>dde.org<\/em><\/h4>\n<\/p>\n<p><p>______________________<\/p>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_a.deepgreen\" style=\"color:#75714d; font-size:2em\">L&rsquo;affreuse confrontation<\/h2>\n<\/p>\n<blockquote>\n<p><p>Les historiens du futur, qui feront frire des cloportes sur leur feu de camp, se souviendront avec \u00e9merveillement et naus\u00e9e de l&rsquo;\u00e9lection de 2020 et de la tentative de d\u00e9molition contr\u00f4l\u00e9e des &Eacute;tats-Unis par la R\u00e9bellion du R\u00e9veil et son avatar incongru, Joe Biden, le Saint-Esprit de l&rsquo;arnaque et du <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Gaslighting\">d\u00e9tournement cognitif<\/a>. Toutes les forces de l&#8217;empire \u00e9taient rassembl\u00e9es pour le soutenir, comme derri\u00e8re l&rsquo;effigie sacr\u00e9e d&rsquo;un obscur saint au cours une procession vers l&rsquo;\u00e9glise, et pourtant, tout ce que les \u00e9lecteurs ont vu, c&rsquo;est un personnage pitoyable hurlant devant des voitures, un vieux chien aboyant inutilement sur un parking dans l&rsquo;obscurit\u00e9 qui s&rsquo;installe.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Et puis il y avait Trump&hellip; un seul mot, Trump&hellip; pas d&rsquo;honneur, car les L\u00e9gions du R\u00e9veil parlaient du d\u00e9test\u00e9 POTUS&hellip; Trump, qui violait toutes leurs normes, mena\u00e7ait leurs bonus, et contestait leurs ridicules shibboleths identitaires de racisme, sexisme, misogynie, homophobie, islamophobie&hellip; le Golem d&rsquo;or de la grandeur convoquant les personnes d\u00e9plorablement non r\u00e9veill\u00e9es dans leurs affreux chapeaux rouges franchissant collines et vall\u00e9es, par milliers, pour l&rsquo;entendre parler sans interm\u00e9diaires et le regarder se d\u00e9hancher avec ce charmant pas de danse sur des airs disco de sa folle jeunesse, et dont le moral \u00e0 toute \u00e9preuve a permis de dissiper la mal\u00e9diction du r\u00e9veil lanc\u00e9e par les l\u00e9gions de n\u00e9o-pa\u00efens de banlieue en col\u00e8re, jusqu&rsquo;\u00e0 ce que nous arrivions au d\u00e9compte \u00e9lectoral du 3 novembre &ndash; et alors la vraie comp\u00e9tition a commenc\u00e9.<\/p>\n<\/p>\n<p><p>Et maintenant&hellip; ? tout le monde se pose la question, lui, elle et tous les autres. Pourquoi devrait-on croire les sondages, \u00e9tant donn\u00e9 la corruption l\u00e2che de toutes les branches m\u00e9diatiques &ndash; et les sondages en font partie, bien s&ucirc;r. Mais les <em>&laquo; affaires &raquo;<\/em> de la famille Biden \u00e0 l&rsquo;\u00e9tranger continuent de couver en arri\u00e8re-plan, comme un feu de racines dans une for\u00eat de pins, attendant de reprendre feu. Il s&rsquo;av\u00e8re que la soci\u00e9t\u00e9 chinoise que les Biden courtisaient en tant que <em>&laquo; partenaires &raquo;<\/em> (CEFC China Energy) ne pouvait pas \u00eatre plus manifestement un agent de l&rsquo;appareil de renseignement du Parti communiste chinois. M\u00eame Hunter le savait, puisque son accord avec la CEFC pour la construction d&rsquo;un terminal de gaz naturel en Louisiane a \u00e9t\u00e9 d\u00e9voil\u00e9 fin 2017. Un enregistrement audio trouv\u00e9 sur le l\u00e9gendaire ordinateur portable de Hunter le fait parler de Ho Chiping (alias Patrick Ho), le dirigeant du CEFC :<\/p>\n<\/p>\n<p><p>Un autre journaliste du <em>New York Times<\/em> m&rsquo;appelle au sujet de ma repr\u00e9sentation de Patrick Ho &ndash; le putain d&rsquo;espion en chef chinois qui a lanc\u00e9 la soci\u00e9t\u00e9 que mon partenaire, qui p\u00e8se 323 milliards de dollars, a fond\u00e9e et qui a maintenant disparu. L&rsquo;homme le plus riche du monde, qui \u00e9tait mon partenaire, a disparu. Il a disparu depuis la derni\u00e8re fois que je l&rsquo;ai vu dans son appartement \u00e0 58 millions de dollars dans le cadre d&rsquo;un contrat de 4 milliards de dollars pour la construction du putain de plus grand port de GNL au monde. Et je re\u00e7ois des appels du District Sud de New York de la part du procureur am\u00e9ricain lui-m\u00eame.<\/p>\n<\/p>\n<p><p>M. Ho a fini par \u00eatre inculp\u00e9 par le District Sud de New York du DOJ pour corruption et blanchiment d&rsquo;argent. Hunter s&rsquo;\u00e9tait port\u00e9 volontaire pour \u00eatre l&rsquo;un des avocats de M. Ho. Il s&rsquo;est av\u00e9r\u00e9 que l&rsquo;influence de la famille Biden n&rsquo;a pas beaucoup aid\u00e9. M. Ho a \u00e9t\u00e9 condamn\u00e9, a fait son temps dans la m\u00eame prison f\u00e9d\u00e9rale \u00e0 Manhattan o&ugrave; Jeffrey Epstein est mort, et a \u00e9t\u00e9 d\u00e9port\u00e9 \u00e0 Hong Kong en 2019. Le CEFC a rapidement \u00e9t\u00e9 mis en faillite par son sponsor, le PCC. Malgr\u00e9 toutes ces sordides complications, la famille Biden s&rsquo;en est sortie avec au moins 4,8 millions de dollars, achemin\u00e9s par une compagnie fant\u00f4me du PCC appel\u00e9e Hudson West III sur le compte bancaire du cabinet d&rsquo;avocats Owasco de Hunter.<\/p>\n<\/p>\n<p><p>Oh, et il y a un \u00e9trange effet miroir de notre <em>marais<\/em> dans tout cela : Le principal exploit de la CEFC pendant les ann\u00e9es de magouille des Biden a \u00e9t\u00e9 l&rsquo;achat de 14 % des parts du g\u00e9ant russe du p\u00e9trole et du gaz, Rosneft, pour aider la Chine \u00e0 contourner les sanctions am\u00e9ricaines sur les ventes de p\u00e9trole russe. Devinez qui \u00e9tait l&rsquo;un des avocats travaillant pour Rosneft : Christopher Wray, juste avant qu&rsquo;il ne devienne directeur du FBI. Et devinez qui est assis sur l&rsquo;ordinateur portable de Hunter Biden depuis au moins d\u00e9cembre 2019. Oh, le FBI. Et devinez quoi d&rsquo;autre : les fichiers de Rosneft ont depuis \u00e9t\u00e9 supprim\u00e9s par l&rsquo;ancien cabinet d&rsquo;avocats de M. Wray, King and Spalding.<\/p>\n<\/p>\n<p><p>Maintenant, la question est de savoir si cette boule puant l&rsquo;escroquerie va exploser en proc\u00e9dure officielle apr\u00e8s l&rsquo;\u00e9lection. Nous sommes inform\u00e9s que le DOJ a ouvert une enqu\u00eate sur le blanchiment d&rsquo;argent de Hunter Biden il y a un an, lorsque des all\u00e9gations ont \u00e9t\u00e9 faites sur son <em>&laquo; travail &raquo;<\/em> \u00e0 85 000 dollars par mois au sein du conseil d&rsquo;administration de la soci\u00e9t\u00e9 ukrainienne Burisma NatGas, qui s&rsquo;est d\u00e9roul\u00e9e de 2014 \u00e0 2019, rapportant des millions \u00e0 Hunter. Le DOJ se penche-t-il \u00e9galement sur les manigances du CEFC ? Le DOJ avait des mandats de la FISA contre l&rsquo;entreprise par le biais de l&rsquo;affaire Patrick Ho, mais la FISA a un statut juridique sp\u00e9cial et les preuves peuvent rester cach\u00e9es ind\u00e9finiment.<\/p>\n<\/p>\n<p><p>Et si, par un myst\u00e9rieux acte de Dieu (ou une fraude \u00e9lectorale), Joe Biden parvient \u00e0 se faire \u00e9lire POTUS, comment pourrait-il \u00eatre inaugur\u00e9 avec sa famille et lui-m\u00eame emp\u00eatr\u00e9s dans une affaire d&rsquo;escroquerie qui implique le service de renseignements du Parti communiste chinois ? Cela n&rsquo;arrivera pas. M. Biden sera oblig\u00e9 de se disqualifier. Est-ce que Kamala Harris deviendrait alors POTUS par d\u00e9faut ? Il n&rsquo;y a pas de pr\u00e9c\u00e9dent pour un pr\u00e9sident \u00e9lu qui d\u00e9missionne avant d&rsquo;avoir pr\u00eat\u00e9 serment. Il n&rsquo;y a aucun doute qu&rsquo;il y aura des poursuites judiciaires \u00e0 ce sujet et qu&rsquo;elles conduiront rapidement \u00e0 un jugement de la Cour supr\u00eame.<\/p>\n<\/p>\n<p><p>En m\u00eame temps, il faut \u00e9galement s&rsquo;attendre \u00e0 une attaque totale du lobby Lawfare contre les r\u00e9sultats des votes individuels des &Eacute;tats et \u00e0 la traduction de votes douteux en d\u00e9l\u00e9gations du coll\u00e8ge \u00e9lectoral. Lawfare mettra \u00e0 profit tous les tours de passe-passe de la n\u00e9cromancie juridique pour faire fonctionner cette escroquerie en faveur du Parti D\u00e9mocrate. Et les avocats de M. Trump ne s&rsquo;y opposeront pas. Et qu&rsquo;est-ce que cela apportera \u00e0 la campagne Lawfare, de toute fa\u00e7on, alors que M. Biden est enseveli sous des all\u00e9gations de faute criminelle ? Et &ndash; pour ne pas l&rsquo;oublier, comme on dit &ndash; que se passera-t-il si, apr\u00e8s les \u00e9lections et avant le 20 janvier, MM. Barr et Durham finissent par mettre en accusation les responsables du <em>RussiaGate<\/em> ? Ne s&rsquo;agira-t-il pas d&rsquo;un g\u00e2chis politique mondial ? Pensez-vous que les march\u00e9s boursiers et obligataires vont l&rsquo;adorer ?<\/p>\n<\/p>\n<p><p>En attendant, allons-nous assister \u00e0 l&rsquo;extravagance des Antifas et de BLM qui br&ucirc;lent et pillent les villes d&rsquo;une mer \u00e0 l&rsquo;autre ? Je pose la question : comment cela pourrait-il ne pas se produire ? Ils ont r\u00e9p\u00e9t\u00e9 pour le Big Show toute l&rsquo;ann\u00e9e. Avec les nouveaux confinements Covid-19, les arm\u00e9es instables de combattants de rue v\u00eatus de noir auront h\u00e2te de r\u00e9activer l&rsquo;espace social qu&rsquo;Antifa et BLM ont si bien pr\u00e9par\u00e9. Les \u00e9meutes sont amusantes ! Surtout lorsque la police n&rsquo;est pas autoris\u00e9e \u00e0 intervenir efficacement pour les arr\u00eater. D\u00e9truire, br&ucirc;ler et piller sont des activit\u00e9s amusantes, comme Halloween et No\u00ebl r\u00e9unis !<\/p>\n<\/p>\n<p><p>Je voterai demain pour M. Trump dans ma petite tentative d&#8217;emp\u00eacher le Parti D\u00e9mocrate de mettre ses mitaines d\u00e9prav\u00e9es sur les leviers du gouvernement. Je vous ferai part d&rsquo;une mise \u00e0 jour post-\u00e9lectorale, ici m\u00eame, mercredi, mais peut-\u00eatre pas \u00e0 l&rsquo;aube.<\/p>\n<\/p>\n<p><h4>JHK<\/h4>\n<\/p>\n<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Mise \u00e0 jour-I (4 novembre 2020, 09H5o)<\/h2>\n<\/p>\n<p><p>L&rsquo;\u00e9lection s&rsquo;est d\u00e9roul\u00e9e comme pr\u00e9vu ici &ndash; c&rsquo;est-\u00e0-dire qu&rsquo;elle n&rsquo;a pas \u00e9t\u00e9 r\u00e9solue le lendemain matin, les \u00e9meutiers Antifa et du BLM \u00e9tant d\u00e9j\u00e0 dans les rues de Washington D.C.<\/p>\n<\/p>\n<p><p>Portland, Oregon, reste dans un tumulte continu apr\u00e8s quatre mois de violence et de destruction, et le maire Ted Wheeler a remport\u00e9 la r\u00e9\u00e9lection contre la <em>&laquo; candidate Antifa &raquo;<\/em> Sarah Iannarone. Portland la chanceuse.<\/p>\n<\/p>\n<p><p>En dehors des &Eacute;tats en balance, les <em>swing states<\/em> encore en jeu, les marges \u00e9taient \u00e9tonnamment d\u00e9s\u00e9quilibr\u00e9es. Le charisme rayonnant de Joe Biden a fonctionn\u00e9 dans les &Eacute;tats c\u00f4tiers bleus habituels &ndash; Californie 65 % contre 33 %, NY 55 % contre 43 % &ndash; mais les marges de M. Trump \u00e9taient tout aussi d\u00e9s\u00e9quilibr\u00e9es dans les &Eacute;tats rouges du centre- Oklahoma 65 % contre 32 %, Tenessee 60 % contre 37 %, Montana 56 %contre\u00e0 41 %. M. Biden a remport\u00e9 une victoire \u00e9clatante dans l&rsquo;&Eacute;tat de Virginie lorsque les comt\u00e9s dortoirs du Deep State, situ\u00e9s \u00e0 c\u00f4t\u00e9 de Washington, sont rentr\u00e9s tard dans la nuit. Mais le pr\u00e9sident a gagn\u00e9 de fa\u00e7on convaincante en Floride, Ohio et Texas.<\/p>\n<\/p>\n<p><p>Pour l&rsquo;instant, \u00e0 9 heures du matin, la course s&rsquo;articule autour des suspects habituels. M. Trump a gagn\u00e9 un demi pour cent dans le Michigan avec 91% des votes compt\u00e9s ; M. Biden a gagn\u00e9 sept dixi\u00e8mes dans le Wisconsin, avec 95% dans&hellip; l&rsquo;attente des r\u00e9sultats de Green Bay (retard\u00e9s, apparemment, parce qu&rsquo;une machine de traitement des votes n&rsquo;a plus d&rsquo;encre (!). Des marges similaires en Caroline du Nord&hellip; pas si proches en G\u00e9orgie, avec le pr\u00e9sident en t\u00eate avec une bonne avance de 2 %, et enfin la sombre gueule du loup, la Pennsylvanie, o&ugrave; Trump m\u00e8ne de plus de dix points de pourcentage (@700 000 votes) ce matin, mais o&ugrave; l&rsquo;on attend plus d&rsquo;un million de bulletins de vote par correspondance.<\/p>\n<\/p>\n<p><p>N&rsquo;oublions pas la remarque plut\u00f4t imprudente faite par le procureur g\u00e9n\u00e9ral de la Pennsylvanie, Josh Shapiro, le soir d&rsquo;Halloween, selon laquelle <em>&laquo; si tous les votes sont additionn\u00e9s, M. Trump va perdre &raquo;<\/em>. Il avait l&rsquo;air plut\u00f4t s&ucirc;r de lui. Si je comprends bien, la Cour supr\u00eame de cet \u00e9tat a r\u00e9cemment d\u00e9cid\u00e9 que les comt\u00e9s pouvaient continuer \u00e0 traiter les votes par correspondance jusqu&rsquo;\u00e0 vendredi et, plus important encore, qu&rsquo;ils n&rsquo;exigeaient pas de cachet de la poste ou d&rsquo;authentification de la signature &ndash; ce qui semblerait \u00eatre une invitation facile \u00e0 la fraude \u00e9lectorale.<\/p>\n<\/p>\n<p><p>Le pr\u00e9sident s&rsquo;est engag\u00e9 mardi soir \u00e0 porter l&rsquo;affaire devant la Cour supr\u00eame des &Eacute;tats-Unis o&ugrave;, je pense, la d\u00e9cision Pennsylvanie sera rejet\u00e9e comme \u00e9tant manifestement mal fond\u00e9e. Les forces de la loi D\u00e9mocrates peuvent-elles contourner ce probl\u00e8me ? Je ne vois pas comment, mais je ne suis pas un avocat constitutionnel. Les D\u00e9mocrates ont travaill\u00e9 dur ces derni\u00e8res ann\u00e9es pour fabriquer le r\u00e9cit inepte et faux selon lequel toute proc\u00e9dure d&rsquo;identification des \u00e9lecteurs \u00e9quivaut \u00e0 une <em>&laquo; suppression &raquo;<\/em>. L&rsquo;Am\u00e9rique doit se faire une id\u00e9e claire de ce point de vue.<\/p>\n<\/p>\n<p><p>La justice a-t-elle d&rsquo;autres tours dans sa manche ? Je m&rsquo;y attends, mais le pr\u00e9sident a eu des mois pour planifier sa propre d\u00e9fense contre la menace d&rsquo;un coup d&rsquo;\u00e9tat du lobby judiciare, donc maintenant nous allons voir le jeu se d\u00e9rouler. En attendant, nous attendons le chaos dans les rues, tol\u00e9r\u00e9 et encourag\u00e9 par le parti de Joe Biden, comme si cela allait le rendre sympathique \u00e0 la nation.<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Mise \u00e0 jour-II (5 Novembre 2020, 9H10)<\/h2>\n<\/p>\n<p><p>Jeudi matin et l&rsquo;\u00e9lection reste non r\u00e9solue avec la perspective d&rsquo;une longue bataille juridique \u00e0 venir. La caract\u00e9ristique la plus frappante de tout cela est l&rsquo;incapacit\u00e9 de l&rsquo;Am\u00e9rique \u00e0 mettre en place un syst\u00e8me \u00e9lectoral juste, honn\u00eate et coh\u00e9rent. Au lieu de cela, nous ajoutons des couches de complexit\u00e9 qui ne font qu&rsquo;augmenter la probabilit\u00e9 d&rsquo;\u00e9chec et les possibilit\u00e9s de tricherie. Mais n&rsquo;oubliez pas que l&rsquo;une des caract\u00e9ristiques de cette longue urgence est l&rsquo;impuissance et l&rsquo;incomp\u00e9tence croissantes du gouvernement f\u00e9d\u00e9ral \u00e0 faire face \u00e0 quoi que ce soit.<\/p>\n<\/p>\n<p><p>Quant aux signaux d&rsquo;alerte, nous avons le d\u00e9p\u00f4t massif de mercredi matin \u00e0 4 heures de 131 000 voix, toutes pour M. Biden, aucune pour M. Trump, \u00e9manant des comt\u00e9s de Shiawassee et d&rsquo;Antrim, dans le Michigan, dont la population est respectivement de 68 000 et 23 000 habitants. Une personne de la cha&icirc;ne a d\u00e9clar\u00e9 qu&rsquo;il s&rsquo;agissait d&rsquo;une <em>&laquo; faute de frappe &raquo;<\/em>, mais les r\u00e9sultats ne montrent pas que le faux chiffre a \u00e9t\u00e9 r\u00e9tract\u00e9. Une action similaire de 27 000 personnes, toutes pour Biden, est venue de Philadelphie, sans explication. Et ce n&rsquo;\u00e9tait que le d\u00e9but d&rsquo;un effort de fabrication en gros de bulletins de vote par correspondance du Parti D\u00e9mocrate qui se poursuit jusqu&rsquo;\u00e0 aujourd&rsquo;hui.<\/p>\n<\/p>\n<p><p>Les d\u00e9mocrates ont mis sur pied une <em>&laquo; \u00e9quipe de transition &raquo;<\/em> pour Biden afin de donner une l\u00e9gitimit\u00e9 \u00e0 leur projet, en esp\u00e9rant que les grands m\u00e9dias vont amplifier l&rsquo;id\u00e9e que c&rsquo;est fini&hellip; mais ce n&rsquo;est pas fini. La campagne Trump a \u00e9galement d\u00e9clar\u00e9 la victoire en Pennsylvanie, dans le Michigan et dans d&rsquo;autres &Eacute;tats qui sont cens\u00e9s continuer \u00e0 faire des d\u00e9puoillements. Tout cela tend vers la Cour Supr\u00eame o&ugrave; certaines personnes vont devoir <em>&laquo; s&rsquo;expliquer &raquo;<\/em>.<\/p>\n<\/p>\n<p><p>Il y a de fortes chances pour que tout cela entre dans une phase d&rsquo;intransigeance violente, avec des foules d&rsquo;<em>&laquo; alli\u00e9s &raquo;<\/em> des D\u00e9mocrates \u00e0 Philadelphie et \u00e0 Detroit, pour d\u00e9tourner l&rsquo;attention de ce qui se passe dans les salles de d\u00e9pouillement des circonscriptions \u00e9lectorales.<\/p>\n<\/p>\n<p><p>Les batailles juridiques pourraient s&rsquo;\u00e9tendre jusqu&rsquo;en d\u00e9cembre, lorsque les &Eacute;tats devront certifier les \u00e9lecteurs. Si cela ne peut \u00eatre r\u00e9solu, la Chambre des repr\u00e9sentants sera saisie pour la premi\u00e8re fois depuis 1876 (<a href=\"https:\/\/fr.wikipedia.org\/wiki\/%C3%89lection_pr%C3%A9sidentielle_am%C3%A9ricaine_de_1876\" style=\"box-sizing: inherit; border-width: 0px 0px 1px; border-bottom-style: solid; border-bottom-color: rgb(51, 51, 51); font-family: inherit; font-size: 14.872400283813477px; font-style: normal; font-weight: normal; margin: 0px; outline: 0px; padding: 0px; vertical-align: baseline; color: rgb(51, 51, 51); text-decoration: none;\">Hayes-Tilden<\/a>).<\/p>\n<\/p>\n<p><h4>James Howard Kunstler<\/h4><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Belle-Fureur de JHK Comme les Qu\u00e9b\u00e9cois aiment \u00e0 se voir li\u00e9s \u00e0 ce qu&rsquo;ils nomment la Belle-Province, nous nommerions volontiers nommer le sentiment que l&rsquo;on distingue chez James Howard Kunstler, ou JHK, et qui le lie \u00e0 sa perception du temps : la belle-Fureur. Les stupides Parisiens qui se situent progressistes-soci\u00e9taux et de l&rsquo;univers&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[1235,4141,3966,2801,3340,2639,19260],"class_list":["post-79509","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-biden","tag-elections","tag-james","tag-kunstler","tag-presidentielles","tag-trump","tag-usa2020"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79509","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79509"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79509\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79509"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79509"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}