{"id":79519,"date":"2020-11-12T11:34:40","date_gmt":"2020-11-12T11:34:40","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2020\/11\/12\/a-t-il-echoue\/"},"modified":"2020-11-12T11:34:40","modified_gmt":"2020-11-12T11:34:40","slug":"a-t-il-echoue","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2020\/11\/12\/a-t-il-echoue\/","title":{"rendered":"A-t-il \u00e9chou\u00e9\u00a0?"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">A-t-il \u00e9chou\u00e9 ?<\/h2>\n<\/p>\n<p><p>L&rsquo;Homme orange \u00e0 la m\u00e8che blonde a-t-il r\u00e9ussi \u00e0 r\u00e9aliser ses promesses de campagne?<\/p>\n<\/p>\n<p><p>Il avait \u00e9t\u00e9 port\u00e9 au pouvoir par les <em>Deplorable<\/em> qui l&rsquo;ont choisi pour son programme de l&#8217;emploi fond\u00e9 sur la r\u00e9-industrialisation du pays et la r\u00e9duction des interventions militaires dans le reste du monde, consommatrices d&rsquo;une bonne part du budget f\u00e9d\u00e9ral sans b\u00e9n\u00e9fice pour eux.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">D\u00e9ficits<\/h3>\n<\/p>\n<p><p>L&rsquo;Homme orange avait ax\u00e9 sa politique sur l&rsquo;augmentation des tarifs douaniers appliqu\u00e9s aux produits import\u00e9s de Chine. Le d\u00e9ficit commercial des Usa a connu un record en 2018, 621 milliards dont 419, 2 pour la seule Chine soit une hausse de 12% par rapport \u00e0 2017. L&rsquo;inflexion de 1,7% du d\u00e9ficit vis-\u00e0-vis de la Chine en 2019, accompagn\u00e9e d&rsquo;un recul des exportations \u00e9tasuniennes, signe davantage un &lsquo;recul d&rsquo;activit\u00e9&rsquo; qu&rsquo;un effet tangible des taxes douani\u00e8res. Les Usa ont import\u00e9 moins de mat\u00e9riaux destin\u00e9s \u00e0 l&rsquo;industrie manufacturi\u00e8re (-9,3%) illustrant la r\u00e9cession dans cette activit\u00e9. L&rsquo;importation des biens d&rsquo;\u00e9quipement (informatique et t\u00e9l\u00e9communication)  a diminu\u00e9, montrant le peu d&#8217;empressement des firmes \u00e0 investir et produire.<\/p>\n<\/p>\n<p><p>Ces baisses, tr\u00e8s notables, sont donc bien ant\u00e9rieures \u00e0 la &lsquo;crise&rsquo; \u00e9conomique que l&rsquo;on peut imputer \u00e0 la pand\u00e9mie de la Covid-19.<\/p>\n<\/p>\n<p><p>En 2019, les importations depuis le Canada (+41,9%), le Mexique (+26%) et le <a href=\"https:\/\/www.lalibre.be\/economie\/placements\/tensions-commerciales-la-nouvelle-guerre-du-vietnam-pour-les-etats-unis-5d4c31d5d8ad5859353fb005#https:\/\/www.lalibre.be\/economie\/placements\/tensions-commerciales-la-nouvelle-guerre-du-vietnam-pour-les-et\">Vietnam<\/a> ont grimp\u00e9, ce qui a aggrav\u00e9 le d\u00e9ficit global.<\/p>\n<\/p>\n<p><p>La pand\u00e9mie a plus que pulv\u00e9ris\u00e9 en 2020 les quelques points de d\u00e9ficit avec la Chine grignot\u00e9s gr\u00e2ce \u00e0 la politique &lsquo;tarifaire&rsquo; agressive de l&rsquo;Homme orange. Pourtant, la Chine a achet\u00e9 massivement du minerai de fer et des circuits, faisant fondre son bilan commercial positif, pour r\u00e9pondre \u00e0 la reprise d&rsquo;activit\u00e9 industrielle nette au deuxi\u00e8me trimestre. Les derniers chiffres publi\u00e9s par la Douane chinoise font \u00e9tat d&rsquo;une augmentation de son exc\u00e9dent commercial avec les Usa de $ 30,75 milliards, soit <a href=\"https:\/\/www.latribune.fr\/economie\/international\/camouflet-pour-trump-la-chine-fait-a-nouveau-plonger-la-balance-commerciale-americaine-859655.html#https:\/\/www.latribune.fr\/economie\/international\/camouflet-pour-trump-la-chine-fait-a-nouveau-plonge\">+ 18,8% en un an<\/a> en donn\u00e9es corrig\u00e9es.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\"> Emploi<\/h3>\n<\/p>\n<p><p>Les Usa ont enregistr\u00e9 un gain net de 400 000 emplois &lsquo;manufacturiers&rsquo;  de novembre 2016 \u00e0 mars 2020. 75% de cette augmentation a bien eu lieu avant que n&rsquo;ait \u00e9t\u00e9 appliqu\u00e9e la nouvelle tarification douani\u00e8re \u00e0 l&rsquo;encontre des produits chinois entr\u00e9e en vigueur en juillet 2018. C&rsquo;est \u00e0 partir de juillet 2018 qu&rsquo;a d\u00e9but\u00e9 le ralentissement de la croissance de l&#8217;emploi, la production manufacturi\u00e8re avait pour sa part culmin\u00e9 en d\u00e9cembre 2018.<\/p>\n<\/p>\n<p><p>A partir de janvier 2020, les usines ont commenc\u00e9 \u00e0 licencier en masse au premier trimestre bien avant que les Usa n&rsquo;aient \u00e9t\u00e9 atteints par la pand\u00e9mie. Le <a href=\"https:\/\/www.forbes.fr\/business\/nike-under-armour-boeing-la-fin-des-pdg-tout-puissants\/#https:\/\/www.forbes.fr\/business\/nike-under-armour-boeing-la-fin-des-pdg-tout-puissants\/\">chiffre impressionnant<\/a> des d\u00e9missions de chefs d&rsquo;entreprise avec 1332 d\u00e9parts entre janvier et octobre 2019 augurait de la r\u00e9cession imminente et d\u00e9j\u00e0 perceptible malgr\u00e9 d&rsquo;\u00e9normes b\u00e9n\u00e9fices et des valorisations boursi\u00e8res \u00e9poustouflantes. Les chiffres de la croissance du PIB ont confirm\u00e9 le  <a href=\"https:\/\/www.tresor.economie.gouv.fr\/Pays\/US\/situation-de-l-economie-americaine-et-perspectives-a-moyen-terme#https:\/\/www.tresor.economie.gouv.fr\/Pays\/US\/situation-de-l-economie-americaine-et-perspectives-a-moyen-terme\">ralentissement<\/a>, +2,3%  en 2019 versus +2,9% en 2018 alors que la Fed avait abaiss\u00e9 par trois fois les taux d&rsquo;int\u00e9r\u00eat afin de lutter contre cette tendance.<\/p>\n<\/p>\n<p><p>Cette cr\u00e9ation d&#8217;emplois est \u00e0 mettre sur le compte de la r\u00e9forme fiscale de Trump tr\u00e8s favorable aux entreprises alors que le niveau d&rsquo;activit\u00e9 \u00e9tait d\u00e9j\u00e0 tr\u00e8s \u00e9lev\u00e9. Au bout de deux ans, ses effets de la manne fiscale se sont estomp\u00e9s. N\u00e9anmoins, le  ch\u00f4mage pour 2019 (tous secteurs confondus), chiffr\u00e9 \u00e0 \u00e0 3,6 %, a atteint des niveaux comparables \u00e0 ceux de 1969, faisant dire qu&rsquo;une situation de plein emploi avait \u00e9t\u00e9 quasiment atteinte. La pand\u00e9mie a effac\u00e9 ces gains en grande partie, le chiffre est \u00e9tabli \u00e0 7,9% en septembre apr\u00e8s une envol\u00e9e \u00e0 14,7% en mai.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Profit<\/h3>\n<\/p>\n<p><p>Le raisonnement de l&rsquo;Homme orange fond\u00e9 sur une analyse des ph\u00e9nom\u00e8nes selon une logique de causalit\u00e9 transitive (des plus vulgaires et abandonn\u00e9e par les plus illettr\u00e9s des \u00e9conomistes) est plus qu&rsquo;erron\u00e9. Il suffirait ainsi de baisser les importations des produits chinois en \u00e9levant les barri\u00e8res douani\u00e8res pour que les emplois industriels reviennent \u00e0 la maison.<\/p>\n<\/p>\n<p><p>C&rsquo;est oublier que le transfert de l&rsquo;activit\u00e9 des industries \u00e9tasuniennes en Chine populaire apr\u00e8s les accords de Nixon r\u00e9pondait \u00e0 un besoin de r\u00e9duction du salaire des ouvriers, pour augmenter leur profit en raison de la loi d&rsquo;airain de la baisse tendancielle de son taux. Or depuis quelques ann\u00e9es d\u00e9j\u00e0, des g\u00e9ants du textile et de l&rsquo;habillement avaient d\u00e9plac\u00e9 leur fabrication au Vietnam en raison du co&ucirc;t de la main d&rsquo;&oelig;uvre moins \u00e9lev\u00e9 qu&rsquo;en Chine. Les fabricants et des assembleurs en \u00e9lectronique y ont \u00e9galement transf\u00e9r\u00e9 leur production. L&rsquo;<a href=\"https:\/\/www.vietnam-briefing.com\/news\/deplacements-de-la-chaine-dapprovisionnement-de-la-chine-au-vietnam.html\/#https:\/\/www.vietnam-briefing.com\/news\/deplacements-de-la-chaine-dapprovisionnement-de-la-chine-au-vietnam.html\/\">environnement<\/a> infrastructurel et fiscal ainsi que les accords commerciaux constituent des crit\u00e8res suppl\u00e9mentaires en faveur de cette d\u00e9localisation it\u00e9rative.<\/p>\n<\/p>\n<p><p>La configuration \u00e9conomique aux Usa est telle que soigner et loger un ouvrier est devenu extr\u00eamement co&ucirc;teux. 15% du salaire passe dans les assurances maladies, et pr\u00e8s de 40% du revenu, c&rsquo;est ce qu&rsquo;autorise la l\u00e9gislation \u00e9tasunienne, est consacr\u00e9 \u00e0 payer la dette  contract\u00e9e pour payer \u00e0 cr\u00e9dit son logement. Les Usa sont le pays de l&rsquo;OCDE qui consacre le budget le plus important \u00e0 la sant\u00e9 (<a href=\"https:\/\/www.sciencesetavenir.fr\/sciences\/usa-des-depenses-de-sante-deux-fois-plus-elevees-que-dans-d-autres-pays-riches_122001#https:\/\/www.sciencesetavenir.fr\/sciences\/usa-des-depenses-de-sante-deux-fois-plus-elevees-que-dans-d-autres-pays-riches\">deux fois plus<\/a> en moyenne) pour une efficacit\u00e9 non \u00e9prouv\u00e9e. L&rsquo;\u00e9quipement et les m\u00e9dicaments co&ucirc;tent plus cher, il faut assurer une rente aux laboratoires pharmaceutiques et aux \u00e9quipementiers. Les honoraires des m\u00e9decins sont \u00e9galement tr\u00e8s \u00e9lev\u00e9s, il faut rembourser les dettes des \u00e9tudes et assurer un revenu confortables aux assurances et aux cabinets d&rsquo;avocats en cas de litiges. L&rsquo;industrie du b\u00e2timent ne repr\u00e9sente qu&rsquo;environ 4% du PIB mais elle irrigue l&rsquo;industrie de la finance par l&rsquo;endettement des m\u00e9nages et des entreprises. Si les taux d&rsquo;int\u00e9r\u00eats sont tr\u00e8s bas, le co&ucirc;t du b\u00e2ti s&rsquo;\u00e9l\u00e8ve davantage, permettant des gains plus consistants aux pr\u00eateurs. Une <a href=\"http:\/\/www.oecd.org\/fr\/economie\/etudes\/Etats-Unis-2018-OECD-etude-economique-synthese.pdf#http:\/\/www.oecd.org\/fr\/economie\/etudes\/Etats-Unis-2018-OECD-etude-economique-synthese.pdf\">\u00e9tude de l&rsquo;OCDE<\/a> portant sur la situation \u00e9conomique des Usa en 2018 montre que parmi les 20% des Etas-uniens les moins riches, 60% consacre plus que la moiti\u00e9 de leur revenu pour se loger. Comme ils sont pauvres, les pr\u00eats sont consid\u00e9r\u00e9s comme risqu\u00e9s et consentis \u00e0 un fort taux d&rsquo;int\u00e9r\u00eat. Ce travail se conclue par l&rsquo;observation faite sur les addictions aux drogues. La toxicomanie fait perdre des points de PIB car elle induit des pertes de salaires et de productivit\u00e9 ainsi que par les co&ucirc;ts de prise en charge th\u00e9rapeutique. D\u00e9sormais, les &lsquo;surdoses&rsquo; sont une cause majeure de mortalit\u00e9. La toxicomanie est donc un important probl\u00e8me de sant\u00e9 publique mais plus que cela, c&rsquo;est l&rsquo;indice que cette soci\u00e9t\u00e9 est vraiment endommag\u00e9e.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Les soldats \u00e0 la maison<\/h3>\n<\/p>\n<p><p>A de nombreuses reprises, Trump a annonc\u00e9 des retraits des troupes am\u00e9ricaines au moins du th\u00e9\u00e2tre proche et moyen oriental et d&rsquo;Afghanistan. Le nombre de soldats de l&rsquo;arm\u00e9e \u00e9tasunienne comme celui des combattants d&rsquo;arm\u00e9es priv\u00e9es n&rsquo;a cess\u00e9 de se contracter pendant son mandat. Sur le dernier et l&rsquo;avant dernier trimestre de 2020, <a href=\"http:\/\/lignesdedefense.blogs.ouest-france.fr\/afghanistan\/#http:\/\/lignesdedefense.blogs.ouest-france.fr\/afghanistan\/\">la baisse<\/a> a \u00e9t\u00e9 de 12% en Afghanistan et de 26% pour l&rsquo;Irak et la Syrie.<\/p>\n<\/p>\n<p><p>Un <a href=\"https:\/\/www.lemonde.fr\/international\/article\/2020\/02\/29\/afghanistan-l-accord-historique-de-doha-ouvre-un-nouveau-chapitre-a-l-issue-incertaine_6031374_3210.html#https:\/\/www.lemonde.fr\/international\/article\/2020\/02\/29\/afghanistan-l-accord-historiq\">accord<\/a> avait \u00e9t\u00e9 sign\u00e9 \u00e0 Doha entre un repr\u00e9sentant des Talibans et un n\u00e9gociateur \u00e9tasunien le 29 f\u00e9vrier \u00e0 Doha, scellant la fin de la guerre de 18 ans lanc\u00e9e par Bush le deuxi\u00e8me pour venger la chute de trois tours \u00e0 New York provoqu\u00e9e par deux avions conduits par des S\u00e9oudiens en septembre 2001. Voil\u00e0 une puissance r\u00e9put\u00e9e grande qui conclut la paix avec non pas un Etat mais un groupe informel de r\u00e9sistants. A Kaboul, dans le m\u00eame temps Mark Esper et le Pr\u00e9sident d Ashraf Ghani faisaient une d\u00e9claration commune par laquelle les Usa s&rsquo;engageaient \u00e0 soutenir les institutions afghanes, mani\u00e8re boiteuse de  masquer la d\u00e9faite \u00e9tasunienne face \u00e0 une milice de montagnards mal \u00e9quip\u00e9s.<\/p>\n<\/p>\n<p><p>Depuis l&rsquo;assassinat du G\u00e9n\u00e9ral iranien Soula\u00efmani d\u00e9but janvier 2020 pr\u00e8s de l&rsquo;a\u00e9roport de Bagdad, les bases am\u00e9ricaines en Irak subissent des <a href=\"https:\/\/www.ouest-france.fr\/monde\/irak\/irak-barrage-de-roquettes-sur-une-base-ou-des-soldats-americains-ont-recemment-ete-tues-6780299#https:\/\/www.ouest-france.fr\/monde\/irak\/irak-barrage-de-roquettes-sur-une-base-ou-des-soldats-americains-ont-rec\">attaques redoubl\u00e9es<\/a> de <a href=\"https:\/\/www.challenges.fr\/monde\/irak-des-roquettes-s-abattent-sur-une-base-militaire-pres-de-bagdad_720706#https:\/\/www.challenges.fr\/monde\/irak-des-roquettes-s-abattent-sur-une-base-militaire-pres-de-bagdad_720706\">roquettes<\/a> tr\u00e8s r\u00e9guli\u00e8rement de la part de milices irakiennes. Les autorit\u00e9s irakiennes, assez peu l\u00e9gitimes et jouant d&rsquo;acrobatie avec le voisin iranien dont elles d\u00e9pendent \u00e9conomiquement et avec l&rsquo;all\u00e9geance port\u00e9e \u00e0 un occupant dont tout le monde souhaite le d\u00e9part, doivent faire face \u00e0 une r\u00e9volte populaire d\u00e9but\u00e9e en octobre 2019 et maintenant \u00e0 la pand\u00e9mie du coronavirus. En septembre 2020, le chef du commandement militaire am\u00e9ricain au Moyen-Orient a r\u00e9duit la pr\u00e9sence militaire \u00e9tasunienne en Irak de <a href=\"https:\/\/www.lapresse.ca\/international\/etats-unis\/2020-09-09\/l-armee-americaine-reduit-encore-sa-presence-en-irak.php#https:\/\/www.lapresse.ca\/international\/etats-unis\/2020-09-09\/l-armee-americaine-reduit-encore-sa-presence-en-irak.php\">5200 \u00e0 3000<\/a>. Elle s&rsquo;est renforc\u00e9e en revanche dans les bases qui lui sont (al)lou\u00e9es dans des pays voisins, le Koweit et l&rsquo;Arabie aux mains des B\u00e9douins du Nedjd.<\/p>\n<\/p>\n<p><p>Sans en avertir l&rsquo;Otan ni les forces locales syriennes rebelles subventionn\u00e9es par les Usa, Trump a d\u00e9cid\u00e9 de retirer <a href=\"https:\/\/www.liberation.fr\/planete\/2019\/11\/15\/soldats-americains-en-syrie-pour-le-petrole-ou-contre-l-ei_1763712#https:\/\/www.liberation.fr\/planete\/2019\/11\/15\/soldats-americains-en-syrie-pour-le-petrole-ou-contre-l-ei_1763712\">en octobre 2019<\/a> mille militaires de l&rsquo;Est syrien quelques jours avant l&rsquo;offensive turque contre les Unit\u00e9s de protection du peuple, les milices kurdes YPG. <\/p>\n<\/p>\n<p><p>Quatre bases ont ainsi \u00e9t\u00e9 \u00e9vacu\u00e9es. L&rsquo;Homme orange a \u00e9t\u00e9 aussit\u00f4t contredit par un responsable militaire qui a indiqu\u00e9 qu&rsquo;il ne s&rsquo;agissait que d&rsquo;un <a href=\"https:\/\/www.francetvinfo.fr\/monde\/usa\/presidentielle\/donald-trump\/syrie-le-retrait-de-soldats-americains-ne-concerne-que-50-a-100-membres-des-forces-speciales_3649395.html#https:\/\/www.francetvinfo.fr\/monde\/usa\/presidentielle\/donald-trump\/syrie-le\">red\u00e9ploiement<\/a> d&rsquo;une centaine de soldats de forces sp\u00e9ciales.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Toujours plus  pour le Pentagone<\/h3>\n<\/p>\n<p><p> D\u00e8s son arriv\u00e9e \u00e0 la Maison Blanche, l&rsquo;Homme orange a accord\u00e9 une rallonge de $ 54 milliards de dollars au Pentagone, soit 10% de hausse pour l&rsquo;ann\u00e9e 2018. Renforcer l&rsquo;arm\u00e9e am\u00e9ricaine, appauvrie selon lui par son pr\u00e9d\u00e9cesseur, \u00e9tait une de ses priorit\u00e9s. Cet imp\u00e9ratif des R\u00e9publicains se r\u00e9alisera en taillant dans le budget d&rsquo;autres D\u00e9partements, les Affaires Etrang\u00e8res (30%) ainsi que celui de l&rsquo;Agence pour la protection de l&rsquo;environnement.<\/p>\n<\/p>\n<p><p>Pour l&rsquo;ann\u00e9e fiscale 2019, le budget militaire approuv\u00e9 par le S\u00e9nat a atteint $<a href=\"https:\/\/www.lesechos.fr\/monde\/etats-unis\/le-buzz-des-etats-unis-trump-juge-fou-le-budget-de-larmee-americaine-206879#https:\/\/www.lesechos.fr\/monde\/etats-unis\/le-buzz-des-etats-unis-trump-juge-fou-le-budget-de-larmee-americaine-206879\">716 milliards<\/a> de dollars, 82 de plus que pour l&rsquo;ann\u00e9e pr\u00e9c\u00e9dente. La nouvelle doctrine militaire d\u00e9velopp\u00e9e dans la  <a href=\"https:\/\/dod.defense.gov\/Portals\/1\/Documents\/pubs\/2018-National-Defense-Strategy-Summary.pdf#https:\/\/dod.defense.gov\/Portals\/1\/Documents\/pubs\/2018-National-Defense-Strategy-Summary.pdf\"><em>National Defense Strategy<\/em><\/a> en 2018 a abandonn\u00e9 l&rsquo;id\u00e9e de la pr\u00e9\u00e9minence de la menace terroriste pour lutter contre les rivaux \u00e9conomiques, la Russie et surtout la Chine.<\/p>\n<\/p>\n<p><p>La loi qui fixe le niveau des d\u00e9penses du Pentagone pour l&rsquo;ann\u00e9e 2020 a \u00e9t\u00e9 adopt\u00e9e le 10 d\u00e9cembre 2020, elle pr\u00e9voit de porter les d\u00e9penses militaires \u00e0 <a href=\"https:\/\/www.lefigaro.fr\/flash-eco\/le-congres-americain-s-accorde-sur-une-budget-militaire-en-hausse-et-une-force-de-l-espace-20191210#https:\/\/www.lefigaro.fr\/flash-eco\/le-congres-americain-s-accorde-sur-une-budget-militaire-en-hausse-et-une-force\">738 milliards<\/a> de dollars. Elle cr\u00e9e une sixi\u00e8me force, r\u00e9pondant aux v&oelig;ux de l&rsquo;Homme orange, celle de l&rsquo;Espace. Le document de plus de 3000 pages a inclus des dispositions l\u00e9gislatives qui entravent la possibilit\u00e9 pour Trump de prendre des d\u00e9cisions intempestives. Le texte interdit de r\u00e9duire les effectifs en Cor\u00e9e du Sud, de vendre les avions furtifs \u00e0 la Turquie et d&rsquo;acheter du mat\u00e9riel ferroviaire \u00e0 la Chine.<\/p>\n<\/p>\n<p><p>Il ne cite pas les limitations des ventes d&rsquo;armement impos\u00e9es par le Lobby isra\u00e9lien au Congr\u00e8s \u00e9tasunien. Ce Lobby qui n&rsquo;existe pas se manifeste pourtant bruyamment actuellement, il est en passe d&rsquo;obtenir que le F35 ne soit pas vendu aux Emirats Arabes Unis qui viennent de signer pourtant un accord naturalisant leurs rapports avec l&rsquo;artefact colonial sioniste. Pelosi s&rsquo;est engag\u00e9e \u00e0 garantir la sup\u00e9riorit\u00e9 strat\u00e9gique \u00e0 Tel Aviv et \u00e0 faire perdre des revenus \u00e0 Lockheed sans cesse renflou\u00e9s par l&rsquo;Etat f\u00e9d\u00e9ral et donc les imp\u00f4ts des Am\u00e9ricains. Il a \u00e9t\u00e9 calcul\u00e9 que l&rsquo;entit\u00e9 a re\u00e7u depuis sa cr\u00e9ation pr\u00e8s de $295 milliards d&rsquo;aides directes des Usa, soit trois fois les sommes engag\u00e9es pour reconstruire l&rsquo;Europe dans le cadre du plan Marshall. <\/p>\n<\/p>\n<p><p>Dans l&rsquo;ensemble, le complexe militaro-industriel a \u00e9t\u00e9 plut\u00f4t satisfait du mandat du 45<sup>\u00e8me<\/sup> Potus. Le fameux Etat profond qui l&rsquo;a combattu durant des quatre derni\u00e8res ann\u00e9es n&rsquo;a pas recrut\u00e9 en son sein m\u00eame si par moment le chef de l&rsquo;ex\u00e9cutif s&rsquo;est pris <a href=\"https:\/\/www.lesechos.fr\/monde\/etats-unis\/le-buzz-des-etats-unis-trump-juge-fou-le-budget-de-larmee-americaine-206879#https:\/\/www.lesechos.fr\/monde\/etats-unis\/le-buzz-des-etats-unis-trump-juge-fou-le-budget-de-larmee-americaine-206879\">\u00e0 d\u00e9plorer<\/a> dans des tweets, estim\u00e9s malvenus par le secr\u00e9taire \u00e0 la D\u00e9fense, la mont\u00e9e vertigineuse de ses d\u00e9penses du Pentagone.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">What is wrong ?<\/h3>\n<\/p>\n<p><p>L&rsquo;\u00e9lection de Trump fut contest\u00e9e en 2016 mais ce fut le cas pour ses trois pr\u00e9d\u00e9cesseurs. <\/p>\n<\/p>\n<p><p>Clinton n&rsquo;avait recueilli que 43% du vote populaire dans une comp\u00e9tition \u00e0 trois candidats au cours de laquelle les R\u00e9publicains ont consid\u00e9r\u00e9 que G H W Bush s&rsquo;est fait voler des voix par le troisi\u00e8me, un milliardaire ind\u00e9pendant, Ross Perrot, qui  avait rassembl\u00e9 sur son nom plus de 19 millions d&rsquo;\u00e9lecteurs. Clinton a \u00e9t\u00e9 consid\u00e9r\u00e9 comme tellement ill\u00e9gitime que deux ans apr\u00e8s sa victoire agr\u00e9\u00e9e, l&rsquo;opposition r\u00e9publicaine a r\u00e9ussi \u00e0 entamer des audiences pour le destituer.<\/p>\n<\/p>\n<p><p>Bush le deuxi\u00e8me est devenu Pr\u00e9sident sur d\u00e9cision de la Cour Supr\u00eame qui a fait arr\u00eater le comptage des voix en Floride au moment o&ugrave; il est devenu favorable \u00e0 G W Bush d&rsquo;\u00e0 peine quelques centaines. Un recomptage complet \u00e0 l&rsquo;\u00e9chelle de tout l&rsquo;Etat aurait donn\u00e9 Al Gore vainqueur selon une analyse fiable ult\u00e9rieure. <\/p>\n<\/p>\n<p><p>Obama a \u00e9t\u00e9 contest\u00e9 essentiellement par l&rsquo;\u00e9quipe de Hillary Clinton qui l&rsquo;a attaqu\u00e9 de mani\u00e8re infond\u00e9e  sur sa non-am\u00e9ricanit\u00e9 en raison de son lieu de naissance au Kenya.<\/p>\n<\/p>\n<p><p>Kennedy fut si violemment contest\u00e9 qu&rsquo;il en a perdu la t\u00eate.<\/p>\n<\/p>\n<p><p>L&rsquo;opposition \u00e0 la politique de Nixon a r\u00e9ussi \u00e0 mener la proc\u00e9dure de la destitution du POTUS quasiment \u00e0 son terme. Sa mise \u00e0 mort avait emprunt\u00e9 une forme plus civilis\u00e9e mais pas moins tranchante, le lynchage par une presse d\u00e9j\u00e0 asservie \u00e0 des int\u00e9r\u00eats \u00e0 l&rsquo;\u00e9poque mal identifi\u00e9s. <\/p>\n<\/p>\n<p><p>Le camp des D\u00e9mocrates n&rsquo;a cess\u00e9 de perturber le mandat de l&rsquo;Homme orange, organisant des manifestations de grande ampleur contre lui d\u00e8s sa nomination puis empruntant de fa\u00e7on obstin\u00e9e une demande de destitution sur des all\u00e9gations de son intelligence avec l&rsquo;ennemi russe. Des montages informatiques bidouill\u00e9s ont tent\u00e9 tour \u00e0 tour de r\u00e9v\u00e9ler une intervention russe de manipulation de l&rsquo;opinion am\u00e9ricaine en p\u00e9riode \u00e9lectorale. Puis ils ont permis d&rsquo;accuser le gouvernement russe de vol de donn\u00e9es informatiques depuis le serveur du Parti d\u00e9mocrate. Toute cette mise en sc\u00e8ne n&rsquo;avait de substance que celle octroy\u00e9e par la presse (intercontinentale) dominante, substance d&rsquo;un bobard grossier mais avec l&rsquo;efficace redoutable mais fongible du travail acharn\u00e9 de journalistes appoint\u00e9s pour diffuser de la propagande.<\/p>\n<\/p>\n<p><p>Un seul moment de r\u00e9pit fut accord\u00e9 \u00e0 l&rsquo;Homme orange. Ses louanges furent chant\u00e9es un court moment lorsqu&rsquo;il s&rsquo;\u00e9tait r\u00e9solu \u00e0 envoyer une bombe sur un hangar d\u00e9saffect\u00e9 en Syrie en avril 2017. Le gazage du peuple syrien qui a servi de d\u00e9clenchement \u00e0 cette op\u00e9ration sans lendemain s&rsquo;est vite r\u00e9v\u00e9l\u00e9 un canular jou\u00e9 par des figurants d&rsquo;Al Qa\u00efda d\u00e9guis\u00e9s en &lsquo;casques blancs&rsquo; pour le tournage de quelques sc\u00e8nes bricol\u00e9es sans conviction.<\/p>\n<\/p>\n<p><p>Trump n&rsquo;a ouvert aucun nouveau front de guerre. Il a tent\u00e9 de r\u00e9duire l&rsquo;engagement de l&rsquo;arm\u00e9e \u00e9tasunienne au Moyen Orient. La construction de la base de drones \u00e0 Agades, consid\u00e9r\u00e9e comme l&rsquo;effort infrastructurel le plus important ces derni\u00e8res ann\u00e9es, entreprise sous son mandat avait \u00e9t\u00e9 d\u00e9cid\u00e9e sous Obama dans la foul\u00e9e de la destruction de la Libye. <\/p>\n<\/p>\n<p><p>Kennedy et Nixon furent sacrifi\u00e9s sur l&rsquo;autel de guerres dont ils ne voulaient pas.<\/p>\n<\/p>\n<p><p>Trump est un personnage d\u00e9testable, x\u00e9nophobe, soutenu par des chr\u00e9tiens fondamentalistes encore plus obscurantistes que la secte des Wahhabites. Il s&rsquo;est odieusement rang\u00e9 sans le filtre d&rsquo;une biens\u00e9ance conf\u00e9r\u00e9e par la &lsquo;communaut\u00e9 internationale&rsquo; du c\u00f4t\u00e9 des sionistes de Tel Aviv, an\u00e9antissant avec brutalit\u00e9 le mythe entretenu depuis 1994 de la possibilit\u00e9 des deux &Eacute;tats       en Palestine occup\u00e9e. Il a supprim\u00e9 la contribution financi\u00e8re d\u00e9volue \u00e0 l&rsquo;Unrwa agence de l&rsquo;ONU qui pr\u00eate secours aux r\u00e9fugi\u00e9s palestiniens, aujourd&rsquo;hui au nombre de 8 millions.  Il a poursuivi l&rsquo;appui logistique des B\u00e9douins du Nedjd dans leur agression sociocidaire du peuple y\u00e9m\u00e9nite. Il a \u00e9trangl\u00e9 le peuple iranien par des sanctions \u00e9conomiques de plus en plus s\u00e9v\u00e8res apr\u00e8s s&rsquo;\u00eatre retir\u00e9 de l&rsquo;accord multilat\u00e9ral sur le nucl\u00e9aire de l&rsquo;Iran. Comme un gar\u00e7on auquel on n&rsquo;a pas appris les bonnes mani\u00e8res, il a sorti les Usa de l&rsquo;accord sur le climat de Paris qui jusqu&rsquo;\u00e0 pr\u00e9sent ne dispose d&rsquo;aucune contrainte pour faire appliquer ses objectifs. <\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Fasciste ?<\/h3>\n<\/p>\n<p><p> Sa qualification de fasciste par les D\u00e9mocrates et la gauche soci\u00e9tale est une aberration. <\/p>\n<\/p>\n<p><p>Le fascisme comme le nazisme tout en affirmant une supr\u00e9matie raciale et\/ou nationale avaient comme objectif une expansion territoriale, celle d&rsquo;un &laquo; espace vital &raquo;  \u00e0 obtenir par des conqu\u00eates militaires. L&rsquo;abolition des fronti\u00e8res \u00e9conomiques r\u00e9alis\u00e9e sous Bill Clinton avec le renfort de l&rsquo;OMC a transform\u00e9 toute la plan\u00e8te en terrain conquis ouvert o&ugrave; se d\u00e9ploient les multinationales \u00e9tasuniennes. Quand les trait\u00e9s n&rsquo;y suffisaient pas, quelques r\u00e9volutions color\u00e9es ou des bombardements sur des pays non encore int\u00e9gr\u00e9s \u00e0 leur pr\u00e9dation ont parachev\u00e9 l&rsquo;affaire. Trump au contraire a souhait\u00e9 pratiquer une politique inspir\u00e9e de l&rsquo;isolationnisme wilsonien. Il s&rsquo;agissait de rendre \u00e0 l&rsquo;Am\u00e9rique sa grandeur- dont tout le monde constate qu&rsquo;elle a \u00e9t\u00e9 perdue. <\/p>\n<\/p>\n<p><p>Trump, \u00e0 l&rsquo;allure et l&rsquo;expression plut\u00f4t clownesque, ne s&rsquo;affirme pas non plus comme un leader charismatique incarnant l&rsquo;essence de la Nation et flottant au-dessus d&rsquo;elle comme un F\u00fchrer ou un Duce. <\/p>\n<\/p>\n<p><p>Sous son mandat, la police n&rsquo;a pas tu\u00e9 plus de civils et pas plus d&rsquo;Afro-Am\u00e9ricains ou de Latinos que sous ses pr\u00e9d\u00e9cesseurs. Ce n&rsquo;est pas lui qui a autoris\u00e9 la police de diff\u00e9rents &Eacute;tats \u00e0 acqu\u00e9rir du mat\u00e9riel militaire anti-\u00e9meutes.<\/p>\n<\/p>\n<p><p>Il n&rsquo;est certainement pas plus cynique que Bush le Deuxi\u00e8me ou Obama le Premier et le Dernier dont Biden fut le vice-Pr\u00e9sident, qui par leurs guerres ont produit 35 millions de r\u00e9fugi\u00e9s dans le monde, singuli\u00e8rement dans le monde arabe et musulman. Parmi eux, certains meurent en mer ou sur des plages, d&rsquo;autres se transforment en terroristes islamistes de petite pointure, loin d&rsquo;\u00eatre aussi performants que les auteurs des attentats dans le m\u00e9tro des d\u00e9cennies pr\u00e9c\u00e9dentes. Biden n&rsquo;a jamais regrett\u00e9 la destruction de l&rsquo;Irak et de l&rsquo;Afghanistan accomplie sous de faux pr\u00e9textes, Trump a au moins d\u00e9clar\u00e9 pour sa part que ce fut une erreur.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Alors, quoi ? L&rsquo;\u00e9conomique !<\/h3>\n<\/p>\n<p><p> Sans pass\u00e9 politique sinon celui d&rsquo;un amuseur dans des \u00e9missions de t\u00e9l\u00e9-r\u00e9alit\u00e9, il n&rsquo;a pas eu l&rsquo;occasion comme Biden l&rsquo;a fait au cours de son tr\u00e8s longue carri\u00e8re <a href=\"https:\/\/books.google.fr\/books?id=D_8BEAAAQBAJ&#038;pg=PT88&#038;lpg=PT88&#038;dq=Biden+pr%C3%A9sident+commission+juridique+%3C%3C%3Cs%C3%A9nat&#038;source=bl&#038;ots=ywe-ZGH2Lk&#038;sig=ACfU3U0l2kTu0K8JPHOX99wTbDtliMowSg&#038;hl=fr&#038;sa=X&#038;ved=2ahUKEwj155OxvvrsAhWhuXEKHf2TAH8Q6AEwCHo\">d&rsquo;\u00e9laborer<\/a> et de faire voter des lois qui ont jet\u00e9 des millions d&rsquo;Afro-Am\u00e9ricains comme travailleurs-esclaves dans les prisons priv\u00e9es sous pr\u00e9texte d&rsquo;une tol\u00e9rance z\u00e9ro vis-\u00e0-vis de la petite d\u00e9linquance. Biden en 1994 avait invent\u00e9 la perp\u00e9tuit\u00e9 pour les r\u00e9cidivistes quelle que soit la nature de leur d\u00e9lit, ce qui avait inspir\u00e9 les ambitions judiciaires de Sark\u00f6zy et de Dati.<\/p>\n<\/p>\n<p><p>Les D\u00e9mocrates comme les R\u00e9publicains n&rsquo;ont en r\u00e9alit\u00e9 aucun autre programme que le sauvetage des institutions financi\u00e8res et du secteur de l&rsquo;immobilier. Ils ne se soucient pas des infrastructures en ruine, des municipalit\u00e9s sans moyens qui vont devoir licencier. L&rsquo;Homme orange en d\u00e9but de mandat voulait engager pourtant 10 000 milliards \u00e0 cet effet. En lieu et place, il a fait appliquer un programme d&rsquo;all\u00e8gement des imp\u00f4ts de 10 000 milliards sur dix ans pour les firmes, juste retour de l&rsquo;aide \u00e0 son \u00e9lection. Les deux partis ont conclu un accord pour injecter 8 000 milliards sur le march\u00e9 boursier et obligataire. La Fed va racheter les pr\u00eats hypoth\u00e9caires pourris et les pr\u00eats pas moins pourris pour l&rsquo;industrie p\u00e9troli\u00e8re et du fracking.<\/p>\n<\/p>\n<p><p>Toute la &lsquo;croissance&rsquo; depuis plus d&rsquo;une d\u00e9cennie est all\u00e9e aux 1%  sous forme de valorisation d&rsquo;actions boursi\u00e8res exub\u00e9rante et injustifi\u00e9e et d&rsquo;augmentation du prix de l&rsquo;immobilier.<\/p>\n<\/p>\n<p><p>C&rsquo;est la manifestation de l&rsquo;effet de la structure capitaliste de la soci\u00e9t\u00e9, l&rsquo;am\u00e9ricaine en est  l&rsquo;expression la plus embl\u00e9matique, in\u00e9galitaire et devenue inefficace du point de vue industriel. C&rsquo;est un capitalisme de rente, la rente des institutions financi\u00e8res qui a transform\u00e9 la formule A-M-A (argent marchandise argent) en A-A&rsquo;, A&rsquo; sup\u00e9rieur \u00e0 A.<\/p>\n<\/p>\n<p><p>Cette formule magique de la cr\u00e9ation de l&rsquo;argent par l&rsquo;argent est une illusion. Dans cette repr\u00e9sentation d&rsquo;allure auto-g\u00e9n\u00e9rative, se dissimulent les activit\u00e9s guerri\u00e8res des Usa.<\/p>\n<\/p>\n<p><p>Trump affiche les convictions d&rsquo;un arch\u00e9o-capitaliste, r\u00e9tif \u00e0 des guerres sans fin en dehors des guerres \u00e9conomiques pas moins meurtri\u00e8res mais sans h\u00e9moglobine ext\u00e9rioris\u00e9e apparente. Son \u00e9quation chinoise ne peut pas dissoudre la projection \u00e9conomique de plus en plus pr\u00e9gnante de la Chine sur les continents asiatique et africain. Elle ne ram\u00e8nera pas les jobs industriels aux Usa, exit la chim\u00e8re Chinam\u00e9rique et place \u00e0 la Chinafrique. La Chine entreprend des travaux d&rsquo;infrastructures chez elle et \u00e0 l&rsquo;ext\u00e9rieur, l&rsquo;\u00e9ducation et la sant\u00e9 sont gratuites. Elle produit par millions des personnes en bonne sant\u00e9 mentale et physique avec de hautes comp\u00e9tences  scientifiques. Elle va consacrer la d\u00e9cennie prochaine \u00e0 amplifier la recherche et les applications dans les technologies de pointe. Pour l&rsquo;instant le secteur bancaire est encore sous le joug des pouvoirs publics au service d&rsquo;un d\u00e9veloppement planifi\u00e9. Elle renoue doucement avec sa puissance d&rsquo;avant les guerres de l&rsquo;opium. Pendant ce temps, la l\u00e9galisation de l&rsquo;usage m\u00e9dical ou r\u00e9cr\u00e9atif du cannabis est adopt\u00e9e par de plus en plus d&rsquo;Etats aux Usa, elle est consid\u00e9r\u00e9e comme un progr\u00e8s social, \u00e9valu\u00e9e sous l&rsquo;angle de rent\u00e9es fiscales et de d\u00e9penses amoindries dans le judiciaire r\u00e9pressif.<\/p>\n<\/p>\n<p><p>L&rsquo;am\u00e9lioration des chiffres du ch\u00f4mage enregistr\u00e9e en d\u00e9but du mandat de L&rsquo;Homme Orange a certainement eu raison des pr\u00e9visions fabriqu\u00e9es de la Presse syst\u00e8me. Il n&rsquo;y a pas eu l&rsquo;affaissement escompt\u00e9 du vote pour Trump. Les positions robustes dans nombre d&rsquo;&Eacute;tats permettent de douter de la sinc\u00e9rit\u00e9 du scrutin. Les recours des R\u00e9publicains sont respectueux de la loi \u00e9lectorale et la contestation n&rsquo;a pas rev\u00eatu la forme d&rsquo;une guerre civile o&ugrave; des milices d&rsquo;extr\u00eame-droite auraient install\u00e9 un climat de terreur fascisto\u00efde.<\/p>\n<\/p>\n<p><p>A cette heure, le 46<sup>\u00e8me<\/sup> Pr\u00e9sident des Usa n&rsquo;est pas encore connu ni d\u00e9sign\u00e9.<\/p>\n<\/p>\n<p><p>S&rsquo;il \u00e9choue \u00e0 \u00eatre victorieux, ce sera de peu et cet \u00e9chec sera \u00e0 mettre sur le compte du pouvoir hypertrophique d&rsquo;une presse depuis longtemps pervertie et convertie \u00e0 la religion n\u00e9o-conservatrice des Guerres sans fin que les Usa ne peuvent m\u00eame plus s&rsquo;offrir.<\/p>\n<\/p>\n<p><p>Mais pour le Reste du Monde, l&rsquo;un ou l&rsquo;autre aura une politique contrainte par la conjoncture \u00e9conomique et pand\u00e9mique qui n&rsquo;est pas faite pour les exploit\u00e9s et les <em>Deplorable<\/em>. La mascarade de l&rsquo;\u00e9lection d&rsquo;un vieillard s\u00e9nile corrompu notoirement mis en jeu \u00e0 la place de la parkinsonienne soustraire \u00e0 la vie publique depuis le scandale Epstein a aid\u00e9 \u00e0 dissiper les quelques illusions persistantes sur la d\u00e9mocratie \u00e9tasunienne. La r\u00e9\u00e9lection de l&rsquo;Homme orange est peu probable, il a objectivement perdu.<\/p>\n<\/p>\n<p><h4>(&#8230;Entre deux acc\u00e8s de fi\u00e8vre de la Covid-19)<\/h4><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A-t-il \u00e9chou\u00e9 ? L&rsquo;Homme orange \u00e0 la m\u00e8che blonde a-t-il r\u00e9ussi \u00e0 r\u00e9aliser ses promesses de campagne? Il avait \u00e9t\u00e9 port\u00e9 au pouvoir par les Deplorable qui l&rsquo;ont choisi pour son programme de l&#8217;emploi fond\u00e9 sur la r\u00e9-industrialisation du pays et la r\u00e9duction des interventions militaires dans le reste du monde, consommatrices d&rsquo;une bonne part&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[31],"tags":[3953,1235,5993,2651,12661,6357,2639,2804],"class_list":["post-79519","post","type-post","status-publish","format-standard","hentry","category-les-carnets-de-badia-benjelloun-1","tag-benjelloun","tag-biden","tag-bilan","tag-du","tag-mandat","tag-situation","tag-trump","tag-usa"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79519","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79519"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79519\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79519"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79519"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}