{"id":79522,"date":"2020-11-15T04:01:00","date_gmt":"2020-11-15T04:01:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2020\/11\/15\/ineluctabilite-de-la-voie-sacree\/"},"modified":"2020-11-15T04:01:00","modified_gmt":"2020-11-15T04:01:00","slug":"ineluctabilite-de-la-voie-sacree","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2020\/11\/15\/ineluctabilite-de-la-voie-sacree\/","title":{"rendered":"In\u00e9luctabilit\u00e9 de la voie sacr\u00e9e"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepblue\" style=\"color:#0f3955; font-size:2em\">In\u00e9luctabilit\u00e9 de la voie sacr\u00e9e<\/h2>\n<\/p>\n<blockquote>\n<p><p>&bull; Ce texte se propose de faire une appr\u00e9ciation g\u00e9n\u00e9rale de la situation \u00e0 partir du constat de l&rsquo;extr\u00eame importance et de l&rsquo;extr\u00eame gravit\u00e9 de la crise de l&rsquo;am\u00e9ricanisme (plus encore que \u00ab\u00a0la crise des USA\u00a0\u00bb), c&rsquo;est-\u00e0-dire la <strong>\u00ab\u00a0crise de l&rsquo;am\u00e9ricanisme\u00a0\u00bb prise comme la crise de la Modernit\u00e9, et donc la crise d&rsquo;une civilisation, de \u00ab\u00a0notre civilisation devenue contre-civilisation\u00a0\u00bb<\/strong> (autre \u00e9nonc\u00e9 pour notre GCES, crise dite \u00ab\u00a0de l&rsquo;Effondrement du Syst\u00e8me\u00a0\u00bb). &bull; Pour l&rsquo;\u00e9nonc\u00e9 et l&rsquo;analyse de la chose, nous citons longuement une partie importante <strong>de la derni\u00e8re analyse d&rsquo;Alastair Crooke<\/strong>, du 13 novembre, dont la d\u00e9marche rencontre parfaitement la n\u00f4tre quant \u00e0 <strong>la dimension de \u00ab\u00a0crise de civilisation\u00a0\u00bb en cours aux USA<\/strong>. &bull; Il s&rsquo;agit de consid\u00e9rer cette crise dans la perspective de la crise de la p\u00e9riode de l&rsquo;&Acirc;ge des Lumi\u00e8res et, aujourd&rsquo;hui, <strong>en directe connexion compl\u00e9mentaire avec la crise dite-sanitaire du Covid19<\/strong>. &bull; Trump ou Biden, etc. ? Nous sommes bien loin de ces consid\u00e9rations qui animent nos d\u00e9bats, quand nous pensons s\u00e9rieusement \u00e0 ce qui se passe aux USA, alors que <strong>les Am\u00e9ricains eux-m\u00eames, obs\u00e9d\u00e9s par Trump, se rendent difficilement compte de ce qui leur arrive, tout en ressentant le poids<\/strong>. &bull; Les \u00e9v\u00e9nements n&rsquo;ont pas besoin de nous, pour bouleverser notre destin, <strong>si nous sommes encore conscients d&rsquo;avoir un destin.<\/strong><\/p>\n<\/p>\n<\/blockquote>\n<p><p>15 novembre 2020 &ndash; Comme toujours, comme nous le r\u00e9p\u00e9tons \u00e0 chaque occasion depuis le 11-septembre d&rsquo;il y a presque vingt ans, les fantastiques \u00e9v\u00e9nements se d\u00e9roulent sous nos yeux qui paraissent parfois aveugles :<\/p>\n<\/p>\n<p><p>&laquo; <em>D&rsquo;abord, il y a ceci : en m\u00eame temps que nous subissions cet \u00e9v\u00e9nement d&rsquo;une force et d&rsquo;une ampleur extr\u00eames, nous observions cet \u00e9v\u00e9nement en train de s&rsquo;accomplir et, plus encore, nous nous observions les uns les autres en train d&rsquo;observer cet \u00e9v\u00e9nement. L&rsquo;histoire se fait, soudain dans un d\u00e9roulement explosif et brutal, nous la regardons se faire et nous nous regardons en train de la regarder se faire. On sait \u00e9galement que ceux qui ont d\u00e9cid\u00e9 et r\u00e9alis\u00e9 cette attaque l&rsquo;ont fait parce qu&rsquo;ils savaient qu&rsquo;existe cet \u00e9norme ph\u00e9nom\u00e8ne d&rsquo;observation des choses en train de se faire, et de nous-m\u00eames en train d&rsquo;observer. Le monde est comme une addition de poup\u00e9es russes, une duplication de la r\u00e9alit\u00e9 en plusieurs r\u00e9alit\u00e9s embo&icirc;t\u00e9es les unes <\/em> [dans]  <em>les autres<\/em>. &raquo; (Premier paragraphe du texte de l&rsquo;essai &laquo; <em>Des tours de Manhattan aux jardins de l&rsquo;&Eacute;lys\u00e9e <\/em>&raquo;, du livre &laquo; <em>Chroniques de l&rsquo;\u00e9branlement<\/em> &raquo;, de Philippe Grasset [\u00e9ditions Mols, 2003].)<\/p>\n<\/p>\n<p><p>\u00ab\u00a0Comme toujours, comme nous le r\u00e9p\u00e9tons \u00e0 chaque occasion depuis le 11-septembre\u00a0\u00bb, la grande r\u00e9volution cognitive de cette \u00e9poque &lsquo;\u00e9trange&rsquo;, &ndash; et cette r\u00e9volution permettant l&rsquo;\u00e9v\u00e9nement principal de la chute de notre civilisation, &ndash; est bien de voir se d\u00e9rouler la tr\u00e8s Grande-Crise de l&rsquo;effondrement de notre civilisation (<a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-la-gces\">GCES<\/a>), et cela effectivement sous notre regard qui para&icirc;t le plus souvent bien impuissant, sinon d\u00e9formant, dans l&rsquo;identification du ph\u00e9nom\u00e8ne. Ce que ressentons, c&rsquo;est ce que nous percevons, c&rsquo;est-\u00e0-dire la puissance cosmique du ph\u00e9nom\u00e8ne, qui nous interdit de pr\u00e9tendre poursuivre nos entreprises comme si rien ne se passait. Cette attitude \u00e0 la fois inconsciente, \u00e0 la fois complice vis-\u00e0-vis de l&rsquo;\u00e9v\u00e9nement, joue un r\u00f4le d&rsquo;acc\u00e9l\u00e9rateur de l&rsquo;\u00e9v\u00e9nement ; et plus l&rsquo;\u00e9v\u00e9nement acc\u00e9l\u00e8re, moins nous le comprenons pour ce qu&rsquo;il est mais contribuons encore \u00e0 son acc\u00e9l\u00e9ration ; ainsi, ayant peut-\u00eatre invent\u00e9 une sorte de &lsquo;mouvement perp\u00e9tuel divin&rsquo;, et toujours \u00e0 notre insu, \u00ab\u00a0de notre plein gr\u00e9\u00a0\u00bb ou de quoi que ce soit d&rsquo;autre.<\/p>\n<\/p>\n<p><p>Alastair Crooke aborde sans aucun doute l&rsquo;essence m\u00eame de l&rsquo;\u00e9v\u00e9nement cosmique en cours, dans son \u00ab\u00a0<em>Conflicts Forum&rsquo;s Weekly Comment<\/em>\u00a0\u00bb du 13 novembre, avec son titre de &laquo; <em>America&rsquo;s Struggle towards a New Civilisational Paradigm<\/em> &raquo;. Nous lui empruntons une part importante de son texte, d\u00e9crivant \u00e0 la fois la signification de l&rsquo;\u00e9v\u00e9nement en cours aux USA comme un &lsquo;changement de civilisation&rsquo; ; les processus institutionnels qui favorisent cette \u00e9volution de \u00ab\u00a0l&rsquo;\u00e9v\u00e9nement en cours\u00a0\u00bb ; la signification globale de cet &lsquo;\u00e9v\u00e9nement en cours&rsquo;, c&rsquo;est-\u00e0-dire de la chute d&rsquo;une civilisation qui, pour avoir \u00e9t\u00e9 port\u00e9e \u00e0 son sommet matriciel et peut-\u00eatre satanique par les USA, n&rsquo;en est effectivement pas moins globale.<\/p>\n<\/p>\n<p><p>On observera deux situations techniques qui sont d&rsquo;abord des occurrences linguistiques, qui permettent de mieux embrasser la description de la d\u00e9marche contenue dans ce texte, et peut-\u00eatre sa signification profonde :<\/p>\n<p>&bull; l&#8217;emploi par Crooke des &lsquo;codes&rsquo; adopt\u00e9s d&rsquo;une fa\u00e7on assez anodine, simplement \u00e0 partir de la cartographie \u00e9lectorale o&ugrave; la tradition s&rsquo;est \u00e9tablie de mettre en bleu les &Eacute;tats d\u00e9mocrates et en rouge les &Eacute;tats r\u00e9publicains, &ndash; d&rsquo;o&ugrave; l&#8217;emploi de &lsquo;bleu&rsquo; pour tout ce qui est d\u00e9mocrate, de &lsquo;rouge&rsquo; pour tout ce qui est r\u00e9publicain ; il est vrai que ces couleurs semblent parfois d\u00e9cal\u00e9es par rapport \u00e0 la description symbolique \u00e0 laquelle on est habitu\u00e9 : ainsi de faire des r\u00e9publicains conservateurs les &lsquo;rouges&rsquo; de l&rsquo;aventure ; peut-\u00eatre que les d\u00e9mocrates, eux, sont plus \u00e0 l&rsquo;aise s&rsquo;ils ont d\u00e9couvert que les soldats des arm\u00e9es de la R\u00e9volution \u00e9taient baptis\u00e9s &lsquo;les bleus&rsquo;, lorsqu&rsquo;ils s&rsquo;opposaient aux Blancs l\u00e9gitimistes-royalistes et liquidaient les populations correspondants, comme ils firent en Vend\u00e9e ;<\/p>\n<p>&bull; la caract\u00e9risation d'\u00a0\u00bbic\u00f4ne\u00a0\u00bb donn\u00e9e \u00e0 la crise sanitaire Covid19 pour caract\u00e9riser les deux c\u00f4t\u00e9s antagonistes : &laquo; <em>Les diff\u00e9rences de r\u00e9action face au Covid-19, confinement ou pas, ont creus\u00e9 ce foss\u00e9 au point que cette crise sanitaire est devenue l&rsquo;ic\u00f4ne de ce qui divise et s\u00e9pare l&rsquo;Am\u00e9rique aujourd&rsquo;hui<\/em>. &raquo; Cela renforce l&rsquo;appr\u00e9ciation que nous proposons selon laquelle la crise-Covid19 est une crise capitale essentiellement du fait r\u00f4le d&rsquo;interm\u00e9diaire qu&rsquo;elle joue, en liant les crises entre elles, en emp\u00eachant le Syst\u00e8me de r\u00e9installer une &lsquo;normalit\u00e9&rsquo; facilement manipulable, en fixant les antagonismes, en se politisant ais\u00e9ment pour entretenir ces antagonismes, etc.<\/p>\n<\/p>\n<p><p>Voici donc le texte d&rsquo;Alastair Crooke, seconde et derni\u00e8re partie de son commentaire du 13 novembre&#8230;<\/p>\n<\/p>\n<p><h2 class=\"titleset_c.deepblue\" style=\"color:#0f3955;font-size:1.25em;\">&laquo; &#8230;Vers un nouveau paradigme civilisationnel<\/h2>\n<\/p>\n<p><p>&laquo; L&rsquo;Am\u00e9rique frissonne.  Il ne s&rsquo;agit pas seulement de \u00ab\u00a0<em>politic as usual<\/em>\u00ab\u00a0.  Il ne s&rsquo;agit m\u00eame pas du pr\u00e9sident Trump (bien que la plupart des partisans des &lsquo;Bleus&rsquo; le croient).  Il ne s&rsquo;agit m\u00eame pas seulement de l&rsquo;Am\u00e9rique.  Il y a des moments o&ugrave;, &ndash; collectivement, mais aussi individuellement, &ndash; les civilisations arrivent \u00e0 une bifurcation.  La civilisation am\u00e9ricaine et ouest-europ\u00e9enne se trouve \u00e0 un tel point. Deux p\u00f4les, les \u00e9lites c\u00f4ti\u00e8res et le centre de l&rsquo;Am\u00e9rique, <a href=\"\/%3chttps:\/thebulwark.com\/be-alarmed\/%3e\">entrent en collision<\/a>, et les \u00e9tincelles et le m\u00e9tal tordu r\u00e9sultant de ce choc frontal alimenteront le brasier qui forcera la &lsquo;civilisation rouge&rsquo; am\u00e9ricaine \u00e0 changer de cap, quel qu&rsquo;en soit le prix. Les cons\u00e9quences de cette collision formeront le bouleversement de l&rsquo;Am\u00e9rique, et de l&rsquo;Europe aussi, o&ugrave; les euro-\u00e9lites ne sont souvent que des simulacres de ces \u00ab\u00a0\u00e9lites c\u00f4ti\u00e8res\u00a0\u00bb am\u00e9ricaines.<\/p>\n<\/p>\n<p><p>&raquo; Quel que soit la personne qui se retrouve \u00e0 la Maison Blanche, l&rsquo;Am\u00e9rique est d\u00e9sormais irr\u00e9m\u00e9diablement divis\u00e9e. <a href=\"\/%3chttps:\/www.anewcivilwar.com\/post\/liberty-to-therapy-don-t-worry-over-civil-war-worry-over-the-transformation-of-american-life%3e\">Comme l&rsquo;\u00e9crit<\/a> l&rsquo;historien am\u00e9ricain Mike Vlahos : \u00ab\u00a0Les progressistes consacrent leur vie \u00e0 cette mission r\u00e9volutionnaire, tandis que les \u00e9lecteurs &lsquo;rouges&rsquo; jurent tout aussi passionn\u00e9ment de l&rsquo;arr\u00eater. Ce mot est le titre, la banni\u00e8re et le proscenium d\u00e9finissant une lutte existentielle : la &lsquo;Transformation&rsquo; est le cri de guerre de notre champ de bataille national\u00a0\u00bb. Les Am\u00e9ricains des &Eacute;tats &lsquo;rouges&rsquo; consid\u00e8rent que l&rsquo;\u00e9lection est un &lsquo;coup d&rsquo;&Eacute;tat&rsquo; contre eux. Ils estiment que les Am\u00e9ricains blancs ont \u00e9t\u00e9 diabolis\u00e9s en raison de leur racisme naturel et (tout naturellement) se sentent vuln\u00e9rables.  Il leur a fallu beaucoup de temps pour le comprendre, mais maintenant ils \u00ab\u00a0comprennent\u00a0\u00bb : la couleur blanche de la peau est consid\u00e9r\u00e9e par une grande partie de l&rsquo;Am\u00e9rique &lsquo;bleue&rsquo; comme un supr\u00e9macisme &lsquo;pathologique&rsquo;, et le &lsquo;racisme\u00a0\u00bb pathologique doit \u00eatre exorcis\u00e9, d\u00e9clame-t-elle.<\/p>\n<\/p>\n<p><p>&raquo; Le probl\u00e8me auquel l&rsquo;Am\u00e9rique est confront\u00e9e est que les initi\u00e9s de l&rsquo;Axe entre Big Tech (les GAFAM) et les &lsquo;Bleus&rsquo; (d\u00e9mocrates) seront conscients qu&rsquo;il y a eu des irr\u00e9gularit\u00e9s \u00e9lectorales. (Les manigances \u00e9lectorales ne sont pas nouvelles aux &Eacute;tats-Unis, et l&rsquo;ampleur de cet \u00e9pisode reste \u00e0 prouver.) L\u00a0\u00bbAm\u00e9rique rouge&rsquo;, elle, clame qu&rsquo;il y a eu fraude. Une narrative est en cours d&rsquo;\u00e9laboration.  Biden aura un probl\u00e8me de l\u00e9gitimit\u00e9, &ndash; quelle que soit la fa\u00e7on dont l&rsquo;on tranchera pour trouver une issue.<\/p>\n<\/p>\n<p><p>&raquo; Les membres de l&rsquo;Axe d\u00e9testent totalement Trump et, de toute fa\u00e7on, consid\u00e9reraient probablement tout \u00ab\u00a0vol\u00a0\u00bb putatif comme l\u00e9gitime, &ndash; afin de se d\u00e9barrasser enfin de Trump. Peut-\u00eatre que l&rsquo;ampleur du soutien apport\u00e9 \u00e0 Trump dans les &Eacute;tats-clef les a pris au d\u00e9pourvu.  Apr\u00e8s l&rsquo;\u00e9chec du <em><a href=\"https:\/\/www.zerohedge.com\/news\/2019-02-12\/stocks-surge-senate-intel-committee-confirms-no-collusion\">Russiagate<\/a><\/em>, et apr\u00e8s l&rsquo;\u00e9chec de la mise en accusation, l&rsquo;abandon d&rsquo;un soutien de pure forme \u00e0 la d\u00e9mocratie am\u00e9ricaine, &ndash; en actes, si ce n&rsquo;est en paroles, &ndash; peut avoir sembl\u00e9 \u00eatre un prix raisonnable \u00e0 payer. Tout pour sortir de l&rsquo;impasse&#8230;<\/p>\n<\/p>\n<p><p>&raquo; \u00ab\u00a0Trump est un raciste et un misogyne. N&rsquo;est-ce pas suffisant ?  Pointer du doigt les faits n&rsquo;est pas diaboliser\u00a0\u00bb, <a href=\"https:\/\/twitter.com\/megynkelly\/status\/1325574561283366913?ref_src=twsrc%5Etfw%7Ctwcamp%5Etweetembed%7Ctwterm%5E1325574561283366913%7Ctwgr%5Eshare_3&#038;ref_url=https%3A%2F%2Fwww.zerohedge.com%2Fpolitical%2Fus-color-revolution-not-so-phantom-menace\">r\u00e9torquent<\/a> les supporteurs des &lsquo;Bleus&rsquo;. En d&rsquo;autres termes, \u00ab\u00a0Comment les \u00e9lecteurs ont-ils pu \u00eatre assez b\u00eates pour glisser deux fois dans l&rsquo;urne l&rsquo;enveloppe avec un vote pour Trump ?\u00a0\u00bb. Toute personne &lsquo;rationnelle&rsquo; comprendrait que les quatre derni\u00e8res ann\u00e9es ont \u00e9t\u00e9 une catastrophe permanente, se plaignent ces partisans avec une perplexit\u00e9 furieuse.<\/p>\n<\/p>\n<p><p>&raquo; Un professeur d&rsquo;histoire d&rsquo;une prestigieuse \u00e9cole am\u00e9ricaine <a href=\"https:\/\/www.theamericanconservative.com\/articles\/a-history-teachers-view-why-liberal-elites-cant-understand-the-trump-vote\/\">sugg\u00e8re<\/a> cette explication :<\/p>\n<\/p>\n<p><p>&raquo; \u00ab\u00a0J&rsquo;ai une r\u00e9ponse simple pour expliquer cette [mentalit\u00e9], qui vient de l&rsquo;observation rationnelle d&rsquo;\u00e9tudiants adolescents, pour la plupart issus de milieux ais\u00e9s. Les \u00e9lites cosmopolites des m\u00e9dias et du monde universitaire, comme l&rsquo;adolescent pr\u00e9suppos\u00e9 qui va \u00e0 l&rsquo;universit\u00e9, qui a de l&rsquo;anciennet\u00e9 et qui a la certitude d&rsquo;avoir compris monde dans sa globalit\u00e9, n&rsquo;ont pas conscience de la nature aveugle et exclusive de leur propre vision du monde ; ce faisant, ils ne comprennent pas toute la complexit\u00e9 de la r\u00e9alit\u00e9 elle-m\u00eame.<\/p>\n<\/p>\n<p><p>&raquo; \u00ab\u00a0La vision du monde \u00e0 laquelle je fais r\u00e9f\u00e9rence porte plusieurs noms : rationalisme, la\u00efcit\u00e9, humanisme, etc. Cette vision \u00e9mane de ce que j&rsquo;appelle le mythe des Lumi\u00e8res : l&rsquo;id\u00e9e que nous sommes arriv\u00e9s au monde moderne parce que nous avons compl\u00e8tement abandonn\u00e9 la religion, la tradition et la coutume. C&rsquo;est l&rsquo;id\u00e9e que la modernit\u00e9 a \u00e9t\u00e9 construite \u00e0 partir de la base et d&rsquo;une Id\u00e9e, par la raison s\u00e9cularis\u00e9e. Comme l&rsquo;expose sans le critiquer le concept classique d&rsquo;histoire europ\u00e9enne, &lsquo;<em>AP European History<\/em>&lsquo; : &lsquo;Ils [les penseurs du Si\u00e8cle des Lumi\u00e8res] ont cherch\u00e9 \u00e0 faire en sorte que la lumi\u00e8re de la raison puisse s&rsquo;opposer \u00e0 l&rsquo;obscurit\u00e9 des pr\u00e9jug\u00e9s, des traditions d\u00e9pass\u00e9es et de l&rsquo;ignorance, &ndash; mettant ainsi totalement en question les valeurs traditionnelles&rsquo;.<\/p>\n<\/p>\n<p><p>&raquo; \u00ab\u00a0Ce qui est remarquable, ce n&rsquo;est pas la d\u00e9claration en elle-m\u00eame, mais le fait que ses auteurs, comme mes \u00e9tudiants et les enqu\u00eateurs qui ont pr\u00e9dit le carnage \u00e9lectoral que devait subir Trump, consid\u00e8rent [l&rsquo;in\u00e9vitable \u00e9crasement de Trump] comme une \u00e9vidence de la r\u00e9alit\u00e9, &ndash; par opposition \u00e0 l&rsquo;historiographie id\u00e9ologique, ouverte au d\u00e9bat\u00a0\u00bb  C&rsquo;est-\u00e0-dire qu&rsquo;ils [les adh\u00e9rents bleus] ont cherch\u00e9 \u00e0 apporter la lumi\u00e8re de la raison triomphant de l&rsquo;obscurit\u00e9 des pr\u00e9jug\u00e9s, des traditions d\u00e9pass\u00e9es et de l&rsquo;ignorance, en remettant en question les valeurs traditionnelles des \u00e9lecteurs de Trump partout o&ugrave; ils se trouvent.<\/p>\n<\/p>\n<p><p>&raquo; Cela nous dit pourquoi la collision est in\u00e9vitable en fin de compte.  L&rsquo;esprit du temps exprim\u00e9 par les [progressistes-soci\u00e9taux antitrumpistes] y voit des faits qui ne sont pas sujets \u00e0 discussion. On ne \u00ab\u00a0fait pas de prisonniers\u00a0\u00bb <a href=\"https:\/\/www.anewcivilwar.com\/post\/liberty-to-therapy-don-t-worry-over-civil-war-worry-over-the-transformation-of-american-life\">dans cette guerre<\/a> pour d\u00e9barrasser l&rsquo;Am\u00e9rique du racisme syst\u00e9mique, &ndash; puisque ce sont \u00ab\u00a0des faits\u00a0\u00bb. Le professeur Vlahos <a href=\"https:\/\/www.anewcivilwar.com\/post\/liberty-to-therapy-don-t-worry-over-civil-war-worry-over-the-transformation-of-american-life\">nous met en garde<\/a> : \u00ab\u00a0A la fin de cette partie fondamentale, le r\u00e9sultat souhait\u00e9 pour notre avenir par les partisans du &lsquo;R\u00e9veil&rsquo; (<em>Woke<\/em>) sera une civilisation diff\u00e9rente\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>&raquo; Voici donc les principaux \u00e9l\u00e9ments du naufrage \u00e0 venir.  Tout d&rsquo;abord, &ndash; contrairement \u00e0 l&rsquo;explication de l&rsquo;<em>hybris<\/em> du personnage, &ndash; l&rsquo;\u00e9lection n&rsquo;a en aucune fa\u00e7on eu de rapports exclusifs avec Trump en tant qu&rsquo;individu. Le vitriol des &lsquo;Bleus&rsquo; est all\u00e9 bien au-del\u00e0 de Trump, il a touch\u00e9 70 millions d&rsquo;Am\u00e9ricains trait\u00e9s de vils, de bigots, de racistes, etc. Proposer que \u00ab\u00a0nous devons nous \u00e9couter les uns les autres\u00a0\u00bb n&rsquo;est pas au programme. Le bromure ne suffit pas. Cette prescription &lsquo;Rouge&rsquo; est maintenant verrouill\u00e9e et pr\u00eate \u00e0 l&rsquo;usage imm\u00e9diat.<\/p>\n<\/p>\n<p><p>&raquo; Deuxi\u00e8mement, la contestation des r\u00e9sultats des \u00e9lections a ouvert la voie, non seulement \u00e0 la mise en cause pour irr\u00e9gularit\u00e9s de certains votes, mais aussi, dans le cas de la Pennsylvanie, \u00e0 la saisine de la Cour supr\u00eame pour les motifs distincts de violation de la Constitution des &Eacute;tats, pour avoir mis en place des r\u00e8gles \u00e9lectorales non autoris\u00e9es par leurs l\u00e9gislature. Cette initiative pourrait avoir des r\u00e9percussions beaucoup plus larges sur la question des votes par correspondance.<\/p>\n<\/p>\n<p><p>&raquo; Plus encore, ce point particulier ouvre la possibilit\u00e9 de persuader les l\u00e9gislateurs r\u00e9publicains au niveau des &Eacute;tats de choisir des Grands &Eacute;lecteurs autoris\u00e9s \u00e0 agir selon leur conscience (s&rsquo;ils en viennent \u00e0 croire que le scrutin dans leur &Eacute;tat a \u00e9t\u00e9 entach\u00e9 d&rsquo;irr\u00e9gularit\u00e9s ; cette possibilit\u00e9 est l\u00e9gale dans la plupart des &Eacute;tats). Tout cela peut conduire \u00e0 une situation o&ugrave; le Congr\u00e8s, s&rsquo;il le peut, serait l&rsquo;arbitre pour choisir le nouveau pr\u00e9sident le 20 janvier, ou conduire \u00e0 une insurrection de la base d\u00e9mocrate si Biden n&rsquo;est pas inaugur\u00e9 ce jour-l\u00e0.<\/p>\n<\/p>\n<p><p>&raquo; Bien s&ucirc;r, comme nous le savons tous, l&rsquo;application de &lsquo;la Loi&rsquo; n&rsquo;est jamais certaine ; mais ce que fait l&rsquo;\u00e9quipe Giuliani, &ndash; \u00e0 part de manipuler les contentieux, &ndash; c&rsquo;est de mettre en sc\u00e8ne un &lsquo;d\u00e9ploiement&rsquo; public d&rsquo;irr\u00e9gularit\u00e9s, d&rsquo;improbabilit\u00e9s statistiques et de d\u00e9sordre postal.  Il semble que Trump et Giuliani vont \u00e9crire leur propre &lsquo;histoire r\u00e9visionniste&rsquo; de l&rsquo;\u00e9lection, ind\u00e9pendamment de l&rsquo;issue des litiges. C&rsquo;est sans doute la raison pour laquelle le Big Tech (les GAFAM) tente d&rsquo;\u00e9touffer la th\u00e8se de la fraude g\u00e9n\u00e9ralis\u00e9e par opposition \u00e0 la fraude sp\u00e9cifique. Le d\u00e9ploiement de l&rsquo;id\u00e9e de la fraude g\u00e9n\u00e9ralis\u00e9e lors des rassemblements publics va creuser plus profond\u00e9ment encore le foss\u00e9 entre les deux Am\u00e9riques.<\/p>\n<\/p>\n<p><p>&raquo; Troisi\u00e8mement, le Big Tech, avec la presseSyst\u00e8me en soutien, a r\u00e9prim\u00e9 ou ferm\u00e9 les sites qui all\u00e8guent la fraude g\u00e9n\u00e9ralis\u00e9e, en les qualifiant de non fond\u00e9s.  Mais voil\u00e0 le hic : alors que les &lsquo;Bleus&rsquo; se drapent dans le progressisme dans toutes ces occurrences, le Big Tech veut bien parler d&rsquo;identit\u00e9 et de genre, mais il n&rsquo;est nullement &lsquo;progressiste&rsquo;.<\/p>\n<\/p>\n<p><p>&raquo; Lui, il se r\u00e9f\u00e8re plut\u00f4t \u00e0 la &lsquo;<em>Davos Crowd<\/em>&lsquo; et \u00e0 son id\u00e9e de &lsquo;<em>Reset<\/em>&lsquo;. S&rsquo;il devient pr\u00e9sident, Biden aura besoin des r\u00e9publicains mod\u00e9r\u00e9s pour faire passer les projets de loi de d\u00e9penses, bien plus qu&rsquo;il n&rsquo;aura besoin du caucus d&rsquo;extr\u00eame gauche de son propre parti. AOC et <em><a href=\"https:\/\/www.dedefensa.org\/article\/leur-fascination-les-fascine\">The Squad<\/a><\/em> sont-elles des illusions promises \u00e0 dispara&icirc;tre ? L&rsquo;administration Biden sera prisonni\u00e8re de son soutien au Big Tech et \u00e0 ce &lsquo;<em>Reset<\/em>&lsquo;, qui n&rsquo;est rien d&rsquo;autre qu&rsquo;une resuc\u00e9e de plus du vieil universalisme mill\u00e9naire.<\/p>\n<\/p>\n<p><p>&raquo; L&rsquo;essentiel \u00e0 retenir est que les Am\u00e9ricains vivent, non seulement baign\u00e9s dans leur m\u00e9contentement mais aussi dans un moment historique essentiel. L&rsquo;Am\u00e9rique &lsquo;rouge&rsquo; s&rsquo;est \u00e9veill\u00e9e du fait de la br&ucirc;lure provoqu\u00e9e par le vitriol qu&rsquo;on lui a balanc\u00e9. L&rsquo;action du Big Tech et de la presseSyst\u00e8me a servi \u00e0 souligner la crise de l&rsquo;isolement de ces \u00e9lecteurs r\u00e9publicains. En temps de crise, hommes et femmes cherchent des explications, &ndash; et des solutions, tr\u00e8s vite.<\/p>\n<\/p>\n<p><p>&raquo; Nous soup\u00e7onnons que le projet \u00ab\u00a0collectiviste\u00a0\u00bb de Davos n&rsquo;est qu&rsquo;un de plus dans trois longs si\u00e8cles de globalisme mill\u00e9nariste, tous qui promettaient un \u00ab\u00a0nouveau monde\u00a0\u00bb et qui ont produit des catastrophes. Non, il est plus probable que ce que nous verrons sera le \u00ab\u00a0libertarisme\u00a0\u00bb des &lsquo;Rouges&rsquo; contre le \u00ab\u00a0collectivisme\u00a0\u00bb des &lsquo;Bleus\u00a0\u00bb. Les diff\u00e9rences de r\u00e9action face au Covid-19, confinement ou pas, ont creus\u00e9 ce foss\u00e9 au point que cette crise sanitaire est devenue l&rsquo;ic\u00f4ne de ce qui divise et s\u00e9pare l&rsquo;Am\u00e9rique aujourd&rsquo;hui.<\/p>\n<\/p>\n<p><p>&raquo; Actuellement, les \u00e9lites c\u00f4ti\u00e8res aux USA et celles de l&rsquo;Europe tentent de contenir ces \u00ab\u00a0d\u00e9sordres\u00a0\u00bb pour \u00e9viter qu&rsquo;ils ne versent dans la violence. Ces tensions, craignent-elles, menacent la durabilit\u00e9 de la notion d&rsquo;une humanit\u00e9 mondiale fond\u00e9e sur des \u00ab\u00a0valeurs\u00a0\u00bb communes, poursuivant une longue marche vers un ordre et une gouvernance globalistes.<\/p>\n<\/p>\n<p><p>&raquo; Pour survivre, l&rsquo;Am\u00e9rique &lsquo;rouge&rsquo; va revenir aux anciennes valeurs (comme le fait toute soci\u00e9t\u00e9 en crise), et essayer de tirer, du r\u00e9cit de leur \u00e9rosion et de leur n\u00e9gligence, une explication, &ndash; une histoire, &ndash; de cette d\u00e9tresse qui est la sienne aujourd&rsquo;hui. Ils peuvent observer que les &lsquo;autres&rsquo; valeurs oppos\u00e9es au collectivisme ont toujours surgi des couches profondes de l&rsquo;exp\u00e9rience et de l&rsquo;histoire humaines.<\/p>\n<\/p>\n<p><p>&raquo; Beaucoup de m\u00e9contents d&rsquo;aujourd&rsquo;hui n&rsquo;ont jamais r\u00e9fl\u00e9chi aux valeurs civilisationnelles qu&rsquo;ils vont maintenant chercher \u00e0 adapter et \u00e0 renouveler.  Peu importe, ce n&rsquo;est pas la question ; les graines d&rsquo;une nouvelle \u00e9tape dans la suite des crises civilisationnelles ont \u00e9t\u00e9 sem\u00e9es dans leur psych\u00e9 collective.  Nous verrons o&ugrave; cela m\u00e8nera. &raquo;<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">La fascination d\u00e9sint\u00e9gr\u00e9e<\/h2>\n<\/p>\n<p><p>C&rsquo;est \u00e9videmment une id\u00e9e que nous poursuivons depuis longtemps, et r\u00e9p\u00e9tons quand cela importe : l&rsquo;Am\u00e9rique comme puissance ma&icirc;tresse du monde, inspiratrice du monde, simulacre du monde. La puissance am\u00e9ricaniste, beaucoup mieux exprim\u00e9e par la communication et la fascination que charrie la communication, est plus que jamais ma&icirc;tresse du monde lorsqu&rsquo;elle menace d&rsquo;exploser\/d&rsquo;imploser. Sa crise est notre crise et elle est la crise de notre-civilisation par excellence. Cette id\u00e9e n&rsquo;a pas cess\u00e9 d&rsquo;enfler, de s&rsquo;enrichir, de s&rsquo;affirmer, depuis au moins deux d\u00e9cennies d&rsquo;une fa\u00e7on extr\u00eamement voyante, &ndash; pendant que les fascin\u00e9s volontaires, dont La Bo\u00e9tie a oubli\u00e9 de parler, suivaient avec fascination [<em>What else ?<\/em>], c&rsquo;est-\u00e0-dire avec d\u00e9lice, la course vers l&rsquo;effondrement de la puissance qui nous soumettrait tous.<\/p>\n<\/p>\n<p><p>Ainsi <em>dedefensa.org <\/em>\u00e9crivait-il, &lsquo;fascin\u00e9 volontaire&rsquo; de la chute de l&rsquo;objet de leur fascination le <a href=\"https:\/\/www.dedefensa.org\/article\/notes-sur-lavenir-des-usa\">14 octobre 2009<\/a> :<\/p>\n<\/p>\n<p><p>&laquo; <em>Nous l&rsquo;avons d\u00e9j\u00e0 \u00e9crit et nous le r\u00e9p\u00e9tons avec force : il ne peut y avoir, aujourd&rsquo;hui, d&rsquo;\u00e9v\u00e9nements plus important pour la situation du monde qu&rsquo;une dynamique de dislocation des &Eacute;tats-Unis d&rsquo;Am\u00e9rique. Nous pensons que la crise actuelle est \u00e0 la fois, et contradictoirement, formidablement amplifi\u00e9e et formidablement bloqu\u00e9e dans sa compr\u00e9hension par la puissance de la communication. Ce ph\u00e9nom\u00e8ne ne cesse de dramatiser et d&rsquo;attiser les conditions de la crise tout en renfor\u00e7ant la pression du conformisme de la pens\u00e9e dominante pour ne pas mettre en cause les \u00e9l\u00e9ments qui sont les fondements de cette crise.<\/em><\/p>\n<p>&raquo; <em>L&rsquo;un des fondements est psychologique, avec le ph\u00e9nom\u00e8ne de fascination &ndash; \u00e0 nouveau ce mot &ndash; pour l&rsquo;attraction exerc\u00e9e sur les esprits par le \u00ab\u00a0mod\u00e8le am\u00e9ricaniste\u00a0\u00bb, qui est en fait la repr\u00e9sentation \u00e0 la fois symbolique et onirique de la modernit\u00e9. C&rsquo;est cela qui est r\u00e9sum\u00e9 sous l&rsquo;expression populaire mais tr\u00e8s substantiv\u00e9e de American Dream. Cette repr\u00e9sentation donn\u00e9e comme seule issue possible de notre civilisation (le facteur dit TINA, pour \u00ab\u00a0There Is No Alternative\u00a0\u00bb) infecte la plupart des \u00e9lites en place; elle repr\u00e9sente un verrou d&rsquo;une puissance inou\u00efe, qui compl\u00e8te d&rsquo;une fa\u00e7on tragique la \u00ab\u00a0fascination de l&rsquo;am\u00e9ricanisme pour sa propre destin\u00e9e catastrophique\u00a0\u00bb pour former une situation totalement bloqu\u00e9e emp\u00eachant de chercher une autre voie tout en d\u00e9gringolant vers la catastrophe. La fin de l&rsquo;American Dream, qui interviendrait avec un processus de parcellisation de l&rsquo;Am\u00e9rique, constituerait un facteur d\u00e9cisif pour d\u00e9bloquer notre perception, \u00e0 la fois des conditions de la crise, de la gravit\u00e9 ontologique de la crise et de la n\u00e9cessit\u00e9 de tenter de chercher une autre voie pour la civilisation &ndash; ou, plus radicalement, une autre civilisation&#8230;<\/em> &raquo;<\/p>\n<\/p>\n<p><p>Il appara&icirc;t remarquable de constater de quelle mani\u00e8re presque parfaite, &ndash; quasi-parfaite comme l&rsquo;on dit quasi-divine, &ndash; les \u00e9v\u00e9nements, sans le moindre rapport avec nos plans, nos espoirs et nos haines, avec nos agitations vaines et nos initiatives d\u00e9risoires, suivent une trajectoire menant inexorablement \u00e0 la dislocation de la puissance, de l&rsquo;id\u00e9e, de la destin\u00e9e de l&rsquo;am\u00e9ricanisme. Il appara&icirc;t clairement que notre propre situation ne pourra tenir si les USA s&rsquo;effondrent comme ils sont en train de faire, et qu&rsquo;il y aura bien l\u00e0 la chute d&rsquo;une civilisation.<\/p>\n<\/p>\n<p><p>Les \u00ab\u00a0autres\u00a0\u00bb, ceux que l&rsquo;on pourrait consid\u00e9rer comme des p\u00f4les de puissance alternatifs, capables de prendre la place des USA, ne le pourront pas parce que la plupart des outils de la domination-fascination sont dans la substance m\u00eame de cette puissance, et seulement dans elle. Aucune force ext\u00e9rieure, \u00e0 notre sens, n&rsquo;est capable de prendre cette place, dans un mod\u00e8le qui a \u00e9t\u00e9 con\u00e7u par et pour l&rsquo;unipolarit\u00e9 agressive des USA. Il nous semble m\u00eame qu&rsquo;on trouve, <a href=\"https:\/\/www.dedefensa.org\/article\/notes-sur-une-nouvelle-resistance\">dans les mots<\/a> du vice-ministre russe des affaires \u00e9trang\u00e8res d\u00e9crivant l&rsquo;attitude russe vis-\u00e0-vis des \u00e9v\u00e9nements US, comme une sorte de fatalit\u00e9 russe, forg\u00e9e au feu d&rsquo;une histoire si intens\u00e9ment tragique, pour nous dire : \u00ab\u00a0Il va y avoir un cataclysme, nous rentrons la t\u00eate dans les \u00e9paules, nous verrouillons portes et fen\u00eatres et nous attendons que passe la temp\u00eate\u00a0\u00bb : &laquo; <em>Nous n&rsquo;avons eu et n&rsquo;avons aucun contact avec l&rsquo;\u00e9quipe Biden. Nous traitons cela comme un changement de temps en-dehors de chez nous, \u00e0 observer de notre fen\u00eatre. <\/em>&raquo;<\/p>\n<\/p>\n<p><p>Il va de soi et on le sent bien, que toutes les roucoulades et rodomontades autour de Biden et de Trump, les d\u00e9lires conspirationnistes et impr\u00e9cateurs contre Trump-le-fasciste, tout cela est extraordinairement hors de propos et de saison. La situation o&ugrave; sont nos dirigeants et nos Z\u00e9lites-Zombies (ZZ), \u00e0 la fois regardant l&rsquo;\u00e9norme crise (et ainsi, fascin\u00e9s par elle comme on le fut par les USA) et en m\u00eame temps n&rsquo;y voyant rien du tout (c&rsquo;est-\u00e0-dire n&rsquo;y comprenant rien du tout), est compl\u00e8tement conforme \u00e0 ce que nous savons et observons d&rsquo;eux par ailleurs.<\/p>\n<\/p>\n<p><p>Le plus remarquable dans l&rsquo;\u00e9volution pr\u00e9sente est l&rsquo;absence relative de violence excessive par rapport \u00e0 ce que l&rsquo;on peut attendre dans cette sorte d&rsquo;\u00e9v\u00e9nement ; ou plut\u00f4t doit-on parler d&rsquo;inutilit\u00e9 de la violence, selon ce qu&rsquo;on entend d&rsquo;habitude dans ce concept ? Il semble que la tension formidable de la communication, avec les haine extr\u00eamement fortes, les simulacres et les <em>narrative<\/em>, le processus presque &lsquo;naturel\u00a0\u00bb de dissolution et de d\u00e9constructuration de toutes les formes les plus n\u00e9cessaires \u00e0 l&rsquo;\u00e9quilibre social, les effets de ceci et de cela sur les psychologies, suffisent pour propulser la crise vers un paroxysme toujours plus haut, toujours plus d\u00e9cisif, sans la d\u00e9samorcer en aucune fa\u00e7on.<\/p>\n<\/p>\n<blockquote>\n<p><p>Bien au contraire, comme on le lit chez Alastair Crooke, on passe dans l&rsquo;ampleur de l&rsquo;\u00e9v\u00e9nement, c&rsquo;est-\u00e0-dire la proposition de plus en plus per\u00e7ue comme coh\u00e9rente que l&rsquo;on est en train de passer \u00e0 un &lsquo;nouvel \u00e2ge&rsquo; et surtout en s&rsquo;appuyant et en se justifiant de cette action sur une opposition f\u00e9roce \u00e0 ce qui est en place, sans v\u00e9ritable difficult\u00e9, sans r\u00e9elle argumentation de d\u00e9ni ; passant d&rsquo;une affaire presque provinciale d&rsquo;ill\u00e9galit\u00e9 \u00e9lectorale r\u00e9alis\u00e9e par des corrompus notoires et des menteurs coutumiers, au naufrage catastrophique d&rsquo;une Id\u00e9e tenant la civilisation en place, laquelle pr\u00e9tendait proclamer la Fin de l&rsquo;Histoire et continuant sa prospective avantageuse en tenant bon sur le remplacement de l&rsquo;intelligence humaine par l&rsquo;AI, selon les conceptions des philosophes absolument \u00e9clair\u00e9s et si s&ucirc;rs d&rsquo;eux qui dirigent Google et autres GAFAM fourr\u00e9s aux $milliards de monnaie de singe.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>(On conc\u00e9dera n\u00e9anmoins que ce dernier point sur les esp\u00e9rances de l&rsquo;AI n&rsquo;est pas vraiment incroyable ni catastrophique lorsqu&rsquo;on contemple ce que les directions politiques de l&rsquo;esp\u00e8ce, pr\u00e9tendument anim\u00e9es par une intelligence humaine &lsquo;naturelle&rsquo;, parviennent \u00e0 produire par <a href=\"https:\/\/www.dedefensa.org\/article\/rapsit-usa2020-les-cons-volant-en-escadrille\">les temps qui volent<\/a>. Cela ne justifie en rien l&rsquo;AI, ni ne lui donne la moindre &lsquo;chance&rsquo; d&rsquo;exister vraiment, mais cela fixe les responsabilit\u00e9s et les complicit\u00e9s.)<\/p>\n<\/p>\n<p><p>Ainsi n&rsquo;est-il pas effectivement assur\u00e9 que cet effondrement doive passer par les violences consid\u00e9rables que l&rsquo;on pr\u00e9voit et attend en g\u00e9n\u00e9ral pour cet \u00e9v\u00e9nement. Il se confirme par ailleurs que cette d\u00e9vastation intellectuelle de l&rsquo;ordre \u00e9tabli se fait le plus simplement du monde, par le biais d&rsquo;un intense pourrissement int\u00e9rieur de cet ordre, aboutissant \u00e0 sa formidable fragilit\u00e9 dans la perception intuitive qu&rsquo;on en a. Ainsi le paradoxe est-il qu&rsquo;on est largement fond\u00e9 \u00e0 affirmer que l&rsquo;ordre en place, le Syst\u00e8me si l&rsquo;on veut, est d&rsquo;une puissance technique, technologique, physique et mat\u00e9rielle, absolument sans \u00e9gale et quasiment-absolue, alors qu&rsquo;il s&rsquo;av\u00e8re d&rsquo;une fragilit\u00e9 extr\u00eame jusqu&rsquo;\u00e0 l&rsquo;autodissolution dans sa structuration, dans ce que l&rsquo;on pourrait nommer sa l\u00e9gitimit\u00e9 psychologique.<\/p>\n<\/p>\n<blockquote>\n<p><p>Cette id\u00e9e n&rsquo;est \u00e9videmment pas neuve ni originale, comme toutes les grandes id\u00e9es, et les USA n&rsquo;ont cess\u00e9 d&rsquo;en sugg\u00e9rer la v\u00e9rit\u00e9 par leur existence, leur pr\u00e9tention, les nombreux simulacres qu&rsquo;ils ont essaim\u00e9s \u00e0 travers le monde. Elle s&rsquo;appuie <em>a contrario <\/em>sur la n\u00e9cessit\u00e9 de l&rsquo;ordre, de l&rsquo;harmonie et de l&rsquo;\u00e9quilibre, trois vertus de forme et d&rsquo;esprit qui d\u00e9finissent la formule des choses et des arrangements durables jusqu&rsquo;\u00e0 s&rsquo;installer dans l&rsquo;essence m\u00e9tahistorique. On est ainsi conduit \u00e0 pr\u00e9senter et \u00e0 d\u00e9velopper sans frein l&rsquo;hypoth\u00e8se que la \u00ab\u00a0civilisation devenue contre-civilisation\u00a0\u00bb, c&rsquo;est-\u00e0-dire avec le v\u00e9ritable hold-up, ou kidnapping, dont fut victime notre civilisation originelle qui luttait d\u00e9j\u00e0 pour sa survie, \u00e0 la fin du XVIII\u00e8me si\u00e8cle, lors de l&rsquo;\u00e9v\u00e9nement que nous avons d\u00e9crit comme le &lsquo;<a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-le-dechainement-de-la-matiere\">d\u00e9cha&icirc;nement de la Mati\u00e8re<\/a>&lsquo;, l&rsquo;hypoth\u00e8se donc que \u00ab\u00a0civilisation devenue contre-civilisation\u00a0\u00bb installait avec elle \u00e0 l&rsquo;origine les conditions de son effondrement ; cet effondrement ressemblant alors, dans la perspective des meilleures sources jusqu&rsquo;\u00e0 citer <a href=\"https:\/\/www.dedefensa.org\/article\/usa2020-la-gces-la-haine-et-le-suicide\">Lincoln lui-m\u00eame<\/a>, \u00e0 un v\u00e9ritable hara-kiri.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Entre d&rsquo;autres et avec d&rsquo;autres, apr\u00e8s et avant d&rsquo;autres, l&rsquo;historien des civilisations Arnold Toynbee avait clairement, &ndash; quoique discr\u00e8tement, \u00e9tant Britannique, &ndash; identifi\u00e9 \u00e0 partir de ses connaissances et de son intuition la fatalit\u00e9 du sort de cette pseudo-&lsquo;civilisation occidentale&rsquo; dans ses \u00e9crits de la fin des ann\u00e9es 1940. On cite ici un passage de &laquo; <em>La Gr\u00e2ce de l&rsquo;Histoire<\/em> &raquo; (Tome-I), se rapportant \u00e0 cet aspect et de notre &lsquo;civilisation&rsquo;, et des conceptions de Toynbee identifiant parfaitement le d\u00e9s\u00e9quilibre par d\u00e9formation de cette &lsquo;civilisation&rsquo; sur elle-m\u00eame et sur l&rsquo;Histoire en g\u00e9n\u00e9ral, sans r\u00e9elle r\u00e9f\u00e9rence m\u00e9tahistorique objective puisque s&rsquo;installant elle-m\u00eame comme la r\u00e9f\u00e9rence m\u00e9taphysique objective ultime de l&rsquo;Histoire.<\/p>\n<\/p>\n<p><p>&laquo; &#8230;<em>Le point fondamental de cette ambigu\u00eft\u00e9<\/em> [de la puissance et de la durabilit\u00e9 de notre &lsquo;civilisation&rsquo;]<em> est bien en ceci qu&rsquo;en m\u00eame temps qu&rsquo;il pr\u00e9voit cette &lsquo;occidentalisation&rsquo; du monde, disons d&rsquo;une fa\u00e7on objective, sans trop para&icirc;tre en faire la critique malgr\u00e9 tout, Toynbee r\u00e9alise une critique disons indirecte mais \u00e0 potentialit\u00e9 fondamentale et bouleversante de cette civilisation occidentale-mondiale. Nous dirions qu&rsquo;il s&rsquo;agit, \u00e0 cet \u00e9gard, de sa position la plus int\u00e9ressante et la plus enrichissante, celle o&ugrave; il reste pleinement historien des civilisations tout en consid\u00e9rant l\u00a0\u00bbactualit\u00e9 civilisationnelle&rsquo;. Ainsi, en remettant constamment la civilisation occidentale \u00e0 sa place, c&rsquo;est-\u00e0-dire comme un \u00e9l\u00e9ment de la relativit\u00e9 de l&rsquo;histoire des civilisations et non comme quelque chose de diff\u00e9rent, d&rsquo;unique, voire de sublime comme l&rsquo;esprit de la modernit\u00e9 s&rsquo;est accoutum\u00e9 \u00e0 en faire la promotion jusqu&rsquo;\u00e0 faire de ses &lsquo;valeurs&rsquo; des \u00e9l\u00e9ments <strong>objectifs <\/strong>sinon <strong>supra-humains<\/strong> de la condition humaine r\u00e9alis\u00e9e et qui ne peut donc se r\u00e9aliser qu&rsquo;au sein de cette civilisation, Toynbee d\u00e9taille pour son analyse quelques consid\u00e9rations qui ne semblent servir qu&rsquo;\u00e0 l&rsquo;argumentaire qui para&icirc;trait de circonstance, et qui sont en r\u00e9alit\u00e9 fondamentales. Il en va dans ce sens lorsqu&rsquo;il explique cette subjectivit\u00e9 &lsquo;objectiv\u00e9e&rsquo; de facto du regard de l&rsquo;Occidental sur sa propre civilisation, c&rsquo;est-\u00e0-dire pour nous cette d\u00e9formation du regard du moderne sur l&rsquo;accomplissement de la modernit\u00e9 : le regard d\u00e9form\u00e9 de l&rsquo;Occidental d\u00e9pend d&rsquo;un \u00ab\u00a0horizon historique <\/em>[qui] <em>s&rsquo;est largement \u00e9tendu, \u00e0 la fois dans les deux dimensions de l&rsquo;espace et du temps<\/em><em>\u00ab\u00a0, mais dont la vision historique \u00ab\u00a0s&rsquo;est rapidement r\u00e9duite au champ \u00e9troit de ce qu&rsquo;un cheval voit entre ses &oelig;ill\u00e8res, ou de ce qu&rsquo;un commandant de sous-marin aper\u00e7oit dans son p\u00e9riscope<\/em>\u00ab\u00a0.&raquo;<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In\u00e9luctabilit\u00e9 de la voie sacr\u00e9e &bull; Ce texte se propose de faire une appr\u00e9ciation g\u00e9n\u00e9rale de la situation \u00e0 partir du constat de l&rsquo;extr\u00eame importance et de l&rsquo;extr\u00eame gravit\u00e9 de la crise de l&rsquo;am\u00e9ricanisme (plus encore que \u00ab\u00a0la crise des USA\u00a0\u00bb), c&rsquo;est-\u00e0-dire la \u00ab\u00a0crise de l&rsquo;am\u00e9ricanisme\u00a0\u00bb prise comme la crise de la Modernit\u00e9, et donc&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[2664,20414,8213,3423,2665,2642,2879,4053,3072,2639,13934],"class_list":["post-79522","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-alastair","tag-autodissolution","tag-bleus","tag-civilisation","tag-crooke","tag-nouvelle","tag-revolution","tag-rouges","tag-toynbee","tag-trump","tag-woke"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79522"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79522\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79522"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79522"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}