{"id":79529,"date":"2020-11-19T20:35:31","date_gmt":"2020-11-19T20:35:31","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2020\/11\/19\/mark-jack-face-a-linsurrection\/"},"modified":"2020-11-19T20:35:31","modified_gmt":"2020-11-19T20:35:31","slug":"mark-jack-face-a-linsurrection","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2020\/11\/19\/mark-jack-face-a-linsurrection\/","title":{"rendered":"Mark &amp; Jack face \u00e0 l&rsquo;insurrection"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Mark &#038; Jack face \u00e0 l&rsquo;insurrection<\/h2>\n<\/p>\n<p><p>19 novembre 2020 &ndash; Sur tous les fronts de la Grande Crise, un des affrontements op\u00e9rationnels essentiels concerne la communication. Je n&rsquo;aime pas et m&rsquo;oppose compl\u00e8tement \u00e0 la vision binaire-d\u00e9faitiste qui consiste \u00e0 dire : \u00ab\u00a0Les puissance de communication du Syst\u00e8me ne cessent de se renforcer et d&rsquo;avancer dans leur offensive, et elles vont bient\u00f4t nous r\u00e9duire au silence parce que nous sommes des moins-que-moutons, des agneaux peureux et consentants ; et nous attendons affol\u00e9s et paralys\u00e9s, et surtout consentants, d&rsquo;\u00eatre r\u00e9duits au &lsquo;silence des agneaux&rsquo;, censure bien ficel\u00e9s\u00a0\u00bb. Au contraire, j&rsquo;ai grande confiance, comme je l&rsquo;ai toujours eu depuis que d\u00e9termin\u00e9 la chose m&rsquo;est apparue \u00e9vidente avec un clin d&rsquo;&oelig;il complice, dans l&rsquo;extraordinaire puissance de <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-leffet-janus\">l&rsquo;effet-Janus<\/a> qui nous donne de plus en plus d&rsquo;armes pour riposter, \u00e0 mesure que s&rsquo;affirme l&rsquo;agression du Syst\u00e8me, &ndash; parce que nous ripostons avec ses armes !<\/p>\n<\/p>\n<p><p>L&rsquo;offensive de communication du Syst\u00e8me est partout en mode-bulldozer, certes, mais elle l&rsquo;est dans cette configuration \u00e9trange du simulacre. La derni\u00e8re chose en date, \u00e9norme, met en \u00e9vidence la principale &lsquo;arme&rsquo; du Syst\u00e8me lorsqu&rsquo;il se trouve brusquement soumis \u00e0 une contre-offensive m\u00e9chante dans le cours de bataille : le silence. Le Syst\u00e8me ne se bat pas, d&rsquo;ailleurs moins par calcul que par stup\u00e9faction sans doute, &ndash; je veux dire, stup\u00e9fait qu&rsquo;on ait os\u00e9 s&rsquo;opposer \u00e0 lui, de cette fa\u00e7on, non mais ! &ndash; le Syst\u00e8me se tait, comme s&rsquo;il proclamait : \u00ab\u00a0Non, cette contre-offensive ne peut \u00eatre et elle n&rsquo;est pas, dans mon monde il n&rsquo;y a pas de place pour elle. Donc, rien \u00e0 dire et taisons-nous, non pas comme si nous n&rsquo;entendions rien, mais r\u00e9ellement comme si rien n&rsquo;\u00e9tait dit puisqu&rsquo;effectivement c&rsquo;est le cas&#8230;\u00a0\u00bb. On le voit, mes agneaux puisque nous en sommes, dans cette affaire de fraude massive en train d&rsquo;\u00eatre hauss\u00e9e dans le domaine juridique formel par l&rsquo;\u00e9quipe de Trump emmen\u00e9e notamment par la super-avocate Sidney Powell, dans cette extraordinaire p\u00e9rip\u00e9tie de l&rsquo;attaque contre une station de la CIA \u00e0 Francfort men\u00e9e par des agences de s\u00e9curit\u00e9 US, &ndash; nous nous trouvons projet\u00e9s dans des circonstances singuli\u00e8rement exceptionnelles. Cela conduit \u00e0 <a href=\"https:\/\/www.dedefensa.org\/article\/rapsit-usa2020-vers-la-guerre-civile\">cette remarque<\/a> qui dit tout tandis qu&rsquo;ils se taisent, attendant fermement du Ciel que s&rsquo;\u00e9vanouisse l&rsquo;incroyable, inacceptable et insupportable <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-verite-de-situation-verite\">v\u00e9rit\u00e9-de-situation<\/a> :<\/p>\n<\/p>\n<p><p>&laquo; <em>Un des aspects extraordinaires, irr\u00e9els et f\u00e9\u00e9riques de cette affaire, est qu&rsquo;elle n&rsquo;est quasiment pas relay\u00e9e par la &lsquo;grande presseSyst\u00e8me&rsquo; du bloc-BAO, bien qu&rsquo;il s&rsquo;agisse de personnalit\u00e9s officielles, faisant des d\u00e9clarations publiques, etc. Il semble donc de plus en plus clairement (?) que nous vivons dans des mondes parall\u00e8les qui sont tout juste dispos\u00e9s \u00e0 se montrer leurs culs ou \u00e0 se cracher dessus de temps en temps, avec l&rsquo;un des camps criant \u00e0 gorge d\u00e9ploy\u00e9, comme un goret qu&rsquo;on \u00e9gorge, sa vertu et sa puissance de tol\u00e9rance, d&rsquo;\u00e9quit\u00e9 et de justice. Dont acte, ou &lsquo;dont acte no-act&rsquo; : il s&rsquo;agit de r\u00e9pondre \u00e0 notre engagement \u00e9vident, et par cons\u00e9quent il s&rsquo;agit de dire que, du c\u00f4t\u00e9 de la presseSyst\u00e8me, de la plus formidable architecture de propagande, jusqu&rsquo;\u00e0 former un r\u00e9el simulacre dont la mission est de faire croire qu&rsquo;il existe et que rien d&rsquo;autre que lui-m\u00eame ne peut exister, tout se passe s\u00e9rieusement comme si rien de s\u00e9rieux ne se passait<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Cette bataille est beaucoup plus forte aux USA que sur nos rivages et sur nos terres grandioses (o&ugrave; il s&rsquo;agit seulement de Covid, puisqu&rsquo;aux USA, pour nous la question est r\u00e9gl\u00e9e, Biden \u00e9lu et tout rentrant dans l&rsquo;ordre), &ndash; mais c&rsquo;est le m\u00eame combat, comme dit la chanson. Ce qui se passe aux USA est donc du plus grand int\u00e9r\u00eat. Justement, que se passe-il ? On passe en revue quelques aspects de la chose, pour constater d&rsquo;ailleurs que, dans cette bataille de la communication comme dans beaucoup d&rsquo;autres, les acteurs de diff\u00e9rents engagements virevoltent et qu&rsquo;il faut s&rsquo;y adapter, tant\u00f4t alli\u00e9s tant\u00f4t adversaires.<\/p>\n<\/p>\n<p><p>&bull; Il y a le cas des super-g\u00e9ants GAFAM, de plus en plus intrusifs et &lsquo;censeuriels&rsquo;, selon le n\u00e9ologisme que je leur r\u00e9serve avec empressement comme l&rsquo;on fait devant des censeurs exemplaires. Par exemple, Mark &#038; Jack, de Facebook et Tweeter, passaient avant-hier, par t\u00e9l\u00e9-citation \u00e0 compara&icirc;tre, devant la Commission des affaires juridiques du S\u00e9nat, r\u00e9unies en autant de t\u00e9l\u00e9-inquisiteurs. Le plus saignant d&rsquo;entre tous fut son pr\u00e9sident, le r\u00e9publicain Lindsay Graham, et il a mis une fois de plus en \u00e9vidence un de ces caract\u00e8res qui n&rsquo;est pas officiels mais qui jouent un r\u00f4le important dans ces entreprises g\u00e9antes o&ugrave; le patron-propri\u00e9taire lest\u00e9 de $milliards joue un r\u00f4le d&rsquo;inspirateur id\u00e9ologique essentiel : ils sont tous d&rsquo;une sottise, d&rsquo;une inculture, d&rsquo;une na\u00efvet\u00e9 politique et d&rsquo;une incons\u00e9quence extraordinaire. Interrog\u00e9s par Graham, ils r\u00e9pondent qu&rsquo;ils ne savent pas, ils se contredisent, pourquoi avoir censur\u00e9 ceci et pas cela, ah oui ah non&#8230; Jamais une g\u00e9n\u00e9ration de &lsquo;g\u00e9ants&rsquo; du <em>business<\/em> US charg\u00e9s d&rsquo;une telle puissance nominale, n&rsquo;aura d\u00e9ploy\u00e9 un vide intellectuel et un go&ucirc;t pour le conformisme dans cette mesure qui les affecte d&rsquo;abord eux-m\u00eames et leurs instructions. Ils sont nuls, purs simulacres postmodernes ; c&rsquo;est pi\u00e8tre satisfaction d&rsquo;avoir de tels ennemis&#8230;<\/p>\n<\/p>\n<p><p>&bull; Par cons\u00e9quent, je ne suis pas m\u00e9content de constater que, cette fois, apr\u00e8s tant d&rsquo;autres occasions o&ugrave; l&rsquo;on r\u00e9clamait la chose, des alternatives \u00e0 leur monopole se pr\u00e9sente. Il y a bien entendu la plate-forme <em><a href=\"https:\/\/parler.com\/auth\/access\">Parler<\/a><\/em>, dont on parle beaucoup en ce moment. Il s&rsquo;agit d&rsquo;une initiative \u00e9videmment politique, largement de tendance conservatrice ou du genre, &ndash; ce qui m&rsquo;importe assez peu. L&rsquo;essentiel est que la chose soit lanc\u00e9e contre les g\u00e9ants-nains du GAFFAM. Le patron de <em>Parler<\/em> commence \u00e0 beaucoup parler, comme il l&rsquo;a fait dans une interview \u00e0 FoxNews, et cela rapport\u00e9 par &lsquo;<em><a href=\"https:\/\/www.theepochtimes.com\/parler-ceo-defends-free-speech-its-not-against-the-law-to-have-those-opinions_3584197.html\">The Epoch Times<\/a><\/em>&lsquo; o&ugrave; on le voit exprimer sans ambages sa position.<\/p>\n<\/p>\n<p><p>&laquo; <em>Le PDG de &lsquo;Parler&rsquo;, r\u00e9seau d\u00e9crit comme une alternative \u00e0 Twitter, a d\u00e9fendu la libert\u00e9 d&rsquo;expression dans une interview mardi alors que se d\u00e9veloppe contre cette plateforme de r\u00e9seaux sociaux une critique tr\u00e8s forte de la presseSyst\u00e8me.<\/em><\/p>\n<p>&raquo; <em>\u00ab\u00a0Les gens disent des choses folles en ce moment\u00a0\u00bb et \u00ab\u00a0ce n&rsquo;est pas ill\u00e9gal d&rsquo;avoir des opinions critiques \u00e0 ce propos\u00a0\u00bb, a d\u00e9clar\u00e9 le PDG de Parler, John Matze, \u00e0 Fox News. Il r\u00e9pondait \u00e0 une question sur les raisons pour lesquelles les m\u00e9dias de la presseSyst\u00e8me sont de plus en plus critiques de sa plateforme.<\/em><\/p>\n<p>&raquo; <em>Je leur demande toujours : \u00ab\u00a0Que pensez-vous du Premier amendement ? Croyez-vous que nous devrions avoir quelqu&rsquo;un \u00e0 New York, disons au milieu de Times Square, pour vous dire ce que vous pouvez dire et ce que vous ne pouvez pas dire ?\u00a0\u00bb observe Matze. \u00ab\u00a0Parce que c&rsquo;est ce que font ces entreprises <\/em>[Facebook, Tweeter &#038; Cie]<em>.\u00a0\u00bb<\/em><\/p>\n<p>&raquo; <em>\u00ab\u00a0J&rsquo;ignore pourquoi ils ont si peur. C&rsquo;est peut-\u00eatre parce qu&rsquo;ils n&rsquo;aiment pas que le peuple reprenne le pouvoir\u00a0\u00bb. <\/em>[&#8230;]<em> \u00ab\u00a0Ce n&rsquo;est pas ill\u00e9gal de s&rsquo;exprimer\u00a0\u00bb, a-t-il poursuivi&#8230; \u00ab\u00a0Si vous aimez un candidat politique ou un autre, si vous croyez ou ne croyez pas au changement climatique, etc., il n&rsquo;y a aucune raison de vous bannir des r\u00e9seaux \u00e0 cause de cela\u00a0\u00bb<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Certes, tout cela n&rsquo;est pas g\u00e9nial ni une r\u00e9v\u00e9lation inattendue, mais il faut dire que Matze joue sur du velours \u00e0 cet \u00e9gard. Au moyen d&rsquo;\u00e9vidences qui sont dans l&rsquo;esprit de tant de gens qui en ont assez de la r\u00e8gle qui vous tape sur les doigts des petits marquis de la pens\u00e9e-<em>Woke<\/em>, Mark &#038; Jack <em>and<\/em> Co., il ne fait que r\u00e9pondre \u00e0 sa main aux attaques qui se d\u00e9veloppent dans le chef des tr\u00e8s-z\u00e9l\u00e9 amis de la presseSyst\u00e8me contre <em>Parler.<\/em> Ces attaques sont la meilleure pub qu&rsquo;on puisse faire au nouveau r\u00e9seau, qui acquiert ainsi, sans grand effort, une place de choix dans \u00ab\u00a0la cour des super-grands\u00a0\u00bb du syst\u00e8me de la communication.<\/p>\n<\/p>\n<p><p>R\u00e9sultat : mont\u00e9e en fl\u00e8che du r\u00e9seau <em>Parler<\/em>, selon une logique prospective qui devrait durer dans la mesure o&ugrave; ce mouvement suit exactement la ligne d&rsquo;affrontement de la crise aux USA. Selon <em><a href=\"https:\/\/www.zerohedge.com\/political\/fox-news-viewership-exodus-so-bad-msnbcs-morning-joe-just-unseated-fox-friends\">ZeroHedge.com<\/a><\/em>, &laquo; <em>&lsquo;Parler&rsquo; a r\u00e9cemment \u00e9t\u00e9 couronn\u00e9 comme l&rsquo;application gratuite la plus t\u00e9l\u00e9charg\u00e9e aux USA, sur l&rsquo;Appel Store mobile de Apple et sur le Play Store de Google. Durant la semaine \u00e9lectorale, &lsquo;Parler&rsquo; a enregistr\u00e9 plus d&rsquo;un million d&rsquo;inscriptions, atteignant \u00e0 ce point un total de 3,6 millions, selon le cabinet de recherche Sensor Tower<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Effectivement, si l&rsquo;on est loin des effectifs des GAFAM, il est tr\u00e8s logique de compter avec une dynamique d&rsquo;ampleur colossale dans ce temps de crise, o&ugrave; le syst\u00e8me de la communication joue un r\u00f4le si important, o&ugrave; les monopolistes-censoriels se montrent si agressifs et si intrusifs, poussant une partie consid\u00e9rable de leur client\u00e8le jusque-l\u00e0 emprisonn\u00e9e vers une alternative qui s&rsquo;affirme, c&rsquo;est-\u00e0-dire <a href=\"https:\/\/thepostmillennial.com\/bongino-backed-parler-soars-to-1-spot-in-app-stores-passes-tiktok-and-youtube\">vers <em>Parler <\/em>essentiellement<\/a>.<\/p>\n<\/p>\n<p><p>&bull; &#8230; Dans ce domaine, je dirais un mot de la plateforme russe <em>V-Kontakte<\/em>, essentiellement \u00e0 client\u00e8le russe jusqu&rsquo;ici. On en parle chez divers antiSyst\u00e8me, dont Patrick Armstrong, qui est un commentateur loyal et efficace. &Eacute;diteur de <em>Russia Observer<\/em>, Armstrong a largement exprim\u00e9 son opinion \u00e0 propos de la plateforme russe. Banni de Facebook pour non-conformit\u00e9, il est pass\u00e9 en 2018 \u00e0 <em><a href=\"https:\/\/vk.com\/?lang=en\">V-Kontakte<\/a> <\/em>et s&rsquo;en est trouv\u00e9 tout \u00e0 fait \u00e0 son aise.<em> V-Kontakt<\/em>, qui affiche plus de 100 millions de membres pour l&rsquo;essentiel en Russie, commence \u00e0 explorer d\u00e9sormais la p\u00e9n\u00e9tration du march\u00e9 antiSyst\u00e8me du <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-bloc-bao-1\">bloc-BAO<\/a>. Il y a notamment une <a href=\"https:\/\/vk.com\/club2378190\">version anglaise<\/a> et une nouvelle <a href=\"https:\/\/vk.com\/club9587648\">version fran\u00e7aise<\/a>.<\/p>\n<\/p>\n<p><p>&bull; Enfin, une derni\u00e8re remarque concernant l&rsquo;\u00e9volution du syst\u00e8me de la communication aux USA, l&rsquo;affaire Trump-FoxNews. Le soir des \u00e9lections, FoxNews a affich\u00e9 la couleur et est pass\u00e9 dans le camp antiTrump, montrant par l\u00e0 que sa pseudo-alliance avec Trump \u00e9tait de pure circonstance tactique. Le volte-face s&rsquo;est faite avec une extr\u00eame brutalit\u00e9 du c\u00f4t\u00e9 de FoxNews, me faisant quant \u00e0 moi m&rsquo;interroger une fois de plus : ces gens manquent-ils totalement de sens tactique, du go&ucirc;t de la man&oelig;uvre, de la nuance ? Ou bien plus simplement et pour l&rsquo;essentiel, &ndash; un peu de r\u00e9alisme-jugeotte, PhG !, &ndash; s&rsquo;agit-il du cas incroyable mais in\u00e9vitable o&ugrave; &lsquo;<em>The Masters of the Universe<\/em>&lsquo;, volant effectivement <a href=\"https:\/\/www.dedefensa.org\/article\/rapsit-usa2020-les-cons-volant-en-escadrille\">en escadrille<\/a>, croient vraiment qu&rsquo;ils sont les ma&icirc;tres de l&rsquo;univers et qu&rsquo;ils peuvent faire ce qu&rsquo;ils veulent, qu&rsquo;ils le resteront (ma&icirc;tres de l&rsquo;univers), etc&#8230; Aussi simple que \u00e7a, en escadrille vous dis-je, et nous dirig\u00e9s par cette pl\u00e8be de l&rsquo;esprit, de la perception, du go&ucirc;t des choses, cette vulgarit\u00e9 du caract\u00e8re&#8230;<\/p>\n<\/p>\n<p><p>Quoi qu&rsquo;il en soit, depuis le 3 novembre, l&rsquo;audience de FoxNews tombe en chute libre, au point que &lsquo;<em>Morning Joe<\/em>&lsquo;, l&rsquo;\u00e9mission-phare du matin de MSNBC, a, pour la premi\u00e8re fois <a href=\"https:\/\/www.zerohedge.com\/political\/fox-news-viewership-exodus-so-bad-msnbcs-morning-joe-just-unseated-fox-friends\">avant-hier<\/a>, d\u00e9pass\u00e9 en audience (6 millions de t\u00e9l\u00e9spectateurs contre 4) l&rsquo;\u00e9mission concurrente &lsquo;<em>Fox &#038; Friends<\/em>&lsquo;. Et, dans ce domaine \u00e9galement, il y a des alternatives, dans le chef de deux r\u00e9seaux de la droite extr\u00eame US, qui se trouvent en embuscade avec leurs audiences \u00e9tiques qu&rsquo;ils voudraient voir \u00e9norm\u00e9ment grossir. On ne trouve pas moins que l&rsquo;un des archers-mercenaires de l&rsquo;arm\u00e9e CNN, pas m\u00e9content de se payer FoxNews, qui nous informe l\u00e0-dessus, \u00e0 propos de <em>NewsMaxTV<\/em>&#8230; <a href=\"https:\/\/cnn.it\/3plqHA3\">Brian Stelter<\/a>, donc (notez, pour mieux appr\u00e9cier les pr\u00e9cisions chronologiques des audiences, que l&rsquo;article a \u00e9t\u00e9 publi\u00e9 le 12 novembre):<\/p>\n<\/p>\n<p><p>&laquo; <em>Les fans du pr\u00e9sident Trump qui pensent que Fox News n&rsquo;est pas assez \u00e0 droite ont une autre option sur le c\u00e2ble et le satellite : Newsmax TV.<\/em><\/p>\n<p>&raquo; <em>Et quelque chose de dramatique est arriv\u00e9 la semaine derni\u00e8re : pour la premi\u00e8re fois, un grand nombre de t\u00e9l\u00e9spectateurs se sont tourn\u00e9s vers Newsmax TV. <\/em><\/p>\n<p>&raquo; <em>Ces deux faits sont li\u00e9s. Certains loyalistes de Trump s&rsquo;en prennent \u00e0 Fox et changent de cha&icirc;ne en faveur de Newsmax. Bien que Newsmax soit encore beaucoup plus petite que la Fox, c&rsquo;est le d\u00e9fi de droite le plus solide jamais lanc\u00e9 \u00e0 Fox.<\/em><\/p>\n<p>&raquo; <em>Au cours de l&rsquo;\u00e9t\u00e9, lorsque j&rsquo;ai commenc\u00e9 \u00e0 surveiller l&rsquo;indice d&rsquo;\u00e9coute Nielsen de Newsmax, la cha&icirc;ne comptait une audience moyenne de 25 000 t\u00e9l\u00e9spectateurs, chiffre vraiment minuscule par rapport \u00e0 n&rsquo;importe quelle norme d&rsquo;information t\u00e9l\u00e9vis\u00e9e. &Agrave; l&rsquo;approche des \u00e9lections, l&rsquo;audience a augment\u00e9, mais ce n&rsquo;\u00e9tait encore qu&rsquo;une mouche sur le dos de l&rsquo;\u00e9l\u00e9phant Fox. Au cours de la derni\u00e8re semaine d&rsquo;octobre, Newsmax n&rsquo;enregistrait encore que 65 000 t\u00e9l\u00e9spectateurs en moyenne.<\/em><\/p>\n<p>&raquo; <em>Puis vint l&rsquo;\u00e9lection. Newsmax a grimp\u00e9 \u00e0 une moyenne de 182 000 t\u00e9l\u00e9spectateurs pendant la semaine \u00e9lectorale qui s&rsquo;est termin\u00e9e dimanche. Et il augmente encore plus cette semaine <\/em>[du 9 novembre]<em>. Lundi <\/em>[9 novembre]<em>, la cha&icirc;ne avait une moyenne de 347 000 t\u00e9l\u00e9spectateurs, le mardi <\/em>[10 novembre]<em>, 437 000. Les \u00e9missions du soir comme &lsquo;Spicer &#038; Co&rsquo; et &lsquo;Greg Kelly Reports&rsquo; atteignent 700 000 et 800 000 t\u00e9l\u00e9spectateurs. Ces \u00e9missions avaient du mal \u00e0 atteindre les 100 000 avant les \u00e9lections ! Quelque chose a chang\u00e9<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>On attend donc le d\u00e9part de Tucker Carlson et de Sean Hannity vers <em>NewsMaxTV<\/em> pour les prochaines semaines&#8230;<\/p>\n<\/p>\n<p><p>&bull; Comme chacun sait, car on l&rsquo;a d\u00e9j\u00e0 dit, cette \u00e9volution &lsquo;censurielle&rsquo; d&rsquo;une domesticit\u00e9 du Syst\u00e8me faite d&rsquo;idiots devenus fous doit continuer en mode-<em>turbo<\/em>. Lorsqu&rsquo;on a affaire \u00e0 des \u00ab\u00a0idiots devenus fous\u00a0\u00bb, le pire est une certitude pour la suite ; et comme ils sont au moins aussi stupides que d\u00e9ments, ils agiront d&rsquo;une fa\u00e7on extr\u00e9miste, de fa\u00e7on \u00e0 se faire au bout du compte le plus de mal possible \u00e0 eux-m\u00eames. Quoi qu&rsquo;il en soit, <a href=\"https:\/\/www.dedefensa.org\/article\/rapsit-usa2020-vers-la-guerre-civile\">on devine d\u00e9j\u00e0<\/a> les menaces qui pointent et qui d\u00e9clencheront, selon le processus dont on voit partout des exemples, des r\u00e9actions extr\u00eamement violentes et compl\u00e8tement inattendues :<\/p>\n<\/p>\n<p><p>&laquo; <em>Il est probable que la bataille de la communication, avec les interf\u00e9rences habituelles et scandaleuses des divers GAFAM, sera elle aussi d&rsquo;une extraordinaire intensit\u00e9. Un lecteur de SST a affirm\u00e9 en commentaire de l&rsquo;annonce par Lang de l&rsquo;annulation de son message avec la r\u00e9f\u00e9rence du texte de Johnson, que la prochaine \u00e9tape serait \u00ab\u00a0l&rsquo;interdiction d&rsquo;acc\u00e8s \u00e0 certains sites \u00e9trangers et m\u00eame US\u00a0\u00bb, par les autorit\u00e9s ; ce lecteur affirme parler \u00e0 partir de sources tr\u00e8s bien inform\u00e9es, dans une rubrique de commentaire (celle de SST) en g\u00e9n\u00e9ral tr\u00e8s riches d&rsquo;informations du fait d&rsquo;un lectorat tr\u00e8s li\u00e9s \u00e0 des carri\u00e8res ou des occupations dans le renseignement. (Lang est un ancien colonel de la DIA.)<\/em> &raquo;<\/p>\n<\/p>\n<p><p>Cette perspective catastrophique ouvre elle aussi des perspectives de r\u00e9actions, calcul\u00e9es ou instinctives peu importe, qui seront \u00e9galement catastrophiques, mais pour celui qui aura d\u00e9clench\u00e9 cette phase de l&rsquo;attaque apr\u00e8s d&rsquo;autres. Chaque fois, les choses se mettent en place de la m\u00eame fa\u00e7on, et le plus extraordinaire est bien que le d\u00e9cha&icirc;nement constant de l&rsquo;\u00e9norme puissance du Syst\u00e8me qui p\u00e8se sur nous depuis si longtemps, ne fait que reculer de plus en plus sinon d\u00e9cisivement le moment sinon la possibilit\u00e9 d&rsquo;une victoire totale, et cela en usant le Syst\u00e8me, en l&rsquo;\u00e9puisant, en le vidant de ses forces comme on vide de son sang ; en le conduisant \u00e0 faire \u00e9talage, sans le poindre frein, de toute son incommensurable stupidit\u00e9.<\/p>\n<\/p>\n<p><p>Que vous dire d&rsquo;autres sinon mon immense satisfaction, du fait du r\u00e9sultat objectif de cette superbe agitation, de ce d\u00e9sordre compl\u00e8tement hors de soi, qui est la destruction suppl\u00e9mentaires de certaines structures du Syst\u00e8me (d\u00e9constructuration) ? Car, que penser d&rsquo;autre, lorsque, par exemple, l&rsquo;on voit l&rsquo;\u00e9volution de FoxNews, qui a eu certes une politique d&rsquo;opposition \u00e0 la presseSyst\u00e8me (dont Fox fait partie), pendant un certain temps, &ndash; temps qui fut celui de nos applaudissement ; mais qui reste un fleuron de la presseSyst\u00e8me du requin-escroc Rupert Murdoch, qui vaut en immonderies et en poubellation-orduriennes les petits marquis des GAFAM ; et donc ses ennuis pour avoir trahi Trump, qui ne vaut gu\u00e8re mieux par beau temps mais qui devient brillant lorsqu&rsquo;on veut le couler, doivent absolument r\u00e9jouir un esprit sain dans un corps sain. Quant au renforcement in\u00e9luctable de quelques organes de communication de la droite tr\u00e8s-dure et la venue possible de nouveaux (une cha&icirc;ne TV-Trump si le pr\u00e9sident quitte la Maison-Blanche ?), cela permettra de crier une fois de plus au fascisme pour renforcer notre m\u00e9tabolisme postmoderne et remplacer les eaux que nous n&rsquo;avons plus le temps de prendre \u00e0 Spa, donc de renforcer les extr\u00eames de la gauche qui sont tr\u00e8s occup\u00e9s \u00e0 miner toute possibilit\u00e9 d&rsquo;une administration d\u00e9mocrate mod\u00e9r\u00e9 bidenienne (style social-d\u00e9mocrate tr\u00e8s BAO toujours jeune), de ce pr\u00e9sident-d\u00e9sign\u00e9 proche de devenir le pr\u00e9sident-faisant-fonction.<\/p>\n<\/p>\n<p><p>J&rsquo;ai certes l&rsquo;air de plaisanter un peu avec cette fa\u00e7on d\u00e9sinvolte de ne pas trop prendre <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-la-tragedie-bouffe\">le bouffe au tragique<\/a> parce que, face \u00e0 ces ombres \u00e9crasantes de fin du monde et d&rsquo;entropisation, l&rsquo;ironie et la satire ont leur place et une belle partie \u00e0 jouer. Elles constituent des armes excellentes et respectables dans l&rsquo;op\u00e9ration g\u00e9n\u00e9rale qui doit occuper toute notre strat\u00e9gie, cette op\u00e9ration du type \u00ab\u00a0le Roi est nu\u00a0\u00bb. Il est parfaitement bienvenu que Fox ait soutenu Trump contre la meute hirsutes des imb\u00e9ciles de la <em>Woke-<\/em>civilisation ; il est parfaitement bienvenu que Fox trahisse Trump d&rsquo;une fa\u00e7on \u00e9videmment ignoble pour que Trump soit oblig\u00e9 de p\u00e9daler encore plus, de s&#8217;emporter au-del\u00e0 de tout ; et l&rsquo;effet d&rsquo;ensemble est parfaitement bienvenu parce qu&rsquo;il s&rsquo;agit d&rsquo;encore plus attiser leur haine, de tendre encore plus la puissance de l&rsquo;antagonisme qui reste confin\u00e9 dans le Grand-Asile-des-Folles qui fait danser et tanguer \u00ab\u00a0D.C.-la-folle\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>Ne vous y m\u00e9prenez pas, nous sommes am\u00e9ricanis\u00e9s jusqu&rsquo;\u00e0 la moelle-pourrie, ce qui est la meilleure des bonnes nouvelles, &ndash; quoique, comme \u00ab\u00a0nouvelle\u00a0\u00bb on fait plus neuf&#8230; Cela signifie que nous suivons ce m\u00eame chemin du d\u00e9sordre et de l&rsquo;effondrement, en bons chiens dress\u00e9s et fid\u00e8les compagnons de service. Nous aussi, nous allons devoir \u00e9voluer vers l&rsquo;insurrection forc\u00e9e de nos moyens de communication ; et, dans certains cas, \u00e0 entendre et voir certaines choses.<\/p>\n<\/p>\n<blockquote>\n<p><p>Ce que j&rsquo;ai trac\u00e9 plus haut, en rassemblant divers \u00e9l\u00e9ments dont certains sont, on l&rsquo;admettra, extr\u00eamement solides, n&rsquo;est qu&rsquo;une possibilit\u00e9. Il y en a d\u00e9j\u00e0 eu d&rsquo;autres de cette sorte et aucune n&rsquo;a \u00e9t\u00e9 d\u00e9cisive jusqu&rsquo;\u00e0 susciter une sorte de transmutation, et celle-l\u00e0 peut conna&icirc;tre le m\u00eame sort ; d&rsquo;autre part, on admettra que cette possibilit\u00e9 (la force de la dynamique &lsquo;en retour&rsquo; jusqu&rsquo;\u00e0 la transmutation) n&rsquo;a jamais \u00e9t\u00e9 aussi forte, jusqu&rsquo;\u00e0 solliciter l&rsquo;\u00e9tiquette de probabilit\u00e9. Le tableau g\u00e9n\u00e9ral pr\u00e9sente une dynamique de d\u00e9sordre convainquant, et la m\u00eame pulsion \u00e9trange continue \u00e0 donner ses effets, de plus en plus pr\u00e9cis\u00e9ment. Chaque phase met \u00e0 jour une puissance extraordinaire du Syst\u00e8me, et chaque fois c&rsquo;est pour encha&icirc;ner des effets contradictoires, voire catastrophiques. Ici, il s&rsquo;agit du domaine fondamental de la communication, o&ugrave; la puissance de leurs actes vicieux semble finir par susciter des r\u00e9actions qu&rsquo;on ne pensait pas possibles ; comme \u00e7a, sans rien chercher ni rien vouloir. Trump lui-m\u00eame, personnage totalement improbable et insignifiant, a d\u00e9clench\u00e9 chez eux une haine d&rsquo;une puissance absolument surhumaine, avec toutes les erreurs, toutes les fautes, toutes les incompr\u00e9hensions qui vont avec ; et aujourd&rsquo;hui Trump qui pourrait para&icirc;tre comme un h\u00e9ros sous certains \u00e9clairages et dans une certaine perspective.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Inutile de vous dire que rien dans tout cela n&rsquo;est ma tasse de th\u00e9, Trump en premier. Mais je ne suis pas l\u00e0 pour lever le petit doigt et boire ma tasse de th\u00e9. Je suis l\u00e0 pour assister, d\u00e9crire et commenter, &ndash; avec une r\u00e9elle fascination je ne le cache pas tout en assurant qu&rsquo;elle ne trouble en rien mon jugement, &ndash; cette m\u00e9canique sans aucun doute suprahumaine qui transforme toute les forces ainsi d\u00e9cha&icirc;n\u00e9es contre l&rsquo;autre en ce que la CIA, avec un flair certain, avait d\u00e8s l&rsquo;origine baptis\u00e9 &lsquo;<em>blowback<\/em>&lsquo;&#8230;  &lsquo;Coup en retour&rsquo;, &lsquo;coup de fouet en retour&rsquo;, cons\u00e9quences brutales et inattendues, peut-\u00eatre irr\u00e9versibles, pour soi, effet impr\u00e9vu d&rsquo;un acte vil et violent qu&rsquo;on a pos\u00e9, dont on attendait une victoire d\u00e9finitive.<\/p>\n<\/p>\n<p><p>(C&rsquo;est dr\u00f4le, la CIA avait song\u00e9 au mot et \u00e0 ce ph\u00e9nom\u00e8ne pour son compte, comme si elle devinait que la puissance dont elle disposait, et m\u00eame allait disposer, donnerait des effets catastrophiques pour elle ; le don de la double vue, ces espions-l\u00e0, excellents espions contrairement \u00e0 ce que l&rsquo;on dit d&rsquo;eux.)<\/p>\n<\/p>\n<p><p>Bref, nous n&rsquo;avons pas de meilleur alli\u00e9 que notre ennemi, et l&rsquo;on entend Jupiter-tonnant \u00e9clater d&rsquo;un rire joyeux.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mark &#038; Jack face \u00e0 l&rsquo;insurrection 19 novembre 2020 &ndash; Sur tous les fronts de la Grande Crise, un des affrontements op\u00e9rationnels essentiels concerne la communication. Je n&rsquo;aime pas et m&rsquo;oppose compl\u00e8tement \u00e0 la vision binaire-d\u00e9faitiste qui consiste \u00e0 dire : \u00ab\u00a0Les puissance de communication du Syst\u00e8me ne cessent de se renforcer et d&rsquo;avancer dans&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[1235,3104,19215,9473,20219,3005,8503,20438,20435,7503,1391,20429,2639,20436,10569],"class_list":["post-79529","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-biden","tag-cia","tag-dorsey","tag-foxnews","tag-gafam","tag-graham","tag-joe","tag-matze","tag-morning","tag-parler","tag-powell","tag-sidney","tag-trump","tag-v-kontakte","tag-zuckerberg"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79529"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79529\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79529"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79529"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}