{"id":79565,"date":"2020-12-14T12:13:26","date_gmt":"2020-12-14T12:13:26","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2020\/12\/14\/echos-de-bho\/"},"modified":"2020-12-14T12:13:26","modified_gmt":"2020-12-14T12:13:26","slug":"echos-de-bho","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2020\/12\/14\/echos-de-bho\/","title":{"rendered":"\u00c9chos de BHO"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">&Eacute;chos de BHO<\/h2>\n<\/p>\n<p><p>14 d\u00e9cembre 2020 &ndash; Disposant sur <em>Netflix <\/em>r\u00e9cemment d&rsquo;un documentaire d&rsquo;une \u00e9quipe de journalistes de HBO et r\u00e9alis\u00e9 par Greg Barker en 2017, je crois bien avoir dispos\u00e9 d&rsquo;une s\u00e9rieuse partie de la r\u00e9ponse \u00e0 la question de la provenance directe de la haine qui d\u00e9vore l&rsquo;Am\u00e9rique. Cette haine se mesure chaque jour, comme lorsque &lsquo;<em>Time<\/em>&lsquo; , commentant son.a &lsquo;<em>Person of The Year<\/em>&lsquo; en la.e unique et <a href=\"http:\/\/glorieux.se\/\">glorieux.se<\/a> &lsquo;personne&rsquo; de Biden-Harris, dit BH, d\u00e9signe Trump sous le surnom de &lsquo;<em>Le Minotaure<\/em>&lsquo;. L&rsquo;on g\u00e9mit dans ce texte \u00e0 propos de la calamit\u00e9 que cette B\u00eate monstrueuse a sem\u00e9e, et \u00e0 la pens\u00e9e vertueuse et courageuse de la t\u00e2che qui attend BH, cette t\u00e2che si lourde, si \u00e9puisante, malgr\u00e9 la superbe et loyale victoire :<\/p>\n<\/p>\n<p><p>&laquo; <em>Defeating the Minotaur was one thing; finding the way out of the labyrinth is another<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>&#8230; Ce qui nous ram\u00e8ne en 2016 car en 2016, avant la date fatale, c&rsquo;\u00e9tait encore la &lsquo;belle-\u00e9poque&rsquo;, avant la labyrinthe immonde o&ugrave; nous a conduit &lsquo;<em>Le Minotaure<\/em>&lsquo; ; et cela me ram\u00e8ne \u00e0 ce documentaire de 2017 dont le titre est &lsquo;<em>The Final Year<\/em>&lsquo;, qui est effectivement 2016, pr\u00e9cis\u00e9ment de janvier 2016 \u00e0 janvier 2017 ; et c&rsquo;est le cr\u00e9puscule injuste d&rsquo;une superbe chevauch\u00e9e qui avait entam\u00e9 la t\u00e2che magnifique de \u00ab\u00a0changer le monde\u00a0\u00bb (\u00ab\u00a0<em>To change the world<\/em>\u00ab\u00a0, rien de moins, car, vous savez, entre nous mais c&rsquo;est si vrai \u00ab\u00a0<em><a href=\"https:\/\/www.youtube.com\/watch?v=47MKGOPP4Zo\">Yes, We Can<\/a><\/em>\u00ab\u00a0), &ndash; ou, dans tous les cas, de commencer, c&rsquo;est promis, c&rsquo;est assur\u00e9.<\/p>\n<\/p>\n<p><p>Donc, une \u00e9quipe de journalistes de HBO a suivi BHO (le jeux des initiales, on n&rsquo;y r\u00e9siste pas), &ndash; le gouvernement Obama dans son &lsquo;ann\u00e9e finale&rsquo;, &ndash; et d&rsquo;ailleurs le docu commence sur une r\u00e9union de Ben Rhodes annon\u00e7ant \u00e0 ses collaborateurs que le pr\u00e9sident, BHO, a donn\u00e9 son accord \u00e0 ce projet. Les principaux personnages de ce &lsquo;<em>The Final Year<\/em>&lsquo;, ils sont quatre, ce sont essentiellement, outre Sa Majest\u00e9 BHO-Saint \u00e9videmment,<\/p>\n<p>Ben Rhodes, conseiller tr\u00e8s proche du pr\u00e9sident, son <em>speechwriter<\/em>, son double et \u00e9minence grise intellectuelle pour la politique de s\u00e9curit\u00e9 nationale ;<\/p>\n<p>Samantha Powers, sorte de <a href=\"https:\/\/www.linternaute.fr\/dictionnaire\/fr\/definition\/grande-gigue\/\">grande gigue<\/a>, ou <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Arapaima_gigas\">gigas<\/a>, efflanqu\u00e9e de haute taille d&rsquo;origine irlandaise, un peu cheffe-scoute et m\u00e8re-poule aussi bien de ses propres enfants que des pauvres petits enfants affam\u00e9s et malades des pays africains ravag\u00e9s par le colonialisme de l&rsquo;homme-blanc europ\u00e9en, du temps affreux des \u00ab\u00a0n\u00e9grillons\u00a0\u00bb, et aussi ambassadrice des USA \u00e0 l&rsquo;ONU ; pr\u00e9sent\u00e9e sous des dehors extr\u00eamement chaleureux et humanistes et s&rsquo;\u00e9tant manifest\u00e9e pour la chronique des envieux et des plumitifs m\u00e9disants, comme une harpie-belliciste des progressistes-interventionnistes (R2P), et adepte extr\u00eamement dou\u00e9e du f\u00e9minisme-guerrier <a href=\"https:\/\/www.dedefensa.org\/article\/hillary-et-ses-harpies-ou-le-feminisme-guerrier\">des \u00ab\u00a0Harpies\u00a0\u00bb d&rsquo;Hillary Clinton<\/a> ;<\/p>\n<p>et enfin l&rsquo;excellent et ondulant John Kerry, secr\u00e9taire d&rsquo;&Eacute;tat, tout en souplesse \u00e9l\u00e9gante et en finesse qui peut \u00eatre d&rsquo;une fermet\u00e9 de fer, repr\u00e9sentant de la vieille tradition diplomatique US et ancien combattant du Vietnam devenu leader de la contestation antiguerre d&rsquo;alors.<\/p>\n<\/p>\n<p><p>Le climat qui r\u00e8gne dans ce documentaire, par ailleurs d&rsquo;excellente facture et d&rsquo;un rythme enlev\u00e9, &ndash; on n&rsquo;a jamais dit que le diable n&rsquo;avait pas de talent de metteur en sc\u00e8ne, bien au contraire, &ndash; est fascinant de sophistication, d&rsquo;adulation d\u00e9contract\u00e9e (pour BHO-Saint), de certitude d&rsquo;exceptionnalit\u00e9 (\u00ab\u00a0<em>They change the world, indeed<\/em>\u00ab\u00a0). Tout ce qui est d&rsquo;habitude un peu lourd dans ce domaine, surtout US, avec les gardes du corps et les flics divers, les h\u00e9licos, les 4&#215;4 en colonnes, les communicants qui ne communiquent pas, les photographes officiels, tout cela devient d&rsquo;une gr\u00e2ce a\u00e9rienne, \u00e0 l&rsquo;image du POTUS-BHO. Ils s&rsquo;envolent, d&rsquo;un bureau de la Maison-Blanche \u00e0 un <em>Air Force One<\/em> de Boeing, d&rsquo;un rang de petits enfants africains que la cheffe-scoute Powers prend dans ses bras \u00e0 une conf\u00e9rence donn\u00e9e par BHO-Saint \u00e0 de jeunes Sud-Cor\u00e9ens enthousiastes.<\/p>\n<\/p>\n<p><p>On les voit bosser dur, s\u00e9rieux, entreprenants, s&rsquo;\u00e9changeant des claques dans le dos, une vraie bande de copains comme vous et moi, vous voyez ? M\u00eame que le bureau annexe pour m\u00e9ditation et pens\u00e9es ultimes de Ben Rhodes, un de ces deux ou trois dizaines de personnes qui m\u00e8nent le monde, est tout-petit-rikiki ; mais l&rsquo;on dirait bien que c&rsquo;est voulu ; de m\u00eame L\u00e9nine travaillait-il, camarade, dans un monstrueux capharna\u00fcm mal entretenu, d&rsquo;o&ugrave; il faisait trembler le monde.<\/p>\n<\/p>\n<p><p>Powers est \u00e0 l&rsquo;ONU comme chez elle et l&rsquo;on dirait qu&rsquo;elle est gardienne, femme de m\u00e9nage, cuisini\u00e8re et ma&icirc;tresse absolue et inconterstable, cette ma&icirc;tresse-femme, de l&rsquo;Organisation des Nations-Unies. Kerry, lui, \u00e0 l&rsquo;entregent des vieux-beaux gar\u00e7ons, si \u00e0 l&rsquo;aise (il a \u00e9pous\u00e9 une riche h\u00e9riti\u00e8re des <em>Katchup<\/em>, je crois), et il vient mettre juste un zeste de bonne tenue du type <a href=\"https:\/\/fr.wikipedia.org\/wiki\/George_Marshall_(g%C3%A9n%C3%A9ral)\">George Marshall<\/a> ou <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Cyrus_Vance\">Cyrus Vance<\/a> chez tous ces jeunes gens peut-\u00eatre un peu trop enthousiastes.<\/p>\n<\/p>\n<p><p>Ces gens ne cessent de parler de \u00ab\u00a0changer le monde\u00a0\u00bb, d&rsquo;y installer la paix bien entendu ; il parle avec une certaine modestie affich\u00e9e sionon ostentatoire, une bonne humeur communicative, un entrain plein d&rsquo;optimisme, dans le futur, dans le progr\u00e8s, dans la technologie, dans l&rsquo;humanitarisation de l&rsquo;humanitarisme. Powers salue sa femme de m\u00e9nage Maria comme une copine et pleure \u00e0 la c\u00e9r\u00e9monie qu&rsquo;elle pr\u00e9side, de la naturalisation en citoyenne US de Maria. Ils vous promettent tous que c&rsquo;est une terrible trag\u00e9die que la Syrie, et encore heureusement que les USA sont intervenus. Kerry parle avec chaleur \u00e0 son garde du corps, Rhodes au journaliste de HBO qui le filme.<\/p>\n<\/p>\n<p><p>Et puis, par-dessus tout, outre BHO-Saint bien entendu, au-dessus et \u00e0 c\u00f4t\u00e9 de lui, ou peut-\u00eatre juste un peu plus haut que lui, l&rsquo;exceptionnalisme de l&rsquo;exceptionnelle Am\u00e9rique. Quoi qu&rsquo;il se passe, quoi qu&rsquo;on en veuille, l&rsquo;Am\u00e9rique est l\u00e0, elle sauve le monde et le monde se pr\u00e9cipite pour l&rsquo;acclamer, l&#8217;embrasser, l&rsquo;aimer, et puis marcher au pas. BHO-Saint sourit de toutes ses dents. Vous vous y laissez prendre, et moi-m\u00eame j&rsquo;en viens \u00e0 dire : quelle efficacit\u00e9, quelle puissance, quelle bonne volont\u00e9, quel c&oelig;ur charmant et quelle simplicit\u00e9 ! Je ne peux cacher l&rsquo;impression d&rsquo;une classe exceptionnelle qui se d\u00e9gage d&rsquo;Obama, souple, \u00e9l\u00e9gant, avec son incroyable <em>cool<\/em>titude (compos\u00e9 de <em>cool-<\/em>attitude), comme disait Antoine de Caunes.<\/p>\n<\/p>\n<p><p>&#8230; Et puis tout d&rsquo;un coup, tout s&rsquo;effrite, tout s&rsquo;effondre, tout se d\u00e9sagr\u00e8ge. Vous avez Ben Rhodes, l&rsquo;<em>alter ego <\/em>du pr\u00e9sident pour la grande politique internationale, l&rsquo;homme de l&rsquo;ombre dont on ne peut se passer, le strat\u00e8ge du g\u00e9nie s\u00e9rieux et tranquille, qui confie \u00e0 la cam\u00e9ra de HBO, et cela en 2016 : &laquo; <em>L&rsquo;erreur qu&rsquo;on a pu faire&#8230; Poutine ne semble pas poursuivre les int\u00e9r\u00eats de la Russie. Il poursuit les int\u00e9r\u00eats de Poutine.. Ca nous a pris longtemps pour s\u00e9parer Poutine des Russes&#8230; Cet acteur hors-la-loi. <\/em>&raquo; Cela veut dire quoi, comme divers clins d&rsquo;yeux et phrases sibyllines nous ont pr\u00e9par\u00e9s \u00e0 le r\u00e9aliser ? Que Poutine est un vulgaire gangster, qu&rsquo;il roule pour lui seul, pour sa fortune, pour sa cruaut\u00e9 et qu&rsquo;il se fout du tiers comme du quart du sort de la Russie ; car &laquo; <em>les int\u00e9r\u00eats de la Russie<\/em> &raquo;, c&rsquo;est de faire ce que Washington D.C. veut que la Russie fasse, et Poutine n&rsquo;obtemp\u00e8re pas ! Ainsi est-il juste de dire que les saloperies pr\u00e9tendument russes, l&rsquo;Ukraine, la Crim\u00e9e, la Syrie, etc., sont en fait des saloperies de Poutine, ce minable petit racketteur, ce porte-flingue de bas \u00e9tage. Ainsi, voil\u00e0 le fin du fin de l&rsquo;esprit de cette prodigieuse bande de g\u00e9nies sous la direction de BHO-Saint ! Vous comprenez alors pourquoi ils travaillent comme des fous \u00e0 une r\u00e9volution de couleur de Moscou \u00e0 Saint-Petersbourg, puisque les Russes la r\u00e9clament, puisque ce sont &laquo; <em>les int\u00e9r\u00eats de la Russie<\/em> &raquo;&#8230; Je vous assure qu&rsquo;ils y croient tous, le dos charg\u00e9 de leurs vertus, de la sauvegarde qu&rsquo;ils dispensent dans ce monde de m\u00e9chants, de cruels, de faux-jeton. &laquo; <em>Seul le pr\u00e9sident Obama a une pens\u00e9e globale inclusive<\/em> &raquo; dit l&rsquo;un d&rsquo;eux, c&rsquo;est-\u00e0-dire \u00e0 inclure dans la super-<em>Pax Americana.<\/em><\/p>\n<\/p>\n<p><p>Puisque soudain le rideau s&rsquo;est d\u00e9chir\u00e9&#8230; Adieu, grande classe, <em>cool<\/em>attitude, exceptionnalisme, humanitarisme humanitarisant. Vrai de vrai, ces gens qui ont attaqu\u00e9 l&rsquo;Irak et l&rsquo;Afghanistan, d\u00e9sint\u00e9gr\u00e9 la Libye, qui bataillent dans combien d&rsquo;autres pays sans qu&rsquo;on ne le leur ait demand\u00e9 en aucune fa\u00e7on, qui assassinent quotidiennement par drones ; ces gens qui pourrissent comme autant d&rsquo;urines d&rsquo;incontinent divers autres pays de leurs r\u00e9volutions de couleur, &ndash; dont l&rsquo;Ukraine de Kiev-2014 est le plus fameux exemple de corruption absolue et n\u00e9o-nazie ; qui se fichent des lois internationales comme on se fiche de son premier papier de toilette&#8230; Eh bien, ces gens croient \u00e0 leur incroyables <em>narrative<\/em>, de l&rsquo;antirussisme &lsquo;primaire d&rsquo;en-dessous la ceinture&rsquo; au <em>Russiagate <\/em>mont\u00e9 contre Trump. Ces gens sont alors d&rsquo;une nullit\u00e9 sans fin, quasiment lucif\u00e9rien sans le savoir et si \u00e9l\u00e9gant en le sachant, ils sont le n\u00e9gatif g\u00e9om\u00e9trique de la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-verite-de-situation-verite\">v\u00e9rit\u00e9-de-situation<\/a> du monde, prisonnier de leur &lsquo;<em>story<\/em>&lsquo;, ce qu&rsquo;on nomme <em><a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-le-determinisme-narrativiste\">narrative<\/a><\/em> dans nos pages.<\/p>\n<\/p>\n<p><p>Il faut dire qu&rsquo;il y a un maitre de c\u00e9r\u00e9monie, un Monsieur Loyal qui fait terriblement bien son travail de bateleur. BHO-Saint, tel qu&rsquo;on le voit lors de cette conf\u00e9rence devant des \u00e9tudiants sud-cor\u00e9ens, ou bien est-ce des Japonais, ou m\u00eame des Chinois pourquoi pas, r\u00e9pondre \u00e0 cette question : &laquo; <em>Vous \u00eates un grand leader : comment faites-vous pour parvenir \u00e0 un grand leadership ? <\/em>&raquo; BHO-Saint est incroyable dans sa capacit\u00e9 de recevoir compliments et hommages, comme on met une lettre \u00e0 la poste, en douceur et selon toute \u00e9vidence&hellip; Et de r\u00e9pondre qu&rsquo;essentiellement, &laquo; <em>il faut avoir une story pour mobiliser les foules<\/em> &raquo; ; et d&rsquo;expliquer ce qu&rsquo;est une &lsquo;<em>story<\/em>&lsquo;, une histoire, un conte \u00e0 applaudir plus que debout, dans une <em>standing ovation <\/em>; et de leur donner cet exemple, \u00ab\u00a0La D\u00e9claration d&rsquo;Ind\u00e9pendance, et puis &lsquo;Tous les hommes naissent \u00e9gaux&rsquo;, c&rsquo;est une belle &lsquo;<em>story<\/em>&lsquo;, non ?\u00a0\u00bb ; et enfin, une petite h\u00e9sitation, sans doute apr\u00e8s avoir mesur\u00e9 ce que signifiait cette r\u00e9v\u00e9lation, que tout est simulacre, y compris \u00ab\u00a0Tous les hommes naissent \u00e9gaux\u00a0\u00bb, et qu&rsquo;il suffit d&rsquo;avoir un bon bonimenteur, &ndash; et de lancer cette habile r\u00e9serve en <em>post-scriptum<\/em> : \u00ab\u00a0Et puis, cela fixe un objectif pour l&rsquo;avenir\u00a0\u00bb&hellip; Bravo l&rsquo;artiste.<\/p>\n<\/p>\n<p><p>Apr\u00e8s cette belle le\u00e7on de magnanimit\u00e9 humaine, nous avons droit au voyage civilisationnel. Le dernier d\u00e9placement international des deux mandats de BHO-Saint est pour la Gr\u00e8ce, parce que, laisse-t-il comprendre, c&rsquo;est le berceau de notre civilisation, &ndash; y compris pour nous, Africains-Am\u00e9ricains ? Pas de pr\u00e9cision n\u00e9cessaire&hellip; BHO-Saint au Parth\u00e9non, les l\u00e8vres un peu serr\u00e9es, le regard lointain sur l&rsquo;Histoire qui nous pr\u00e9c\u00e8de, et vous disant que c&rsquo;est l\u00e0, oui c&rsquo;est bien l\u00e0, il y a 2500 ans, qu&rsquo;est n\u00e9e la d\u00e9mocratie. Il y a de quoi vous faire r\u00e9fl\u00e9chir, n&rsquo;est-ce pas ? Parce que tout de m\u00eame, cela ne manque ni de grandeur de vue, ni d&rsquo;originalit\u00e9.<\/p>\n<\/p>\n<blockquote>\n<p><p>Mais le clou du spectacle et la clef d\u00e9cisive de l&rsquo;\u00e9nigme, en v\u00e9rit\u00e9, c&rsquo;est Ben Rhodes qui nous le donne, sur la fin du film. C&rsquo;est le soir de l&rsquo;\u00e9lection de Trump. Plusieurs fois interrog\u00e9 auparavant, Rhodes avait affirm\u00e9, sans surprise et avec bien des arguments, que Trump n&rsquo;avait strictement aucune chance et qu&rsquo;Hillary poursuivrait l&rsquo;&oelig;uvre de BHO-Saint \u00e0 laquelle lui-m\u00eame, Rhodes, \u00e9tait corps et \u00e2me attach\u00e9. Ce soir-l\u00e0 de novembre 2016, il est assis, seul, sur l&rsquo;appui en ciment ceinturant une esplanade, dans l&rsquo;ombre en clair-obscur d&rsquo;un cr\u00e9puscule aux couleurs tragiques, et dans l&rsquo;horrible marasme d&rsquo;un immense d\u00e9sarroi. Le cameraman-journaliste l&rsquo;interroge : \u00ab\u00a0Que ressentez-vous ?\u00a0\u00bb Je crois que Rhodes essaie cinq ou six fois de r\u00e9pondre, avec des silences interminables pour rythmer la tentative, &laquo; <em>I mean &#8230; uh&#8230;<\/em> &raquo;, &laquo; <em>I can explain&#8230;<\/em> &raquo;, &laquo; <em>I mean &#8230; euh&#8230;<\/em> &raquo;, puis il abandonne : &laquo; <em>I don&rsquo;t find the words <\/em>&raquo;. Il n&rsquo;est m\u00eame pas triste \u00e0 pleurer, comme l&rsquo;est Powers qu&rsquo;on a montr\u00e9e auparavant, il est sonn\u00e9, KO, psychologiquement \u00e9tendu par terre et inconscient, quasiment laiss\u00e9 pour mort.<\/p>\n<\/p>\n<p><p>Alors, on comprend me semble-t-il : tous ces gens ont cru jusqu&rsquo;au bout \u00e0 la \u00ab\u00a0&lsquo;<em>story<\/em>&lsquo;, ce qu&rsquo;on nomme <em><a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-le-determinisme-narrativiste\">narrative<\/a><\/em> dans nos pages\u00a0\u00bb que leur susurrait BHO-Saint, et peut-\u00eatre le Saint lui-m\u00eame y a-t-il cru, &ndash; non, s&ucirc;rement il y a cru. Voir tout cela d\u00e9truit, ce r\u00eave bris\u00e9, cette illusion perdue en devenant r\u00e9ellement illusion, et de la sale patte de ce milliardaire comme \u00e9ternel nouveau-riche \u00e0 cheveux jaunes, vulgaire, sans foi ni loi de notre-caste, &lsquo;<em>fucking idiot<\/em>&lsquo; mais aussi &lsquo;<em>Minotaur<\/em>&lsquo; ! On comprend qu&rsquo;\u00e0 cet instant na&icirc;t cette haine inextinguible et inexpiable, promise \u00e0 durer jusqu&rsquo;\u00e0 la mort de l&rsquo;impie et bien au-del\u00e0, haine et mal\u00e9diction de l&rsquo;impie jusqu&rsquo;\u00e0 la dixi\u00e8me g\u00e9n\u00e9ration s&rsquo;il le faut. Adieu l&rsquo;artiste.<\/p>\n<\/p>\n<\/blockquote>\n<p><h2 class=\"titleset_d.deepgreen\" style=\"color:#75714d; font-size:1.05em\"><em>The End<\/em> ? <em>Happy End !<\/em><\/h2>\n<\/p>\n<p><p>Ce qui attend BH, \u00ab\u00a0cette t\u00e2che si lourde, si \u00e9puisante, malgr\u00e9 la superbe et loyale victoire\u00a0\u00bb du 3 novembre 2020, cela peut \u00eatre aussi une belle &lsquo;<em>story<\/em>&lsquo; inspir\u00e9e par la stature magnifique de l&rsquo;Alexandre-diversit\u00e9 des temps modernes. BH est la projection, \u00e0 quatre ans de distance, de BHO-Saint ; il en fallait bien deux, BH comme les &lsquo;Dupont-Dupond&rsquo; de \u00ab\u00a0<em>Change the world<\/em>\u00ab\u00a0, Acte-II, pour poursuivre la Sainte-Mission. BH, c&rsquo;est BHO sans O comme vous l&rsquo;avez remarqu\u00e9, puisqu&rsquo;Obama a trac\u00e9 la voie, montr\u00e9 la lumi\u00e8re, trac\u00e9 les ouvertures et les horizons sans fin du Paradis-<em>on-Earth<\/em>. &lsquo;<em>Yes, They Can<\/em>&lsquo;, et vachement, et c&rsquo;est la belle-&lsquo;<em>story<\/em>&lsquo; \u00e0 nouveau sur pied, qui nous sortira du labyrinthe.<\/p>\n<\/p>\n<p><p>C&rsquo;est comme &lsquo;<em>Alice in Wonderland<\/em>&lsquo;, en plus racis\u00e9, en mieux genris\u00e9, en compl\u00e8tement hollywoodis\u00e9, et qui trouve la sortie du terrier labyrinthique o&ugrave; l&rsquo;avait tra&icirc;treusement attir\u00e9e &lsquo;<em>The Minotaur<\/em>&lsquo; \u00e0 la chevelure jaune, l\u00e2chement grim\u00e9 en lapin blanc et qui s&rsquo;est av\u00e9r\u00e9 \u00eatre \u00e9galement un chapelier fou. Bon d\u00e9barras, <em>The-Donald <\/em>! Vir\u00e9 par le plus beau et le plus exemplaire scrutin, l&rsquo;\u00e9lection sans faute ni fraude la plus belle que nous ait offert la Grande D\u00e9mocratie de la Grande R\u00e9publique, qui arriuve \u00e0 se frauder elle-m\u00eame \u00e0 l&rsquo;insu de son pleuin gr\u00e9. La &lsquo;belle-\u00e9poque&rsquo; devenue la belle-&lsquo;<em>story<\/em>&lsquo;, avec BHO-Saint r\u00e9incarn\u00e9 en BH.<\/p>\n<\/p>\n<p><p>Trump est et restera d\u00e9sormais l&rsquo;objet, la cause, la raison, l&rsquo;argument, l&rsquo;aliment, le <em>Bourbon <\/em>et son ivresse de notre haine absolue, perp\u00e9tuelle, de notre haine sans fin, comme les horizons sans fin, grossier milliardaire qui la ram\u00e8ne un peu trop, figure \u00e9ternelle des minables <em><a href=\"https:\/\/www.dedefensa.org\/article\/french-touch-nous-sommes-tous-les-deplorables\">Deplorable<\/a><\/em>, ploucs, beaufs, que sais-je encore, qui pr\u00e9tendent se r\u00e9volter et qui se r\u00e9voltent parfois. La riposte sera, ou est d\u00e9j\u00e0 bien entendu, une haine encore plus forte, de la part des trumpistes et de Trump si \u00e7a lui chante. Et les lendemains, eux aussi, chanteront \u00e0 pleine voix le d\u00e9sordre terminal de la Grande Crise.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&Eacute;chos de BHO 14 d\u00e9cembre 2020 &ndash; Disposant sur Netflix r\u00e9cemment d&rsquo;un documentaire d&rsquo;une \u00e9quipe de journalistes de HBO et r\u00e9alis\u00e9 par Greg Barker en 2017, je crois bien avoir dispos\u00e9 d&rsquo;une s\u00e9rieuse partie de la r\u00e9ponse \u00e0 la question de la provenance directe de la haine qui d\u00e9vore l&rsquo;Am\u00e9rique. Cette haine se mesure chaque&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[3066,3265,7935,2998,20506,20507,3961,855,2711,20505,4321,6208,3478,3146,706,10972,5332,3867,3050,2639,5050,3986,7934],"class_list":["post-79565","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-americaniste","tag-ben","tag-can","tag-change","tag-exceoptionnalisme","tag-hbo","tag-john","tag-kerry","tag-le","tag-minautaure","tag-narrative","tag-obama","tag-onu","tag-powers","tag-rhodes","tag-samantha","tag-story","tag-syrie","tag-the","tag-trump","tag-we","tag-world","tag-yes"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79565","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79565"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79565\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79565"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79565"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79565"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}