{"id":79567,"date":"2020-12-15T12:10:19","date_gmt":"2020-12-15T12:10:19","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2020\/12\/15\/la-parabole-des-15-milliards\/"},"modified":"2020-12-15T12:10:19","modified_gmt":"2020-12-15T12:10:19","slug":"la-parabole-des-15-milliards","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2020\/12\/15\/la-parabole-des-15-milliards\/","title":{"rendered":"La parabole des 15 milliards"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">La parabole des 15 milliards<\/h2>\n<\/p>\n<p><p>15 d\u00e9cembre 2020 &ndash; Hier, avisant par pur hasard (qui sait ?) et fr\u00f4lement de biblioth\u00e8que un bouquin qui tra&icirc;nait&#8230; Je feuilletais <em>Les Rostand<\/em>, qui rapporte l&rsquo;histoire des diverses et brillantes individualit\u00e9s de cette famille, notamment et bien s&ucirc;r le premier chapitre sur le premier d&rsquo;entre les Rostand, avec le formidable \u00e9v\u00e9nement th\u00e9\u00e2tral et litt\u00e9raire qu&rsquo;il cr\u00e9a avec <em>Cyrano de Bergerac<\/em>.<\/p>\n<\/p>\n<p><p>On ne peut lire un texte sur cette pi\u00e8ce consid\u00e9rable \u00e0 tous \u00e9gards sans s&rsquo;arr\u00eater au mot qui la caract\u00e9rise absolument en englobant, en ciselant le personnage de Cyrano : le panache. Edmond Rostand en donne cette d\u00e9finition :<\/p>\n<\/p>\n<p><p>&laquo; <em>Le panache n&rsquo;est pas la grandeur mais quelque chose qui s&rsquo;ajoute \u00e0 la grandeur, et qui bouge au-dessus d&rsquo;elle. C&rsquo;est quelque chose de voltigeant, d&rsquo;excessif &mdash; et d&rsquo;un peu fris\u00e9<\/em> [&hellip;]<em>, le panache c&rsquo;est l&rsquo;esprit de bravoure. <\/em>[&hellip;] <em>Plaisanter en face du danger c&rsquo;est la supr\u00eame politesse, un d\u00e9licat refus de se prendre au tragique ; le panache est alors la pudeur de l&rsquo;h\u00e9ro\u00efsme, comme un sourire par lequel on s&rsquo;excuse d&rsquo;\u00eatre sublime<\/em>&#8230; &raquo;<\/p>\n<\/p>\n<p><p>Je trouve beaucoup de choses dans ce mot, et la d\u00e9finition de Rostand y aide consid\u00e9rablement. J&rsquo;y trouve surtout quelque chose, non pas d&rsquo;a\u00e9rien mais d&rsquo;au-dessus de l&rsquo;humain (&laquo; <em>quelque chose qui s&rsquo;ajoute \u00e0 la grandeur, et qui bouge au-dessus d&rsquo;elle<\/em> &raquo;<em>) <\/em>; une sorte de vertu d&rsquo;au-dessus de l&rsquo;humain mais affirm\u00e9e avec bienveillance et empathie, une gr\u00e2ce harmonieuse et apais\u00e9e, qui d\u00e9tonnerait presque en l&rsquo;harmonisant de l&rsquo;esp\u00e8ce de tohu-bohu sublime qui caract\u00e9rise les manifestations humaines du panache, qui lui donne la gratuit\u00e9 permettant d&rsquo;\u00e9chapper aux contraintes du sort et des affaires. (Par exemple, Obama, <a href=\"https:\/\/www.dedefensa.org\/article\/echos-de-bho\">comme vu hier<\/a>, a de la grande classe, il n&rsquo;a pas de panache. Il ne fait rien qui ne soit command\u00e9 principalement  par la cause qui l&rsquo;anime et l&rsquo;effet, la somme, l&rsquo;avantage qu&rsquo;il en esp\u00e8re.)<\/p>\n<\/p>\n<p><p>Bref et ainsi d\u00e9fini, je trouve au panache quelque chose de m\u00e9taphysique.<\/p>\n<\/p>\n<p><p>Et aussit\u00f4t, consid\u00e9rant la d\u00e9rision et la petitesse des situations humaines \u00e0 propos de laquelle se manifeste le panache, parfois jusqu&rsquo;\u00e0 la mort (Cyrano), j&rsquo;en viens \u00e0 une r\u00eaverie au d\u00e9part bien conventionnelle, pour acter cette parent\u00e9 peu ordinaire entre la d\u00e9rision des causes d&rsquo;un comportement, puis d&rsquo;un acte qui leur est li\u00e9, et la grandeur de la gr\u00e2ce qui peut aller jusqu&rsquo;au sacrifice de sa vie. Ma r\u00e9flexion revient assez vite \u00e0 un commun \u00ab\u00a0on est bien peu de choses\u00a0\u00bb,  m\u00eame si c&rsquo;est avec panache et quoique le panache signifie tout de m\u00eame de grandes choses ; ainsi d\u00e9filent les images jusqu&rsquo;\u00e0 celles qui fait de ces \u00eatres de \u00ab\u00a0bien peu de choses\u00a0\u00bb comme des petites choses qui se dispersent dans l&rsquo;immensit\u00e9 de l&rsquo;univers ; et d\u00e8s lors que j&rsquo;insiste sur la grandeur du panache qui est \u00ab\u00a0au-dessus d&rsquo;elle\u00a0\u00bb et donne \u00e0 ces \u00ab\u00a0petites choses\u00a0\u00bb assez ordinaires un poids si particulier et si extraordinaire, c&rsquo;est qu&rsquo;alors \u00ab\u00a0l&rsquo;immensit\u00e9 de l&rsquo;univers\u00a0\u00bb tend \u00e0 se pr\u00e9senter comme l&rsquo;infini qui permet leur transmutation, et qu&rsquo;il faut alors y voir quelque chose de divin. C&rsquo;est ainsi que j&rsquo;en viens \u00e0 la parabole de l'\u00a0\u00bbimmense univers\u00a0\u00bb qui serait comme l&rsquo;Esprit de Dieu, le cerveau immense qui recueille ces \u00ab\u00a0bien peu de choses\u00a0\u00bb pourtant touch\u00e9s par la gr\u00e2ce dans son \u00e9ternit\u00e9.<\/p>\n<\/p>\n<p><p>Il faut alors pr\u00e9ciser que j&rsquo;avais \u00e0 l&rsquo;esprit, pour me conduire \u00e0 la parabole, la connaissance de deux chiffres concernant les nombres de deux certains types sp\u00e9cifiques de plan\u00e8tes et de neurones, &ndash; que je qualifierais pour marquer leur extr\u00eame relativit\u00e9 scientifique de plan\u00e8tes-X et de neurones-X, &ndash; choses entendues tr\u00e8s r\u00e9cemment de sources qu&rsquo;on doit qualifier \u00e0 la fois, dans la d\u00e9ferlante de la communication et de la post-v\u00e9rit\u00e9,  d&rsquo;assez &lsquo;cr\u00e9dibles&rsquo; et de compl\u00e8tement &lsquo;incertaines&rsquo;. Je ne fais ici qu&rsquo;appliquer la nouvelle r\u00e8gle \u00e9tablie par le d\u00e9ferlement de crit\u00e8res assur\u00e9s et de jugements &lsquo;scientifiques&rsquo; \u00e9galement assur\u00e9s, qui sont \u00e0 la fois diff\u00e9rents et contradictoires, qui sont parfaitement de ce temps nouveau de la post-v\u00e9rit\u00e9 o&ugrave; la v\u00e9rit\u00e9 ne compte plus, et tout cela dans le plus complet d\u00e9sordre.<\/p>\n<\/p>\n<p><p>La crise du Covid et le d\u00e9ferlement des sp\u00e9cialistes avec chacun leurs versions, leurs points de vue antagonistes, leurs jalousies acides, &ndash; \u00ab\u00a0humain, trop humain\u00a0\u00bb, &ndash;dans notre soci\u00e9t\u00e9 satur\u00e9e jusqu&rsquo;\u00e0 la naus\u00e9e de communications, ont marqu\u00e9 profond\u00e9ment et d\u00e9cisivement \u00e0 mon sens ce nouveau caract\u00e8re des sciences&#8230; On en tire le constat assur\u00e9 de la crise compl\u00e8te de la s&ucirc;ret\u00e9 de la donn\u00e9e scientifique, de la s&ucirc;ret\u00e9 du diagnostic, de la s&ucirc;ret\u00e9 du jugement scientifiques. Je pr\u00e9tends que le caract\u00e8re absolument objectif de la science s&rsquo;est ab&icirc;m\u00e9e enti\u00e8rement jusqu&rsquo;\u00e0 la d\u00e9sint\u00e9gration compl\u00e8te dans la compl\u00e8te subjectivit\u00e9 de cette \u00e9poque post-v\u00e9rit\u00e9. Voici les r\u00e8gles de cette nouvelle situation selon mon estimation et sous mon enti\u00e8re responsabilit\u00e9, mais \u00e9galement dans ma compl\u00e8te subjectivit\u00e9 puisque c&rsquo;est la fa\u00e7on o&ugrave; l&rsquo;on est forc\u00e9 d&rsquo;\u00eatre d\u00e9sormais, et pour mon compte \u00e0 partir de quoi je recherche sans aucunement me d\u00e9courager les <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-verite-de-situation-verite\">v\u00e9rit\u00e9s-de-situation<\/a> :<\/p>\n<\/p>\n<p><p>&bull; \u00ab\u00a0la seule chose dont on est assur\u00e9 d\u00e9sormais dans le flux dynamique des connaissances scientifiques, c&rsquo;est qu&rsquo;au plus ces connaissances progressent dans une mesure exponentielle gigantesque comme elles font, au moins on est assur\u00e9 de la v\u00e9racit\u00e9 de cette dynamique et de la v\u00e9rit\u00e9 de ce qui en est produit\u00a0\u00bb ;<\/p>\n<p>&bull; \u00ab\u00a0la seule perspective mesur\u00e9e qu&rsquo;on peut envisager est celle de la post-v\u00e9rit\u00e9 dans les sciences, sans doute destructrice des sciences occidentales : au plus nous avan\u00e7ons avec de monstrueux amas de &lsquo;connaissances&rsquo;, au plus dispara&icirc;t ce qui reste d&rsquo;affirmation de vision objective du monde, et cela jusqu&rsquo;\u00e0 la n\u00e9antisation de cette pr\u00e9tention en cours de r\u00e9alisation\u00a0\u00bb ;<\/p>\n<p>&bull; \u00ab\u00a0La seule chose dont je suis assur\u00e9 pour mon compte est que les sciences ont totalement perdu leur pr\u00e9tention \u00e0 l&rsquo;objectivit\u00e9 vertueuse, que je ne veux plus par cons\u00e9quent envisager la v\u00e9racit\u00e9 et la v\u00e9rit\u00e9 des sciences ; car les sciences font partie d\u00e9sormais de l&rsquo;hyperd\u00e9sordre, ph\u00e9nom\u00e8ne de la &lsquo;post-v\u00e9rit\u00e9&rsquo; dont je crois absolument \u00e0 l&rsquo;existence et \u00e0 la pertinence\u00a0\u00bb ;<\/p>\n<p>&bull; \u00ab\u00a0Par cons\u00e9quent, la seule chose dont on est assur\u00e9 aujourd&rsquo;hui dans les sciences, c&rsquo;est que rien n&rsquo;est assur\u00e9 ; et le savoir sans rechigner est un pr\u00e9cieux atout pour l&rsquo;esprit\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>Install\u00e9 avec assurance dans la certitude de cette compl\u00e8te absence de certitude, avec un sourire narquois pour moi-m\u00eame (par solidarit\u00e9) et essentiellement pour le <em>sapiens-<\/em>scientifique redevenu<em> sapiens<\/em> incertain et h\u00e9sitant des origines, je ne d\u00e9battrai pas une seconde sur la justesse de ces deux chiffres dont je parle ici (neurones-X et plan\u00e8te-X), ni n&rsquo;accepterai qu&rsquo;on en d\u00e9batte pour les contester. Je ne fais pas une tentative de d\u00e9monstration qui serait presque de facture scientifique (un comble !), j&rsquo;instruis mon lecteur \u00e0 propos de la formation d&rsquo;une parabole.<\/p>\n<\/p>\n<p><p>L&rsquo;essentiel est que j&rsquo;avais \u00e0 l&rsquo;esprit ces chiffres de 15 milliards &#038; 15 milliards avant d&rsquo;en venir \u00e0 l&rsquo;intuition dont je fus l&rsquo;objet et que je ces prends chiffres pour ce qu&rsquo;ils sont, comme un facteur structurant de mon esprit toujours en qu\u00eate de v\u00e9rit\u00e9-de-situation, existant avant l&rsquo;intuition \u00e0 ce propos et lui servant de guide pour l&rsquo;op\u00e9rationnaliser. Les deux chiffres concernant les neurones-X et les plan\u00e8tes-X sont pris comme facteurs de r\u00e9v\u00e9lation pour mon parcours intuitif que je d\u00e9cris : apprenant d&rsquo;abord r\u00e9cemment qu&rsquo;on avait comptabilis\u00e9 r\u00e9cemment dans le cerveau le nombre de 15 milliards de neurones-X, j&rsquo;appris plus r\u00e9cemment qu&rsquo;on avait comptabilis\u00e9 le nombre de  plan\u00e8tes-X dans l&rsquo;univers.<\/p>\n<\/p>\n<p><p>J&rsquo;entendis que ce deuxi\u00e8me nombre \u00e9tait \u00e9galement de 15 milliards. La correspondance me sembla \u00e0 la fois extraordinaire et r\u00e9v\u00e9latrice.<\/p>\n<\/p>\n<p><p>C&rsquo;est dire, avec deux chiffres pr\u00e9cis mais sans la moindre assurance de v\u00e9racit\u00e9 et v\u00e9rit\u00e9, comme le reste, tout le reste, &ndash; c&rsquo;est dire combien je tenais l\u00e0 la parabole tr\u00e8s puissante d&rsquo;une correspondance \u00e0 la fois v\u00e9ridique et r\u00e9elle qui \u00e9claire le raisonnement que j&rsquo;ai rapport\u00e9 \u00e0 partir d&rsquo;une intuition : le cerveau humain structur\u00e9 comme l&rsquo;univers connu, selon la parabole intuitive que l&rsquo;univers &lsquo;connu&rsquo; est le cerveau de Dieu ; et le cerveau, qui est \u00e9galement le \u00ab\u00a0Tout&rsquo; dans ce cas, \u00e9tant bien l&rsquo;Esprit de Dieu.<\/p>\n<\/p>\n<p><p>On comprend que les deux chiffres dont la fonction est d&rsquo;\u00eatre compl\u00e8tement incertains, ne sont l\u00e0 que pour \u00e9tablir une correspondance qui doit illustrer l&rsquo;\u00e9vidence que cette conception ne dit strictement rien des capacit\u00e9s humaines, et surtout pas de leur puissance affirm\u00e9es depuis la Renaissance ; qu&rsquo;elle dit tout de cette vieille image que Dieu fait tout &lsquo;\u00e0 son image&rsquo; ; qu&rsquo;elle redonne ainsi quelque cr\u00e9dit \u00e0 cette conception du Fond des Temps de l&rsquo;affirmation \u00e9vidente, allant-de-soi, d&rsquo;un divin-existant, dans ces temps de compl\u00e8te d\u00e9route d&rsquo;une science pr\u00e9tendant se substituer au divin.<\/p>\n<\/p>\n<p><p>Maintenant, concluons notre histoire : je vous emm\u00e8ne quelques d\u00e9cennies plus t\u00f4t, au temps de ma jeunesse b\u00e9nie&#8230;<\/p>\n<\/p>\n<p><p>Quelque part entre 1966 et 1968, je ne sais plus tr\u00e8s bien, j&rsquo;avais lu une nouvelle de Ray Bradbury dont j&rsquo;ai oubli\u00e9 le titre. C&rsquo;\u00e9tait l&rsquo;\u00e9poque de l&rsquo;installation au d\u00e9but de leur d\u00e9veloppement des ordinateurs, avec l&rsquo;existence des mod\u00e8les g\u00e9ants procurant une capacit\u00e9 \u00e0 mesure. Dans sa nouvelle, Bradbury imagine bien entendu une sorte de F\u00e9d\u00e9ration Mondiale des &Eacute;tats qui se r\u00e9unit un jour pour aborder cette question centrale : \u00ab\u00a0Comment trancher d\u00e9finitivement la question de l&rsquo;existence de Dieu ?\u00a0\u00bb (L&rsquo;arriv\u00e9e des ordinateurs-g\u00e9ants ouvrait en effet l&rsquo;\u00e8re des Fins derni\u00e8res r\u00e9solues pour <em>sapiens-<\/em>simulacre.) Cela donna \u00e0 peu pr\u00e8s ceci, dans sa conclusion, rapport\u00e9e ici dans l&rsquo;esprit de la chose et nullement dans la pr\u00e9cision du d\u00e9tail et de la situation.<\/p>\n<\/p>\n<p><p>On d\u00e9cida de rassembler et de connecter tous les ordinateurs g\u00e9ants que poss\u00e9daient les &Eacute;tats, pour arriver \u00e0 une unit\u00e9, &ndash; nommons-l\u00e0 U.P. pour Unit\u00e9 Plan\u00e9taire, &ndash; qui disposerait de toutes leurs capacit\u00e9s ajout\u00e9es, &ndash; et lui poser LA question.<\/p>\n<\/p>\n<p><p>On proc\u00e9da \u00e0 l&rsquo;op\u00e9ration, assez longue et complexe. Lorsque cela fut fait, ce fut le Grand Jour et l&rsquo;on mit en marche, pour la premi\u00e8re fois dans l&rsquo;histoire de l&rsquo;Humanit\u00e9, l&rsquo;U.P. f\u00e9cond\u00e9e par le sperme plan\u00e9taire et n\u00e9anmoins informatique de tous les ordinateurs-g\u00e9ants dignes de ce nom&#8230; (Cette image eut du mal \u00e0 passer la censure-Tweeter, pour blasph\u00e8me antif\u00e9ministe, mais enfin nous voil\u00e0.)<\/p>\n<\/p>\n<p><p>&ndash; Dieu existe-t-il ?\u00a0\u00bb interrogea la F\u00e9d\u00e9ration Mondiale, attendant, haletante, pour la premi\u00e8re fois les mots et la voix de U.P. (&laquo; <em>Au commencement \u00e9tait le Verbe <\/em>&raquo;, murmura un \u00e9v\u00eaque qui avait men\u00e9 la charge de la modernit\u00e9 au Concile <em>Vatican II <\/em>et en avait oubli\u00e9 comment l&rsquo;on se signe<em>.<\/em>)<\/p>\n<\/p>\n<p><p>&ndash; D\u00e9sormais et \u00e0 partir de maintenant, Il existe\u00a0\u00bb, r\u00e9pondit l&rsquo;Unit\u00e9 Plan\u00e9taire.<\/p>\n<\/p>\n<p><p>Les conceptions, imaginations &#038; intuitions peuvent diverger jusqu&rsquo;\u00e0 l&rsquo;opposition radicale et sans appel ni retour, pour traiter la m\u00eame question. On le mesure ici. On fera son choix entre l'\u00a0\u00bbimmense univers\u00a0\u00bb qui est le cerveau et l&rsquo;Esprit de Dieu d&rsquo;une part, et l&rsquo;U.P. d&rsquo;autre part ; ou bien l&rsquo;on ira boire un verre dans un caf\u00e9 rouvert, d\u00e9confinement act\u00e9 pour une semaine ou deux, avant de r\u00e9int\u00e9grer le <em>Goulag.<\/em><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La parabole des 15 milliards 15 d\u00e9cembre 2020 &ndash; Hier, avisant par pur hasard (qui sait ?) et fr\u00f4lement de biblioth\u00e8que un bouquin qui tra&icirc;nait&#8230; Je feuilletais Les Rostand, qui rapporte l&rsquo;histoire des diverses et brillantes individualit\u00e9s de cette famille, notamment et bien s&ucirc;r le premier chapitre sur le premier d&rsquo;entre les Rostand, avec le&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[20519,6241,2752,20511,2631,2898,3466,7364,12322,20514,8397,2622,20516,20512,20518,12913,20510,16863,9715,5445],"class_list":["post-79567","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-bradbury","tag-cerveau","tag-covid","tag-cyrano","tag-de","tag-desintegration","tag-dieu","tag-esprit","tag-eternite","tag-immense","tag-intuition","tag-la","tag-neurone-x","tag-panache","tag-planete-x","tag-post-verite","tag-rostand","tag-scientifique","tag-univers","tag-verite"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79567","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79567"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79567\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79567"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79567"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}