{"id":79575,"date":"2020-12-21T18:17:57","date_gmt":"2020-12-21T18:17:57","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2020\/12\/21\/maturite-de-la-postverite\/"},"modified":"2020-12-21T18:17:57","modified_gmt":"2020-12-21T18:17:57","slug":"maturite-de-la-postverite","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2020\/12\/21\/maturite-de-la-postverite\/","title":{"rendered":"Maturit\u00e9 de la postv\u00e9rit\u00e9"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Maturit\u00e9 de la postv\u00e9rit\u00e9<\/h2>\n<\/p>\n<p><p>21 d\u00e9cembre 2020 &ndash; Je crois et dirais bien que 2020, qui se m\u00e9lange si bien <a href=\"https:\/\/www.dedefensa.org\/article\/je-doute-donc-je-suis\">avec 2002<\/a>, est l&rsquo;arriv\u00e9e \u00e0 maturit\u00e9 de l&rsquo;op\u00e9rationnalisation de la Post-V\u00e9rit\u00e9 (disons PV, pour faire court), &ndash; la Post-V\u00e9rit\u00e9-PV, ou \u00e9crit &lsquo;postv\u00e9rit\u00e9&rsquo; selon l&rsquo;usage auquel je me tiendrai. Je tiens par contre avec fermet\u00e9 \u00e0 cette expression, ainsi amend\u00e9e, d&rsquo; \u00ab\u00a0op\u00e9rationnalisation de la postv\u00e9rit\u00e9\u00a0\u00bb, et non PV tout court car c&rsquo;est bien de cela qu&rsquo;il s&rsquo;agit. Nous sommes, c&rsquo;est ma th\u00e8se, en mode-PV complet et achev\u00e9 dans les op\u00e9rations du monde et la psychologie collective, bel et bien dans les \u00e9v\u00e9nements du monde, sans la moindre interstice de v\u00e9rit\u00e9 pour ne pas prendre froid.<\/p>\n<\/p>\n<p><p>(Laissons par cons\u00e9quent de c\u00f4t\u00e9, puisque ce n&rsquo;est pas le sujet, l&rsquo;aspect th\u00e9orique de la chose, les th\u00e8ses, hypoth\u00e8ses, affirmations &#038; d\u00e9n\u00e9gations, sur la question de la v\u00e9rit\u00e9\/V\u00e9rit\u00e9 et de toutes les variations faussaires, simulacres, etc., sur lesquels les esprits travaillent depuis l&rsquo;Antiquit\u00e9, et m\u00eame avant je vous l&rsquo;assure. Voyez l&rsquo;article du <em>Wiki <\/em>sur le sujet, &ndash;en fait, sur &laquo; <em><a href=\"https:\/\/fr.wikipedia.org\/wiki\/\u00c8re_post-v\u00e9rit\u00e9\">L&rsquo;&Egrave;re post-v\u00e9rit\u00e9<\/a><\/em> &raquo;, &ndash; il est absolument kilom\u00e9trique, un des plus longs sur les concepts qu&rsquo;il m&rsquo;ait \u00e9t\u00e9 donn\u00e9 de feuilleter et de ne pas lire sinon en diagonale modeste [trop long].)<\/p>\n<\/p>\n<p><p>La raison de ce constat en forme d&rsquo;hypoth\u00e8ses est qu&rsquo;en 2020, on se trouve avec deux \u00e9v\u00e9nements, qui sont ces deux crises colossales faisant partie int\u00e9grante et quasi-exclusive de la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-la-gces\">GCES<\/a> au point qu&rsquo;elles parviennent \u00e0 elles seules \u00e0 d\u00e9finir et d\u00e9terminer dans l&rsquo;illimit\u00e9 la Grande Crise ; il s&rsquo;agit de la crise-Covid et de la crise du syst\u00e8me de l&rsquo;am\u00e9ricanisme, ces deux crises dont il est impossible \u00e0 mon sens et selon ma perception de les appr\u00e9cier selon une approche \u00e0 pr\u00e9tention v\u00e9ridique. Nul ne peut dire le vrai de ces deux \u00e9v\u00e9nements et dans ces deux \u00e9v\u00e9nements, o&ugrave; chaque \u00e9l\u00e9ment se trouve comme un mur infranchissable devant vous, que ce soit le nombre de morts-Covid et la valse des vaccins, que ce soit le score \u00e9lectoral de <em>Old-Joe <\/em>Biden et la validit\u00e9 des machines \u00e0 compter\/\u00e0 frauder de la marque Dominion.<\/p>\n<\/p>\n<p><p>&#8230; C&rsquo;en est au point qu&rsquo;\u00e0 cette occasion vous reviennent les vieilles rengaines poussi\u00e9reuses, engourdies dans les d\u00e9bris de la v\u00e9rit\u00e9 d\u00e9sint\u00e9gr\u00e9e, et qui pourtant vous disent le vrai&#8230; \u00ab\u00a0Je ne suis s&ucirc;r que d&rsquo;une chose, c&rsquo;est que je ne suis s&ucirc;r de rien\u00a0\u00bb ; ou bien \u00ab\u00a0Je ne sais qu&rsquo;une chose, c&rsquo;est que je ne sais rien\u00a0\u00bb ; et ainsi de suite, dans le genre privatif et cadenass\u00e9&#8230; Inutile d\u00e9sormais, vous disent ces sages formules, d&rsquo;attendre quelque v\u00e9rit\u00e9 que ce soit de ce monde encalmin\u00e9 comme un navire errant, un &lsquo;Hollandais Volant&rsquo; qui ne saurait plus naviguer, sur le territoire visqueux et spongieux d&rsquo;une affreuse Mer des Sargasses.<\/p>\n<\/p>\n<p><p>Bref, car il n&#8217;emp\u00eache que le vieux et v\u00e9n\u00e9rablement corrompu <em>Wiki <\/em>vous signale tout de m\u00eame que l&rsquo;expression \u00ab\u00a0post-v\u00e9rit\u00e9\u00a0\u00bb a \u00e9t\u00e9 utilis\u00e9e publiquement, pour la premi\u00e8re fois, en 2004, c&rsquo;est-\u00e0-dire effectivement op\u00e9rationnalis\u00e9e dans le langage courant :<\/p>\n<p>&laquo; <em>L&rsquo;expression \u00ab\u00a0post-v\u00e9rit\u00e9\u00a0\u00bb (post-truth) appara&icirc;t en 2004, quand l&rsquo;\u00e9crivain am\u00e9ricain Ralph Keyes l&rsquo;utilise dans son livre &lsquo;The Post-Thruth Era: Dishonesty and Deception in Contemporary life&rsquo;. La m\u00eame ann\u00e9e, le journaliste Eric Alterman parle d&rsquo;un \u00ab\u00a0environnement politique post-v\u00e9rit\u00e9\u00a0\u00bb et de \u00ab\u00a0la pr\u00e9sidence post-v\u00e9rit\u00e9\u00a0\u00bb en analysant les fausses assertions de l&rsquo;administration Bush apr\u00e8s les attentats du 11 septembre 2001<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>(A noter en passant, pour illustrer les gambades du facteur postv\u00e9rit\u00e9 avec influence sur les psychologies fragiles, et commen\u00e7ant par cette question : <em>Wiki <\/em>s&rsquo;est-il laisser aller \u00e0 une faiblesse postv\u00e9rit\u00e9 ? Il \u00e9crit effectivement et sans la moindre pr\u00e9caution de d\u00e9n\u00e9gation &laquo; <em>les <strong>fausses <\/strong>assertions<\/em> &raquo; de la bande-GW sur l&rsquo;attaque 9\/11, ce qui fait furieusement complotiste ; comme quoi, la v\u00e9rit\u00e9 peut aussi sortir de la bouche de la postv\u00e9rit\u00e9&#8230;)<\/p>\n<\/p>\n<p><p>En v\u00e9rit\u00e9 (!), si cette chronologie semblait fixer l&rsquo;usage op\u00e9rationnel de la postv\u00e9rit\u00e9, et par cons\u00e9quent son origine op\u00e9rationnelle, je la fixerais pour mon compte \u00e0 cette fameuse ann\u00e9e 2002 d\u00e9j\u00e0 signal\u00e9e, et dans le chef d&rsquo;un homme dont j&rsquo;estime qu&rsquo;il \u00e9tait la crapule la plus dou\u00e9e et la plus inventive de l&rsquo;inf\u00e2me administration GW Bush. On a devin\u00e9 qu&rsquo;il s&rsquo;agit du ministre de la d\u00e9fense Donald Rumsfeld, et je prends 2002 par f\u00e9tichisme et symbolisme \u00e9gotique, puisque l&rsquo;article auquel je me r\u00e9f\u00e8re est originellement de janvier 2002 dans l&rsquo;\u00e9dition papier de <em>dedefensa &#038; eurostrat\u00e9gie. <\/em>(Reprise sur le site <a href=\"https:\/\/www.dedefensa.org\/article\/je-doute-donc-je-suis\">le 15 mars 2003<\/a> sous le titre philosophe, &ndash; comme Rumsfeld lui-m\u00eame l&rsquo;\u00e9tait, <a href=\"https:\/\/www.dedefensa.org\/article\/je-doute-donc-je-suis\">philosophe<\/a> et m\u00eame <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-crisis-la-source-de-tous-les-maux-1\">m\u00e9taphysique<\/a>, &ndash; de &laquo; <em>Je doute, donc je suis <\/em>&raquo; ; sans doute, dans ce cas, pour f\u00eater joyeusement l&rsquo;h\u00e9ro\u00efque, vertueuse et triomphante attaque de l&rsquo;Irak.)<\/p>\n<\/p>\n<p><p>Cet article signalait qu&rsquo;\u00e0 l&rsquo;issue de la courte campagne qu&rsquo;on consid\u00e9rait \u00ab\u00a0vingt ans avant\u00a0\u00bb comme victorieuse sinon triomphale contre les talibans afghans, de l&rsquo;automne 2001 et jusqu&rsquo;en d\u00e9cembre, il y eut un \u00e9v\u00e9nement remarquable quoique fort peu remarqu\u00e9 :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>L&rsquo;hebdomadaire am\u00e9ricain Aviation Week &#038; Space Technology du 17 d\u00e9cembre 2001, dans sa rubrique Washington Outlook, nous annonce qu&rsquo;<\/em>\u00ab\u00a0[i]<em>l ne faut pas s&rsquo;attendre \u00e0 voir le Pentagone nous dire comment la guerre a \u00e9t\u00e9 gagn\u00e9e, une fois que le conflit sera termin\u00e9. Une autre victime du conflit sera le document traditionnel des &lsquo;le\u00e7ons du conflit&rsquo;, diffus\u00e9 publiquement, selon ce que nous dit un officiel de haut niveau. Les \u00e9tudes sur les besoins des services \u00e0 la lumi\u00e8re des enseignements du conflit feront \u00e9galement partie des domaines sur les enseignements techniques et op\u00e9rationnels qui seront tenus secrets selon la volont\u00e9 g\u00e9n\u00e9rale du secr\u00e9taire \u00e0 la d\u00e9fense Rumsfeld \u00e0 cet \u00e9gard. Des sources officielles indiquent qu&rsquo;un usage extensif du polygraphe (d\u00e9tecteur de mensonges) sera fait pour pr\u00e9venir les fuites et un certain nombre de programmes seront transf\u00e9r\u00e9s du domaine blanc <\/em>[ouvert]<em> au domaine noir <\/em>[secret]<em>\u00ab\u00a0<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Cette nouvelle, venue d&rsquo;une revue sp\u00e9cialis\u00e9e, mais de tr\u00e8s haut vol (<em>AW&#038;ST <\/em>\u00e9tait alors, &ndash; j&rsquo;ignore si sa r\u00e9putation est toujours solide au poste, &ndash; le New York <em>Times <\/em>des nouvelles de l&rsquo;armement et des guerres), constituait effectivement une r\u00e9volution pour l&rsquo;information (pour la communication). Bien que cela ne f&ucirc;t pas formellement \u00e9crit, elle venait de Rumsfeld sp\u00e9cifiquement et, bient\u00f4t, elle ferait t\u00e2che d&rsquo;huile comme doctrine &lsquo;officielle&rsquo; de communication dans tous les appareils et bureaucraties de la communaut\u00e9 de s\u00e9curit\u00e9 nationale, puis du reste, &ndash; ou bien \u00e9tait-ce d\u00e9j\u00e0 le cas :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>La d\u00e9cision extraordinaire des autorit\u00e9s am\u00e9ricaines n&rsquo;a aucun caract\u00e8re formel, elle n&rsquo;a pas \u00e9t\u00e9 annonc\u00e9e comme telle (ni m\u00eame appr\u00e9hend\u00e9e comme telle par nombre de journalistes). Elle n&rsquo;a pas \u00e9t\u00e9 spectaculaire dans le sens m\u00e9diatique du terme, et l&rsquo;on comprend ais\u00e9ment pourquoi ; mais elle a \u00e9t\u00e9 pr\u00e9cis\u00e9ment exprim\u00e9e, \u00e0 un point o&ugrave; l&rsquo;on peut juger qu&rsquo;elle porte une signification fondamentale, qu&rsquo;on peut effectivement mesurer. Cette d\u00e9cision marque un tournant consid\u00e9rable dans l&rsquo;attitude des autorit\u00e9s politiques en g\u00e9n\u00e9ral, dans la mesure o&ugrave; une autorit\u00e9 centrale de cette importance d\u00e9cide de se d\u00e9partir de son r\u00f4le formel (apparent) de r\u00e9f\u00e9rence en mati\u00e8re d&rsquo;information pour se plonger dans la subjectivit\u00e9 g\u00e9n\u00e9rale. Cette autorit\u00e9 d\u00e9cide d&rsquo;\u00eatre d\u00e9sormais \u00ab\u00a0de parti pris\u00a0\u00bb. Nous vivons dans un monde o&ugrave; une autorit\u00e9 officielle, cens\u00e9e repr\u00e9senter le bien public, vous dit de fa\u00e7on ouverte qu&rsquo;elle tentera de vous mentir, de vous induire en erreur, de vous manipuler, selon ses int\u00e9r\u00eats. Rumsfeld n&rsquo;a pas cach\u00e9 qu&rsquo;il ne s&rsquo;estimait plus tenu d\u00e9sormais \u00e0 la n\u00e9cessit\u00e9 de dire la v\u00e9rit\u00e9 (\u00ab\u00a0La v\u00e9rit\u00e9 est une chose trop pr\u00e9cieuse pour ne pas la prot\u00e9ger d&rsquo;une forteresse de mensonges\u00a0\u00bb, dit-il, finaud, en citant Winston Churchill en temps de guerre).<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Et cela constat\u00e9 avant d&rsquo;\u00eatre \u00e9crit pour d\u00e9buter puis clore l&rsquo;\u00e9crit, ainsi le pauvre PhG se lamentait-il, en introduction et en conclusion du texte, comme s&rsquo;il &lsquo;doublonnait&rsquo; en langage journalistique :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>Nous sommes, nous, les analystes et les commentateurs, plus que jamais plac\u00e9s devant une t\u00e2che d&rsquo;enqu\u00eateur. Notre enqu\u00eate ne se d\u00e9roule plus pour trouver les faits, mais pour distinguer, parmi les faits par multitudes incroyables qui nous sont offerts, et parmi lesquels, par multitudes \u00e9galement significatives, sont gliss\u00e9s des faits fabriqu\u00e9s, d\u00e9form\u00e9s et ainsi de suite, entre ceux qui valent d&rsquo;\u00eatre retenus et ceux qui doivent \u00eatre \u00e9cart\u00e9s<\/em>. [&#8230;]<\/p>\n<p>&raquo; <em>Nous autres, journalistes et commentateurs, sommes seuls d\u00e9sormais. Nous sommes \u00ab\u00a0ind\u00e9pendants\u00a0\u00bb, pour le meilleur et pour le pire. Nous disons cela, qui semble impliquer le fait qu&rsquo;il n&rsquo;y aurait eu jamais que la source d&rsquo;information am\u00e9ricaine comme r\u00e9f\u00e9rence, parce que nous nous \u00e9tions mis et avions accept\u00e9 d&rsquo;\u00eatre mis dans une situation o&ugrave; c&rsquo;\u00e9tait exactement le cas (le \u00ab\u00a0nous\u00a0\u00bb repr\u00e9sente les pays europ\u00e9ens notamment et tout ce qui pr\u00e9tend, dans ces pays, se trouver dans le circuit de l&rsquo;information)<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>On peut reprendre la citation de Churchill par Rumsfeld pour structurer la perception que je vous expose, expliquer comment et pourquoi l&rsquo;on parle de mensonges et de propagande ici, et de postv\u00e9rit\u00e9 l\u00e0. Churchill est dans un cadre et sur un ton d\u00e9fensifs : &laquo; <em>La v\u00e9rit\u00e9 est une chose trop pr\u00e9cieuse pour ne pas la prot\u00e9ger d&rsquo;une forteresse de mensonges<\/em>&#8230; &raquo; Il parle implicitement de surveillances, \u00e9ventuellement de montages de la part de services de renseignement, de d\u00e9sinformation, etc., bref les habituels attributs de la maison mensonges &#038; propagande. Mais ces attitudes de voiler la v\u00e9rit\u00e9, d&rsquo;en surveiller l&rsquo;acc\u00e8s n&rsquo;impliquent nullement, justement, d&rsquo;en nier l&rsquo;existence, bien au contraire.<\/p>\n<\/p>\n<p><p>Il ne s&rsquo;agit pas de cr\u00e9er un univers alternatif, une construction faites de ce qu&rsquo;on n&rsquo;ose plus appeler des &lsquo;mensonges&rsquo;, mais de sortes d&rsquo;artefacts divers, de <em>narrative <\/em>destin\u00e9es bient\u00f4t \u00e0 remplacer la r\u00e9alit\u00e9, c&rsquo;est-\u00e0-dire \u00e0 s&rsquo;installer l\u00e0 o&ugrave; se trouvait l&rsquo;expression op\u00e9rationnelle de la v\u00e9rit\u00e9 para&icirc;t-il. Et en effet, c&rsquo;est bien cela : avec Rumsfeld, on se trouve sur le mode offensif, de la cr\u00e9ation d&rsquo;une nouvelle v\u00e9rit\u00e9 lorsqu&rsquo;il pr\u00e9cisa en confidences qu&rsquo;il entendait faire produire \u00e0 ses services des <em>narrative <\/em>clefs en main, et tout cela bien s&ucirc;r pour pr\u00e9server secrets et complots intimes de la s\u00e9curit\u00e9 nationale ; et bient\u00f4t l&rsquo;on arrive au constat que la v\u00e9rit\u00e9 n&rsquo;existait pas puisque la v\u00e9rit\u00e9-simulacre est l\u00e0, aujourd&rsquo;hui, fabriqu\u00e9e de toutes pi\u00e8ces, v\u00e9rit\u00e9 de la postv\u00e9rit\u00e9.<\/p>\n<\/p>\n<p><p>C&rsquo;est en effet le projet et le programme que d\u00e9velopp\u00e8rent Rumsfeld &#038; Cie. Le ministre de la d\u00e9fense axa une part importante de son action sur la &lsquo;communication strat\u00e9gique&rsquo; comme il nommait le domaine, en accord implicite avec les autres principaux membres du cabinet, et surtout du vice-pr\u00e9sident Dick Cheney et de sa cohorte de <em>neocons<\/em> et <em>neo-neocons<\/em>. En 2003, j&rsquo;\u00e9crivais dans ce livre publi\u00e9 \u00e0 la fin de la m\u00eame ann\u00e9e (&lsquo;<em>Chronique de l&rsquo;\u00e9branlement<\/em>&lsquo;), cette remarque sur une visite d&rsquo;adieu de l&rsquo;ambassadeur de France faite \u00e0 Cheney, o&ugrave; Cheney, justement, lui expliquait entre les lignes que les USA \u00e9taient entr\u00e9s dans un nouveau monde, par cons\u00e9quent l\u00e0 o&ugrave; il r\u00e9gissait les fredaines de la v\u00e9rit\u00e9 devenue ainsi postv\u00e9rit\u00e9. Pour le reste de la remarque, je me trompais compl\u00e8tement, croyant que les Europ\u00e9ens s&rsquo;affirmeraient d&rsquo;un point de vue g\u00e9opolitique, alors que la question \u00e9tait psychologique et pathologique, et notre suppos\u00e9 soumission qui suivit et s&rsquo;affirma de plus en plus \u00e9tait en v\u00e9rit\u00e9 (!) une irr\u00e9sistible fascination pour le ma&icirc;tre des v\u00e9rit\u00e9s multiples ; et ainsi \u00e9tait-il \u00e9crit, et j&rsquo;avais bien mal lu, que nous rejoindrions finalement les mutants et zombies am\u00e9ricanistes dans leur &lsquo;<em>Wonderland<\/em>&lsquo; :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>\u00ab\u00a0Vous autres, Europ\u00e9ens, vous n&rsquo;imaginez pas l&rsquo;ampleur de l&rsquo;effet qu&rsquo;a produit sur nous l&rsquo;attaque du 11 septembre\u00a0\u00bb : ce mot du vice-pr\u00e9sident Cheney \u00e0 un ambassadeur d&rsquo;un pays europ\u00e9en venu lui faire ses adieux, en novembre 2002, r\u00e9sume bien l&rsquo;effet le plus profond de l&rsquo;\u00e9v\u00e9nement, exactement contraire \u00e0 ce que nous en cr&ucirc;mes, de fa\u00e7on presque unanime, quand il se produisit. L&rsquo;\u00e9v\u00e9nement trace une rupture. Nous croyions tous qu&rsquo;il allait nous rapprocher, nous autres \u00ab\u00a0civilis\u00e9s\u00a0\u00bb, notre r\u00e9f\u00e9rence am\u00e9ricaine avec le reste (ils disent the Rest Of the World, ou ROW, pour nous d\u00e9signer). Au contraire, l&rsquo;\u00e9v\u00e9nement nous d\u00e9chire et nous s\u00e9pare, et d&rsquo;une fa\u00e7on si in\u00e9luctable qu&rsquo;on se demande si la f\u00ealure n&rsquo;existait pas avant, et qu&rsquo;elle ne demandait qu&rsquo;\u00e0 b\u00e9er<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>A ce moment-l\u00e0, les USA de GW Bush \u00e9taient entr\u00e9s dans cet univers parall\u00e8le de la postv\u00e9rit\u00e9 o&ugrave; le chef de la communication de GW Bush, Karl Rove, ne se privait pas une seconde de dire <a href=\"https:\/\/www.dedefensa.org\/article\/valsez-mensonges\">\u00e0 l&rsquo;auteur Ron Suskind<\/a>, \u00e0 l&rsquo;\u00e9t\u00e9 2002, ces phrases fameuses :<\/p>\n<p>&laquo; <em>Nous sommes un empire maintenant et quand nous agissons nous cr\u00e9ons notre propre r\u00e9alit\u00e9. Et alors que vous \u00e9tudierez cette r\u00e9alit\u00e9, &ndash; judicieusement, si vous voulez, &ndash; nous agirons de nouveau, cr\u00e9ant d&rsquo;autres nouvelles r\u00e9alit\u00e9s, que vous pourrez \u00e0 nouveau \u00e9tudier, et c&rsquo;est ainsi que continuerons les choses. Nous sommes <\/em>[les cr\u00e9ateurs] <em>de l&rsquo;histoire&#8230; Et vous, vous tous, il ne vous restera qu&rsquo;\u00e0 \u00e9tudier ce que nous avons <\/em>[cr\u00e9\u00e9]<em>.<\/em> &raquo;<\/p>\n<\/p>\n<p><p>Il m&rsquo;appara&icirc;t alors r\u00e9trospectivement \u00e9vident, si je parle depuis 2020 comme je le fais, que nous \u00e9tions entr\u00e9s dans la postv\u00e9rit\u00e9 pr\u00e9tendant \u00e0 l&rsquo;op\u00e9rationnalit\u00e9 puisque rien, aucune catastrophe, aucun d\u00e9sastre, aucune maladresse cosmique, comme les USA avec nous dans leurs pas en accumul\u00e8rent durant presque deux d\u00e9cennies, ni m\u00eame <a href=\"https:\/\/www.dedefensa.org\/article\/un-nouveau-910-pour-rumsfeld\">la reconnaissance par Rumsfeld<\/a> lui-m\u00eame des \u00e9checs terribles dans le domaine de l&rsquo;expansion de &lsquo;sa&rsquo; postv\u00e9rit\u00e9 (la &lsquo;communication strat\u00e9gique&rsquo;), ne les firent modifier leurs certitudes d&rsquo;\u00eatre ces cr\u00e9ateurs &lsquo;en continu&rsquo; de postv\u00e9rit\u00e9 en postv\u00e9rit\u00e9, de la Libye \u00e0 la Syrie, \u00e0 l&rsquo;Ukraine, \u00e0 l&rsquo;OTAN, \u00e0 l&rsquo;Iran, \u00e0 la Russie et \u00e0 la Chine et ainsi de suite. Notre <em>Glossaire.dde <\/em>a accumul\u00e9 les concepts qu&rsquo;il nous fut n\u00e9cessaire de d\u00e9velopper pour affronter cette course de la postv\u00e9rit\u00e9 en ne perdant pas trop pied, en r\u00e9sistant \u00e0 cette ivresse compl\u00e8tement fabriqu\u00e9e, &ndash; du <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-le-determinisme-narrativiste\">d\u00e9terminisme narrativiste<\/a> pour mesurer leur folie, \u00e0 la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-verite-de-situation-verite\">v\u00e9rit\u00e9-de-situation<\/a> pour continuellement leur opposer nos contre-feux.<\/p>\n<\/p>\n<p><p>Ce que nous e&ucirc;ment quelques difficult\u00e9s \u00e0 r\u00e9aliser, parce que nous vivions ces \u00e9v\u00e9nements au jour le jour, c&rsquo;est que ce temps d\u00e9vor\u00e9 d&rsquo;une fa\u00e7on hyst\u00e9rique, en d\u00e9non\u00e7ant toutes les menaces du monde et proclamant irr\u00e9sistiblement nos formidables vertus, aggravait chaque jour un peu plus notre cas en nous enfon\u00e7ant dans cette postv\u00e9rit\u00e9 devenue une sorte de &lsquo;plat du jour&rsquo; chaque jour recommenc\u00e9 pour satisfaire notre app\u00e9tit de simulacre. Depuis 2001-2002, nous vivons sur le rythme forcen\u00e9 d&rsquo;une psychologie absolument exacerb\u00e9e, une esp\u00e8ce de tension permanente charg\u00e9e de visions et d&rsquo;ombres diaboliques comme l&rsquo;on trouve dans les cavernes platoniciennes. Le monde de la postv\u00e9rit\u00e9 nous \u00e9crase impitoyablement dans nos simulacres vertueux.<\/p>\n<\/p>\n<p><p>C&rsquo;est ainsi qu&rsquo;aujourd&rsquo;hui j&rsquo;\u00e9value ces longues ann\u00e9es de d\u00e9sordre sanglants et de chaos indescriptible. Le fait, c&rsquo;est-\u00e0-dire la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-verite-de-situation-verite\">v\u00e9rit\u00e9-de-situation<\/a> pour notre compte, est bien que tout le petit monde a suivi, s&rsquo;enfon\u00e7ant dans les <em>narrative<\/em>, inventant les <em>FakeNews <\/em>des autres, d\u00e9couvrant un complotiste, un Russe, un diable et une <em>Alice au Pays des Merveilles<\/em>. Tout cela est bien connu et doit \u00eatre \u00e9galement appr\u00e9ci\u00e9 \u00e0 l&rsquo;aune de ce ph\u00e9nom\u00e8ne de la postv\u00e9rit\u00e9, avec un paroxysme offert par l&rsquo;\u00e9lection de Trump, tout cela jusqu&rsquo;en 2020 qui est cette si terrible ann\u00e9e que nous vivons tous en direct, entre les divers cauchemars et labyrinthes que nous suivons pas \u00e0 pas.<\/p>\n<\/p>\n<blockquote>\n<p><p>Aujourd&rsquo;hui, en 2020, le fardeau est \u00e9norme, consid\u00e9rable et \u00e9crasant, il est arriv\u00e9 \u00e0 son point d&rsquo;inflexion, celui o&ugrave; Atlas lui-m\u00eame titube. Aujourd&rsquo;hui, en 2020, la postv\u00e9rit\u00e9 a effectivement atteint son stade de compl\u00e8te op\u00e9rationnalisation. Elle n&rsquo;a plus de concurrente \u00e0 craindre, qui lui dirait que la v\u00e9rit\u00e9 existe, la mettant dans le plus grand embarras. Elle a rencontr\u00e9 son ma&icirc;tre, sa formule magique, dans la conjonction extraordinaire d&rsquo;un virus venu de l&rsquo;enfer et d&rsquo;un bouffon que tant de grands et beaux esprits d\u00e9crivent comme le gardien de l&rsquo;enfer. Nous, de la brigade de la postv\u00e9rit\u00e9, nous avons atteint ce stade o&ugrave; nous ne parvenons plus \u00e0 fabriquer des simulacres faisant office de v\u00e9rit\u00e9s-\u00e0-la-place-de-la-v\u00e9rit\u00e9, o&ugrave; la postv\u00e9rit\u00e9 elle-m\u00eame nous devient insupportable&#8230;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Car dans la postv\u00e9rit\u00e9 achev\u00e9e, compl\u00e8tement op\u00e9rationnalis\u00e9e, plus rien n&rsquo;est vrai, y compris les choses les plus sacralis\u00e9es que nous avions mis sur nos offertoires en carton bouilli et en papier m\u00e2ch\u00e9. La psychologie n&rsquo;y r\u00e9siste pas. Elle se laisse d\u00e9licieusement emporter dans le paroxysme de l&rsquo;\u00e9pisode maniaque auquel nous assistons aujourd&rsquo;hui avec nos <a href=\"https:\/\/www.dedefensa.org\/article\/wokez-vous-de-nous\">petits soldats du wokenisme<\/a>, lequel est une repr\u00e9sentation acceptable de la maturit\u00e9 de la postv\u00e9rit\u00e9, de son op\u00e9rationnalit\u00e9 finale. C&rsquo;est \u00e0 ce moment-l\u00e0 que na&icirc;t le temps des opportunit\u00e9s : quand ils n&rsquo;ont plus de v\u00e9rit\u00e9s-simulacres \u00e0 mettre \u00e0 la place de la v\u00e9rit\u00e9 pour tenir le rythme de la postv\u00e9rit\u00e9, \u00e0 se mettre sous la dent, parce que comme moi ils n&rsquo;ont plus de dent. (Seulement, moi je ne pr\u00e9tends pas mordre.)<\/p>\n<\/p>\n<blockquote>\n<p><p>En d&rsquo;autres mots un peu plus brefs, je dirais que la postv\u00e9rit\u00e9 est n\u00e9e de la crise qu&rsquo;on jugea terminale de la v\u00e9rit\u00e9 alors qu&rsquo;on \u00e9tait soi-m\u00eame cause de cette crise. Que faire alors lorsqu&rsquo;on r\u00e9alise que l&rsquo;op\u00e9rationnalit\u00e9 finale de la postv\u00e9rit\u00e9 \u00e9rig\u00e9e en cr\u00e9atrice de mondes nouveaux ressemble \u00e0 s&rsquo;y m\u00e9prendre \u00e0 la crise finale de la postv\u00e9rit\u00e9 ?<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Cette question se pose \u00e0 eux, qui se disaient en 2002 \u00ab\u00a0cr\u00e9ateurs de l&rsquo;histoire\u00a0\u00bb, pas \u00e0 moi. Je suis de ceux qui attendaient ce moment, qui se lavent les mains du trouble terrible o&ugrave; ils se trouvent plong\u00e9s. J&rsquo;attends avec int\u00e9r\u00eat, sinon une certaine jubilation n\u00e9cessairement angoiss\u00e9e, de voir ce que l&rsquo;Histoire va juger opportun de faire de ces d\u00e9bris sinistres de cette tentative extraordinairement arrogante de ma&icirc;triser l&rsquo;univers avec des incantations de sorciers de pacotille.<\/p>\n<\/p>\n<p><p>Voyons cela&#8230; Nous verrons bien, r\u00e9pondit le sphinx avec un sourire malicieux.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Maturit\u00e9 de la postv\u00e9rit\u00e9 21 d\u00e9cembre 2020 &ndash; Je crois et dirais bien que 2020, qui se m\u00e9lange si bien avec 2002, est l&rsquo;arriv\u00e9e \u00e0 maturit\u00e9 de l&rsquo;op\u00e9rationnalisation de la Post-V\u00e9rit\u00e9 (disons PV, pour faire court), &ndash; la Post-V\u00e9rit\u00e9-PV, ou \u00e9crit &lsquo;postv\u00e9rit\u00e9&rsquo; selon l&rsquo;usage auquel je me tiendrai. Je tiens par contre avec fermet\u00e9 \u00e0&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[16316,9698,3015,17879,12412,2631,13053,5135,857,13122,8386,4321,3099,1480,569,3068,4373,19260,12511,11721],"class_list":["post-79575","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-11-septembre","tag-afghanidstan","tag-communication","tag-covid19","tag-createurs","tag-de","tag-gces","tag-hysterie","tag-irak","tag-karl","tag-lhistoire","tag-narrative","tag-psychologie","tag-rove","tag-rumsfeld","tag-strategique","tag-suskind","tag-usa2020","tag-verite-de-situation","tag-wikipedia"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79575","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79575"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79575\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79575"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79575"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}