{"id":79583,"date":"2020-12-27T12:44:14","date_gmt":"2020-12-27T12:44:14","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2020\/12\/27\/visions-de-luongo-smith\/"},"modified":"2020-12-27T12:44:14","modified_gmt":"2020-12-27T12:44:14","slug":"visions-de-luongo-smith","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2020\/12\/27\/visions-de-luongo-smith\/","title":{"rendered":"Visions de Luongo-Smith"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Visions de Luongo-Smith<\/h2>\n<\/p>\n<p><p>27 d\u00e9cembre 2020 &ndash; Peut-\u00eatre cela appara&icirc;t-il <a href=\"https:\/\/www.dedefensa.org\/article\/rapsit-usa2020-la-secession-libertarienne\">dans le texte<\/a> de notre site bien-aim\u00e9, dans tous les cas je suis frapp\u00e9 par l&rsquo;effet sur moi-m\u00eame des observations conjugu\u00e9es et additionn\u00e9s de Tom Luongo et Brandon Smith (Luongo-Smith). J&rsquo;ignore (encore ?) pourquoi, mais elles me paraissent comme soulign\u00e9es, \u00e9clair\u00e9es d&rsquo;une lumi\u00e8re exceptionnelle, et qui nous baigne de clart\u00e9 moins par sa puissance que par l&rsquo;harmonie qu&rsquo;elle met en \u00e9vidence. Leurs observations, c&rsquo;est-\u00e0-dire le ton et la mesure qu&rsquo;on y distingue, autant que la force de l&rsquo;\u00e9vidence, presque comme une sorte de sagesse, seraient peut-\u00eatre assez fortes pour nous d\u00e9gager de la pr\u00e9gnance fascinatoire, comme l&rsquo;on est fascin\u00e9 par une sorte de b\u00eatise infernale, du bin\u00f4me-bouffe Trump-Biden.<\/p>\n<\/p>\n<p><p>Disons d&rsquo;abord qu&rsquo;il y a dans l&rsquo;ontologie de la crise une extraordinaire pertinacit\u00e9, &ndash; mot nouveau pour moi, qui me surprend et me s\u00e9duit, du latin <em>pertinax <\/em>pour pers\u00e9v\u00e9rant. Le paradoxe, car nous y sommes d\u00e9j\u00e0, est que cette crise, matrice et c&oelig;ur hurlant de la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-la-gces\">Grande Crise<\/a>, est due d&rsquo;abord \u00e0 cet homme si d\u00e9testable. Le narcissisme et le furieux ent\u00eatement de Trump, refusant par vaniteuse bravade et de toutes les fa\u00e7ons possibles, les us &#038; coutumes du Syst\u00e8me, et notamment le Dieu-Fraude du Syst\u00e8me devant lequel chacun se doit de faire r\u00e9v\u00e9rence et se prosterner, et notamment encore la fa\u00e7on qu&rsquo;il a <a href=\"https:\/\/www.theepochtimes.com\/trump-urges-gop-senators-to-step-up-and-fight-for-the-presidency_3633397.html\">d&rsquo;asticoter les s\u00e9nateurs r\u00e9publicains<\/a>, d&rsquo;une couardise \u00e0 ne pas croire, qui refusent de se battre vraiment pour le soutenir&#8230;<\/p>\n<\/p>\n<p><p>Autre forme du ph\u00e9nom\u00e8ne que nous signale mon nouveau mot, la pertinacit\u00e9 exceptionnelle aux USA o&ugrave;, plus qu&rsquo;en aucun autre pays, la crise Covid19 est v\u00e9cue comme compl\u00e8tement m\u00e9tahistorique, ce qu&rsquo;elle est exactement, et observ\u00e9e, utilis\u00e9e, manipul\u00e9e, conduite et jug\u00e9e par la politique, ce qui est rendre \u00e9videmment compte d&rsquo;une situation incontestable, d&rsquo;une <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-verite-de-situation-verite\">v\u00e9rit\u00e9-de-situation<\/a> comme si l&rsquo;on \u00f4tait le masque.<\/p>\n<\/p>\n<p><p>(Quelle bassesse en France, par comparaison avec la micro-gestion de la chose ; colossale arrogance de nos sentencieux toubibs s&rsquo;\u00e9charpant comme comm\u00e8res en furie au chevet de la Science-la\u00efque ; explications infantilisantes et vanit\u00e9-scientogiste de charlatan de nos soignants et politiciens-soignants ; extr\u00eame propagandisme-narrativiste [pourquoi ne pas fabriquer une nouvelle expression dans l&rsquo;avanc\u00e9e <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-le-determinisme-narrativiste\">d&rsquo;une chose<\/a> d\u00e9j\u00e0 si catastrophique ?] de nos commentateur si \u00e9pris des libert\u00e9s de la d\u00e9esse-La\u00efcit\u00e9 ; \u00e0 la t\u00eate de tout ce <em>souk-smala<\/em>, l&rsquo;\u00e9trange avorton [AVBI, pour Avorton-Volant Bien Identifi\u00e9], qui ne sait que faire du sceptre et du globe, Jupiter des <em>start-ups<\/em> du Progr\u00e8s en-marche sur l&rsquo;autoroute de l&rsquo;Olympe<em>.<\/em>)<\/p>\n<\/p>\n<p><p>D&rsquo;ailleurs, quelle est pr\u00e9cis\u00e9ment la situation dans ces m\u00eames USA ? Je vous propose quelques lignes de Robert Gore, de <em><a href=\"https:\/\/straightlinelogic.com\/2020\/12\/23\/the-gray-curtain-descends-part-1-by-robert-gore\/\">StraightLineLogic<\/a><\/em>, transitant par l&rsquo;in\u00e9vitable <em><a href=\"https:\/\/www.zerohedge.com\/political\/gray-curtain-descends-part-1\">ZeroHedge.com<\/a>.<\/em><\/p>\n<\/p>\n<p><\/p>\n<p>&laquo; <em>Dispensez-vous de l&rsquo;obsc\u00e9nit\u00e9 qui fait que les intentions exprim\u00e9es excusent tous les crimes et les cons\u00e9quences.<\/em><\/p>\n<p>&raquo; <em>Il s&rsquo;agit d&rsquo;une lutte serr\u00e9e entre deux <\/em><em>narrative <\/em><em>officiellement approuv\u00e9es<\/em><em> pour d\u00e9terminer laquelle est la plus faussaire : l<\/em><em>e coronavirus comme fl\u00e9au de l&rsquo;humanit\u00e9 ou l&rsquo;\u00e9lection libre et \u00e9quitable en Am\u00e9rique. La premi\u00e8re a permis la seconde, et elles ont \u00e9t\u00e9 propag\u00e9es par les m\u00eames personnes \u00e0 la suite d&rsquo;une prise de pouvoir g\u00e9n\u00e9ralis\u00e9e. Les deux sont truff\u00e9s d&rsquo;incoh\u00e9rences flagrantes et de fraudes, dont aucune n&rsquo;est mentionn\u00e9e dans la soci\u00e9t\u00e9 polic\u00e9e du politiquement-correct.<\/em><\/p>\n<p>&raquo; <em>\u00ab\u00a0<\/em><em>Il est \u00e9trange, pensait-elle, d&rsquo;obtenir des nouvelles par le biais de rien d<\/em><em>&lsquo;<\/em><em>autre que des d\u00e9n\u00e9gations, comme si l<\/em><em>&lsquo;<\/em><em>existence avait cess\u00e9, <\/em><em>comme si <\/em><em>les faits avaient disparu<\/em><em>, comme si s<\/em><em>eules les <\/em><em>d\u00e9n\u00e9gation<\/em><em>s fr\u00e9n\u00e9tiques prononc\u00e9es par les fonctionnaires et les chroniqueurs donnaient une id\u00e9e de la r\u00e9alit\u00e9 qu&rsquo;ils nient<\/em><em>\u00ab\u00a0<\/em><em>.<\/em><em> [&lsquo;<\/em><em>Atlas Shrugged<\/em><em>&lsquo;<\/em><em>, Ayn Rand, 1957<\/em><em>]<\/em><\/p>\n<p>&raquo; <em>Les propagateurs de ces histoires ne s&rsquo;attaquent pas aux incoh\u00e9rences et \u00e0 la fraude parce qu&rsquo;ils ne le peuvent pas ; ils nient simplement leur existence. Ils suppriment les questions, les enqu\u00eates et l&rsquo;exploration de preuves et de faits r\u00e9els, et promeuvent des slogans stupides. La censure <\/em><em>classique <\/em><em>des m\u00e9dias <\/em><em>tourne \u00e0 plein, <\/em><em>mais pas aussi efficace qu&rsquo;on l&rsquo;esp\u00e9rait, en grande partie gr\u00e2ce aux m\u00e9dias alternatifs. La censure elle-m\u00eame est une sonnerie stridente pour nous alarmer. Si les reportages approuv\u00e9s sont <\/em><em>d&rsquo;une &lsquo;v\u00e9rit\u00e9 aveuglante&rsquo;, <\/em><em>pourquoi ne peuvent-ils pas \u00eatre contest\u00e9s ?<\/em><\/p>\n<p>&raquo; <em>Les propagandistes <\/em><em>sont en charge de la suppression de la libert\u00e9 d&rsquo;enqu\u00eater et de d\u00e9battre, et <\/em><em>ils sont sur le point <\/em><em>d&rsquo;y parvenir <\/em><em>compl\u00e8tement. Avec l&rsquo;<\/em><em>arriv\u00e9e<\/em><em> de Biden-Harris le mois prochain et la cabale de pr\u00e9dateurs et de parasites au pouvoir \u00e0 laquelle ils rendent compte, l<\/em><em>a formidable importance de l&rsquo;enjeu est en place. <\/em><em>Ils ne voient pas la n\u00e9cessit\u00e9 de continuer \u00e0 feindre la fid\u00e9lit\u00e9 \u00e0 autre chose que l<\/em><em>a recherche de l&rsquo;<\/em><em>ass<\/em><em>ervissement et du <\/em><em>contr\u00f4le<\/em>. &raquo;<\/p>\n<\/p>\n<p><\/p>\n<p>C&rsquo;est contre cela que Luongo-Smith bataillent puisqu&rsquo;il le peuvent (&laquo; <em>La censure <\/em><em>classique <\/em><em>des m\u00e9dias<\/em>&#8230; [&#8230;] <em>pas aussi efficace qu&rsquo;on l&rsquo;esp\u00e9rait, en grande partie gr\u00e2ce aux m\u00e9dias alternatifs<\/em>. &raquo;) &#8230; Cette pertinacit\u00e9 am\u00e9ricaniste, \u00e0 nulle autre pareille parce que la crise est d&rsquo;une amplitude, d&rsquo;une puissance et d&rsquo;une profondeur \u00e0 nulles autres pareilles comme on vient de la d\u00e9crire, fait sortir chez certains des uns et des autres les \u00e9tats fondamentaux de l&rsquo;\u00e2me.<\/p>\n<\/p>\n<p><p>Ainsi ai-je \u00e9t\u00e9 frapp\u00e9 par Luongo-Smith, leur esprit d&rsquo;ind\u00e9pendance et de dissidence, affirm\u00e9 soudain avec clart\u00e9. Chez Luongo, pourtant le contraire de tout cela, personnage s\u00e9rieux qui doit \u00eatre parfois p\u00e9remptoire, et qui \u00e9crit, presqu&rsquo;avec de la po\u00e9sie comme pr\u00e9monition, avec les id\u00e9es platoniciennes voletant comme papillons au printemps, pour se poser sur son \u00e9paule, lui chuchoter \u00e0 l&rsquo;oreille&#8230; &laquo; <em>Ainsi, pour moi, l&rsquo;id\u00e9e que les &Eacute;tats-Unis se s\u00e9parent en plusieurs parties a \u00e9t\u00e9 une constante compagne pendant la majeure partie de ma vie adulte. Et, en tant que libertarien, je pense toujours en termes de s\u00e9cession d&rsquo;abord, plut\u00f4t que de r\u00e9volution. <strong>Cette id\u00e9e est assise sur mon \u00e9paule et me chuchote \u00e0 l&rsquo;oreille la v\u00e9rit\u00e9 de ce qui est devant nous<\/strong>.<\/em> &raquo;<\/p>\n<\/p>\n<p><p>Dans la logique de la forme de son discours, Luongo poursuit avec une affirmation qui ne s&#8217;embarrassent nullement de la charge habituelle de &lsquo;faits av\u00e9r\u00e9s&rsquo;, d\u00a0\u00bbarguments de raison&rsquo;, de &lsquo;raisonnements de logique&rsquo;, de &lsquo;mesure du propos&rsquo; qu&rsquo;affectionnent de porter nos &lsquo;sachants&rsquo; tout du Rien, tels autant d&rsquo;Atlas postmodernes des salons et des plateaux ; Luongo plut\u00f4t proph\u00e9tique, que certains jugeront hyst\u00e9rique du haut de leur <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-crisis-la-crise-de-la-raison-humaine-1\">Raison-subvertie<\/a> : &laquo; <em>Nous sommes arriv\u00e9s \u00e0 un moment tr\u00e8s important de l&rsquo;histoire du monde.<\/em> &raquo;<\/p>\n<\/p>\n<p><p>Mais passons outre (je cite Jehanne) et laissons l\u00e0 Luongo-Smith, apr\u00e8s qu&rsquo;ils nous en aient instruits, pour en venir au c&oelig;ur et \u00e0 l&rsquo;\u00e9chapp\u00e9e finale de mon propos.<\/p>\n<\/p>\n<p><p>Je crois que les choses essentielles de cette phase extraordinairement critique de la Grande Crise ne se situent nullement l\u00e0 o&ugrave; l&rsquo;on croit les d\u00e9busquer. Dans cette qu\u00eate, je laisse de c\u00f4t\u00e9 le brouhaha extraordinaire du &lsquo;Rien&rsquo; qui nous environne et nous presse, mensonges, anath\u00e8mes, simulacres \u00e9pouvantables, cynisme furieux et hyst\u00e9rique, et l&rsquo;hyst\u00e9rie, l&rsquo;hyst\u00e9rie qui ne cesse d&rsquo;agresser et d&rsquo;accabler notre psychologie de ce tintamarre inimaginable du &lsquo;Rien&rsquo; nous enjoignant de le  prendre pour le vrai ! Le vrai de ces temps de <a href=\"https:\/\/www.dedefensa.org\/article\/maturite-de-la-postverite\">postv\u00e9rit\u00e9<\/a>, quelle trouvaille !<\/p>\n<\/p>\n<p><p>Non, je crois plut\u00f4t \u00e0 la puissance cach\u00e9e, lumineuse et n\u00e9cessairement obscure pour nos sens accabl\u00e9s chez ceux qui c\u00e8dent \u00e0 cet accablement ; choses venues du tr\u00e9fonds abyssal des plus grandes hauteurs du Ciel, pour nous inonder d&rsquo;une sublime lumi\u00e8re obscure, transmut\u00e9s en irr\u00e9fragable sur\u00e9minence dans l&rsquo;oxymore des tr\u00e8s-grandes choses, intuition haute &#038; transcendance absolue&#8230; Le &laquo; <em>Je crois aux forces de l&rsquo;Esprit <\/em>&raquo; d&rsquo;un Mitterrand agonisant, et pour cette fois, quittant les oripeaux du Florentin de ses vaines man&oelig;uvres, pour une fois sinc\u00e8re et v\u00e9ridique.<\/p>\n<\/p>\n<p><p>(Croiriez-vous que je puisse \u00e9crire cela \u00e0 propos d&rsquo;un Macron, pauvre f\u00e9tu de paille impuissant \u00e0 toute combustion, sold\u00e9 en bourse et emport\u00e9 par la temp\u00eate qui nous importe, cette souterraine et insaisissable grandeur pour qui ne sait pas hausser son regard vers les fulgurances du Ciel ?)<\/p>\n<\/p>\n<p><p>Certes, les bouleversements sont en marche, dans un grondement inaudible et comme lib\u00e9r\u00e9 pour les oreilles attentives, plut\u00f4t comme une petite musique soutenue par une basse continue qui parvient \u00e0 ma&icirc;triser leurs grosses caisses et leur rythme de vaudou-zombis\u00e9, <em>Rap <\/em>et<em> Hip-Hop<\/em> transmut\u00e9s en autant d&rsquo;hymnes transnationaux hallucin\u00e9s du transgenrisme enfin mesur\u00e9 \u00e0 l&rsquo;aube du transhumanisme ; comme des Wagner enfin postmodernis\u00e9s en une cacophonie fondatrice du monde-mondialis\u00e9 et du genre-genris\u00e9, et de l&rsquo;identit\u00e9 r\u00e9duite aux acqu\u00eats de cette bouillie pour les zombies \u00e9merg\u00e9s du recyclage de bazar r\u00e9alis\u00e9 au sons de ces bruits de foire d\u00e9mente&#8230; Comme l&rsquo;on sait, Nietzsche, pour substantiver son combat transcendantal contre Wagner, lui opposait Bizet et sa musique m\u00e9diterran\u00e9enne, rendue si a\u00e9rienne par les legs grec et romain ; et cette petite musique et sa basse continue de notre temps, pour les oreilles attentives, nous disant : \u00ab\u00a0Les choses arrivent, les choses arrivent\u00a0\u00bb<\/p>\n<\/p>\n<p><p>Je crois que nous ne les voyons pas venir, pas encore, ces choses, car il est \u00e9vident que nous \u00e9coutons souvent tr\u00e8s mal ce que nous entendons. Tous nos sens sont mobilis\u00e9s par leurs bruits inf\u00e2mes, leurs hurlements comme autant de r\u00f4ts et \u00e9ructations venus des enfers souterrains, et du Diable ricanant devant l&rsquo;incendie du monde&#8230; Sans doute certains, &ndash; et ils sont si nombreux ! &ndash; jugeront-ils pr\u00e9f\u00e9rables de s&rsquo;en tenir l\u00e0, et, discutant des gestes-barri\u00e8re, de la la\u00efcit\u00e9 et de l&rsquo;insupportable ent\u00eatement de l&rsquo;Autre \u00e0 proclamer que les \u00e9lections ont \u00e9t\u00e9 fraud\u00e9es comme jamais&#8230; Qu&rsquo;importe, les choses viennent, elles avancent \u00ab\u00a0\u00e0 bas-bruit\u00a0\u00bb comme ils disent, mais bruit si profond, bruit si compl\u00e8tement d\u00e9cisif, bruit qu&rsquo;un Giono identifierait comme <em>La chant du monde<\/em>.<\/p>\n<\/p>\n<p><p>Mais laissons cela. Je vous parlais donc de Luongo et de Smith&#8230;<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Visions de Luongo-Smith 27 d\u00e9cembre 2020 &ndash; Peut-\u00eatre cela appara&icirc;t-il dans le texte de notre site bien-aim\u00e9, dans tous les cas je suis frapp\u00e9 par l&rsquo;effet sur moi-m\u00eame des observations conjugu\u00e9es et additionn\u00e9s de Tom Luongo et Brandon Smith (Luongo-Smith). J&rsquo;ignore (encore ?) pourquoi, mais elles me paraissent comme soulign\u00e9es, \u00e9clair\u00e9es d&rsquo;une lumi\u00e8re exceptionnelle, et&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[831,20315,12650,17879,2631,3460,6641,13053,2891,19411,11605,2913,5649,2617,6717,20551,20552,20553,4457,2639],"class_list":["post-79583","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-a","tag-bas-bruit","tag-brandon","tag-covid19","tag-de","tag-forces","tag-fraude","tag-gces","tag-grande","tag-grise","tag-lesprit","tag-les","tag-luongo","tag-macron","tag-mitterrand","tag-oxymore","tag-pertinacite","tag-propagandisme-narrativiste","tag-smith","tag-trump"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79583","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79583"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79583\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79583"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79583"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}