{"id":79605,"date":"2021-01-11T15:09:39","date_gmt":"2021-01-11T15:09:39","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2021\/01\/11\/leur-1789-delire-les-gafam-sortent-du-bois\/"},"modified":"2021-01-11T15:09:39","modified_gmt":"2021-01-11T15:09:39","slug":"leur-1789-delire-les-gafam-sortent-du-bois","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2021\/01\/11\/leur-1789-delire-les-gafam-sortent-du-bois\/","title":{"rendered":"Leur 1789-d\u00e9lire\u00a0: les GAFAM sortent du bois"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Leur 1789-d\u00e9lire : les GAFAM sortent du bois<\/h2>\n<\/p>\n<p><p>11 janvier 2021 &ndash; Chaque fois que je commence une chronique, ces temps-ci encore plus que les Temps d&rsquo;Avant, parce que les Temps Derniers sont plus foisonnants et plus occup\u00e9s, &ndash; chaque fois je me demande : \u00ab\u00a0Quel sujet choisir ?\u00a0\u00bb, puis, ayant choisi, je m&rsquo;interroge \u00e0 nouveau : \u00ab\u00a0Par quoi commencer ?\u00a0\u00bb C&rsquo;est dire l&rsquo;abondance des choses, des nouvelles, des informations, des manipulations, des <em>FakeNews<\/em> (je vous rassure pour ces derni\u00e8res : elles viennent essentiellement de ceux qui les d\u00e9noncent, comme chante la poule qui a fait l&rsquo;&oelig;uf).<\/p>\n<\/p>\n<p><p>Cela pr\u00e9cis\u00e9 pour bien situer le contexte o&ugrave; j&rsquo;\u00e9volue, voil\u00e0 que j&rsquo;ai choisi et que je sais par quoi commencer : \u00ab\u00a0Petite le\u00e7on de chose par AMLO\u00a0\u00bb, de l&rsquo;abr\u00e9viation de &laquo; <em><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Andr\u00e9s_Manuel_L\u00f3pez_Obrador\">Andr\u00e9s Manuel L&oacute;pez Obrador<\/a>, parfois d\u00e9sign\u00e9 sous l&rsquo;acronyme d&rsquo;AMLO, n\u00e9 le 13 novembre 1953 \u00e0 Tepetit&aacute;n, &#8230;  homme d&rsquo;&Eacute;tat mexicain, et pr\u00e9sident de la R\u00e9publique depuis le 1er d\u00e9cembre 2018<\/em> &raquo;.<\/p>\n<\/p>\n<p><p>C&rsquo;est vous dire combien c&rsquo;est &lsquo;du lourd&rsquo;, car AMLO est bien une ic\u00f4ne de la gauche exotique, ex-tiers-mondisme et devenue plus urbaine, sinon &lsquo;bobo&rsquo;, sinon m\u00eame-<a href=\"https:\/\/www.dedefensa.org\/article\/notes-sur-le-wokenisme-seul-ii\">wokenis\u00e9e<\/a> pour certains. Il se trouve que ce n&rsquo;est pas la voie d&rsquo;AMLO&#8230; Surprise, surprise&#8230;<\/p>\n<\/p>\n<p><p>Cela se passe vendredi, Obrador donne une conf\u00e9rence de presse. Il parle des \u00e9v\u00e9nements aux USA. L\u00a0\u00bbattaque&rsquo; du Capitole, qu&rsquo;en pense-t-il ? Rien de sp\u00e9cial \u00e0 dire, semble-t-il, et disant cela parce qu&rsquo;il est poli, et qu&rsquo;en fait il s&rsquo;en fiche. Il en vient \u00e0 son sujet manifestement favori et essentiel pour lui, qui est l&rsquo;action des GAFAM contre Trump et la suite de la Grande-Purge.<\/p>\n<\/p>\n<p><p>AMLO est dans une grande fureur et ne m\u00e2che pas ses mots. Il \u00ab\u00a0sent\u00a0\u00bb que Zuckerberg est un type &laquo; <em>arrogant<\/em> &raquo; et &laquo; <em>ayant une haute opinion de lui-m\u00eame<\/em> &raquo;, &ndash; et ce n&rsquo;est manifestement pas l&rsquo;opinion de AMLO. Ce pr\u00e9sident mexicain, &lsquo;ic\u00f4ne exotique&rsquo; de la gauche, parle longuement du sujet des GAFAM. <a href=\"https:\/\/finance.yahoo.com\/news\/mexican-president-chides-arrogant-zuckerberg-171235540.html\">Cela le passionne<\/a>, et pour <a href=\"https:\/\/www.zerohedge.com\/political\/mexicos-president-condemns-moves-censor-trump-twitter-facebook-acting-inquisition\">tonner de col\u00e8re<\/a> !  Et disant ainsi, et d&rsquo;abord \u00e0 propos de Trump censur\u00e9 :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Je n&rsquo;aime pas que quelqu&rsquo;un soit censur\u00e9 ou qu&rsquo;on lui retire le droit de poster un message sur Twitter ou Facebook. Je ne suis pas d&rsquo;accord avec cela, je n&rsquo;accepte pas cela<\/em>&#8230;<\/p>\n<\/p>\n<p><p>&raquo; <em>Comment pouvez-vous censurer quelqu&rsquo;un, comme si vous disiez \u00ab\u00a0Voyons, c&rsquo;est simple, en tant que juge de la Sainte Inquisition je vais vous punir parce que je pense que ce que vous dites est nuisible.<\/em> [&#8230;] <em>O&ugrave; est la loi, o&ugrave; est le r\u00e8glement, quelles sont les normes ? C&rsquo;est une question de gouvernement, ce n&rsquo;est pas une question pour les entreprises priv\u00e9es\u00a0\u00bb.<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Rappelez-vous tout de m\u00eame que l&rsquo;un des piliers de la haine contre Trump a \u00e9t\u00e9 ses intentions proclam\u00e9es d&rsquo;\u00e9riger un mur entre le Mexique et les USA, semblant vouer ce pays (le Mexique) aux g\u00e9monies. AMLO a pu constater entretemps que Trump a beaucoup moins fait contre son pays que n&rsquo;avait fait, avant lui, la brillante bande des humanitaristes-obamiens. (Les enfants migrants \u00ab\u00a0dans les cages\u00a0\u00bb, c&rsquo;est une trouvaille du temps d&rsquo;Obama.)<\/p>\n<\/p>\n<p><p>Mais le climat s&rsquo;est brutalement alourdi, d\u00e9sormais beaucoup trop lourd pour qu&rsquo;on se rappelle quoi que ce soit des <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-verite-de-situation-verite\">v\u00e9rit\u00e9s-de-situation<\/a>, &ndash; s&rsquo;ils ont jamais rencontr\u00e9 cela (une v\u00e9rit\u00e9-de-situation). Il y a eu l'\u00a0\u00bbattaque\u00a0\u00bb du Capitole, qui m\u00e9rite de plus en plus <a href=\"https:\/\/off-guardian.org\/2021\/01\/07\/the-storming-of-the-capitol-americas-reichstag-fire\/\">des guillemets<\/a> tant elle a des aspects bouffe et des <a href=\"https:\/\/www.theepochtimes.com\/self-proclaimed-revolutionary-eggs-on-capitol-intruders-as-he-records-them-publishes-video_3649617.html?utm_source=morningbriefnoe&#038;utm_medium=email&#038;utm_campaign=mb-2021-01-10\">aspects-bidons<\/a> \u00e0 c\u00f4t\u00e9 de la trag\u00e9die des 5 morts. Mais les r\u00e9actions qu&rsquo;elle a provoqu\u00e9es ont \u00e9t\u00e9 d&rsquo;une telle \u00ab\u00a0obsc\u00e9nit\u00e9\u00a0\u00bb !<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>C&rsquo;est un acte insens\u00e9 au point d&rsquo;\u00eatre obsc\u00e8ne que de comparer l&rsquo;incursion d&rsquo;hier \u00e0 l&rsquo;attaque du 11 septembre ou (comme l&rsquo;a fait le s\u00e9nateur Chuck Schumer <a href=\"https:\/\/email.mg2.substack.com\/c\/eJwlkduOhCAMhp9muMNwcFAvuNibfQ2DUJVZBMJhXd9-cSZpSlP6t81XrQpsIV0yhlzQ7eZyRZAezuygFEioZkizNZKOE-Mj4cjI3tDxOSKb5zUBHMo6WVIFFOvirFbFBv9WsFEIhnapn5wtvaYA67j0fOUDrIIN00BMPwo-fAaraix4DTJ4d707Iyf3UmJ-8K8H-262upCsUTE4W6zOnQ5Hy6qkd_sLuYV8YpOgWO9V_-DcngMSzurK-KU8FpgRRvFpncOuKbD1zVZ1XMjK-4tQMtCJsJ53tDv_GJxTJS--PXpybKzLdclF6Z97Lkoy7tbZGGFLKmcorciAgRV8Vl1I241jbpVH9bZcM3i1ODAfUuUD_M1u3sBDaocwsyqSCkpIL6jgI6cfMA0lp5RzNlHUVjChqbzcGiB_Kmf-ARIbmbs\">hier soir<\/a>) \u00e0 Pearl Harbor. <\/em>&raquo; (<a href=\"https:\/\/www.dedefensa.org\/article\/rapsit-usa2021-apres-106-au-capitole\">Greenwald<\/a>)<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Puis l&rsquo;offensive t\u00e9moignant d&rsquo;une <em>hybris <\/em>paroxystique des GAFAM, soulevant la saine col\u00e8re de AMLO, mais soudain installant symboliquement et op\u00e9rationnellement ce climat de terreur et de tyrannie possible. Le colonel Lang met <a href=\"https:\/\/turcopolier.typepad.com\/sic_semper_tyrannis\/2021\/01\/denial-of-freedom-of-speech-underway.html\">ce bref message<\/a> sur son site <em>Sic Semper Tyrannis<\/em>, le <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Sic_semper_tyrannis\">bien-nomm\u00e9<\/a> par les temps qui courent et cible parmi tant d&rsquo;autres de ces Derniers Temps qui nous \u00e9crasent : &laquo; <em>Le d\u00e9ni de la libert\u00e9 d&rsquo;expression est en marche &ndash; &Eacute;tant donn\u00e9 la purge en cours des clients de Twitter et les efforts actuels de CNN pour que FoxNews se voit refuser les services de transmission, je m&rsquo;attends \u00e0 ce que ma page Facebook disparaisse bient\u00f4t.  Est-ce que Typepad<\/em> [serveur du site SST] <em>suivra ? Attendez-vous \u00e0 cela<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>En attendant, l&rsquo;on suit les tribulations de <em>Parler.com<\/em>, la plate-forme qui-ne-censure-pas, en butte \u00e0 <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-verite-de-situation-verite\">des attaques<\/a> (des vraies, celles-l\u00e0) <a href=\"https:\/\/www.rt.com\/usa\/512050-amazon-coordinated-attack-parler\/\">coordonn\u00e9es<\/a> de Google, de Apple et, en derni\u00e8re minute car on ne peut pas rater le train de l&rsquo;humanitarisme-postmoderne, d&rsquo;Amazon soi-m\u00eame, qui fournit \u00e0 <em>Parler.com<\/em> ses serveurs. Par cons\u00e9quent, Parler <a href=\"https:\/\/www.rt.com\/news\/512110-conservative-website-parler-offline\/\">est bloqu\u00e9<\/a> pour l&rsquo;instant, \u00e0 la recherche d&rsquo;un nouveau serveur qu&rsquo;il esp\u00e8re trouver cette semaine.<\/p>\n<\/p>\n<p><p>Par contre, les affaires vont bien pour un autre larron conservateur qui est apparu sur le devant de la sc\u00e8ne, sourire aux dents. <em><a href=\"https:\/\/gab.com\/\">Gab.com<\/a> <\/em>a pris la pr\u00e9caution de s&rsquo;\u00e9quiper lui-m\u00eame de ses serveur(s) et tout le tremblement n\u00e9cessaire \u00e0 une plate-forme et \u00e0 sa diffusion, par cons\u00e9quent compl\u00e8tement apte \u00e0 ne plus passer par le <em>diktat <\/em>parfum\u00e9 des petits-marquis, et racketteurs de <em>Silicon Valley<\/em>, les Capone-vertueux des GAFAM. <em><a href=\"https:\/\/gab.com\/\">Gab.com<\/a><\/em> est donc un twitter sans Dorsey, ni passage oblig\u00e9 par Bezos. <a href=\"https:\/\/gab.com\/a\">Andrew Tobas<\/a>, le CEO de <em>Gab.com <\/em>annon\u00e7ait hier en fin de journ\u00e9e :  &laquo; <em>600 000 nouveaux Gabeurs aujourd&rsquo;hui<\/em>. &raquo; On avait remarqu\u00e9 un certain ralentissement de fonctionnement de ce r\u00e9seau &lsquo;alternatif&rsquo; ces deux derniers jours ; un communiqu\u00e9 d&rsquo;hier nous explique : &laquo; <em>Notre trafic a <a href=\"https:\/\/www.breitbart.com\/tech\/2021\/01\/09\/free-speech-platform-gab-reports-750-increase-in-traffic\/\">augment\u00e9 de 753%<\/a> ces derni\u00e8res 24 heures. Des dizaines de millions de visite.<\/em> &raquo; <a href=\"https:\/\/www.rt.com\/usa\/512081-tech-censorship-trump-gab\/\">RT.com<\/a> nous fait un point sur cette situation o&ugrave; le ralentissement de la vitesse d&rsquo;ex\u00e9cution s&rsquo;explique par l&rsquo;afflux des visites et des inscriptions.<\/p>\n<\/p>\n<p><p>(&#8230;Et j&rsquo;ajouterais avant de passer \u00e0 la description-RT.com de la situation que les vigilants gardiens qui nous prot\u00e8gent contre les terribles desseins et armements [RT.com compris] de Poutine et de la Russie ne seront pas les derniers \u00e0 relever que la couleur de base de <em>Gab.com <\/em>est d&rsquo;un vert qui se rapproche de celui de RT.com. Je vous laisse \u00e0 penser combien cela laisse \u00e0 penser.)<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>La &lsquo;Purge&rsquo;<\/em> [des GAFAM] <em>a donn\u00e9 une impulsion inattendue \u00e0 Gab, une autre plateforme de type Twitter dont l&rsquo;argument de vente est son engagement d\u00e9clar\u00e9 en faveur de la libert\u00e9 d&rsquo;expression. Gab existe depuis 2016, mais son existence a \u00e9t\u00e9 contrari\u00e9e au d\u00e9part par la controverse en raison de la prolif\u00e9ration de contenus racistes sur sa plateforme et du refus de son CEO Andrew Torba de \u00ab\u00a0contr\u00f4ler ce qui est un discours de haine et ce qui ne l&rsquo;est pas\u00a0\u00bb.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Les utilisateurs interdits de m\u00e9dias sociaux classiques ont commenc\u00e9 \u00e0 s&rsquo;inscrire en masse \u00e0 Gab au cours des trois derniers jours. Dans un post samedi, Torba a affirm\u00e9 que plus de 10 000 nouveaux utilisateurs s&rsquo;inscrivaient chaque heure.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Contrairement \u00e0 Parler, Gab fonctionne sur ses propres serveurs, ce qui signifie qu&rsquo;un fournisseur comme Amazon ne peut pas d\u00e9cider de sa circulation ou pas. Apr\u00e8s avoir \u00e9t\u00e9 mis sur la liste noire des processeurs de paiement et des fournisseurs de messagerie \u00e9lectronique, Gab a construit sa propre infrastructure de paiement et de messagerie interne, ainsi que son propre service de messagerie, son navigateur web et son application vid\u00e9o<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>Cependant, l&rsquo;arriv\u00e9e soudaine de nouveaux trafics a ralenti Gab. Torba a \u00e9crit mercredi que de nouveaux serveurs seront ajout\u00e9s, et qu&rsquo;il a d\u00e9j\u00e0 invit\u00e9 Trump \u00e0 s&rsquo;installer sur Gab<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>&bull; Parall\u00e8lement \u00e0 ces \u00e9v\u00e9nements majeurs, le climat au Congr\u00e8s est du plus terrible chaos du meilleur jus r\u00e9volutionnaire, rappelant \u00e0 certains voyants capables de voyager dans le temps les pires jours de la Convention, lorsque l&rsquo;ombre de la guillotine rythmait les interventions des orateurs cherchant \u00e0 se d\u00e9douaner. Qui est le Maximilien de cette basse-cour de terreur ? Est-ce l&rsquo;hyst\u00e9rique Pelosi qui veut destituer Trump m\u00eame apr\u00e8s son mandat, pour qu&rsquo;\u00e0 jamais il disparaisse du monde des vivants ? Est-ce le ricanant et impitoyable Schumer, qui voit des Pearl Harbor partout et trouve que Trump a les yeux brid\u00e9s \u00e0-la-Yamamoto ?<\/p>\n<\/p>\n<p><p>Revenant \u00e0 son micro apr\u00e8s une phase de traitement d&rsquo;un cancer en phase terminale, le c\u00e9l\u00e8bre commentateur-radio Rush Limbaugh (classifi\u00e9 fasciste de premi\u00e8re cat\u00e9gorie selon les consignes) a comment\u00e9 les \u00e9v\u00e9nements en s&rsquo;attachant au constat qu&rsquo;un tr\u00e8s grand nombre d&rsquo;alli\u00e9s de Trump l&rsquo;abandonnent apr\u00e8s l&rsquo;affreuse agression du Capitole, \u00e9quivalant, r\u00e9p\u00e9tons-le aussi souvent qu&rsquo;il faudra, \u00e0 un Pearl Harbor venue de l&rsquo;int\u00e9rieur :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p><a href=\"https:\/\/www.wnd.com\/2021\/01\/rush-limbaugh-explains-trump-backers-government-abandoning-ship\/\">Limbaugh<\/a> &laquo; <em>a fait remarquer que l&rsquo;ancien procureur g\u00e9n\u00e9ral William Barr a d\u00e9clar\u00e9 que Trump avait trahi la pr\u00e9sidence en incitant la foule \u00e0 l&rsquo;attaque, et que son alli\u00e9 d&rsquo;autrefois, le s\u00e9nateur Lindsey Graham, d\u00e9clarait que l&rsquo;h\u00e9ritage du pr\u00e9sident avait \u00e9t\u00e9 \u00ab\u00a0terni\u00a0\u00bb, et disant \u00e0 ses coll\u00e8gues du S\u00e9nat : \u00ab\u00a0Qu&rsquo;on ne compte plus sur moi<\/em> [pour d\u00e9fendre Trump]. <em>Trop c&rsquo;est trop&#8230;\u00a0\u00bb<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0Si vous voulez vivre dans la classe politique \u00e9lue \u00e0 Washington\u00a0\u00bb, a dit Limbaugh, \u00ab\u00a0vous devez dire<\/em> [que Trump a trahi la pr\u00e9sidence]<em>, vous devez le dire. Il n&rsquo;y a pas d&rsquo;alternative<\/em>\u00ab\u00a0. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>&bull; Le professeur <a href=\"https:\/\/jonathanturley.org\/2021\/01\/09\/say-it-aint-so-joe-the-failure-of-biden-to-denounce-this-impeachment-is-a-missed-presidential-opportunity\/#more-167804\">Turley proteste<\/a> d&rsquo;un point de vue tr\u00e8s constitutionnaliste, contre l&rsquo;attitude fort peu pr\u00e9sidentielle de Biden vis-\u00e0-vis de la mise en accusation-express de Trump. Interrog\u00e9 sur cette question, notre-POTUS du 20 janvier prochain a r\u00e9pondu ceci, qui trace bien l&rsquo;esprit de sa politique, ressemblant \u00e0 s&rsquo;y m\u00e9prendre \u00e0 Ponce-Pilote selon la doctrine \u00ab\u00a0Certes, &lsquo;Avec moi le d\u00e9luge&rsquo;, mais l\u00e0, pour le moment, il y a d&rsquo;autres choses bien plus importantes\u00a0\u00bb :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>\u00ab\u00a0Je me concentre sur le virus, le vaccin et la croissance \u00e9conomique. Ce que le Congr\u00e8s d\u00e9cide de faire, c&rsquo;est \u00e0 lui d&rsquo;en d\u00e9cider\u00a0\u00bb, a r\u00e9pondu M. Biden lorsqu&rsquo;on lui a demand\u00e9 s&rsquo;il soutenait de telles mesures&#8230; \u00ab\u00a0Nous allons faire notre travail et le Congr\u00e8s peut d\u00e9cider de la mani\u00e8re de proc\u00e9der avec le leur. C&rsquo;est au Congr\u00e8s de prendre cette d\u00e9cision. Je suis concentr\u00e9 sur mon travail\u00a0\u00bb<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Du coup (de quel &lsquo;coup&rsquo; d&rsquo;ailleurs, et porteur d&rsquo;un entonnoir n&rsquo;est-ce pas ?), Pelosi, qui aimerait une fois d\u00e9barrass\u00e9e de Trump placer les codes nucl\u00e9aires en sautoir et sur la petite cha&icirc;ne de sa petite croix de bonne catholique pratiquante, a envoy\u00e9 un ultimatum \u00e0 Pence pour que lui, en tant que vice-pr\u00e9sident, demande l&rsquo;application du 25\u00e8mr amendement ordonnant la destitution du pr\u00e9sident pour incomp\u00e9tence, ou bien incapacit\u00e9 mentale, etc. Tout cela doit \u00eatre fait pour hier matin. Pence a refus\u00e9. Nouvel ultimatum de Pelosi : Pence doit s&rsquo;ex\u00e9cuter dans les 24 heures sinon c&rsquo;est elle, Pelosi, qui s&rsquo;y mettra. On lui souhaite bonne vent.<\/p>\n<\/p>\n<p><p>&bull; D&rsquo;une fa\u00e7on g\u00e9n\u00e9rale, le chaos est total au Congr\u00e8s et autour du Congr\u00e8s, du point de vue de la communication <a href=\"https:\/\/redstate.com\/darth641\/2021\/01\/11\/opinion-enough-there-was-no-riot-insurrection-or-storming-n307795\">rendant compte<\/a> de la description de l\u00a0\u00bbattaque&rsquo; du Capitole.<\/p>\n<\/p>\n<p><p>Jeudi, les progressistes d\u00e9non\u00e7aient la Police du Congr\u00e8s qui avait laiss\u00e9 entrer les tueurs de Trump, les deux faisant infamie commune comme c&rsquo;est le cas entre tous les fascistes. Aujourd&rsquo;hui, on d\u00e9couvre que non, pas du tout ! Les policiers du Congr\u00e8s ont m\u00eame <a href=\"https:\/\/www.wnd.com\/2021\/01\/video-trapped-capitol-police-officer-wrecks-medias-let-narrative\/\">\u00e9t\u00e9 h\u00e9ro\u00efques<\/a>, ils ont \u00e9vit\u00e9 un carnage, des pendaisons, <a href=\"https:\/\/www.rt.com\/usa\/512092-capitol-police-shooting-lawmakers-lynching\/\">un g\u00e9nocide \u00e9videmment raciste<\/a> au Congr\u00e8s, dont devaient \u00eatre victimes (du KKK, des supr\u00e9macistes, des Gilets-blanchis\u00e9s), tous les extr\u00e9mistes arc-en-ciel du parti des <em>serial-<\/em>victimes, AOC (Alexandria Ocasio-Cortez) en t\u00eate. <em>Politico <\/em>vous explique dans une incroyable cascade sans fin de t\u00e9moignages du meilleur cr\u00e9dit possible, combien cela <a href=\"https:\/\/www.politico.com\/news\/magazine\/2021\/01\/07\/capitol-storming-siege-congress-inside-first-person-oral-history-455715\">aurait pu \u00eatre le carnage<\/a> au Congr\u00e8s, l&rsquo;Alamo revu par Verdun \u00e0 l&rsquo;ombre de l&rsquo;Holocauste, &ndash; pas moins. A la vision des divers documents r\u00e9f\u00e9renc\u00e9s ici et l\u00e0, vous comprendrez l&rsquo;humeur o&ugrave; je suis de croire que la folie de &lsquo;D.C.-la-folle&rsquo; d\u00e9passe tout ce qu&rsquo;on pouvait envisager d&rsquo;oser imaginer&#8230;<\/p>\n<\/p>\n<p><p>&bull; Dans cette revue d&rsquo;un extr\u00eame brouhaha, de &lsquo;D.C.-la folle&rsquo; compl\u00e8tement en folie sous le regard du <em>Rest Of the World <\/em>qui attendait un retour \u00e0 la normale du bon vieux temps avec <em>Ol&rsquo;White Joe<\/em>, que peut-on retenir qui marquerait une certaine stabilit\u00e9 du jugement, disons un fait affirm\u00e9 avec des cons\u00e9quences pr\u00e9visibles possibles ? Ma qu\u00eate, effectivement, est celle de la stabilit\u00e9 d&rsquo;une information, d&rsquo;une consid\u00e9ration, d&rsquo;un commentaire, quelque chose qui puisse sortir le lecteur-spectateur hors de cette impression chaotique extr\u00eamement \u00e9trange et qui secoue impitoyablement le <em>Titanic<\/em>.<\/p>\n<\/p>\n<p><p>(Je dirais m\u00eame qu&rsquo;il aurait bien de la peine, le lecteur-spectateur dans ce chaos total, \u00e0 transformer la &lsquo;Guerre Civile 2.0&rsquo; en vraie guerre civile, \u00e0 l&rsquo;image de la premi\u00e8re du nom, connue comme \u00ab\u00a0la Guerre de S\u00e9cession\u00a0\u00bb. Pourtant, le fait m\u00eame de la s\u00e9cession est une bonne piste que je recommande de suivre ; notamment elle exsude comme enseignement indirect mais solide des constats de haute tenue que <a href=\"https:\/\/www.dedefensa.org\/article\/il-etait-une-foi-en-lamerique\">nous livre aujourd&rsquo;hui<\/a> le professeur Turley.)<\/p>\n<\/p>\n<p><p>Ce fait qui pourrait marquer \u00ab\u00a0une certaine stabilit\u00e9 du jugement, disons un fait affirm\u00e9 avec des cons\u00e9quences pr\u00e9visibles possibles\u00a0\u00bb, c&rsquo;est l&rsquo;acte fondamental des GAFAM. Les petits-polissons aux \u00e9normes $milliards viennent tout simplement de jeter le masque pour appara&icirc;tre pour ce qu&rsquo;ils sont : des petits-&lsquo;ma&icirc;tres-censeurs&rsquo; au service d&rsquo;une dynamique de d\u00e9construction et de n\u00e9antisation. Ce qu&rsquo;ils ont fait en faisant cela, c&rsquo;est ce qu&rsquo;on nomme \u00ab\u00a0crever l&rsquo;abc\u00e8s\u00a0\u00bb. Tout le monde vivait jusqu&rsquo;ici dans le faux-semblant de l&rsquo;illusion d&rsquo;un syst\u00e8me de r\u00e9seaux sociaux rest\u00e9 fid\u00e8le \u00e0 ses origines, fonctionnant normalement et de fa\u00e7on uniquement commerciale, et selon les r\u00e8gles du droit et de la recherche de la plus grande impartialit\u00e9 politique.<\/p>\n<\/p>\n<p><p>Oserais-je avancer qu&rsquo;il s&rsquo;agit d&rsquo;une faute strat\u00e9gique majeure, cette sortie des GAFAM, id\u00e9e-id\u00e9ologis\u00e9e sortie de cerveaux gav\u00e9s de $milliards et d&rsquo;une m\u00e9diocrit\u00e9 \u00e0 mesure, sans compr\u00e9hension de la nature humaine, de sa psychologie ? Abandonnant leur statut incertain mais exceptionnel de neutralit\u00e9 politique, &ndash; comme les Suisses, tiens, &ndash; ils s&rsquo;affichent pour ce qu&rsquo;ils sont, nouveaux-riches, morveux insupportables, aussi s&ucirc;rs d&rsquo;eux qu&rsquo;ils sont incultes. Ils s&rsquo;exposent \u00e0 la mitraille, eux qui n&rsquo;ont jamais entendu p\u00e9ter un bouchon de champagne&#8230;<\/p>\n<\/p>\n<p><p>Ce fait majeur entra&icirc;ne d\u00e9sormais des r\u00e9actions sans doute d&rsquo;une grande importance : le surgissement d&rsquo;alternatives n\u00e9cessairement antiSyst\u00e8me. Ce ph\u00e9nom\u00e8ne ne concerne pas les seuls USA, d&rsquo;ailleurs comme on l&rsquo;a vu par l&rsquo;entame de cette page qui a \u00e9t\u00e9 confi\u00e9e au pr\u00e9sident mexicain AMLO. Il s&rsquo;agit d&rsquo;un ph\u00e9nom\u00e8ne mondial (&lsquo;global&rsquo; si l&rsquo;on veut), mettant en \u00e9vidence pour la premi\u00e8re fois d&rsquo;une fa\u00e7on si massive les effets potentiellement consid\u00e9rables de cette &lsquo;Guerre Civile 2.0&rsquo; aux USA, et plus g\u00e9n\u00e9ralement de toutes les querelles internes actuelles aux USA.<\/p>\n<\/p>\n<p><p>Selon l&rsquo;\u00e9vidente formule que seul le Syst\u00e8me peut avoir raison du Syst\u00e8me dans sa dynamique d&rsquo;autodestruction, seule la puissance US peut avoir raison de la puissance US, par le biais de ses mortelles querelles int\u00e9rieures. D&rsquo;autre part, je serais inclin\u00e9 \u00e0 voir dans tout cela la d\u00e9monstration <em>in vivo <\/em>de ce terrible prolongement qu&rsquo;a identifi\u00e9 Turley, de <a href=\"https:\/\/www.dedefensa.org\/article\/il-etait-une-foi-en-lamerique\">la perte de la foi en l&rsquo;Am\u00e9rique<\/a> qui s&rsquo;est install\u00e9e chez les citoyens am\u00e9ricains. Je pense que ce ph\u00e9nom\u00e8ne est d&rsquo;une profondeur extr\u00eame, et qu&rsquo;il explique cette d\u00e9cid\u00e9ment \u00e9trange &lsquo;Guerre Civile 2.0&rsquo;, dont les cons\u00e9quences aboutissent toutes \u00e0 un affaiblissement du statut et de la perception des USA dans le <em>Rest Of the World<\/em>, si tant est que l&rsquo;on puisse parler encore s\u00e9rieusement, sur cette grande mar\u00e9e rugissante de d\u00e9sordre, de statut et de perception.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Leur 1789-d\u00e9lire : les GAFAM sortent du bois 11 janvier 2021 &ndash; Chaque fois que je commence une chronique, ces temps-ci encore plus que les Temps d&rsquo;Avant, parce que les Temps Derniers sont plus foisonnants et plus occup\u00e9s, &ndash; chaque fois je me demande : \u00ab\u00a0Quel sujet choisir ?\u00a0\u00bb, puis, ayant choisi, je m&rsquo;interroge \u00e0&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[5717,2870,1235,10874,3285,2651,20594,2943,4604,7503,6140,2948],"class_list":["post-79605","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-amlo","tag-attaque","tag-biden","tag-capitole","tag-congres","tag-du","tag-gab-com","tag-mexique","tag-obrador","tag-parler","tag-pelosi","tag-turley"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79605","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79605"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79605\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79605"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79605"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}