{"id":79625,"date":"2021-01-26T09:43:00","date_gmt":"2021-01-26T09:43:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2021\/01\/26\/rapsit-usa2021-le-president-de-limpuissance\/"},"modified":"2021-01-26T09:43:00","modified_gmt":"2021-01-26T09:43:00","slug":"rapsit-usa2021-le-president-de-limpuissance","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2021\/01\/26\/rapsit-usa2021-le-president-de-limpuissance\/","title":{"rendered":"RapSit-USA2021\u00a0: Le pr\u00e9sident de l&rsquo;impuissance"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">RapSit-USA2021 : Le pr\u00e9sident de l&rsquo;impuissance<\/h2>\n<\/p>\n<p><p>En quelques rapides interventions et commentaires, autour de la mise en place des derni\u00e8res dispositions pour l&rsquo;absurde et partisan proc\u00e8s en destitution d&rsquo;un pr\u00e9sident qui n&rsquo;est plus en fonction, c&rsquo;est l&rsquo;impuissance et l&#8217;emprisonnement du pr\u00e9sident en fonction qui appara&icirc;t.<\/p>\n<\/p>\n<p><p>Cette impuissance et cet emprisonnement de Biden sont porteurs d&rsquo;une aggravation dramatique de la division antagoniste qu&rsquo;on constate aujourd&rsquo;hui, au Congr\u00e8s et dans la population des USA. Elles marquent surtout qu&rsquo;en plus d&rsquo;\u00eatre un &lsquo;pr\u00e9sident impuissant&rsquo;, Biden est &lsquo;le pr\u00e9sident de l&rsquo;impuissance&rsquo; o&ugrave; se trouve encalmin\u00e9 le pouvoir politique \u00e0 Washington D.C.<\/p>\n<\/p>\n<p><p>Le proc\u00e8s va s&rsquo;engager, sans doute dans la seconde semaine de f\u00e9vrier, avec un S\u00e9nat plong\u00e9 dans des convulsions terribles. La grande question de la pr\u00e9sidence du S\u00e9nat transform\u00e9 en tribunal a \u00e9t\u00e9 r\u00e9solue de la pire des fa\u00e7ons. C&rsquo;est normalement le pr\u00e9sident de la Cour Supr\u00eame (SCOTUS) qui pr\u00e9side une telle proc\u00e9dure. Mais le Juge Roberts a finalement d\u00e9cid\u00e9 de ne pas tenir ce r\u00f4le, officiellement pour des raisons formelles concernant l&rsquo;aspect fort peu constitutionnel du processus (l&rsquo;accus\u00e9 n&rsquo;\u00e9tant plus dans la position qui est mise en question), mais en r\u00e9alit\u00e9 pour ne pas \u00eatre pris dans une pol\u00e9mique partisane. On a d\u00e9j\u00e0 vu, lors de la plainte du Texas concernant l&rsquo;\u00e9lection, en d\u00e9cembre 2020, que Roberts ne brille ni par son courage, ni par la fermet\u00e9 de sa logique constitutionnelle. Il est \u00e9vident qu&rsquo;il a pu constater l&rsquo;opposition de la rumeur d\u00e9mocrate \u00e0 sa nomination, sous l&rsquo;accusation que sa position d&rsquo;\u00e9quit\u00e9 \u00e9tait en fait un parti-pris pro-Trump. Cela doit \u00eatre compris dans le sens de l&rsquo;habituelle inversion de la logique wokenisrte : l\u00a0\u00bb\u00e9quit\u00e9&rsquo; selon les canons de la gauche radicale du parti d\u00e9mocrate consiste \u00e0 juger Trump coupable de tout, d&rsquo;avance, et sans appel. C&rsquo;est bien assez pour d\u00e9courager un Roberts, qui n&rsquo;a d\u00e9cid\u00e9ment rien d&rsquo;un Maximilien&#8230;<\/p>\n<\/p>\n<p><p>Le juge sera donc le s\u00e9nateur Leahy, ont d\u00e9cid\u00e9 les d\u00e9mocrates. Selon de tr\u00e8s nombreux avis, il n&rsquo;y avait pas pire choix, Leahy \u00e9tant le s\u00e9nateur d\u00e9mocrate le plus froidement d\u00e9termin\u00e9 des antiTrump qu&rsquo;on puisse trouver. D&rsquo;o&ugrave; la cons\u00e9quence que les r\u00e9publicains se retrancheront dans une opposition maximale \u00e0 la proc\u00e9dure et \u00e0 toute condamnation. (Il faut une majorit\u00e9 des deux tiers pour un jugement de culpabilit\u00e9 du S\u00e9nat, donc les d\u00e9mocrates ont besoin du soutien de 17 s\u00e9nateurs r\u00e9publicains.)<\/p>\n<\/p>\n<p><p>Quelques mots de commentaires <a href=\"https:\/\/www.rt.com\/usa\/513599-impeachment-democratic-senator-preside\">de RT.com<\/a>, recueillis avant que Roberts annonce sa d\u00e9cision de s&rsquo;abstenir et que Leahy soit nomm\u00e9 :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Les conservateurs ont d\u00e9j\u00e0 cri\u00e9 au scandale, arguant que Leahy n&rsquo;est pas apte \u00e0 jouer ce r\u00f4le en raison de son \u00e9vident (pour eux) parti pris antiTrump. L&rsquo;ancien conseiller de Trump, Boris Epshteyn, a qualifi\u00e9 le l\u00e9gislateur d\u00e9mocrate de \u00ab\u00a0partisan froid comme du marbre\u00a0\u00bb, en faisant valoir que \u00ab\u00a0tout semblant d&rsquo;\u00e9quit\u00e9 ou de proc\u00e9dure r\u00e9guli\u00e8re\u00a0\u00bb lors du proc\u00e8s imminent est vou\u00e9 \u00e0 \u00eatre \u00ab\u00a0jet\u00e9 par la fen\u00eatre\u00a0\u00bb si Leahy est en charge.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Leahy a \u00e9galement fait l&rsquo;objet de critiques de la part de commentateurs antiTrump. \u00ab\u00a0Ce sera un cauchemar pour cette nation lorsque les r\u00e9publicains s&rsquo;opposeront, et ils le feront\u00a0\u00bb, a d\u00e9clar\u00e9 une source qui se d\u00e9crit elle-m\u00eame comme oppos\u00e9e au &lsquo;trumpisme&rsquo;. \u00ab\u00a0C&rsquo;est de nous qu&rsquo;il s&rsquo;agit <\/em>[de notre coh\u00e9sion, de notre logique]<em>, pas des pro-Trump\u00a0\u00bb.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em> \u00ab\u00a0Je pense que vous \u00eates g\u00e9niaux <\/em>[de vouloir condamner Trump]<em>et je comprends la logique ici, mais les r\u00e9publicains cherchent, eux, un moyen de sortir de la logique radicale du proc\u00e8s <\/em>[sans para&icirc;tre trop trahir Trump]<em>. Pour cette raison, il faut laisser le Pr\u00e9sident de la Cour supr\u00eame pr\u00e9sider\u00a0\u00bb, a d\u00e9clar\u00e9 une autre source &raquo;<\/em>, &ndash; trop tard&#8230;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Il y a donc une logique radicalisant, extr\u00e9miste, catastrophique pour la situation politique, qui poursuit une route irr\u00e9sistible au Congr\u00e8s. Et qu&rsquo;en dit le pr\u00e9sident Biden ? s&rsquo;\u00e9tonnent divers commentateurs, des opposants \u00e0 Biden mais aussi des partisans mod\u00e9r\u00e9s. Biden s&rsquo;est tenu compl\u00e8tement sur la r\u00e9serve dans cette affaire, estimant platement, avant m\u00eame de pr\u00eater serment, que \u00ab\u00a0c&rsquo;\u00e9tait l&rsquo;affaire du Congr\u00e8s\u00a0\u00bb, c&rsquo;est-\u00e0-dire s&rsquo;en lavant les mains \u00e0 la mani\u00e8re d&rsquo;un Ponce-Pilate maximaliste,  qui ne se sentirait pas concern\u00e9 par une affaire int\u00e9rieure conduite par son propre parti, et d&rsquo;une si grande importance politique.<\/p>\n<\/p>\n<p><p>Biden n&rsquo;est sorti de cette r\u00e9serve <a href=\"https:\/\/www.marketwatch.com\/story\/biden-tells-cnn-that-trumps-impeachment-trial-has-to-happen-though-he-doubts-senate-will-convict-11611623955?mod=mixifeed&#038;mod=mixi\">qu&rsquo;hier soir<\/a>, sur CNN, confirmant toutes les craintes qu&rsquo;on pouvait avoir \u00e0 son sujet. Pour Biden, le proc\u00e8s est in\u00e9luctable, et il sera perdu pour les d\u00e9mocrates ; c&rsquo;est-\u00e0-dire que Biden a parfaitement conscience qu&rsquo;il s&rsquo;agit d&rsquo;un \u00e9norme ferment de division qui ne satisfera personne, m\u00eame pas l&rsquo;aile extr\u00e9miste des d\u00e9mocrates&#8230; Mais voil\u00e0, on n&rsquo;y peut rien et il n&rsquo;y peut rien, et si les forces politiques ont profond\u00e9ment chang\u00e9 les proc\u00e9dures et les habitudes du S\u00e9nat ne permettent pas de les prendre en compte : nous aurons donc une machinerie d&#8217;emprisonnement entre l&rsquo;exasp\u00e9ration de la radicalisation que l&rsquo;on ne peut affronter ni d\u00e9cevoir (selon Biden, montrant ainsi toute son impuissance), et la pesanteur de la machinerie institutionnelle&#8230; <\/p>\n<\/p>\n<p><p>Ainsi, nous dit Biden en clair, \u00ab\u00a0ce qui se pr\u00e9pare est une catastrophe mais je n&rsquo;y peux rien, parce que s&rsquo;y opposer serait pour moi, pr\u00e9sident impuissant, une catastrophe pire encore&#8230;\u00a0\u00bb. <\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Le pr\u00e9sident Joe Biden ne pense pas que le S\u00e9nat condamnera Donald Trump, mais il estime que la proc\u00e9dure de destitution doit encore avoir lieu.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Parlant <a href=\"https:\/\/www.cnn.com\/2021\/01\/25\/politics\/joe-biden-trump-impeachment\/index.html\">lundi \u00e0 CNN<\/a>, Biden a d\u00e9clar\u00e9 que le proc\u00e8s de destitution \u00ab\u00a0doit avoir lieu\u00a0\u00bb, et qu&rsquo;il y aurait un \u00ab\u00a0effet pire encore s&rsquo;il n&rsquo;avait pas lieu\u00a0\u00bb.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Au moins 17 s\u00e9nateurs r\u00e9publicains devraient rejoindre les d\u00e9mocrates pour que Trump soit reconnu coupable. Biden a d\u00e9clar\u00e9 \u00e0 CNN que l&rsquo;issue aurait pu \u00eatre diff\u00e9rente s&rsquo;il restait six mois de mandat de pr\u00e9sidence pour Trump, mais maintenant qu&rsquo;il n&rsquo;est plus en fonction, il estime qu&rsquo;il y a peu de chances d&rsquo;obtenir une condamnation.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0Le S\u00e9nat a chang\u00e9 depuis que j&rsquo;y \u00e9tais, mais pas tant que \u00e7a\u00a0\u00bb, a-t-il d\u00e9clar\u00e9 \u00e0 CNN<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Il y a un commentaire tr\u00e8s mod\u00e9r\u00e9 de Newt Gingrich qui r\u00e9sume bien la situation. On doit se dire que lorsque Gingrich, qui fut <em>Speaker<\/em>r\u00e9publicain de la Chambre de 1994 \u00e0 1999 et reste un pol\u00e9miste redout\u00e9, fait un commentaire mod\u00e9r\u00e9 sur un pr\u00e9sident d\u00e9mocrate confront\u00e9 \u00e0 un d\u00e9fi politique tr\u00e8s important, c&rsquo;est que la situation est tr\u00e8s grave pour tous, r\u00e9publicains et d\u00e9mocrate : &laquo; <em>Si le pr\u00e9sident<\/em>[Biden] <em>ne r\u00e9ussit pas, l&rsquo;Am\u00e9rique sera dans une situation tr\u00e8s grave.<\/em> &raquo;<\/p>\n<\/p>\n<p><p>Quelques extraits de son commentaire publi\u00e9 dans le <a href=\"https:\/\/www.washingtontimes.com\/news\/2021\/jan\/25\/bidens-empty-words-belie-his-actions\/?utm_source=Boomtrain&#038;utm_medium=manual&#038;utm_campaign=newsalert&#038;utm_content=newsalert&#038;utm_term=newsalert&#038;bt_ee=WhCcwGUn9cVn%2FjmZLksIRqF0jMRDj8H5QdO%2BCfaTg5L5wDFtZ7ZRm23jSHmB7MO0&#038;bt_ts=1611598101667\">Washington<em>Times <\/em>d&rsquo;hier<\/a> :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>En voyant <\/em><em>l&rsquo;\u00e9lite des m\u00e9dias lib\u00e9raux s&#8217;emparer de l&rsquo;inauguration du pr\u00e9sident Joe Biden<\/em><em>pour la magnifier<\/em><em>, j&rsquo;ai attendu qu&rsquo;au moins quelqu&rsquo;un analyse la diff\u00e9rence fascinante entre le discours inaugural du pr\u00e9sident Biden et ses actes inauguraux. <\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Tout d&rsquo;abord, j&rsquo;ai trouv\u00e9 que le discours \u00e9tait incroyablement<\/em><em>excellent<\/em><em>. Il promettait l&rsquo;unit\u00e9, la solidarit\u00e9 et la recherche d&rsquo;un terrain d&rsquo;entente, &ndash; discours de bipartisme am\u00e9ricain classique et de bonne volont\u00e9 civique. Il a promis de tendre la main \u00e0 tout le monde, de travailler avec tout le monde et d&rsquo;\u00eatre un pr\u00e9sident am\u00e9ricain, plut\u00f4t qu&rsquo;un pr\u00e9sident d\u00e9mocrate et partisan<\/em>.[&#8230;]<\/p>\n<\/p>\n<p><p>&raquo; <em>Quelques heures apr\u00e8s avoir prononc\u00e9 son excellent discours inaugural, le pr\u00e9sident Biden s&rsquo;est rendu \u00e0 la Maison Blanche et a sign\u00e9 17 d\u00e9crets, &ndash; dont plus d&rsquo;une douzaine qui contredisent totalement sa promesse de bipartisme, d&rsquo;unit\u00e9 et de recherche d&rsquo;un terrain d&rsquo;entente<\/em>. [&#8230;]<\/p>\n<\/p>\n<p><p>&raquo; <em>Maintenant, rien de tout cela <\/em>[cette critique de ses premiers actes]<em>ne doit \u00eatre interpr\u00e9t\u00e9 comme un souhait ou un d\u00e9sir que le pr\u00e9sident Biden \u00e9choue dans sa fonction de chef de l&rsquo;ex\u00e9cutif. &Agrave; moins que vous ne soyez irrationnel, chaque Am\u00e9ricain devrait souhaiter que le pr\u00e9sident am\u00e9ricain r\u00e9ussisse. Si le pr\u00e9sident ne r\u00e9ussit pas, l&rsquo;Am\u00e9rique <\/em><em>sera dans une situation tr\u00e8s grave<\/em><em>.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Cela doit \u00eatre consid\u00e9r\u00e9 comme un d\u00e9fi lanc\u00e9 au pr\u00e9sident Biden pour que ses actes correspondent \u00e0 ses paroles. <\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Jusqu&rsquo;\u00e0 pr\u00e9sent, je l<\/em><em>&lsquo;entends<\/em><em>parler d&rsquo;unit\u00e9 et appeler \u00e0 ce que nous travaillions tous ensemble, mais je suis curieux de savoir \u00e0 qui il pense lorsqu&rsquo;il parle de ce <\/em><em>\u00ab\u00a0n<\/em><em>ous<\/em><em>\u00ab\u00a0<\/em>.  &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>&laquo; <em>Do the Democrats Really Want Unity? <\/em>&raquo;, interroge <a href=\"https:\/\/jonathanturley.org\/2021\/01\/25\/do-the-democrats-really-want-unity\/\">Jonathan Turley<\/a>&hellip; Poser la question, c&rsquo;est \u00e9videmment y r\u00e9pondre. Peut-\u00eatre que le pauvre Biden y pense parfois, mais tout juste en r\u00eave. Le commentaire &lsquo;mod\u00e9r\u00e9&rsquo; de Gingrich refl\u00e8te paradoxalement la gravit\u00e9 de la situation bloqu\u00e9e par des \u00e9tats d&rsquo;esprits catastrophistes. Les d\u00e9clarations de Biden \u00e0 CNN sont effectivement stup\u00e9fiantes : \u00ab\u00a0certes, c&rsquo;est une catastrophe (la destitution), mais ce serait une catastrophe plus grande encore que d&rsquo;\u00e9viter cette catastrophe\u00a0\u00bb. Quand on en arrive \u00e0 de telles logiques sophistiques appliqu\u00e9es \u00e0 la politique op\u00e9rationnelle, on comprend que le cr\u00e9puscule n&rsquo;est plus tr\u00e8s loin. L&rsquo;immense soupir de soulagement du &lsquo;monde civilis\u00e9&rsquo; avec la prise de fonction de Biden mesure la cr\u00e9tinerie pathologique de ce &lsquo;monde civilis\u00e9&rsquo; ivre de ses propres simulacres : la <em>Soci\u00e9t\u00e9 du Spectacle <\/em>fonctionne d&rsquo;abord pour ceux qui montent le spectacle.<\/p>\n<\/p>\n<p><p>Lorsqu&rsquo;un Jean-Luc Hees, pr\u00e9sent\u00e9 comme un parangon du journalisme de r\u00e9flexion sur les Etats-Unis, nous dit, comme il le fit le 20 janvier sur LCI, que &laquo; <em>la d\u00e9cision de destitution est une erreur politique mais c&rsquo;est une obligation morale et il y a des occasions o&ugrave; la morale doit primer sur la politique <\/em>&raquo;, il confirme le diagnostic de cr\u00e9tinerie pathologique o&ugrave; ces pauvres \u00eatres sont enferm\u00e9s, avec en suppl\u00e9ment-cadeau l&rsquo;id\u00e9e qu&rsquo;il y a souvent des occasions rat\u00e9es de se taire, ou de s&rsquo;abstenir d&rsquo;aller au &lsquo;Spectacle&rsquo; offert par la &lsquo;Soci\u00e9t\u00e9&rsquo;, &ndash; la Covid et le confinement obligent. <\/p>\n<\/p>\n<p><p>Quels que soient ses d\u00e9fauts et ses corruptions qu&rsquo;on sait innombrables, il y a d&rsquo;abord ce fait que Biden est prisonnier d&rsquo;un \u00e9tat d&rsquo;esprit, d&rsquo;un irr\u00e9sistible enfermement dans une machinerie hors de tout contr\u00f4le, accompagn\u00e9e par les jappements des pions de service, &ndash; Pelosi et Schumer en l&rsquo;occurrence. Le Congr\u00e8s emprisonne le pr\u00e9sident, l&rsquo;\u00e9tat d&rsquo;esprit de la radicalit\u00e9 emprisonne le Congr\u00e8s, Gingrich joue en vain au mod\u00e9r\u00e9, &ndash; en croyant-Syst\u00e8me si vous voulez, &ndash;  tandis que le Syst\u00e8me emporte tout cela dans sa course effr\u00e9n\u00e9e \u00e0 l&rsquo;autodestruction. Le chaos est au rendez-vous d&rsquo;une Am\u00e9rique prisonni\u00e8re de ses vertus politiques (&laquo; <em>Si vous parvenez \u00e0 d\u00e9truire l&rsquo;esclavage dans le Midi, il y aura au moins dans le monde un gouvernement aussi parfait que la raison humaine peut le concevoir<\/em> &raquo;, disait Germaine [de Sta\u00ebl] \u00e0 Jefferson en 1816) ; les vertus du \u00ab\u00a0gouvernement parfait\u00a0\u00bb o&ugrave; les forces s&rsquo;\u00e9quilibrent (&lsquo;<em>Check &#038; Balance<\/em>&lsquo;) deviennent les venins de la paralysie r\u00e9ciproque engendr\u00e9e par la d\u00e9mence de l&rsquo;id\u00e9ologie, offrant au terme chaos et terreur plut\u00f4t qu&rsquo;\u00e9quilibre cr\u00e9ateur entretenue par la corruption. Comme les USA n&rsquo;ont rien de commun avec une France prisonni\u00e8re des emportements parisiens (voyez 1793), la s\u00e9cession comme une r\u00e9pulsion de sauvegarde sera au rendez-vous. Les gouverneurs <a href=\"https:\/\/www.dedefensa.org\/article\/rapsit-usa2021-la-grande-dissolution\">l&rsquo;ont d\u00e9j\u00e0 signal\u00e9<\/a>en expliquant sans am\u00e9nit\u00e9 qu&rsquo;ils &laquo; <em>ne sont pas les domestiques de Nancy Pelosi <\/em>&raquo;.<\/p>\n<\/p>\n<p><p>Mis en ligne le 26 janvier 2021 \u00e0 09H45<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>RapSit-USA2021 : Le pr\u00e9sident de l&rsquo;impuissance En quelques rapides interventions et commentaires, autour de la mise en place des derni\u00e8res dispositions pour l&rsquo;absurde et partisan proc\u00e8s en destitution d&rsquo;un pr\u00e9sident qui n&rsquo;est plus en fonction, c&rsquo;est l&rsquo;impuissance et l&#8217;emprisonnement du pr\u00e9sident en fonction qui appara&icirc;t. Cette impuissance et cet emprisonnement de Biden sont porteurs d&rsquo;une&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[21],"tags":[1235,6045,3285,2631,4911,4566,9140,20637,15558,2949,12464,2646],"class_list":["post-79625","post","type-post","status-publish","format-standard","hentry","category-breves-de-crise","tag-biden","tag-catastrophe","tag-congres","tag-de","tag-destitution","tag-gingrich","tag-gouverneurs","tag-hees","tag-leahy","tag-secession","tag-stael","tag-wokenisme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79625","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79625"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79625\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79625"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79625"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}