{"id":79657,"date":"2021-02-18T18:28:28","date_gmt":"2021-02-18T18:28:28","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2021\/02\/18\/shakespeare-moliere-en-un-acte-metaphysique\/"},"modified":"2021-02-18T18:28:28","modified_gmt":"2021-02-18T18:28:28","slug":"shakespeare-moliere-en-un-acte-metaphysique","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2021\/02\/18\/shakespeare-moliere-en-un-acte-metaphysique\/","title":{"rendered":"Shakespeare &amp; Moli\u00e8re, en un Acte m\u00e9taphysique"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Shakespeare &#038; Moli\u00e8re, en un Acte m\u00e9taphysique<\/h2>\n<\/p>\n<p><p>18 f\u00e9vrier 2021 &ndash; Je vais tenter de faire un parall\u00e8le analogique entre deux auteurs de deux nations diff\u00e9rentes, mais toutes les deux charg\u00e9es de gloire dans &lsquo;n\u00f4tre&rsquo; Histoire commune, toutes deux ainsi que les deux auteurs constituant des \u00e9v\u00e9nements \u00e0 la fois symboliques, arch\u00e9typiques, m\u00e9taphoriques, mais aussi du domaine du mythe et du <em>logos <\/em>autant que de la m\u00e9taphysique selon une approche que j&rsquo;affectionne de l&rsquo;histoire per\u00e7ue et grandie en de la m\u00e9taphysique de l&rsquo;Histoire.<\/p>\n<\/p>\n<p><p>En \u00e9cartant toute id\u00e9e et suggestion de concurrence, d&rsquo;\u00e9valuations compar\u00e9es, du &lsquo;supr\u00e9macisme&rsquo; (mot bienvenu pour l&rsquo;un et pour l&rsquo;autre) de l&rsquo;un ou de l&rsquo;autre par rapport \u00e0 l&rsquo;un ou l&rsquo;autre, de susceptibilit\u00e9s nationales, etc. Mon jugement est d&rsquo;ordre culturel dans le sens le plus large du verbe avec une tr\u00e8s-forte dimension psychologique et intuitive, jusqu&rsquo;\u00e0 une approche logocratique, \u00e0 la fois dans le sens civilisationnel et, \u00e0 nouveau, m\u00e9taphysique de l&rsquo;Histoire ; et sans nul parti-pris de ma part entre les deux, bien entendu.<\/p>\n<\/p>\n<p><p>&#8230; Car c&rsquo;est une occasion r\u00eav\u00e9e, et peut-\u00eatre, et m\u00eame sans aucun doute, que ces deux-l\u00e0, ces deux grandes gloires de la culture et des arts, et de la pens\u00e9e, se signalent dans un m\u00eame moment, dans des circonstances compl\u00e8tement li\u00e9es \u00e0 l&rsquo;actualit\u00e9 la plus br&ucirc;lante, la plus pressante ; dans des conditions dont tout \u00eatre digne de lui-m\u00eame devrait avoir honte au nom de lui-m\u00eame et des autres si les autres se taisent&#8230; Dans un temps marqu\u00e9 par une d\u00e9mence au-del\u00e0 de toute mesure ; par un d\u00e9sir effr\u00e9n\u00e9 de tuer tout ce qu&rsquo;il y a dans le pass\u00e9 qui pourrait servir d&rsquo;enseignement et d&rsquo;exemple pour ce qui suit, et particuli\u00e8rement pour notre temps ; par une cr\u00e9tinerie, une sottise, un \u00e9bahissement complet de la pens\u00e9e&#8230; Enfin, vous voyez, n&rsquo;est-ce pas, de quoi, de qui je veux parler&#8230;<\/p>\n<\/p>\n<blockquote>\n<p><p>Alors, je vais essayer de d\u00e9finir ce qui les rapproche jusqu&rsquo;\u00e0 en faire des fr\u00e8res quasiment jumeaux d&rsquo;une civilisation qui <strong>aurait pu \u00eatre (et qui ne le fut pas) <\/strong>un acte m\u00e9taphysique d\u00e9cisif pour cette portion du cycle historique, le moment o&ugrave; cette portion du cycle d\u00e9j\u00e0 brutalement \u00e9branl\u00e9e, semble se donner quelques derni\u00e8res chances, dont celle-ci, de se sauvegarder et de se hausser m\u00e9taphysiquement et spirituellement avant la Chute&#8230; Au contraire comme l&rsquo;on sait, l&rsquo;on bascula dans la Chute grim\u00e9e en modernit\u00e9 savante eyt en progr\u00e8s aguicheur.<\/p>\n<\/p>\n<p><p>Bref, je ne les oppose en aucune fa\u00e7on, je ne les compare pas, je ne les classe pas ; j&rsquo;appr\u00e9cie le m\u00eame symbole et le m\u00eame mythe qu&rsquo;ils repr\u00e9sentent ; je les prends, les deux en un.. Et voici ce qu&rsquo;il fait qu&rsquo;ils sont \u00ab\u00a0les deux en un\u00a0\u00bb.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>&bull; Shakespeare et Moli\u00e8re repr\u00e9sentent symboliquement (m\u00eame si l&rsquo;on en discute sans fin par ailleurs) ce qu&rsquo;il y a de plus haut dans la langue de deux des plus grandes nations d&rsquo;Europe, v\u00e9hiculant les deux langues les plus importantes \u00e0 diff\u00e9rentes \u00e9poques et occurrences, et repr\u00e9sentant chacune un g\u00e9nie renvoyant \u00e0 la civilisation dont chacune d&rsquo;elle est l&rsquo;\u00e9manation. Ne dit-on pas d&rsquo;une fa\u00e7on imag\u00e9e, pour l&rsquo;anglais et le fran\u00e7ais, &laquo; <em>dans la langue de Shakespeare<\/em> &raquo; et &laquo; <em>dans la langue de Moli\u00e8re<\/em> &raquo;. (Je parle l\u00e0 <a href=\"https:\/\/www.dedefensa.org\/article\/ma-verite-de-situation\">en logocrate<\/a>, pour lequel le langage a cette importance originelle, et gardant dans tous les temps cette op\u00e9rationnalit\u00e9. Je le suis absolument, logocrate. Je tiens que l&rsquo;on peut \u00eatre fascin\u00e9s, emport\u00e9s, inspir\u00e9s, en \u00e9coutant du Shakespeare ou du Moli\u00e8re, sans rien entendre de l&rsquo;anglais ni du fran\u00e7ais, par la simple beaut\u00e9 du verbe, la profondeur devin\u00e9e des mots, le rythme et la musique que v\u00e9hiculent ces mots. [*])<\/p>\n<\/p>\n<p><p>&bull; Tous les deux, ils ont une personnalit\u00e9 myst\u00e9rieuse et intrigante, \u00e9ventuellement multiple ou pr\u00eate-noms dissimul\u00e9s, ce qui nous dispense de renvoyer \u00e0 l&rsquo;individualisme stupide et trompeur du g\u00e9nie personnel dont on nous accable tant pour les grands auteurs, pour au contraire nourrir l&rsquo;id\u00e9e infiniment plus f\u00e9conde d&rsquo;un g\u00e9nie collectif. Ils s&rsquo;agit donc de Shakespeare et de Moli\u00e8re, mais qui sont pr\u00e9cis\u00e9ment Shakespeare et Moli\u00e8re ? On sait que le myst\u00e8re et la pol\u00e9mique entourent la personnalit\u00e9 de l&rsquo;Anglais Shakespeare ; je signale <a href=\"https:\/\/www.letemps.ch\/culture\/shakespeare-estil-lauteur-pieces-lenquete-continue\">ce texte<\/a> pour l&rsquo;illustration, il y en a tant d&rsquo;autres, &ndash; et tant de noms cit\u00e9s derri\u00e8re Shakespeare, &ndash; Francis Bacon, Christopher Marlowe, John Florio, etc., qui pourraient \u00eatre la v\u00e9ritable plume de Shakespeare. Quant \u00e0 Moli\u00e8re, m\u00eame si la pol\u00e9mique est plus simple, elle est n\u00e9anmoins extr\u00eamement document\u00e9e : depuis un article de l&rsquo;\u00e9crivain exotique Pierre Lou&yuml;s en 1921, elle reste tr\u00e8s vivace comme le montre un documentaire tr\u00e8s r\u00e9cent de Franck Ferrand dans la s\u00e9rie &lsquo;<em><a href=\"https:\/\/fr.wikipedia.org\/wiki\/L%27Ombre_d%27un_doute_(\u00e9mission_de_t\u00e9l\u00e9vision)\">L&rsquo;ombre d&rsquo;un doute<\/a><\/em>&lsquo; (cha&icirc;ne Histoire). On, y suit une discussion particuli\u00e8rement s\u00e9rieuse, o&ugrave; se trouve fort bien soutenue et argument\u00e9e la th\u00e8se selon laquelle nombre de pi\u00e8ces de Moli\u00e8re parmi les plus grandes (&lsquo;<em>Le Misanthrope<\/em>&lsquo; notamment) ont \u00e9t\u00e9 \u00e9crites par Pierre Corneille. C&rsquo;\u00e9tait le temps o&ugrave; l&rsquo;&oelig;uvre d&rsquo;art \u00e9tait &oelig;uvre collective et donc propri\u00e9t\u00e9 d&rsquo;une culture plus que d&rsquo;une personne.<\/p>\n<\/p>\n<p><p>&bull; Tous deux, l&rsquo;auteur-Shakespeare et l&rsquo;auteur-Moli\u00e8re, se situent comme des phares culturels fondamentaux dans deux des plus grandes p\u00e9riodes, sinon les plus grandes, de ces deux grands pays europ\u00e9ens, pour la plus grande gloire de la civilisation europ\u00e9enne selon l&rsquo;id\u00e9e, \u00e9trange aujourd&rsquo;hui, qu&rsquo;on en avait alors. L&rsquo;auteur-Shakespeare est la gloire elle-m\u00eame qui \u00e9claire toute la p\u00e9riode \u00e9lisab\u00e9thaine (&Eacute;lisabeth I\u00e8re) ; l&rsquo;auteur-Moli\u00e8re est ce qu&rsquo;il est pour le temps du plus grand Roi du Monde (Louis XIV).<\/p>\n<\/p>\n<p><p>&bull; Ah oui, j&rsquo;oubliais : ils \u00e9taient tous deux, morbleu, des &laquo; <em>m\u00e2les blancs<\/em> &raquo;.<\/p>\n<\/p>\n<blockquote>\n<p><p>C&rsquo;est en m\u00eame temps \u00e0 peu pr\u00e8s qu&rsquo;on les passe \u00e0 la trappe, la t\u00eate au bout d&rsquo;une pique ; cela, au milieu d&rsquo;un d\u00e9luges extraordinaires de ce que je nommerais, qu&rsquo;on me pardonne mon audace d&rsquo;apparence n\u00e9ologiste, &lsquo;un d\u00e9luge guillotineur\u00a0\u00bb ; parce que je trouve, qu&rsquo;on me pardonne mes images douteuses, que les statues d\u00e9boulonn\u00e9es, les arguments d\u00e9velopp\u00e9s, les anath\u00e8mes comme autant de papiers-toilette un peu usag\u00e9s, ont tous le go&ucirc;t et l&rsquo;odeur de la guillotine&#8230; Un bruit sec, la lame qui siffle, et &lsquo;<em>basta !<\/em>&lsquo;, &ndash; explications inutiles, \u00e9vidences indiscutables.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>C&rsquo;est bien pour le symbole et pour la m\u00e9taphore, et donc pour la signification de la chose, que nos <a href=\"https:\/\/www.dedefensa.org\/article\/notes-sur-la-liquidation-de-platon-aristote\">wokenistes<\/a> aient song\u00e9 \u00e0 liquider en m\u00eame temps les deux types-&laquo; <em>m\u00e2les blancs<\/em> &raquo; dont je parle. Pour enrichir encore leurs dossiers \u00e0 charge et agacer un peu plus ceux qui trouve que je fais trop long, voici l&rsquo;une et l&rsquo;autre pr\u00e9cisions ou illustrations, pour situer l&rsquo;environnement et l&rsquo;esprit de mon propos, et montrer combien ce d\u00e9bat est extraordinairement actuel malgr\u00e9 qu&rsquo;il s&rsquo;agisse de &laquo; <em>m\u00e2les blancs<\/em> &raquo; vieux de trois et quatre si\u00e8cles au moins&#8230;<\/p>\n<\/p>\n<p><p>Dans une sorte de simultan\u00e9it\u00e9 chronologique qui m&rsquo;inspire beaucoup, on trouve beaucoup, en ce m\u00eame moment, de cette sorte de textes o&ugrave; nos chers guillotineurs voudraient, &ndash; maintenant, soyons s\u00e9rieux, hein !, &ndash; <a href=\"https:\/\/jonathanturley.org\/2021\/02\/16\/this-is-about-white-supremacy-and-colonization-teacher-group-calls-for-shakespeare-to-be-removed-from-reading-lists\/\">effacer<\/a> (&lsquo;<em>to cancel<\/em>&lsquo;) <a href=\"https:\/\/www.wnd.com\/2021\/02\/woke-faculty-members-condemn-shakespeare-white-supremacist\/\">Shakespeare<\/a> et Moli\u00e8re, d&rsquo;une fa\u00e7on ou l&rsquo;autre. (Pour Moli\u00e8re, c&rsquo;est <a href=\"https:\/\/www.lci.fr\/education\/theatre-moliere-va-t-il-vraiment-etre-reecrit-pour-etre-plus-accessible-2178333.html\">plus distingu\u00e9, plus sympa<\/a>, on parle de r\u00e9\u00e9crire, l&rsquo;original \u00e9tant destin\u00e9 \u00e0 faire du papelard \u00e0 usage multiple j&rsquo;imagine, &ndash; d\u00e9bat corn\u00e9lien certes mais on arrivera bien \u00e0 l&rsquo;\u00e9limination pour pr\u00e9server l&rsquo;environnement et les arbres qu&rsquo;on abat pour faire du papier. Peu importe, l&rsquo;intention y est parce que ces vieilles <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Barde\">bardes.ses<\/a> [au cas o&ugrave; ils seraient transgenres, Shakespeare et Moli\u00e8re] nous gonflent.)<\/p>\n<\/p>\n<p><p>&bull; Pour d\u00e9finir Shakespeare, qu&rsquo;on trouvait dans les environs romantiques de la campagne anglaise de Stratford-upon-Avon, j&rsquo;ai choisi un extrait d&rsquo;un texte <a href=\"https:\/\/www.rt.com\/op-ed\/515811-too-white-meaningless-default-criticism\/\">(RT.com<\/a>) de Frank Furedi, auteur et commentateur, auteur de ce livre qui en dit tant sur nos aujourd&rsquo;hui : &laquo; <em>How Fear Works: The Culture of Fear in the 21st Century<\/em> &raquo;. Dans sa chronique sur le sujet que vous devinez, il \u00e9voque ainsi la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-la-tragedie-bouffe\">trag\u00e9die-bouffe<\/a> et n\u00e9anmoins shakespearienne qui occupe nos esprits, et combien cela est absolument actuel, lors d&rsquo;une promenade champ\u00eatre dans la somptueuse campagne deu Kent :<\/p>\n<\/p>\n<p><p>&laquo; <em>Au fil des ans, je me suis habitu\u00e9 \u00e0 ce que les gens m&rsquo;informent que tel ou tel village ou ville de province qu&rsquo;ils ont visit\u00e9 est si &lsquo;blanc&rsquo;. Je n&rsquo;y pensais pas beaucoup jusqu&rsquo;\u00e0 ce qu&rsquo;un coll\u00e8gue am\u00e9ricain vienne me rendre visite dans mon ancienne maison du petit village de Throwley, dans le Kent. Apr\u00e8s notre promenade, il m&rsquo;a dit que bien que la campagne soit belle, le village \u00e9tait \u00ab\u00a0trop blanc\u00a0\u00bb. J&rsquo;ai essay\u00e9 de lui expliquer qu&rsquo;il y a beaucoup de petits villages dans le monde qui sont ethniquement homog\u00e8nes. Il a \u00e9t\u00e9 stup\u00e9fait par ma r\u00e9ponse et a sugg\u00e9r\u00e9 que Throwley \u00e9tait par d\u00e9finition une communaut\u00e9 culturellement et moralement inf\u00e9rieure \u00e0 Londres et \u00e0 d&rsquo;autres endroits divers<\/em>.<\/p>\n<p>&raquo; <em>Notre conversation s&rsquo;est termin\u00e9e lorsque j&rsquo;ai fait remarquer \u00e0 mon coll\u00e8gue am\u00e9ricain que lorsque j&rsquo;ai men\u00e9 mes recherches de doctorat dans de petits villages de la vall\u00e9e du Rift au Kenya, je n&rsquo;ai jamais pens\u00e9 qu&rsquo;il \u00e9tait remarquable <\/em>[et d\u00e9plorable]<em> que tous les membres de ces communaut\u00e9s soient manifestement noirs. Il ne m&rsquo;est jamais venu \u00e0 l&rsquo;esprit que ces villages \u00e9taient \u00ab\u00a0trop noirs\u00a0\u00bb. &Agrave; ses yeux, mon refus d&rsquo;\u00eatre d&rsquo;accord avec sa d\u00e9claration selon laquelle Throwley \u00e9tait trop blanc indiquait que j&rsquo;\u00e9tais ir-r\u00e9-cu-p\u00e9-rable<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>&bull; Pour Moli\u00e8re, je fais plus direct, mais en observant avec minutie ce caract\u00e8re qui m&rsquo;importe de voir dans ces \u00e9v\u00e9nements consid\u00e9rable un ph\u00e9nom\u00e8ne compl\u00e8tement d&rsquo;actualit\u00e9 et de notre temps. L\u00e0 aussi, comme pour Shakespeare, je vais dans le sens catastrophique de citer des remarques qui, directement ou indirectement, prennent la voie compl\u00e8tement d\u00e9mente d&rsquo;une certaine mise en cause de la d\u00e9marche compl\u00e8tement accord\u00e9e \u00e0 son temps, n\u00e9cessaire \u00e0 n\u00f4tre temps, dont nous avons un si urgent besoin. Dans ce texte (&lsquo;<em><a href=\"https:\/\/www.lefigaro.fr\/vox\/societe\/olivier-babeau-laissons-moliere-en-version-originale-20210216\">Figaro-Vox<\/a><\/em>&lsquo;) d&rsquo;Olivier Babeau, il est effet plaid\u00e9 que l&rsquo;un des bons usages de Moli\u00e8re serait de rechercher une critique de notre temps et pr\u00eater quelque utilit\u00e9 r\u00e9f\u00e9rentielle au pass\u00e9. C&rsquo;est dire&#8230;<\/p>\n<\/p>\n<p><p>&laquo; <em>R\u00e9\u00e9crire Moli\u00e8re, serait baisser le niveau d&rsquo;exigence et ne servirait qu&rsquo;\u00e0 augmenter encore un peu plus les in\u00e9galit\u00e9s.<\/em> [&#8230;] <em>Il ne s&rsquo;agit que d&rsquo;un pr\u00e9texte pour masquer l&rsquo;\u00e9chec du syst\u00e8me scolaire, et une tentative id\u00e9ologique d&rsquo;effacer une partie du pass\u00e9 \u00e0 l&rsquo;aune des crit\u00e8res moraux actuels.<\/em>.. [&#8230;]<\/p>\n<p>&raquo; <em>Rester fid\u00e8le, autant que possible, au texte original, c&rsquo;est permettre \u00e0 nos \u00e9l\u00e8ves de prendre une utile distance critique vis-\u00e0-vis de leur propre \u00e9poque et de les ouvrir aux r\u00e9alit\u00e9s de l&rsquo;histoire de notre civilisation<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Tout cela semblerait relever d&rsquo;une pol\u00e9mique d\u00e9plorable, &ndash; d\u00e9plorable parce que l&rsquo;\u00e9vidence nous en sugg\u00e8re tellement le sens. Je voudrais relever un peu la chose, sans me perdre \u00e0 argumenter pour faire triompher ce qui serait mon point de vue sur leur catastrophique et exceptionnelle cr\u00e9atin\u00e9mie, d&rsquo;ailleurs parce que j&rsquo;estime que dans cette sorte de pol\u00e9mique il n&rsquo;y a pas de d\u00e9bat, donc pas de point de vue, parce que ce serait risquer de me charger de quelque poussi\u00e8re mals\u00e9ante que d&rsquo;en faire valoir un ; parce que cela serait vraiment leur faire trop d&rsquo;honneur et leur pr\u00eater trop d&rsquo;attention, et une perte de mon temps pr\u00e9cieux, que de leur opposer le moindre argument. Cela est parce que cela est, &laquo; <em>les choses \u00e9tant ce qu&rsquo;elles sont <\/em>&raquo; ; leur cr\u00e9tinerie est partie prenante de ce domaine<\/p>\n<\/p>\n<blockquote>\n<p><p>Par contre, il m&rsquo;int\u00e9resse que les deux, si proches selon des rangements inhabituels, tels que je les ai d\u00e9taill\u00e9s plus haut, tombent sous les sabots de leur horde au m\u00eame moment. Je crois alors que les hordes wokenistes ont d\u00e9sormais atteint leur &lsquo;<a href=\"https:\/\/www.dedefensa.org\/article\/notes-sur-leffet-benghazi\">Point <em>Omega<\/em> inverti<\/a>&lsquo;, en s&rsquo;attaquant \u00e0 ces deux figures qui rassemblent tant de symboles jusqu&rsquo;\u00e0 \u00eatre des mythes qui renvoient \u00e0 l&rsquo;habillage m\u00e9taphysique de notre civilisation devenant contre-civilisation. Ils sont \u00e0 la fois, Shakespeare et Moli\u00e8re, le dernier espoir de notre civilisation, et le premier regret de notre contre-civilisation ; une sorte de &lsquo;derni\u00e8re chance&rsquo; que le Ciel, au travers de leur expression transcrivant des intuitions primordiales, entendait nous offrir. Ils figurent ainsi assez bien les pr\u00e9misses de la Chute et les premiers roulements de la Chute, en nous avertissant : \u00ab\u00a0Voici la Chute\u00a0\u00bb !<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Je dois pr\u00e9ciser \u00e0 nouveau qu&rsquo;il ne s&rsquo;agit pas d&rsquo;une interpr\u00e9tation chronologique, que Shakespeare-Moli\u00e8re indiqueraient un moment sp\u00e9cifique de l&rsquo;Histoire o&ugrave; la Chute s&rsquo;amorce, ou bien serait \u00e9vit\u00e9e selon ce que nous ferions de notre civilisation. Dans le grand courant de nos Derniers Temps, plusieurs occurrences de cette sorte peuvent appara&icirc;tre dans le d\u00e9roulement du Destin, \u00e0 partir du moment o&ugrave; nous commen\u00e7ons \u00e0 d\u00e9vier (\u00e0 partir du Temps des Cath\u00e9drales pour mon compte, voir &lsquo;<em>La Gr\u00e2ce<\/em>&lsquo;, Tome-II) ; et le moment o&ugrave; la Chute engag\u00e9e est devenue irr\u00e9sistible, irr\u00e9versible. Je crois bien que dans ce d\u00e9compte, l&rsquo;occurrence Shakespeare-Moli\u00e8re pr\u00e9sent\u00e9e comme symbole et mythe \u00e0 la fois, mais aussi comme m\u00e9taphore pour cette occurrence, constituent l&rsquo;une des derni\u00e8res, voire la derni\u00e8re possibilit\u00e9 d&rsquo;interf\u00e9rer et de modifier l&rsquo;\u00e9lan de la Chute, ou de tenter de le faire. D\u00e8s le XVIIIe, tout est perdu tandis que se \u00ab\u00a0<a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-le-dechainement-de-la-matiere\">d\u00e9cha&icirc;ne la Mati\u00e8re<\/a>\u00ab\u00a0.<\/p>\n<\/p>\n<p><p>Bien entendu, cette observation doit \u00eatre comprise effectivement comme une m\u00e9taphore pour nous ouvrir une perspective intuitive sur les \u00e9v\u00e9nements courants. Lorsque l&rsquo;on parle de deux grands esprits et grands initi\u00e9s vieux de trois-quatre si\u00e8cles, et des manigances pr\u00e9sentes \u00e0 leur encontre, on parle du destin de notre situation pr\u00e9sente et imm\u00e9diate et la m\u00e9taphore demande \u00e0 \u00eatre entendue dans ce sens, selon cette situation chronologique historique. Lorsque ce sont ceux-l\u00e0 que la d\u00e9mence courante et n\u00e9anmoins exceptionnaliste attaque comme de formidables d\u00e9molisseurs agissant en surpuissance <a href=\"https:\/\/www.dedefensa.org\/article\/lart-contemporain-ac-de-lautodestruction\">pour l&rsquo;autodestruction<\/a>, on doit y voir le signe que cette d\u00e9mence, comme le serpent qui forme cercle en se mordant la queue, atteint elle-m\u00eame le moment o&ugrave; elle devient Chute elle-m\u00eame. Je dirais volontiers, l\u00e0-dessus, qu&rsquo;il ne m&rsquo;\u00e9tonnerait nullement qu&rsquo;il y ait, dans les yeux de Shakespeare &#038; Moli\u00e8re, &laquo; <em>m\u00e2les blancs<\/em> &raquo; de trois-quatre si\u00e8cles ressuscit\u00e9s pour \u00eatre mieux soi-disant abaiss\u00e9s par les cr\u00e9tins, une dose non n\u00e9gligeable de goguenardise devant ce destin fort-d\u00e9plorable.<\/p>\n<\/p>\n<p><p>Bien s&ucirc;r, faire cette hypoth\u00e8se et la d\u00e9velopper comme je le fais, sans vergogne sur le domaine de la m\u00e9taphysique, c&rsquo;est peut-\u00eatre audacieux ; certains trouveront cela audacieux, d&rsquo;autres farfelue ; les uns et les autres se rencontreront pour y ajouter une solide d\u00e9rision, eux qui ont le jugement s\u00e9rieux et la perception rationnalis\u00e9e. Je leur demande, \u00e0 ceux-l\u00e0, ce qu&rsquo;il trouve de \u00ab\u00a0s\u00e9rieux\u00a0\u00bb et de \u00ab\u00a0rationnalis\u00e9\u00a0\u00bb dans les \u00e9v\u00e9nements que nous suivons dans nos Derniers Temps qui courent la chamade, notamment avec les hordes wokenistes. Je leur demande, aux m\u00eames, qu&rsquo;est-ce qu&rsquo;il trouve de \u00ab\u00a0s\u00e9rieux\u00a0\u00bb et de \u00ab\u00a0rationnel\u00a0\u00bb, sinon selon quelque r\u00e9f\u00e9rence satanique et diabolique qui a toute sa place, dans cette fantastique entreprise de d\u00e9constructuration, de constante r\u00e9f\u00e9rence au Mal, de destructions, de dissolution et de n\u00e9antisation.<\/p>\n<\/p>\n<p><p>Quand on se trouve dans des eaux si tourment\u00e9s, avec les foules des zombies-\u00e9lites portant beaux leurs entonnoirs du dernier cri d&rsquo;une mode que rien n&rsquo;arr\u00eate, par ailleurs porte chef de rigueur lorsqu&rsquo;on obtient une permission sp\u00e9ciale de sortie pour le week-end de l&rsquo;asile, &ndash; c&rsquo;est alors qu&rsquo;il faut avoir de l&rsquo;audace dans la pens\u00e9e (et dans les hypoth\u00e8ses, et dans les incursions m\u00e9taphysiques par cons\u00e9quent).<\/p>\n<\/p>\n<p><p>Un de nos lecteurs (&lsquo;J.C.&rsquo;) aime \u00e0 citer la phrase-embl\u00e8me, le fanion de notre action et de notre destin, &ndash; &laquo; <em>Aujourd&rsquo;hui, la sagesse c&rsquo;est l&rsquo;audace de la pens\u00e9e.<\/em> &raquo; Je crois que nous faisons preuve, ma pens\u00e9e et moi, d&rsquo;une certaine audace.<\/p>\n<\/p>\n<p><h2 class=\"titleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Note<\/h2>\n<\/p>\n<p><p>(*) Je me rappelle les m\u00e9moires de Jouvet, en tourn\u00e9e en Am\u00e9rique du Sud, jouant Alceste plusieurs jours de suite dans la m\u00eame capitale, rep\u00e9rant le m\u00eame spectateur tous les jours \u00e0 la m\u00eame place, le retrouvant lors d&rsquo;un cocktail d&rsquo;adieu au th\u00e9\u00e2tre, allant vers lui pour lui dire quelques mots : l&rsquo;autre ne parlait ni ne comprenait le fran\u00e7ais, il venait l\u00e0 pour la pure beaut\u00e9 de la langue<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Shakespeare &#038; Moli\u00e8re, en un Acte m\u00e9taphysique 18 f\u00e9vrier 2021 &ndash; Je vais tenter de faire un parall\u00e8le analogique entre deux auteurs de deux nations diff\u00e9rentes, mais toutes les deux charg\u00e9es de gloire dans &lsquo;n\u00f4tre&rsquo; Histoire commune, toutes deux ainsi que les deux auteurs constituant des \u00e9v\u00e9nements \u00e0 la fois symboliques, arch\u00e9typiques, m\u00e9taphoriques, mais aussi&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[3808,20712,3482,3423,20711,2631,16027,3079,20710,7948,2622,3694,14157,20709,17972,2646],"class_list":["post-79657","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-blanc","tag-chance","tag-chute","tag-civilisation","tag-corneiulle","tag-de","tag-derniere","tag-europeenne","tag-foredi","tag-genie","tag-la","tag-langue","tag-logocrate","tag-male","tag-metaphore","tag-wokenisme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79657","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79657"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79657\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79657"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79657"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}