{"id":79707,"date":"2021-03-31T16:09:15","date_gmt":"2021-03-31T16:09:15","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2021\/03\/31\/lotan-woke-colour-revolution-entre-soi\/"},"modified":"2021-03-31T16:09:15","modified_gmt":"2021-03-31T16:09:15","slug":"lotan-woke-colour-revolution-entre-soi","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2021\/03\/31\/lotan-woke-colour-revolution-entre-soi\/","title":{"rendered":"L&rsquo;OTAN-<em>woke\u00a0<\/em>: \u2018<em>colour revolution<\/em>&lsquo; entre-soi\u00a0?"},"content":{"rendered":"<div>\n<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">L&rsquo;OTAN-<em>woke <\/em>: &lsquo;<em>colour revolution<\/em>&lsquo; entre-soi ?<\/h2>\n<\/p>\n<blockquote>\n<p><p>&bull; <strong>L&rsquo;OTAN va-t-elle se <a href=\"https:\/\/www.dedefensa.org\/article\/notes-sur-le-wokenisme-seul-ii\">wok\u00e9niser<\/a> <\/strong>? &bull; Bien s&ucirc;r <strong>que oui<\/strong>, et son tr\u00e8s-<em>sexy <\/em>Secr\u00e9taire G\u00e9n\u00e9ral sait ce qu&rsquo;il importe de faire \u00e0 cet \u00e9gard, promouvant des projets de transformation qui devrait faire de l&rsquo;OTAN le rendez-vous favori <strong>des LGTBQ et des migrants, et l&rsquo;outil id\u00e9al pour lutter contre la Covid<\/strong>. &bull; Principal outil de ces projets : le \u00ab\u00a0Centre pour la R\u00e9silience D\u00e9mocratique\u00a0\u00bb de l&rsquo;OTAN, <strong>qui fera la police chez les membres<\/strong> de l&rsquo;honorable confr\u00e9rie pour v\u00e9rifier que les consignes wokenistes sont appliqu\u00e9es avec vigueur. &bull; <strong>Les Russes ont vu venir cette mue trans-civilisationnelle<\/strong>&#8230;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Il y a, ce <a href=\"https:\/\/southfront.org\/nato-pushes-for-creation-of-democratic-resilience-center\/\">30 mars 2021<\/a>, un int\u00e9ressant texte de <em>Southfront.org<\/em>, concernant une \u00e9volution qui pourrait \u00eatre majeure, &ndash; et \u00e9ventuellement-certainement catastrophique, esp\u00e9rons-le ; \u00e9volution de l&rsquo;OTAN, suivant avec z\u00e8le et componction, sous la direction du luth\u00e9rien et <em>sexy-<\/em>SecGen Stoltenberg, la voie trac\u00e9e par le wokenisme, le parti d\u00e9mocrate US, le <em>DeepState<\/em>. Et tout le reste progressiste-soci\u00e9tal. Cette \u00e9volution a un nom de d\u00e9part du popint de vue porganisationnel : le \u00ab\u00a0Centre pour la R\u00e9silience D\u00e9mocratique\u00a0\u00bb (disons CRD entre nous, d&rsquo;autant mieux que les initiales sont similaires en <em>NATO<\/em>&#8211;<em>english<\/em>) que l&rsquo;OTAN installe dans son sein. Elle a son importance, potentiellement consid\u00e9rable, &ndash; selon notre interpr\u00e9tation, compl\u00e8tement acquise au wokenisme et \u00e0 la r\u00e9volution qui vient avec, des USA qui plus est, &ndash; <em>His Master&rsquo;s Voice&#8230;<\/em><\/p>\n<\/p>\n<p><p>Sans y prendre garde (cela dit sinc\u00e8rement et candidement de notre fait), nous avions inconsciemment pr\u00e9empt\u00e9 la chose par rapport \u00e0 ce que l&rsquo;on trouve dans nos colonnes, sans doute instruit par un demi-dieu du type-Dionysos \u00e9quip\u00e9 de sa fl&ucirc;te de Pan. Rappelez-vous, ceci date du <a href=\"https:\/\/www.dedefensa.org\/article\/destruction-incontinente\">15 mars 2021<\/a>, alors que PhG se m\u00ealait de consid\u00e9rations sur <a href=\"https:\/\/www.dedefensa.org\/article\/vision-du-pentagone-catastrophe\">la folle \u00e9volution<\/a> des forces arm\u00e9es US :<\/p>\n<p>&laquo; <em>Peu importe les d\u00e9tails des circonstances car seul importe ce fait que je tiens de la meilleure source du monde : le Secr\u00e9taire G\u00e9n\u00e9ral de l&rsquo;OTAN Soltenberg (<a href=\"https:\/\/www.dedefensa.org\/article\/lettre-a-limmonde\">j&rsquo;en parlais hier<\/a>) a rencontr\u00e9 le ministre canadien de la d\u00e9fense. L&rsquo;entretien a dur\u00e9 20 minutes ; par ces temps troubl\u00e9s, parcourus de crises intenses et de menaces horribles, les sujets d&rsquo;ordre strat\u00e9gique et militaire ne durent pas manquer&#8230; Le vrai est que dix de ces 20 minutes ont \u00e9t\u00e9 consacr\u00e9es aux questions soci\u00e9tales de l&rsquo;introduction des pratiques LGTBQ et du wokenisme au sein des forces arm\u00e9es ; apr\u00e8s, on a un peu parl\u00e9 des missiles et de la prochaine guerre avec la Russie<\/em>.<\/p>\n<p>&raquo; <em>Cela est pour dire que si le sujet principal semble ici celui des forces arm\u00e9es US tel que nous en avons commenc\u00e9 <a href=\"https:\/\/www.dedefensa.org\/article\/vision-du-pentagone-catastrophe\">\u00e0 en parler hier<\/a>, le sujet r\u00e9el touche bien toutes les forces arm\u00e9es de l&rsquo;extr\u00eamement civilisationnel <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-bloc-bao-1\">bloc-BAO<\/a>, dont le <strong>broc<\/strong>-OTAN est l&rsquo;expression institutionnelle de sa quincaillerie et de son h\u00e9ro\u00efsme casqu\u00e9-masqu\u00e9<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Enfin, que se passe-t-il avec ce CRD ? Nous allons citer l&rsquo;introduction du texte de <em>Southfront.org<\/em>, qui nous instruit l\u00e0-dessus. L&rsquo;id\u00e9e n&rsquo;est pas neuve, bien entendu, le r\u00eave persistant ayant toujours \u00e9t\u00e9, du c\u00f4t\u00e9 des otaniens-am\u00e9ricanistes, de mettre le nez de l&rsquo;OTAN dans toutes, absolument toutes les affaires internes de ses membres. Cette fois, l&rsquo;occasion est belle, si belle, trop belle !<\/p>\n<\/p>\n<p><p>Il s&rsquo;agit de mettre l&rsquo;OTAN \u00ab\u00a0\u00e0 niveau\u00a0\u00bb, de faire entrer l&rsquo;Organisation de plain-pied dans l&rsquo;\u00e9poque du wokenisme, des cohortes LGTBQ et tout le reste, et tambour battant encore, avec Biden-Harris comme sergents-recruteurs et <em>pom-pom girls<\/em>&#8230; On notera la place accord\u00e9e \u00e0 l&rsquo;Assembl\u00e9e de l&rsquo;Atlantique-Nord (nous gardons <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Assembl\u00e9e_parlementaire_de_l%27OTAN\">son nom d&rsquo;origine<\/a> par mauvais esprit et esprit de contradiction), organisme-croupion qui ne servit strictement \u00e0 rien sinon d&rsquo;ornement d\u00e9mocratique durant la Guerre Froide et les quelques ann\u00e9es d&rsquo;apr\u00e8s, et qui a trouv\u00e9 sa vertu ontologique fondamentale avec le courant wokeniste qui balaie l&rsquo;Am\u00e9rique, sous la direction d\u00e9mocrate.<\/p>\n<\/p>\n<p><p>(Ce n&rsquo;est pas pour rien que les USA ont plac\u00e9 un pr\u00e9sident, d\u00e9mocrate de surcro&icirc;t donc wokeniste, &ndash; le d\u00e9put\u00e9 d\u00e9mocrate de la Virginie Connolly, -&ndash; \u00e9lu, par \u00ab\u00a0acclamation \u00e9lectronique\u00a0\u00bb [oups-l\u00e0-l\u00e0], \u00e0 la pr\u00e9sidence de l&rsquo;AAN, ou Assembl\u00e9e Parlementaire de l&rsquo;OTAN, lors de la session annuelle [la 66<sup>\u00e8me<\/sup>] de l&rsquo;assembl\u00e9e, et la premi\u00e8re virtuelle comme il se devait, le <a href=\"https:\/\/www.nato-pa.int\/news\/us-congressman-connolly-elected-nato-pa-president-vows-champion-values\">22 novembre 2020<\/a>.)<\/p>\n<\/p>\n<p><p>&laquo; <em>Au sein de l&rsquo;OTAN, la cr\u00e9ation du Centre pour la R\u00e9silience D\u00e9mocratique a fait surface, une fois de plus.<\/em><\/p>\n<p>&raquo; <em>Le concept est que <\/em>[le CRD] <em>devra surveiller les faits de violation de la d\u00e9mocratie dans les pays membres et aider les alli\u00e9s \u00e0 d\u00e9velopper plus efficacement les institutions d\u00e9mocratiques<\/em>.<\/p>\n<p>&raquo; <em>Une premi\u00e8re fois, l&rsquo;initiative de cr\u00e9er ce centre avait \u00e9t\u00e9 exprim\u00e9e en 2019, puis elle a \u00e9t\u00e9 not\u00e9e dans le concept de d\u00e9veloppement de l&rsquo;alliance de l&rsquo;OTAN 2030. Enfin, un groupe de travail a \u00e9t\u00e9 cr\u00e9\u00e9 au sein de l&rsquo;Assembl\u00e9e Parlementaire de l&rsquo;OTAN, qui tentera de traduire cette id\u00e9e dans la r\u00e9alit\u00e9.<\/em><\/p>\n<p>&raquo; <em>Il suffit de dire que l&rsquo;objectif principal du centre est vraisemblablement de traiter de la censure de l&rsquo;espace d&rsquo;information et de la discrimination contre les minorit\u00e9s ethniques dans les &Eacute;tats baltes, des accusations constantes de violations des droits de l&rsquo;homme contre la Turquie par la Gr\u00e8ce, ainsi que de l&rsquo;attitude non d\u00e9mocratique de la Pologne \u00e0 l&rsquo;\u00e9gard de l&rsquo;avortement et de la communaut\u00e9 LGBT au sens europ\u00e9en.<\/em><\/p>\n<p>&raquo; <em>La priorit\u00e9 absolue pour l&rsquo;Assembl\u00e9e Parlementaire de l&rsquo;OTAN est d&rsquo;aider l&rsquo;Alliance \u00e0 se consacrer \u00e0 nouveau \u00e0 ses fondements d\u00e9mocratiques.<\/em><\/p>\n<p>&raquo; <em>\u00ab\u00a0L&rsquo;attaque contre le Capitole, le 6 janvier, a montr\u00e9 que la d\u00e9mocratie, si elle est r\u00e9sistante, est aussi fragile. Et les preuves r\u00e9cemment publi\u00e9es de l&rsquo;ing\u00e9rence de la Russie dans nos \u00e9lections soulignent la menace que la marche mondiale de l&rsquo;autocratie fait peser sur nos d\u00e9mocraties\u00a0\u00bb, a not\u00e9 le d\u00e9put\u00e9 <\/em>[pr\u00e9sident de l&rsquo;AAN, ou APO]<em> Connolly. \u00ab\u00a0Nous devons constamment renforcer et prot\u00e9ger la d\u00e9mocratie contre les tentatives de la miner, &ndash; tant de l&rsquo;int\u00e9rieur que de l&rsquo;ext\u00e9rieur.\u00a0\u00bb<\/em> &raquo;<\/p>\n<\/p>\n<p><p>Tous les bobards sont l\u00e0, au garde-\u00e0-vous, avec l&rsquo;attaque du Capitole du 6 janvier et le <em>sexy-<\/em>Stoltenberg ouvrant le ban devant le verrou de plus (l&rsquo;AAN sous la pr\u00e9sidence de Connolly) pos\u00e9 sur l&rsquo;Alliance. La man&oelig;uvre est superbe de convenance, de conformisme et de politiquement-correct, avec pour but d&rsquo;habiller de couleurs radieuses, si possible de l&rsquo;arc-en-ciel LGTBQ, l&rsquo;Alliance absolument rajeunie. Connolly nous assure \u00e0 ce propos qu&rsquo;elle est le meilleur instrument imaginable pour coordonner transatlantiquement les efforts n\u00e9cessaires pour liquider la Covid \u00e0 jamais, ce qui devrait rassurer \u00ab\u00a0sachants\u00a0\u00bb et \u00ab\u00a0soignants\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>On notera d&rsquo;ores et d\u00e9j\u00e0 et bien entendu combien cette \u00e9volution correspond \u00e0 ce que les Russes ont identifi\u00e9 de leur c\u00f4t\u00e9, appelant cela \u00ab\u00a0guerre mentale\u00a0\u00bb comme nouveau concept venu de l&rsquo;Ouest, qui se montre impuissant dans tous les autres domaines (puissance militaire, sanctions \u00e9conomiques, etc.) et portant sur un affrontement de \u00ab\u00a0modes de vie\u00a0\u00bb civilisationnels, avec, d\u00e9sormais \u00e0 l&rsquo;Ouest dans les r\u00e9seaux de communication, la plus haute main donn\u00e9e au wokenisme.<\/p>\n<\/p>\n<p><p>&#8230;&rsquo;<em>Way of Life<\/em>&lsquo; dit-on bien entendu en guise de &lsquo;mode de vie&rsquo;, &ndash; avant, il y a tr\u00e8s longtemps, si longtemps, et d&rsquo;une toute autre mani\u00e8re, les Fran\u00e7ais parlaient de &laquo; <em>l&rsquo;art de vivre <\/em>&raquo; ; ces Fran\u00e7ais-l\u00e0 sont morts, remplac\u00e9s par les cr\u00e9tins universels et la b\u00eatise qui r\u00e8gne&#8230; Dans tous les cas, PhG notait dans le texte consacr\u00e9 \u00e0 cette &laquo; <em>guerre en cours <\/em>&raquo; telle que per\u00e7ue par les Russes et dont le CRD deviendra sans le moindre doute un \u00e9l\u00e9ment privil\u00e9gi\u00e9 dont chacun saura d&rsquo;o&ugrave; il vient et quels sont ses buts :<\/p>\n<\/p>\n<p><\/p>\n<p>&laquo; <em>Finalement, l&rsquo;int\u00e9r\u00eat principal des remarques d&rsquo;Ilnitsky est de nous communiquer ce qui est sans doute l&rsquo;avis des dirigeants russes, et notamment de l&rsquo;arm\u00e9e dont il est le conseiller, que cette \u00ab\u00a0guerre pour les \u00e2mes\u00a0\u00bb qui n&rsquo;est pas nouvelle, cette \u00ab\u00a0guerre pour la civilisations\u00a0\u00bb, a d\u00e9sormais la premi\u00e8re place, qu&rsquo;elle est le centre de la situation crisique conflictuelle g\u00e9n\u00e9rale o&ugrave; nous nous trouvons. Il s&rsquo;agit l\u00e0 de l&rsquo;\u00e9v\u00e9nement essentiel du propos, et de la s\u00e9quence que nous vivons actuellement.<\/em><\/p>\n<p>&raquo; <em>(Nous disons bien \u00ab\u00a0guerre pour la civilisations\u00a0\u00bb et non pas \u00ab\u00a0choc des civilisations\u00a0\u00bb puisque de notre c\u00f4t\u00e9 il n&rsquo;y a plus de \u00ab\u00a0civilisation\u00a0\u00bb, mais une \u00ab\u00a0contre-civilisation\u00a0\u00bb, c&rsquo;est-\u00e0-dire une entreprise de destruction de la civilisation. Il ne s&rsquo;agit pas d&rsquo;un \u00ab\u00a0mod\u00e8le\u00a0\u00bb contre un autre, mais bien d&rsquo;une d\u00e9fense et d&rsquo;une r\u00e9action vitale du concept de civilisation contre une entreprise de destruction de la civilisation, &ndash; effectivement antiSyst\u00e8me contre Syst\u00e8me.)<\/em> &raquo;<\/p>\n<\/p>\n<p><p>On ajoutera la derni\u00e8re partie du texte de <em>SouthFront.org <\/em>se r\u00e9f\u00e9rant \u00e0 une intervention en ligne dans un s\u00e9minaire de l&rsquo;universit\u00e9 de Floride du Sud, dans l&rsquo;&Eacute;tat de Floride des &Eacute;tats-Unis, du Secr\u00e9taire G\u00e9n\u00e9ral Soltenberg. Il parle de la mise en &oelig;uvre l&rsquo;Article 5 du Trait\u00e9 de l&rsquo;Alliance atlantique. On d\u00e9couvre alors de nouveaux horizons&#8230; Comme on le lit Soltenberg ne parle que de cyberguerre, mais la logique ainsi expos\u00e9e doit \u00eatre poursuivie \u00e0 la lumi\u00e8re de l&rsquo;agitation d\u00e9crite ci-dessus.<\/p>\n<\/p>\n<p><p>&laquo; <em>Il convient \u00e9galement de noter que l&rsquo;OTAN a l&rsquo;intention de recourir \u00e0 la force m\u00eame si l&rsquo;agression contre ses pays membres est commise \u00e0 l&rsquo;aide de moyens qui ne sont pas militaires. Le secr\u00e9taire g\u00e9n\u00e9ral de l&rsquo;OTAN, Jens Stoltenberg, a lanc\u00e9 un tel avertissement lors d&rsquo;un s\u00e9minaire r\u00e9alis\u00e9 en ligne et organis\u00e9 par l&rsquo;Universit\u00e9 de Floride du Sud.<\/em><\/p>\n<p>&raquo; <em>\u00ab\u00a0Nous n&rsquo;accorderons jamais \u00e0 notre adversaire potentiel le privil\u00e8ge de savoir exactement quand nous<\/em> [les Alli\u00e9s de l&rsquo;OTAN] <em>utilisons l&rsquo;article 5. Mais nous avons clairement indiqu\u00e9 que nous utiliserons l&rsquo;article 5 lorsque nous le jugerons n\u00e9cessaire. En outre, nous pouvons utiliser l&rsquo;article 5 lorsque nous constatons une agression utilisant d&rsquo;autres moyens que les moyens militaires conventionnels\u00a0\u00bb, a d\u00e9clar\u00e9 M. Stoltenberg.<\/em><\/p>\n<p>&raquo; <em>Il faisait r\u00e9f\u00e9rence \u00e0 l&rsquo;Article 5 du Trait\u00e9 de l&rsquo;Atlantique Nord sign\u00e9 \u00e0 Washington en 1949. Il consacre le principe de d\u00e9fense collective de l&rsquo;Organisation du trait\u00e9 de l&rsquo;Atlantique Nord. L&rsquo;article pr\u00e9voit une r\u00e9ponse collective en cas d'\u00a0\u00bbattaque arm\u00e9e contre un ou plusieurs\u00a0\u00bb pays membres de l&rsquo;OTAN.<\/em><\/p>\n<p>&raquo; <em>\u00ab\u00a0Nous avons vu que des actions agressives ont \u00e9t\u00e9 men\u00e9es <\/em>[dans un pass\u00e9 r\u00e9cent]<em> par d&rsquo;autres pays contre des alli\u00e9s de l&rsquo;OTAN, lorsque non pas des moyens militaires traditionnels, mais des moyens non militaires ont \u00e9t\u00e9 utilis\u00e9s pour essayer de saper nos positions, de nous diviser, de nous attaquer\u00a0\u00bb, a soutenu le secr\u00e9taire g\u00e9n\u00e9ral, sans entrer dans les d\u00e9tails.<\/em><\/p>\n<p>&raquo; <em>Selon lui, \u00ab\u00a0c&rsquo;est exactement ce \u00e0 quoi l&rsquo;OTAN doit s&rsquo;adapter\u00a0\u00bb. Et l&rsquo;alliance prend les d\u00e9cisions n\u00e9cessaires, a pr\u00e9cis\u00e9 M. Stoltenberg. Il a rappel\u00e9 qu&rsquo;aujourd&rsquo;hui, par exemple, l&rsquo;OTAN est pr\u00eate \u00e0 appliquer l&rsquo;article 5 en r\u00e9ponse \u00e0 des cyberattaques. \u00ab\u00a0Nous avons d\u00e9cid\u00e9 il y a quelques ann\u00e9es qu&rsquo;une attaque dans le cyberespace, une cyberattaque, pouvait d\u00e9clencher l&rsquo;article 5. Il s&rsquo;agit d&rsquo;un signal totalement nouveau <\/em>[pour un adversaire potentiel]<em>\u00ab\u00a0, a d\u00e9clar\u00e9 M. Stoltenberg.<\/em><\/p>\n<p>&raquo; <em>En outre, il a appel\u00e9 l&rsquo;OTAN \u00e0 commencer \u00e0 \u00ab\u00a0contrer plus activement la d\u00e9sinformation\u00a0\u00bb et \u00e0 prot\u00e9ger les \u00ab\u00a0infrastructures critiques\u00a0\u00bb de l&rsquo;alliance<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Stoltenberg ne parle certes, dans cet extrait et comme on l&rsquo;a d\u00e9j\u00e0 signal\u00e9 plus haut, que de \u00ab\u00a0cyberguerre\u00a0\u00bb comme occurrence non-militaire d&rsquo;une intervention type-Article 5. Mais, comme nous le disent nos \u00ab\u00a0ennemis\u00a0\u00bb russes dans le texte d\u00e9j\u00e0 r\u00e9f\u00e9renc\u00e9 comme dans un autre, m\u00eame la cyberguerre est une \u00e9tape d\u00e9j\u00e0 ancienne, dans tous les cas pass\u00e9e et d\u00e9pass\u00e9e ; la nouvelle s&rsquo;appelle \u00ab\u00a0la guerre des \u00e2mes\u00a0\u00bb, c&rsquo;est-\u00e0-dire tout ce qui concerne le comportement civilisationnel. Entrent dans cette cat\u00e9gorie l&rsquo;enti\u00e8ret\u00e9 du fourbi r\u00e9volutionnaire du n\u00e9o-capitalisme transhumaniste, des LGTBQ au BLM, jusqu&rsquo;au wokenisme. Au reste, toutes ces choses sont dites <em>in fine <\/em>lorsqu&rsquo;il est question du CRD ; mais il n&rsquo;est alors question que de \u00ab\u00a0surveillance\u00a0\u00bb, d'\u00a0\u00bbaide\u00a0\u00bb, etc., \u00e0 l&rsquo;intention des pays-membres, si besoin est n&rsquo;est-ce pas : &laquo; <em>Le concept est que <\/em>[le CRD] <em>devra surveiller les faits de violation de la d\u00e9mocratie dans les pays membres et aider les alli\u00e9s \u00e0 d\u00e9velopper plus efficacement les institutions d\u00e9mocratiques<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Pourtant c&rsquo;est bien de ces domaines (&laquo; &#8230;<em>la discrimination contre les minorit\u00e9s ethniques dans les &Eacute;tats baltes, des accusations constantes de violations des droits de l&rsquo;homme contre la Turquie par la Gr\u00e8ce, ainsi que de l&rsquo;attitude non d\u00e9mocratique de la Pologne \u00e0 l&rsquo;\u00e9gard de l&rsquo;avortement et de la communaut\u00e9 LGBT au sens europ\u00e9en<\/em> &raquo;) dont les Russes eux-m\u00eames parlent lorsqu&rsquo;ils \u00e9voquent la \u00ab\u00a0guerre des \u00e2mes\u00a0\u00bb. Les Russes pensent qu&rsquo;aujourd&rsquo;hui l&rsquo;agression se situe dans ces domaines, et nous les comprenons tellement que nous sommes bien d&rsquo;accord avec eux. Alors, les actions envisag\u00e9es pour le CRD, de l&rsquo;OTAN vis-\u00e0-vis de tel ou tel de ses membres, rel\u00e8veraient-elles d&rsquo;une d\u00e9fense face \u00e0 une \u00ab\u00a0agression\u00a0\u00bb contre ce membre, une \u00ab\u00a0agression\u00a0\u00bb que ce membre-l\u00e0 se lancerait contre lui-m\u00eame ?  Ou encore : si, demain, le Conseil de l&rsquo;Atlantique Nord, qui pourrait bien ne plus suivre le principe de l&rsquo;unanimit\u00e9 en 2030, juge que la Pologne d\u00e9roge gravement \u00e0 la d\u00e9mocratie sur les questions de l&rsquo;avortement et des LGTBQ, d\u00e9cidera-t-elle d&rsquo;intervenir, contre le gouvernement polonais, par exemple au nom de l&rsquo;Article 5 ? Cela pourrait \u00eatre nomm\u00e9, par exemple (bis et suite) : \u00ab\u00a0<em>colour revolution<\/em>\u00a0\u00bb entre-soi&#8230;<\/p>\n<\/p>\n<p><p>(Et, d&rsquo;ici l\u00e0, la Pologne si ardemment traditionnaliste ne ferait-elle pas bien bien de r\u00e9fl\u00e9chir pour savoir o&ugrave; se trouve son v\u00e9ritable ennemi : \u00e0 Moscou, comme elle l&rsquo;imagine fi\u00e9vreusement dans ses simulacres cauchemardesques sans voir que la Russie est la seule et solide d\u00e9fenderesse de la tradition dans la sph\u00e8re des \u00ab\u00a0civilis\u00e9s\u00a0\u00bb, ou \u00e0 Bruxelles-Washington o&ugrave; l&rsquo;on c\u00e9l\u00e8bre les transgenres et o&ugrave; les <em>Marines <\/em>volent \u00e0 bord de F-35 peints en rose mais clou\u00e9s au sol pour cause d&rsquo;interruption volontaire d&rsquo;\u00e9lectronique ?)<\/p>\n<\/p>\n<p><p>Tout cela est passionnant \u00e0 suivre, et surtout il faut reconna&icirc;tre au couple OTAN-Soltenberg une extraordinaire v\u00e9locit\u00e9 pour se prosterner comme il faut, \u00e0 la fois comme en-mosqu\u00e9e et envaccin\u00e9, avant de faire le beau devant le drapeau <em>Spangled-<\/em>LGTBQ. Heureuses soient l&rsquo;OTAN, qui eu la pr\u00e9monition d&rsquo;\u00eatre f\u00e9minine (Organisation), de m\u00eame que l&rsquo;Alliance atlantique. Il s&rsquo;agit d&rsquo;un don exceptionnel de voyance, qui montre bien combien l&rsquo;OTAN sut, de tous temps, \u00eatre en avance sur son temps, jusqu&rsquo;\u00e0 l&rsquo;\u00eatre encore aujourd&rsquo;hui pour demain.<\/p>\n<\/p>\n<p><p>Reste une question sympathique : que fait-on si, demain justement, par exemple en 2024, il venait \u00e0 un Trump, ou \u00e0 un clone de Trump, l&rsquo;id\u00e9e saugrenue et fort r\u00e9actionnaire de devenir pr\u00e9sident et de jeter \u00e0 la mer toute cette bouillie wokeniste ?<\/p>\n<\/p>\n<p><p>Mis en ligne le 31 mars 2021 \u00e0 15H50<\/p>\n<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;OTAN-woke : &lsquo;colour revolution&lsquo; entre-soi ? &bull; L&rsquo;OTAN va-t-elle se wok\u00e9niser ? &bull; Bien s&ucirc;r que oui, et son tr\u00e8s-sexy Secr\u00e9taire G\u00e9n\u00e9ral sait ce qu&rsquo;il importe de faire \u00e0 cet \u00e9gard, promouvant des projets de transformation qui devrait faire de l&rsquo;OTAN le rendez-vous favori des LGTBQ et des migrants, et l&rsquo;outil id\u00e9al pour lutter contre&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[7790,3395,20819,20820,2604,2645,13256,584,20821,11979,17780,2646],"class_list":["post-79707","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-ames","tag-assemblee","tag-crd","tag-democratrique","tag-des","tag-guerre","tag-lgtbq","tag-otan","tag-parlementaire","tag-resilience","tag-soltenberg","tag-wokenisme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79707"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79707\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79707"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79707"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}