{"id":79714,"date":"2021-04-06T14:39:22","date_gmt":"2021-04-06T14:39:22","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2021\/04\/06\/lukraine-aux-couleurs-du-wokenisme\/"},"modified":"2021-04-06T14:39:22","modified_gmt":"2021-04-06T14:39:22","slug":"lukraine-aux-couleurs-du-wokenisme","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2021\/04\/06\/lukraine-aux-couleurs-du-wokenisme\/","title":{"rendered":"L&rsquo;Ukraine aux couleurs du wokenisme"},"content":{"rendered":"<div>\n<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\"><strong>L&rsquo;Ukraine aux couleurs du wokenisme<\/strong><\/h2>\n<\/p>\n<p><p>6 avril 2021 &ndash; Une expression favorite de notre \u00e9poque immens\u00e9ment stupide, &ndash; <a href=\"https:\/\/www.dedefensa.org\/article\/la-betise-comme-element-metahistorique\">b\u00eatise<\/a> oblige, &ndash; est celle-ci : \u00ab\u00a0faire bouger les lignes\u00a0\u00bb. Pour la plupart d&rsquo;entre eux, les perroquets qui r\u00e9p\u00e8tent cela ignorent totalement qu&rsquo;ils d\u00e9finissent cette \u00ab\u00a0\u00e9poque immens\u00e9ment stupide\u00a0\u00bb. La seule expression qui vaille est celle-ci, et elle vaut pour tous ceux qui tentent de saisir quelques \u00e9vidences de cette \u00e9poque stupide et du Syst\u00e8me qui la domine, tous ceux qui tentent d&rsquo;\u00e9chapper \u00e0 la loi arbitraire et d&rsquo;exception du simulacre : non pas \u00ab\u00a0faire bouger les lignes\u00a0\u00bb mais \u00ab\u00a0d\u00e9sint\u00e9grer les lignes\u00a0\u00bb, les faire exploser, les r\u00e9duire en bouillie, les n\u00e9antiser !<\/p>\n<\/p>\n<p><p>Cela signifie que tout est li\u00e9, que tous les \u00e9v\u00e9nements crisiques de la colossale <a href=\"https:\/\/www.dedefensa.org\/article\/structure-crisique\">structure crisique<\/a> qu&rsquo;a cr\u00e9\u00e9e le Syst\u00e8me en voie d&rsquo;effondrement, d\u00e9pendent justement de la m\u00eame matrice, du m\u00eame ventre immonde et f\u00e9cond d&rsquo;o&ugrave; la B\u00eate nourrit son chaos ; et \u00ab\u00a0la B\u00eate\u00a0\u00bb, chers au faibles d&rsquo;esprit et \u00e0 l&rsquo;apprenti-zombie, c&rsquo;est le Syst\u00e8me, la m\u00eame \u00e9crasante entit\u00e9, &ndash; loin de tous les \u00ab\u00a0ismes\u00a0\u00bb que nous affectionnons, et principalement si pas exclusivement le plus utilis\u00e9 d&rsquo;entre eux, le \u00ab\u00a0fascisme\u00a0\u00bb ; cette hideuse et obligeante \u00ab\u00a0B\u00eate immonde\u00a0\u00bb pieusement conserv\u00e9e dans le grenier poussi\u00e9reux des souvenirs convenables et bienpensants d&rsquo;il y a un bon si\u00e8cle, que l&rsquo;on \u00e9voque comme l&rsquo;on d\u00e9gaine \u00e0 chaque pet de lapin qui semblerait vouloir nous enfumer.<\/p>\n<\/p>\n<p><p>Mais je m&rsquo;\u00e9gare, pourriez-vous croire, alors que mon but est de vous parler de l&rsquo;Ukraine, o&ugrave; l&rsquo;alarme est consid\u00e9rable :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>Tension tr\u00e8s forte entre l&rsquo;Ukraine de Zelenski et la Russie, <strong>la plus forte depuis le \u00ab\u00a0coup de Kiev\u00a0\u00bb ex\u00e9cut\u00e9 par les USA en f\u00e9vrier 2014<\/strong> et ce qui a imm\u00e9diatement suivi<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Vous allez observer n\u00e9anmoins combien cette introduction a de rapport avec la situation telle qu&rsquo;elle est, et non pas telle qu&rsquo;on la simulacre aussit\u00f4t, &ndash; du quasi-n\u00e9ologisme dans son emploi, qu&rsquo;on me pardonnera, &ndash; en v\u00e9rit\u00e9 <a href=\"https:\/\/www.cnrtl.fr\/definition\/dmf\/simulacrer?str=1\">verbe \u00ab\u00a0simulacrer\u00a0\u00bb<\/a> signifiant en toute proximit\u00e9 du vieux latin, &laquo; <em>adorer de faux dieux <\/em>&raquo;, &ndash; et y e&ucirc;t-il jamais une d\u00e9finition plus explicite de l&#8217;emprisonnement o&ugrave; nous nous trouvons ?<\/p>\n<\/p>\n<p><p>Bien, venons-en \u00e0 l&rsquo;Ukraine.<\/p>\n<\/p>\n<p><p>L&rsquo;alarme y est donc tr\u00e8s s\u00e9rieuse, certes \u00e0 cause de l&rsquo;habituelle provoc&rsquo; ukrainienne, mais surtout parce que, depuis quelques temps assez courts, &ndash; tiens, notamment depuis le \u00ab\u00a0Poutine est &laquo; <em>un tueur sans \u00e2me <\/em>&raquo;\u00a0\u00bb de Joe Biden, &ndash; les Russes sont devenus mortellement <strong>s\u00e9rieux<\/strong>. C&rsquo;est-\u00e0-dire qu&rsquo;ils envisagent <strong>s\u00e9rieusement<\/strong> d&rsquo;entrer dans un conflit s&rsquo;ils estiment que les choses vont trop loin. Et il s&rsquo;agit d&rsquo;un conflit, bien s&ucirc;r, o&ugrave;, quelque forme tactique qu&rsquo;il prenne, nous-autres braves Occidentaux soutiens de l&rsquo;Ukraine, prendrons une m\u00e9morable racl\u00e9e (en excluant l&rsquo;hypoth\u00e8se de la forme strat\u00e9gique nucl\u00e9aire, o&ugrave; la racl\u00e9e sera celle du genre humain en g\u00e9n\u00e9ral).<\/p>\n<\/p>\n<p><p>Plusieurs textes d&rsquo;auteurs directement connect\u00e9s avec les affaires russes prolif\u00e8rent. Je parle des vrais auteurs des vraies affaires russes, c&rsquo;est-\u00e0-dire des auteurs luttant contre la subversion du Syst\u00e8me \u00e9voluant notamment sous le masque d&rsquo;un pitoyable Zelenski et autres clowns-bouffe, et donc auteurs qu&rsquo;on placerait n\u00e9cessairement du c\u00f4t\u00e9 de la Russie. Il y a notamment les textes autour des <a href=\"https:\/\/www.msn.com\/en-gb\/news\/world\/russian-analyst-warns-european-or-world-war-could-break-out-in-ukraine\/ar-BB1fgTTc\">observations sc\u00e9naristiques<\/a> d&rsquo;une guerre probable Russie-Ukraine (d\u00e9but mai est la date envisag\u00e9e) du <a href=\"https:\/\/jamestown.org\/analyst\/pavel-felgenhauer\/\">Dr. Pavel E. Felgenhauer<\/a>, analyste russe travaillant notamment pour la <a href=\"https:\/\/jamestown.org\/\">Jamestown Foundation<\/a>. Il y a aussi, et c&rsquo;est sur ce texte que je veux m&rsquo;attarder, <a href=\"https:\/\/smoothiex12.blogspot.com\/2021\/04\/they-neocons-may-have-anger-issues.html\">le texte<\/a> d&rsquo;Andrei Martianov dont <em>Le Sakerfrancophone <\/em>nous donne une <a href=\"https:\/\/lesakerfrancophone.fr\/bruits-de-bottes-en-ukraine\">adaptation fran\u00e7aise<\/a>, apr\u00e8s une <a href=\"http:\/\/thesaker.is\/what-will-the-empire-do-to-support-the-ukronazis-open-thread-4\/\">rapide mise en forme<\/a> et recommandation du <em>Saker US <\/em>nous conseillant la lecture de ce texte (de Martianov).<\/p>\n<\/p>\n<p><p>Martianov d\u00e9veloppe l&rsquo;id\u00e9e effectivement de la possibilit\u00e9 d&rsquo;une guerre, en en attribuant la responsabilit\u00e9 aux \u00ab\u00a0<em>usual suspects<\/em>\u00a0\u00bb (ou mieux encore, \u00ab\u00a0<em>usual culprits<\/em>\u00ab\u00a0), ceux qu&rsquo;on d\u00e9signe \u00e0 D.C. sous l&rsquo;expression de <em>neocons<\/em>. Pour situer son propos, Martianov emprunte un extrait d&rsquo;une d\u00e9claration de Michael Hudson, \u00e9conomiste fameux, professeur \u00e0 l&rsquo;universit\u00e9 du Missouri, auteur, etc., &ndash; Hudson parlant lors d&rsquo;un dialogue en conf\u00e9rence qu&rsquo;il a avec P\u00e9p\u00e9 Escobar, <a href=\"https:\/\/www.unz.com\/mhudson\/in-quest-of-a-multipolar-economic-world-order\/\">\u00e0 la fin mars<\/a> :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>Les Am\u00e9ricains veulent la guerre. Les personnes que Biden a nomm\u00e9es ont une haine \u00e9motionnelle de la Russie. J&rsquo;ai parl\u00e9 \u00e0 des membres du gouvernement qui sont proches du parti D\u00e9mocrate, et ils m&rsquo;ont dit qu&rsquo;il y a un d\u00e9sir \u00e9motionnel pathologique de faire la guerre contre la Russie, provenant en grande partie du fait que les Tsars \u00e9taient antis\u00e9mites et qu&rsquo;il y a toujours la haine de leurs anc\u00eatres : \u00ab\u00a0Regardez ce qu&rsquo;ils ont fait \u00e0 mon arri\u00e8re-grand-p\u00e8re\u00a0\u00bb. Et donc ils sont pr\u00eats \u00e0 soutenir les nazis, \u00e0 soutenir les antis\u00e9mites ukrainiens. Ils sont pr\u00eats \u00e0 soutenir les antis\u00e9mites d&rsquo;aujourd&rsquo;hui dans le monde entier, tant qu&rsquo;ils r\u00e9cup\u00e8rent cette concentration \u00e9motionnelle sur une sorte d&rsquo;\u00e9conomie post-19e si\u00e8cle. J&rsquo;ai rencontr\u00e9 ces gens. Leur \u00e9motion est celle de la haine et de la col\u00e8re. Vous pouvez regarder leur visage et voir ce qu&rsquo;ils sont devenus. C&rsquo;est vraiment dangereux. Ils sont fous. Et Poutine a tout \u00e0 fait raison. L&rsquo;Am\u00e9rique a obtenu son pouvoir en ne respectant pas ses accords. Elle a rompu toutes ses promesses avec les natifs am\u00e9ricains pour prendre leurs terres. Elle a rompu son accord avec l&rsquo;Iran. Elle a rompu l&rsquo;accord ukrainien de Minsk, et le JCPOA auparavant. Alors quel est l&rsquo;int\u00e9r\u00eat de signer un accord avec les Am\u00e9ricains<\/em>&#8230; <em>?<\/em>  &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>A la suite de quoi, Martianov d\u00e9crit ces Am\u00e9ricains qui &laquo; <em>veulent la guerre<\/em> &raquo;, en vient aussit\u00f4t aux <em>neocons<\/em>, qu&rsquo;il d\u00e9construit \u00e9galement aussit\u00f4t en montrant que cette \u00e9tiquette ne veut rien dire, et surtout pas tous les caract\u00e8res politiques (n\u00e9o-conservateurs, trotskistes, etc.) dont on l&rsquo;a affubl\u00e9e depuis des lustres. Il ne reste, au sens tr\u00e8s large et g\u00e9n\u00e9reux de l&rsquo;am\u00e9ricanisme, que les \u00ab\u00a0fauteurs de guerre\u00a0\u00bb (\u00ab\u00a0<em>warmongers<\/em>\u00ab\u00a0), qui sont l\u00e9gion \u00e0 DC jusqu&rsquo;\u00e0 n&rsquo;\u00eatre que la seule cat\u00e9gorie envisageable et admissible par la matrice. Martianov garde l&rsquo;explication de la folie, ce qui est pour moi une \u00e9vidence, mais implicitement \u00e9galement l&rsquo;explication beaucoup plus incertaine de \u00ab\u00a0l&rsquo;antis\u00e9mitisme des tsars\u00a0\u00bb :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>Voici ce que j&rsquo;essaie constamment de souligner : on ne n\u00e9gocie pas avec une bande de fous, surtout afflig\u00e9e d&rsquo;un traumatisme ethno-religieux \u00e9troit<\/em> <em>qui au fil des ans est r\u00e9amplifi\u00e9 dans la chambre d&rsquo;\u00e9cho de l&rsquo;immigration juive am\u00e9ricaine, dont l&rsquo;ascension au sommet du pouvoir et de l&rsquo;influence politique dans la p\u00e9riode qui a suivi la Seconde Guerre mondiale s&rsquo;est faite par le biais de ce<\/em> <em>que certains, \u00e0 tort, continuent de consid\u00e9rer comme un mouvement n\u00e9oconservateur (trotskiste) intellectuel, qui n&rsquo;est en r\u00e9alit\u00e9 ni \u00ab\u00a0conservateur\u00a0\u00bb, dans aucun sens applicable, ni, surtout, intellectuel&#8230; <\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Donc, pour mon compte, l&rsquo;explication de la folie suffit : lorsqu&rsquo;on a la folie, on tient la cause absolue du comportement, et tous les arguments que d\u00e9veloppe le fou, ou qu&rsquo;on lui pr\u00eate, ne sont que des amuse-gueule de passage et de fortune. Ainsi, justifier la haine contre la Russie par la folie me convient parfaitement, parce que la haine \u00e0 ce degr\u00e9 de surdit\u00e9 et avec cette constance aveugle rime dans ce cas avec \u00ab\u00a0folie\u00a0\u00bb ; mais lui adjoindre du poids incertain d&rsquo;un objet comme \u00ab\u00a0l&rsquo;antis\u00e9mitisme des tsars\u00a0\u00bb (qui n&rsquo;existe plus, s&rsquo;il exist\u00e2t jamais, depuis 1917) qu&rsquo;on continue \u00e0 combattre avec l&rsquo;appoint des antis\u00e9mites actuels les plus extr\u00eames possibles (la branche n\u00e9o-nazie extr\u00eamement active des Ukrainiens antirusses) me para&icirc;t inutile et insatisfaisant. On ne peut mettre sur le m\u00eame pied la folie qui se manifeste \u00e0 DC et cette incertaine architecture, ni expliquer celle-ci par celle-l\u00e0 ; alors que et par ailleurs, la pr\u00e9sence nazie en Ukraine avec laquelle nous avions fait et continuons \u00e0 faire alliance avait <a href=\"https:\/\/www.dedefensa.org\/article\/notes-sur-nos-amis-nazis\">mis en \u00e9vidence<\/a> certains points <a href=\"https:\/\/www.dedefensa.org\/article\/l-ukraine-a-swastika-decouverte\">tr\u00e8s particuliers<\/a> de notre bloc-BAO, bien loin de l&rsquo;affaire de \u00ab\u00a0l&rsquo;antis\u00e9mitisme des tsars\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>Le titre de l&rsquo;article de Martianov est &laquo; <em>They (Neocons) May Have Anger Issues<\/em>&#8230; &raquo;, dont la signification interpr\u00e9tatoire est assez ambigu\u00eb. Pour moi, le meilleur choix, si on donne au mot \u00ab\u00a0<em>anger<\/em>\u00a0\u00bb son sens le plus large d&rsquo;une folle passion devrait \u00eatre : \u00ab\u00a0Les <em>neocons <\/em>ont peut-\u00eatre trouv\u00e9 le th\u00e9\u00e2tre de l&rsquo;op\u00e9rationnalit\u00e9 de leur col\u00e8re haineuse\u00a0\u00bb (ou \u00ab\u00a0de leur col\u00e8re furieuse\u00a0\u00bb, etc.). On comprend le sens de l&rsquo;interpr\u00e9tation, et l&rsquo;on comprend aussi que ces mots divers (\u00ab\u00a0col\u00e8re\u00a0\u00bb, \u00ab\u00a0haine\u00a0\u00bb, \u00ab\u00a0fureur\u00a0\u00bb, et l&rsquo;on pourrait mettre aussi \u00ab\u00a0passion\u00a0\u00bb) ont tous une connexion avec la folie. D&rsquo;o&ugrave; la justesse du jugement sur la \u00ab\u00a0bande de fous\u00a0\u00bb, &laquo; <em>C&rsquo;est vraiment dangereux. Ils sont fous.<\/em> &raquo;, &ndash; qu&rsquo;il faut prendre dans son sens le plus puissant : nous parlons bien d&rsquo;une pathologie de la d\u00e9mence. C&rsquo;est sur ce point que je veux m&rsquo;arr\u00eater.<\/p>\n<\/p>\n<p><p>Je comprends mal, pour mon compte, pourquoi et comment l&rsquo;on ne fait pas le lien entre cette soudaine r\u00e9surgence du sentiment de guerre (et non la r\u00e9surgence des <em>neocons <\/em>ou des<em> warmongers <\/em>qui n&rsquo;ont jamais cess\u00e9 d&rsquo;exister), qui s&rsquo;exerce contre la Russie, mais \u00e9galement contre la Chine, contre l&rsquo;Iran, contre la Syrie, etc., &ndash; et la d\u00e9mence qui s&rsquo;exprime dans le mouvement du <a href=\"https:\/\/www.dedefensa.org\/article\/notes-sur-le-wokenisme-seul-ii\">wokenisme<\/a>. La folie n&rsquo;est pas une pand\u00e9mie qui se limite \u00e0 telle ou telle cat\u00e9gorie, c&rsquo;est au contraire la pand\u00e9mie la plus universelle qui soit lorsqu&rsquo;elle se d\u00e9clare dans un milieu, dans un segment de pens\u00e9e, dans un courant id\u00e9ologique, dans un sentiment collectif d'\u00a0\u00bbexceptionnalit\u00e9\u00a0\u00bb comme celui qui continue \u00e0 entretenir, \u00e0 bercer, et m\u00eame \u00e0 renforcer l&rsquo;addiction de Washington D.C. dans son simulacre.<\/p>\n<\/p>\n<p><p>Oui, j&rsquo;ai du mal \u00e0 comprendre pourquoi l&rsquo;on ne fait pas le lien entre cette soudaine renaissance d&rsquo;un d\u00e9sir de guerre dans le champ clos, pourri et corrompu, et <a href=\"https:\/\/www.dedefensa.org\/article\/lalerte-ukrainienne-et-lami-joe\">si familier<\/a> au nouveau pr\u00e9sident, de l&rsquo;Ukraine, et la dynamique du wokenisme qui bouleverse absolument les fondements sociaux, soci\u00e9taux, psychologiques. Pour moi, l&rsquo;un ne va pas sans l&rsquo;autre, et aucun ne demande d&rsquo;explication \u00ab\u00a0rationnelle\u00a0\u00bb, ou m\u00eame \u00ab\u00a0id\u00e9ologique\u00a0\u00bb, ou ethnique et religieuse, etc. ; au contraire, cette sorte d&rsquo;explication diminue l&rsquo;id\u00e9e m\u00eame de la d\u00e9mence et nous fait rater la v\u00e9ritable ampleur et la signification de la situation ; bref, elle nous fait rater la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-verite-de-situation-verite\">v\u00e9rit\u00e9-de-situation<\/a>.<\/p>\n<\/p>\n<p><p>Au contraire, la r\u00e9activation de la possibilit\u00e9 d&rsquo;une guerre avec l&rsquo;Ukraine, une sorte de \u00ab\u00a0retour \u00e0 2014\u00a0\u00bb, ou \u00ab\u00a02014.02\u00a0\u00bb, suit la parfaite logique de la folie qui ne cesse de chercher, et de se trouver un objet qui entre en-dedans elle (dans la logique de la folie), pour justifier et subir le d\u00e9cha&icirc;nement de ses actes incompr\u00e9hensibles parce qu'\u00a0\u00bbinsens\u00e9s\u00a0\u00bb. Martianov lui-m\u00eame, en m\u00eame temps qu&rsquo;il tentera plus loin de l&rsquo;expliquer, parle comme d&rsquo;une \u00e9vidence, au fil de la plume, de &laquo; <em>la politique \u00e9trang\u00e8re insens\u00e9e des &Eacute;tats-Unis ou, plut\u00f4t, de son absence<\/em> &raquo;.<\/p>\n<\/p>\n<p><p>L\u00e0-dessus et pour finir sur une perspective coh\u00e9rente (?), je vais tout de m\u00eame dire quelques mot des pr\u00e9visions du Dr. Felgenhauer, <a href=\"https:\/\/www.dailymail.co.uk\/news\/article-9433075\/Russian-military-analyst-warns-European-world-war-possible-month-tensions-rise-Ukraine.html\">cit\u00e9 plus haut<\/a>. Apr\u00e8s avoir longuement d\u00e9crit les diff\u00e9rentes tactiques envisag\u00e9es par les Russes pour la racl\u00e9e qu&rsquo;ils pr\u00e9voient d&rsquo;administrer aux \u00ab\u00a0<em>Ukronazis<\/em>\u00ab\u00a0, comme on d\u00e9signe famili\u00e8rement les gens de Kiev, . Felgenhauer explique que la position des Occidentaux (l&rsquo;OTAN, l&rsquo;Europe, les am\u00e9ricanistes-europ\u00e9istes, nous quoi) face \u00e0 ce conflit qui arrive vers nous, et gr\u00e2ce \u00e0 nous principalement, \u00e0 grands tours de chenilles de char, &ndash; eh bien, cette position &laquo; <em>n&rsquo;est pas tr\u00e8s claire<\/em> &raquo;.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>Certains <\/em>[\u00e0 l&rsquo;Ouest] <em>disent que les Russes ne devraient pas \u00eatre provoqu\u00e9s, et qu&rsquo;une intervention militaire <\/em>[de l&rsquo;OTAN] <em>est trop risqu\u00e9e.<\/em><\/p>\n<p>&raquo; <em>D&rsquo;autres, au contraire, sont en faveur d&rsquo;une unification (de la Russie et de l&rsquo;Ukraine) et d&rsquo;une confrontation ouverte, parce qu&rsquo;alors il sera possible de n\u00e9gocier avec les Russes. <\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>La seconde hypoth\u00e8se vous para&icirc;t-elle \u00e9trange, comme \u00e0 moi ? Elle pr\u00e9voit de favoriser une confrontation, de fa\u00e7on \u00e0 ce que les Russes conqui\u00e8rent l&rsquo;Ukraine, parce qu&rsquo;alors il sera plus facile de n\u00e9gocier avec les Russes ? (Peut-\u00eatre parce qu&rsquo;alors, ayant gagn\u00e9 la guerre en conqu\u00e9rant l&rsquo;Ukraine, la Russie ne pourra plus nier qu&rsquo;elle a effectivement envahi l&rsquo;Ukraine, comme on le dit et le r\u00e9p\u00e8te avec tant de certitude depuis 2014 ? En effet, n&rsquo;est-il pas plus habile, et plus loyal, de provoquer les \u00e9v\u00e9nements selon notre <em>narrative<\/em>, \u00e0 l&rsquo;avantage des Russes dont on d\u00e9crit toutes les turpitudes agressives et furieuses qui vont si bien avec, pour prouver la justesse de notre <em>narrative <\/em>? Ah, beaut\u00e9 sans fin du <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-le-determinisme-narrativiste\">d\u00e9terminisme-narrativiste<\/a>&#8230;)<\/p>\n<\/p>\n<p><p>Bref et outre l&rsquo;imperturbable s\u00e9rieux des Russes qui d\u00e9ploient leurs troupes, la v\u00e9ritable nouvelle dans cet \u00e9v\u00e9nement crisique de l&rsquo;Ukraine est qu&rsquo;il est confirm\u00e9 que les fous sont plus fous qu&rsquo;ils n&rsquo;ont jamais \u00e9t\u00e9, au moins \u00e0 un degr\u00e9 fondamental plus haut dans la folie, jusques et y compris proche de ses sommets ultimes, &ndash; et que la guerre sera wokeniste ou ne sera pas&#8230; Au reste, l&rsquo;on apprendra avec soulagement que l&rsquo;U.S. Army, r\u00e9form\u00e9e aux couleurs du wokenisme, <a href=\"https:\/\/www.zerohedge.com\/geopolitical\/biden-administration-alert-over-russian-saber-rattling-eastern-europe-arctic\">a averti<\/a> qu&rsquo;elle \u00e9tait pr\u00eate \u00e0 toute \u00e9ventualit\u00e9.<\/p>\n<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;Ukraine aux couleurs du wokenisme 6 avril 2021 &ndash; Une expression favorite de notre \u00e9poque immens\u00e9ment stupide, &ndash; b\u00eatise oblige, &ndash; est celle-ci : \u00ab\u00a0faire bouger les lignes\u00a0\u00bb. Pour la plupart d&rsquo;entre eux, les perroquets qui r\u00e9p\u00e8tent cela ignorent totalement qu&rsquo;ils d\u00e9finissent cette \u00ab\u00a0\u00e9poque immens\u00e9ment stupide\u00a0\u00bb. La seule expression qui vaille est celle-ci, et elle&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[5804,3000,14921,4020,7647,10039,13454,4357,1104,584,2730,12664,20832,1296,2671],"class_list":["post-79714","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-antisemite","tag-demence","tag-felgenhauer","tag-folie","tag-hudson","tag-invasion","tag-martianov","tag-michael","tag-neocons","tag-otan","tag-russie","tag-saker","tag-simulacrer","tag-ukraine","tag-us"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79714","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79714"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79714\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79714"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79714"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}