{"id":79719,"date":"2021-04-10T16:02:52","date_gmt":"2021-04-10T16:02:52","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2021\/04\/10\/rapsit-usa2021-gouverneurs-en-armes\/"},"modified":"2021-04-10T16:02:52","modified_gmt":"2021-04-10T16:02:52","slug":"rapsit-usa2021-gouverneurs-en-armes","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2021\/04\/10\/rapsit-usa2021-gouverneurs-en-armes\/","title":{"rendered":"RapSit-USA2021\u00a0: Gouverneurs en armes"},"content":{"rendered":"<div>\n<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">RapSit-USA2021 : Gouverneurs en armes<\/h2>\n<\/p>\n<p><p>Un certain nombre de gouverneurs d&rsquo;Etat (des r\u00e9publicains pour l&rsquo;instant) ont r\u00e9agi au discours de jeudi du pr\u00e9sident Biden sur diverses mesures limitant et contr\u00f4lant le port et la possession d&rsquo;armes \u00e0 feu. Les arguments contre cette attaque sur la question de la possession d&rsquo;armes \u00e0 feu sont connus : extension inappropri\u00e9e relevant de l&rsquo;abus de pouvoir du pouvoir f\u00e9d\u00e9ral, violation du Deuxi\u00e8me Amendement de la Constitution qui autorise express\u00e9ment le port d&rsquo;armes. Certains gouverneurs ont d\u00e9j\u00e0 sign\u00e9 ou vont signer une loi de leur &Eacute;tat annulant la d\u00e9cision pr\u00e9sidentielle.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>Dans <a href=\"https:\/\/www.newsmax.com\/politics\/gop-governors-guncontrol-laws\/2021\/04\/09\/id\/1017054\/\">la matin\u00e9e de jeudi<\/a>, &laquo; <em>Biden a pr\u00e9sent\u00e9 une s\u00e9rie de d\u00e9crets<\/em> [\u00ab\u00a0<em>Executive Orders<\/em>\u00ab\u00a0] <em>visant \u00e0 r\u00e9duire la violence arm\u00e9e et \u00e0 renforcer le contr\u00f4le des armes \u00e0 feu. Il a notamment demand\u00e9 au minist\u00e8re de la Justice de proposer une r\u00e8gle pour mettre un terme aux \u00ab\u00a0armes fant\u00f4mes\u00a0\u00bb, c&rsquo;est-\u00e0-dire aux armes \u00e0 feu artisanales qui sont g\u00e9n\u00e9ralement assembl\u00e9es \u00e0 partir de pi\u00e8ces et frais\u00e9es \u00e0 l&rsquo;aide d&rsquo;une machine \u00e0 d\u00e9couper le m\u00e9tal, et qui n&rsquo;ont ainsi pas de num\u00e9ro de s\u00e9rie permettant de les retracer.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Une deuxi\u00e8me proposition de r\u00e8gle renforcera la r\u00e9glementation sur les supports de stabilisation des pistolets, comme celui utilis\u00e9 par le tireur de Boulder, Colorado, le mois dernier.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>S&rsquo;exprimant depuis le Rose Garden, Biden a d\u00e9clar\u00e9 : \u00ab\u00a0Aucun amendement \u00e0 la Constitution n&rsquo;est absolu&#8230; D\u00e8s le d\u00e9but, vous ne pouviez pas poss\u00e9der l&rsquo;arme que vous vouliez. Depuis le tout d\u00e9but de l&rsquo;existence du deuxi\u00e8me amendement, certaines personnes n&rsquo;\u00e9taient pas autoris\u00e9es \u00e0 poss\u00e9der des armes. Il est donc tout simplement bizarre de sugg\u00e9rer que certaines des choses que nous recommandons sont contraires \u00e0 la Constitution\u00a0\u00bb<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Les premi\u00e8res r\u00e9actions enregistr\u00e9es de gouverneurs (\u00e9videmment r\u00e9publicains) sont les suivantes :<\/p>\n<\/p>\n<p><p>&bull; Nouveau projet de loi du gouverneur de l&rsquo;Arizona, Doug Ducey, sign\u00e9 <a href=\"https:\/\/www.fox10phoenix.com\/news\/arizona-governor-signs-second-amendment-freedom-act-protecting-state-from-federal-gun-laws\">jeudi<\/a>. Il s&rsquo;agit d&rsquo;une loi g\u00e9n\u00e9rale et radicale, destin\u00e9e \u00e0 bloquer &laquo; <em>toute restriction f\u00e9d\u00e9rale contre le deuxi\u00e8me amendement dans l&rsquo;&Eacute;tat<\/em> &raquo;.<\/p>\n<\/p>\n<p><p>&bull; Dans le Tennessee, le gouverneur Bill Lee signe le m\u00eame jour un projet de loi autorisant les habitants de l&rsquo;&Eacute;tat \u00e0 porter des armes de poing, dissimul\u00e9es ou visibles, sans permis n\u00e9cessaire.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>J&rsquo;ai sign\u00e9 cette autorisation constitutionnelle ce jour pr\u00e9cis\u00e9ment <\/em>[o&ugrave; Biden annonce son d\u00e9cret] <em>pour signifier aux habitants du Tennessee et \u00e0 tout autre qu&rsquo;il n&rsquo;existe <\/em>[dans cet &Eacute;tat] <em>aucun obstacle \u00e0 l&rsquo;exercice de leurs droits<\/em> [selon le Deuxi\u00e8me Amendement] &raquo;, \u00e9crit Lee dans un tweet. &laquo; <em>Remerciements aux membres de l&rsquo;Assembl\u00e9e g\u00e9n\u00e9rale de la l\u00e9gislature et de la National Rifle Association, d&rsquo;avoir aid\u00e9 \u00e0 obtenir ce r\u00e9sultat<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>&bull; Le gouverneur de l&rsquo;Oklahoma Kevin Stitt, <a href=\"https:\/\/www.foxbusiness.com\/politics\/oklahoma-gov-stitt-blasts-bidens-gun-control-plans-as-total-overreach-by-federal-government\">a qualifi\u00e9<\/a> les plans de contr\u00f4le des armes \u00e0 feu de Biden, d&rsquo;&laquo; <em>abus complet du pouvoir f\u00e9d\u00e9ral<\/em> &raquo; et a promis une riposte sous forme de loi de l&rsquo;&Eacute;tat.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>Ce qui se passe \u00e0 D.C. est d\u00e9solant,  avec cet esprit partisan dont fait preuve le pr\u00e9sident<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>Notre mode de vie dans l&rsquo;Oklahoma est quelque chose de pr\u00e9cieux que j&rsquo;entends prot\u00e9ger&#8230; Il y a des manigances en cours pour empi\u00e9ter sur notre pouvoir et tenter de retirer leurs droits aux citoyens en Oklahoma. Nous croyons aux libert\u00e9s et \u00e0 la responsabilit\u00e9 personnelle et c&rsquo;est ce que je d\u00e9fendrai en tant que gouverneur<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>&bull; Le gouverneur du Texas Greg Abbott qualifie l&rsquo;intervention de Biden de &laquo; <em>coup de force lib\u00e9ral<\/em> [progressiste] <em>visant \u00e0 nous priver de nos armes<\/em>&hellip; <\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>Nous ne permettrons PAS cela au Texas<\/em> &raquo; \u00e9crit Abbott sur son <a href=\"https:\/\/twitter.com\/GregAbbott_TX\/status\/1380200140439498754\">tweet<\/a>. &laquo; <em>Le temps est venu de r\u00e9diger une loi faisant du Texas un &Eacute;tat sanctuaire du Deuxi\u00e8me amendement et de la d\u00e9poser sur mon bureau pour signature<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>&bull; Pour le gouverneur de l&rsquo;Alaska <a href=\"https:\/\/twitter.com\/GovDunleavy\/status\/1380252138102644738\">Mike Dunleavy<\/a>, les d\u00e9crets de Biden &laquo; <em>ne sauveront pas de vies et n&rsquo;arr\u00eateront pas les criminels<\/em> &raquo;.<\/p>\n<\/p>\n<p><p>&bull; Kim Reynolds, gouverneur de l&rsquo;Iowa, a \u00e9crit <a href=\"https:\/\/www.dailywire.com\/news\/multiple-governors-signal-they-wont-put-up-with-bidens-second-amendment-attack-out-of-control\">une longue tirade<\/a> contre Biden et la situation du gouvernement f\u00e9d\u00e9ral, d\u00e9passant largement le cadre des seules lois sur la possession et le port d&rsquo;armes :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>Je pense que la situation est hors de contr\u00f4le. Il est \u00e9vident qu&rsquo;ils ne peuvent pas faire passer leurs lois par le Congr\u00e8s, alors Biden agit par d\u00e9crets, de son propre chef, et il le fait \u00e0 un rythme effr\u00e9n\u00e9. Je ne pense pas qu&rsquo;il y ait eu un autre pr\u00e9sident dans l&rsquo;histoire qui ait mis en &oelig;uvre un tel nombre de d\u00e9crets que ce pr\u00e9sident a mis en &oelig;uvre aussi rapidement. C&rsquo;est une hypocrisie compl\u00e8te de se pr\u00e9senter comme un unificateur et un pr\u00e9sident rassembleur des deux partis pour sauver ce pays, et d&rsquo;agir comme il le fait. Il continue \u00e0 diviser le pays et il le fait d&rsquo;une fa\u00e7on provocante, avec tous ces d\u00e9crets abracadabrants<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>On voit que, cette fois, encore plus qu&rsquo;avec ses d\u00e9crets concernant l&rsquo;immigration ill\u00e9gale qui ne concernaient <a href=\"https:\/\/www.dedefensa.org\/article\/rapsit-usa2021-le-texit-sapproprie-son-sud\">que les &Eacute;tats-fronti\u00e8re<\/a>, Biden a provoqu\u00e9 une r\u00e9action qui devrait s&rsquo;amplifier et sans doute toucher les 27 &Eacute;tats qui ont des gouverneurs r\u00e9publicains. Si l&rsquo;on tient compte des positions des uns et des autres, on peut envisager qu&rsquo;il s&rsquo;agit du d\u00e9but d&rsquo;une \u00e9preuve de force o&ugrave; le langage employ\u00e9 est celui de la s\u00e9cession contre le pouvoir f\u00e9d\u00e9ral central.<\/p>\n<\/p>\n<p><p>Il y a effectivement deux aspects dans cette affaire : le cas lui-m\u00eame de la possession et du port d&rsquo;armes \u00e0 feu, devenu extr\u00eamement sensible pour les r\u00e9publicains (surtout les trumpistes et les populistes) qui soup\u00e7onnent le pouvoir d\u00e9mocrate de vouloir les priver de leurs armes pour mieux les contraindre \u00e0 suivre une politique radicalement nouvelle en mati\u00e8re de m&oelig;urs, de droits, d&rsquo;interf\u00e9rences dans la vie priv\u00e9e et associative, etc., &ndash; bref, tout ce qui caract\u00e9rise le wokenisme. Au-del\u00e0, le deuxi\u00e8me aspect est celui de la pr\u00e9valence des pouvoirs, celui des &Eacute;tats sur leurs territoires, contre le pouvoir f\u00e9d\u00e9ral de DC sur tout le territoire de l&rsquo;Union ; et, dans ce cas, le r\u00f4le capital des gouverneurs, d\u00e9j\u00e0 soulign\u00e9s par nous \u00e0 plusieurs reprises, est d\u00e9montr\u00e9.<\/p>\n<\/p>\n<p><p>En g\u00e9n\u00e9ral, aux Etats-Unis et dans les pays \u00e0 r\u00e9gime f\u00e9d\u00e9ral, ces affrontements sont contenus et contr\u00f4l\u00e9s lorsque et parce que la situation politique est bonne au compromis, et les divergences mineures. On comprend que c&rsquo;est, aujourd&rsquo;hui, l&rsquo;exact contraire, et la question de la possession et du port d&rsquo;armes par les citoyens est \u00ab\u00a0parfaite\u00a0\u00bb pour op\u00e9rationnaliser le conflit.<\/p>\n<\/p>\n<p><p>Plusieurs remarques peuvent alors \u00eatre \u00e9nonc\u00e9es.<\/p>\n<\/p>\n<p><p>&bull; D&rsquo;abord, le rapport de cause \u00e0 effet entre la vente libre des armes \u00e0 feu et la violence (la d\u00e9linquance et la violence \u00ab\u00a0de masse\u00a0\u00bb) n&rsquo;est pas \u00e9vidente. Le cas de la d\u00e9budg\u00e9tisation de nombre de polices dans les &Eacute;tats et villes d\u00e9mocrates, la r\u00e9duction de la pr\u00e9sence de policiers arm\u00e9s, etc., suite de la campagne post-Loyd de caillassage des <em>Black Lives Matter <\/em>(BLM), conduisent \u00e0 une explosion de d\u00e9linquance ; bref, la r\u00e9duction des armes \u00e0 feu engendre \u00e9videmment l&rsquo;accroissement vertigineux des d\u00e9lits, dont les crimes de sang. Tout cela situe l&rsquo;atmosph\u00e8re du d\u00e9bat, son ambigu\u00eft\u00e9, l&rsquo;impossibilit\u00e9 de rapprocher les positions antagonistes.<\/p>\n<\/p>\n<p><p>&bull; Si les &Eacute;tats r\u00e9publicains promulguent des lois contredisant les d\u00e9crets Biden, on va se trouver avec une Am\u00e9rique divis\u00e9e en deux, non plus symboliquement et psychologiquement, mais op\u00e9rationnellement, dans la vie courante et la violence habituelle. C&rsquo;est l&rsquo;amorce d&rsquo;une sorte de \u00ab\u00a0s\u00e9paratisme\u00a0\u00bb (on aime bien ce mot en France) ou de s\u00e9cession <em>de facto<\/em>, qui ne peut pas ne pas avoir d&rsquo;effets au niveau de la politique nationale et de la situation int\u00e9rieure d\u00e9j\u00e0 tr\u00e8s tendue et fractur\u00e9e.<\/p>\n<\/p>\n<p><p>&bull; Les lois des &Eacute;tats r\u00e9duisant \u00e0 n\u00e9ant sur leurs territoires les d\u00e9crets de Biden, l&rsquo;effet de ces d\u00e9crets devient nul en th\u00e9orie (selon une interpr\u00e9tation favorable aux &Eacute;tats). En effet, ce qui importe d&rsquo;abord (et ce qui est le but ultime des d\u00e9mocrates), c&rsquo;est l&rsquo;acquisition libre d&rsquo;armes \u00e0 feu : qui ne peut acqu\u00e9rir une arme en Californie peut aller en acheter une en Arizona.<\/p>\n<\/p>\n<p><p>&bull; D&rsquo;o&ugrave; une premi\u00e8re s\u00e9rie de questions fondamentales qui se posent, ouvrant la cat\u00e9gorie des questions porteuses de tous les conflits possibles. Quelle est le loi qui a pr\u00e9valence : celle du gouverneur ou celle du pr\u00e9sident ? Faudra-t-il aller devant la Cour Supr\u00eame, et quel parti perdant dans cette affaire acceptera une d\u00e9cision de la Cour Supr\u00eame, si celle-ci accepte seulement de statuer ? (&Eacute;ventuellement, cela peut activer les projets d\u00e9mocrate de <a href=\"https:\/\/sputniknews.com\/us\/202104101082590353-biden-mocked-after-video-of-his-calling-us-supreme-court-packing-bonehead-idea-resurfaces-online\/\">refonte compl\u00e8te<\/a> de la Cour, dont nombre de r\u00e9publicains estiment que ce serait un cas majeur de guerre civile.)<\/p>\n<\/p>\n<p><p>&bull; Il y a aussi des questions fondamentales au niveau op\u00e9rationnel. Faut-il envisager des \u00ab\u00a0fronti\u00e8res\u00a0\u00bb entre les &Eacute;tats de tendance diff\u00e9rence, pour surveiller la possession d&rsquo;armes ? Les organismes de surveillance et de r\u00e9pression f\u00e9d\u00e9raux, comme le FBI, pourraient-ils intervenir dans les &Eacute;tats qui se sont prononc\u00e9s contre les d\u00e9crets Biden, pour les y faire appliquer ? On ne voit pas un gouverneur ayant fait voter sa loi anti-Biden accepter cela, sinon \u00e0 se mettre dans une position intenable dans son &Eacute;tat ; et voit-on Biden, appuy\u00e9 par les hordes wokenistes, reculer devant de telles violations de son autorit\u00e9 et de son programme ?<\/p>\n<\/p>\n<blockquote>\n<p><p>Les sc\u00e9narios vont \u00e0 l&rsquo;infini, dans ce pays o&ugrave; la Constitution est extr\u00eamement vague quant \u00e0 la pr\u00e9valence des diff\u00e9rents pouvoirs. Parmi les tr\u00e8s nombreux conflits qu&rsquo;engendrent les d\u00e9cisions radicales de l&rsquo;administration Biden, celles qui concernent les armes \u00e0 feu occupe une bonne position pour, disons, mettre le feu aux poudres.<\/p>\n<\/p>\n<\/blockquote>\n<\/p>\n<p><p>Mis en ligne le 10 avril 2021 \u00e0 16H00<\/p>\n<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>RapSit-USA2021 : Gouverneurs en armes Un certain nombre de gouverneurs d&rsquo;Etat (des r\u00e9publicains pour l&rsquo;instant) ont r\u00e9agi au discours de jeudi du pr\u00e9sident Biden sur diverses mesures limitant et contr\u00f4lant le port et la possession d&rsquo;armes \u00e0 feu. Les arguments contre cette attaque sur la question de la possession d&rsquo;armes \u00e0 feu sont connus :&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[21],"tags":[831,19599,7664,3992,1235,9654,2631,4889,5786,9466,3769,2949,13317,3421],"class_list":["post-79719","post","type-post","status-publish","format-standard","hentry","category-breves-de-crise","tag-a","tag-alaska","tag-arizona","tag-armes","tag-biden","tag-conflits","tag-de","tag-etats","tag-feu","tag-oklahoma","tag-pouvoir","tag-secession","tag-tennessee","tag-texas"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79719"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79719\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79719"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79719"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}