{"id":79752,"date":"2021-05-07T14:46:17","date_gmt":"2021-05-07T14:46:17","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2021\/05\/07\/une-menace-nucleaire-tres-intelligente\/"},"modified":"2021-05-07T14:46:17","modified_gmt":"2021-05-07T14:46:17","slug":"une-menace-nucleaire-tres-intelligente","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2021\/05\/07\/une-menace-nucleaire-tres-intelligente\/","title":{"rendered":"Une menace nucl\u00e9aire \u201ctr\u00e8s intelligente\u201d"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Une menace nucl\u00e9aire \u00ab\u00a0tr\u00e8s intelligente\u00a0\u00bb<\/h2>\n<\/p>\n<blockquote>\n<p><p>&bull; Confidence <strong>tr\u00e8s alarm\u00e9e<\/strong> du vieux Kissinger : une guerre nucl\u00e9aire d&rsquo;an\u00e9antissement est aujourd&rsquo;hui <strong>beaucoup plus possible que pendant la Guerre Froide<\/strong>. &bull; En cause : l&rsquo;intervention tr\u00e8s importante de la technologie <strong>(Intelligence Artificielle) dans la prise de d\u00e9cision<\/strong>. &bull; En m\u00eame temps, le Pentagone, tr\u00e8s affaibli, a pris le pr\u00e9sident Biden par la main pour lui faire signer un trait\u00e9 garantissant la d\u00e9fense du Japon (et de Taiwan ?) par le nucl\u00e9aire. &bull; En cause : <strong>la d\u00e9gradation dramatique des capacit\u00e9s US dans le domaine conventionnel face \u00e0 la Chine<\/strong>.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>La vieille crapule qu&rsquo;est par nature et forfaits divers Henry Kissinger, incroyablement vieilli (97 ans) mais pas encore g\u00e2teux, continue \u00e0 avoir une parole qui compte. Cela se passait cette semaine lors d&rsquo;un \u00ab\u00a0<em>webinaire<\/em>\u00a0\u00bb (s\u00e9minaire virtuel, traduit-on, via les outils des r\u00e9seaux) organis\u00e9 dans le cadre du Sedona Forum de l&rsquo;Institut McCain. Kissinger a \u00e9voqu\u00e9 une tr\u00e8s grave menace de guerre nucl\u00e9aire, notamment entre la Chine et les USA, une menace de guerre nucl\u00e9aire potentiellement plus grave que celles qui exist\u00e8rent durant la Guerre Froide.<\/p>\n<\/p>\n<p><p>Certes, la Chine et les USA sont en cause, mais Kissinger parle d&rsquo;abord d&rsquo;un probl\u00e8me de d\u00e9cision d&rsquo;engager une telle guerre, avec l&rsquo;intervention des technologies avanc\u00e9es ; il parle sans doute principalement pour les USA, et notamment avec l&rsquo;autorit\u00e9 du fait qu&rsquo;il reste une personne inform\u00e9e des \u00ab\u00a0progr\u00e8s\u00a0\u00bb en ces mati\u00e8res, en raison des positions qu&rsquo;il a occup\u00e9es qui lui donnent droit \u00e0 l&rsquo;acc\u00e8s \u00e0 des informations confidentielles. Ainsi peut-il dire que le conflit potentiel entre la Chine et les USA (qu&rsquo;il semble juger plus aigu qu&rsquo;entre la Russie et les USA, qui entre dans la m\u00eame cat\u00e9gorie des potentialit\u00e9s) pourrait \u00eatre bien plus catastrophique que cette sorte de situation durant la Guerre Froide. C&rsquo;est, dit-il &laquo; <em>le plus gros probl\u00e8me pour l&rsquo;Am\u00e9rique, le plus gros probl\u00e8me pour le monde<\/em> &raquo;.<\/p>\n<\/p>\n<p><p>RT.com nous dit <a href=\"https:\/\/www.rt.com\/op-ed\/522952-kissinger-nuclear-danger-us-china\/\">quelques mots<\/a> l\u00e0-dessus :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p><em>&laquo; Comment est-ce possible, peut-on se demander ? La premi\u00e8re guerre froide ne s&rsquo;est-elle pas accompagn\u00e9e de menaces d&rsquo;immense destruction dans l&rsquo;\u00e9ventualit\u00e9 d&rsquo;un conflit nucl\u00e9aire mutuel entre USA et URSS ? En quoi celle-ci pourrait-elle \u00eatre pire ? Kissinger<\/em> [&#8230;] <em>a fait valoir que, malgr\u00e9 ces parall\u00e8les, les progr\u00e8s technologiques signifient que les capacit\u00e9s des deux pays \u00e0 se d\u00e9truire mutuellement, et avec cela le reste du monde, sont bien plus importantes que celles des ann\u00e9es 1960 ou 1970.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0Pour la premi\u00e8re fois dans son histoire, l&rsquo;humanit\u00e9 a la capacit\u00e9 de s&rsquo;\u00e9teindre elle-m\u00eame dans un laps de temps fini\u00a0\u00bb, a d\u00e9clar\u00e9 Kissinger, <\/em>[&#8230;] <em>soulignant qu&rsquo;\u00e0 \u00ab\u00a0la question nucl\u00e9aire s&rsquo;ajoute la question de la haute technologie, qui, dans le domaine de l&rsquo;intelligence artificielle, repose essentiellement sur le fait que l&rsquo;homme devient un partenaire des machines et que les machines peuvent d\u00e9velopper leur propre jugement.\u00a0\u00bb Il ne s&rsquo;agit pas seulement de missiles nucl\u00e9aires, comme \u00e0 l&rsquo;\u00e9poque de l&rsquo;Am\u00e9rique et de l&rsquo;Union Sovi\u00e9tique, mais aussi de la capacit\u00e9 des technologies avanc\u00e9es \u00e0 r\u00e9-imaginer et \u00e0 affiner la guerre d&rsquo;une mani\u00e8re qui n&rsquo;avait pas \u00e9t\u00e9 con\u00e7ue auparavant<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>C&rsquo;est-\u00e0-dire, si l&rsquo;on comprend bien, que l&rsquo;intervention des capacit\u00e9s d&rsquo;interpr\u00e9tation, de jugement, \u00e0 la limite de la d\u00e9cision, des technologies de l&rsquo;IA, joueraient et joueront un r\u00f4le essentiel dans la d\u00e9cision d&#8217;emploi du nucl\u00e9aire dans le cas d&rsquo;une situation pr\u00e9-conflictuelle plac\u00e9e devant cette possibilit\u00e9. C&rsquo;est-\u00e0-dire, encore et si l&rsquo;on comprend toujours, que l&rsquo;IA venue des machines auraient beaucoup plus \u00ab\u00a0les tripes\u00a0\u00bb de recommander sinon d&rsquo;induire une d\u00e9cisions d&#8217;emploi du nucl\u00e9aire, que les pauvres esprits humains encombr\u00e9s de consid\u00e9rations humanitaires et autres. C&rsquo;est-\u00e0-dire enfin que si l&rsquo;IA avait exist\u00e9 au niveau qu&rsquo;indique Kissinger en octobre 1962, bien entendu nous aurions eu la guerre. Grande satisfaction des bureaucraties impliqu\u00e9es, notamment celles de SRATCOM (<em>Strategic Command<\/em>) h\u00e9riti\u00e8res de l&rsquo;esprit du <em>Strategic Air Command <\/em>(SAC), cr\u00e9ation jalousement favoris\u00e9e du <a href=\"https:\/\/www.dedefensa.org\/article\/ecrire-la-guerre-froide\">g\u00e9n\u00e9ral LeMay<\/a>. Dans un article paru en 2009, Daniel Ellsberg, l&rsquo;homme des \u00ab\u00a0<em>Pentagon Papers<\/em>\u00ab\u00a0, avait donn\u00e9 <a href=\"https:\/\/www.dedefensa.org\/article\/pour-600-millions-de-morts-de-plus\">un aper\u00e7u de l&rsquo;\u00e9tat d&rsquo;esprit<\/a> de la bureaucratie du SAC (et l&rsquo;obsessions de l'\u00a0\u00bb<em>overkill<\/em>\u00ab\u00a0, &ndash; sur-tuer ou \u00ab\u00a0tuer plusieurs fois\u00a0\u00bb), notamment \u00e0 partir de divers documents officiels auxquels il avait eu acc\u00e8s :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>Le document rappelle \u00e9galement une remarque, datant de d\u00e9cembre 1980, de l&rsquo;amiral Roy L. Johnson, Deputy Director of Joint Strategic Target Planning Staff de 1961 \u00e0 1963, effectivement \u00e0 cette \u00e9poque de la toute-puissance de l&rsquo;\u00e9quipe LeMay-Poser sur la pens\u00e9e strat\u00e9gique US: \u00ab\u00a0Les gens du SAC ne semblaient jamais pouvoir accepter l&rsquo;id\u00e9e que tuer une fois serait suffisant. Ils voulaient tuer, sur-tuer, sur-tuer encore, parce que tout cela a construit le prestige du SAC, cela a cr\u00e9\u00e9 le besoin de plus de forces, d&rsquo;un plus grand budget<\/em>. [&#8230;] <em>C&rsquo;est comme \u00e7a qu&rsquo;ils pensaient.\u00a0\u00bb<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><h2 class=\"titleset_c.deepblue\" style=\"color:#0f3955; font-size:1.25em\">Exercice pratique : le Japon<\/h2>\n<\/p>\n<p><p>L&rsquo;on comprend donc bien que l'\u00a0\u00bbintelligence\u00a0\u00bb (artificielle mais qu&rsquo;importe, cr\u00e9ation humaine apr\u00e8s tout) semble en selle pour pousser jusqu&rsquo;\u00e0 presque son terme une menace de guerre nucl\u00e9aire. Certes, c&rsquo;est en th\u00e9orie que nous parle Kissinger, bien qu&rsquo;il mentionne la Chine et les USA ; mais voil\u00e0 qu&rsquo;il se trouve qu&rsquo;un exercice pratique est en cours, et il ne nous \u00e9tonnerait pas que Kissinger se soit senti oblig\u00e9 de parler \u00e0 cause de cette circonstance qui rapproche si nettement la pratique de la th\u00e9orie, &ndash; <em>ditto<\/em>, l&rsquo;accord entre le Japon et les USA, du 16 avril dernier.<\/p>\n<\/p>\n<p><p><a href=\"https:\/\/www.strategic-culture.org\/news\/2021\/05\/04\/nuclear-climate-change-washington-heats-things-up\/\">Le 4 mai<\/a>, Brian Cloughley a consacr\u00e9 une analyse \u00e0 cet accord entre le Japon et les USA. Cloughley consacre la premi\u00e8re partie de cet article aux projets de STRATCOM d&rsquo;expansion de ses capacit\u00e9s nucl\u00e9aires, &ndash; travail sans fin, bien entendu, &ndash; conform\u00e9ment \u00e0 l&rsquo;esprit de la bureaucratie-SAC, bien entendu :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; &#8230;[E]<em>t au lieu d&rsquo;essayer de faire appel \u00e0 leurs esprits indubitablement dou\u00e9s pour concevoir des moyens de r\u00e9duire cette menace, les planificateurs et les promoteurs<\/em> [de STRACOM] <em>et du Pentagone, soutenus \u00e0 bout de bras par des politiciens et d&rsquo;autres personnes ayant des int\u00e9r\u00eats financiers dans la production d&rsquo;armes, ont l&rsquo;intention d&rsquo;\u00e9tendre la puissance nucl\u00e9aire de l&rsquo;Am\u00e9rique dans le monde entier et dans l&rsquo;espace<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Suit un long passage sur une d\u00e9position au Congr\u00e8s le 20 avril de l&rsquo;amiral Charles Richard, commandant STRATCOM, pour convaincre des convertis (les parlementaires) de la terrible menace nucl\u00e9aire que repr\u00e9sente la Chine (320 munitions nucl\u00e9aires contre 5 800 pour les USA), et du fait que la Chine ne donne gu\u00e8re de publicit\u00e9 sur ses projets d&rsquo;expansion de ce domaine :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>Peu importe que les &Eacute;tats-Unis, comme l&rsquo;indique<\/em> [l&rsquo;institut su\u00e9dois] <em>SIPRI, aient \u00ab\u00a0mis fin \u00e0 la pratique consistant \u00e0 divulguer publiquement la taille de leur stock\u00a0\u00bb, mais on attend de toutes les autres nations qu&rsquo;elles fassent preuve d&rsquo;une transparence absolue sur leurs programmes nucl\u00e9aires (Isra\u00ebl compris ?)<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>L\u00e0-dessus, Cloughley passe \u00e0 la deuxi\u00e8me partie de son analyse, qui concerne l&rsquo;accord entre les USA et le Japon, qui vient d&rsquo;\u00eatre sign\u00e9 le 16 avril.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>Il y a cependant un aspect de la politique nucl\u00e9aire sur lequel Washington est transparent, et cela a \u00e9t\u00e9 clairement exprim\u00e9 lorsque le pr\u00e9sident Biden a rencontr\u00e9 le Premier ministre japonais Yoshihide Suga \u00e0 la Maison Blanche le 16 avril. Leur <a href=\"https:\/\/www.whitehouse.gov\/briefing-room\/statements-releases\/2021\/04\/16\/u-s-japan-joint-leaders-statement-u-s-japan-global-partnership-for-a-new-era\/\">d\u00e9claration commune<\/a>, intitul\u00e9e \u00ab\u00a0U.S.-Japan Global Partnership for a New Era\u00a0\u00bb, est \u00e0 ce jour l&rsquo;indication la plus significative que Biden a r\u00e9solument approuv\u00e9 la volont\u00e9 de longue date de Washington de s&rsquo;engager \u00e9ventuellement dans une guerre nucl\u00e9aire. Ce document gla\u00e7ant ne donne aucune indication qu&rsquo;il puisse y avoir un jour une possibilit\u00e9 de compromis avec la Chine sur quelque sujet que ce soit et il est conflictuel au plus haut point concernant ce que Biden et Suga savent tr\u00e8s bien \u00eatre une pierre angulaire de la politique internationale de la Chine : son affirmation de souverainet\u00e9 sur les &icirc;les de la mer de Chine m\u00e9ridionale.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>La position des &Eacute;tats-Unis \u00e0 l&rsquo;\u00e9gard de la mer de Chine m\u00e9ridionale se fonde, selon Washington, sur le droit international, et la d\u00e9claration de Biden et Suga sur la confrontation avec la Chine met l&rsquo;accent sur l&rsquo;accord visant \u00e0 \u00ab\u00a0promouvoir des normes communes dans le domaine maritime, y compris la libert\u00e9 de navigation et de survol, telles que consacr\u00e9es par la Convention des Nations unies sur le droit de la mer (UNCLOS)\u00a0\u00bb. Cette d\u00e9claration pourrait \u00eatre accept\u00e9e comme justifi\u00e9e si les &Eacute;tats-Unis d&rsquo;Am\u00e9rique n&rsquo;avaient pas refus\u00e9 de ratifier l&rsquo;UNCLOS, \u00e0 l&rsquo;instar d&rsquo;&Eacute;tats comme l&rsquo;Iran, Isra\u00ebl, la Syrie, la Cor\u00e9e du Nord et la Libye. Biden ordonne aux autres nations de mener leurs affaires maritimes conform\u00e9ment \u00e0 un important accord international que Washington a rejet\u00e9.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Cette situation serait absurde et risible si Biden n&rsquo;affirmait pas qu&rsquo;il engagerait si n\u00e9cessaire les &Eacute;tats-Unis dans une guerre pour soutenir le Japon, et que, par d\u00e9finition, l&rsquo;UNCLOS pourrait servir de justification \u00e0 cette guerre. M. Biden <a href=\"https:\/\/www.whitehouse.gov\/briefing-room\/speeches-remarks\/2021\/04\/16\/remarks-by-president-biden-and-prime-minister-suga-of-japan-at-press-conference\/\" target=\"_blank\">d\u00e9clare<\/a> effectivement son \u00ab\u00a0soutien ind\u00e9fectible \u00e0 l&rsquo;alliance am\u00e9ricano-japonaise et \u00e0 notre s\u00e9curit\u00e9 commune\u00a0\u00bb et pr\u00e9cise que Washington et Tokyo sont \u00ab\u00a0d\u00e9termin\u00e9s \u00e0 travailler ensemble pour relever les d\u00e9fis pos\u00e9s par la Chine et des questions telles que la mer de Chine orientale, la mer de Chine m\u00e9ridionale, ainsi que la Cor\u00e9e du Nord\u00a0\u00bb. Le point fort de la d\u00e9claration conjointe est la notification du \u00ab\u00a0soutien in\u00e9branlable de Washington \u00e0 la d\u00e9fense du Japon dans le cadre du trait\u00e9 de coop\u00e9ration et de s\u00e9curit\u00e9 mutuelles entre les &Eacute;tats-Unis et le Japon, en utilisant toute la gamme de ses capacit\u00e9s, y compris nucl\u00e9aires\u00a0\u00bb. Les mots essentiels sont : \u00ab\u00a0y compris nucl\u00e9aire\u00a0\u00bb.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>L&rsquo;\u00e9p\u00e9e ultime a \u00e9t\u00e9 brandie. Le 16 avril, le pr\u00e9sident am\u00e9ricain a menac\u00e9 sans ambages d&rsquo;utiliser des armes nucl\u00e9aires contre la Chine et, quatre jours plus tard, le chef du commandement strat\u00e9gique a insist\u00e9 aupr\u00e8s du S\u00e9nat pour qu&rsquo;il approuve les 95 $milliards d\u00e9pens\u00e9spour le nouveau \u00ab\u00a0dissuasif strat\u00e9gique terrestre\u00a0\u00bb destin\u00e9 \u00e0 remplacer les centaines de missiles balistiques intercontinentaux Minuteman qui sont en \u00e9tat d&rsquo;alerte permanent pour d\u00e9truire des villes en Russie et en Chine.<\/em>&raquo; [Dans ce contexte de la signature de l&rsquo;accord USA-Japon],<em> il ne fut pas surprenant de lire un \u00e9ditorial (semi-officiel) dans le Global Times de Chine observant que Washington et Tokyo \u00ab\u00a0tentent de faire de la confrontation le th\u00e8me principal de toute la r\u00e9gion\u00a0\u00bb. Cela semble \u00eatre la politique suivie, et l&rsquo;accent mis par Washington sur les armes nucl\u00e9aires a tr\u00e8s fortement aggrav\u00e9 le climat de confrontation. Nous nous sommes rapproch\u00e9s encore un peu plus de la destruction de la plan\u00e8te<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Bien entendu, tout cela n&rsquo;a rien \u00e0 voir avec Biden, qui est dans l&rsquo;\u00e9tat qu&rsquo;on sait, et tout avec les bureaucraties du Pentagone et leurs adjoints experts-guerriers et autres suppl\u00e9tifs. Ce n&rsquo;est pas un hasard si, d\u00e9sormais, le Pentagone et tous les commandements des forces mettent en avant la possibilit\u00e9 d&rsquo;une guerre nucl\u00e9aire, et l&rsquo;absence de r\u00e9ticence des directions militaires US pour une telle perspective, et cela notamment dans cette zone strat\u00e9gique de confrontation avec la Chine. On a vu que les plus r\u00e9centes simulations et man&oelig;uvres \u00e0 propos de Taiwan mettent en \u00e9vidence que les forces arm\u00e9es US, qui se sont auto-proclam\u00e9es garantes de l&rsquo;int\u00e9gralit\u00e9 de l&rsquo;&icirc;le, seraient battues si elles avaient \u00e0 affronter les forces chinoises d&rsquo;invasion. Le seul moyen d&rsquo;\u00e9viter une telle horrible catastrophe est l&#8217;emploi du nucl\u00e9aire<\/p>\n<\/p>\n<p><p>Le probl\u00e8me serait \u00e0 peu pr\u00e8s similaire dans l&rsquo;hypoth\u00e8se du Japon comme dans toutes celles qui concernent des alli\u00e9s des USA, &ndash; \u00e9tant \u00e9videmment admis, dans l&rsquo;esprit des experts du Pentagone, que la Chine ne r\u00eavent que d&rsquo;une ou deux choses de cette sorte : mettre \u00e0 feu et \u00e0 sang toute la zone et conqu\u00e9rir toutes les terres et nations qui la composent. Contre cette menace suppos\u00e9e, et lourdement suppos\u00e9e, avec la plus grande insistance, les forces US ne font plus du tout le poids, comme elles s&rsquo;en sont avis\u00e9es. Alors, elles introduisent le param\u00e8tre nucl\u00e9aire, et en menacent la Chine, comme elles en menacent la Russie \u00e9galement en d&rsquo;autres occasions. Il y a diverses psychologies \u00e0 l&rsquo;&oelig;uvre dans cette attitude qui peut sembler bien extr\u00eame :<\/p>\n<\/p>\n<p><p>&bull; La crainte de l&rsquo;usage du nucl\u00e9aire <em>per se<\/em> (destruction mutuelle assur\u00e9e) chez leurs adversaires potentiels, qui devrait faire reculer ces adversaires devant la possibilit\u00e9 d&rsquo;exp\u00e9ditions militaires non-nucl\u00e9aires contre lesquelles les USA ne font plus le poids si l&rsquo;on en reste au conventionnel, et que les USA se proposent de contrer justement avec du nucl\u00e9aire ;<\/p>\n<p>&bull; normalement, les USA devraient \u00e9prouver la m\u00eame crainte qui est commune puisqu&rsquo;elle concerne un sort commun (destruction mutuelle assur\u00e9e), mais les bureaucraties washingtoniennes impliqu\u00e9es s&rsquo;en dispensent, gr\u00e2ce au mode d&rsquo;action et \u00e0 l&rsquo;irr\u00e9sistibilit\u00e9 des psychologies triomphantes de l&rsquo;am\u00e9ricanisme (\u00ab\u00a0<a href=\"http:\/\/www.dedefensa.org\/article-l_inculpabilite_comme_fondement_de_la_psychologie_americaniste_06_05_2006.html\">inculpabilit\u00e9<\/a>\u00ab\u00a0, ou absence de perception de la possibilit\u00e9 de sa propre culpabilit\u00e9 ; \u00ab\u00a0<a href=\"http:\/\/www.dedefensa.org\/article\/apres-linculpabilite-lindefectibilite\">ind\u00e9fectibilit\u00e9<\/a>\u00ab\u00a0, absence de la perception de la possibilit\u00e9 de sa propre inf\u00e9riorit\u00e9 et\/ou d\u00e9faite) ;<\/p>\n<p>&bull; au reste, le Pentagone envisage depuis plusieurs ann\u00e9es d&rsquo;utiliser le nucl\u00e9aire d&rsquo;une mani\u00e8re \u00ab\u00a0flexible\u00a0\u00bb, en mode tactique, en croyant pouvoir \u00e9viter de monter aux extr\u00eames de la guerre nucl\u00e9aire strat\u00e9gique d&rsquo;an\u00e9antissement, en rupture compl\u00e8te notamment avec la pens\u00e9e militaire russe \u00e0 cet \u00e9gard ;<\/p>\n<p>&bull; il est \u00e9vident que les machines si pleines d'\u00a0\u00bbintelligence artificielle\u00a0\u00bb, telles que signal\u00e9es par Kissinger, seraient l\u00e0 pour renforcer ces conceptions sur la possibilit\u00e9 d&rsquo;utiliser du nucl\u00e9aire dans de nombreuses circonstances et sans trop d&rsquo;encombvrantes pr\u00e9occupations humanitaires, et ainsi de r\u00e9affirmer l&rsquo;incontestable sup\u00e9riorit\u00e9 US puisque les autres se montrent si pusillanimes quant \u00e0 l&rsquo;usage de cette arme.<\/p>\n<\/p>\n<p><p>On attend la fin pour signaler <a href=\"https:\/\/www.zerohedge.com\/geopolitical\/white-house-says-we-support-ukraines-ambitions-join-nato\">la cerise sur le g\u00e2teau<\/a>, qui a une forme ukrainienne. Dans l&rsquo;avion pr\u00e9sidentiel, une porte-parole du pr\u00e9sident a affirm\u00e9 que le susdit pr\u00e9sident soutenait la candidature de l&rsquo;Ukraine pour entrer dans l&rsquo;OTAN. Le propos a ensuite \u00e9t\u00e9 att\u00e9nu\u00e9, comme l&rsquo;on passe du nucl\u00e9aire strat\u00e9gique au nucl\u00e9aire tactique. L&rsquo;Ukraine dans l&rsquo;OTAN, cela \u00e9quilibrerait bien, &ndash; \u00ab\u00a0en m\u00eame temps\u00a0\u00bb, formule fameuse, &ndash; une bagarre avec la Chine pour Ta\u00efwan ; bien entendu, avec toutes formes de nucl\u00e9aire envisageables.<\/p>\n<\/p>\n<p><p>Mis en ligne le 7 mai 2021 \u00e0 14H45<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une menace nucl\u00e9aire \u00ab\u00a0tr\u00e8s intelligente\u00a0\u00bb &bull; Confidence tr\u00e8s alarm\u00e9e du vieux Kissinger : une guerre nucl\u00e9aire d&rsquo;an\u00e9antissement est aujourd&rsquo;hui beaucoup plus possible que pendant la Guerre Froide. &bull; En cause : l&rsquo;intervention tr\u00e8s importante de la technologie (Intelligence Artificielle) dans la prise de d\u00e9cision. &bull; En m\u00eame temps, le Pentagone, tr\u00e8s affaibli, a pris le&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[2623,3977,2651,3147,2662,4662,3736,3004,2615,6417,2871,20908],"class_list":["post-79752","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-bureaucratie","tag-chine","tag-du","tag-ellsberg","tag-en","tag-japon","tag-kissinger","tag-nucleaire","tag-premier","tag-stratcom","tag-taiwan","tag-utilisation"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79752","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79752"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79752\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79752"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79752"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}