{"id":79756,"date":"2021-05-11T08:53:26","date_gmt":"2021-05-11T08:53:26","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2021\/05\/11\/panique-a-bord-1\/"},"modified":"2021-05-11T08:53:26","modified_gmt":"2021-05-11T08:53:26","slug":"panique-a-bord-1","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2021\/05\/11\/panique-a-bord-1\/","title":{"rendered":"Panique \u00e0 bord"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d;font-size:1.65em;font-variant:small-caps;\">Panique \u00e0 bord<\/h2>\n<\/p>\n<p><p>11 mai 2021 &ndash; Souvenir, souvenir&#8230; Un des \u00e9v\u00e9nements les plus importants pour moi dans l&rsquo;\u00e9lection de Mitterrand du 10 mai 1981, &ndash; je rappelle aux esprits l\u00e9gers qu&rsquo;elle eut 40 ans hier, &ndash; se situa \u00e0 l&rsquo;OTAN. A cette \u00e9poque, j&rsquo;\u00e9tais encore bien vu dans cette sympathique organisation qui n&rsquo;\u00e9tait pas encore envahie par tant d&rsquo;alli\u00e9s d&rsquo;infortune flairant le magot. J&rsquo;avais quelques bons amis, dont un bien plac\u00e9 \u00e0 la communication, un vieux dur-\u00e0-cuire parlant une bonne demi-douzaine de langues, et qui \u00e9tait d\u00e9j\u00e0 compl\u00e8tement de nationalit\u00e9 otanienne avant m\u00eame que tout ce bazar soit transf\u00e9r\u00e9 de France en Belgique. Il m&rsquo;avait pris en amiti\u00e9 et se fichait bien de mon orientation politique \u00e0 venir ; il y avait, comme \u00e7a, parfois, des vieux dur-\u00e0-cuire otanien qui ne vous saoulait pas avec le politiquement-correct de l&rsquo;OTAN. (*)<\/p>\n<\/p>\n<p><p>Pour lui, l&rsquo;\u00e9v\u00e9nement le plus important de cette \u00e9lection de Mitterrand fut la visite impromptue et terriblement amicale que lui rendit le vice-pr\u00e9sident George H.W. Bush (disons le VP Bush-p\u00e8re), le 24 juin. Quelques ann\u00e9es plus tard, \u00e9voquant vaguement ce souvenir, mon vieux dur-\u00e0-cuire otanien me glissa, \u00e9nigmatique et l&rsquo;air de rien : \u00ab\u00a0On l&rsquo;a \u00e9chapp\u00e9 belle\u00a0\u00bb. Cela demandait des explications et cela me valut un d\u00e9jeuner hors de la cantine du Quartier-G\u00e9n\u00e9ral, dans un joli restaurant d&rsquo;Evere.<\/p>\n<\/p>\n<p><p>Il faut se rappeler que cette \u00e9poque de l&rsquo;arriv\u00e9e de Mitterrand \u00e9tait terriblement tendue, pour plusieurs raisons. J&rsquo;en rappelle rapidement quelques-unes :<\/p>\n<\/p>\n<p><p>&bull; La Russie d&rsquo;alors, prisonni\u00e8re de l&rsquo;URSS, \u00e9tait engag\u00e9e militairement en Afghanistan depuis d\u00e9cembre 1979 ;<\/p>\n<p>&bull; depuis 1979, l&rsquo;Iran vivait sous la loi des mollahs et dans la mal\u00e9diction de l&rsquo;Occident ;<\/p>\n<p>&bull; depuis ao&ucirc;t 1980, la Pologne vivait dans la folie <em>Solidarnosc-<\/em>Walesa et l&rsquo;URSS s&rsquo;interrogeait \u00e0 propos d&rsquo;une intervention ;<\/p>\n<p>&bull; entre l&rsquo;URSS, l&rsquo;Europe et les USA grondait depuis 1977 et officiellement depuis 1979 (<a href=\"https:\/\/grip.org\/il-y-a-40-ans-debutait-la-crise-des-euromissiles\/\">double d\u00e9cision de l&rsquo;OTAN<\/a>) la plus grave crise de la fin de la Guerre Froide, celle des euromissiles, jusqu&rsquo;au paroxysme de 1983-1984, et brusquement interrompue par l&rsquo;entr\u00e9e en sc\u00e8ne de Gorbatchev, le 9 mars 1985.<\/p>\n<\/p>\n<p><p>C&rsquo;\u00e9tait alors une sacr\u00e9e, une incroyable tension qui mena\u00e7ait tout l&rsquo;\u00e9difice de l'\u00a0\u00bb\u00e9quilibre de la terreur\u00a0\u00bb et faisait craindre la possibilit\u00e9 d&rsquo;une guerre nucl\u00e9aire totale, que soulignaient les grandes manifestations pacifistes antinucl\u00e9aires, aux USA et en Europe (dans les deux Allemagnes) en 1981-1983. A cela s&rsquo;ajoutait, dans les coulisses et ce qu&rsquo;on sait moins, une tr\u00e8s difficile situation du pouvoir am\u00e9ricaniste.<\/p>\n<\/p>\n<p><p>L&rsquo;\u00e9lection de Reagan (entr\u00e9e en fonction en janvier 1981) signifiait un tournant radical vers une politique de s\u00e9curit\u00e9 nationale terriblement durcie. Cela impliquait la mise en place d&rsquo;une nouvelle \u00e9quipe, chacun des dirigeants devant trouver sa place et son territoire en se coordonnant avec les autres, puis la mise au point de cette nouvelle politique. Brutalement, tout l&rsquo;\u00e9chafaudage de l&rsquo;\u00e9difice en construction vacilla le 30 mars 1981, lorsqu&rsquo;un homme tira sur le pr\u00e9sident Reagan. Rapidement, on assura qu&rsquo;il s&rsquo;agissait d&rsquo;une blessure l\u00e9g\u00e8re alors que Reagan se trouvait encore et toujours sur le billard. On lui fit faire ensuite, quelques jours plus tard, quelques signes de la main de sa chambre d&rsquo;h\u00f4pital ; il quitta triomphalement ce m\u00eame h\u00f4pital pour sa convalescence le 17 avril, alors que sa popularit\u00e9 grimpait en fl\u00e8che. La r\u00e9alit\u00e9, on le sut plus tard, \u00e9tait que la blessure \u00e9tait s\u00e9rieuse, qu&rsquo;elle fut longue \u00e0 gu\u00e9rir hors de l&rsquo;h\u00f4pital, et m\u00eame, dirent certains, qu&rsquo;elle laissa des s\u00e9quelles.<\/p>\n<\/p>\n<p><p>Le jour de l&rsquo;attentat, il y eut un couac colossal. Le secr\u00e9taire d&rsquo;&Eacute;tat Haig prit sur lui d&rsquo;annoncer la nouvelle et conclut : &laquo; <em>I&rsquo;m in charge<\/em> &raquo;, comme s&rsquo;il \u00e9tait le rempla\u00e7ant temporaire de Reagan. En r\u00e9alit\u00e9, le ministre des affaires \u00e9rtrang\u00e8rees, ou secr\u00e9taire d&rsquo;&Eacute;tat,  est le troisi\u00e8me sur la liste de succession (temporaire dans ce cas) en cas d&rsquo;incapacit\u00e9 temporaire ou d\u00e9finitive du pr\u00e9sident, le vice-pr\u00e9sident et le <em>Speaker <\/em>de la Chambre \u00e9tant le premier et le second. Tous les deux \u00e9taient parfaitement disponibles pour cet int\u00e9rim, et particuli\u00e8rement Bush-p\u00e8re, en tant que VP. Il s&rsquo;ensuivit une p\u00e9riode tr\u00e8s incertaine de plusieurs semaines ; rapidement tout de m\u00eame, Bush-p\u00e8re assura sa position comme directeur de la <em>task-force <\/em>temporaire qui, \u00e0 la Maison-Blanche, assurait l&rsquo;int\u00e9rim.<\/p>\n<\/p>\n<p><p>Dans ce cadre, les relations entre Bush-p\u00e8re et Haig, d\u00e9j\u00e0 assez m\u00e9diocres, se tendirent dramatiquement. Bush-p\u00e8re, un r\u00e9publicain mod\u00e9r\u00e9, r\u00e9agit durement \u00e0 l&rsquo;incursion de Haig, un r\u00e9publicain belliciste ; Bush-p\u00e8re, il avait d\u00e9j\u00e0 donn\u00e9, ayant \u00e9t\u00e9 victime d&rsquo;une cabale bureaucratique de cinq avant, du secr\u00e9taire \u00e0 la d\u00e9fense d&rsquo;alors, notre ami Rumsfeld, qui crut l&rsquo;\u00e9carter d&rsquo;une probable course \u00e0 la pr\u00e9sidence de 1980 (assumant que Ford serait \u00e9lu\/r\u00e9\u00e9lu en novembre 1976) en le faisant rappeler de Chine et nommer \u00e0 la t\u00eate de la CIA cette m\u00eame ann\u00e9e 1976. C&rsquo;est ainsi qu&rsquo;en attendant le r\u00e9tablissement complet de Reagan, un \u00e9tat de guerre froide bureaucratique exista entre Bush-p\u00e8re et Haig, qui fut finalement remport\u00e9 par le premier (Haig, par ailleurs de plus en plus isol\u00e9, capitula en 1982 et d\u00e9missionna).<\/p>\n<\/p>\n<p><p>On \u00e9tait donc en plein dans l&rsquo;\u00e9pisode paroxystique de cette bataille bureaucratique lorsque, le 10 mai, Mitterrand fut \u00e9lu pr\u00e9sident.<\/p>\n<\/p>\n<p><p>\u00ab\u00a0Comme d&rsquo;habitude, les Am\u00e9ricains n&rsquo;ont rien vu venir, bien trop occup\u00e9s \u00e0 leur baston interne. Ils ne lisent ni les d\u00e9p\u00eaches de leurs ambassades, ni celles de leurs chefs de station de la CIA\u00a0\u00bb, m&rsquo;expliqua mon ami, le vieux dur-\u00e0-cuire otanien. \u00ab\u00a0Alors, imagine leur fureur t\u00e9tanis\u00e9e, voire leur terreur tout court lorsqu&rsquo;ils ont d\u00e9couvert que Mitterrand \u00e9lu pr\u00e9sident \u00e9tait aussi socialiste, puis, quelques jours plus tard, qu&rsquo;il prenait des communistes dans son gouvernement, tout cela faisait na&icirc;tre des images fantasmagoriques de blind\u00e9 sovi\u00e9tiques fon\u00e7ant sur Paris ! Pourtant la bureaucratie concern\u00e9e, la CIA, tout le monde le savait depuis des mois sinon des ann\u00e9es, que le socialiste Mitterrand pouvaiut \u00eatre \u00e9lu et qu&rsquo;il prendrait des ministres communistes, mais cela n&rsquo;int\u00e9ressait personne parce qu&rsquo;on avait bien d&rsquo;autres choses \u00e0 suivre d&rsquo;un plus haut int\u00e9r\u00eat, dans les bagarres internes\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>Haig fut l\u00e0 aussi, pour l&rsquo;\u00e9lection fran\u00e7aise, le plus rapide \u00e0 intervenir. Il faut dire qu&rsquo;il venait du poste de SACEUR (commandant en chef des forces alli\u00e9es [OTAN] et des forces US en Europe), quitt\u00e9 en 1979. \u00ab\u00a0Haig a fait marcher ses r\u00e9seaux, il gardait beaucoup de contacts, \u00e0 Bruxelles, \u00e0 Ramstein, \u00e0 Stuttgart et il a alert\u00e9 quelques g\u00e9n\u00e9raux, sans m\u00eame passer par Weinberger\u00a0\u00bb [le secr\u00e9taire \u00e0 la d\u00e9fense]. Haig ne voyait rien de moins que la pr\u00e9paration d&rsquo;une intervention arm\u00e9e US en France ! r\u00e9suma ironiquement mon interlocuteur et informateur.<\/p>\n<p>\u00ab\u00a0Est-ce possible ?\u00a0\u00bb, dis-je, un peu interloqu\u00e9.<\/p>\n<p>\u00ab\u00a0Dans la bureaucratie des <em>Yanks<\/em>, tout est possible, dans tous les cas en th\u00e9orie, pour la planification, et m\u00eame&#8230; Il y a eu des bruits, certaines unit\u00e9s US mises en alerte, etc. L\u00e0, on est dans la sp\u00e9culation autant que dans l&rsquo;info, hein\u00a0\u00bb. Puis mon ami, me regardant, avec quelques secondes de silence, un sourire narquois et haussant les \u00e9paules, mais pas m\u00e9content de son effet :<\/p>\n<p>\u00ab\u00a0Enfin, bon ! On s&rsquo;est tout de m\u00eame vite aper\u00e7u de ce que tramait Haig, qui en fait avait comme but d&rsquo;\u00e9largir le territoire de son pouvoir plut\u00f4t que celui des &Eacute;tats-Unis en Germanie. Il n&#8217;emp\u00eache, on peut tr\u00e8s bien lancer des aventures de dingue de cette fa\u00e7on.\u00a0\u00bb<\/p>\n<\/p>\n<p><p>Bush-p\u00e8re riposta aussit\u00f4t. Il alla voir le pr\u00e9sident qui ne marchait que sur une patte et lui demanda de lui laisser s&rsquo;occuper de cette affaire, qu&rsquo;il fallait contr\u00f4ler Haig. Les deux conclurent qu&rsquo;il \u00e9tait du meilleur go&ucirc;t et du jugement le plus avis\u00e9 de d\u00e9samorcer toutes les mines anti-personnel pos\u00e9es par les faucons qui ne demandaient qu&rsquo;\u00e0 soutenir, voire \u00e0 pousser Haig (on y trouvait d\u00e9j\u00e0 de futures vedettes <em>neocon <\/em>comme Richard Perle au Pentagone). Pour tout cela, une mission du plus haut niveau serait lanc\u00e9e aupr\u00e8s de Mitterrand pour lui demander diplomatiquement qu&rsquo;il rassur\u00e2t ses amis washingtoniens. Bush-p\u00e8re proposa de se charger lui-m\u00eame de la chose ; le demi-pr\u00e9sident approuva et poussa un soupir de soulagement.<\/p>\n<\/p>\n<p><p>\u00ab\u00a0Je n&rsquo;en sais pas tellement plus, et j&rsquo;ignore si Bush informa Mitterrand des circonstances de coulisse. Le contact entre les deux hommes fut excellent je crois, malgr\u00e9 l&rsquo;extr\u00eame sensibilit\u00e9 de Mitterrand \u00e0 la question de la souverainet\u00e9 nationale. Alors oui c&rsquo;est-\u00e0-dire peut-\u00eatre, je crois que Bush, qui est un ma&icirc;tre en diplomatie, a d&ucirc; lui glisser quelques mots dans le sens du poil, quelques mots \u00e0 double sens, uniquement pour le secret commun des deux hommes, pas un mot \u00e0 quiconque, tu vois ? Avec un Florentin comme Mitterrand, cela ne pouvait que marcher&#8230;\u00a0\u00bb<\/p>\n<\/p>\n<p><p>Tout cela qui m&rsquo;\u00e9tait rapport\u00e9 alors que l&rsquo;\u00e9quipe Reagan \u00e9tait au terme de son mandat et que Bush-p\u00e8re s&rsquo;appr\u00eatait \u00e0 suivre, fut assorti d&rsquo;un \u00ab\u00a0<em>Just For Your Ears<\/em>\u00ab\u00a0, &ndash; ne rien \u00e9crire mais le savoir, dans tous les cas pour la s\u00e9quence en cours. Je crois qu&rsquo;il y a prescription, d&rsquo;ailleurs mon vieil ami nous a quitt\u00e9s depuis longtemps et nul ne saura rien de lui. Simplement, le souvenir de cette conversation enterr\u00e9e dans la brume de l&rsquo;oubli m&rsquo;est revenue pour ces quarante ann\u00e9es du souvenir, et l&rsquo;on peut apr\u00e8s tout, si l&rsquo;on veut, la tenir pour des propos de restaurant du commerce. <\/p>\n<\/p>\n<p><p>Je suis tout de m\u00eame conduit \u00e0 penser que tout cela, si c&rsquo;est le vrai, a peut-\u00eatre \u00e0 voir avec l&rsquo;estime r\u00e9ciproque et l&rsquo;amiti\u00e9 qui se concr\u00e9tis\u00e8rent dans leurs rapports lorsque Bush-p\u00e8re fut devenu pr\u00e9sident, en 1989-1992, tandis que le vieux Mitterrand restait dans les limbes que dispensaient ses fonctions royales. Je pense aussi que cette sorte de coup de fi\u00e8vre bureaucratique et dissimul\u00e9e du printemps 1981 pr\u00e9figurait d\u00e9j\u00e0 la folie de 9\/11 et de ce qui a suivi, et o&ugrave; nous sommes plus que jamais, jusqu&rsquo;au cou, simplement avec la d\u00e9mence qui change de forme et se choisit des sujets de plus en plus abracadabrantesques si c&rsquo;est possible, &ndash; et d\u00e9mence toujours mais plus que jamais, toujours plus, d\u00e9sormais inarr\u00eatable, comme cow-boy en goguette et train \u00e0 tr\u00e8s-grande-vitesse folle&#8230;<\/p>\n<\/p>\n<p><p>Et puis, en <em>Post-Scriptum<\/em>sur un mode plus personnel&#8230; Je dirais que je rapporte cette saillie originale pas seulement par l&rsquo;attrait de l&rsquo;occasion d&rsquo;une comm\u00e9moration. Dans les divers entretiens en c\u00e9l\u00e9bration de ces derniers jours et des jours qui vont et viennent, on entend parfois, rappel\u00e9es en goguenardant parmi les bobos wokenis\u00e9s qui se retrouvent deux fois <em>Vingt Ans Apr\u00e8s<\/em>, et qui moquent ces terreurs d&rsquo;antan eux qui n&rsquo;ont peur de rien, &ndash; donc on entendit dans ces propos de comptoir plusieurs fois \u00e9voqu\u00e9es les craintes qu&rsquo;eurent certains de voir, \u00e0 la suite de Mitterrand, \u00ab\u00a0les chars russes descendant les Champs-&Eacute;lys\u00e9es\u00a0\u00bb, guid\u00e9s par les ministres communistes. On moque \u00e0 cet \u00e9gard le ministre giscardien Poniatowski, homme de grand secret, ami de \u00ab\u00a0Porthos\u00a0\u00bb, dit Alexandre de Marenches pour la direction du SDECE qu&rsquo;il assuma, et cr\u00e9ateur du <em><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Safari_Club\">Safari Club<\/a><\/em>.<\/p>\n<\/p>\n<p><p>Lors de la conversation que je rapporte, j&rsquo;avais rappel\u00e9 cette anecdote qui tra&icirc;nait encore dans les m\u00e9moires \u00e0 mon dur-\u00e0-cuire otanien, en mati\u00e8re de plaisanterie quoiqu&rsquo;un peu pince-sans-rire ; et pour lui dire, brusquement angoiss\u00e9 au bout de la plaisanterie brusquement pinc\u00e9e : \u00ab\u00a0Les Ricains, les cow-boys, ils n&rsquo;ont tout de m\u00eame pas cru \u00e0 \u00e7a, non ? Les chars russes sur les Champs-&Eacute;lys\u00e9es ! Dis, s\u00e9rieux ?\u00a0\u00bb. L&rsquo;autre m&rsquo;avait regard\u00e9, \u00e9nigmatique et mi-figue mi-raisin : \u00ab\u00a0Qui peut dire&#8230; On serait surpris.\u00a0\u00bb<\/p>\n<\/p>\n<p><p>Je comprends mieux pourquoi les bobos postmodernes-d\u00e9constructeurs les trouvent si formidables aujourd&rsquo;hui, les Ricains, les <em>Yanks <\/em>comme disait mon dur-\u00e0-cuire otanien. En fait de simulacre, c&rsquo;est juste leur pointure.<\/p>\n<\/p>\n<p><h2 class=\"titleset_c.deepgreen\" style=\"color:#75714d;font-size:1.25em;\">Note<\/h2>\n<\/p>\n<p><p>(*) Je le dis s\u00e9rieusement, hors contexte : \u00e0 l&rsquo;OTAN aussi, il y a 40-50 ans lorsque j&rsquo;y fus accr\u00e9dit\u00e9 comme journaliste jouant \u00e0 l&rsquo;enqu\u00eateur, on \u00e9tait bien plus libre de parole qu&rsquo;on ne l&rsquo;est devenu, hier et aujourd&rsquo;hui, disons depuis la guerre du Kosovo de 1999 et le 9\/11 de 2001. Bien qu&rsquo;en terre \u00e9trang\u00e8re, sinon ennemie, je ne m&rsquo;y sentais jamais prisonnier.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Panique \u00e0 bord 11 mai 2021 &ndash; Souvenir, souvenir&#8230; Un des \u00e9v\u00e9nements les plus importants pour moi dans l&rsquo;\u00e9lection de Mitterrand du 10 mai 1981, &ndash; je rappelle aux esprits l\u00e9gers qu&rsquo;elle eut 40 ans hier, &ndash; se situa \u00e0 l&rsquo;OTAN. A cette \u00e9poque, j&rsquo;\u00e9tais encore bien vu dans cette sympathique organisation qui n&rsquo;\u00e9tait pas&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[3939,18716,3917,3137,2913,6717,1104,584,3215,2890,2710,20915],"class_list":["post-79756","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-bush-pere","tag-champs-elysees","tag-chars","tag-haig","tag-les","tag-mitterrand","tag-neocons","tag-otan","tag-reagan","tag-russes","tag-sur","tag-yanks"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79756"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79756\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79756"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79756"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}