{"id":79807,"date":"2021-06-23T13:17:47","date_gmt":"2021-06-23T13:17:47","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2021\/06\/23\/la-technosphere-setouffe-avec-une-puce\/"},"modified":"2021-06-23T13:17:47","modified_gmt":"2021-06-23T13:17:47","slug":"la-technosphere-setouffe-avec-une-puce","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2021\/06\/23\/la-technosphere-setouffe-avec-une-puce\/","title":{"rendered":"La technosph\u00e8re s&rsquo;\u00e9touffe avec une puce"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">La technosph\u00e8re s&rsquo;\u00e9touffe avec une puce<\/h2>\n<\/p>\n<p><p>La technosph\u00e8re, que j&rsquo;ai d\u00e9finie dans mon livre de 2016 \u00ab\u00a0<em><a href=\"https:\/\/www.amazon.com\/Shrinking-Technosphere-Technologies-Autonomy-Self-Sufficiency\/dp\/0865718385\">Shrinking the Technosphere<\/a><\/em>\u00a0\u00bb comme une intelligence \u00e9mergente mondiale non humaine anim\u00e9e par une t\u00e9l\u00e9ologie abstraite de contr\u00f4le total, a vu ses int\u00e9r\u00eats grandement avanc\u00e9s au cours de la pand\u00e9mie de coronavirus de 2020-21, avec de grandes parties des populations humaines forc\u00e9es de se soumettre \u00e0 des mesures de contr\u00f4le qui se moquent de leurs droits humains et de leurs valeurs d\u00e9mocratiques tant vant\u00e9s. C&rsquo;\u00e9tait \u00e0 pr\u00e9voir : les technologies les plus puissantes de la technosph\u00e8re sont celles qui tuent, et la fa\u00e7on dont elle s&rsquo;en sert refl\u00e8te sa haine profonde pour tous les \u00eatres vivants, en particulier ceux qui sont volontaristes et difficiles \u00e0 contr\u00f4ler. Mais ensuite, la technosph\u00e8re a commenc\u00e9 \u00e0 r\u00e9tr\u00e9cir dans certains endroits. Elle est encore forte dans d&rsquo;autres, mais il n&rsquo;est pas trop t\u00f4t pour imaginer (oserais-je dire, pr\u00e9dire ?) comment elle pourrait continuer \u00e0 r\u00e9tr\u00e9cir et quelles en seront les cons\u00e9quences.<\/p>\n<\/p>\n<p><p>Dans mon livre, j&rsquo;ai d\u00e9crit les raisons et les m\u00e9thodes qui nous permettront d&rsquo;\u00e9viter de nous retrouver pi\u00e9g\u00e9s sous la carcasse inerte de la technosph\u00e8re. J&rsquo;ai m\u00eame fourni une feuille de route que les lecteurs pouvaient utiliser pour suivre leurs progr\u00e8s en se lib\u00e9rant des griffes de la technosph\u00e8re. Comme on pouvait s&rsquo;y attendre, cela n&rsquo;a servi \u00e0 rien. Les seuls livres pratiques de ce monde sont les livres de cuisine ; les autres sont lus principalement pour se divertir &ndash; d&rsquo;abord seul et, plus tard, lors de cocktails. Et le but de les \u00e9crire est de gagner un peu d&rsquo;argent suppl\u00e9mentaire pour payer les baby-sitters (du moins, c&rsquo;\u00e9tait mon cas \u00e0 l&rsquo;\u00e9poque).<\/p>\n<\/p>\n<p><p>Pour comprendre ce qui semble devoir se passer, il faut d&rsquo;abord se plonger dans l&rsquo;ontologie de la technosph\u00e8re : sur quoi fonctionne son logiciel d&rsquo;intelligence \u00e9mergente ? Il s&rsquo;av\u00e8re que, vu comme un syst\u00e8me d&rsquo;exploitation de r\u00e9seau, il fonctionne en partie sur des cerveaux humains, mais surtout sur diverses puces \u00e9lectroniques, auxquelles est attach\u00e9 un large assortiment de capteurs optiques, \u00e9lectromagn\u00e9tiques et m\u00e9caniques. Bien que les humains exercent (pensent exercer) encore un minimum de contr\u00f4le sur la technosph\u00e8re, celle-ci a une tendance naturelle \u00e0 lui retirer le contr\u00f4le, m\u00eame lorsqu&rsquo;il s&rsquo;agit de prendre des d\u00e9cisions de vie ou de mort, comme l&rsquo;a montr\u00e9 un \u00e9v\u00e9nement r\u00e9cent en Libye o&ugrave; un avion militaire sans pilote a pris de mani\u00e8re autonome la d\u00e9cision de tuer quelqu&rsquo;un. Et l&rsquo;exercice du contr\u00f4le n\u00e9cessite des circuits de contr\u00f4le.<\/p>\n<\/p>\n<p><p>Ayant eu une carri\u00e8re r\u00e9ussie en tant qu&rsquo;ing\u00e9nieur en \u00e9lectronique, puis en tant qu&rsquo;ing\u00e9nieur en logiciel, je suis en quelque sorte un mus\u00e9e ambulant de la technologie de l&rsquo;automatisation et je peux vous faire faire un bref tour de son d\u00e9veloppement. L&rsquo;\u00e9l\u00e9ment de commande le plus stupide est l&rsquo;interrupteur. Il n&rsquo;a pas de m\u00e9moire et ne d\u00e9cide de rien. L&rsquo;\u00e9l\u00e9ment de commande suivant, un peu moins stupide, est un interrupteur \u00e0 bascule : il se souvient si la lumi\u00e8re est allum\u00e9e ou \u00e9teinte et, lorsqu&rsquo;il est actionn\u00e9, il l&rsquo;\u00e9teint ou l&rsquo;allume. Nous sommes d\u00e9j\u00e0 bien avanc\u00e9s : pour construire un ordinateur, nous n&rsquo;avons besoin que de quelques \u00e9l\u00e9ments suppl\u00e9mentaires. Nous avons besoin d&rsquo;un interrupteur \u00e0 seuil avec deux boutons, qui, selon ce que vous voulez, allume la lumi\u00e8re lorsque l&rsquo;un des boutons est enfonc\u00e9 (appel\u00e9 une \u00ab\u00a0<em><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Fonction_OU\">porte OU<\/a><\/em>\u00ab\u00a0) ou lorsque les deux boutons sont enfonc\u00e9s (appel\u00e9 une \u00ab\u00a0porte ET\u00a0\u00bb). Nous avons \u00e9galement besoin d&rsquo;un \u00ab\u00a0Non\u00a0\u00bb : quelque chose qui \u00e9teint la lumi\u00e8re lorsqu&rsquo;il est actionn\u00e9. Enfin, nous avons besoin d&rsquo;un actionneur ; au lieu d&rsquo;allumer une ampoule, tous ces \u00e9l\u00e9ments doivent \u00eatre capables de pousser les boutons les uns des autres. Et nous voil\u00e0 partis pour la course !<\/p>\n<\/p>\n<p><p>Tout ce qui pr\u00e9c\u00e8de peut \u00eatre mis en &oelig;uvre \u00e0 partir d&rsquo;un nombre quelconque de composants : m\u00e9caniques, pneumatiques, hydrauliques, mais aucun d&rsquo;entre eux n&rsquo;\u00e9tait particuli\u00e8rement pratique pour automatiser les fonctions de contr\u00f4le. L&rsquo;av\u00e8nement des circuits \u00e9lectriques a rendu possible l&rsquo;utilisation de composants \u00e9lectrom\u00e9caniques, permettant la grande perc\u00e9e que fut le commutateur <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Almon_Strowger\">Strowger<\/a>, brevet\u00e9 en 1891. Il remplace le standardiste humain : au lieu de tourner une manivelle et de dire \u00ab\u00a0Num\u00e9ro 17, s&rsquo;il vous pla&icirc;t !\u00a0\u00bb, il suffit de tourner le cadran rotatif, d&rsquo;abord sur 1, puis sur 2, ce qui entra&icirc;ne un clic, une pause, puis 7 clics rapides (les num\u00e9ros de t\u00e9l\u00e9phone \u00e0 deux chiffres \u00e9taient la limite \u00e0 l&rsquo;\u00e9poque, limitant un central t\u00e9l\u00e9phonique \u00e0 99 abonn\u00e9s).<\/p>\n<\/p>\n<p><p>Ce syst\u00e8me a fonctionn\u00e9 pendant une p\u00e9riode \u00e9tonnamment longue. Au milieu des ann\u00e9es 1970, je me suis retrouv\u00e9 dans une chambre d&rsquo;h\u00f4tel en Italie, \u00e9quip\u00e9e d&rsquo;un t\u00e9l\u00e9phone \u00e0 cadran rotatif muni d&rsquo;un petit cadenas pour emp\u00eacher les clients de composer un num\u00e9ro. Mais j&rsquo;avais besoin de t\u00e9l\u00e9phoner en Russie, alors j&rsquo;ai tap\u00e9 tout le num\u00e9ro interurbain sur le \u00ab\u00a0crochet\u00a0\u00bb. Apr\u00e8s tout, le cadran rotatif ne fait qu&rsquo;actionner un interrupteur c\u00e2bl\u00e9 en s\u00e9quence avec le \u00ab\u00a0crochet\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>L&rsquo;\u00e9volution des circuits de commande est pass\u00e9e de l&rsquo;\u00e9lectrom\u00e9canique (bas\u00e9 sur des sol\u00e9no\u00efdes et des relais) au tube \u00e0 vide (compos\u00e9 d&rsquo;interrupteurs \u00e0 tube \u00e0 vide et de noyaux de ferrite pour former des cellules de m\u00e9moire), puis au transistor discret, aux premiers circuits int\u00e9gr\u00e9s (quelques centaines \u00e0 quelques milliers de transistors sur une puce) et enfin aux circuits int\u00e9gr\u00e9s modernes \u00e0 grande \u00e9chelle, avec un r\u00e9cent record \u00e9tabli par la puce de m\u00e9moire flash V-NAND eUFS (empil\u00e9e en 3D) de Samsung, avec 2 000 milliards de <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Transistor_%C3%A0_effet_de_champ_%C3%A0_grille_m%C3%A9tal-oxyde\">MOSFETs<\/a> \u00e0 grille flottante (4 bits par transistor). Ne vous inqui\u00e9tez pas si vous ne comprenez pas ce que cela signifie ; retenez simplement que c&rsquo;est sacr\u00e9ment impressionnant, parce que \u00e7a l&rsquo;est. Mais c&rsquo;est l\u00e0 que r\u00e9side le danger. La course \u00e0 la construction de puces de plus en plus puissantes pourrait bien se diriger vers une falaise.<\/p>\n<\/p>\n<p><p>&Agrave; l&rsquo;heure actuelle, presque tous les objets &ndash; voitures, machines \u00e0 laver, chauffe-eau, routeurs Internet&hellip; &ndash; sont \u00e9quip\u00e9s de circuits de commande, tous bas\u00e9s sur des micropuces. &Agrave; leur tour, ces puces sont fabriqu\u00e9es dans des usines gigantesques dont la construction co&ucirc;te plusieurs milliards de dollars. Comme les \u00e9conomies d&rsquo;\u00e9chelle ne sont r\u00e9alisables qu&rsquo;en concentrant la production, chaque micropuce est g\u00e9n\u00e9ralement fabriqu\u00e9e dans une seule usine. Pour conserver un avantage concurrentiel, les micropuces ne sont pas interchangeables. Par cons\u00e9quent, chaque conception de dispositif comprenant des micropuces (ce qui est d\u00e9sormais le cas de la plupart d&rsquo;entre eux) ne peut \u00eatre construite que si chaque micropuce qu&rsquo;elle utilise est disponible. Si ce n&rsquo;est pas le cas, il faut alors un processus de reconception tr\u00e8s co&ucirc;teux pour remplacer cette puce par une autre. Souvent, cela n&rsquo;est pas \u00e9conomiquement r\u00e9alisable, ce qui signifie que les lignes de production sont simplement arr\u00eat\u00e9es jusqu&rsquo;\u00e0 ce que tous les composants n\u00e9cessaires soient disponibles.<\/p>\n<\/p>\n<p><p>Nous avons d\u00e9j\u00e0 eu des alertes. Un tsunami au Japon en 2011 a fait grimper les prix de certaines puces de m\u00e9moire d&rsquo;ordinateur, dont plus de la moiti\u00e9 \u00e9tait produite au Japon. Une inondation en Tha\u00eflande a provoqu\u00e9 une p\u00e9nurie de r\u00e9gulateurs de tension, interrompant les cha&icirc;nes de production automobile dans le monde entier. Et maintenant, apr\u00e8s une ann\u00e9e d&rsquo;urgence due au coronavirus, il y a une grave p\u00e9nurie de puces en raison des arr\u00eats des usines de semi-conducteurs dans le monde entier. Jusqu&rsquo;\u00e0 pr\u00e9sent, la Covid-19 a tu\u00e9 3,75 millions de personnes dans le monde, soit environ 0,047 % de la population mondiale, ajoutant moins de 5 % au taux de mortalit\u00e9 annuel normal de 0,7 %. Maintenant que de nombreux vaccins sont disponibles (le Spoutnik-V russe a \u00e9t\u00e9 approuv\u00e9 dans plus de 65 pays) et que des protocoles sont en place dans le monde entier pour d\u00e9tecter rapidement et limiter la propagation de toute nouvelle contagion, une reprise [de la pand\u00e9mie] semble peu probable.<\/p>\n<\/p>\n<p><p>Ce qui semble probable (et qui est d\u00e9j\u00e0 observable dans de nombreux endroits du monde), c&rsquo;est une grave dislocation \u00e9conomique. Les arr\u00eats de production dus au coronavirus ont provoqu\u00e9 des perturbations de la cha&icirc;ne d&rsquo;approvisionnement dans le monde entier, notamment dans l&rsquo;industrie des semi-conducteurs, entra&icirc;nant l&rsquo;arr\u00eat de nombreuses cha&icirc;nes de production. Et puis, il y a les effets d&rsquo;entra&icirc;nement. Les arr\u00eats des cha&icirc;nes de production automobile ont entra&icirc;n\u00e9 une hausse de prix des voitures neuves. Les soci\u00e9t\u00e9s de location de voitures ont donc d&ucirc; augmenter leurs tarifs. &Agrave; leur tour, de nombreux touristes ont reconsid\u00e9r\u00e9 leurs projets de voyage, ce qui a fait chuter les revenus des voitures de location, qui ont achet\u00e9 moins de voitures neuves lorsque la production a repris, ce qui a rendu plus difficile pour les constructeurs automobiles de r\u00e9cup\u00e9rer leurs pertes.<\/p>\n<\/p>\n<p><p>La reprise post-coronavirus en forme de V \u00e0 laquelle on s&rsquo;attendait ne s&rsquo;est pas mat\u00e9rialis\u00e9e ; au lieu de cela, nous assistons \u00e0 un d\u00e9but d&rsquo;hyperinflation. Pour les gouvernements tr\u00e8s endett\u00e9s, principalement en Occident mais aussi ailleurs, le rem\u00e8de habituel consistant \u00e0 lutter contre l&rsquo;inflation en r\u00e9duisant les d\u00e9penses tout en augmentant les taux d&rsquo;int\u00e9r\u00eat n&rsquo;est plus possible, car m\u00eame une l\u00e9g\u00e8re augmentation des taux d&rsquo;int\u00e9r\u00eat les rendrait incapables de payer les int\u00e9r\u00eats de leur dette, sauf \u00e0 imprimer encore plus de monnaie, ce qui ferait encore <a href=\"https:\/\/brunobertez.com\/2021\/06\/16\/les-premiers-barreaux-de-lechelle-de-perroquet-de-linflation-sont-montes\/\">augmenter l&rsquo;inflation<\/a>.<\/p>\n<\/p>\n<p><p>Mais ces r\u00e9percussions ne sont qu&rsquo;\u00e9conomiques et financi\u00e8res ; les pires seront physiques et se manifesteront par l&rsquo;incapacit\u00e9 de maintenir les divers syst\u00e8mes de survie qui contr\u00f4lent l&rsquo;approvisionnement en eau, en \u00e9lectricit\u00e9, en carburant, en nourriture, en m\u00e9dicaments et autres produits essentiels. Au cours des derni\u00e8res d\u00e9cennies, les syst\u00e8mes qui fonctionnaient auparavant sur la base de calendriers papier et d&rsquo;op\u00e9rations manuelles (tourner des vannes et actionner des interrupteurs) ont \u00e9t\u00e9 automatis\u00e9s, ce qui les rend plus efficaces (dans un sens limit\u00e9) mais beaucoup plus fragiles.<\/p>\n<\/p>\n<p><p>Les syst\u00e8mes de contr\u00f4le \u00e9lectronique sont un mille-feuilles de couches de technologies. &Agrave; la base, on trouve des serveurs install\u00e9s dans les racks de centres de donn\u00e9es et des syst\u00e8mes clients avec des \u00e9crans et des claviers dans les salles de contr\u00f4le. Au-dessus de ce mat\u00e9riel se trouvent des syst\u00e8mes d&rsquo;exploitation. Par-dessus les syst\u00e8mes d&rsquo;exploitation, on trouve des environnements de d\u00e9veloppement int\u00e9gr\u00e9s utilis\u00e9s pour d\u00e9velopper des outils d&rsquo;automatisation des processus. Enfin, les outils d&rsquo;automatisation des processus permettent aux int\u00e9grateurs de syst\u00e8mes de configurer les syst\u00e8mes de contr\u00f4le en faisant un glisser-d\u00e9poser graphique et en reliant les composants du syst\u00e8me tels que les actionneurs et les capteurs, et de d\u00e9finir les r\u00e8gles et les param\u00e8tres de configuration pour leur fonctionnement. Si l&rsquo;on supprime un \u00e9l\u00e9ment d&rsquo;une couche quelconque, l&rsquo;ensemble de ce syst\u00e8me <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Machine_de_Rube_Goldberg\">Rube Goldberg<\/a>, fragile et pr\u00e9caire, cesse de fonctionner. L&rsquo;impossibilit\u00e9 de remplacer l&rsquo;un de ces composants lorsqu&rsquo;il tombe en panne par une unit\u00e9 compatible &ndash; qu&rsquo;il s&rsquo;agisse d&rsquo;un simple capteur, d&rsquo;un routeur ou d&rsquo;un serveur &ndash; oblige au moins une partie de l&rsquo;ensemble du syst\u00e8me \u00e0 s&rsquo;arr\u00eater. Et si ce remplacement ne peut \u00eatre trouv\u00e9, le syst\u00e8me reste en panne.<\/p>\n<\/p>\n<p><p>Si l&rsquo;on cherche la premi\u00e8re victime de l&rsquo;effondrement, l&rsquo;industrie mondiale des semi-conducteurs est une candidate de choix. Elle est tr\u00e8s gourmande en \u00e9nergie et extr\u00eamement capitalistique. Elle d\u00e9pend d&rsquo;un approvisionnement \u00e9nerg\u00e9tique r\u00e9gulier et fiable &ndash; l&rsquo;\u00e9olien et le solaire ne suffisent pas en raison de leur intermittence. Elle d\u00e9pend de la disponibilit\u00e9 de silicium cristallin de la plus haute puret\u00e9 et d&rsquo;\u00e9l\u00e9ments de terres rares qui ne proviennent que de quelques endroits dans le monde, le principal \u00e9tant la Chine. Enfin, elle exige une main-d&rsquo;&oelig;uvre hautement disciplin\u00e9e et qualifi\u00e9e. Le plus grand exportateur de circuits int\u00e9gr\u00e9s est de loin la Chine (Hong Kong et Ta\u00efwan inclus), suivie de la Cor\u00e9e du Sud, de Singapour et de la Malaisie. Les &Eacute;tats-Unis ne sont que le premier d&rsquo;une longue liste d&rsquo;acteurs mineurs sur des march\u00e9s de niche.<\/p>\n<\/p>\n<p><p>Il semble naturel de s&rsquo;attendre \u00e0 ce que, dans la mesure o&ugrave; les conditions de march\u00e9 affectant l&rsquo;industrie des semi-conducteurs continuent de se d\u00e9t\u00e9riorer alors que la demande de composants critiques n\u00e9cessaires au maintien des syst\u00e8mes d&rsquo;infrastructure vitaux dans le monde entier ne faiblit pas, la Chine soit en mesure d&rsquo;exercer une influence disproportionn\u00e9e sur la disponibilit\u00e9 de ces composants. Il est tout \u00e0 fait pr\u00e9visible que le parti communiste chinois consid\u00e8re l&rsquo;industrie des semi-conducteurs comme strat\u00e9giquement importante et en nationalise des parties cl\u00e9s, en en faisant un outil de politique \u00e9trang\u00e8re. Les &Eacute;tats-Unis feront bien s&ucirc;r semblant de faire quelque chose pour rem\u00e9dier \u00e0 cet \u00e9tat de fait, ce qui cr\u00e9era un environnement international bruyant, mais ils ne seront pas en mesure d&#8217;emp\u00eacher que l&rsquo;acc\u00e8s aux produits semi-conducteurs soit rationn\u00e9, la Chine ayant le contr\u00f4le presque total des arrangements.<\/p>\n<\/p>\n<p><p>Ces arrangements seront probablement appliqu\u00e9s par la Chine et la Russie, qui travaillent en tandem. La Chine est insulaire par nature et peut en g\u00e9n\u00e9ral soit commercer avec d&rsquo;autres cultures, soit les absorber. La seule exception est la Russie, \u00e0 laquelle la Chine s&rsquo;accroche maintenant comme une petite amie en manque d&rsquo;affection. La symbiose est naturelle : contrairement \u00e0 la Chine, la Russie est \u00e0 l&rsquo;oppos\u00e9 de l&rsquo;insularit\u00e9 et peut dig\u00e9rer et s&rsquo;approprier des civilisations \u00e9trang\u00e8res enti\u00e8res. Un si\u00e8cle, ce sont les Mongols ; le suivant, les Allemands ; puis toute la cour imp\u00e9riale russe se met \u00e0 parler fran\u00e7ais ; et maintenant l&rsquo;anglais est \u00e0 la mode.<\/p>\n<\/p>\n<p><p>Comme l&rsquo;a dit Poutine, &laquo;<em> les fronti\u00e8res de la F\u00e9d\u00e9ration de Russie ne s&rsquo;arr\u00eatent nulle part <\/em>&raquo;. Contrairement \u00e0 la Chine, dont l&rsquo;arm\u00e9e est \u00e9norme mais n&rsquo;a pas \u00e9t\u00e9 test\u00e9e au combat et ne s&rsquo;int\u00e9resse pas \u00e0 la projection de puissance, les Russes sont une culture guerri\u00e8re qui s&rsquo;enorgueillit de son invincibilit\u00e9 et qui a fait de la coercition \u00e0 la paix sa sp\u00e9cialit\u00e9. La Russie excelle dans la construction et l&rsquo;exploitation d&rsquo;\u00e9normes syst\u00e8mes de production d&rsquo;\u00e9nergie, de transport et de mat\u00e9riaux dont la Chine a besoin et elle dispose des vastes ressources naturelles pour continuer \u00e0 les exploiter pendant des si\u00e8cles. Ses combustibles fossiles tiendront encore un demi-si\u00e8cle ; ensuite, si tout se passe comme pr\u00e9vu, elle passera \u00e0 la combustion d&rsquo;uranium appauvri gr\u00e2ce \u00e0 sa technologie de cycle nucl\u00e9aire ferm\u00e9, dont elle a d\u00e9j\u00e0 stock\u00e9 l&rsquo;\u00e9quivalent de quelques milliers d&rsquo;ann\u00e9es.<\/p>\n<\/p>\n<p><p>Face \u00e0 ces difficult\u00e9s majeures, la technosph\u00e8re n&rsquo;a pas baiss\u00e9 les bras. Sans remplir de formulaire de changement d&rsquo;adresse, elle s&rsquo;est discr\u00e8tement d\u00e9localis\u00e9e et s&rsquo;affaire \u00e0 faire du t\u00e9l\u00e9travail entre Moscou et P\u00e9kin. Les fringants gar\u00e7ons de Davos et leur m\u00e9chant James Bond en herbe, Klaus Schwab, doivent encore s&rsquo;habituer \u00e0 cette tournure des \u00e9v\u00e9nements. Poutine et Xi le leur ont dit en face lors de leur derni\u00e8re conf\u00e9rence virtuelle, mais je ne pense pas qu&rsquo;ils aient encore pris conscience de la nouvelle ; laissons-leur le temps. Les Allemands semblent \u00eatre plus rapides \u00e0 comprendre que les autres, car ils ont compris que sans le gaz naturel russe, ils ne seraient rien. Les Am\u00e9ricains semblent \u00eatre les plus lents ; \u00e0 ce rythme, il faudra peut-\u00eatre une \u00e9ternit\u00e9 pour que la lumi\u00e8re monte aux \u00e9tages. Ils risquent de sombrer dans le vide gargouillant tout en s&rsquo;exclamant que leur Atlantide ne coule pas !<\/p>\n<\/p>\n<p><p>Et veuillez acheter mon dernier livre, <a href=\"https:\/\/www.amazon.com\/dp\/B095GSG5ZS\">The Arctic Fox Cometh.<\/a><\/p>\n<\/p>\n<p><p>Le 13 juin 2021, <a href=\"http:\/\/cluborlov.blogspot.com\/2021\/06\/the-technosphere-chokes-on-chip.html\">Club Orlov<\/a> &ndash; Traduction du <em><a href=\"https:\/\/lesakerfrancophone.fr\/la-technosphere-setouffe-avec-une-puce\">Sakerfrancophone<\/a><\/em><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La technosph\u00e8re s&rsquo;\u00e9touffe avec une puce La technosph\u00e8re, que j&rsquo;ai d\u00e9finie dans mon livre de 2016 \u00ab\u00a0Shrinking the Technosphere\u00a0\u00bb comme une intelligence \u00e9mergente mondiale non humaine anim\u00e9e par une t\u00e9l\u00e9ologie abstraite de contr\u00f4le total, a vu ses int\u00e9r\u00eats grandement avanc\u00e9s au cours de la pand\u00e9mie de coronavirus de 2020-21, avec de grandes parties des populations&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[29],"tags":[2752,6588,2668,21018,2847,4096,2846,21020],"class_list":["post-79807","post","type-post","status-publish","format-standard","hentry","category-les-carnets-de-dimitri-orlov-1","tag-covid","tag-inflation","tag-orlov","tag-puves","tag-rares","tag-technologies","tag-terres","tag-vhine"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79807","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79807"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79807\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79807"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79807"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}