{"id":79847,"date":"2021-07-26T19:27:10","date_gmt":"2021-07-26T19:27:10","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2021\/07\/26\/ineluctable-medaille-dor-pour-covid21\/"},"modified":"2021-07-26T19:27:10","modified_gmt":"2021-07-26T19:27:10","slug":"ineluctable-medaille-dor-pour-covid21","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2021\/07\/26\/ineluctable-medaille-dor-pour-covid21\/","title":{"rendered":"In\u00e9luctable m\u00e9daille d&rsquo;or pour Covid21"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepgreen\" style=\"color:#75714d; font-size:2em\">In\u00e9luctable m\u00e9daille d&rsquo;or pour Covid21<\/h2>\n<\/p>\n<blockquote>\n<p><p>&bull; Articles du 26 juillet 23021. &bull; D&rsquo;une certaine fa\u00e7on, on pourrait dire que les JO de l&rsquo;\u00e9trange ann\u00e9e 2021 (ex-2020) ne seront pas infect\u00e9s <strong>par l&rsquo;inf\u00e2me virus du nationalisme<\/strong> du fait que <strong>toutes les m\u00e9dailles d&rsquo;or sont et seront d&rsquo;office attribu\u00e9es \u00e0 un virus globaliste-internationaliste<\/strong>. &bull; Covid21est effectivement le Tr\u00e8s-Grand vainqueur de ces Jeux. &bull; Le site <em>WSWS.org <\/em>voit dans Tokyo-2021, en fait d&rsquo;infamie mais d&rsquo;une autre forme, <strong>l&rsquo;\u00e9quivalent des JO de Berlin-1936<\/strong>. &bull; Par cons\u00e9quent, <strong>nous attendons la guerre<\/strong>. &bull; Contributions : <em>dedefensa.org<\/em> et <em>WSWS.org<\/em>.<\/p>\n<\/p>\n<\/blockquote>\n<\/p>\n<p><p>D&rsquo;une part, il y a longtemps que nous avons cess\u00e9 d&rsquo;esp\u00e9rer y voir clair, &ndash; si nous avons jamais esp\u00e9rer y voir quelque chose, <a href=\"https:\/\/www.dedefensa.org\/article\/epidemie-de-stupefaction\">instruits par l&rsquo;exp\u00e9rience<\/a>, &ndash; dans cette \u00e9trange pand\u00e9mie du Covid19. Ce brouillard global qui va-et-vient d&rsquo;annonces triomphales en rechutes n&rsquo;a pas emp\u00each\u00e9 les officiels nippons et leurs vis-\u00e0-vis du CIO de maintenir les JO de Tokyo-2020, revus et surveill\u00e9s en JO-2021. Le temps passant dans le d\u00e9sordre exponentiel qu&rsquo;on sait, nous nous sommes permis, du moins pour la comp\u00e9tition qui se d\u00e9roule \u00e0 guichets ferm\u00e9s et en aveugle, de baptiser temporairement le Covid du matricule Covid21.<\/p>\n<\/p>\n<p><p>Aussi faut-il lire, &ndash; c&rsquo;est instructif, &ndash; <a href=\"https:\/\/www.wsws.org\/fr\/articles\/2021\/07\/26\/pers-j26.html\">l&rsquo;article<\/a> assez furieux et un peu apocalyptique que le site de la IVe Internationale trotskiste, <em>WSWS.org<\/em>, consacre \u00e0 l&rsquo;\u00e9v\u00e9nement de l&rsquo;ouverture des JO. <em>WSWS.org<\/em>, d\u00e9barrass\u00e9 en bonne partie de son obsession trumpiste, redevient un site fr\u00e9quentable dans la mesure o&ugrave; il nous pr\u00e9sente une chronique r\u00e9guli\u00e8re d&rsquo;une forme de la folie-Covid, c&rsquo;est-\u00e0-dire pour ce cas de sa propre folie trotskiste : en effet, <em>WSW.org <\/em>est absolument catastrophiste et voit une \u00e9norme machination en route, qui touche le globe et l&rsquo;esp\u00e8ce.<\/p>\n<\/p>\n<p><p><em>WSWS.org<\/em> n&rsquo;est pas complotiste par position id\u00e9ologique ou par obsession hallucin\u00e9e, &ndash; les deux se m\u00e9langent, &ndash; il est devenu ontologiquement complot pur. Pour <em>WSWS.org<\/em>, le capitalisme-imp\u00e9rialisme, type bloc-BAE, et ses divers alli\u00e9s fascistes, int\u00e9gristes, &lsquo;illib\u00e9raux&rsquo;, r\u00e9actionnaires, etc. (Hongrie, Russie, Chine, Iran, Turquie, Syrie, Br\u00e9sil, peut-\u00eatre Cuba, etc.), complotent tous pour dissimuler les v\u00e9ritables effets de la pand\u00e9mie, pour faciliter la reprise de l&rsquo;\u00e9conomie de profit au d\u00e9pense de la s\u00e9curit\u00e9 des populations dont on se d\u00e9barrasserait bien, pour \u00e9carter toutes les mesures de protection, etc. Pour les JO de Tokyo-2021, cela se termine par l&rsquo;habituelle le\u00e7on de bonnes mani\u00e8res :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Tout doit \u00eatre mis en &oelig;uvre pour lutter contre ces politiques meurtri\u00e8res. L&rsquo;indignation populaire face \u00e0 la mise en danger inconsid\u00e9r\u00e9e de la vie humaine qui s&rsquo;est manifest\u00e9e au Japon, ainsi qu&rsquo;ailleurs dans le monde, doit \u00eatre dirig\u00e9e selon des lignes politiques ind\u00e9pendantes contre l&rsquo;ordre social capitaliste et sa subordination de la vie humaine aux int\u00e9r\u00eats de profit de l&rsquo;oligarchie financi\u00e8re<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>L&rsquo;on croirait que l&rsquo;on se moque et l&rsquo;on aurait bien tort. Tout cela n&rsquo;est peut-\u00eatre pas faux, en partie plus ou  moins grande, ou le contraire ; etc. ; <em>WSWS.org <\/em>n&rsquo;est pas plus cr\u00e9dible qu&rsquo;une BBC, qu&rsquo;un New York <em>Times<\/em> ou que L&rsquo;Im-<em>Monde <\/em>fran\u00e7ais, mais il ne l&rsquo;est pas moins non plus, \u00f4 combien. Sur ce cas pr\u00e9cis de la pand\u00e9mie et bien qu&rsquo;on ne se dissimule pas une seconde les parti-pris id\u00e9ologiques d\u00e9formant toutes les r\u00e9alit\u00e9s, ce constat des immenses incertitudes et simulacres sur les quelques organes cit\u00e9s n&rsquo;est en aucune fa\u00e7on un jugement sur les uns ou sur les autres ; aucun jugement, certes, car il y a longtemps que la justice est pass\u00e9e et oubli\u00e9e, et cette observation particuli\u00e8rement valable pour la crise-Covid qui constitue le plus formidable champ de man&oelig;uvre pour l&rsquo;<a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-laffectivisme-postmoderne\">affectivisme<\/a>, le <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-le-determinisme-narrativiste\">d\u00e9terminisme-narrativiste<\/a>, l&rsquo;irrationalisme, et enfin les escadrilles de simulacres du monde de la postv\u00e9rit\u00e9 annonc\u00e9 par <a href=\"https:\/\/www.dedefensa.org\/article\/je-doute-donc-je-suis\">le visionnaire Rumsfeld<\/a> il y a vingt ans.<\/p>\n<\/p>\n<p><p>Voyez par exemple, \u00e0 c\u00f4t\u00e9 du cas des JO-Covid21, le texte que <em>WSWS.org<\/em> nous donne ce jour <a href=\"https:\/\/www.wsws.org\/en\/articles\/2021\/07\/26\/pers-j26.html\">du 26 juillet<\/a> sur la situation aux USA, devenue pour nous beaucoup plus brumeuse et lointaine depuis la liquidation de Trump marquant le triomphe de l&rsquo;am\u00e9ricanisme et de ses r\u00eaves pour nos pauvres  perceptions \u00e9puis\u00e9es, et par cions\u00e9quent lza victoire des USA sur le Covid. Rien du tout ! affirme <em>WSWS.org. <\/em>Les trotskistes annoncent tout simplement un redoublement de l&rsquo;apocalypse de d\u00e9part, et d&rsquo;ailleurs au nom de quoi se jugerait-on fonder \u00e0 repousser ce tableau, voire \u00e0 seulement le critiquer ? Tout y est mesur\u00e9 tout en restant confin\u00e9 (!) dans l&rsquo;extr\u00eame, les sources r\u00e9f\u00e9renc\u00e9es apr\u00e8s un choix circonstanci\u00e9, etc., &ndash; \u00e0 peu pr\u00e8s comme font tous les organes de presse et d&rsquo;information plus ou moins li\u00e9s \u00e0 la civilisation actuelle et au Syst\u00e8me qui la dirige, &ndash; qui pour pr\u00e9tendre l&rsquo;exalter, qui pour pr\u00e9tendre y voir les signes document\u00e9s et irr\u00e9futables de sa mort. <\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Le 4 juillet, le pr\u00e9sident Joe Biden a prononc\u00e9 un discours dans lequel il a effectivement affirm\u00e9 que la pand\u00e9mie de COVID-19 \u00e9tait termin\u00e9e en Am\u00e9rique. M. Biden a d\u00e9clar\u00e9 que les &Eacute;tats-Unis \u00ab\u00a0d\u00e9claraient leur ind\u00e9pendance vis-\u00e0-vis d&rsquo;un virus mortel&#8230; Nous pouvons vivre nos vies, nos enfants peuvent retourner \u00e0 l&rsquo;\u00e9cole, notre \u00e9conomie reprend son essor\u00a0\u00bb.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>C&rsquo;est un th\u00e8me que Biden a r\u00e9p\u00e9t\u00e9 dans de nombreux discours. Le 13 mai, il a d\u00e9clar\u00e9 que l&rsquo;Am\u00e9rique approchait de la \u00ab\u00a0ligne d&rsquo;arriv\u00e9e\u00a0\u00bb de la pand\u00e9mie. Le 15 juin, il a dit : \u00ab\u00a0L&rsquo;Am\u00e9rique se dirige vers un \u00e9t\u00e9 dramatiquement diff\u00e9rent de celui de l&rsquo;ann\u00e9e derni\u00e8re : un \u00e9t\u00e9 de libert\u00e9, un \u00e9t\u00e9 de joie, un \u00e9t\u00e9 de rencontres et de c\u00e9l\u00e9brations. Un \u00e9t\u00e9 tout am\u00e9ricain que ce pays m\u00e9rite apr\u00e8s le long, long et sombre hiver que nous avons tous endur\u00e9.\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>En r\u00e9alit\u00e9, depuis l&rsquo;annonce par Biden de son \u00ab\u00a0ind\u00e9pendance\u00a0\u00bb vis-\u00e0-vis du COVID-19, les cas ont \u00e9t\u00e9 multipli\u00e9s par sept et les hospitalisations et d\u00e9c\u00e8s sont en hausse, le dangereux variant Delta de la maladie \u00e9tant devenue dominant. Dans les \u00e9picentres de la pand\u00e9mie actuelle, &ndash; Arkansas, Louisiane et Floride &ndash; les cas sont \u00e0 leur plus haut niveau depuis janvier et sont en passe d&rsquo;\u00e9tablir de nouveaux records. <\/em>[&#8230;]<\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0On a signal\u00e9 presque le m\u00eame nombre de cas aujourd&rsquo;hui (70 264) que ce jour-l\u00e0 l&rsquo;ann\u00e9e derni\u00e8re (71 600)\u00a0\u00bb, a d\u00e9clar\u00e9 dimanche Caitlin Rivers, \u00e9pid\u00e9miologiste \u00e0 l&rsquo;Universit\u00e9 Johns Hopkins.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Mais le pire est encore \u00e0 venir. Mercredi dernier, le COVID-19 Scenario Modeling Hub, un consortium de chercheurs travaillant en concertation avec les Centers for Disease Control and Prevention (CDC), a publi\u00e9 un mod\u00e8le montrant que le nombre de d\u00e9c\u00e8s quotidiens dus au COVID-19 aux &Eacute;tats-Unis pourrait atteindre 4 000 d&rsquo;ici octobre, &ndash; le niveau le plus \u00e9lev\u00e9 de toutes les p\u00e9riodes de la pand\u00e9mie.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Bien qu&rsquo;il s&rsquo;agisse du sc\u00e9nario le plus pessimiste du mod\u00e8le, les auteurs de l&rsquo;\u00e9tude soulignent que la pouss\u00e9e actuelle de la pand\u00e9mie est conforme \u00e0 leurs projections ant\u00e9rieures les plus pessimistes. \u00ab\u00a0Ce qui se passe dans le pays avec le virus correspond \u00e0 nos sc\u00e9narios les plus pessimistes\u00a0\u00bb, note Justin Lessler, \u00e9pid\u00e9miologiste \u00e0 l&rsquo;universit\u00e9 de Caroline du Nord, qui participe \u00e0 la gestion du centre de mod\u00e9lisation. <\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>&#8230; Et <em>WSWS.org <\/em>d&rsquo;encha&icirc;ner sur ses exhortations \u00e0 s&rsquo;orienter vers la seule solution envisageable, qui est la liquidation du capitalisme monstrueux et la mise au pas de l&rsquo;oligarchie financi\u00e8re qui ne songe qu&rsquo;\u00e0 ses b\u00e9n\u00e9fices. Qui discuterait la vertu de cette cure ?<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>D\u00e8s le d\u00e9but de la pand\u00e9mie, la r\u00e9ponse des gouvernements du monde entier a \u00e9t\u00e9 enti\u00e8rement anim\u00e9e par l&rsquo;objectif de pr\u00e9server la richesse et les privil\u00e8ges de l&rsquo;oligarchie financi\u00e8re, au d\u00e9triment de la pr\u00e9servation des vies humaines.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>En r\u00e9ponse aux politiques meurtri\u00e8res d'\u00a0\u00bbimmunit\u00e9 collective de la classe dirigeante, les travailleurs doivent exiger des mesures urgentes pour arr\u00eater la propagation de la maladie, y compris la fermeture de toutes les installations de production non essentielles, des lieux de travail et des \u00e9coles, avec une compensation compl\u00e8te pour les salaires perdus et des billions de dollars de d\u00e9penses suppl\u00e9mentaires en soins de sant\u00e9 pour garantir la capacit\u00e9 de tester, de suivre et d&rsquo;isoler chaque cas&#8230;<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>&#8230;Non que nous ne pr\u00e9tendions pas, au travers de notre d\u00e9sint\u00e9r\u00eat sur le sort de la pand\u00e9mie, avoir une opinion, un \u00ab\u00a0point de vue\u00a0\u00bb, sur le sort de la chose (la civilisation), &ndash; on conna&icirc;t notre <em>Delenda Est Systema<\/em>. Simplement, nous croyons qu&rsquo;il est devenu impossible de documenter cette chute, la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-la-gces\">Grande Crise<\/a>, donc de pr\u00e9tendre peu ou prou la pr\u00e9voir dans une forme pr\u00e9cise, dont on se doute bien que les commentateurs de cette sorte d&rsquo;exercice esp\u00e8rent sortir des arguments pour leur propre chapelle, &ndash;m\u00eame et surtout s&rsquo;il s&rsquo;agit d&rsquo;une chapelle fun\u00e9raire.<\/p>\n<\/p>\n<p><p>La Grande Crise est en cours, c&rsquo;est une probabilit\u00e9 intuitive tr\u00e8s forte pour notre compte, mais nous n&rsquo;avons plus depuis un certain temps, et chaque jour de moins en moins, les facteurs s\u00e9lectifs d&rsquo;information qui permettraient d&rsquo;en dire l\u00e0-dessus plus pr\u00e9cis\u00e9ment. Ainsi, le d\u00e9roulement de la pand\u00e9mie, ses hauts et ses bas, son d\u00e9sordre, son caract\u00e8re extraordinairement volatile et insaisissable, nous conduisent \u00e0 nous refuser \u00e0 toute analyse suivie qui conduirait en fait \u00e0 suivre les tensions id\u00e9ologiques, les foucades psychologiques, les envol\u00e9es hyst\u00e9riques des complotistes et les marmonnements bienpensants des bienpensants, les uns et les autres se manifestant de tous les c\u00f4t\u00e9s. Rien de solide, rien de s\u00e9rieux, rien de pr\u00e9visible et encore moins de pr\u00e9visionniste, &ndash; rien qui puisse nous permettre de trancher sur la situation de la Grande Crise&#8230;.<\/p>\n<\/p>\n<p><p>Les textes de <em>WSWS.org <\/em>\u00e9voqu\u00e9s ici, ou celui pr\u00e9sent\u00e9 ci-dessous, le sont donc \u00e0 titre d&rsquo;exemples d&rsquo;une tendance extr\u00eame, interpr\u00e9t\u00e9e par des virtuoses de la documentation s\u00e9lective, bureaucratiques, pr\u00e9cises, entre les impr\u00e9cations antifascistes courantes qui sont redevenues aujourd&rsquo;hui moins embarrassantes pour la lecture depuis le d\u00e9part de Trump qui semait partout et directement l&rsquo;hyst\u00e9rie dans les \u00e2mes sensibles. Cela nous permet d&rsquo;appr\u00e9cier au moins, l\u00e0-dessus sans le moindre doute, que ces JO maintenus co&ucirc;te que co&ucirc;te se r\u00e9alisent dans une atmosph\u00e8re fantomatique, o&ugrave; la folie des psychologies exacerb\u00e9es guettent autant le <em>sapiens<\/em> que le virus Covid21. Ce seront donc des JO de zombies, quoi qu&rsquo;il en soit des performances.<\/p>\n<\/p>\n<p><h4><em>dedefensa.org<\/em><\/h4>\n<\/p>\n<p><p>_________________________<\/p>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Les JO et le spectre de la mort collective<\/h2>\n<\/p>\n<p><p>Les Jeux olympiques d&rsquo;\u00e9t\u00e9 se sont ouverts jeudi avec en toile de fond une pouss\u00e9e massive de la pand\u00e9mie de COVID-19. &Agrave; l&rsquo;instar des Jeux olympiques de Berlin de 1936 qui ont pr\u00e9c\u00e9d\u00e9 le d\u00e9clenchement de la Seconde Guerre mondiale et les horreurs qui l&rsquo;ont accompagn\u00e9e, les jeux de cette ann\u00e9e laissent planer le danger imminent d&rsquo;une trag\u00e9die humaine.<\/p>\n<\/p>\n<p><p>Les Jeux olympiques de 2020 n&rsquo;ont pas eu lieu l&rsquo;ann\u00e9e derni\u00e8re, au moment de la premi\u00e8re vague de la pand\u00e9mie. Les jeux se d\u00e9roulent maintenant sous le pr\u00e9texte que la pand\u00e9mie est maitris\u00e9e et que le rassemblement de masse des athl\u00e8tes et de leur personnel d&rsquo;encadrement est sans danger.<\/p>\n<\/p>\n<p><p>Mais cette illusion est mise \u00e0 mal par l&rsquo;augmentation massive des cas de COVID-19 \u00e0 l&rsquo;int\u00e9rieur du village olympique et dans le monde entier.<\/p>\n<\/p>\n<p><p> &laquo;Dans le temps qu&rsquo;il me faut pour faire ces remarques, plus de 100 personnes perdront la vie \u00e0 cause du COVID-19&raquo;, a not\u00e9 le directeur g\u00e9n\u00e9ral de l&rsquo;Organisation mondiale de la sant\u00e9, le Dr Tedros Adhanom Ghebreyesus, dans ses remarques au Comit\u00e9 international olympique mercredi. &laquo;Et d&rsquo;ici \u00e0 ce que la flamme olympique s&rsquo;\u00e9teigne le 8 ao&ucirc;t, plus de 100.000 personnes suppl\u00e9mentaires p\u00e9riront.&raquo;<\/p>\n<\/p>\n<p><p>Dans le monde entier, le nombre de nouveaux cas quotidiens de COVID-19 a augment\u00e9 de 47 pour cent au cours du mois dernier pour atteindre plus de 523.000 cas par jour, et le nombre de d\u00e9c\u00e8s quotidiens s&rsquo;\u00e9l\u00e8ve \u00e0 7.900.<\/p>\n<\/p>\n<p><p>Les cas parmi les dizaines de milliers d&rsquo;athl\u00e8tes et de membres du personnel olympique se propagent \u00e9galement. Cent dix personnes qui travaillent directement pour les Jeux olympiques ou qui y participent ont \u00e9t\u00e9 infect\u00e9es jusqu&rsquo;\u00e0 pr\u00e9sent. Parmi eux environ deux tiers sont des citoyens japonais qui travaillent pour les Jeux et les autres sont des athl\u00e8tes ou des membres du personnel des \u00e9quipes nationales qui ont voyag\u00e9 depuis l&rsquo;\u00e9tranger. Au moins quatre des cas sont survenus dans des municipalit\u00e9s en dehors de Tokyo o&ugrave; les athl\u00e8tes s&rsquo;entra&icirc;nent, ce qui indique l&rsquo;\u00e9tendue de la propagation, et des dizaines d&rsquo;autres ont \u00e9t\u00e9 en contact \u00e9troit avec les personnes infect\u00e9es.<\/p>\n<\/p>\n<p><p>Le fait que tant de personnes aient \u00e9t\u00e9 infect\u00e9es montre clairement que les mesures symboliques qui visent \u00e0 isoler les athl\u00e8tes du reste de la population et vice versa ont \u00e9chou\u00e9. Le d\u00e9compte effectu\u00e9 par Forbes montre que les infections se sont produites avant et apr\u00e8s l&rsquo;arriv\u00e9e des athl\u00e8tes au Japon, ainsi que chez plusieurs d&rsquo;entre eux qui sont parfaitement vaccin\u00e9s et ont pris toutes les pr\u00e9cautions n\u00e9cessaires contre le virus.<\/p>\n<\/p>\n<p><p>Hans Westerbeek, professeur \u00e0 l&rsquo;Institut de la sant\u00e9 et du sport de l&rsquo;Universit\u00e9 de Victoria, en Australie, a pr\u00e9venu dans une interview accord\u00e9e \u00e0 Newsweek: &laquo;les cas de COVID chez les athl\u00e8tes signal\u00e9s \u00e0 Tokyo sont tr\u00e8s probablement le d\u00e9but d&rsquo;une super-propagation&raquo;. Il a ajout\u00e9: &laquo;&Eacute;tant donn\u00e9 la proximit\u00e9 des athl\u00e8tes et de leurs \u00e9quipes, ainsi que les d\u00e9placements et les interactions constants dans les quartiers d&rsquo;habitation, les r\u00e9fectoires et les sites d&rsquo;entra&icirc;nement et de comp\u00e9tition, le virus est susceptible de se propager rapidement.&raquo;<\/p>\n<\/p>\n<p><p>En d&rsquo;autres termes, chaque athl\u00e8te participe \u00e0 deux concours diff\u00e9rents: la poursuite athl\u00e9tique et le repoussement des limites de l&rsquo;accomplissement physique humain, tout en \u00e9tant dans une course effrayante pour \u00e9chapper \u00e0 l&rsquo;infection.<\/p>\n<\/p>\n<p><p>Le Japon, pays h\u00f4te des Jeux olympiques, enregistre plus de 3.500 nouveaux cas de COVID-19 par jour, dont pr\u00e8s de 1.400 pour la seule ville de Tokyo, et ce chiffre est en augmentation. Au total, le Japon a connu plus de 852.000 cas de la maladie et 15.000 d\u00e9c\u00e8s enregistr\u00e9s, dont la grande majorit\u00e9 est survenue depuis le d\u00e9but de cette ann\u00e9e.<\/p>\n<\/p>\n<p><p>Les sondages montrent que jusqu&rsquo;\u00e0 83 pour cent de la population japonaise s&rsquo;oppose \u00e0 la tenue des Jeux olympiques cette ann\u00e9e. Des manifestants se sont rassembl\u00e9s devant le stade national pendant la c\u00e9r\u00e9monie d&rsquo;ouverture en scandant &laquo;Annulez les Jeux olympiques! Arr\u00eatez-les imm\u00e9diatement! Arr\u00eatez la c\u00e9r\u00e9monie d&rsquo;ouverture maintenant!&raquo;<\/p>\n<\/p>\n<p><p>Une p\u00e9tition en ligne sur change.org, intitul\u00e9e &laquo;Annulez les Jeux olympiques de Tokyo pour prot\u00e9ger nos vies&raquo;, a recueilli jusqu&rsquo;\u00e0 pr\u00e9sent plus de 458.000 signatures. Elle pose la question pr\u00e9cise suivante: &laquo;L&rsquo;organisation des Jeux olympiques vaut-elle la peine de risquer nos vies?&raquo;<\/p>\n<\/p>\n<p><p>Malgr\u00e9 les menaces mortelles qui p\u00e8sent sur la vie des athl\u00e8tes, de leurs entra&icirc;neurs, du personnel des stades et de la population en g\u00e9n\u00e9ral, le pr\u00e9sident du Comit\u00e9 international olympique (CIO) Thomas Bach, a affirm\u00e9 que les Jeux olympiques \u00e9taient &laquo;s&ucirc;rs et s\u00e9curis\u00e9s&raquo; et qu&rsquo;ils se poursuivraient jusqu&rsquo;au 8 ao&ucirc;t.<\/p>\n<\/p>\n<p><p>Ces d\u00e9clarations expriment l&rsquo;ignorance et la cruaut\u00e9 d&rsquo;une part, notamment \u00e0 l&rsquo;\u00e9gard des athl\u00e8tes eux-m\u00eames, et des int\u00e9r\u00eats de classe nus d&rsquo;autre part.<\/p>\n<\/p>\n<p><p>Il y a, bien s&ucirc;r, une immense quantit\u00e9 d&rsquo;argent investie dans les jeux, environ 15 milliards de dollars. Le CIO a \u00e9galement des contrats de diffusion et de sponsoring qu&rsquo;il cherche \u00e0 prot\u00e9ger, dont la valeur est estim\u00e9e \u00e0 5,7 milliards de dollars.<\/p>\n<\/p>\n<p><p>Mais un motif encore plus sinistre est \u00e0 l&rsquo;&oelig;uvre. Parmi les classes dirigeantes du monde, les Jeux olympiques sont consid\u00e9r\u00e9s comme une grande exp\u00e9rience qui vise \u00e0 d\u00e9terminer s&rsquo;il est possible, selon la devise des Jeux, de &laquo;regarder en avant&raquo; en reprenant l&rsquo;activit\u00e9 \u00e9conomique alors m\u00eame que les cas, les hospitalisations et les d\u00e9c\u00e8s explosent.<\/p>\n<\/p>\n<p><p>Selon le <em>Wall Street Journal<\/em>, le monde est en train de r\u00e9aliser un &laquo;test&raquo; pour savoir s&rsquo;il est possible de &laquo;profiter d&rsquo;une vie proche de celle d&rsquo;avant la pand\u00e9mie face \u00e0 des versions du virus qui se transmettent rapidement&raquo;.<\/p>\n<\/p>\n<p><p>&laquo;L&rsquo;exp\u00e9rience devrait indiquer clairement si le Covid-19 peut \u00eatre rel\u00e9gu\u00e9 au rang de menace saisonni\u00e8re g\u00e9rable, comme la grippe, et si les confinements et la distanciation sociale peuvent \u00eatre rel\u00e9gu\u00e9s au pass\u00e9.&raquo;<\/p>\n<\/p>\n<p><p>Les Jeux olympiques sont \u00e9galement une exp\u00e9rience cruelle, dans laquelle les athl\u00e8tes, le personnel et la population du Japon doivent \u00eatre des sujets d&rsquo;essai pour d\u00e9terminer &laquo;si le confinement et la distanciation sociale peuvent \u00eatre rel\u00e9gu\u00e9s au pass\u00e9&raquo;.<\/p>\n<\/p>\n<p><p>La logique d&rsquo;une telle &laquo;exp\u00e9rience&raquo; est de transformer la plan\u00e8te enti\u00e8re en une bo&icirc;te de Petri pour le coronavirus, produisant presque in\u00e9vitablement un variant qui va &laquo;plus vite, plus haut, plus fort&raquo; que m\u00eame le virulent variant Delta responsable de la plus r\u00e9cente vague mondiale, mettant dans la balance la vie de chaque personne sur la plan\u00e8te.<\/p>\n<\/p>\n<p><p>En 1936, les Jeux olympiques de Berlin ont \u00e9t\u00e9 utilis\u00e9s par le parti fasciste nazi pour faire avancer ses conceptions id\u00e9ologiques de supr\u00e9matie raciale et d&rsquo;antis\u00e9mitisme. De m\u00eame, les Jeux olympiques de 2020 sont con\u00e7us pour envoyer un message id\u00e9ologique de la classe capitaliste \u00e0 la population mondiale: aucune mesure ne sera prise pour sauver des vies humaines, quel qu&rsquo;en soit le co&ucirc;t.<\/p>\n<\/p>\n<p><p>Tout doit \u00eatre mis en &oelig;uvre pour lutter contre ces politiques meurtri\u00e8res. L&rsquo;indignation populaire face \u00e0 la mise en danger inconsid\u00e9r\u00e9e de la vie humaine qui s&rsquo;est manifest\u00e9e au Japon, ainsi qu&rsquo;ailleurs dans le monde, doit \u00eatre dirig\u00e9e selon des lignes politiques ind\u00e9pendantes contre l&rsquo;ordre social capitaliste et sa subordination de la vie humaine aux int\u00e9r\u00eats de profit de l&rsquo;oligarchie financi\u00e8re.<\/p>\n<\/p>\n<p><p>(Article paru en anglais le <a href=\"https:\/\/www.wsws.org\/en\/articles\/2021\/07\/24\/pers-j24.html\">24 juillet 2021<\/a>)<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In\u00e9luctable m\u00e9daille d&rsquo;or pour Covid21 &bull; Articles du 26 juillet 23021. &bull; D&rsquo;une certaine fa\u00e7on, on pourrait dire que les JO de l&rsquo;\u00e9trange ann\u00e9e 2021 (ex-2020) ne seront pas infect\u00e9s par l&rsquo;inf\u00e2me virus du nationalisme du fait que toutes les m\u00e9dailles d&rsquo;or sont et seront d&rsquo;office attribu\u00e9es \u00e0 un virus globaliste-internationaliste. &bull; Covid21est effectivement le&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[2997,7719,14989,8742,6320,21031,5169],"class_list":["post-79847","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-extremes","tag-jeux","tag-mesures","tag-olympiques","tag-pandemie","tag-tokyo","tag-wsws-org"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79847"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79847\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79847"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79847"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}