{"id":79858,"date":"2021-08-04T21:36:32","date_gmt":"2021-08-04T21:36:32","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2021\/08\/04\/rapsit-usa2021-covid-est-il-raciste\/"},"modified":"2021-08-04T21:36:32","modified_gmt":"2021-08-04T21:36:32","slug":"rapsit-usa2021-covid-est-il-raciste","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2021\/08\/04\/rapsit-usa2021-covid-est-il-raciste\/","title":{"rendered":"RapSit-USA2021\u00a0: Covid est-il raciste\u00a0?"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">RapSit-USA2021 : Covid est-il raciste ?<\/h2>\n<\/p>\n<p><p>Dr\u00f4le de meccano&#8230; O&ugrave; l&rsquo;on trouve, dans le cadre des agitations wokenistes (y compris Covid) qui secouent New York City une \u00e9trange occurrence nous donnant une image assez fid\u00e8le quoique joliment contrast\u00e9e des variables de la super crise qui est devenue la r\u00e8gle quotidienne des &Eacute;tats-Unis. On retrouve les m\u00eames pressions et paradoxes des crises qui s&rsquo;entrechoquent et se contredisent que dans nombre de pays, sp\u00e9cialement du <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-bloc-bao-1\">bloc-BAO<\/a>&#8230;<\/p>\n<\/p>\n<p><p>Une fois de plus, New York City, la ville-pilote de la modernit\u00e9, nous montre le chemin ; on notera qu&rsquo;il n&rsquo;est pas exactement attrayant, entre racisme et apartheid-Covid, corruption des \u00e9lites et <em>narrative <\/em>\u00e0 s&rsquo;\u00e9veiller debout (<em>woke up<\/em>, wokenisme !)&#8230;<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>Le maire de New York City, Bill de Blasio, a annonc\u00e9 mardi que les habitants de la ville la plus peupl\u00e9e des &Eacute;tats-Unis devront pr\u00e9senter un passe-sanitaire baptis\u00e9e \u00ab\u00a0Key to NYC Pass\u00a0\u00bb, pour pouvoir entrer dans un restaurant, dans une salle de sport ou dans un lieu de divertissement couvert, quel qu&rsquo;il soit.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Le passe-sanitaire du maire de Blasio est le premier acte de ce type aux &Eacute;tats-Unis. Il intervient un jour seulement apr\u00e8s que le gouverneur de l&rsquo;&Eacute;tat de New York Andrew Cuomo ait appel\u00e9 les entreprises priv\u00e9es \u00e0 discriminer les personnes non vaccin\u00e9es afin d&rsquo;inciter les New-Yorkais \u00e0 se faire vacciner.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Alors qu&rsquo;une grande partie de l&rsquo;indignation courante<\/em> [autoris\u00e9e] <em>s&rsquo;est concentr\u00e9e mardi sur l&rsquo;annonce par la procureure g\u00e9n\u00e9rale de l&rsquo;&Eacute;tat, Letitia James, des all\u00e9gations d&rsquo;inconduite sexuelle de Cuomo avec son personnel f\u00e9minin, mais sans inculpation p\u00e9nale, plus d&rsquo;un critique a soulign\u00e9 que le maire et le gouverneur soutiennent une exigence identitaire bien plus contraignante que l&rsquo;obligation de pr\u00e9senter une carte d&rsquo;identit\u00e9 pour voter, que leurs coll\u00e8gues d\u00e9mocrates ont d\u00e9nonc\u00e9 comme raciste<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>Le journaliste ind\u00e9pendant <a href=\"https:\/\/twitter.com\/mtracey\/status\/1422591448982163464?ref_src=twsrc%5Etfw%7Ctwcamp%5Etweetembed%7Ctwterm%5E1422591448982163464%7Ctwgr%5E%7Ctwcon%5Es1_&#038;ref_url=https%3A%2F%2Fwww.rt.com%2Fusa%2F531055-vaccine-pass-racist-voter-id%2F\">Michael Tracey<\/a> s&rsquo;est appuy\u00e9 sur les statistiques de vaccination, &ndash; montrant que seulement 38 % des Afro-Am\u00e9ricains de la ville de New York ont \u00e9t\u00e9 vaccin\u00e9s<\/em> [contre 81% des Asiatiques-Am\u00e9ricains, 53% des Latinos et 53% des Blancs], <em>&ndash; pour affirmer l&rsquo;\u00e9vidence : cette politique aura un impact racial d&rsquo;apartheid d\u00e9favorable aux Noirs<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>Pourtant, les progressistes de la ville ont applaudi \u00e0 cette politique, a-t-il ajout\u00e9, bien qu&rsquo;elle viole la seule norme <\/em>[le racisme] <em>\u00e0 laquelle ils semblent normalement s&rsquo;int\u00e9resser<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>Interrog\u00e9e \u00e0 ce sujet mardi apr\u00e8s-midi, l&rsquo;attach\u00e9e de presse de la Maison Blanche, <a href=\"https:\/\/twitter.com\/CurtisHouck\/status\/1422639077111865352?ref_src=twsrc%5Etfw%7Ctwcamp%5Etweetembed%7Ctwterm%5E1422639077111865352%7Ctwgr%5E%7Ctwcon%5Es1_&#038;ref_url=https%3A%2F%2Fwww.rt.com%2Fusa%2F531055-vaccine-pass-racist-voter-id%2F\">Jan Psaki<\/a>, a d\u00e9clar\u00e9 que l&rsquo;objectif de l&rsquo;administration Biden \u00e9tait de \u00ab\u00a0combler cet \u00e9cart d&rsquo;\u00e9quit\u00e9\u00a0\u00bb, &ndash; expression rest\u00e9e incertaine quant \u00e0 sa signification, &ndash; mais elle a ajout\u00e9 que les villes et les communaut\u00e9s locales \u00ab\u00a0devraient pouvoir prendre des mesures pour inciter davantage de personnes \u00e0 se faire vacciner\u00a0\u00bb, approuvant ainsi implicitement la d\u00e9cision de Blasio.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>C&rsquo;est la m\u00eame administration Biden qui a d\u00e9clar\u00e9 que la loi sur l&rsquo;int\u00e9grit\u00e9 des \u00e9lections en G\u00e9orgie, exigeant une pi\u00e8ce d&rsquo;identit\u00e9 pour voter par correspondance, \u00e9tait \u00ab\u00a0une loi Jim Crow<\/em> [loi d&rsquo;apartheid dans le Sud de la fin du XIXe si\u00e8cle] <em>trait\u00e9e aux st\u00e9ro\u00efdes\u00a0\u00bb et qui a demand\u00e9 au minist\u00e8re de la Justice de poursuivre l&rsquo;&Eacute;tat au motif de racisme<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Cette question a soulev\u00e9 chez certains des interrogations sur la &laquo; <em>gymnastique mentale<\/em> &raquo; qu&rsquo;allaient devoir pratiquer les d\u00e9mocrates pour justifier, ou plut\u00f4t \u00ab\u00a0effacer\u00a0\u00bb (\u00ab\u00a0<em>to cancel<\/em>\u00ab\u00a0) ces \u00e9tranges disparit\u00e9s on ne peut plus racistes. En fait de \u00ab\u00a0gymnastique\u00a0\u00bb, Psaki a laiss\u00e9, dans sa salle de presse, l&rsquo;une ou l&rsquo;autre rare question sur le sujet simplement sans r\u00e9ponse. La plupart des journalistes de la presseSyst\u00e8me accr\u00e9dit\u00e9s et pr\u00e9sents, ont eux aussi baill\u00e9 d&rsquo;indiff\u00e9rence devant le probl\u00e8me ainsi soulev\u00e9. Toute cette chor\u00e9graphie devant tout \u00e0 la \u00ab\u00a0<em>cancel culture<\/em>\u00a0\u00bb appliqu\u00e9e \u00e0 soi-m\u00eame est r\u00e9gl\u00e9e comme du papier \u00e0 musique, et les meilleurs journalistes du monde comme les accr\u00e9dit\u00e9s presseSyst\u00e8me \u00e0 la Maison-Blanche se consid\u00e8rent, sont des danseurs hors-pair.<\/p>\n<\/p>\n<p><p>Il reste donc les brebis galeuses des r\u00e9seaux sociaux maudits pour effectivement faire quelques remarques qui ne vont pas dans le sens du vent. On en cite quelques-unes :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>\u00ab\u00a0Une preuve de vaccination pour faire n&rsquo;importe quelle activit\u00e9 est estim\u00e9e acceptable, mais une pi\u00e8ce d&rsquo;identit\u00e9 avec photo pour voter est une charge d\u00e9raisonnable\u00a0\u00bb, a tweet\u00e9 <a href=\"https:\/\/twitter.com\/LevineJonathan\/status\/1422611638977433607\">Jonathan Levine<\/a> du New York Post.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0Donc c&rsquo;est raciste de rendre obligatoire la carte d&rsquo;identit\u00e9 des \u00e9lecteurs mais pas de rendre obligatoire la carte d&rsquo;identit\u00e9 des vaccins ? Cela me semble hypocrite\u00a0\u00bb, a ironis\u00e9 le commentateur politique <a href=\"https:\/\/twitter.com\/TheNicholasSams\/status\/1422639532642557955?ref_src=twsrc%5Etfw%7Ctwcamp%5Etweetembed%7Ctwterm%5E1422639532642557955%7Ctwgr%5E%7Ctwcon%5Es1_&#038;ref_url=https%3A%2F%2Fwww.rt.com%2Fusa%2F531055-vaccine-pass-racist-voter-id%2F\">Nicholas Sams<\/a>.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0J&rsquo;ai v\u00e9cu ici toute ma vie. J&rsquo;en ai fini. Je vais planifier mon d\u00e9m\u00e9nagement en <\/em>[Floride]<em> ou au <\/em>[Texas]<em> imm\u00e9diatement\u00a0\u00bb <\/em>[deux &Eacute;tats qui ne pratiquent ni le masque ni le passe-sanitaire]<em>, a \u00e9crit l&rsquo;artiste <a href=\"https:\/\/twitter.com\/NotMikeHarlow\/status\/1422561699719176192?ref_src=twsrc%5Etfw%7Ctwcamp%5Etweetembed%7Ctwterm%5E1422561699719176192%7Ctwgr%5E%7Ctwcon%5Es1_&#038;ref_url=https%3A%2F%2Fwww.rt.com%2Fusa%2F531055-vaccine-pass-racist-voter-id%2F\">Mike Harlow<\/a>, ajoutant : \u00ab\u00a0Nous obtenons le fascisme que nous permettons. Nous avons permis cela.\u00a0\u00bb<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Cette passe d&rsquo;arme est remarquable en ce qu&rsquo;elle nous donne un condens\u00e9 des sous-crises qui structures la Grande Crise, et m\u00eame des interp\u00e9n\u00e9trations in\u00e9dites nous confirmant combien le Covid est compl\u00e8tement int\u00e9gr\u00e9e comme crise politique, soci\u00e9tale et psychologique s&rsquo;adaptant parfaitement \u00e0 la crise du wokenisme.<\/p>\n<\/p>\n<p><p>&bull; Effectivement, le passe-sanitaire officialise bruyamment et racistement pourrait-on dire, sinon fascistement (ne l\u00e9sinons pas sur les n\u00e9ologismes) cette int\u00e9gration fondamentale dans la dimension politique la plus aig\u00fce de la crise. Le classement par communaut\u00e9s (ou ethnies, ou races, selon l&rsquo;humeur), pratiqu\u00e9e syst\u00e9matiquement aux USA, met en \u00e9vidence un apartheid raciste largement aux d\u00e9pens des Noirs (on l&rsquo;a vu, 38% de vaccin\u00e9s noirs, contre 53% de Blancs et de Latinos, et 83% d&rsquo;Asiatiques). Les Noirs se retrouvent avec une situation qui rappelle en partie celles qu&rsquo;ils v\u00e9curent dans le Sud, m\u00eame en plus s\u00e9v\u00e8re puisque tous les lieux publics de rassemblement sont interdits d&rsquo;acc\u00e8s \u00e0 une grande majorit\u00e9 d&rsquo;entre eux, non vaccin\u00e9s (dans le Sud de l&rsquo;<em>apartheid<\/em>, il y avait de tels lieux publics r\u00e9serv\u00e9s pour eux, &lsquo;<em>Colored Only<\/em>&lsquo;). Cette situation rejoint les critiques antiracistes affirmant que les Noirs sont plus touch\u00e9s par le Covid que les autres communaut\u00e9s ; d&rsquo;autre part, la faible vaccination des Noirs vient \u00e9galement du souvenir r\u00e9cent des exp\u00e9rimentations m\u00e9dicales sur la syphilis pratiqu\u00e9es \u00e0 leur insu sur des Noirs \u00e0 <a href=\"https:\/\/fr.wikipedia.org\/wiki\/\u00c9tude_de_Tuskegee_sur_la_syphilis\">Tuskagee<\/a>, de 1932 jusqu&rsquo;en 1970.<\/p>\n<\/p>\n<p><p>&bull; Ainsi voit-on deux crises sanitaires soci\u00e9tales s&rsquo;imbriquer et se contredire, celle du wokenisme (de l&rsquo;antiracisme) et celle du Covid. La pr\u00e9f\u00e9rence est donn\u00e9e absolument au Covid, et le d\u00e9cha&icirc;nement antiraciste des d\u00e9mocrates et de leurs alli\u00e9s (notamment de la presseSyst\u00e8me) se perd dans les souterrains de l&rsquo;indiff\u00e9rence programm\u00e9e avec indolence. Il n&#8217;emp\u00eache, New York City n&rsquo;est qu&rsquo;un d\u00e9but pour le passe-sanitaire aux USA, et cette mesure du passe-sanitaire est favoris\u00e9e dans les &Eacute;tats d\u00e9mocrates. Les d\u00e9mocrates vont donc devoir continuer \u00e0 se contorsionner pour \u00e9viter les questions qui f\u00e2chent, puisque partout les Noirs sont de loin les moins nombreux \u00e0 se faire vacciner.<\/p>\n<\/p>\n<p><p>&bull; Pendant qu&rsquo;est pratiqu\u00e9e dans l&rsquo;indiff\u00e9rence g\u00e9n\u00e9rale une mesure de passe-sanitaire obligatoire dans les lieux publics, mesure d\u00e9j\u00e0, largement contest\u00e9e en elle-m\u00eame et qui s&rsquo;av\u00e8re raciste \u00e0 l&rsquo;insu de son plein gr\u00e9, une autre crise est en train de m&ucirc;rir, &ndash; cette fois, au c&oelig;ur du parti d\u00e9mocrate, et mesurant le degr\u00e9 d&rsquo;antagonisme et de corruption qu&rsquo;atteignent les directions du parti. En r\u00e9clamant publiquement la d\u00e9mission du Cuomo pour harc\u00e8lements sexuels, voire pire, \u00e0 l&rsquo;encontre de diverses employ\u00e9es f\u00e9minines de son \u00e9quipe, on pourrait penser que Biden a liquid\u00e9 le gouverneur Cuomo. Ce n&rsquo;est pas tout \u00e0 fait assur\u00e9, comme le montre l&rsquo;attitude actuelle (qui peut \u00e9voluer, certes) de la procureure de l&rsquo;&Eacute;tat Letitia James : elle rend publique le rapport accablant des accusations des victimes de Cuomo mais ne prononce (pour l&rsquo;instant) aucune inculpation. La bataille est intense entre la direction d\u00e9mocrate, que relaie Biden, et Cuomo qui affirme, selon un <a href=\"https:\/\/redstate.com\/tladuke\/2021\/08\/03\/new-york-speaker-of-the-house-signals-cuomo-impeachment-will-happen-n420890\">article critique<\/a>, que &laquo; <em>tout le monde ment et<\/em> [qu&rsquo;]<em>il est innocent. Il a m\u00eame r\u00e9ussi \u00e0 utiliser une histoire d&rsquo;agression sexuelle d&rsquo;un membre de sa famille pour se d\u00e9fendre, car ce type n&rsquo;a aucune honte<\/em>. &raquo; Il est probable que l&rsquo;on se dirige vers une proc\u00e9dure de destitution par le Congr\u00e8s de l&rsquo;&Eacute;tat de New York, qui va d\u00e9chirer le parti d\u00e9mocrate et mettre \u00e0 jour des corruptions diverses en son sein, &ndash; puisque Cuomo ne veut pas, dans tous les cas jusqu&rsquo;ici, \u00ab\u00a0coop\u00e9rer\u00a0\u00bb, c&rsquo;est-\u00e0-dire d\u00e9missionner.<\/p>\n<\/p>\n<p><p>Tout cela est int\u00e9ressant si l&rsquo;on consid\u00e8re New York City comme cette \u00ab\u00a0ville-pilote de la modernit\u00e9\u00a0\u00bb d\u00e9j\u00e0 signal\u00e9e plus haut. La puissance extraordinaire des ph\u00e9nom\u00e8nes crisiques du wokenisme et du Covid, entra&icirc;ne \u00e9galement des d\u00e9chirements, des contradictions et des antagonismes chez ceux-l\u00e0 m\u00eame qui manipulent ces ph\u00e9nom\u00e8nes, &ndash; qui les manipulent non pas parce qu&rsquo;ils les ont provoqu\u00e9s mais simplement parce qu&rsquo;ils sont aux manettes et entendent en faire profiter leurs int\u00e9r\u00eats et leur id\u00e9ologisation. L&rsquo;avantage paradoxal de la d\u00e9structuration accompagnant la d\u00e9construction est qu&rsquo;elle atteint tr\u00e8s vite, \u00e0 cause de sa puissance irr\u00e9sistible et indompt\u00e9e, un domaine o&ugrave; elle se d\u00e9construit et se d\u00e9structure elle-m\u00eame, si bien que les deux ph\u00e9nom\u00e8nes tendent tr\u00e8s vite \u00e0 s&rsquo;accomplir presque simultan\u00e9ment.<\/p>\n<\/p>\n<p><p>New York City est un excellent exemple, si l&rsquo;on a \u00e0 l&rsquo;esprit qu&rsquo;il s&rsquo;agit d&rsquo;un des principaux berceaux (avec la Californie et San Francisco) de l&rsquo;int\u00e9gration politique du wokenisme, du gauchisme soci\u00e9tal et mondain, avec des vedettes du mouvement tr\u00f4nant dans leur Capitole, si proches soudain d&rsquo;\u00eatre balanc\u00e9es de la Roche Tarp\u00e9ienne. Cuomo, super \u00ab\u00a0grande gueule\u00a0\u00bb s&rsquo;il en est, avait atteint un tel degr\u00e9 de vedettariat lors de la premi\u00e8re vague du Covid au printemps 2020 qu&rsquo;il \u00e9tait tr\u00e8s vite apparu, pendant plusieurs semaines et pour une partie importante des d\u00e9mocrates,  comme une alternative naturelle sinon \u00e9vidente au toussotant Biden, &ndash; bref un homme \u00e0 la stature pr\u00e9sidentielle ; voil\u00e0 qu&rsquo;il est d\u00e9sormais sur la voie d&rsquo;un calvaire emportant tous ses espoirs, une destitution probable pour abus et d\u00e9lits sexuels.<\/p>\n<\/p>\n<p><p>Mis en ligne le 4 ao&ucirc;t 2021 \u00e0 21H35<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>RapSit-USA2021 : Covid est-il raciste ? Dr\u00f4le de meccano&#8230; O&ugrave; l&rsquo;on trouve, dans le cadre des agitations wokenistes (y compris Covid) qui secouent New York City une \u00e9trange occurrence nous donnant une image assez fid\u00e8le quoique joliment contrast\u00e9e des variables de la super crise qui est devenue la r\u00e8gle quotidienne des &Eacute;tats-Unis. On retrouve les&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[21],"tags":[21111,15448,5513,11618,21110,4911,3256,21108,3424,17958,2646,3257],"class_list":["post-79858","post","type-post","status-publish","format-standard","hentry","category-breves-de-crise","tag-anti-noirs","tag-apartheid","tag-city","tag-cuomo","tag-delits","tag-destitution","tag-new","tag-passe-sanitaire","tag-racisme","tag-sexuels","tag-wokenisme","tag-york"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79858"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79858\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}