{"id":79864,"date":"2021-08-11T17:01:35","date_gmt":"2021-08-11T17:01:35","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2021\/08\/11\/histoire-tweetee-de-vaccin\/"},"modified":"2021-08-11T17:01:35","modified_gmt":"2021-08-11T17:01:35","slug":"histoire-tweetee-de-vaccin","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2021\/08\/11\/histoire-tweetee-de-vaccin\/","title":{"rendered":"Histoire tweet\u00e9e de vaccin"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Histoire tweet\u00e9e de vaccin<\/h2>\n<\/p>\n<p><p>11 ao&ucirc;t 2021 &ndash; Nous sommes au temps des m\u00e9moires courtes puisque le Temps passe si vite et ne nous laisse aucune dur\u00e9e. L&rsquo;amour fou du Syst\u00e8me pour le vaccin, qui va jusqu&rsquo;aux anath\u00e8mes venus du fond des Temps pour les anti-vaxx, s&rsquo;accompagne du souvenir furieux de celui qui a sans aucun doute introduit cette peste, cette contagion, r\u00e9sistance monstrueuse au Progr\u00e8s, le d\u00e9clencheur de tous les fascismes et populismes. C&rsquo;est dire si le souvenir nous remet en m\u00e9moire le monstrueux Trump, cause de tout ce d\u00e9sordre et donc de la r\u00e9sistance anti-vaxx, &ndash; n&rsquo;est-il pas ?<\/p>\n<\/p>\n<p><p>Pourtant, si l&rsquo;on prend un peu de potion pour la faire un peu moins courte, la m\u00e9moire, l&rsquo;on se rappelle qu&rsquo;il y eut une r\u00e9union le 2 mars 2020 (je r\u00e9p\u00e8te : &lsquo;2020&rsquo;), \u00e0 la Maison-Blanche, entre Trump &#038; son \u00e9quipe d&rsquo;une part, les grands patrons-friqu\u00e9s de <em>Big Pharma <\/em>d&rsquo;autre part. Le 2 avril 2020, il y eut le lancement par la Maison-Blanche du programme &lsquo;<em><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Op\u00e9ration_Warp_Speed\">Operation Warp Speed<\/a><\/em>&lsquo;, Trump annon\u00e7ant que par ce processus pouvoir f\u00e9d\u00e9ral\/secteur priv\u00e9 acc\u00e9l\u00e9r\u00e9, il y aurait des vaccins \u00e0 la fin de l&rsquo;ann\u00e9e (2020).<\/p>\n<\/p>\n<p><p>L&rsquo;on rit bien fort alors dans les chaumi\u00e8res et dans les colonnes de la presseSyst\u00e8me : \u00ab\u00a0Ce type est fou\u00a0\u00bb, \u00ab\u00a0encore une <em>FakeNews<\/em>\u00ab\u00a0, \u00ab\u00a0ces vaccins seront du bidon, du poison-g\u00e9nocidaire, de l&rsquo;arsenic d\u00e9guis\u00e9e en vaxx, s&rsquo;en \u00e9loigner absolument\u00a0\u00bb. Le jugement g\u00e9n\u00e9ral \u00e9tait, finalement, que Trump lan\u00e7ait une op\u00e9ration compl\u00e8tement folle pour se faire valoir et r\u00e9\u00e9lire, et que, de toutes les fa\u00e7ons, rien de bon ne pouvait venir de ce type, fasciste, populiste &#038; Cie. Bref, les hordes-Syst\u00e8me du gauchisme-wokeniste, de la presseSyst\u00e8me, des autorit\u00e9s sanitaires convenables, se m\u00e9fiaient grandement et \u00e0 juste titre moralinateur, et enfin juraient bien qu&rsquo;elles en resteraient aux masques, confinements et le reste, et jamais ne c\u00e9deraient \u00e0 ces vaccins trumpistes qui ne seraient que vaste simulacre fasc(h)o-populiste.<\/p>\n<\/p>\n<p><p>Un exemple de ce sentiment d&rsquo;hostilit\u00e9, \u00e0 Trump \u00e9videmment jusqu&rsquo;\u00e0 l&rsquo;hyst\u00e9rie d\u00e9mente, et par cons\u00e9quent au vaccin tout aussi radicalement, comme aucun anti-vaxx d&rsquo;aujourd&rsquo;hui n&rsquo;oserait se poser: Joy Ann Reid, pr\u00e9sentatrice de la cha&icirc;ne pro-d\u00e9mocrate (pro-Biden), ultra-<em>woke <\/em>MSNBC, avec ces <a href=\"https:\/\/twitter.com\/JoyAnnReid\/status\/1306762204058914823\">deux<\/a> <a href=\"https:\/\/twitter.com\/JoyAnnReid\/status\/1306762734076342273\">tweets<\/a> cons\u00e9cutifs le 18 septembre 2020 :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&bull; &laquo; <em>L&rsquo;administration Trump a tellement bris\u00e9 le gouvernement f\u00e9d\u00e9ral et plusieurs gouvernements d&rsquo;&Eacute;tat gr\u00e2ce \u00e0 des gouverneurs flagorneurs comme <a href=\"https:\/\/twitter.com\/RonDeSantisFL\">@RonDeSantisFL<\/a><\/em><em>, <\/em><em><a href=\"https:\/\/twitter.com\/BrianKempGA\">@BrianKempGA<\/a><\/em><em>, <\/em><em><a href=\"https:\/\/twitter.com\/GregAbbott_TX\">@GregAbbott_TX<\/a><\/em><em>, <\/em><em><a href=\"https:\/\/twitter.com\/KristiNoem\">@KristiNoem<\/a><\/em><em>, <\/em><em>etc etc etc &#8230; Je n&rsquo;arrive m\u00eame pas \u00e0 concevoir comment on pourrait leur<\/em> [donner un nouveau mandat] <em>et restaurer une quelconque cr\u00e9dibilit\u00e9<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>&bull; &laquo; <em>Je veux dire, est-ce que quelqu&rsquo;un&#8230; quelqu&rsquo;un n&rsquo;importe o&ugrave;&#8230; pourrait faire encore pleinement confiance au <a href=\"https:\/\/twitter.com\/CDCgov\">@CDCgov<\/a><\/em> [<em>Centers for Disease Control &#038; Prevention<\/em>]<em> ? Et qui sur la terre de Dieu pourrait faire confiance \u00e0 un vaccin approuv\u00e9 par le <a href=\"https:\/\/twitter.com\/US_FDA\">@US_FDA<\/a><\/em> [<em>Foods &#038; Drugs Administration<\/em>]<em> ?? Comment faire distribuer un vaccin apr\u00e8s que ce non-sens trumpiste ait d\u00e9sint\u00e9gr\u00e9 et tout infect\u00e9 ? M\u00eame si Biden gagne ?<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Et Lois Crowley, \u00e9ducatrice, enseignante des &Eacute;tudes Globales et de l&rsquo;Histoire Am\u00e9ricaine, le m\u00eame <a href=\"https:\/\/twitter.com\/Altmaiergirl4\/status\/1306763133302775808\">18 septembre 2020<\/a>, r\u00e9pondant \u00e0 Joy Ann Reid par tweet \u00e9galement car il n&rsquo;est nul besoin d&rsquo;arguer longuement sur l&rsquo;extraordinaire inversion de la situation :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&bull; &laquo; <em>C&rsquo;est le probl\u00e8me&#8230; Si Biden gagne, les trumpistes se r\u00e9volteront pour porter des masques&#8230; prolongeant la destruction \u00e9conomique d&rsquo;eux-m\u00eames&#8230; et la mort des autres&#8230; ils sont d\u00e9cha&icirc;n\u00e9s&#8230; ils sont une force aussi mauvaise que le changement climatique<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Le <a href=\"https:\/\/twitter.com\/JoyAnnReid\/status\/1325818947803996160\">9 novembre 2020<\/a>, Joy Ann Reid revint sur l&rsquo;affaire, \u00e9tant dans un \u00e9tat d&rsquo;esprit un peu diff\u00e9rent puisque les augures compteuses \u00e0 leur mani\u00e8re avaient d\u00e9clar\u00e9 Biden vainqueur, malgr\u00e9 la r\u00e9sistance farouche de Trump. D\u00e9sormais, elle \u00e9tait plus s\u00e9lective quant \u00e0 son rejet absolu des vaccins, consentant \u00e0 tendre et \u00e0 envisager de faire examiner le Pfizer avec des pincettes, mais continuant \u00e0 rejeter absolument et \u00e0 jamais (\u00ab\u00a0ne dites jamais jamais\u00a0\u00bb) tout le reste puisque venu de Trump :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&bull; &laquo; <em>Franchement, le fait que Pfizer ne fait pas partie de \u00ab\u00a0Operation Warp Speed\u00a0\u00bb et n&rsquo;ait re\u00e7u aucun financement du gouvernement Trump me fait me sentir mieux \u00e0 propos de leur vaccin. Pour ma part, je ne m&rsquo;approcherais pas de tout ce avec quoi Trump ou sa FDA politis\u00e9e a quoi que ce soit \u00e0 voir<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Ce sont deux larrons suspects qui ont ressorti hier cette histoire de m\u00e9moire courte-allong\u00e9e, <a href=\"https:\/\/summit.news\/2021\/08\/10\/msnbc-host-it-was-ok-to-be-an-anti-vaxxer-when-trump-was-president\/\">Steve Watson<\/a> sur son site &lsquo;<em>Summit.News<\/em>&lsquo; (repris par &lsquo;<em><a href=\"https:\/\/www.zerohedge.com\/political\/msnbc-host-it-was-ok-be-anti-vaxxer-when-trump-was-president\">ZeroHedge.com<\/a><\/em>&lsquo;) : &laquo; &#8230; <em>C&rsquo;\u00e9tait OK d&rsquo;\u00eatre anti-vaxx lorsque Trump \u00e9tait pr\u00e9sident<\/em> &raquo; ; et Glenn Greenwald, qui rappelle la chose alors qu&rsquo;il <a href=\"https:\/\/twitter.com\/ggreenwald\/status\/1424730022087204871\">s&rsquo;attaque<\/a> <a href=\"https:\/\/twitter.com\/ggreenwald\/status\/1424733041696591876\">principalement<\/a> au sujet de la bombastique et grandiose <em>party <\/em>qu&rsquo;Obama a donn\u00e9e pour son soixanti\u00e8me anniversaire, alors que l&rsquo;a\u00e9roport de Martha&rsquo;s Vineyard <a href=\"\/Clearly%20all%20those%20celebs%20are%20terrified%20what%20CO%20emissions%20do%20to%20the%20environment\">\u00e9tait encombr\u00e9<\/a> d&rsquo;une noria de jets priv\u00e9s amenant les invit\u00e9s de l&rsquo;ancien pr\u00e9sident (&laquo; <em>Il est \u00e9vident que toutes ces c\u00e9l\u00e9brit\u00e9s sont terrifi\u00e9es \u00e0 l&rsquo;id\u00e9e des d\u00e9g\u00e2ts que les \u00e9missions de CO2 font \u00e0 l&rsquo;environnement<\/em> &raquo;)&#8230;<\/p>\n<\/p>\n<p><p>Voil\u00e0&#8230; M\u00e9moire courte \u00e0 peine rallong\u00e9e ; et ne croyez pas qu&rsquo;on soit tomb\u00e9 sur un ph\u00e9nom\u00e8ne exceptionnel (Joy Ann Reid, de MSNBC). Ils sont tous comme \u00e7a ; y compris les Clooney, Spielberg, Kerry &#038; Cie venus dans leurs zincs flambants neuf \u00e0 $5-$10 millions, pour la <em>fiesta <\/em>de Martha&rsquo;s Vineyard, donn\u00e9e par Obama-Saint. Cela ne fait pas pour autant la gloire visionnaire de ce Trump que les progressistes voudrait \u00ab\u00a0canceler\u00a0\u00bb (&lsquo;<em>to cancel<\/em>&lsquo;) ; Trump reste l&rsquo;homme de la t\u00e9l\u00e9-r\u00e9alit\u00e9 et le milliardaire <em>bling-bling <\/em>qu&rsquo;il est, tout juste balanc\u00e9 dictateur fasciste ou h\u00e9ros populiste pour les besoins de la cause, dans tous les cas acc\u00e9l\u00e9rateur de la production en urgence des vaccins, d&rsquo;abord pour les besoins du <em>business <\/em>et les b\u00e9n\u00e9fices de <em>Big Pharma<\/em>, comme tout bon pr\u00e9sident US classique dans cette sorte de circonstance. Il reste que c&rsquo;est lui, le monstre d\u00e9cri\u00e9 de toutes parts par les hyper-provaxx bienpensants d&rsquo;aujourd&rsquo;hui, qui a suscit\u00e9 en urgence et obtenu la fabrication des vaccins.<\/p>\n<\/p>\n<p><p>C&rsquo;est \u00e0 ce niveau que tout cela se suffit pour nous en expliquer, et si vous croyez que cela fait des vaccins une potion magique du grand-Sage <em>Assurancetourix <\/em>voulant lib\u00e9rer le monde ou un poison-g\u00e9nocide d&rsquo;une sorte de \u00a0\u00bb Reine <em>Grimhilde<\/em>\u00a0\u00bb (<a href=\"https:\/\/disney.fandom.com\/fr\/wiki\/Reine_(Blanche-Neige_et_les_Sept_Nains)\">belle-m\u00e8re<\/a> de Blanche-Neige)  fasciste-dictatrice voulant contr\u00f4ler le monde, je crois que vous n&rsquo;y \u00eates pas vraiment. Ces <em>narrative <\/em>diverses sont du genre \u00ab\u00a0embrassons ce que nous ne pouvons \u00e9touffer\u00a0\u00bb, tandis que les vaccins sont aussi bienvenus qu&rsquo;incertains, \u00e0 l&rsquo;image de la crise-Covid qui est un infernal labyrinthe o&ugrave; nos pontifiants scientifiques-\u00ab\u00a0sachants\u00a0\u00bb nous ont embarqu\u00e9s, persuad\u00e9s d&rsquo;y trouver le Graal alors qu&rsquo;il ne font que rebondir de porte verrouill\u00e9e en porte verrouill\u00e9e.<\/p>\n<\/p>\n<p><p>(Moi au moins, je sais que ce sont des portes verrouill\u00e9es, et je sais que je ne trouverai pas le Graal, ni en prenant le vaxx, ni en le refusant&#8230; \u00ab\u00a0Mais vous n&rsquo;aurez pas Covid si vous prenez le vaxx\u00a0\u00bb me dira l&rsquo;un ; \u00ab\u00a0mais vous serez leur prisonnier si vous prenez le vaxx\u00a0\u00bb, dira l&rsquo;autre&#8230; Je leur r\u00e9pondrai : \u00ab\u00a0Je ne suis pas de votre monde de d\u00e9ments : je l&rsquo;observe, ce monde de d\u00e9ments, sans m&rsquo;y plonger, comme un brave scientifique fabrique un vaccin tandis que <em>Big Pharma<\/em>  empoche.\u00a0\u00bb A part cela, certes, je suis [du verbe \u00ab\u00a0suivre\u00a0\u00bb, mais \u00ab\u00a0pas que&#8230;\u00a0\u00bb ?] les \u00e9v\u00e9nements en enqu\u00eatant \u00e0 leur propos, les favorisant ou les condamnant selon leur distance ou leur connivence avec le Syst\u00e8me)<\/p>\n<\/p>\n<p><p>C&rsquo;est par contre \u00e0 un autre niveau que se r\u00e9v\u00e8le la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-verite-de-situation-verite\">v\u00e9rit\u00e9-de-situation<\/a> de l&rsquo;aventure de cette fin de civilisation, et alors la path\u00e9tique Reid, pr\u00e9sentatrice \u00e0 MSNBC tout de m\u00eame, absolument d\u00e9risoire et bouffonne jusqu&rsquo;\u00e0 la plus compl\u00e8te na\u00efvet\u00e9 dans son hyst\u00e9rie absolument inarr\u00eatable, nous le dit bien ; elle nous le dit pour elle mais aussi pour tous les autres, tous ses semblables, jusqu&rsquo;aux plus influents, aux plus hauts plac\u00e9s, aux plus manipulateurs et aux plus militants de l&rsquo;un ou l&rsquo;autre camp, avec les pour et les contre, tous ces gens emport\u00e9s par le feu de l&rsquo;hyst\u00e9rie d\u00e9mente, aujourd&rsquo;hui s&rsquo;affrontant pour ou contre le vaccin comme s&rsquo;il s&rsquo;agissait, &ndash; toujours lui, &ndash; du Saint-Graal&#8230; Reid disant, la semaine derni\u00e8re pour s&rsquo;expliquer de ses tweets anti-vaxx d&rsquo;il y a un an, s&rsquo;adressant dans une interview \u00e0 la ni\u00e8ce-tra&icirc;tresse de Trump [<a href=\"file:\/\/\/...%20Puis%20s'adressant%20dans%20une%20interview%20\u00e0%20la%20ni\u00e8ce-tra\u00eetresse%20de%20Trump%20\">vid\u00e9o<\/a>] :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>J&rsquo;ai \u00e9t\u00e9 l&rsquo;objet de beaucoup de critiques pour avoir dit en septembre<\/em> [2020] <em>que, si Donald Trump restait pr\u00e9sident, je ne ferais pas confiance \u00e0 tout ce qui sortait en termes de vaccins qu&rsquo;il proposait, et qu&rsquo;il \u00e9tait d\u00e9sormais difficile de faire confiance au CDC apr\u00e8s qu&rsquo;il<\/em> [Trump] <em>l&rsquo;ait d\u00e9form\u00e9 si profond\u00e9ment, et que, m\u00eame s&rsquo;il n&rsquo;\u00e9tait pas r\u00e9\u00e9lu, il serait difficile de restaurer ce genre de confiance<\/em>&#8230; &raquo;<\/p>\n<\/p>\n<p><p>&raquo;  <em>J&rsquo;ai dit \u00e7a<\/em> [en septembre 2020] <em>parce que, dans mon esprit, un psychopathe \u00e9tait pr\u00e9sident. Et si un psychopathe vous dit, prenez ce vaccin, c&rsquo;est ce que vous devriez prendre,&ndash; alors qu&rsquo;il fait d&rsquo;abord cela pour sa r\u00e9\u00e9lection, &ndash; il y a une bonne raison de ne pas le croire<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>Mais maintenant, il n&rsquo;y a plus de psychopathe \u00e0 la Maison Blanche&#8230;<\/em> &raquo;<\/p>\n<\/p>\n<p><p>&laquo; <em>Pensez-vous qu&rsquo;il y a un moyen de changer, en quelque sorte, l&rsquo;attitude des gens qui sont juste h\u00e9sitants, en se basant sur le fait que, &lsquo;Regardez, les gars, il n&rsquo;y a plus de fou l\u00e0-bas, d\u00e9sormais&rsquo; ?<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Vous pouvez faire confiance au gouvernement quand il est entre les mains de quelqu&rsquo;un de sain d&rsquo;esprit<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Ces d\u00e9clarations, ces explications, sont aussi int\u00e9ressantes qu&rsquo;une s\u00e9ance mi-psychiatrie mi-psychanalyse (si cela existe) dans un h\u00f4pital de m\u00eame cat\u00e9gorie, et elles ont vocation \u00e0 embrasser l&rsquo;essentiel des attitudes qu&rsquo;on observe aujourd&rsquo;hui, en profondeur, tout au fond de nos consciences inconscientes, bien entendu en-dessous de la bave stagnante et accablante des bla-bla des \u00ab\u00a0sachants\u00a0\u00bb-m\u00e9dicaux et des journaleux-Syst\u00e8me. Ainsi n&rsquo;est-il pas question une seconde de vaccin en tant que cr\u00e9ation de la m\u00e9decine (enfin, de <em>Big Pharma<\/em>), ni de Covid en tant que pand\u00e9mie, ni de Trump et de Biden en tant que pr\u00e9sidents, mais de Trump transmut\u00e9 Covid et Biden transmut\u00e9 vaccin, et vice-versa, et ici et l\u00e0 l&rsquo;\u00e9tat moralinesque du Covid et du vaccin s&#8217;emparant de la personne pour l&rsquo;envoyer aux enfers ou l&rsquo;\u00e9lever au pinacle ; et le m\u00eame sch\u00e9ma de fa\u00e7on de penser, ou plut\u00f4t d&rsquo;im-penser, se retrouvant un peu partout \u00e0 des degr\u00e9s divers, plus ou moins bien fard\u00e9s, avec des personnages diff\u00e9rents qu&rsquo;importe, en France juste apr\u00e8s les USA, comme aux USA.<\/p>\n<\/p>\n<p><p>Il y a un v\u00e9ritable transfert psychologique et psychotrope de masse dans un monde \u00ab\u00a0magique\u00a0\u00bb, o&ugrave; le Covid, puis le vaccin se m\u00e9tamorphosent en personnages de folle-id\u00e9ologie maquill\u00e9e par nos citoyens hyst\u00e9riques en acteurs politiques enferm\u00e9s dans des cat\u00e9gories comme dans une cellule de haute s\u00e9curit\u00e9. Le ph\u00e9nom\u00e8ne est si fort et si pr\u00e9gnant qu&rsquo;il en impr\u00e8gne tous les moyens de communication et les voix pr\u00e9tendument s\u00e9rieuses du Syst\u00e8me (et parfois sinon souvent de l&rsquo;antiSyst\u00e8me), qui suivent cette \u00e9trange m\u00e9tamorphose de la dialectique et de la perception, jusqu&rsquo;\u00e0 en infecter les esprits correspondants.<\/p>\n<\/p>\n<p><p>Bien entendu, il faut bien prendre soin de reconna&icirc;tre que ce sont les compagnons du wokenisme, les voltigeurs du <em>woke-<\/em>syst\u00e8me et de la <em>cancel<\/em>-culture, qui ont lanc\u00e9 cette folie, l&rsquo;imposant \u00e0 tous, notamment aux autres pour qu&rsquo;ils puissent figurer l\u00e0 o&ugrave; ils doivent \u00eatre, &ndash; pour pouvoir soutenir le rythme et mener la bataille. Cela \u00e9tabli, qui permet de mieux identifier la position qu&rsquo;on doit tenir en r\u00e9f\u00e9rence \u00e0 notre <em>Delenda Est Systema<\/em>, il me semble que l&rsquo;on comprend mieux la forme d&rsquo;un combat o&ugrave; il faut bien se garder de tenter de comprendre directement les choses. La d\u00e9mence y est la r\u00e8gle et, pour tenir, il est essentiel d&rsquo;en tenir compte ; je veux dire qu&rsquo;il faut passer de l&rsquo;autre c\u00f4t\u00e9 du miroir, et l\u00e0, \u00ab\u00a0passez, muscade !\u00a0\u00bb, &ndash; vous pourrez en juger.<\/p>\n<\/p>\n<p><p>Il faut enfin se dire, comme je ne cesse de le dire et de me le dire, que cela, cette pi\u00e8tre com\u00e9die-<em>Fantasy <\/em>humaine ou <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-la-tragedie-bouffe\">trag\u00e9die-bouffe<\/a> d\u00e9mente, n&#8217;emp\u00eache en rien, mais en rien du tout et en aucune fa\u00e7on, les plus grands \u00e9v\u00e9nements du monde de se propager \u00e0 la vitesse d&rsquo;un incendie cosmique. Au contraire, elle leur ouvre encore plus largement le champ libre pour leur laisser tout le champ d&rsquo;azur dont ils ont besoin, et je les entends se gausser, ces \u00e9v\u00e9nements, sous les regards d&rsquo;une ironie mordante des dieux de l&rsquo;Olympe.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Histoire tweet\u00e9e de vaccin 11 ao&ucirc;t 2021 &ndash; Nous sommes au temps des m\u00e9moires courtes puisque le Temps passe si vite et ne nous laisse aucune dur\u00e9e. L&rsquo;amour fou du Syst\u00e8me pour le vaccin, qui va jusqu&rsquo;aux anath\u00e8mes venus du fond des Temps pour les anti-vaxx, s&rsquo;accompagne du souvenir furieux de celui qui a sans&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[6606,5463,21065,2752,6944,21127,6794,6208,5191,3818,19579,19752,21128,8559],"class_list":["post-79864","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-ann","tag-anniversaire","tag-antivaxx","tag-covid","tag-greenwald","tag-joy","tag-msnbc","tag-obama","tag-operation","tag-reid","tag-speed","tag-vaccin","tag-warp","tag-watson"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79864","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79864"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79864\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79864"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79864"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}