{"id":79873,"date":"2021-08-19T21:11:50","date_gmt":"2021-08-19T21:11:50","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2021\/08\/19\/the-second-civil-war\/"},"modified":"2021-08-19T21:11:50","modified_gmt":"2021-08-19T21:11:50","slug":"the-second-civil-war","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2021\/08\/19\/the-second-civil-war\/","title":{"rendered":"\u2018<em>The Second Civil War<\/em>&lsquo;"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">&lsquo;<em>The Second Civil War<\/em>&lsquo;<\/h2>\n<\/p>\n<p><p>19 ao&ucirc;t 2021 &ndash; Derri\u00e8re la catastrophe de Kaboul, dont certains nous assurent \u00e9videmment qu&rsquo;elle est une manipulation mod\u00e8le-standard et un complot comme convenu entre-soi, &ndash; derri\u00e8re donc est en train d&rsquo;appara&icirc;tre un probl\u00e8me du style &lsquo;d\u00e9g\u00e2t collat\u00e9ral&rsquo; qui va peut-\u00eatre bien nous occuper \u00e0 plein temps. Il s&rsquo;agit des r\u00e9fugi\u00e9s afghans, ceux qui nous aid\u00e8rent et qui fuient le nouveau r\u00e9gime, que nous allons devoir accueillir. Les Fran\u00e7ais y pensent, avec dans le r\u00f4le du gardien-chef, le martial sinon imp\u00e9rial pr\u00e9sident Macron, portant sur son macaron de revers, en un clin d&rsquo;&oelig;il et un tournemain, le pouce lev\u00e9 : \u00ab\u00a02022 ! &ndash; <em>Make France Great Again<\/em>\u00ab\u00a0. L&rsquo;enjeu est de grande taille.<\/p>\n<\/p>\n<p><p>Les Am\u00e9ricains font de m\u00eame, avec une mauvaise humeur \u00e9vidente, comme le montre Tucker Carlson, l&rsquo;homme-phare de FoxNews et de la t\u00e9l\u00e9vision US en g\u00e9n\u00e9ral. Carlson pense qu&rsquo;on ne pourra <a href=\"https:\/\/www.foxnews.com\/opinion\/tucker-carlson-resettling-afghan-refugees-rescuing-american-citizens\">penser \u00e0 l&rsquo;accueil d&rsquo;Afghans<\/a> qu&rsquo;une fois tous les Am\u00e9ricains sortis de ce gu\u00eapier  (cela prendra du temps, consid\u00e9rant l&rsquo;habilet\u00e9 de l&rsquo;usine \u00e0 gaz pentagonesque). Je vous dis, moi, que nous tenons l\u00e0 un d\u00e9bat qui tiendra sa place&#8230; Mais plus encore d&rsquo;ailleurs, car tout cela, cette introduction avec un zeste d&rsquo;ironie, ce sujet, tout cela est pr\u00e9par\u00e9 bien entendu pour vous conduire l\u00e0 o&ugrave; je voudrais que vous alliez.<\/p>\n<\/p>\n<p><p>Avez-vous vu le film devenu t\u00e9l\u00e9film de Joe Dante, &lsquo;<em><a href=\"\/The%20Second%20Civil%20War&#039;\">The Second Civil War&rsquo;<\/a><\/em>, de 1997 ? Cela est trait\u00e9 dans le style parodique et satirique, grin\u00e7ant et burlesque, souvent assez dr\u00f4le \u00e0 tr\u00e8s dr\u00f4le, avec des num\u00e9ros excellents (James Coburn en <em>spin doctor <\/em>[conseiller de communication] du pr\u00e9sident des USA). L&rsquo;histoire est celle d&rsquo;un encha&icirc;nement-bouffe menant \u00e0 une \u00ab\u00a0seconde Guerre de S\u00e9cession\u00a0\u00bb, \u00e0 \u00ab\u00a0notre \u00e9poque\u00a0\u00bb (\u00e0 l&rsquo;\u00e9poque du film, c&rsquo;est-\u00e0-dire durant les deux mandats Clinton suivant la fin de la Guerre Froide).<\/p>\n<\/p>\n<p><p>Juste quelques extraits de la description du film par le <em>Wiki<\/em>, sans autre pr\u00e9tention que documentaire, pour vous faire affuter votre perception des choses, le brio de Dante, r\u00e9alisateur magistral et marginal boycott\u00e9 par Hollywood ; pour vous faire sentir surtout et combien l&rsquo;\u00e9poque Clinton, &ndash; une fois pass\u00e9e la parenth\u00e8se (horreur de dire cela !) de 9\/11 &#038; cons\u00e9quences, &ndash; pr\u00e9figurait d\u00e9j\u00e0 la n\u00f4tre avec les probl\u00e8mes soci\u00e9taux et communautaristes, la crise end\u00e9mique puis paroxystique de l&rsquo;immigration, la pr\u00e9dominance de la communication influant fondamentalement sur le comportement des hommes politiques, sur les \u00e9v\u00e9nements, les psychologies parfaitement \u00e0 mesure et d\u00e9j\u00e0 allum\u00e9es, etc&#8230;<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Alors qu&rsquo;une guerre nucl\u00e9aire a \u00e9clat\u00e9 entre l&rsquo;Inde et le Pakistan, Islamabad ayant \u00e9t\u00e9 ray\u00e9e de la carte, des milliers d&rsquo;orphelins pakistanais, plac\u00e9s sous la protection d&rsquo;une organisation non gouvernementale controvers\u00e9e, doivent \u00eatre recueillis par les &Eacute;tats-Unis. Le pays est gouvern\u00e9 par un pr\u00e9sident politiquement impuissant et totalement manipul\u00e9 par son entourage, notamment son conseiller en communication ou spin doctor. La politique est \u00e9galement \u00e0 la merci de News Net (parodie de CNN1), une cha&icirc;ne d&rsquo;information influente et racoleuse pour cr\u00e9er de l&rsquo;audimat.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>L&rsquo;accueil des r\u00e9fugi\u00e9s n&rsquo;est pas sans \u00e9cueils car en raison des diff\u00e9rents troubles tel que les guerres, la famine ou l&rsquo;usage excessif d&rsquo;insecticide, la migration am\u00e9ricaine et le communautarisme qui l&rsquo;accompagne avait atteint un niveau sans pr\u00e9c\u00e9dent : le maire de Los Angeles a comme naturelle l&rsquo;espagnol, Rhode Island est \u00e0 majorit\u00e9 chinoise, le Congr\u00e8s des &Eacute;tats-Unis est partag\u00e9 entre les Cor\u00e9ens, un Indien repr\u00e9sente l&rsquo;Alabama ainsi que le parti national islamiste. Le reporteur Kalla consid\u00e8re cela comme \u00ab\u00a0les ruines du melting pot\u00a0\u00bb, et News Net d\u00e9pend des annonceurs \u00e9trangers. Le gouverneur de l&rsquo;Idaho, Jim Farley, appuy\u00e9 sur les milices d&rsquo;extr\u00eame-droite, suit une politique hostile \u00e0 l&rsquo;immigration et refuse d&rsquo;accueillir le quota d&rsquo;orphelins qui doit \u00eatre install\u00e9 dans son &Eacute;tat. Il donne l&rsquo;ordre de mettre en place des barrages sur les routes aux limites de l&rsquo;Idaho<\/em>. <em>News Net met ce conflit en \u00e9pingle au moment o&ugrave; le gouverneur tombe amoureux de leur journaliste hispano-am\u00e9ricaine, Christina Fernandez. Le gouverneur devient obnubil\u00e9 par la journaliste et montre \u00e0 plusieurs reprises que son comportement est en contradiction avec ses id\u00e9es politiques.<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>S&rsquo;ensuivent diverses entrelacs-bouffe, mais refl\u00e9tant bien des attitudes que l&rsquo;on retrouve aujourd&rsquo;hui, parfois au centuple, et notamment toute cette tension et ce chaos intra-communautaires \u00e9crasant, et transformant les USA en un capharna\u00fcm pr\u00eat \u00e0 exploser. Et cela explose donc, notamment \u00e0 cause d&rsquo;un mot mal prononc\u00e9 ou bien mal entendu&#8230; C&rsquo;est comme si nous y \u00e9tions, non ?<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Le spectre d&rsquo;une nouvelle guerre de S\u00e9cession est proche, \u00e0 travers la mobilisation militaire au Pentagone et \u00e0 Fort Bragg, l&rsquo;US Army est mobilis\u00e9e contre la Garde Nationale de l&rsquo;Idaho. News Net monte en puissance et veut cr\u00e9er l&rsquo;information, en dramatisant la situation. Le pays tombe alors en pleine d\u00e9liquescence. D&rsquo;autres &Eacute;tats de l&rsquo;Union alli\u00e9s \u00e0 Farley envoient leurs arm\u00e9es pour soutenir le gouverneur. Fort Alamo est incendi\u00e9 par les Latinos, la statue de la Libert\u00e9 est abattue par un groupe pro-Farley. Le pr\u00e9sident est d\u00e9pass\u00e9 et se rend compte que tout son \u00e9lectorat et ses relations commerciales ne sont bas\u00e9s que sur des alliances ethniques et nationalistes. &Agrave; l&rsquo;approche de l&rsquo;ultimatum, des mutineries \u00e9clatent au sein de l&rsquo;US Army, des mutins sont fusill\u00e9s. &Agrave; la suite d&rsquo;une information erron\u00e9e, Farley <\/em>[d\u00e9missionnaire par amour]<em> ayant annonc\u00e9 une conf\u00e9rence \u00ab\u00a0pour la succession\u00a0\u00bb \u00e0 son poste que Buchan comprend comme \u00ab\u00a0pour la s\u00e9cession\u00a0\u00bb, le pr\u00e9sident am\u00e9ricain, guid\u00e9 cette fois par l&rsquo;exemple d&rsquo;Abraham Lincoln, d\u00e9clenche les op\u00e9rations militaires<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Dante envisageait ainsi une cons\u00e9quence fortuite mais directe et d&rsquo;une importance consid\u00e9rable d&rsquo;un \u00e9v\u00e9nement de politique ext\u00e9rieure sur la situation int\u00e9rieure des &Eacute;tats-Unis d\u00e9j\u00e0 dans une \u00e9tat de grande tension. M\u00eame si l&rsquo;\u00e9v\u00e9nement ext\u00e9rieur imagin\u00e9 par Dante est totalement diff\u00e9rent du cas afghan, la question des r\u00e9fugi\u00e9s afghans pourrait poser un probl\u00e8me assez similaire. Elle pourrait s&rsquo;instituer notamment comme une vivante image rappelant la d\u00e9route des USA \u00e0 Kaboul. Elle installerait une pression sp\u00e9cifique aggravant la tension avec l&rsquo;implication directe d&rsquo;un pr\u00e9sident d\u00e9j\u00e0 contest\u00e9, objet de pol\u00e9miques consid\u00e9rables, d\u00e9sormais avec celle de l&rsquo;affaire afghane qui vient de s&rsquo;imposer avec fracas en suppl\u00e9ment de toutes les autres. Cela est envisag\u00e9 bien entendu dans le cadre d&rsquo;une Am\u00e9rique absolument fractur\u00e9e, furieuse, avec sa branche r\u00e9volutionnaire et sa branche de r\u00e9sistance, donc dans un \u00e9tat de tension bien plus grave que durant les ann\u00e9es-Clinton.<\/p>\n<\/p>\n<p><p>Cette id\u00e9e des effets int\u00e9rieurs possibles de la d\u00e9b\u00e2cle du grand vaincu de la guerre en Afghanistan est d&rsquo;autre part caract\u00e9ris\u00e9e par ce qui a \u00e9t\u00e9 <a href=\"https:\/\/www.dedefensa.org\/article\/une-enigme-biden\">mis hier en \u00e9vidence<\/a> avec les hypoth\u00e8ses faites autour du r\u00f4le personnel de Biden dans la d\u00e9cision de retrait acc\u00e9l\u00e9r\u00e9, notamment celle de la querelle qui l&rsquo;aurait oppos\u00e9 aux g\u00e9n\u00e9raux. D\u00e9j\u00e0 on esquissait hier un aspect de cette possible circonstance, qui est de l&rsquo;ordre du psychologique, concernant Biden :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p><em>&laquo; L&rsquo;hypoth\u00e8se est donc bien d\u00e9velopp\u00e9e et pr\u00e9sente sous une \u00e9trange lumi\u00e8re les \u00e9v\u00e9nements d&rsquo;Afghanistan, en faisant d&rsquo;une querelle de centres de pouvoir \u00e0 Washington D.C. le d\u00e9clencheur d&rsquo;une catastrophe qui affecte le statut de puissance des &Eacute;tats-Unis dans le monde. Ce serait un signe de plus de la crise du pouvoir, r\u00e9v\u00e9lant par ailleurs un pr\u00e9sident certifi\u00e9 s\u00e9nile, mais accroch\u00e9 \u00e0 certaines obsessions politiques et inhumaines qui le conduisent \u00e0 mal appr\u00e9cier le v\u00e9ritable poids de son pouvoir : l\u00e0 o&ugrave; Trump a c\u00e9d\u00e9 \u00e0 ses militaires par prudence, Biden aurait tenu bon et provoqu\u00e9 indirectement le d\u00e9sastre afghans par incapacit\u00e9 de jugement des forces bureaucratiques, avec ses g\u00e9n\u00e9raux arrogants et plus int\u00e9ress\u00e9s par les privil\u00e8ges de leur caste que par la s\u00e9curit\u00e9 nationale des Etats-Unis<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>On comprend qu&rsquo;ici, ce qui m&rsquo;int\u00e9resse n&rsquo;est pas tant le fait (d&rsquo;ailleurs \u00e9tudi\u00e9 hier) de la description \u00e9ventuelle d&rsquo;un d\u00e9saccord entre Biden et ses g\u00e9n\u00e9raux aboutissant \u00e0 la d\u00e9b\u00e2cle US, et par cons\u00e9quent une explication de cette d\u00e9b\u00e2cle. Ce qui m&rsquo;int\u00e9resse est la forme de cette d\u00e9marche par rapport \u00e0 la forme de la crise afghane, l&rsquo;appr\u00e9ciation de cet incident pour ce qu&rsquo;il est, une bataille bureaucratique et une sp\u00e9cificit\u00e9 psychologique (celle de Biden) qui n&rsquo;ont, ni l&rsquo;une ni l&rsquo;autre, de lien direct avec la crise afghane que nous vivons. Ce lien s&rsquo;\u00e9tablit ensuite, \u00e0 la lumi\u00e8re des \u00e9v\u00e9nements qui suivent en Afghanistan et il appara&icirc;t soudainement extraordinairement puissant ; mais au d\u00e9part, on a purement et simplement un affrontement bureaucratique, une querelle de pouvoirs plus concurrents que hi\u00e9rarchis\u00e9s, donc un \u00e9v\u00e9nement crisique qui n&rsquo;implique l&rsquo;Afghanistan que comme outil de convenance.<\/p>\n<\/p>\n<p><p>Dans ce cadre, on comprend aussit\u00f4t que l&rsquo;aspect sur lequel je veux revenir est effectivement la psychologie de Biden, concernant ce qui est une attitude de longue date, et qu&rsquo;il est logique de voir renforc\u00e9e par l&rsquo;\u00e9tat de s\u00e9nilit\u00e9 du pr\u00e9sident, impliquant le renforcement des obsessions, la perte de vision des cons\u00e9quences, l&rsquo;ent\u00eatement irr\u00e9fragable. Il est bien pr\u00e9cis\u00e9 que, gr\u00e2ce \u00e0 leurs man&oelig;uvres bureaucratiques, les g\u00e9n\u00e9raux bloqu\u00e8rent les d\u00e9cisions de retrait d&rsquo;Afghanistan, plus ou moins prises, d&rsquo;Obama et de Trump, chez lesquels ils trouv\u00e8rent une part de mesure, de prudence, les conduisant \u00e0 ne pas trop insister. Poursuivant cette hypoth\u00e8se, mon avis serait bien que c&rsquo;est effectivement l&rsquo;\u00e9tat psychologique de Biden, sa s\u00e9nilit\u00e9, ses probl\u00e8mes cognitifs, etc., bref ses faiblesses qui auraient fait paradoxalement sa force par inconscience face aux g\u00e9n\u00e9raux &ndash; le renforcement de ses obsessions, l&rsquo;ent\u00eatement irr\u00e9fragable, son refus du moindre compromis, sa perception r\u00e9duite \u00e0 l&rsquo;angle tr\u00e8s r\u00e9duit de la satisfaction de son obsession mais tr\u00e8s puissante dans ce cadre r\u00e9duit. Dans tout cela, je le r\u00e9p\u00e8te, il n&rsquo;est question d&rsquo;Afghanistan qu&rsquo;accessoirement, comme un motif de l&rsquo;affrontement, un outil, rien de fondamental.<\/p>\n<\/p>\n<p><p>On entrerait alors dans un sch\u00e9ma d\u00e9j\u00e0 d\u00e9velopp\u00e9 pour la crise-Covid : l&rsquo;intervention d&rsquo;une circonstance compl\u00e8tement al\u00e9atoire, compl\u00e8tement improbable et hors-sujet, provoquant une succession d&rsquo;\u00e9v\u00e9nements acc\u00e9l\u00e9rant la crise de l&rsquo;am\u00e9ricanisme, donc la Grande-Crise bien entendu. (Effectivement, faire l&rsquo;hypoth\u00e8se acceptable que Biden ait tenu ce r\u00f4le constitue une circonstance compl\u00e8tement impr\u00e9visible et inattendue ; de m\u00eame, au d\u00e9part la crise-Covid est impr\u00e9visible et inattendue dans son soudain d\u00e9veloppement de crise politique, dans sa \u00ab\u00a0politisation\u00a0\u00bb.)<\/p>\n<\/p>\n<p><p>Cette circonstance de la querelle Biden-g\u00e9n\u00e9raux serait d&rsquo;autant plus al\u00e9atoire, improbable et hors-sujet dans son effet acc\u00e9l\u00e9rateur de la crise, qu&rsquo;aucun des acteurs, tous engag\u00e9s dans un affrontement o&ugrave; seuls sont pris en compte des int\u00e9r\u00eats de caste et des attitudes d&rsquo;humeur, n&rsquo;aurait appr\u00e9ci\u00e9 cette circonstance de m\u00e9sentente de ce point de vue des effets d&rsquo;acc\u00e9l\u00e9ration de la crise. En effet, et l\u00e0 je pense qu&rsquo;il s&rsquo;agit du vrai, la seule chose qui les a fait tous revenir \u00e0 la r\u00e9alisation de la profondeur de la crise, et qui a donc \u00e9clat\u00e9 comme telle dans les r\u00e9seaux du syst\u00e8me de la communication, c&rsquo;est l&rsquo;effet psychologique \u00e9norme de la d\u00e9b\u00e2cle am\u00e9ricaniste qui s&rsquo;est d\u00e9velopp\u00e9 de lui-m\u00eame, notamment gr\u00e2ce \u00e0 la puissance incontr\u00f4lable du syst\u00e8me de la communication.<\/p>\n<\/p>\n<p><p>Moi-m\u00eame, je l&rsquo;avoue bien volontiers et sans barguigner, je n&rsquo;avais pas appr\u00e9hend\u00e9 la d\u00e9b\u00e2cle probable des USA en Afghanistan comme suscitant un tel \u00e9cho, une telle sensation unanime d&rsquo;un revers terrible, qui pourrait bien se transmuer en un revers irr\u00e9versible de la puissance g\u00e9n\u00e9rale des &Eacute;tats-Unis. Je voyais cela comme la fin d&rsquo;une guerre qui s&rsquo;\u00e9teint, comme une buche consum\u00e9e, finalement sans un effet extraordinaire, &ndash; mais soudain, sentir la tension monter, exploser en un instant, et toute la communication du monde exploser ! Il me semble que tout le monde a ressenti cet effet psychologique sans l&rsquo;avoir pr\u00e9vu une seule seconde, et alors il me semble \u00e9galement dans cette m\u00eame logique de l&rsquo;insaisissable quoiqu&rsquo;\u00e9ventuellement pr\u00e9visible ou dans tous les cas envisageable, qu&rsquo;un encha&icirc;nement comme celui que met en sc\u00e8ne Joe Dante pourrait avoir lieu.<\/p>\n<\/p>\n<p><p>Alors, alors, avec tous ces \u00ab\u00a0si\u00a0\u00bb \u00e9cart\u00e9s par les faits, &ndash; chose difficile en temps normal mais nous sommes dans des temps o&ugrave; rien n&rsquo;est impossible, surtout l&rsquo;impossible inattendu, &ndash; effectivement l&rsquo;on se trouverait dans un cas \u00e0 mettre en parall\u00e8le, je veux dire dans la m\u00eame famille crisique que le Covid. Nul n&rsquo;attend des cons\u00e9quences consid\u00e9rables d&rsquo;un affrontement interne de cette sorte s&rsquo;il a lieu (Biden et ses g\u00e9n\u00e9raux), et personne ne s&rsquo;y pr\u00e9pare psychologiquement. Ce que nous a montr\u00e9 la d\u00e9b\u00e2cle afghane, une fois de plus apr\u00e8s d&rsquo;autres, c&rsquo;est l&rsquo;importance absolument cruciale de la psychologie, surtout dans les cas incertains, dans l&rsquo;impr\u00e9vu et l&rsquo;insaisissable.<\/p>\n<\/p>\n<p><p>C&rsquo;est sur ces terres incertaines que la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-la-gces\">Grande Crise de l&rsquo;Effondrement du Syst\u00e8me<\/a> donnera toute sa mesure, nous fera montre de toute son tr\u00e8s grande puissance. Nous assisterons et assistons d&rsquo;ailleurs, sans avoir \u00e9t\u00e9 pr\u00e9venus du spectacle \u00e0 cause du caract\u00e8re impr\u00e9vu des crises s&rsquo;ajoutant les unes aux autres, \u00e0 l&rsquo;effondrement d&rsquo;une civilisation qui se croyait immortelle. Mais nous la verrons, pr\u00e9cis\u00e9ment, directement, l\u00e0, sous nos yeux. Nous ne l&rsquo;aurons pas vu venir dans sa chute finale mais nous verrons sa chute finale, &quot;en temps r\u00e9el\u00a0\u00bb come l&rsquo;on dit dans le jargon courant.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&lsquo;The Second Civil War&lsquo; 19 ao&ucirc;t 2021 &ndash; Derri\u00e8re la catastrophe de Kaboul, dont certains nous assurent \u00e9videmment qu&rsquo;elle est une manipulation mod\u00e8le-standard et un complot comme convenu entre-soi, &ndash; derri\u00e8re donc est en train d&rsquo;appara&icirc;tre un probl\u00e8me du style &lsquo;d\u00e9g\u00e2t collat\u00e9ral&rsquo; qui va peut-\u00eatre bien nous occuper \u00e0 plein temps. Il s&rsquo;agit des r\u00e9fugi\u00e9s&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[3236,1235,2752,5381,2631,3532,5160,2645,8503,12744,2949],"class_list":["post-79873","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-afghanistan","tag-biden","tag-covid","tag-dante","tag-de","tag-deuxieme","tag-generaux","tag-guerre","tag-joe","tag-migrants","tag-secession"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79873"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79873\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79873"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79873"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}