{"id":79885,"date":"2021-08-29T19:52:10","date_gmt":"2021-08-29T19:52:10","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2021\/08\/29\/du-nominalisme-au-complotisme\/"},"modified":"2021-08-29T19:52:10","modified_gmt":"2021-08-29T19:52:10","slug":"du-nominalisme-au-complotisme","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2021\/08\/29\/du-nominalisme-au-complotisme\/","title":{"rendered":"Du nominalisme au complotisme"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d;font-size:1.65em;font-variant:small-caps;\">Du nominalisme au complotisme<\/h2>\n<\/p>\n<p><p>29 ao&ucirc;t 2021 &ndash; On n&rsquo;en a pas fini, et on n&rsquo;en aura pas fini avant longtemps d&rsquo;analyser cette \u00ab\u00a0guerre\u00a0\u00bb d&rsquo;Afghanistan (les guillemets sugg\u00e8re ce que j&rsquo;en pense), l&rsquo;\u00e9chec qui l&rsquo;a caract\u00e9ris\u00e9e tout au long des op\u00e9rations, et la catastrophe qui l&rsquo;a conclue \u00e0 ce stade de la s\u00e9quence. Pour suivre sans trop s&rsquo;ennuyer, et sortir, et hausser chacun de nos esprits, toujours menac\u00e9 d&rsquo;anesth\u00e9sie, il faut chercher quelques commentateurs originaux ; il nous faut du \u00ab\u00a0hors des sentiers battus\u00a0\u00bb. William S. Lind est l&rsquo;un de ceux-l\u00e0, on peut le suivre sans craindre de se faire agresser.<\/p>\n<\/p>\n<p><p>On a d\u00e9j\u00e0 parl\u00e9 de Lind sur ce site, assez souvent \u00e0 une \u00e9poque, moins (mais \u00e0 peine, apr\u00e8s tout) depuis qu&rsquo;il s&rsquo;est largement retir\u00e9 du monde de la communication tout en maintenant une chronique r\u00e9guli\u00e8re sur le site  o&ugrave; on le retrouve, qui fait un clin d&rsquo;oeil aux traditionnalistes. C&rsquo;est un sp\u00e9cialiste de l&rsquo;histoire et de la technique des conflits, fameux surtout pour ses th\u00e8ses sur la Guerre de Quatri\u00e8me G\u00e9n\u00e9ration (G4G) <a href=\"https:\/\/www.dedefensa.org\/article\/g4g-la-victoire-du-modele-hezbollah\">avec ses rapports<\/a> avec les mod\u00e8les des &Eacute;tats faillis ; mais \u00e9galement, dans un mode plus sp\u00e9cifiquement historien, tr\u00e8s int\u00e9ress\u00e9 par la Grande Guerre et attentif \u00e0 mettre en \u00e9vidence <a href=\"https:\/\/www.dedefensa.org\/article\/les-americains-14-18\">le r\u00f4le fondamental de la France<\/a> bien souvent minor\u00e9 et d\u00e9daign\u00e9 par les historiens anglo-saxons suivant le train britannique qui attribue bien \u00e9videmment l&rsquo;essentiel de la vertu op\u00e9rationnelle et la gloire guerri\u00e8re \u00e0 l&rsquo;arm\u00e9e de Sa Majest\u00e9.<\/p>\n<\/p>\n<p><p>Ci-dessous et pour mieux nous rappeler de lui, un extrait <a href=\"https:\/\/www.dedefensa.org\/article\/vision-de-william-s-lind\">d&rsquo;une pr\u00e9sentation<\/a> d&rsquo;un texte de Lind, sous le titre g\u00e9n\u00e9ral de &laquo; <em>Vision de William S. Lind<\/em> &raquo;. On y retrouve d&rsquo;autres r\u00e9f\u00e9rences plus lointaines de Lind sur notre site :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>Nous-m\u00eame connaissons bien William S. Lind (premi\u00e8re citation et r\u00e9f\u00e9rence \u00e0 Lind <a href=\"http:\/\/www.dedefensa.org\/redaction\/articles\/list\">le 3 mars 2003<\/a>) et son concept de G4G (premi\u00e8re citation et r\u00e9f\u00e9rence <a href=\"http:\/\/www.dedefensa.org\/article\/la-g4g-et-la-legitimite\">le 30 juillet 2006<\/a>). Le concept de Lind, que nous avons souvent interpr\u00e9t\u00e9 de diff\u00e9rentes fa\u00e7ons op\u00e9rationnelles nous int\u00e9resse parce qu&rsquo;il est si proche des conceptions gaullistes (voir <a href=\"http:\/\/www.dedefensa.org\/article\/la-g4g-est-elle-gaulliste\">le 23 janvier 2009<\/a>), c&rsquo;est-\u00e0-dire d&rsquo;une conception principielle du monde bas\u00e9e sur la souverainet\u00e9 et la l\u00e9gitimit\u00e9.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Nous avons la perception que les \u00e9v\u00e9nements, tout en ne d\u00e9classant en rien la G4G telle qu&rsquo;elle est pr\u00e9sent\u00e9e, surtout selon sa r\u00e9f\u00e9rence \u00e0 la Grande Strat\u00e9gie, doit donner \u00e0 un nouveau prolongement, que nous nommons G5G, <a href=\"http:\/\/www.dedefensa.org\/article\/we-the-people-a-transmute-le-concept-dinsurrection-1\">d\u00e9j\u00e0 r\u00e9f\u00e9renc\u00e9e<\/a> pour introduire une analyse plus profonde<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Lind a un parcours original, marqu\u00e9 par ses tr\u00e8s fortes convictions catholiques et un choix politique qu&rsquo;il a quelquefois qualifi\u00e9, d&rsquo;ailleurs en r\u00e9f\u00e9rence \u00e0 la France, de \u00ab\u00a0royaliste\u00a0\u00bb. Il ne faut donc pas s&rsquo;\u00e9tonner, et c&rsquo;est bien mon cas, s&rsquo;il donne une analyse de l&rsquo;affaire afghane d&rsquo;un point de vue philosophique extr\u00eamement \u00ab\u00a0essentialiste\u00a0\u00bb (j&rsquo;aurais pu \u00e9crire \u00ab\u00a0essentiellement essentialiste\u00a0\u00bb ?) qui prend pour cible et d\u00e9nonce le \u00ab\u00a0nominalisme\u00a0\u00bb caract\u00e9risant selon lui la \u00ab\u00a0vision du monde\u00a0\u00bb de l&rsquo;<em>establishment <\/em>washingtonien&#8230; Bien, on pourrait aussi bien parler, &ndash; mais ceci n&rsquo;exclue certainement pas cela dans une \u00e9poque o&ugrave; tout se d\u00e9grade, &ndash; de simulacre, de <em>narrative <\/em>et de virtualisme.<\/p>\n<\/p>\n<p><p>Par ailleurs, et pour corser le propos, on peut faire un tour du c\u00f4t\u00e9 d&rsquo;une vision originale sinon exotique, venue de l&rsquo;\u00e9trange et peu ou prou improbable guerrier de &lsquo;<em>veteranstoday.com<\/em>&lsquo; [VT], Kevin Barrett. L&rsquo;\u00e9diteur de VT ne recule jamais devant une hypoth\u00e8se audacieuse et des changements spectaculaires de position, parfois avec des interpr\u00e9tations ou des sources dont il faut savoir saisir l&rsquo;int\u00e9r\u00eat.<\/p>\n<\/p>\n<p><p>J&rsquo;ignore dans quelle cat\u00e9gorie classer <a href=\"https:\/\/www.veteranstoday.com\/2021\/08\/28\/taliban911\/\">ce texte<\/a> de Barrett, qui nous annonce que les talibans venus au pouvoir, qu&rsquo;il applaudit avec force, pourraient demander l&rsquo;ouverture d&rsquo;une enqu\u00eate internationale sur l&rsquo;attaque du 11 septembre 2001 (20<sup>e<\/sup> anniversaire dans une quinzaine). Cela nous rappelle au moins qu&rsquo;au doit, nous, rappeler \u00e0 la grande campagne de chasse au complotisme qu&rsquo;a d\u00e9clench\u00e9 le Covid dans le chef des milices de la vigilance, que le complotisme de la modernit\u00e9-tardive ne date pas de nos temps vaccinaux, qu&rsquo;il a connu sa naissance tumultueuse et son existence-premi\u00e8re (qui n&rsquo;est pas termin\u00e9e) avec les remous autour de l&rsquo;attaque 9\/11&#8230; La plume \u00e0 Barrett :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>Les talibans ont repris le pouvoir en Afghanistan quelques semaines seulement apr\u00e8s le retrait des troupes am\u00e9ricaines annonc\u00e9 par Biden, &ndash; et moins d&rsquo;un mois avant le 20e anniversaire des \u00e9v\u00e9nements du 11 septembre 2001. Les m\u00e9dias occidentaux, se faisant l&rsquo;\u00e9cho de leurs sources gouvernementales et militaires, se disent choqu\u00e9s. Qu&rsquo;est-ce qui a provoqu\u00e9 ce d\u00e9sastre ? Comment une arm\u00e9e de p\u00e9quenauds ruraux, d\u00e9vou\u00e9s et mal \u00e9quip\u00e9s, a-t-elle pu vaincre la seule superpuissance du monde ?<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>La r\u00e9ponse, en un mot, est <strong>le moral<\/strong>. La r\u00e9sistance afghane s&rsquo;est battue fi\u00e8rement pour d\u00e9fendre sa nation contre un envahisseur \u00e9tranger. Les Am\u00e9ricains et leurs laquais locaux, en revanche, n&rsquo;ont jamais vraiment eu le c&oelig;ur au combat. Pourquoi ? Parce qu&rsquo;ils savaient tous, d&rsquo;une mani\u00e8re ou d&rsquo;une autre, qu&rsquo;ils se battaient pour un mensonge.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>&Eacute;tonnamment, les politiciens pusillanimes et les abrutis de <\/em>[la presseSyst\u00e8me]<em> ne semblent pas l&rsquo;avoir compris. Ils continuent \u00e0 colporter sans vergogne le gros mensonge qui nous a mis dans le p\u00e9trin afghan en premier lieu. <\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Le New York Times rapporte : \u00ab\u00a0Le dimanche (15 ao&ucirc;t, jour de la prise de Kaboul par les talibans), Blinken a \u00e9galement d\u00e9clar\u00e9 que les talibans n&rsquo;oseraient pas risquer d&rsquo;\u00eatre surpris en train d&rsquo;abriter des terroristes internationaux comme Ben Laden, qui a planifi\u00e9 les attaques du 11 septembre 2001 depuis l&rsquo;Afghanistan.\u00a0\u00bb La National Public Radio nous dit : \u00ab\u00a0Le casus belli de l&rsquo;invasion de l&rsquo;Afghanistan par les &Eacute;tats-Unis \u00e0 la suite des attaques terroristes du 11 septembre 2001 \u00e9tait le refus des Talibans de livrer Oussama ben Laden, &ndash;  consid\u00e9r\u00e9 par Washington comme un fugitif international.\u00a0\u00bb Et ainsi de suite.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Comme d&rsquo;habitude, <\/em>[notre presseSyst\u00e8me]<em> colportent des fake news. La v\u00e9rit\u00e9 est qu&rsquo;Oussama Ben Laden n&rsquo;a jamais \u00e9t\u00e9 recherch\u00e9 en relation avec les \u00e9v\u00e9nements du 11 septembre, car il n&rsquo;y a jamais eu de preuves tangibles contre lui. Ce n&rsquo;est pas mon opinion. C&rsquo;est la position officielle du FBI, comme l&rsquo;a d\u00e9clar\u00e9 pour m\u00e9moire le porte-parole du Bureau, Rex Tomb : \u00ab\u00a0La raison pour laquelle le 11 septembre n&rsquo;est pas mentionn\u00e9 sur la page des personnes les plus recherch\u00e9es par Oussama Ben Laden est que le FBI ne dispose pas de preuves tangibles reliant Ben Laden au 11 septembre.\u00a0\u00bb<\/em> [&#8230;]<\/p>\n<\/p>\n<p><p>&raquo; <em>Les talibans ont toujours su que Ben Laden n&rsquo;avait rien \u00e0 voir avec le 11 septembre, comme l&rsquo;a soulign\u00e9 Suhail Shaheen, le principal porte-parole des talibans, dans une interview accord\u00e9e <a href=\"https:\/\/m911t.blogspot.com\/2019\/09\/talibans-top-spokesman-claims-al-qaeda.html\">\u00e0 CBS en 2019<\/a>.<\/em> [&#8230;]<\/p>\n<\/p>\n<p><p>&raquo; <em>L&rsquo;agence de renseignement du Pakistan, l&rsquo;ISI, est dirig\u00e9e par des hommes qui comprennent et ont des informations privil\u00e9gi\u00e9es sur le &lsquo;false flag&rsquo; du 11 septembre. J&rsquo;ai interview\u00e9 <a href=\"\/interviewed%20former%20ISI%20head%20Hamid%20Gul%20on%20my%20radio%20show\">l&rsquo;ancien chef de l&rsquo;ISI, Hamid Gul<\/a>, dans mon \u00e9mission de radio en 2010, et Gul a \u00e9t\u00e9 tr\u00e8s clair \u00e0 ce sujet. <\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>L&rsquo;ISI sait bien ce qu&rsquo;est le 11 septembre et entretient de bonnes relations avec les talibans. Il est \u00e0 l&rsquo;aise avec le premier ministre pakistanais Imran Khan, qui est favorable \u00e0 la v\u00e9rit\u00e9 sur le 11 septembre. <\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>L&rsquo;ISI devrait expliquer aux hauts dirigeants talibans qu&rsquo;ils doivent mettre la question de la v\u00e9rit\u00e9 sur le 11 septembre au premier plan. Les talibans devraient demander une enqu\u00eate internationale sur la d\u00e9molition contr\u00f4l\u00e9e du World Trade Center.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>En blanchissant le nom de Ben Laden et en prouvant qu&rsquo;Al-Qa\u00efda n&rsquo;a rien \u00e0 voir avec le 11 septembre, les talibans pourraient renforcer leur l\u00e9gitimit\u00e9 et prouver que l&rsquo;occupation contre laquelle ils se sont battus si longtemps et si efficacement \u00e9tait fond\u00e9e sur un mensonge.<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Certes, il serait \u00e9tonnant que les talibans, et les Pakistanais d&rsquo;une certaine fa\u00e7on, suivent le conseil de Barrett dans le contexte \u00e9voqu\u00e9 nous mettant dans une atmosph\u00e8re particuli\u00e8rement &lsquo;<em>rock&rsquo;n&rsquo;roll<\/em>&lsquo;. Il n&#8217;emp\u00eache pas pour autant qu&rsquo;avec la prise de pouvoir des talibans, on en revient effectivement aux origines de l&rsquo;actuelle s\u00e9quence ouverte dans le fracas extraordinaire du 11 septembre 2001, suivi presqu&rsquo;aussit\u00f4t (le 7 octobre 2001) par l&rsquo;attaque de l&rsquo;Afghanistan des talibans d&rsquo;alors. C&rsquo;est comme si une r\u00e9volution, dans le sens orbital et spatial que rappelait Hanna Arendt, parvenait \u00e0 son terme en revenant \u00e0 son point de d\u00e9part. Le symbolisme ne manquera pas de frapper ceux qui y sont attentifs.<\/p>\n<\/p>\n<p><p>Donc, William S. Lind, sur lequel je reviens, est l\u00e0, ci-dessous, pour nous rapporter ce qui, \u00e0 son avis justifia, guida et structura l&rsquo;extraordinaire catastrophe qu&rsquo;est cette campagne de vingt ans en Afghanistan. Si son propos prend pour cible le nominalisme, on retrouve \u00e9videmment et par cons\u00e9quent le penchant de Lind pour la l\u00e9gitimit\u00e9, l&rsquo;autorit\u00e9, et la fa\u00e7on dont les choses sans essence ni transcendance en sont dramatiquement priv\u00e9es. Si c&rsquo;est effectivement le cas, on comprend combien ce qui constitue la mascarade de civilisation que nous sommes devenus se trouve dans un \u00e9tat de d\u00e9liquescence tr\u00e8s accentu\u00e9e.<\/p>\n<\/p>\n<p><p>Nul ne s&rsquo;\u00e9tonnera que le site o&ugrave; Lind publie des chroniques deux \u00e0 quatre fois par mois, dont <a href=\"https:\/\/www.traditionalright.com\/nominalism-and-the-defeat-of-afghanistan\/\">celle-ci<\/a> il y a six jours, se nomme &lsquo;<em>traditionalright.com<\/em>&lsquo; (ais\u00e9 \u00e0 traduire).<\/p>\n<\/p>\n<p><h4>PhG, <em>Semper Phi<\/em><\/h4>\n<\/p>\n<p><p>_________________________<\/p>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d;font-size:1.65em;font-variant:small-caps;\">Le nominalisme de la d\u00e9faite en Afghanistan<\/h2>\n<\/p>\n<p><p>Les R\u00e9publicains tentent de rendre le pr\u00e9sident Biden responsable de la d\u00e9faite en Afghanistan, tandis que les D\u00e9mocrates d\u00e9signent l&rsquo;accord de paix du pr\u00e9sident Trump avec les Talibans comme en \u00e9tant la cause.  En fait, une victoire des talibans est devenue in\u00e9vitable lorsque, au d\u00e9but de la guerre, les &Eacute;tats-Unis ont \u00e9largi leurs objectifs, passant de la chasse ou de l&rsquo;\u00e9limination d&rsquo;Al-Qa\u00efda \u00e0 la transformation de l&rsquo;Afghanistan en une d\u00e9mocratie moderne et la\u00efque.  Cet objectif \u00e9tait inatteignable, quoi que nous fassions.  Si nous voulons bl\u00e2mer les pr\u00e9sidents, les coupables sont George W. Bush et son idiotie et Barack Obama et son vide \u00e9l\u00e9gant. Le premier a permis la d\u00e9rive de la mission et le second a pr\u00e9sid\u00e9 \u00e0 sa poursuite, se contentant de botter en touche. Il est tout \u00e0 l&rsquo;honneur de Biden et de Trump d&rsquo;avoir pris la d\u00e9cision, apr\u00e8s dix-neuf ans d&rsquo;\u00e9chec, d&rsquo;\u00e9teindre la lumi\u00e8re et de d\u00e9brancher la prise.<\/p>\n<\/p>\n<p><p>Mais comment l&rsquo;ensemble de l&rsquo;establishment de Washington en mati\u00e8re de d\u00e9fense et de politique \u00e9trang\u00e8re a-t-il pu se tromper \u00e0 ce point ?  Une r\u00e9ponse est que, si vous voulez devenir et rester un membre de l&rsquo;establishment, vous ne devez jamais faire de vagues.  Comme presque toutes les personnes en question veulent \u00eatre quelque chose, et non faire quelque chose, elles suivent cette r\u00e8gle, o&ugrave; qu&rsquo;elle m\u00e8ne.  Une d\u00e9faite \u00e0 la guerre n&rsquo;est qu&rsquo;une petite affaire compar\u00e9e \u00e0 un risque pour leur carri\u00e8re.<\/p>\n<\/p>\n<p><p>Une autre r\u00e9ponse est que les membres de l&rsquo;establishment sont presque tous nominalistes. C&rsquo;est-\u00e0-dire que s&rsquo;ils donnent un nom \u00e0 une chose, celle-ci prend une existence r\u00e9elle dans leur esprit. L&rsquo;arm\u00e9e nationale afghane en est un parfait exemple. &lsquo;Parce que nous l&rsquo;appelions une arm\u00e9e, que nous lui donnions beaucoup d&rsquo;argent, d&rsquo;\u00e9quipement et de formation am\u00e9ricaines, et que nous connaissions son ordre de bataille, c&rsquo;\u00e9tait une arm\u00e9e.  Mais ce n&rsquo;\u00e9tait pas le cas. &Agrave; part quelques unit\u00e9s de commandos, c&rsquo;\u00e9tait un ramassis de types qui avaient besoin d&rsquo;un emploi et qui n&rsquo;avaient que peu ou pas d&rsquo;int\u00e9r\u00eat pour le combat.  Ces hommes voyaient rarement leur solde, car elle \u00e9tait vol\u00e9e avant de leur parvenir.  Les rations et les munitions subissaient souvent le m\u00eame sort.  Cette arm\u00e9e s&rsquo;est effondr\u00e9e du jour au lendemain parce qu&rsquo;elle n&rsquo;a jamais vraiment exist\u00e9 en dehors de l&rsquo;esprit des nominalistes de l&rsquo;establishment.<\/p>\n<\/p>\n<p><p>Ce m\u00eame nominalisme s&rsquo;est appliqu\u00e9 \u00e0 l&rsquo;ensemble du gouvernement afghan.  Les nominalistes de Washington pensaient qu&rsquo;il \u00e9tait r\u00e9el ; les Afghans savaient qu&rsquo;il ne l&rsquo;\u00e9tait pas.  Un commandant de bataillon des Marines tout juste rentr\u00e9 d&rsquo;Afghanistan a bien exprim\u00e9 cette situation : &laquo; Parler \u00e0 un villageois afghan du 14e si\u00e8cle du gouvernement de Kaboul, c&rsquo;est comme parler \u00e0 votre chat de la face cach\u00e9e de la lune.  Vous ne savez pas ce que c&rsquo;est et lui, il n&rsquo;en a rien \u00e0 battre. &raquo;<\/p>\n<\/p>\n<p><p>On constate que le nominalisme est omnipr\u00e9sent dans l&rsquo;\u00e9laboration de la politique am\u00e9ricaine. Les nominalistes de Washington pensent que l&rsquo;Irak est un &Eacute;tat. Ce n&rsquo;est pas le cas, car le pouvoir r\u00e9el est entre les mains de milices ethniques et religieuses. L&rsquo;&Eacute;tat n&rsquo;est qu&rsquo;une fa\u00e7ade, mais comme il a un parlement, des \u00e9lections, des ministres, etc., il est r\u00e9el pour les nominalistes. Il n&rsquo;est pas surprenant que notre politique l\u00e0-bas ait \u00e9t\u00e9 une s\u00e9rie de d\u00e9sastres depuis le d\u00e9sastre initial de l&rsquo;invasion de la chose.<\/p>\n<\/p>\n<p><p>Le nominalisme de l&rsquo;\u00e9lite de Washington ne se limite pas \u00e0 la politique \u00e9trang\u00e8re. Elle consid\u00e8re l&rsquo;arm\u00e9e am\u00e9ricaine de la m\u00eame mani\u00e8re.  Si vous appelez quelque chose une arm\u00e9e, elle doit \u00eatre capable de se battre, m\u00eame si vous avez rempli ses rangs de femmes, fait d\u00e9pendre la promotion du politiquement correct plut\u00f4t que des capacit\u00e9s militaires et mis des bureaucrates \u00e0 la place des g\u00e9n\u00e9raux.  Lorsqu&rsquo;elle perd une guerre, comme elle vient de le faire en Afghanistan, on dit que c&rsquo;est la faute \u00e0 \u00ab\u00a0pas d&rsquo;chance\u00a0\u00bb. Le fait qu&rsquo;elle ait cess\u00e9 d&rsquo;\u00eatre une v\u00e9ritable arm\u00e9e il y a des d\u00e9cennies n&rsquo;a pas droit de cit\u00e9.<\/p>\n<\/p>\n<p><p>Les civils de l&rsquo;establishment de Washington se sont impr\u00e9gn\u00e9s du nominalisme depuis qu&rsquo;ils ont commenc\u00e9 leur \u00ab\u00a0\u00e9ducation\u00a0\u00bb dans diverses institutions d&rsquo;\u00e9lite.  Malheur \u00e0 ceux qui ont fait remarquer que l&rsquo;ONU s&rsquo;est av\u00e9r\u00e9e inutile d&rsquo;une crise \u00e0 l&rsquo;autre, que nos alli\u00e9s \u00ab\u00a0d\u00e9mocratiques\u00a0\u00bb sont tous en r\u00e9alit\u00e9 des oligarchies ou que l&rsquo;id\u00e9e des \u00ab\u00a0droits de l&rsquo;homme\u00a0\u00bb varie \u00e9norm\u00e9ment dans sa d\u00e9finition d&rsquo;une culture et d&rsquo;un peuple \u00e0 l&rsquo;autre. Appeler une entit\u00e9 un &Eacute;tat, une arm\u00e9e ou une d\u00e9mocratie signifie qu&rsquo;elle le devient comme par magie. Et la pens\u00e9e magique qui domine l&rsquo;image que l&rsquo;establishment se fait du monde conduit \u00e0 des d\u00e9b\u00e2cles r\u00e9p\u00e9t\u00e9es dont il ne tire nulle le\u00e7on.<\/p>\n<\/p>\n<p><p>Un retour \u00e0 la r\u00e9alit\u00e9 \u00e0 partir du nominalisme ne peut se produire que lorsque l&rsquo;ensemble de l&rsquo;establishment est remplac\u00e9. C&rsquo;est ce qui vient de se passer en Afghanistan \u00e0 une vitesse stup\u00e9fiante. Je soup\u00e7onne que l&rsquo;effondrement de l&rsquo;establishment am\u00e9ricain sera tout aussi rapide lorsqu&rsquo;il commencera.<\/p>\n<\/p>\n<p><h4>William S. Lind<\/h4><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Du nominalisme au complotisme 29 ao&ucirc;t 2021 &ndash; On n&rsquo;en a pas fini, et on n&rsquo;en aura pas fini avant longtemps d&rsquo;analyser cette \u00ab\u00a0guerre\u00a0\u00bb d&rsquo;Afghanistan (les guillemets sugg\u00e8re ce que j&rsquo;en pense), l&rsquo;\u00e9chec qui l&rsquo;a caract\u00e9ris\u00e9e tout au long des op\u00e9rations, et la catastrophe qui l&rsquo;a conclue \u00e0 ce stade de la s\u00e9quence. Pour suivre&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[354,370,3236,3265,5949,3266,1012,3866,3321,3865],"class_list":["post-79885","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-354","tag-370","tag-afghanistan","tag-ben","tag-kaboul","tag-laden","tag-lind","tag-s","tag-septembre","tag-william"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79885"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79885\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79885"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79885"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}