{"id":79910,"date":"2021-09-19T18:49:12","date_gmt":"2021-09-19T18:49:12","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2021\/09\/19\/une-etrange-coalition-de-rencontre\/"},"modified":"2021-09-19T18:49:12","modified_gmt":"2021-09-19T18:49:12","slug":"une-etrange-coalition-de-rencontre","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2021\/09\/19\/une-etrange-coalition-de-rencontre\/","title":{"rendered":"Une \u00e9trange coalition de rencontre"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Une \u00e9trange coalition de rencontre<\/h2>\n<\/p>\n<blockquote>\n<p><p>&bull; Qui dirait <strong>une proposition aussi saugrenue<\/strong> que \u00ab\u00a0Macron et la rappeuse US Nikki Minaj, m\u00eame combat\u00a0\u00bb ? &bull; Alors que <strong>ce combat est, pour ce qu&rsquo;il dure, un combat antiSyst\u00e8me<\/strong> puisque, toutes choses consid\u00e9r\u00e9es par ailleurs, il reste que \u00ab\u00a0D.C.-l&rsquo;hyperfolle\u00a0\u00bb et son Empereur-g\u00e2teux sont absolument le Syst\u00e8me&#8230; &bull; Ainsi en est-il de l&rsquo;instant et du moment pr\u00e9sent : Macron et Minaj, pourtant adversaires sur la vaccination, <strong>pr\u00e9sentent tous deux un obstacle pr\u00e9occupant pour \u00ab\u00a0la bande \u00e0 Biden\u00a0\u00bb<\/strong>. &bull; L&rsquo;antiSyst\u00e8me, <strong>par d\u00e9finition producteur de d\u00e9sordre du Syst\u00e8me<\/strong>.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Nous parlons \u00ab\u00a0coalitions\u00a0\u00bb plus qu'\u00a0\u00bballiance\u00a0\u00bb, car il nous para&icirc;t bien improbable et \u00e9trange d&rsquo;envisager que cette \u00ab\u00a0\u00e9trange coalition de rencontre\u00a0\u00bb puisse devenir \u00ab\u00a0alliance\u00a0\u00bb. Nous sommes dans des temps-bouffe en plus qu&rsquo;\u00eatre devenus-fous, et plus rien n&rsquo;est \u00e0 rejeter pourvu que cela acc\u00e9l\u00e8re le tempo du d\u00e9sordre qui se fait de plus en plus antiSyst\u00e8me ; plus rien, y compris que la rappeuse consid\u00e9rable Nikki Minaj, Afro-Am\u00e9ricaine issue de La Trinidad, \u00e0 la respectable fortune de 100 $millions et aux nombreux millions de &lsquo;<em>followers<\/em>&lsquo; sur son compte, devienne pour les sp\u00e9cialistes une actrice \u00ab\u00a0m\u00e9tahistorique\u00a0\u00bb en d\u00e9clarant une \u00ab\u00a0guerre sainte\u00a0\u00bb contre la vaccination anti-Covid d\u00e9cr\u00e9t\u00e9e par une directive de Biden.<\/p>\n<\/p>\n<p><p>En suivant cette fois la voie trac\u00e9e par le site exotique &lsquo;<em>WhatDoesItMeans<\/em>&lsquo; (WDIM), dont nous avons d\u00e9j\u00e0 soulign\u00e9 combien ses analyses se rapprochaient de plus en plus de certaines v\u00e9rit\u00e9s-de-situation (bien identifi\u00e9es par les sources cit\u00e9es), nous allons \u00eatre conduit \u00e0 examiner deux cas en train de se d\u00e9velopper, dont le rapprochement, fait par WDIM constitue une occurrence inattendue, paradoxale, grossi\u00e8re, etc., et pourtant compl\u00e8tement \u00e0 consid\u00e9rer puisque le Syst\u00e8me impose effectivement cette sorte d&rsquo;occurrence par ses agissements absolument insupportables et compl\u00e8tement grotesques dans le cadre de simulacres absolument insupportables.<\/p>\n<\/p>\n<p><p>Voici donc ces deux cas, chacun improbable en eux-m\u00eames, et dont le rapprochement l&rsquo;est encore bien plus.<\/p>\n<\/p>\n<p><p>&bull; Mais commen\u00e7ons par le \u00ab\u00a0raisonnable\u00a0\u00bb, qui n&rsquo;est en fait pas une production de la raison dont on sait qu&rsquo;elle est <a href=\"https:\/\/www.dedefensa.org\/article\/critique-de-la-raison-subvertie\">subvertie<\/a> mais bien, \u00e0 notre sens, un effet d&rsquo;un climat, d&rsquo;une tension interne au pays (la France) et, fort probablement, &ndash; nous tenons ferme \u00e0 cette hypoth\u00e8se, &ndash; une occasion pour son pr\u00e9sident qui voit avec une certaine appr\u00e9hension approcher le terme de son mandat, une occasion d&rsquo;affirmer une posture d&rsquo;extr\u00eame fermet\u00e9 qui pourrait flatter la nostalgie gaullienne de son \u00e9lectorat. En bref, la France ne d\u00e9col\u00e8re pas et parle de mesures radicales contre son \u00ab\u00a0grand alli\u00e9\u00a0\u00bb am\u00e9ricaniste qui ne l&rsquo;est plus du tout pour l&rsquo;instant, &ndash; et ce n&rsquo;est pas de la \u00ab\u00a0Grande Politique\u00a0\u00bb d\u00e9cid\u00e9e par une volont\u00e9 ferme mais bien, pour nous, de la psychologie \u00e0 l&rsquo;int\u00e9rieur d&rsquo;objurgations tr\u00e8s fermes de la communication et de ses communicants. (Mais l&rsquo;on sait bien qu&rsquo;il y a un formidable <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-leffet-janus\">effet-<em>Janus<\/em><\/a> dans la communication.)<\/p>\n<\/p>\n<p><p>Par cons\u00e9quent, l&rsquo;on d\u00e9couvre que la fureur fran\u00e7aise \u00e0 propos des <a href=\"https:\/\/www.dedefensa.org\/article\/notes-submersibles-sur-une-tragedie-bouffe\">sous-marins AUKUS<\/a> semble se faire de plus en plus forte, et qu&rsquo;elle para&icirc;t de moins en moins feinte, comme si la posture de communication du d\u00e9part semblait se colorer modestement d&rsquo;une conviction que l&rsquo;affaire ne peut en rester l\u00e0, qu&rsquo;elle est grave et que cela doit \u00eatre marqu\u00e9 du sceau de la r\u00e9solution pr\u00e9sidentielle. La France attaque donc durement, les USA et l&rsquo;Australie, tout en traitant avec un m\u00e9pris du genre que les Britanniques n&rsquo;aiment pas, le Royaume-Unis de \u00ab\u00a0cinqui\u00e8me roue du carrosse\u00a0\u00bb ou de \u00ab\u00a0petit commissionnaire\u00a0\u00bb dans cette affaire. (A preuve, si la France a rappel\u00e9 \u00ab\u00a0pour consultations\u00a0\u00bb ses ambassadeurs en Australie et aux USA, elle a laiss\u00e9 celui de Londres dans ses appartements.)<\/p>\n<\/p>\n<p><p>Ainsi RT.com, destin\u00e9 aux lecteurs et spectateurs aux USA, nous donnent-ils quelques \u00e9l\u00e9ments \u00e0 m\u00e9diter, si tant est <a href=\"https:\/\/www.rt.com\/news\/535232-france-australia-submarines-nato\/\">qu&rsquo;il y ait mati\u00e8re<\/a>, assez dans tous les cas pour conduire une m\u00e9ditation  :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>\u00ab\u00a0Le fait que, pour la premi\u00e8re fois dans l&rsquo;histoire des relations entre les &Eacute;tats-Unis et la France, nous rappelions notre ambassadeur pour des consultations, est un acte politique grave qui montre l&rsquo;intensit\u00e9 de la crise aujourd&rsquo;hui entre nos deux pays et aussi avec l&rsquo;Australie\u00a0\u00bb, a d\u00e9clar\u00e9 Le Drian aux m\u00e9dias samedi.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0Les alli\u00e9s\u00a0\u00bb, a d\u00e9clar\u00e9 Le Drian \u00e0 la t\u00e9l\u00e9vision France 2, \u00ab\u00a0ne se comportent pas comme les &Eacute;tats-Unis et d&rsquo;autres ont fait avec le r\u00e9cent accord\u00a0\u00bb. Le ministre des affaires \u00e9trang\u00e8res a \u00e9galement r\u00e9v\u00e9l\u00e9 que le pr\u00e9sident fran\u00e7ais Emmanuel Macron et le pr\u00e9sident am\u00e9ricain Joe Biden n&rsquo;ont pas encore eu de conversation sur l&rsquo;accord AUKUS et les tensions qui en d\u00e9coulent.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>L&rsquo;avenir de l&rsquo;OTAN, a ajout\u00e9 M. Le Drian, sera affect\u00e9 car elle doit prendre en compte et s&rsquo;impliquer dans la crise entre les pays. L&rsquo;Espagne accueillera le prochain sommet de l&rsquo;OTAN \u00e0 Madrid en 2022 et, selon la France, cette situation ne pourra y passer inaper\u00e7ue. Le pr\u00e9sident du Comit\u00e9 militaire de l&rsquo;OTAN, l&rsquo;amiral Rob Bauer, a d\u00e9j\u00e0 tent\u00e9 de minimiser la tension, affirmant qu&rsquo;elle n&rsquo;aurait pas d&rsquo;impact sur la \u00ab\u00a0coop\u00e9ration militaire\u00a0\u00bb de l&rsquo;organisation.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Samedi, la France a toutefois sembl\u00e9 d\u00e9termin\u00e9e \u00e0 faire comprendre que le conflit ne restera pas sans suite, en promettant de \u00ab\u00a0travailler \u00e0 un programme commun d&rsquo;actions concr\u00e8tes pour d\u00e9fendre un ordre international v\u00e9ritablement multilat\u00e9ral\u00a0\u00bb avec l&rsquo;Inde <\/em>[Ndlr : larron plus \u00e9loign\u00e9 et disculp\u00e9 des manigances anglo-saxons]<em>, tout en promettant \u00e9galement de faire de la strat\u00e9gie de s\u00e9curit\u00e9 de l&rsquo;UE, &ndash; qui implique depuis longtemps l&rsquo;id\u00e9e contest\u00e9e d&rsquo;une arm\u00e9e de l&rsquo;Union europ\u00e9enne, &ndash; la priorit\u00e9 de Paris<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Oui enfin ! Il y a beaucoup \u00e0 m\u00e9diter dans cette affaire, du bon et du moins bon, du sans-surprise et du surprenant. Si l&rsquo;ancien chef du renseignement militaire fran\u00e7ais <a href=\"https:\/\/fr.sputniknews.com\/international\/202109191046150397-malgre-la-crise-grave-des-sous-marins-paris-va-continuer-de-suivre-washington-estime-le-general\/\">nous assure<\/a> que la France continuera \u00e0 suivre Washington, &ndash; question de flair si l&rsquo;on veut, &ndash; la presse londonienne nous informe que toute l&rsquo;affaire a \u00e9t\u00e9 mont\u00e9e au cours, ou plut\u00f4t <a href=\"https:\/\/sputniknews.com\/20210919\/french-blindsided-as-aukus-details-were-discussed-at-g7-summit-leaving-macron-out---report-1089201184.html\">en marge du G7<\/a> avec Johnson en \u00ab\u00a0petit commissionnaire\u00a0\u00bb entretenant l&rsquo;Australien, tandis que Macron s&rsquo;entretenait, lui, avec le g\u00e2teux empereur dans ce que certains imb\u00e9ciles baptis\u00e8rent une \u00ab\u00a0<em>bromance<\/em>\u00ab\u00a0, et par cons\u00e9quent n&rsquo;y voyait que du feu. <em>Start-Up <\/em>mais cocu.<\/p>\n<\/p>\n<p><p>Pourtant, WDIM, dans son r\u00f4le de boutefeu, y croit dur comme fer et pr\u00e9sente Macron comme sur le point de d\u00e9serter le navire transatlantique. Il ne le pr\u00e9cise pas mais nous le faisons pour lui en nous r\u00e9p\u00e9tant : le personnage est assez immerg\u00e9 dans les contines de ses communicants pour croire qu&rsquo;une telle posture, poursuivie le plus loin possible, serait un excellent atout \u00e9lectoral ; ce qui, en soi et sans affirmer plus, pourrait nous conduire \u00e0 des incidents regrettables sinon fatals, parce que \u00ab\u00a0D.C.-l&rsquo;hyperfolle\u00a0\u00bb ne plaisante pas avec l&rsquo;alignement dans les rangs ; et l\u00e0 se trouve le suspens, si Macron d\u00e9cide de tirer un bon coup sur la corde pour para&icirc;tre un peu plus napol\u00e9onien-gaulliste, et si les wokenistes-am\u00e9ricanistes de l&rsquo;entourage de Biden prennent la mouche, et que l&rsquo;on monte aux extr\u00eames, et que l&rsquo;on se trouve dans une situation inextricable de f\u00e2cheries et de bouderies&#8230; Et cela donne <a href=\"https:\/\/www.whatdoesitmean.com\/index3690.htm\">ceci de WDIM<\/a>, un peu de grain \u00e0 moudre, avec les am\u00e9nagements d&rsquo;usage dans la traduction devenue adaptation, du fait du style assez peu orthodoxe habituel  \u00e0 ce site pour lequel Biden n&rsquo;est rien de moins qu&rsquo;un \u00ab\u00a0leader socialiste\u00a0\u00bb :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Dans cette transcription et bien que l&rsquo;\u00e9loignement de l&rsquo;Europe du leader socialiste Biden semble \u00ab\u00a0tr\u00e8s similaire\u00a0\u00bb \u00e0 ce que le pr\u00e9sident Donald Trump tentait de faire, <\/em>[les sources consult\u00e9es] <em>s&rsquo;accordent \u00e0 observer que la principale diff\u00e9rence r\u00e9side dans le fait que Trump savait que l&rsquo;OTAN \u00e9tait devenue obsol\u00e8te et n&rsquo;\u00e9tait plus n\u00e9cessaire dans un monde multipolaire. C&rsquo;est un fait \u00e9galement connu du pr\u00e9sident fran\u00e7ais Emmanuel Macron, qui avait pr\u00e9c\u00e9demment averti les pays europ\u00e9ens : \u00ab\u00a0Ce que nous vivons actuellement, c&rsquo;est <a href=\"https:\/\/www.economist.com\/europe\/2019\/11\/07\/emmanuel-macron-warns-europe-nato-is-becoming-brain-dead\">la mort c\u00e9r\u00e9brale de l&rsquo;OTAN<\/a>\u00ab\u00a0. En raison de la trahison de Biden, la France enrag\u00e9e a <a href=\"https:\/\/www.rt.com\/news\/535167-france-recalls-ambassadors-aukus\/\">rappel\u00e9 ses ambassadeurs<\/a> des &Eacute;tats-Unis et d&rsquo;Australie, et des commentateurs demandent maintenant : \u00ab\u00a0Alors que la France furieuse pr\u00e9pare sa vengeance pour la trahison de l&rsquo;Am\u00e9rique sur son accord sur les sous-marins, choisira-t-elle <a href=\"https:\/\/www.rt.com\/op-ed\/535118-france-plots-revenge-us-treachery\/\">l&rsquo;option nucl\u00e9aire de quitter l&rsquo;OTAN<\/a> ?\u00a0\u00bb&#8230;<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>&bull; L&rsquo;audace de la <em>narrative <\/em>ainsi d\u00e9velopp\u00e9e est \u00e9galement que nous passons, <a href=\"https:\/\/www.whatdoesitmean.com\/index3690.htm\">presque sans transition<\/a>, des sous-marins, de l&rsquo;OTAN, de Macron en campagne et de la fureur fran\u00e7aise, \u00e0 la rappeuse Nicki Minaj qui fait l&rsquo;essentiel du second cas examin\u00e9. Il s&rsquo;agit bien d&rsquo;audace, mais \u00e0 nos yeux compl\u00e8tement justifi\u00e9e comme nous nous en expliquerons plus loin. Dans tous les cas, les multiples occupations de &lsquo;<em>Ol&rsquo;white Joe<\/em>&lsquo; autorisent cette audace et l&rsquo;encha&icirc;nement va de soi, qui nous entra&icirc;ne sur les traces rythm\u00e9es de la consid\u00e9rable Nicki Minaj. C&rsquo;en est au point o&ugrave; un \u00e9lu de la nation, le d\u00e9put\u00e9 r\u00e9publicain Gaetz, en fait la colisti\u00e8re de Trump en 2024, ce qui nous laisse \u00e0 penser \u00e0 propos du s\u00e9rieux consid\u00e9rable de l&rsquo;affaire (nous laissons, disons en \u00ab\u00a0rappeuse-dans-le-texte\u00a0\u00bb l&rsquo;\u00e9nonc\u00e9 des fureurs terribles de Minaj <a href=\"https:\/\/redstate.com\/bonchie\/2021\/09\/17\/nicki-minaj-fights-back-against-harassing-reporters-and-im-here-for-it-n444688\">qui n&rsquo;h\u00e9site pas une seconde<\/a> \u00e0 d\u00e9noncer ceux qui, parmi les journalistes wokenistes, n&rsquo;ont pas h\u00e9sit\u00e9 \u00e0 la d\u00e9noncer pour son anti-vaxxisme) :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Dans le m\u00eame temps o&ugrave; il subissait les suites de  ce qui est d\u00e9crit comme \u00ab\u00a0une plaisanterie dangereuse qui ne fera qu&rsquo;aggraver la crise g\u00e9opolitique avec la Chine\u00a0\u00bb, le leader socialiste Biden a vu son programme de vaccination forc\u00e9e<\/em> [&#8230;] <em>contrari\u00e9 apr\u00e8s que la FDA ait rejet\u00e9 les injections de rappel parce qu&rsquo;elle a constat\u00e9 un risque accru d&rsquo;inflammation cardiaque chez ceux qui les recevaient<\/em>&#8230; [&#8230;] <em>Tout cela est connu de la c\u00e9l\u00e8bre rappeuse noire Nicki Minaj, dont la \u00ab\u00a0guerre sainte sur Internet\u00a0\u00bb<\/em> [contre les vaccins]  [&#8230;] <em>est <a href=\"https:\/\/www.washingtonpost.com\/opinions\/2021\/09\/17\/nicki-minaj-vaccine-tweet-covid-infertility-misinformation\/\">maintenant rejointe<\/a> par d&rsquo;autres musiciens noirs, tels que le rappeur Busta Rhymes et les chanteuses R&#038;B Tank et Summer Walker, qui sont intervenus sur sc\u00e8ne et sur les m\u00e9dias sociaux pour remettre en question la s\u00e9curit\u00e9 et de l&rsquo;utilit\u00e9 de ces vaccins exp\u00e9rimentaux&#8230;<\/em> [&#8230;] <em>Minaj a d\u00e9clar\u00e9 : \u00ab\u00a0Ne venez pas me dire que je ne peux pas \u00eatre d&rsquo;accord avec un r\u00e9publicain !\u00a0\u00bb, <a href=\"https:\/\/boundingintocomics.com\/2021\/09\/17\/rapper-nicki-minaj-compares-cancel-culture-to-censorship-in-communist-china-following-vaccine-comments\/\">comparant<\/a> ensuite le &lsquo;culture de l&rsquo;annulation&rsquo;<\/em> [du wokenisme] <em>\u00e0 la censure en Chine communiste. Lorsque les m\u00e9dias gauchistes l&rsquo;ont attaqu\u00e9e hier, Minaj a lanc\u00e9 ses dizaines de millions de fans sur eux en affichant les num\u00e9ros de t\u00e9l\u00e9phone et les adresses de certains journalistes, \u00e9crivant \u00e0 <a href=\"https:\/\/www.thedailybeast.com\/nicki-minaj-sics-her-fans-on-reporters\">l&rsquo;une d&rsquo;entre eux<\/a> : \u00ab\u00a0Sharlene Rampersad BITCH YOUR DAYS ARE FUCKING NUMBERED YOU DIRTY HOE\u00a0\u00bb. Hier, des fans de Mme Minaj ont poursuivi leur protestation au si\u00e8ge du CDC en scandant \u00ab\u00a0<a href=\"https:\/\/pagesix.com\/2021\/09\/17\/nicki-minaj-fans-chat-at-cdc-hq-that-star-told-the-truth-on-vaccines\/\">Elle dit la v\u00e9rit\u00e9 !<\/a>\u00ab\u00a0, et Matt Gaetz, d\u00e9put\u00e9 r\u00e9publicain, \u00e0 la Chambre, a tweet\u00e9 le message hilarant \u00ab\u00a0<a href=\"https:\/\/www.rawstory.com\/trump-nicki-manij-vp-2024\/\">Trump\/Minaj 2024<\/a>\u00ab\u00a0, proposant un &lsquo;ticket&rsquo; pr\u00e9sidentiel Trump-Nicki Minaj pour les pr\u00e9sidentielles de 2024<\/em>&#8230; &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Tout cela semble ressortir du <em>showbiz<\/em>-en-folie que nous connaissons aujourd&rsquo;hui, mais c&rsquo;est aussi de la politique puisque, dans cette <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-la-tragedie-bouffe\">trag\u00e9die-bouffe<\/a> et dans ces temps-devenus-fous, la politique n&rsquo;est rien d&rsquo;autre que du \u00ab\u00a0<em>showbiz<\/em>-en-folie\u00a0\u00bb. Puisque l&rsquo;on a fait du Covid et du vaccin, et <a href=\"https:\/\/www.dedefensa.org\/article\/letrange-cadeau-danniversaire-covid911\">Biden en premier<\/a>, une cause politique o&ugrave; s&rsquo;y opposer devient antiSyst\u00e8me, alors Minaj est antiSyst\u00e8me et son exemple ne doit pas d\u00e9plaire \u00e0 ses \u00ab\u00a0fr\u00e8res\u00a0\u00bb Africains-Am\u00e9ricains, comme \u00e0 ses millions de \u00ab\u00a0<em>followers<\/em>\u00ab\u00a0. L&rsquo;on sait bien que les Noirs ont, aux USA, une f\u00e2cheuse m\u00e9moire des \u00ab\u00a0exp\u00e9rimentations\u00a0\u00bb m\u00e9dicales, et qu&rsquo;ils sont, de tr\u00e8s loin, les moins port\u00e9s \u00e0 se faire vacciner, ce qui installe comme on l&rsquo;a d\u00e9j\u00e0 vu, une paradoxale situation de <a href=\"https:\/\/www.thegatewaypundit.com\/2021\/09\/welcome-legalized-segregation-new-york-family-kicked-restaurant-failing-produce-vaccine-passport\/\">racisme et d&rsquo;apartheid<\/a> dans un r\u00e9gime absolument vou\u00e9 \u00e0 l&rsquo;antiracisme, au wokenisme, aux minorit\u00e9s et ainsi de suite. C&rsquo;est un contexte, <a href=\"https:\/\/www.whatdoesitmean.com\/index3688.htm\">d\u00e9j\u00e0 pr\u00e9sent\u00e9 par WDIM<\/a>, particuli\u00e8rement inqui\u00e9tant pour le Syst\u00e8me et ses manigances, alors que Minaj intervient&#8230;<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>&#8230; De tous les Am\u00e9ricains, les Noirs semblent \u00eatre les seuls \u00e0 savoir que quelque chose ne tourne pas rond dans la fa\u00e7on dont le r\u00e9gime socialiste de Biden g\u00e8re le Covid et ces vaccins exp\u00e9rimentaux ARNm.<\/em> [C&rsquo;est] <em>un fait montr\u00e9 par le CDC, qui, dans son rapport du 8 septembre, r\u00e9v\u00e8lent de mani\u00e8re stup\u00e9fiante que selon la statistique par race sur les 59% de personnes vaccin\u00e9es aux USA, on d\u00e9couvre que  <a href=\"https:\/\/www.kff.org\/coronavirus-covid-19\/issue-brief\/latest-data-on-covid-19-vaccinations-race-ethnicity\/\">seulement 10%<\/a> des Noirs am\u00e9ricains le sont,<\/em> [alors que,] <em>malgr\u00e9 la directive ill\u00e9gale de Biden, le<\/em> [rythme des vaccinations] <em><a href=\"http:\/\/www.informationliberation.com\/?id=62546\">continue de baisser<\/a><\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>&#8230; Ainsi comprendra-t-on ais\u00e9ment que ce qu&rsquo;il nous importe de montrer n&rsquo;est certainement pas la possibilit\u00e9 presque surr\u00e9aliste d&rsquo;une crise centrale au sein de l&rsquo;OTAN du fait de la r\u00e9silience pseudo-n\u00e9o-gaulliste d&rsquo;un Macron pr\u00e9-\u00e9lectoral, ni les ambitions politiques aupr\u00e8s du futur pr\u00e9sident Trump de la rappeuse Minaj, mais bien plut\u00f4t que, dans cette valse \u00e0 plusieurs milliers de temps qu&rsquo;est l&rsquo;\u00e9poque, tout tourbillonne, et partout peut se fixer l&rsquo;antiSyst\u00e8me d&rsquo;un instant insaisissable ou d&rsquo;un moment plus lent et plus long. Aucune \u00e9tiquette n&rsquo;est fix\u00e9e, et le d\u00e9sordre grandit sans aucun doute au c&oelig;ur du Syst\u00e8me, \u00e0 voir ce tourbillon.<\/p>\n<\/p>\n<p><p>(Le d\u00e9sordre est quelque chose d&rsquo;inh\u00e9rent \u00e0 l&rsquo;antiSyst\u00e8me, sans qu&rsquo;il y ait mati\u00e8re \u00e0 s&rsquo;en plaindre, puisque l&rsquo;antiSyst\u00e8me est n\u00e9cessairement d\u00e9sordre s&rsquo;attaquant \u00e0 l&rsquo;ordre du Syst\u00e8me ; et par cons\u00e9quent, il n &lsquo;y a rien de plus grave pour le Syst\u00e8me et son ordre, que le d\u00e9sordre, et par cons\u00e9quent le d\u00e9sordre est antiSyst\u00e8me&#8230; Tout cela tourne comme toupies en bataille, comme une valse devenue folle.)<\/p>\n<\/p>\n<p><p>Apr\u00e8s tout, aujourd&rsquo;hui, \u00e0 l&rsquo;instant donn\u00e9 ici et selon les circonstances, l&rsquo;impeccable costum\u00e9-Syst\u00e8me Macron est autant un antiSyst\u00e8me que la volumineuse rappeuse africaine-am\u00e9ricaine Minaj ; alors que, tous deux et entre eux, Macron pro-vaccin et Minaj anti-vaxx, ils s&rsquo;opposent sur un  point aujourd&rsquo;hui politiquement fondamental. C&rsquo;est que, dans cette \u00e9poque folle de ces temps-devenus-fous comme on l&rsquo;a vu quelques lignes plus haut, il appara&icirc;t \u00e9galement que tout et n&rsquo;importe quoi sont politiques, jusqu&rsquo;aux choses les plus d\u00e9risoires en v\u00e9rit\u00e9, et la position d&rsquo;un instant comme celle d&rsquo;un moment peut vous propulser dans l&rsquo;antiSyst\u00e8me alors que tout dans vous fait, ou devrait faire un acharn\u00e9 serviteur du Syst\u00e8me.<\/p>\n<\/p>\n<p><p>Mis en ligne le 19 septembre 2021 \u00e0 18H40<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une \u00e9trange coalition de rencontre &bull; Qui dirait une proposition aussi saugrenue que \u00ab\u00a0Macron et la rappeuse US Nikki Minaj, m\u00eame combat\u00a0\u00bb ? &bull; Alors que ce combat est, pour ce qu&rsquo;il dure, un combat antiSyst\u00e8me puisque, toutes choses consid\u00e9r\u00e9es par ailleurs, il reste que \u00ab\u00a0D.C.-l&rsquo;hyperfolle\u00a0\u00bb et son Empereur-g\u00e2teux sont absolument le Syst\u00e8me&#8230; &bull; Ainsi&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[21057,4646,4787,1235,3356,13117,2711,2617,21194,13141,584,21193,19035,19752],"class_list":["post-79910","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-anti-vaxx","tag-antisysteme","tag-australie","tag-biden","tag-desordre","tag-drian","tag-le","tag-macron","tag-minaj","tag-nikki","tag-otan","tag-rappeuse","tag-sous-marins","tag-vaccin"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79910","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79910"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79910\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79910"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79910"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}