{"id":79938,"date":"2021-10-14T17:39:19","date_gmt":"2021-10-14T17:39:19","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2021\/10\/14\/poutine-danse-avec-le-dollar\/"},"modified":"2021-10-14T17:39:19","modified_gmt":"2021-10-14T17:39:19","slug":"poutine-danse-avec-le-dollar","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2021\/10\/14\/poutine-danse-avec-le-dollar\/","title":{"rendered":"Poutine danse avec le dollar"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Poutine danse avec le dollar<\/h2>\n<\/p>\n<blockquote>\n<p><p>&bull; Le pr\u00e9sident russe donne une interview o&ugrave; il <strong>dit tout le mal qu&rsquo;il pense du comportement am\u00e9ricanistes vis-\u00e0-vis du <\/strong><strong>dollar<\/strong>. &bull; C&rsquo;est moins pour s&rsquo;en plaindre que pour avertir la direction US qui, bien entendu, <strong>ne tient aucun compte ni m\u00eame n&rsquo;\u00e9coute ce genre de propos<\/strong>, assur\u00e9 qu&rsquo;elle est de sa justesse de comportement et de la jalousie et de l&rsquo;incompr\u00e9hension russes. &bull; Cela dit, Poutine dit ceci : <strong>Les USA &laquo; <\/strong><strong><em>scient la branche sur laquelle ils sont assis<\/em><\/strong><em> en sapant la domination du dollar en tant que monnaie de r\u00e9serve mondiale<\/em> &raquo; \u00e0 cause d&rsquo;une politique du court-terme.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Les Russes estiment que les USA suivent une folle politique en mati\u00e8re de dollar, qu&rsquo;ils sont en train de porter des coups terribles au dollar. C&rsquo;est Poutine qui dit cela dans une interview \u00e0 CNBC, en marge d&rsquo;un s\u00e9minaire annuel, \u00ab\u00a0La Semaine Russe de l&rsquo;&Eacute;nergie\u00a0\u00bb. Poutine met en cause la politique US de sanctions, qui conduit et contraint c&rsquo;est selon, les pays \u00ab\u00a0sanctionn\u00e9s\u00a0\u00bb \u00e0 recherche une autre devise d&rsquo;\u00e9change que le dollar.<\/p>\n<\/p>\n<p><p>L\u00e0-dessus, Poutine constate que les USA, en imprimant du dollar comme on imprime des tracts \u00e9lectoraux, gonflent leur dette nationale d\u00e9j\u00e0 stratosph\u00e9rique et activent une inflation chez eux \u00e0 un rythme sans gu\u00e8re de pr\u00e9c\u00e9dent historique ; c&rsquo;est ce qu&rsquo;un humoriste multilingue et cr\u00e9ateur de n\u00e9ologismes a d\u00e9sign\u00e9 comme une politique \u00ab\u00a0histo-risques &#038; p\u00e9rils\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>On laisse <a href=\"https:\/\/www.rt.com\/russia\/537407-putin-cnbc-dollar-inflation\/\">Poutine parler<\/a> :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>\u00ab\u00a0Il me semble que les &Eacute;tats-Unis font une tr\u00e8s grosse erreur en utilisant le dollar comme instrument de sanctions&#8230; en emp\u00eachant le paiement en dollars des produits sanctionn\u00e9s\u00a0\u00bb, a <a href=\"http:\/\/kremlin.ru\/events\/president\/transcripts\/66920\">d\u00e9clar\u00e9 Poutine<\/a> \u00e0 Hadley Gamble de CNBC mercredi, apr\u00e8s un panel au s\u00e9minaire de \u00ab\u00a0La Semaine Russe de l&rsquo;&Eacute;nergie\u00a0\u00bb.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Les pays confront\u00e9s aux sanctions am\u00e9ricaines, comme la Russie, \u00ab\u00a0n&rsquo;ont pas d&rsquo;autre choix, nous sommes simplement oblig\u00e9s de passer \u00e0 des r\u00e8glements dans d&rsquo;autres monnaies\u00a0\u00bb, a-t-il ajout\u00e9. Gamble avait pos\u00e9 une question sur la possibilit\u00e9 d&rsquo;utiliser des crypto-monnaies comme le bitcoin pour vendre du p\u00e9trole et du gaz, id\u00e9e que Poutine accueille favorablement en principe mais pr\u00e9cisant qu&rsquo;il est \u00ab\u00a0encore trop t\u00f4t\u00a0\u00bb en raison de la volatilit\u00e9 des crypto-monnaies.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>La Russie continue \u00e0 utiliser le dollar dans le commerce de l&rsquo;\u00e9nergie, &ndash; pour l&rsquo;instant &ndash; et n&rsquo;envisage pas de se d\u00e9barrasser compl\u00e8tement du dollar am\u00e9ricain, observe Poutine. Mais \u00ab\u00a0si la politique des autorit\u00e9s am\u00e9ricaines se poursuit&#8230; alors nous n&rsquo;aurons rien \u00e0 faire <\/em>[d&rsquo;autre qu&rsquo;abandonner le dollar]<em>. Les &Eacute;tats-Unis vont eux-m\u00eames saper la confiance dans le dollar.\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>M\u00eame les alli\u00e9s des &Eacute;tats-Unis r\u00e9duisent leurs avoirs en dollars et leur d\u00e9pendance \u00e0 l&rsquo;\u00e9gard de la monnaie am\u00e9ricaine dans leurs \u00e9changes commerciaux, a soulign\u00e9 le dirigeant russe. Non seulement parce que le dollar a \u00e9t\u00e9 transform\u00e9 en une arme \u00e0 cause des sanctions, mais aussi parce que Washington d\u00e9value la monnaie chez lui, en imprimant de l&rsquo;argent et en augmentant la dette nationale.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0Pour la premi\u00e8re fois, probablement dans leur histoire, l&rsquo;inflation aux &Eacute;tats-Unis augmente \u00e0 un rythme que l&rsquo;on n&rsquo;a plus connu depuis depuis aussi longtemps\u00a0\u00bb, a d\u00e9clar\u00e9 Poutine \u00e0 CNBC.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0Tout le monde se pose maintenant la question : et apr\u00e8s ? Que vont faire les autorit\u00e9s \u00e9conomiques am\u00e9ricaines de cette dette colossale ? Que vont-elles faire, effectuer des manipulations avec le dollar, faire baisser sa valeur ?\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Les &Eacute;tats-Unis sont en train de \u00ab\u00a0scier la branche sur laquelle ils sont assis\u00a0\u00bb, a d\u00e9clar\u00e9 Poutine, \u00ab\u00a0en sapant la domination du dollar en tant que monnaie de r\u00e9serve mondiale pour obtenir des avantages politiques \u00e0 court terme dans leur pays, mais en nuisant \u00e0 leurs int\u00e9r\u00eats \u00e9conomiques strat\u00e9giques\u00a0\u00bb \u00e0 long terme<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Cela fait si longtemps que l&rsquo;on parle du dollar&#8230; Pour la s\u00e9quence actuelle et en remontant \u00e0 l&rsquo;imm\u00e9diat apr\u00e8s-crise, apr\u00e8s cette crise des <em>subprimes <\/em>de l&rsquo;automne 2008, on doit se rappeler que les rumeurs allaient bon train (<a href=\"https:\/\/www.dedefensa.org\/article\/dollar-sur-la-table-et-nerfs-a-vif\">en mars 2009<\/a>) concernant des croisades de liquidation du dollars. Alors, le Br\u00e9silien Lula poussait au feu, recevant Gordon Brown dans l&rsquo;avant-premi\u00e8re d&rsquo;un G20 incandescent, et disant qu&rsquo;il maudissait la crise, les banquiers \u00ab\u00a0blancs aux yeux bleus\u00a0\u00bb et le dollar :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>C&rsquo;est une crise qui a \u00e9t\u00e9 caus\u00e9e par des gens, des blancs aux yeux bleus. Et avant la crise, ils avaient l&rsquo;air de tout savoir sur l&rsquo;\u00e9conomie. Une fois de plus, une grande partie des pauvres dans le monde qui n&rsquo;avaient pas encore <\/em>[obtenu]<em> leur part du d\u00e9veloppement fourni par la globalisation, ont \u00e9t\u00e9 les premiers \u00e0 en souffrir. Comme je ne connais pas de banquiers noirs, sans doute devrais-je croire que cette partie de l&rsquo;humanit\u00e9, qui est la principale victime de la crise mondiale, devrait payer pour la crise ? Je ne peux pas accepter cela.<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>C&rsquo;\u00e9tait une \u00e9poque o&ugrave; l&rsquo;on pouvait encore juger avec ironie cette r\u00e9f\u00e9rence \u00e0 la \u00ab\u00a0race\u00a0\u00bb comme une transgression : &laquo; <em>D&rsquo;abord, grandes seront la surprise et l&rsquo;indignation des salons et talk-shows, parisiens et germanopratins, devant la suggestion \u00e0 peine d\u00e9guis\u00e9e qu&rsquo;il existe bien des \u00ab\u00a0races\u00a0\u00bb<\/em>&#8230; &raquo; On dira donc, songeant au wokenisme, que les temps ont bien chang\u00e9. Par contre, le dollar, lui, est toujours l\u00e0, t\u00e9moignant moins de la puissance des &Eacute;tats-Unis que de l&rsquo;impuissance des autres \u00e0 se regrouper et \u00e0 obtenir, de gr\u00e9 ou de force, des am\u00e9nagements \u00e0 la situation. Le fait est plut\u00f4t que la situation crisique pressante da l&rsquo;imm\u00e9diat apr\u00e8s-2008 a morph\u00e9 en une longue croisi\u00e8re au cours de laquelle toutes les crises se sont aggrav\u00e9es sans qu&rsquo;aucune ne soit r\u00e9solue. Washington D.C. n&rsquo;entendra certainement rien des remarques de Poutine, tout occup\u00e9 \u00e0 attiser et \u00e0 radicaliser sa crise int\u00e9rieure, tout en poursuivant sa production de billets verts.<\/p>\n<\/p>\n<p><p>Le sort du dollar est une mesure exacte, non pas de la r\u00e9silience de la puissance des USA mais bien plut\u00f4t de la paralysie des relations internationales (\u00e9conomiques, juridiques, etc.) mises en coupe r\u00e9gl\u00e9e par ces m\u00eames USA, et les emprisonnant eux-m\u00eames et comme le reste dans la poursuite de positions que les uns et les autres ne peuvent plus tenir. L&rsquo;inertie des USA, aussi bien que l&rsquo;impuissance \u00e0 une entente commune et \u00e0 une \u00ab\u00a0d\u00e9salliance\u00a0\u00bb des USA, ont concouru au maintien de cette situation. Pendant cette p\u00e9riode, la substance m\u00eame de la puissance des USA s&rsquo;est consid\u00e9rablement \u00e9rod\u00e9e, pour parvenir aux catastrophes de la politique int\u00e9rieure (fracture du pays, wokenisme) et de la politique ext\u00e9rieure, et ainsi la puissance du dollar devient-elle un simulacre enrobant un fant\u00f4me occup\u00e9 \u00e0 se d\u00e9chirer lui-m\u00eame.<\/p>\n<\/p>\n<p><p>La situation actuelle (celle des USA et, par cons\u00e9quent, des autres), o&ugrave; le dollar tient bien entendu la premi\u00e8re place, est parfaitement caract\u00e9ris\u00e9e par ce commentaire d&rsquo;Alastair Crooke, concernant une situation g\u00e9n\u00e9rale compos\u00e9e \u00e9videmment de nombre de crises irr\u00e9solues et insolubles s&#8217;empilant les unes sur les autres. Crooke emprunte \u00e0 l&rsquo;analyste Paul McCulley le concept de \u00ab\u00a0stabilit\u00e9 du d\u00e9s\u00e9quilibre\u00a0\u00bb&#8230; Selon notre point de vue, ce concept fonctionne selon une dynamique de \u00ab\u00a0stabilit\u00e9 dans le d\u00e9s\u00e9quilibre\u00a0\u00bb jusqu&rsquo;\u00e0 ce que le d\u00e9s\u00e9quilibre l&#8217;emporte par l&rsquo;une ou l&rsquo;autre crise \u00e9chappant \u00e0 cette \u00ab\u00a0stabilit\u00e9\u00a0\u00bb ;  entra&icirc;nant alors le tout dans une sorte d&rsquo;\u00e9trange ph\u00e9nom\u00e8ne de ce \u00ab\u00a0d\u00e9s\u00e9quilibre stable\u00a0\u00bb perdant sa stabilit\u00e9 et redevenant lui-m\u00eame, pur d\u00e9s\u00e9quilibre. Le ph\u00e9nom\u00e8ne agit alors avec une force d\u00e9cupl\u00e9e qui s&rsquo;est constitu\u00e9e dans cette contrainte de stabilit\u00e9 et, lib\u00e9r\u00e9e, se d\u00e9tendant brutalement, comme un ressort. Dans cet ensemble, le dollar tient une place particuli\u00e8re dans la mesure o&ugrave; il est soumis, du fait m\u00eame des USA, \u00e0 deux tensions (l&rsquo;ext\u00e9rieur avec les sanctions et l&rsquo;int\u00e9rieur surtout, avec la dette et l&rsquo;inflation).<\/p>\n<\/p>\n<p><p>Crooke <a href=\"https:\/\/www.strategic-culture.org\/news\/2021\/09\/13\/pandemic-authoritarianism-as-red-grains-cascade\/\">\u00e9crit<\/a> :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>En fin de compte, il n&rsquo;y a rien de plus qu&rsquo;un seul fil conducteur commun \u00e0 tous ces foyers d&rsquo;instabilit\u00e9 : il s&rsquo;agit de la tentative d&rsquo;imposer une gestion technique id\u00e9alis\u00e9e \u00e0 une r\u00e9alit\u00e9 complexe et critique, plut\u00f4t que de rechercher de v\u00e9ritables solutions aux probl\u00e8mes, &ndash; et du recours \u00e0 la psychologie du contr\u00f4le comportemental pour dissimuler la pourriture sous-jacente et forcer \u00e0 la conformit\u00e9.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Nous nous trouvons donc aujourd&rsquo;hui dans un \u00e9tat critique de ce que Paul McCulley appelle une \u00ab\u00a0<a href=\"https:\/\/www.mauldineconomics.com\/frontlinethoughts\/ubiquity-complexity-and-sandpiles\">stabilit\u00e9 du d\u00e9s\u00e9quilibre<\/a>\u00ab\u00a0, o&ugrave; tous les acteurs s&rsquo;efforcent de maximiser leurs r\u00e9sultats personnels et de r\u00e9duire leur exposition aux risques d\u00e9cha&icirc;nant l&rsquo;instabilit\u00e9.  Mais plus le jeu se prolonge, dit Paul McCulley, plus il risque de se terminer par un violent d\u00e9ferlement, car les risques de l&rsquo;instabilit\u00e9 ont plus de temps pour se renforcer dans leurs effets et l&rsquo;\u00e9tat de stabilit\u00e9 du d\u00e9s\u00e9quilibre devient de plus en plus critique.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Quel risque se d\u00e9cha&icirc;nera en se transmutant en instabilit\u00e9 en premier ? Encore une fois, il s&rsquo;agit d&rsquo;impr\u00e9visibilit\u00e9 : tout risque rencontrant son point de fusion peut,  par une dynamique de type dominos, provoquer <\/em>[comme dans un incendie de for\u00eat]<em> un encha&icirc;nement catastrophique pr\u00e9cipitant et transmutant les risques voisins dans la m\u00eame instabilit\u00e9<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Il nous semble que la Russie consid\u00e8re ce ph\u00e9nom\u00e8ne comme de plus en plus plausible \u00e0 partir de la question (de la crise) du dollar, et qu&rsquo;elle appr\u00e9hende surtout l&rsquo;\u00e9volution de la politique int\u00e9rieure US. C&rsquo;est un domaine o&ugrave; elle n&rsquo;a strictement aucun moyen d&rsquo;action et aucune influence, non pas \u00e0 cause du rapport de force mais plus simplement \u00e0 cause de la condition d&rsquo;autisme qui les s\u00e9pare. Pour eux, pour les Russes, les USA constituent un fantastique carrefour de d\u00e9s\u00e9quilibre et ils ne parviennent pas \u00e0 leur faire entendre raison, de leur point de vue, dans une aventure o&ugrave; tout le monde a \u00e0 perdre, mais les USA plus que tout autre certes.<\/p>\n<\/p>\n<p><p>Par exemple, cette <a href=\"https:\/\/www.rt.com\/russia\/537272-ryabkov-relations-russia-us-worsen\/\">sorte de commentaire<\/a> (lundi, apr\u00e8s un entretien des Russes avec une d\u00e9l\u00e9gation US \u00e0 Moscou) a tout \u00e0 voir avec cette situation de communication entre les deux pays, et particuli\u00e8rement pour les risques pris par les USA concernant le dollar (m\u00eame si on a rapidement recouvert d&rsquo;un <a href=\"https:\/\/www.rt.com\/russia\/537440-relations-between-washington-moscow\/\">baume d&rsquo;optimisme<\/a> bon pour les deux parties, la communication des suites de la rencontre) :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>\u00ab\u00a0Les Am\u00e9ricains ne nous \u00e9coutent pas\u00a0\u00bb&#8230;<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Bien que<\/em> [l&rsquo;adjointe au secr\u00e9taire d&rsquo;&Eacute;tat pour les affaires europ\u00e9ennes Victoria] <em>Nuland se soit d\u00e9clar\u00e9e \u00ab\u00a0heureuse d&rsquo;\u00eatre de retour en Russie pour s&rsquo;occuper des relations bilat\u00e9rales\u00a0\u00bb,<\/em> [le vice-ministre des affaires \u00e9trang\u00e8res russes] <em>Riabkov a d\u00e9clar\u00e9 qu&rsquo;il y avait de fortes chances que l&rsquo;\u00e9tat des choses ne fasse qu&#8217;empirer en cons\u00e9quence de ces entretiens.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0Je ne peux pas dire que nous ayons fait de grands progr\u00e8s. Les questions des visas, des conditions de fonctionnement des missions diplomatiques, de la rotation du personnel diplomatique, de la normalisation g\u00e9n\u00e9rale des activit\u00e9s des missions \u00e9trang\u00e8res russes aux &Eacute;tats-Unis et des &Eacute;tats-Unis en Russie conservent un potentiel de crise important, et il n&rsquo;est pas exclu que de nouvelles exacerbations soient possibles dans ces domaines\u00a0\u00bb, a-t-il d\u00e9clar\u00e9.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0Les positions des parties ne s&rsquo;accordent pas bien. Les Am\u00e9ricains n&rsquo;\u00e9coutent pas notre logique et nos demandes&#8230;\u00a0\u00bb<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Washington D.C. n&rsquo;\u00e9coute pas les Russes ? Il y a huit jours, quatre s\u00e9nateurs du Congr\u00e8s des &Eacute;tats-Unis ont demand\u00e9 \u00e0 Biden qu&rsquo;il prenne des mesures imm\u00e9diates contre les Russes dans la querelle des ambassades, en expulsant au moins <a href=\"https:\/\/www.rt.com\/russia\/536725-us-senators-boot-russian-diplomats\/\">300 diplomates russes<\/a>. Les Russes oint \u00e0 nouveau compt\u00e9 sur leurs doigts et reconnu piteusement : \u00ab\u00a0Nous n&rsquo;avons pas 300 diplomates \u00e0 l&rsquo;ambassade de Russie \u00e0 Washington\u00a0\u00bb. Par cons\u00e9quent, il n&rsquo;y aura pas 300 diplomates expuls\u00e9s et les Russes pourront dire que les relations avec les USA s&rsquo;am\u00e9liorent .<\/p>\n<\/p>\n<p><p>Mis en ligne le 14 octobre 2021 \u00e0 17H40<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Poutine danse avec le dollar &bull; Le pr\u00e9sident russe donne une interview o&ugrave; il dit tout le mal qu&rsquo;il pense du comportement am\u00e9ricanistes vis-\u00e0-vis du dollar. &bull; C&rsquo;est moins pour s&rsquo;en plaindre que pour avertir la direction US qui, bien entendu, ne tient aucun compte ni m\u00eame n&rsquo;\u00e9coute ce genre de propos, assur\u00e9 qu&rsquo;elle est&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[21237,2665,8383,8064,5252,6588,2711,21238,2707,5520,8400],"class_list":["post-79938","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-alastairt","tag-crooke","tag-dans","tag-desequilibre","tag-dette","tag-inflation","tag-le","tag-mcculley","tag-moscou","tag-nuland","tag-stabilite"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79938"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79938\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79938"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79938"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}