{"id":79961,"date":"2021-11-05T19:09:30","date_gmt":"2021-11-05T19:09:30","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2021\/11\/05\/le-watergate-de-russiagate\/"},"modified":"2021-11-05T19:09:30","modified_gmt":"2021-11-05T19:09:30","slug":"le-watergate-de-russiagate","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2021\/11\/05\/le-watergate-de-russiagate\/","title":{"rendered":"Le \u2018<em>Watergate<\/em>&lsquo; de \u2018<em>Russiagate<\/em>&lsquo;\u00a0?"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Le &lsquo;<em>Watergate<\/em>&lsquo; de &lsquo;<em>Russiagate<\/em>&lsquo; ?<\/h2>\n<\/p>\n<p><p>5 novembre 2021 &ndash; On sait l&rsquo;estime o&ugrave;, selon mon jugement, l&rsquo;on doit tenir Jonathan Turley, le premier constitutionnaliste aux USA, dans cette mati\u00e8re labyrinthique et incertaine qu&rsquo;est l&rsquo;interpr\u00e9tation et l&rsquo;application de la sacro-sainte Constitution aux Etats-Unis. Lorsque Turley \u00e9crit d&rsquo;une affaire, d&rsquo;un acte, d&rsquo;un fait, qu&rsquo;il est d&rsquo;un caract\u00e8re &laquo; <em>sismique<\/em> &raquo;, \u00e0 l&rsquo;image d&rsquo;un tremblement de terre, on peut \u00eatre s&ucirc;r que nous nous trouvons devant la possibilit\u00e9, sinon la probabilit\u00e9 d&rsquo;un \u00e9v\u00e9nement d&rsquo;importance. <a href=\"https:\/\/jonathanturley.org\/2021\/11\/04\/igor-danchenko-arrested-as-part-of-durham-investigation\/\">Dont acte<\/a>&#8230;<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Le bureau du conseiller sp\u00e9cial John Durham a confirm\u00e9 l&rsquo;arrestation d&rsquo;Igor Danchenko, <a href=\"https:\/\/www.foxnews.com\/politics\/fbi-arrests-steele-dossier-sub-source-durham-investigation\">une source clef<\/a> de l&rsquo;ex-espion britannique Christopher Steele. Il s&rsquo;agit de la troisi\u00e8me arrestation de Durham, qui se dirige vers la phase d&rsquo;accusation de son enqu\u00eate sur les origines du scandale de la collusion russe <\/em>[dans l&rsquo;\u00e9lection de Donald Trump]<em>. Durham est d\u00e9crit comme \u00e9tant soit douloureusement m\u00e9thodique, soit positivement glacial en tant que procureur. Mais il est largement reconnu pour \u00eatre un procureur acharn\u00e9 et absolument apolitique. L&rsquo;arrestation de Danchenko est un d\u00e9veloppement sismique et confirme que Durham est loin d&rsquo;avoir termin\u00e9 son enqu\u00eate<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Comme le note Turley, Durham prend son temps et agit avec discr\u00e9tion, pour vous sortir des coups fumants. Amateur de base-ball, Turley <a href=\"https:\/\/jonathanturley.org\/2021\/08\/16\/beware-the-eephus-washington-on-edge-as-durham-prepares-possible-indictments-and-report\/\">parle de lui<\/a> en citant le &laquo; <em><a href=\"https:\/\/duckduckgo.com\/?q=eephus+pitch&#038;t=osx&#038;ia=web\">Eephus pitch<\/a><\/em> &raquo;, terme de base-ball que je ne me risquerais pas \u00e0 traduire, mais qui renvoie (!), aux frappes coup\u00e9es, slic\u00e9es, lift\u00e9es, amorties du tennis et du volley ball, etc., voire au \u00ab\u00a0service flottant\u00a0\u00bb du volley (pratiqu\u00e9 \u00e0 mon \u00e9poque, &ndash; je ne sais si le terme existe encore, &ndash; une frappe redoutable, qui vous donne une balle \u00e0 la trajectoire lat\u00e9ralement courbe, erratique et d&rsquo;apparence faussement lente dans sa progression, un peu comme une feuille dans le vent, mais tournant sur elle-m\u00eame tr\u00e8s rapidement, tr\u00e8s difficile \u00e0 appr\u00e9cier pour une r\u00e9ception sans faute).<\/p>\n<\/p>\n<p><p>Pour faire bref, on croyait le procureur sp\u00e9cial sur le &lsquo;<em>Russiagate<\/em>&lsquo; Durham endormi, en tranquille <em>burnout<\/em>, \u00e0 la retraite par procuration, mais il r\u00e9appara&icirc;t soudain \u00e0 <a href=\"https:\/\/jonathanturley.org\/2021\/08\/16\/beware-the-eephus-washington-on-edge-as-durham-prepares-possible-indictments-and-report\/\">la mi-ao&ucirc;t<\/a>, comme un \u00ab\u00a0<em>Eephus<\/em>\u00ab\u00a0, une balle \u00ab\u00a0flottante\u00a0\u00bb qui vous pr\u00e9sente une trajectoire compl\u00e8tement inattendue, voire incongrue. Aujourd&rsquo;hui, il vient avec du lourd, du tr\u00e8s-tr\u00e8s lourd, du quelque chose qui peut mettre compl\u00e8tement \u00e0 nu le \u00ab\u00a0<a href=\"https:\/\/www.dedefensa.org\/article\/russiagate-simulacre-extreme\">simulacre supr\u00eame<\/a>\u00a0\u00bb que fut le &lsquo;<em>Russiagate<\/em>&lsquo;, qui faisait de Trump une marionnette de Poutine.<\/p>\n<\/p>\n<p><p>Pour vous donner une id\u00e9e du man\u00e8ge, d\u00e9crit un peu partout comme chez &lsquo;<em><a href=\"https:\/\/redstate.com\/streiff\/2021\/11\/04\/the-danchenko-indictment-shows-the-fbi-knew-the-steele-dossier-was-a-lie-and-probably-russian-influenced-since-2017-n469826\">RedState.com<\/a><\/em>&lsquo;, juste ce passage de <a href=\"https:\/\/www.rt.com\/op-ed\/539391-danchenko-indictment-steele-russiagate\/\">Nebojsa Malic<\/a>, dans RT.Com :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; &#8230;<em>Une autre accusation est li\u00e9e \u00e0 un cadre anonyme d&rsquo;une soci\u00e9t\u00e9 de relations publiques proche des d\u00e9mocrates. Bien qu&rsquo;il ne soit mentionn\u00e9 que comme \u00ab\u00a0PR-Executive-1\u00a0\u00bb, les journalistes d&rsquo;investigation ont \u00e9tabli une correspondance avec Charles H. Dolan de Ketchum Public Relations.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>L&rsquo;un d&rsquo;entre eux est arriv\u00e9 \u00e0 cette conclusion en recoupant la d\u00e9position d&rsquo;Olga Galkina, une amie d&rsquo;\u00e9cole de Danchenko qui a \u00e9t\u00e9 identifi\u00e9e comme l&rsquo;une de ses sources de seconde main l&rsquo;ann\u00e9e derni\u00e8re. <\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Plus tard dans la journ\u00e9e, un avocat repr\u00e9sentant Dolan a confirm\u00e9 qu&rsquo;il \u00e9tait bien \u00ab\u00a0PR-Executive-1\u00a0\u00bb. Son implication met en place une cha&icirc;ne de dominos dans le \u00ab\u00a0Russiagate\u00a0\u00bb : Les d\u00e9mocrates ont transmis<\/em> [via Dolan] <em>des informations<\/em> [infos-bidons, dites <em>FakeNews<\/em>]<em> \u00e0 Danchenko, qui les a transmises \u00e0 Steele, qui les a vendues \u00e0 Fusion GPS <\/em>[entreprise connect\u00e9e aux Clinton]<em>, qui les a divulgu\u00e9es aux m\u00e9dias <\/em>[de la presseSyst\u00e8me]<em>, qui ont \u00e0 leur tour accus\u00e9 Trump de \u00ab\u00a0collusion\u00a0\u00bb avec le Kremlin.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>L&rsquo;acte d&rsquo;accusation confirme \u00e9galement la <a href=\"https:\/\/www.rt.com\/usa\/501631-steele-dossier-subsource-investigation-fbi\/\">r\u00e9v\u00e9lation de 2020<\/a> selon laquelle le FBI \u00e9tait au courant des fausses d\u00e9clarations de Danchenko au d\u00e9but de 2017, mais a continu\u00e9 \u00e0 utiliser le dossier Steele comme motif d&rsquo;espionnage de la pr\u00e9sidence Trump. Le dossier a servi de base au mandat FISA initial pour espionner la campagne Trump via <\/em>[l&rsquo;espionnage de son] <em>ancien assistant Carter Page, \u00e0 partir de l&rsquo;\u00e9lection de 2016 et apr\u00e8s la prestation de serment de Trump<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Pourquoi parlerais-je d&rsquo;un \u00ab\u00a0<em>Watergate<\/em>\u00a0\u00bb de &lsquo;<em>Russiagate<\/em>&lsquo; ? (*) Selon au moins deux \u00e9l\u00e9ments :<\/p>\n<p>&bull; parce qu&rsquo;avec l&rsquo;inculpation de Danchenko, on arrive au c&oelig;ur du \u00ab\u00a0complot\u00a0\u00bb (pardonnez ce terme pour une affaire impliquant les d\u00e9mocrates et Hillary) dit &lsquo;<em>Russiagate<\/em>&lsquo;, pour impliquer Trump dans un \u00ab\u00a0complot\u00a0\u00bb (cette fois, le mot convient !) russe, de Poutine lui-m\u00eame, pour faire perdre <em>The-Donald <\/em>(rat\u00e9) et lui pourrir sa pr\u00e9sidence jusqu&rsquo;au bout (r\u00e9ussi) ;<\/p>\n<p>&bull; parce que Durham est un dur de dur, un inflexible-incorruptible, qui ne l\u00e2che jamais sa proie lorsqu&rsquo;il la tient entre ses m\u00e2choires ; il devrait donc aller jusqu&rsquo;au bout sur la piste fra&icirc;che de l&rsquo;imposture, notamment gr\u00e2ce aux pouvoirs extraordinaires donn\u00e9s \u00e0 un  procureur sp\u00e9cial.<\/p>\n<\/p>\n<p><p>Cet extraordinaire montage que fut le &lsquo;<em>Russiagate<\/em>&lsquo;, extraordinaire <a href=\"https:\/\/www.dedefensa.org\/article\/debkafiles-defend-les-russes-contre-clinton\">parce qu&rsquo;aussit\u00f4t<\/a> gros comme une maison et en plus d&rsquo;une stupidit\u00e9 sans bornes, comme l&rsquo;est le document Steele lui-m\u00eame qui est son document essentiel, a une tr\u00e8s grande importance. Par la m\u00e9thode du mensonge le plus grossier, de la campagne syst\u00e9matique, ou disons syst\u00e9mique puisqu&rsquo;ils s&rsquo;alignent dans la presseSyst\u00e8me comme dans un syst\u00e8me, il est \u00e0 la base et il est fondateur des accusations d&rsquo;ing\u00e9rence lanc\u00e9es contre les Russes depuis. La plus petite \u00e9lection, m\u00eame partielle, m\u00eame \u00e0 Trifouillis-les-Oies, est honor\u00e9e d&rsquo;une suggestion d&rsquo;une ing\u00e9rence de Poutine lui-m\u00eame, \u00ab\u00a0aux manettes\u00a0\u00bb. Plus c&rsquo;est gros a-t-on conclu, mieux \u00e7a passe.<\/p>\n<\/p>\n<p><p>Lre r\u00f4le d\u00e9volu \u00e0 Poutine et \u00e0 la Russie a son histoire. Jusqu&rsquo;\u00e0 Trump et au &lsquo;<em>Russiagate<\/em>&lsquo;, on pouvait taper sur Poutine dans le cadre de l&rsquo;expansion militaristo-imp\u00e9rialiste russe qui, comme on le sait bien, ravage le monde depuis des d\u00e9cennies. Il avait organis\u00e9 un putsch \u00e0 Kiev, envahi en marche arri\u00e8re le Donbass, menac\u00e9 la G\u00e9orgie (capitale, Atlanta), install\u00e9 ses fronti\u00e8res \u00e0 une proximit\u00e9 inqui\u00e9tante des bases uniquement-d\u00e9fensives de l&rsquo;OTAN, attaqu\u00e9 les djihadistes tentant d&rsquo;organiser leur d\u00e9mocratie, viol\u00e9 la souverainet\u00e9 syrienne combien de fois en installant l&rsquo;imposteur russe Saddam Al Assadov \u00e0 Damas, et tant de choses de la m\u00eame infamie.<\/p>\n<\/p>\n<p><p>Mais le &lsquo;<em>Russiagate<\/em>&lsquo; a soudain chang\u00e9 le territoire du simulacre en le poussant au plus intime. Il a ouvert les portes de l&rsquo;entre-nous et soudain, &ndash; ce fut un miracle, &ndash; voil\u00e0 qu&rsquo;on d\u00e9couvrit un coupable absolument sur mesure pour toutes les avanies, les horribles circonstances, les escroqueries et les affreux soup\u00e7ons que les \u00e9v\u00e9nements de nos vertueuses contr\u00e9es faisaient peser sur nous, c&rsquo;est-\u00e0-dire sur les honn\u00eates \u00e9lites et directions des contr\u00e9es de la civilisation. Imaginez l&rsquo;aubaine : nous avions pris, la main dans le sac, la cause de toutes nos cons\u00e9quences.<\/p>\n<\/p>\n<p><p>Ainsi &lsquo;<em>Russiagate<\/em>&lsquo; ouvra-t-il une nouvelle p\u00e9riode de notre riche vie politique. M\u00eame ces merveilleux Fran\u00e7ais, ces glorieuses phalanges d\u00e9ploy\u00e9es &lsquo;En-Marche&rsquo;, purent nous r\u00e9v\u00e9ler le pot-aux-roses ; que ce soit les frasques de Benalla ou celles de Griveaux, que ce soit les gilets habill\u00e9s de jaune, nous tenions le coupable : Poutine aux manettes !<\/p>\n<\/p>\n<p><p>Ainsi cette affaire de l&rsquo;ent\u00eatement du tr\u00e8s s\u00e9v\u00e8re <em>Special Attorney<\/em> Burnham, le Robespierre de la modernit\u00e9-tardive, le &laquo; <em>douloureusement m\u00e9thodique<\/em> &raquo; et le &laquo; <em>positivement glacial <\/em>&ndash; est-elle une aubaine, &ndash; et dans l&rsquo;autre sens cette fois. Je n&rsquo;avance rien qui ne soit garanti car le Syst\u00e8me sait se d\u00e9fendre, mais j&rsquo;observe que nous sommes sur deux voies qui, par miracle et si miracle il y a, pourraient d\u00e9boucher sur des perspectives exaltantes.<\/p>\n<\/p>\n<p><p>&bull; Aux USA m\u00eame, \u00e0 Washington D.C., \u00e0 \u00ab\u00a0D.C.-l&rsquo;hyperfolle\u00a0\u00bb, son enqu\u00eate peut conduire \u00e0 des mises en cause bouleversantes, qui viendraient se coller sur un pays d\u00e9j\u00e0 plong\u00e9 dans une immense crise pour la porter \u00e0 \u00e9bullition. Hillary Clinton est en bout de piste et en haut de la liste. Bien d&rsquo;autres peuvent d\u00e9j\u00e0 craindre de sentir le vent du boulet, y compris le Saint des Saints, Barack Obama, qui risquerait de conna&icirc;tre une situation d\u00e9licate puisque, comme le rappelle Turley :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>M\u00eame pour ceux d&rsquo;entre nous qui ont suivi et \u00e9crit sur l&rsquo;enqu\u00eate sur la Russie pendant cinq ans, beaucoup de choses ont \u00e9t\u00e9 r\u00e9v\u00e9l\u00e9es l&rsquo;ann\u00e9e derni\u00e8re. Il a \u00e9t\u00e9 r\u00e9v\u00e9l\u00e9 en octobre, par exemple, que <a href=\"https:\/\/jonathanturley.org\/2020\/10\/07\/a-means-of-distracting-the-public-brennan-briefed-obama-on-clinton-plan-to-lie-trump-to-russia\/\">le pr\u00e9sident Obama a \u00e9t\u00e9 inform\u00e9<\/a> par son directeur de la CIA, John Brennan, le 28 juillet 2016, de renseignements sugg\u00e9rant qu&rsquo;Hillary Clinton pr\u00e9voyait de lier le candidat de l&rsquo;\u00e9poque, Donald Trump, \u00e0 la Russie comme \u00ab\u00a0un moyen de distraire le public de son utilisation d&rsquo;un serveur de messagerie priv\u00e9\u00a0\u00bb. La date \u00e9tait significative car l&rsquo;enqu\u00eate sur la Russie a \u00e9t\u00e9 ouverte le 31 juillet 2016, soit trois jours plus tard seulement<\/em>&#8230; &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>&bull; Pour l&rsquo;instant, Trump se tait, attendant son heure si l&rsquo;horloge va dans le bon sens. Imaginez ses cris \u00e9pouvantables si l&rsquo;on arrive \u00e0 la conclusion, \u00e9vidente par ailleurs mais qui porterait alors le sceau magique et insoup\u00e7onnable du procureur Sp\u00e9cial, que le &lsquo;<em>Russiagate<\/em>&lsquo; est bien ce que l&rsquo;on sait, un montage, un simulacre mis en sc\u00e8ne par des r\u00e9seaux de comploteurs au service des plus grandes personnalit\u00e9s d\u00e9mocrates, globalistes et gauchistes de salon ! Nos convictions en seraient fortement \u00e9branl\u00e9es, avec la presseSyst\u00e8me bien oblig\u00e9e d&rsquo;en dire quelques mots. Comment faire appel \u00e0 un bouc-\u00e9missaire si ce bouc-\u00e9missaire se trouve blanchi par les plus hautes instances de la justice am\u00e9ricaniste ? Il faudrait alors imposer \u00e0 notre <em>narrative <\/em>une inflexion \u00e9pouvantable et insupportable. Il faudrait nuancer notre jugement sur Poutine et la Russie, et tout le reste.<\/p>\n<\/p>\n<p><p>Nous sommes gravement menac\u00e9s de voir notre int\u00e9grit\u00e9 battue en br\u00e8che, notre image, notre <em>narrative<\/em>, nos imp\u00e9ratifs jugement sur Poutine. Nous dansons sur un volcan, notre \u00e9quilibre ne tient plus qu&rsquo;au fil de l&rsquo;\u00e9quilibriste survolant l&rsquo;\u00e9tat critique qu&rsquo;il voudrait sans fin d&rsquo;&laquo; <em>une \u00ab\u00a0<a href=\"https:\/\/www.mauldineconomics.com\/frontlinethoughts\/ubiquity-complexity-and-sandpiles\">stabilit\u00e9 du d\u00e9s\u00e9quilibre<\/a>\u00ab\u00a0, o&ugrave; tous les acteurs s&rsquo;efforcent de maximiser leurs r\u00e9sultats personnels et de r\u00e9duire leur exposition aux risques d\u00e9cha&icirc;nant l&rsquo;instabilit\u00e9<\/em> &raquo;&#8230; Car la culpabilit\u00e9 affirm\u00e9e sans fin de Poutine et commenc\u00e9e avec le &lsquo;<em>Russiagate<\/em>&lsquo;, est certainement le pilier central, la poutre-ma&icirc;tresse de notre \u00ab\u00a0stabilit\u00e9 dans l&rsquo;instabilit\u00e9\u00a0\u00bb. Si le pilier c\u00e8de&#8230;<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le &lsquo;Watergate&lsquo; de &lsquo;Russiagate&lsquo; ? 5 novembre 2021 &ndash; On sait l&rsquo;estime o&ugrave;, selon mon jugement, l&rsquo;on doit tenir Jonathan Turley, le premier constitutionnaliste aux USA, dans cette mati\u00e8re labyrinthique et incertaine qu&rsquo;est l&rsquo;interpr\u00e9tation et l&rsquo;application de la sacro-sainte Constitution aux Etats-Unis. Lorsque Turley \u00e9crit d&rsquo;une affaire, d&rsquo;un acte, d&rsquo;un fait, qu&rsquo;il est d&rsquo;un caract\u00e8re&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[934,21265,20072,3278,916,11261,3344,2639,2948],"class_list":["post-79961","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-clinton","tag-danchenko","tag-durham","tag-hillary","tag-poutine","tag-procureur","tag-special","tag-trump","tag-turley"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79961","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79961"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79961\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79961"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79961"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79961"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}