{"id":79972,"date":"2021-11-16T13:45:38","date_gmt":"2021-11-16T13:45:38","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2021\/11\/16\/noosphere-vi-mythologies-trinitaires\/"},"modified":"2021-11-16T13:45:38","modified_gmt":"2021-11-16T13:45:38","slug":"noosphere-vi-mythologies-trinitaires","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2021\/11\/16\/noosphere-vi-mythologies-trinitaires\/","title":{"rendered":"Noosph\u00e8re, VI : Mythologies trinitaires"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Noosph\u00e8re, VI : Mythologies trinitaires<\/h2>\n<\/p>\n<p><p>Il n&rsquo;y a qu&rsquo;une seule mythologie trinitaire qui m\u00e9rite d&rsquo;\u00eatre discut\u00e9e, et c&rsquo;est le christianisme. Le Dieu chr\u00e9tien est la Sainte Trinit\u00e9, compos\u00e9e du P\u00e8re (le vieux Dieu h\u00e9breu), du Fils (J\u00e9sus-Christ) et du Saint-Esprit. Dieu le P\u00e8re est arriv\u00e9 par l&rsquo;interm\u00e9diaire des textes sacr\u00e9s juifs, qui se sont trouv\u00e9s \u00eatre \u00e0 vendre juste au moment o&ugrave; le christianisme a commenc\u00e9 \u00e0 se d\u00e9velopper, les Juifs venant de perdre une sale guerre contre les Romains, qui les ont ensuite d\u00e9log\u00e9s (encore une fois) de Palestine. Avant d&rsquo;acheter en gros les textes sacr\u00e9s juifs, les chr\u00e9tiens \u00e9taient consid\u00e9r\u00e9s par d&rsquo;autres sectes, plus instruites, comme &laquo;<em> un peuple sans livre <\/em>&raquo;.<\/p>\n<\/p>\n<p><p>L&rsquo;incorporation des textes sacr\u00e9s juifs dans la secte chr\u00e9tienne naissante \u00e9tait en quelque sorte une b\u00e9n\u00e9diction mitig\u00e9e, car ces textes sont cribl\u00e9s de contradictions internes. Prenons, par exemple, l&rsquo;exemple assez simple du meurtre. L&rsquo;Exode 20:13 est tr\u00e8s clair sur ce point : &laquo;<em> Tu ne commettras pas de meurtre <\/em>&raquo;. Cela concorde assez bien avec les enseignements du Christ, qui vont tout \u00e0 fait dans le sens oppos\u00e9 au meurtre : &laquo;<em> Aimez vos ennemis, faites du bien \u00e0 ceux qui vous ha\u00efssent, b\u00e9nissez ceux qui vous maudissent, priez pour ceux qui vous maltraitent. <\/em>&raquo; [Luc 6:27-28] La justification d&rsquo;une telle indulgence est que pour punir il faut d&rsquo;abord juger et que juger est une pr\u00e9rogative de Dieu que les chr\u00e9tiens ne doivent pas usurper : &laquo;<em> Ne jugez pas, afin que vous ne soyez pas jug\u00e9s. <\/em>&raquo; [Matthieu 7:1]<\/p>\n<\/p>\n<p><p>Vous pourriez vous exclamer : \u00ab\u00a0Ce n&rsquo;est pas une fa\u00e7on de g\u00e9rer un bordel digne de ce nom\u00a0\u00bb, et vous auriez raison, bien s&ucirc;r. Et c&rsquo;est ici que l&rsquo;Ancien Testament a \u00e9t\u00e9 tr\u00e8s utile pour subvertir l&rsquo;enseignement chr\u00e9tien originel et le faire servir aux besoins non seulement des tenanciers de bordels mais aussi des empereurs sanguinaires, des maniaques de l&rsquo;homicide et des oligarques rapaces. Dans l&rsquo;Exode, qui nous exhorte \u00e0 ne pas tuer, il est dit ceci : &laquo;<em> Quiconque couchera avec un animal sera mis \u00e0 mort <\/em>&raquo;. [Exode 22:19] Zoophiles, prenez garde ! L&rsquo;adult\u00e8re est \u00e9galement un crime capital : &laquo;<em> Si un homme commet un adult\u00e8re avec la femme de son prochain, l&rsquo;adult\u00e8re et la femme adult\u00e8re seront mis \u00e0 mort.<\/em> &raquo; [L\u00e9vitique 20:10] Tout comme l&rsquo;homosexualit\u00e9  : &laquo;<em> Si un homme couche avec un m\u00e2le comme avec une femme, tous deux ont commis une abomination ; ils seront mis \u00e0 mort <\/em>&raquo; [L\u00e9vitique 20:13].<\/p>\n<\/p>\n<p><p>J\u00e9sus (selon l&rsquo;interpr\u00e9tation des auteurs de l&rsquo;&Eacute;vangile, quels qu&rsquo;ils soient) a pris soin de ne pas se pr\u00e9senter comme une sorte de dissident de cette orthodoxie de l&rsquo;Ancien Testament :  &laquo; <em>Ne croyez pas que je sois venu abolir la Loi ou les Proph\u00e8tes ; je ne suis pas venu les abolir, mais les accomplir.<\/em> &raquo; [Matthieu 5:17] Sans doute, ce brin de conformisme avait-il beaucoup \u00e0 voir avec le terrain min\u00e9 suivant contenu dans le Deut\u00e9ronome 13 &laquo;<em> Si un proph\u00e8te&hellip; appara&icirc;t au milieu de vous et vous annonce un signe ou un prodige, et&hellip; dit : \u00ab\u00a0Suivons d&rsquo;autres dieux\u00a0\u00bb&hellip;. \u00ab\u00a0et adorons-les\u00a0\u00bb, vous ne devez pas \u00e9couter les paroles de ce proph\u00e8te ou de ce r\u00eaveur&hellip; Ce proph\u00e8te ou ce r\u00eaveur doit \u00eatre mis \u00e0 mort pour avoir incit\u00e9 \u00e0 la r\u00e9bellion contre le Seigneur ton Dieu&hellip; Vous devez purger le mal au milieu de vous <\/em>&raquo;. Par cons\u00e9quent, comme le prouvent plusieurs fragments de papyrus sur lesquels les paroles du Christ avaient \u00e9t\u00e9 consign\u00e9es, et qui sont ant\u00e9rieurs de plusieurs d\u00e9cennies aux &Eacute;vangiles, J\u00e9sus \u00e9tait plut\u00f4t r\u00e9ticent \u00e0 l&rsquo;id\u00e9e de se faire appeler Dieu. Selon ces fragments, la version originale de &laquo;<em> Rendez \u00e0 C\u00e9sar ce qui est \u00e0 C\u00e9sar, et \u00e0 Dieu ce qui est \u00e0 Dieu <\/em>&raquo; [Marc 12:17] se terminait par &laquo;<em> et \u00e0 moi ce qui est \u00e0 moi <\/em>&raquo;.<\/p>\n<\/p>\n<p><p>Vous voyez, la vieille foi h\u00e9bra\u00efque consiste \u00e0 tuer, \u00e0 tuer, puis \u00e0 tuer encore. Mais tu ne tueras pas, attention ! Les chr\u00e9tiens auraient peut-\u00eatre mieux fait de laisser ces textes sacr\u00e9s h\u00e9breux pourrir dans le foss\u00e9 o&ugrave; les Romains les avaient jet\u00e9s. Il s&rsquo;est av\u00e9r\u00e9 que toute personne sachant lire pouvait trouver une citation justifiant \u00e0 peu pr\u00e8s n&rsquo;importe quelle sorte de meurtre et de mutilation et passer directement \u00e0 l&rsquo;acte, en la faisant pr\u00e9c\u00e9der de \u00ab\u00a0car il est \u00e9crit&hellip;\u00a0\u00bb et en l&rsquo;accompagnant d&rsquo;un certain remuement de doigt bien-pensant. Au cours des si\u00e8cles, beaucoup de sang a coul\u00e9 pour des questions doctrinales apparemment stupides qui semblaient tr\u00e8s importantes \u00e0 l&rsquo;\u00e9poque, et toute l&rsquo;histoire des h\u00e9r\u00e9sies chr\u00e9tiennes et des efforts inlassables d\u00e9ploy\u00e9s pour les fomenter puis les r\u00e9primer constitue une lecture tr\u00e8s \u00e9trange. Aujourd&rsquo;hui encore, des sectes telles que les T\u00e9moins de J\u00e9hovah (interdits dans la F\u00e9d\u00e9ration de Russie, je suis l\u00e9galement tenu de le mentionner) sont \u00e9quip\u00e9es de citations bibliques pour toutes les occasions et les manient de mani\u00e8re experte pour embobiner tous ceux qui leur tombent sous la main.<\/p>\n<\/p>\n<p><p>Et pourtant, \u00e0 partir de mat\u00e9riaux de construction aussi d\u00e9fectueux, les th\u00e9ologiens chr\u00e9tiens ont r\u00e9ussi \u00e0 construire une structure \u00e9tonnamment solide qui a r\u00e9sist\u00e9 \u00e0 l&rsquo;\u00e9preuve du temps. Ils y sont parvenus en utilisant l&rsquo;\u00e9l\u00e9ment structurel le plus solide fourni par la nature : le triangle, alias la Sainte Trinit\u00e9. J\u00e9sus-Christ est le fils de Dieu le P\u00e8re qui a f\u00e9cond\u00e9 la Vierge Marie par l&rsquo;interm\u00e9diaire du Saint-Esprit. J\u00e9sus est donc un Dieu, mais aussi un \u00eatre humain en chair et en os, \u00e0 la fois mortel (il meurt sur la croix) et immortel (il ressuscite d&rsquo;entre les morts trois jours plus tard). Bien que, durant sa vie terrestre, J\u00e9sus se soit qualifi\u00e9 de &laquo;<em> Fils de l&rsquo;homme <\/em>&raquo;, il a clairement obtenu une promotion apr\u00e8s son sacrifice sur la croix : &laquo;<em> &hellip;le Fils de l&rsquo;homme sera assis \u00e0 la droite de la puissance de Dieu <\/em>&raquo;. [Luc 22:69]. J\u00e9sus est un Dieu tout \u00e0 fait inhabituel : la plupart des dieux exigent que vous leur fassiez des sacrifices, alors que J\u00e9sus s&rsquo;est sacrifi\u00e9 (en mourant sur la croix) pour vous, afin que vous puissiez entrer dans le Royaume des Cieux et obtenir la vie \u00e9ternelle. Dieu le P\u00e8re n&rsquo;a pas <em>&laquo; engendr\u00e9 &raquo;<\/em> J\u00e9sus, malgr\u00e9 la malencontreuse traduction anglaise du terme grec monog\u00e8nes par &laquo;<em> seul engendr\u00e9 <\/em>&raquo; [Jean 3:16], alors que le sens correct est &laquo;<em> unique, le seul de son esp\u00e8ce <\/em>&raquo;. Ainsi, le P\u00e8re, le Fils et le Saint-Esprit sont les trois sommets d&rsquo;un triangle et les trois manifestations diff\u00e9rentes d&rsquo;un seul et m\u00eame Dieu singulier.<\/p>\n<\/p>\n<p><p>L&rsquo;Esprit Saint joue un r\u00f4le d\u00e9terminant dans tout cela. C&rsquo;est l&rsquo;Esprit Saint qui a f\u00e9cond\u00e9 la Vierge Marie qui a ensuite donn\u00e9 naissance \u00e0 J\u00e9sus-Christ. Cela permet d&rsquo;\u00e9viter le probl\u00e8me de Dieu le P\u00e8re qui engendre des enfants \u00e0 la mani\u00e8re des pa\u00efens ; si c&rsquo;\u00e9tait le cas, pourquoi n&rsquo;y aurait-il pas de nombreux petits J\u00e9sus courant dans tous les sens avec Dieu le patriarche les regardant d&rsquo;un air approbateur en disant &laquo;<em> Le fruit de mes entrailles <\/em>&raquo; ? Zeus, par exemple, \u00e9tait l&rsquo;heureux p\u00e8re de six enfants : Art\u00e9mis, Apollon, Herm\u00e8s, Ath\u00e9na, Ar\u00e8s et Aphrodite. (Si j&rsquo;\u00e9tais Zeus, je serais tout \u00e0 fait insupportablement fier d&rsquo;une prog\u00e9niture aussi illustre et c\u00e9l\u00e8bre et je montrerais constamment leurs photos aux \u00e9trangers, les r\u00e9galant des r\u00e9cits de leurs exploits). Mais la relation entre Dieu le P\u00e8re et la Vierge Marie est purement spirituelle et indirecte : l&rsquo;incarnation d&rsquo;une partie de la trinit\u00e9 (J\u00e9sus) a \u00e9t\u00e9 m\u00e9diatis\u00e9e par une autre (le Saint-Esprit). Ainsi, la relation p\u00e8re-fils entre deux parties de la Sainte Trinit\u00e9 est strictement m\u00e9taphorique et existe purement au niveau des arch\u00e9types humains plut\u00f4t que comme une question de g\u00e9n\u00e9alogie divine.<\/p>\n<\/p>\n<p><p>Le Saint-Esprit est rarement explor\u00e9 en d\u00e9tail, et c&rsquo;est regrettable, car c&rsquo;est la partie de la Sainte Trinit\u00e9 qui joue le plus grand r\u00f4le dans la vie des chr\u00e9tiens &ndash; \u00e0 travers les sacrements. Il entre dans les enfants (et, chez les anabaptistes, dans les adultes) lors du bapt\u00eame, bannissant les d\u00e9mons qui les ont poss\u00e9d\u00e9s jusque-l\u00e0. Il transforme le pain et le vin en corps et en sang du Christ pour qu&rsquo;ils puissent les consommer pendant la communion : non seulement le Dieu chr\u00e9tien est sacrifi\u00e9 pour nous sauver (au lieu que, comme avec la plupart des divinit\u00e9s, nous lui fassions des sacrifices pour nous attirer les faveurs divines), mais nous pouvons aussi manger notre Dieu, devenant dans une certaine mesure ce que nous mangeons. Ainsi, l&rsquo;Esprit Saint nous offre une exp\u00e9rience directe de l&rsquo;une des trois manifestations de Dieu : un sixi\u00e8me sens pour la pr\u00e9sence du divin.<\/p>\n<\/p>\n<p><p>Il peut s&rsquo;agir, bien s&ucirc;r, de rituels creux d\u00e9pourvus de contenu spirituel, mais si ce n&rsquo;est pas le cas, ils peuvent, chez certaines personnes, se d\u00e9velopper en un sens r\u00e9el qui nous permet de sentir le Saint-Esprit couler en nous et de sentir sa pr\u00e9sence (et, peut-\u00eatre encore plus important, son absence) chez les autres, creusant des canaux pour le flux de l&#8217;empathie. Bien s&ucirc;r, rien de tout cela ne pourra jamais \u00eatre prouv\u00e9 : en vertu d&rsquo;une politique divine stricte, Dieu ne se pr\u00e9sente jamais aux incroyants, sceptiques et autres qui doutent. Quelle que soit leur position, la pr\u00e9sence de l&rsquo;Esprit Saint fait que les personnes atteintes de possession d\u00e9moniaque se d\u00e9forment gravement, et c&rsquo;est toujours amusant \u00e0 regarder, aussi cruel que cela puisse \u00eatre. Quoi qu&rsquo;il en soit, toute action observ\u00e9e du Saint-Esprit peut toujours \u00eatre expliqu\u00e9e \u00e0 l&rsquo;aide d&rsquo;un ensemble standard d&rsquo;explications comprenant l&rsquo;effet placebo, l&rsquo;auto-hypnose, les soucoupes volantes et\/ou le gaz des marais, la raison humaine \u00e9tant une petite pute en chaleur toujours pr\u00eate \u00e0 rendre service.<\/p>\n<\/p>\n<p><p>Le mod\u00e8le 1+1+1=1 peut sembler \u00eatre un peu un <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Rube_Goldberg\">Rube Goldberg<\/a> compar\u00e9 \u00e0 d&rsquo;autres mythologies religieuses plus simples, mais il s&rsquo;est av\u00e9r\u00e9 \u00eatre remarquablement stable. Il faut se rappeler qu&rsquo;il est apparu \u00e0 une \u00e9poque de concurrence extr\u00eame entre les mythologies religieuses. Le nombre de cultes diff\u00e9rents au sein de l&rsquo;Empire romain, la plupart pa\u00efens, certains monoth\u00e9istes, se comptait par centaines, et tout ce que les Romains demandaient \u00e9tait que chacun honore ses dieux. Mais cette structure mythique chr\u00e9tienne d&rsquo;un Dieu unique combinant trois manifestations diff\u00e9rentes qui incluent les arch\u00e9types du p\u00e8re et du fils, un dieu comestible qui vous est sacrifi\u00e9 et un esprit qui vous habite et habite les v\u00f4tres \u00e0 un excellent effet a fait exploser l&rsquo;Empire romain. L&#8217;empire romain occidental a fini par \u00eatre abandonn\u00e9. La vieille Rome s&rsquo;est retrouv\u00e9e coinc\u00e9e dans une boucle du <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Un_jour_sans_fin\">Jour de la marmotte<\/a>, recyclant sans cesse le vieil \u00e9gr\u00e9gore fatigu\u00e9 de l&#8217;empereur romain sous la forme du pape, le Vatican revendiquant l&rsquo;extr\u00eame pr\u00e9tention d&rsquo;\u00eatre le seul bureau de vente de Dieu et le seul concessionnaire autoris\u00e9 de biscuits de communion sur Terre. Pendant ce temps, le nouvel empire chr\u00e9tien s&rsquo;est install\u00e9 \u00e0 Constantinople, la nouvelle Rome des <a href=\"https:\/\/boowiki.info\/art\/byzantins\/romei.html\">Romei<\/a>, o&ugrave; il a poursuivi sa route pendant mille ans, exer\u00e7ant une influence majeure sur une grande partie du reste de l&rsquo;Eurasie.<\/p>\n<\/p>\n<p><p>Ce tr\u00e9pied de spiritualit\u00e9 a r\u00e9sist\u00e9 \u00e0 l&rsquo;\u00e9preuve du temps, bien qu&rsquo;il ait \u00e9t\u00e9 remis en question de temps \u00e0 autre par diverses h\u00e9r\u00e9sies et schismes. L&rsquo;une des principales causes de ces h\u00e9r\u00e9sies \u00e9tait li\u00e9e \u00e0 la double nature paradoxale du Christ : comment quelqu&rsquo;un peut-il \u00eatre simultan\u00e9ment un humain et un dieu ? Certains passages de l&rsquo;&Eacute;vangile ont donn\u00e9 \u00e0 r\u00e9fl\u00e9chir. Par exemple, il y a ceci : &laquo;<em> Il s&rsquo;avan\u00e7a encore un peu, tomba sur sa face et pria ainsi : Mon P\u00e8re, s&rsquo;il est possible, que cette coupe passe loin de moi<\/em>. &raquo; [Matthieu 26:39] Ici, l&rsquo;une des manifestations de Dieu demande \u00e0 une autre d&rsquo;\u00eatre \u00e9pargn\u00e9e d&rsquo;une mort atroce, qui choisit en retour de garder un silence implacable. Ressentir de l&rsquo;inqui\u00e9tude &ndash; une \u00e9motion humaine &ndash; est indigne d&rsquo;un Dieu tout-puissant. Certains h\u00e9r\u00e9tiques ont donc d\u00e9cid\u00e9 que le Christ \u00e9tait purement divin (doc\u00e9tisme), d&rsquo;autres qu&rsquo;il n&rsquo;\u00e9tait pas aussi divin que Dieu le P\u00e8re mais plut\u00f4t humain (arianisme) et quelques-uns qu&rsquo;il n&rsquo;\u00e9tait ni pleinement divin ni pleinement humain (apollinarisme). Mais ceux-ci ont fini par \u00eatre combattus et le paradoxe central du christianisme &ndash; un Dieu pleinement divin qui est aussi humain que vous et moi &ndash; est rest\u00e9 en place depuis pr\u00e8s de deux mill\u00e9naires maintenant.<\/p>\n<\/p>\n<p><p>Les schismes sont une autre histoire, et ils persistent encore aujourd&rsquo;hui. C&rsquo;est un sujet assez complexe, et pour lui rendre justice, il faudrait au moins un autre article de la m\u00eame longueur que celui-ci, je me contenterai donc d&rsquo;en souligner les points saillants. Apr\u00e8s le schisme orthodoxe\/catholique, le catholicisme s&rsquo;est d\u00e9compos\u00e9 en un culte de J\u00e9sus et Marie, probablement en raison d&rsquo;une p\u00e9nurie du Saint-Esprit pour maintenir la Sainte Trinit\u00e9 coll\u00e9e ensemble. C&rsquo;\u00e9tait un repli vers une mythologie dualiste, mais sans l&rsquo;id\u00e9e d&rsquo;\u00e9quilibre dynamique, puisqu&rsquo;il n&rsquo;y avait pas de notion de trop de J\u00e9sus ou trop de Marie. Puis vint le protestantisme, et une nouvelle d\u00e9ch\u00e9ance vers une mythologie moniste, incarn\u00e9e par la d\u00e9claration grotesque suivante : &laquo;<em> Le vrai christianisme est une relation personnelle avec J\u00e9sus-Christ. <\/em>&raquo; Comparez et opposez-la \u00e0 &laquo;<em> Car l\u00e0 o&ugrave; deux ou trois sont r\u00e9unis en mon nom, je suis au milieu d&rsquo;eux. <\/em>&raquo; [Matthieu 18:20] Le nom de qui ? C&rsquo;est juste l\u00e0, devant et au centre, dans chaque service religieux : &laquo;<em> Au nom du P\u00e8re, du Fils et du Saint-Esprit. <\/em>&raquo; L&rsquo;avant-derni\u00e8re \u00e9tape de ce voyage est une relation personnelle avec une statuette de J\u00e9sus en plastique coll\u00e9e sur le tableau de bord de votre camionnette, signalant une descente jusqu&rsquo;\u00e0 l&rsquo;idol\u00e2trie polyth\u00e9iste. Et la destination finale est atteinte soit en r\u00e9alisant spontan\u00e9ment, soit en se faisant expliquer qu&rsquo;une telle idol\u00e2trie est un pur non-sens. Et cela nous am\u00e8ne jusqu&rsquo;\u00e0 NULL.<\/p>\n<\/p>\n<p><p>Il existe \u00e9galement un raccourci pour arriver \u00e0 NULL : le culte du diable. Pour cela, il n&rsquo;est pas n\u00e9cessaire d&rsquo;accepter litt\u00e9ralement le Diable comme votre seigneur et ma&icirc;tre. Il suffit de croire en un anti-syst\u00e8me : un syst\u00e8me de croyances qui voit le monde, et l&rsquo;humanit\u00e9 en son sein, comme un mal qui doit \u00eatre d\u00e9truit. Par exemple, les \u00eatres humains surpeuplent la plan\u00e8te, \u00e9vincent les autres esp\u00e8ces et, par cons\u00e9quent, la croissance d\u00e9mographique doit \u00eatre arr\u00eat\u00e9e et invers\u00e9e par des avortements, la castration chimique et chirurgicale des enfants, la promotion des perversions sexuelles, etc. Autre exemple : les humains d\u00e9truisent le climat de la plan\u00e8te et il faut donc r\u00e9duire l&rsquo;activit\u00e9 humaine pour limiter les \u00e9missions de dioxyde de carbone, sans tenir compte du fait que l&rsquo;hypoth\u00e8se selon laquelle le CO2 affecte gravement le climat n&rsquo;a pas \u00e9t\u00e9 prouv\u00e9e, que la plupart du CO2 provient du d\u00e9gazage du magma et d&rsquo;autres processus naturels et que si toutes les \u00e9missions anthropiques de CO2 \u00e9taient arr\u00eat\u00e9es, l&rsquo;effet serait inf\u00e9rieur \u00e0 1% du total.<\/p>\n<\/p>\n<p><p>De tels anti-syst\u00e8mes apparaissent tous les mille ans environ avec une certaine r\u00e9gularit\u00e9. La plupart des gens ont entendu parler de la Sainte Inquisition qui a br&ucirc;l\u00e9 un grand nombre de sorci\u00e8res et d&rsquo;h\u00e9r\u00e9tiques sur le b&ucirc;cher. Beaucoup d&rsquo;entre eux \u00e9taient de v\u00e9ritables adorateurs du diable. Ils \u00e9taient difficiles \u00e0 d\u00e9busquer car leur credo les obligeait \u00e0 mentir sur leur credo. Nous ne semblons pas avoir ce probl\u00e8me \u00e0 l&rsquo;heure actuelle ; tout ce que nous avons \u00e0 faire pour trouver des adorateurs du diable est de regarder leurs pages de m\u00e9dias sociaux. Il semble terriblement peu aimable de consid\u00e9rer que ceux qui, actuellement, castrent chimiquement et chirurgicalement des enfants en les incitant \u00e0 demander un changement de sexe devraient \u00eatre br&ucirc;l\u00e9s sur le b&ucirc;cher ou tortur\u00e9s \u00e0 mort. D&rsquo;un autre c\u00f4t\u00e9, Vladimir Poutine a r\u00e9cemment assimil\u00e9 ce qu&rsquo;ils font \u00e0 des crimes contre l&rsquo;humanit\u00e9, et il n&rsquo;est pas du genre \u00e0 jeter des paroles en l&rsquo;air.<\/p>\n<\/p>\n<p><p>Mais il y a un autre point \u00e0 consid\u00e9rer : les adeptes de ces anti-syst\u00e8mes s&rsquo;\u00e9teignent d&rsquo;eux-m\u00eames parce qu&rsquo;ils ne parviennent pas \u00e0 se reproduire biologiquement. Cela a \u00e9t\u00e9 le cas tout au long de l&rsquo;histoire. Si vous regardez la g\u00e9n\u00e9ration actuelle des \u00e9lites occidentales, un grand nombre d&rsquo;entre elles sont sans enfants : Angela Merkel, Emmanuel Macron, Theresa May, Nicola Sturgeon, Jean-Claude Juncker, Mark Rutte&hellip; la liste est longue. La situation n&rsquo;est pas meilleure non plus en bas de la hi\u00e9rarchie sociale. Pour \u00e9viter l&rsquo;extinction biologique, une nation doit produire une moyenne de 2,1 enfants par femme, et aucune nation europ\u00e9enne ne s&rsquo;en approche.<\/p>\n<\/p>\n<p><p>Confusion des sexes et absence d&rsquo;enfants, addiction aux gadgets et culpabilit\u00e9 environnementale, ils semblent accueillir l&rsquo;oubli \u00e0 bras ouverts. &Agrave; cause d&rsquo;un environnementalisme malavis\u00e9, ils sont occup\u00e9s \u00e0 d\u00e9truire l&rsquo;infrastructure \u00e9nerg\u00e9tique dont d\u00e9pend leur survie, ils ont livr\u00e9 leurs gouvernements \u00e0 la merci d&rsquo;hommes d&rsquo;argent transnationaux, et ils permettent \u00e0 leurs pays d&rsquo;\u00eatre inond\u00e9s de jeunes troglodytes mal \u00e9lev\u00e9s provenant d&rsquo;&Eacute;tats en faillite qui seront peut-\u00eatre assez gentils pour donner le coup de gr\u00e2ce avant longtemps.<\/p>\n<\/p>\n<p><p>Le NULL peut sembler ascendant pour le moment, mais il s&rsquo;\u00e9teindra comme il le fait toujours. Et ce qui viendra apr\u00e8s est peut-\u00eatre mieux sugg\u00e9r\u00e9 par cette ligne c\u00e9l\u00e8bre des B\u00e9atitudes : &laquo;<em> Heureux les doux, car ils h\u00e9riteront de la terre. <\/em>&raquo; [Divers th\u00e9ologiens et philosophes ont essay\u00e9 de gagner leur vie en proposant des interpr\u00e9tations fantaisistes des termes <em>\u00ab\u00a0<\/em>doux\u00a0\u00bb et \u00ab\u00a0la terre\u00a0\u00bb, certains pensant au Royaume biblique d&rsquo;Isra\u00ebl et \u00e0 la fin des temps, d&rsquo;autres, comme Nietzsche, critiquant s\u00e9v\u00e8rement la douceur comme une &laquo;<em> morale d&rsquo;esclave <\/em>&raquo;.]<\/p>\n<\/p>\n<p><p>Mais je trouve que l&rsquo;explication la plus simple fonctionne le mieux : la terre est le sol sur lequel les choses poussent ; les doux sont les personnes qui le cultivent. Ils sont doux parce qu&rsquo;ils savent qu&rsquo;ils ne contr\u00f4lent rien et essaient simplement de faire ce qui est bon pour leurs parents, leur mari ou leur femme, leurs enfants, leurs voisins et leur terre natale, en faisant tous les sacrifices personnels n\u00e9cessaires pour y parvenir. Et ils ont le choix entre plusieurs mythologies, bas\u00e9es sur les chiffres 1, 2 et 3, dont chacune peut donner un sens \u00e0 leur vie.<\/p>\n<\/p>\n<p><p>Le 4 novembre 2021, <a href=\"https:\/\/cluborlov.wordpress.com\/2021\/11\/04\/noosphere-part-vi-trinitarian-mythologies\/\">Club Orlov<\/a>, &ndash; traduction du <em><a href=\"https:\/\/lesakerfrancophone.fr\/noosphere-partie-vi-mythologies-trinitaires\">Sakerfrancophone<\/a><\/em><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Noosph\u00e8re, VI : Mythologies trinitaires Il n&rsquo;y a qu&rsquo;une seule mythologie trinitaire qui m\u00e9rite d&rsquo;\u00eatre discut\u00e9e, et c&rsquo;est le christianisme. Le Dieu chr\u00e9tien est la Sainte Trinit\u00e9, compos\u00e9e du P\u00e8re (le vieux Dieu h\u00e9breu), du Fils (J\u00e9sus-Christ) et du Saint-Esprit. Dieu le P\u00e8re est arriv\u00e9 par l&rsquo;interm\u00e9diaire des textes sacr\u00e9s juifs, qui se sont trouv\u00e9s&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[29],"tags":[13007,2963,2856,21276,2647,2668,3778,13611],"class_list":["post-79972","post","type-post","status-publish","format-standard","hentry","category-les-carnets-de-dimitri-orlov-1","tag-ancien","tag-christianisme","tag-critique","tag-jesus-chriost","tag-nouveau","tag-orlov","tag-religion","tag-testament"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79972","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79972"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79972\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79972"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79972"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}