{"id":79976,"date":"2021-11-21T15:30:30","date_gmt":"2021-11-21T15:30:30","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2021\/11\/21\/la-trahison-pepere\/"},"modified":"2021-11-21T15:30:30","modified_gmt":"2021-11-21T15:30:30","slug":"la-trahison-pepere","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2021\/11\/21\/la-trahison-pepere\/","title":{"rendered":"La trahison-p\u00e9p\u00e8re"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepgreen\" style=\"color:#75714d; font-size:2em\">La trahison-p\u00e9p\u00e8re<\/h2>\n<\/p>\n<blockquote>\n<p><p>&bull; Articles du 21 novembre 2021. &bull; La situation de la gauche face \u00e0 l&rsquo;immigration, appr\u00e9ci\u00e9e d&rsquo;un oeil extr\u00eamement critique, mais sans forcer le trait <strong>tant la \u00ab\u00a0trahison\u00a0\u00bb de ses id\u00e9aux par la gauche<\/strong> est chose \u00e9vidente. &bull; Mise en perspective de cette \u00e9volution, <strong>qui conduit la gauche \u00e0 \u00eatre un des plus utiles &laquo; <em>idiots utiles de la globalisation<\/em> &raquo;<\/strong>, alors qu&rsquo;elle \u00e9tait, dans les ann\u00e9es 2000, et souvent au c\u00f4t\u00e9 d&rsquo;une droite anti-imp\u00e9rialiste, <strong>l&rsquo;adversaire le plus d\u00e9termin\u00e9 du Syst\u00e8me<\/strong>. &bull; Contributions de <em>dedefensa.org<\/em> et Jean-Philippe Mall\u00e9 (interview de RT-France).<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Ce qu&rsquo;il y a de plus ind\u00e9cent, disons de plus obsc\u00e8ne, ou finalement de plus \u00ab\u00a0p\u00e9p\u00e8re\u00a0\u00bb dans la trahison de la gauche, c&rsquo;est l&rsquo;impunit\u00e9 de conscience qu&rsquo;elle s&rsquo;offre \u00e0 elle-m\u00eame en brandissant le poing marxiste-l\u00e9niniste\/wokeniste et en encaissant les gros talbins de $100-$1 000 par piles et conteneurs, que le capitalisme de l&rsquo;hyper-luxe globalis\u00e9 lui balance comme par h\u00e9licopt\u00e8re.<\/p>\n<\/p>\n<p><p>(Fameuse image du pr\u00e9sident de la Fed Ben Bernanke, d\u00e9cidant en 2009 d&rsquo;imprimer des talbins par tonnes pour lutter contre la crise, et les distribuer \u00e0 foison et par dizaines de kilos, comme par h\u00e9licopt\u00e8re, &ndash; d&rsquo;o&ugrave; le fameux surnom d'\u00a0\u00bbHelicopter Ben\u00a0\u00bb [Bernanke]&#8230; Voyez <a href=\"https:\/\/francais.rt.com\/international\/86272-rokhaya-diallo-integre-branche-gender-justice-universite-georgetown\">Diallo<\/a>, zieutez <a href=\"https:\/\/francais.rt.com\/france\/87906-assa-traore-partenariat-avec-louboutin-pour-egalite-justice-pour-tous\">Traor\u00e9<\/a>, oyez la <a href=\"https:\/\/www.dedefensa.org\/article\/rapsit-usa2021-la-belle-vie-blm-inc\">cheffe-Patrisse<\/a> des BLM, tout.es activistes fameusement int\u00e9gr\u00e9.es.)<\/p>\n<\/p>\n<p><p>Dans son \u00e9mission r\u00e9guli\u00e8re &lsquo;<em>Le d\u00e9sordre mondial<\/em>&lsquo;, l&rsquo;excellente chroniqueuse de Spoutnik-fran\u00e7ais Rachel Madsen faisait <a href=\"https:\/\/fr.sputniknews.com\/20211110\/il-y-a-une-corruption-generalisee-de-la-democratie-dans-loccident-mine-par-la-guerre-culturelle-1052529170.html\">le 10 novembre<\/a> un commentaire politique d&rsquo;introduction \u00e0 une interview de l&rsquo;\u00e9crivain Philippe-Joseph Salazar. Elle se demandait si nous ne sommes pas en train de vivre la confirmation voyante d&rsquo;un bouleversement des clivages politiques.<\/p>\n<\/p>\n<p><p>Elle notait donc qu&rsquo;il existe d\u00e9sormais un affrontement entre d&rsquo;une part \u00ab\u00a0les \u00e9lites progressistes\u00a0\u00bb et globalistes, &ndash; c&rsquo;est-\u00e0-dire ce qu&rsquo;on nomme d\u00e9sormais \u00ab\u00a0la gauche\u00a0\u00bb, &ndash; et d&rsquo;autre part le \u00ab\u00a0camp anti-<em>establishment<\/em>\u00ab\u00a0. Pour notre compte, nous constatons que sa remarque conduit principalement \u00e0 mettre clairement les \u00ab\u00a0\u00e9lites progressistes et globalistes \u00a0\u00bb (la gauche) du c\u00f4t\u00e9 du Syst\u00e8me. Si elle parle principalement de la situation am\u00e9ricaniste, notre propos est bien d&rsquo;\u00e9tendre ce constat \u00e0 l&rsquo;ensemble du bloc-BAO au moins, selon les r\u00e8gles \u00e9videntes de la globalisation qui est compl\u00e8tement partie prenante.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Barack Obama a r\u00e9cemment critiqu\u00e9 la notion de divisions id\u00e9ologiques. \u00ab\u00a0L&rsquo;heure est grave et nous avons besoin de gens s\u00e9rieux. Nous avons trop \u00e0 faire pour revenir en arri\u00e8re\u00a0\u00bb, a d\u00e9clar\u00e9 l&rsquo;ancien Pr\u00e9sident am\u00e9ricain.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0Nous essayons de nous remettre d&rsquo;une pand\u00e9mie mondiale qui a tu\u00e9 plus de 700.000 Am\u00e9ricains et mis des millions de personnes en danger. Nous n&rsquo;avons pas de temps \u00e0 perdre avec de fausses guerres culturelles ou de faux scandales que les m\u00e9dias de droite ne colportent que pour faire monter leur audience.\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Au cas o&ugrave; vous ne l&rsquo;auriez pas remarqu\u00e9, la classique ligne de fracture droite-gauche n&rsquo;est plus le principal clivage politique au sein des soci\u00e9t\u00e9s occidentales. Elle a depuis \u00e9t\u00e9 remplac\u00e9e par l&rsquo;opposition entre ceux qui adh\u00e8rent au discours de l&rsquo;establishment sur les probl\u00e8mes clefs de nos soci\u00e9t\u00e9s et les sceptiques qui d\u00e9fient cete bienpensance.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>C&rsquo;est donc fort de caf\u00e9 qu&rsquo;Obama fustige maintenant les guerres culturelles qu&rsquo;alimente depuis tant de temps la propagande de l&rsquo;establishment qu&rsquo;il propage pour son compte depuis si longtemps. Vous ne pouvez pas r\u00e9citer le cat\u00e9chisme mondialiste de gauche et recevoir l&rsquo;onction du mouvement anti-establishment, d\u00e9sormais domin\u00e9 par la droite politique<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Ce qu&rsquo;on nomme \u00ab\u00a0la gauche\u00a0\u00bb a eu une attitude variable depuis la fin de l&rsquo;URSS. Une esp\u00e8ce de pr\u00e9tention \u00e0 la r\u00e9f\u00e9rence hors de toute critique s&rsquo;est \u00e9tabli dans le bloc-BAO, comme une sorte de \u00ab\u00a0discours de la bienpensance\u00a0\u00bb, notamment vis-\u00e0-vis des \u00e9v\u00e9nements internationaux qui, \u00e0 notre sens, sont les moteurs des principales \u00e9volutions int\u00e9rieures, soci\u00e9tales, etc., justement dans la mesure o&ugrave; ils se sont \u00e9largis \u00e0 des mati\u00e8res soci\u00e9tales en m\u00eame temps que les conflits prenaient une forme tr\u00e8s vari\u00e9e (\u00ab\u00a0hybride\u00a0\u00bb) o&ugrave; justement entrent en ligne des mati\u00e8res jusqu&rsquo;alors \u00e9trang\u00e8res aux conflits.<\/p>\n<\/p>\n<p><p>La gauche a certes soutenu en g\u00e9n\u00e9ral la premi\u00e8re guerre du Golfe sans beaucoup de mal, compte tenu de la quasi-unanimit\u00e9 engag\u00e9e derri\u00e8re ce simulacre de \u00ab\u00a0guerre juste\u00a0\u00bb suivant un pi\u00e8ge tendu par les USA, &ndash; par l&rsquo;ambassadrice <a href=\"https:\/\/www.dedefensa.org\/article\/quand-april-rencontrait-saddam\">April Gaspie<\/a> \u00e0 Saddam Hussein en juillet 1990 (le pi\u00e8ge, consistant \u00e0 dire \u00e0 Saddam que les USA ne r\u00e9agiraient pas \u00e0 une invasion du Kowe\u00eft, ayant \u00e9t\u00e9 mont\u00e9, semble-t-il, \u00e0 l&rsquo;insu de Gaspie qui aurait transmis l&rsquo;information en la croyant fond\u00e9e). La longue guerre civile de l&rsquo;ex-Yougoslavie, termin\u00e9e par l&rsquo;infamie de la guerre du Kosovo, sema une grande confusion entre opposants et partisans en grand d\u00e9sordre par rapport aux \u00e9tiquettes politiques. C&rsquo;est \u00e0 partir de l'\u00a0\u00bb\u00e8re 9\/11&Prime; que les choses se pr\u00e9cis\u00e8rent.<\/p>\n<\/p>\n<p><p>Tr\u00e8s vite, la guerre projet\u00e9e contre l&rsquo;Irak (printemps 2003) r\u00e9ussit \u00e0 provoquer une synth\u00e8se qu&rsquo;on jugerait, &ndash; aujourd&rsquo;hui, r\u00e9trospectivement sans aucun doute, &ndash; rien moins que miraculeuse. Un immense mouvement antiguerre (en f\u00e9vrier 2003, des manifestations regroupant des dizaines de millions de personnes dans le monde) se d\u00e9ploya, avec en plus le soutien parall\u00e8le de gouvernements tr\u00e8s importants (France et Allemagne) s&rsquo;opposant \u00e0 la guerre. La <a href=\"https:\/\/www.dedefensa.org\/article\/a-propos-de-notre-grande-crise\">conjonction droite-gauche<\/a> dans un sens compl\u00e8tement antiSyst\u00e8me dans la circonstance fut absolument remarquable. (On relira les chroniques de Justin Raimondo, libertarien d&rsquo;extr\u00eame-droite aux USA et remarquable commentateur de cette p\u00e9riode, pour prendre la mesure du ph\u00e9nom\u00e8ne. [Son site &lsquo;<em>Antiwar.com<\/em>&lsquo; avait d\u00e9j\u00e0 \u00e9t\u00e9 <a href=\"https:\/\/www.dedefensa.org\/article\/notre-samizdat-globalise\">tr\u00e8s actif<\/a> d\u00e8s la guerre du Kosovo.])<\/p>\n<\/p>\n<p><p>Tout cela changea avec l&rsquo;arriv\u00e9e de Sarkozy en France et d&rsquo;Obama aux USA, &ndash; comme marques politiques symboliques de l&rsquo;alignement pro-Syst\u00e8me de nombre d&rsquo;activistes progressistes, &ndash; ce changement devenant \u00ab\u00a0op\u00e9rationnel\u00a0\u00bb avec le pseudo-&lsquo;<em>printemps arabe<\/em>&lsquo; de 2010 ; savoir, essentiellement la catastrophique aventure libyenne et surtout la longue guerre de Syrie o&ugrave; tous les regroupements vol\u00e8rent en \u00e9clats. Plus que de \u00ab\u00a0gauche\u00a0\u00bb et de \u00ab\u00a0droite\u00a0\u00bb, l&rsquo;on parlerait en effet de Syst\u00e8me et d&rsquo;antiSyst\u00e8me, les premiers \u00e9tant d\u00e9cid\u00e9s \u00e0 d\u00e9truire Assad, f&ucirc;t-ce au prix du triomphe de l&rsquo;islamisme-<em>Daesh<\/em> et de son <em>djihad<\/em>. La confusion des \u00e9tiquettes \u00e9tant acquise, on d\u00e9couvrit la gauche et une droite particuli\u00e8rement stupide m\u00eal\u00e9es pour soutenir ces incomparablement stupides guerres de d\u00e9structuration. Bien entendu, ces guerres interventionnistes conduisaient \u00e0 du terrorisme en Europe et des migrations d\u00e9stabilisantes ouvrant une \u00e9norme perspective int\u00e9rieure \u00e0 partir d&rsquo;une politique \u00e9trang\u00e8re <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-laffectivisme-postmoderne\">affectiviste<\/a>, c&rsquo;est-\u00e0-dire \u00e0 la fois hyst\u00e9rique, aveugle et incoh\u00e9rente.<\/p>\n<\/p>\n<p><p>Effectivement, la bataille, tout en gardant une n\u00e9cessaire dimension ext\u00e9rieure, est devenue essentiellement int\u00e9rieure (communautarisme, souverainisme, jusqu&rsquo;au wokenisme d&rsquo;aujourd&rsquo;hui). Pour comprendre ce qui se passe aujourd&rsquo;hui dans les crises int\u00e9rieures, il est imp\u00e9ratif de les envisager comme des productions des crises ext\u00e9rieures, l&rsquo;ensemble donnant la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-la-gces\">Grande Crise<\/a> install\u00e9e \u00e0 partir de 2016-2020 (Covid + wokenisme, populisme &#038; tradition <em>versus <\/em>progressisme-soci\u00e9tal &#038; globalisation). La droite s&rsquo;est finalement \u00e0 peu pr\u00e8s regroup\u00e9e en antiSyst\u00e8me, comme le note Madsen, mais sans pour autant bien comprendre la dimension ext\u00e9rieure jusqu&rsquo;\u00e0 poursuivre dans des erreurs d&rsquo;un compl\u00e8te inversion. La gauche, elle, a compl\u00e8tement bascul\u00e9 dans la trahison de sa fonction essentielle, comme le notait James Carden, le <a href=\"https:\/\/www.dedefensa.org\/article\/quest-donc-la-gauche-antiwardevenue\">7 juillet 2020<\/a> :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Dans ses m\u00e9moires r\u00e9cemment publi\u00e9es, &lsquo;Circle in the Darkness&rsquo;, l&rsquo;auteur et journaliste <a href=\"https:\/\/www.dedefensa.org\/article\/echos-de-la-gauche-profonde\">Diana Johnstone<\/a> rappelle qu&rsquo;il y a seulement \u00ab\u00a0quelques d\u00e9cennies, la &lsquo;gauche&rsquo; \u00e9tait consid\u00e9r\u00e9e comme le centre de l&rsquo;opposition \u00e0 l&rsquo;imp\u00e9rialisme et le champion du droit des peuples \u00e0 l&rsquo;autod\u00e9termination\u00a0\u00bb.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Diana Johnstone fait partie d&rsquo;une lign\u00e9e distingu\u00e9e d&rsquo;\u00e9crivains am\u00e9ricains expatri\u00e9s qui, peut-\u00eatre en raison de l&rsquo;objectivit\u00e9 conf\u00e9r\u00e9e par la distance, voyaient leur pays plus clairement que nombre de leurs contemporains rest\u00e9s aux &Eacute;tats-Unis. Parmi les membres de ce club figurent <a href=\"https:\/\/www.dedefensa.org\/article\/salut-a-un-gaulliste-americain\">William Pfaff<\/a>, qui a \u00e9crit depuis Paris pendant de nombreuses ann\u00e9es, et Patrick Lawrence, correspondant de longue date en Asie. Johnstone, bas\u00e9 \u00e0 Paris, apporte une clart\u00e9 morale aux questions de guerre et de paix qui est, h\u00e9las, trop souvent absente de la plupart des \u00e9crits contemporains sur les affaires \u00e9trang\u00e8res. Son absence quasi-totale au sein de la gauche durant les ann\u00e9es Trump devrait donner lieu \u00e0 une r\u00e9flexion et \u00e0 une inqui\u00e9tude<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Du c\u00f4t\u00e9 fran\u00e7ais, comme exemple parall\u00e8le de cette trahison de la gauche \u00ab\u00a0<em>Antiwar<\/em>\u00a0\u00bb mais sans aucunement la dignit\u00e9 si intelligente d&rsquo;un Pfaff ou d&rsquo;une Johnstone sans nul go&ucirc;t pour la trahison, nous avons M\u00e9lenchon, ou p\u00e9p\u00e8re-M\u00e9lenchon. Nommons-le ainsi puisqu&rsquo;apr\u00e8s tout il s&rsquo;agit d&rsquo;une trahison-p\u00e9p\u00e8re, c&rsquo;est-\u00e0-dire tr\u00e8s confortablement install\u00e9e dans son id\u00e9ologie primaire, radicale et aguicheuse (le \u00ab\u00a0camp du Bien\u00a0\u00bb, quoi), de la gauche par elle-m\u00eame. M\u00e9lenchon garde une belle vision de politique ext\u00e9rieure qui ne lui sert pratiquement \u00e0 rien puisque, dans sa politique int\u00e9rieure, <a href=\"https:\/\/www.dedefensa.org\/article\/melenchon-et-son-simulacre\">il en est l\u00e0<\/a>, au milieu sinon en t\u00eate (la morale porte beau) de la trahison de la gauche dans son soutien enthousiaste m\u00eame si non-affich\u00e9e (on a ses pudeurs) au capitalisme globalis\u00e9 que projettent les bandes am\u00e9ricanistes :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Ainsi se conclut pour le temps pr\u00e9sent l&rsquo;affligeante histoire de l&rsquo;ex-trotskiste, par d\u00e9finition sp\u00e9cialiste de l'\u00a0\u00bbentrisme\u00a0\u00bb, victime de cette m\u00eame tactique de la part des minoritaires indig\u00e9nistes\/wokenistes, et par cons\u00e9quent tout cela nous menant \u00e0 la belle trouvaille de la \u00ab\u00a0cr\u00e9oalisation\u00a0\u00bb.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>M\u00e9lenchon sera conduit \u00e0 boire le calice jusqu&rsquo;\u00e0 la lie en s&rsquo;imaginant que c&rsquo;est un grand cru, lorsqu&rsquo;il verra confirm\u00e9s ses soup\u00e7ons sur l&rsquo;une des origines et dans tous les cas un des moteurs puissants de ces mouvements. Assa Traor\u00e9, Rokhaya Diallo et toute la compagnie sont des compagnes directes de la Fondation Obama, qui les finance, leur fournit des postes de prestige et ainsi de suite. \u00ab\u00a0Elle est tr\u00e8s intelligente ou tr\u00e8s bien conseill\u00e9e, elle r\u00e9pond exactement \u00e0 ce que les Am\u00e9ricains attendent. Ils doivent \u00eatre tr\u00e8s contents d&rsquo;elle\u00a0\u00bb, <a href=\"https:\/\/fr.sputniknews.com\/20210530\/avec-assa-traore-la-fondation-obama-renforce-ses-reseaux-ideologiques-en-france-1045668040.html\">dit Fran\u00e7ois-Bernard Huyghe<\/a> de Assa Traor\u00e9<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Avec le texte ci-dessous, nous passons \u00e0 un aspect particulier de cette vaste fresque o&ugrave; il est imp\u00e9ratif de m\u00ealer \u00e9v\u00e9nements ext\u00e9rieurs et \u00e9v\u00e9nements int\u00e9rieurs pour y vraiment comprendre quelque chose, et parce que ces deux politiques forment un tout. Ainsi notera-t-on que le fameux rapport de l&rsquo;Institut &lsquo;<em>Terra Nova<\/em>&lsquo; cit\u00e9 dans ce texte, qui servit de feuille de route au changement complet d&rsquo;orientation de la gauche en France, est de 2011, en m\u00eame temps que d\u00e9marrait le &lsquo;<em>printemps arabe<\/em>&lsquo; et la guerre en Syrie qui servirent d&rsquo;exercice pratique ext\u00e9rieur et de producteur de catastrophes [migration, etc.] pour ce tournant : en plus d&rsquo;\u00eatre de la \u00ab\u00a0chair \u00e0 canon\u00a0\u00bb, les victimes de ces conflits furent de la \u00ab\u00a0chair \u00e0 id\u00e9ologie\u00a0\u00bb pour la gauche hyper-progressiste et si contente de l&rsquo;\u00eatre.<\/p>\n<\/p>\n<p><p>Il s&rsquo;agit d&rsquo;une interview de L&rsquo;ex-d\u00e9put\u00e9 socialiste Jean-Philippe Mall\u00e9 sur l&rsquo;attitude de la gauche vis-\u00e0-vis de l&rsquo;immigration, &ndash; Mall\u00e9 ainsi pr\u00e9sent\u00e9 : &laquo; <em>Vice-pr\u00e9sident d&rsquo;Oser la France (fond\u00e9 par le d\u00e9put\u00e9 Les R\u00e9publicains Julien Aubert), ce gaulliste de gauche dresse un constat sans concession sur son ancien camp politique<\/em>. &raquo; Ce texte, paru le <a href=\"https:\/\/francais.rt.com\/france\/92800-immigration-gauche-a-desormais-haine-contre-idee-nation\">19 novembre 2021<\/a> sur RT-France, a comme titre initial : &laquo; <em>Immigration : \u00ab\u00a0La gauche a d\u00e9sormais une haine contre l&rsquo;id\u00e9e de nation\u00a0\u00bb<\/em> &raquo;.<\/p>\n<\/p>\n<p><h4><em>dedefensa.org<\/em><\/h4>\n<\/p>\n<p><p>_________________________<\/p>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Immigration : &laquo; Une haine contre l&rsquo;id\u00e9e de nation &raquo;<\/h2>\n<\/p>\n<p><p><strong>RT France<\/strong> : &laquo; Les candidats Fabien Roussel et Arnaud Montebourg ont essay\u00e9 d&rsquo;aborder le sujet de l&rsquo;immigration lors de leur campagne respective sans en faire un sujet tabou. En r\u00e9ponse, une grande partie de la gauche les a attaqu\u00e9s, de La France insoumise jusqu&rsquo;aux socialistes en passant par les \u00e9cologistes. Que r\u00e9v\u00e8le selon vous cette lev\u00e9e de boucliers? &raquo;<\/p>\n<\/p>\n<p><p><strong>Jean-Philippe Mall\u00e9<\/strong> : &laquo; Cela r\u00e9v\u00e8le le fait que la gauche est dans une forme de d\u00e9ni de la r\u00e9alit\u00e9 nationale. Je l&rsquo;ai v\u00e9cu au sein du Parti socialiste. Au sein de La France insoumise et des \u00e9cologistes c&rsquo;est au fond la m\u00eame chose. Majoritairement \u00e0 gauche, il y a une d\u00e9fiance vis-\u00e0-vis de la nation.  Historiquement, la gauche a pourtant port\u00e9 &ndash; depuis la R\u00e9volution fran\u00e7aise en particulier &ndash; l&rsquo;id\u00e9e de nation comme construction politique, vue comme un id\u00e9al universaliste. Elle a d\u00e9sormais abandonn\u00e9 le triptyque Nation-Etat-R\u00e9publique, source d&rsquo;\u00e9mancipation, au profit d&rsquo;autres choses, d&rsquo;autres objectifs. &raquo;<\/p>\n<\/p>\n<p><p><strong>RT France<\/strong> : &laquo; Quels sont pour vous ces objectifs ? &raquo;<\/p>\n<\/p>\n<p><p><strong>Jean-Philippe Mall\u00e9<\/strong> : &laquo; Il suffit de lire la note d\u00e9sormais tr\u00e8s connue de Terra Nova [un think tank influent proche du Parti socialiste], qui en 2011 a marqu\u00e9 un tournant. La gauche \u00e9tait alors domin\u00e9e par le Parti socialiste. Terra nova a fait le constat que les classes populaires et les classes moyennes inf\u00e9rieures ne votaient plus pour la gauche. Pour Terra Nova, elle devait donc se lancer dans d&rsquo;autres combats, bas\u00e9s sur des revendications minoritaires par segment. C&rsquo;est le marketing appliqu\u00e9 \u00e0 la politique. Et c&rsquo;est donc tout ce que vous savez : le combat pour les minorit\u00e9s et orientations sexuelles, les immigr\u00e9s, les communautarismes&#8230;<\/p>\n<\/p>\n<p><p>Lorsqu&rsquo;Arnaud Montebourg a fait cette proposition de bloquer les transferts de fonds priv\u00e9s [pour les pays \u00e9trangers non coop\u00e9ratifs] ou lorsque d&rsquo;autres politiques font des propositions comme la suppression du droit du sol&#8230; il ne s&rsquo;agit pas d&rsquo;interdire totalement l&rsquo;immigration ou d&rsquo;aller vers une immigration z\u00e9ro. Il s&rsquo;agit de r\u00e9guler l&rsquo;immigration. Sauf que lorsqu&rsquo;on aborde ces questions, la gauche pousse des cris d&rsquo;orfraie, parce que le communautarisme devient sa client\u00e8le \u00e9lectorale. &raquo;<\/p>\n<\/p>\n<p><p><strong>RT France<\/strong> : &laquo; Vous sentez-vous tr\u00e8s \u00e9loign\u00e9 de cette gauche, vous, ancien \u00e9lu socialiste ? &raquo;<\/p>\n<\/p>\n<p><p><strong>Jean-Philippe Mall\u00e9<\/strong> : &laquo; La gauche d&rsquo;aujourd&rsquo;hui, ce sont les idiots utiles de la globalisation. M\u00eame si elle a toujours eu une dimension d&rsquo;\u00e9mancipation individuelle, elle avait, dans l&rsquo;histoire, d&rsquo;abord une ambition collective \u00e0 travers la nation ou la lutte des classes. D\u00e9sormais c&rsquo;est l&rsquo;individualisme XXL, avec les revendications des droits de l&rsquo;individu, de la communaut\u00e9, de la minorit\u00e9. C&rsquo;est tout ce qu&rsquo;on appelle <a href=\"https:\/\/francais.rt.com\/international\/86272-rokhaya-diallo-integre-branche-gender-justice-universite-georgetown\">la gauche woke<\/a>.<\/p>\n<\/p>\n<p><p>Cela n&rsquo;est que le revers de la m\u00e9daille de la globalisation. On peut l&rsquo;illustrer avec Assa Traor\u00e9 <a href=\"https:\/\/francais.rt.com\/france\/87906-assa-traore-partenariat-avec-louboutin-pour-egalite-justice-pour-tous\">et ses chaussures Louboutin<\/a>. Le march\u00e9 mondialis\u00e9 ne veut pas de fronti\u00e8res et de cultures nationales.<\/p>\n<\/p>\n<p><p>J&rsquo;ai plus de respect pour les anciens militants communistes ouvriers des ann\u00e9es 80 qui avaient bien compris qu&rsquo;une immigration non r\u00e9gul\u00e9e, cela pouvait peser sur le co&ucirc;t du travail en France. Et c&rsquo;\u00e9tait tr\u00e8s clairement dit. &raquo;<\/p>\n<\/p>\n<p><p><strong>RT France<\/strong> : &laquo; Oui, Georges Marchais durant sa campagne pr\u00e9sidentielle de 1981 notamment&hellip; &raquo;<\/p>\n<\/p>\n<p><p><strong>Jean-Philippe Mall\u00e9<\/strong> : &laquo; Bien s&ucirc;r. Donc, j&rsquo;ai plus de respect pour ce Parti communiste que pour la gauche actuelle qui se drape d&rsquo;humanisme et des droits de l&rsquo;homme, mais qui fait beaucoup de tort aux classes populaires en France. Car l&rsquo;immigration p\u00e8se sur le co&ucirc;t du travail. Les classes populaires le voient bien. Si le Rassemblement national et Eric Zemmour sont \u00e0 ce niveau, la gauche en est responsable et coupable. C&rsquo;est son d\u00e9ni de r\u00e9alit\u00e9 du fait que, pour elle, il n&rsquo;y a plus de fronti\u00e8re, plus de nation&#8230; il n&rsquo;y a plus de peuple. Mais les Fran\u00e7ais, notamment les plus modestes et fragiles, ont bien compris qu&rsquo;il n&rsquo;y aura pas de d\u00e9bouch\u00e9 social, hors de la nation. &raquo;<\/p>\n<\/p>\n<p><p><strong>RT France<\/strong> : &laquo; Selon vous, les \u00e9lecteurs de gauche ont-ils massivement gliss\u00e9 chez Marine Le Pen et Eric Zemmour ? &raquo;<\/p>\n<\/p>\n<p><p><strong>Jean-Philippe Mall\u00e9<\/strong> : &laquo; Surtout Marine Le Pen&#8230; Et on les comprend. On se retrouve dans cette situation o&ugrave; l&rsquo;ensemble de la gauche r\u00e9uni aujourd&rsquo;hui est \u00e0 25%. Et elle ne se remet m\u00eame pas en question. C&rsquo;est assez fascinant.<\/p>\n<\/p>\n<p><p>Aussi, quand quelqu&rsquo;un comme l&rsquo;\u00e9cologiste Emmanuelle Cosse &ndash; qui a \u00e9t\u00e9 ministre sous Fran\u00e7ois Hollande &ndash; d\u00e9clare qu&rsquo;il faut dissoudre l&rsquo;&Eacute;tat-nation, c&rsquo;est totalement irresponsable. Si vous d\u00e9faites l&rsquo;architecture \u00ab\u00a0Nation, &Eacute;tat, R\u00e9publique\u00a0\u00bb, que reste-t-il ? Il reste des clans, des tribus, des communaut\u00e9s et l&rsquo;individu. C&rsquo;est ce que nous a pr\u00e9par\u00e9 la gauche. &raquo;<\/p>\n<\/p>\n<p><p><strong>RT France<\/strong> : &laquo; Pour vous, le tournant id\u00e9ologique date v\u00e9ritablement et seulement de 2011 avec la note de Terra Nova ? &raquo;<\/p>\n<\/p>\n<p><p><strong>Jean-Philippe Mall\u00e9<\/strong> : &laquo; Structurellement, on peut remonter aux ann\u00e9es 60, particuli\u00e8rement la date symbolique de 1968, avec la mont\u00e9e du consum\u00e9risme, de l&rsquo;individualisme, avec la remise en cause des grandes structures verticales comme l&rsquo;Etat mais aussi le Parti communiste, tout comme l&rsquo;&Eacute;glise catholique. Tout cela au profit d&rsquo;une atomisation de la soci\u00e9t\u00e9. On est pass\u00e9 d&rsquo;une soci\u00e9t\u00e9 holiste \u00e0 une soci\u00e9t\u00e9 individualiste.<\/p>\n<\/p>\n<p><p>N\u00e9anmoins, 2011, sur le plan du champ politique de la gauche et du Parti socialiste, c&rsquo;est une date importante. En effet, avec la note de Terra Nova, d\u00e9sormais, tout cela est \u00e9crit, conceptualis\u00e9, th\u00e9oris\u00e9, \u00e9crit noir sur blanc. &raquo;<\/p>\n<\/p>\n<p><p><strong>RT France<\/strong> : &laquo; A vous \u00e9couter, la gauche semble avoir arr\u00eat\u00e9 de r\u00e9fl\u00e9chir sur l&rsquo;immigration. Cela a-t-il eu une cons\u00e9quence sur sa r\u00e9flexion \u00e0 propos de la nation ? &raquo;<\/p>\n<\/p>\n<p><p><strong>Jean-Philippe Mall\u00e9<\/strong> : &laquo; Pour la gauche, l&rsquo;immigration ne m\u00e9rite m\u00eame pas d&rsquo;\u00eatre pens\u00e9e car elle a d\u00e9sormais une haine contre l&rsquo;id\u00e9e de nation. Elle ne veut pas voir les cons\u00e9quences sur les communautarismes, sur le fait qu&rsquo;on n&rsquo;arrive pas \u00e0 assimiler. La nation est devenue leur ennemi.<\/p>\n<\/p>\n<p><p>Il y a quelques mois, un homme d&rsquo;une gauche devenue ultra-minoritaire, Didier Leschi [directeur g\u00e9n\u00e9ral de l&rsquo;Office fran\u00e7ais de l&rsquo;immigration et de l&rsquo;int\u00e9gration], a fait une interview retentissante et juste dont le titre \u00e9tait : \u00ab\u00a0Une hospitalit\u00e9 pour tous est une hospitalit\u00e9 pour personne.\u00a0\u00bb Tous ces gens de gauche devenus majoritaires, si humanistes, si attach\u00e9s \u00e0 accueillir tout le monde, ils ne mesurent pas leurs \u00e9checs sur les politiques d&rsquo;int\u00e9gration et m\u00eame d&rsquo;assimilation. La nation est devenue leur ennemi.<\/p>\n<\/p>\n<p><p>En cons\u00e9quence, la gauche a abandonn\u00e9 l&rsquo;universalisme r\u00e9publicain. Beaucoup d&rsquo;intellectuels ont pes\u00e9 autrefois sur elle comme Jacques Julliard. Il suffit de lire ses \u00e9ditos d&rsquo;aujourd&rsquo;hui. Comme d&rsquo;autres, cet intellectuel de la CFDT et de la deuxi\u00e8me gauche ne se reconna&icirc;t plus dans la gauche d&rsquo;aujourd&rsquo;hui. Celle-ci ne parle plus que de races, de communaut\u00e9s.<\/p>\n<\/p>\n<p><p>La situation de la gauche est catastrophique. Mais je constate que la droite Les R\u00e9publicains a aussi arr\u00eat\u00e9 de r\u00e9fl\u00e9chir sur l&rsquo;immigration et la nation. On peut m\u00eame remonter au RPR de Jacques Chirac qui a \u00ab\u00a0d\u00e9-gaullis\u00e9\u00a0\u00bb ce parti. Un ph\u00e9nom\u00e8ne qui s&rsquo;est poursuivi sous Nicolas Sarkozy. &raquo;<\/p>\n<\/p>\n<p><h4>Propos recueillis par Bastien Gouly<\/h4><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La trahison-p\u00e9p\u00e8re &bull; Articles du 21 novembre 2021. &bull; La situation de la gauche face \u00e0 l&rsquo;immigration, appr\u00e9ci\u00e9e d&rsquo;un oeil extr\u00eamement critique, mais sans forcer le trait tant la \u00ab\u00a0trahison\u00a0\u00bb de ses id\u00e9aux par la gauche est chose \u00e9vidente. &bull; Mise en perspective de cette \u00e9volution, qui conduit la gauche \u00e0 \u00eatre un des plus&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[3675,4363,2632,3330,21285,12836,8315,4337,3867,2646],"class_list":["post-79976","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-antiwar","tag-capitalisme","tag-globalisation","tag-immigration","tag-jean-philippe","tag-malle","tag-melenchon","tag-raimondo","tag-syrie","tag-wokenisme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79976","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79976"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79976\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79976"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79976"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79976"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}