{"id":79988,"date":"2021-12-01T16:52:35","date_gmt":"2021-12-01T16:52:35","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2021\/12\/01\/deconstructuration-au-pas-de-loie\/"},"modified":"2021-12-01T16:52:35","modified_gmt":"2021-12-01T16:52:35","slug":"deconstructuration-au-pas-de-loie","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2021\/12\/01\/deconstructuration-au-pas-de-loie\/","title":{"rendered":"D\u00e9constructuration au pas de l&rsquo;oie"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepblue\" style=\"color:#0f3955; font-size:2em\">D\u00e9constructuration au pas de l&rsquo;oie<\/h2>\n<\/p>\n<blockquote>\n<p><p>&bull; Merkel s&rsquo;en est all\u00e9e ou est-elle sur le point de le faire, et d\u00e9j\u00e0 l&rsquo;on commence \u00e0 l&rsquo;oublier. &bull; Dans un pays qu&rsquo;on croit r\u00e9gl\u00e9 comme du papier \u00e0 musique depuis sa r\u00e9cup\u00e9ration d&rsquo;apr\u00e8s le sanglant apocalypse nazi, la succession <strong>d&rsquo;une <em>Kaiserin<\/em> qui a r\u00e9gn\u00e9 lourdement et avec ent\u00eatement pendant pr\u00e8s de vingt ans<\/strong> suscite la question se pose de savoir <strong>s&rsquo;il peut y avoir un changement de quelque importance<\/strong>. &bull; Apr\u00e8s tout, pourquoi l&rsquo;Allemagne \u00e9chapperait-elle au vent de changement cul-par-dessus-t\u00eate et de folie invertie qui secoue le monde ? &bull; C&rsquo;est <strong>avec cet esprit profond\u00e9ment subversif, toujours \u00e0 la recherche de ce qui peut \u00e9branler le Syst\u00e8me<\/strong>, que nous consid\u00e9rons les possibilit\u00e9s qui s&rsquo;offrent \u00e0 l&rsquo;Allemagne. &bull; Or, il semble qu&rsquo;elles soient paradoxales et se r\u00e9sument \u00e0 la possibilit\u00e9 de ceci : en suivant naturellement ses ambitions naturelles, <strong>l&rsquo;Allemagne post-Merkel pourrait bien mettre le feu aux poudres dans les soutes de l&rsquo;UE<\/strong>. &bull; Les nouveaux\/nouvelles-venues n&rsquo;ont rien d&rsquo;excitant et sont tr\u00e8s conformes : c&rsquo;est bien cela qui est potentiellement explosif. &bull; <strong>Badaboum par inadvertance ?<\/strong><\/p>\n<\/p>\n<\/blockquote>\n<p><p>1er d\u00e9cembre 2021 &ndash; Le nouveau gouvernement allemand va bient\u00f4t prendre ses fonctions : l&rsquo;accord entre les trois partis (SPD, Verts et lib\u00e9raux-FDB) est boucl\u00e9, sign\u00e9, pes\u00e9&#8230; 178 pages ou 59 000 mots,  c&rsquo;est du lourd. Merkel va donc nous quitter avec dans son sillage pr\u00e8s de vingt ans de r\u00e8gne sans partage, pleins de fausses-crises d\u00e9samorc\u00e9es, de pseudo-incertitudes vite dissip\u00e9es, une sorte de lourdeur qui nous la faisait percevoir de plus en plus ind\u00e9boulonnable. Sous sa direction, l&rsquo;Allemagne est devenue une puissance \u00e0 la fois effac\u00e9e et \u00e9touffante, une puissance qui a retrouv\u00e9 avec une discr\u00e9tion exemplaire une conscience d&rsquo;un destin remarquable o&ugrave; tra&icirc;nent quelques restes des temps anciens, \u00e0 l&rsquo;ombre vertueuse de la d\u00e9mocratie, des droits de l&rsquo;homme et du migrant, et de la manipulation comme allant de soi de l&rsquo;Union Europ\u00e9enne.<\/p>\n<\/p>\n<p><p>Dans le m\u00eame temps de l&rsquo;I.G. Merkel, et avec l&rsquo;\u00e9l\u00e9gance brillante qu&rsquo;on lui conna&icirc;t, la France s&rsquo;\u00e9vertuait, sous la succession de trois pr\u00e9sidents de plus en plus calamiteux, de plus en plus m\u00e9diocres et de plus en plus bien de leur temps, \u00e0 perdre avec application et \u00e0 la fois, tout ce qui lui restait de tous les outils et de tous les attributs qui faisaient son originalit\u00e9 et sa puissance souveraine au c&oelig;ur de l&rsquo;Europe. La France a donc servi sur un plateau d&rsquo;argent serti de joyaux divers (Airbus, Ariane, etc.) la direction naturelle de l&rsquo;Europe \u00e0 la soci\u00e9t\u00e9 I.G. Merkel. La r\u00e9cipiendaire a accept\u00e9 avec un sourire pinc\u00e9 mais une poigne ferme.<\/p>\n<\/p>\n<p><p>Aujourd&rsquo;hui se pose alors une question : cet empire discret qui p\u00e8se sur l&rsquo;Europe, et dont on ne voit pas qui pourrait le lui contester, que vont en faire les successeurs de I.G. Merkel ? C&rsquo;est l\u00e0 une question du plus grand int\u00e9r\u00eat, conclut-on apr\u00e8s avoir lu <a href=\"https:\/\/www.rt.com\/op-ed\/541658-olaf-scholz-germany-eu\/\">l&rsquo;article<\/a> de Paul A. Nuttall, historien, auteur et un ancien politicien qui fut membre du Parlement Europ\u00e9en entre 2009 et 2019, et un fervent partisan du Brexit. Bref, selon notre point de vue, un connaisseur, ce qui explique que l&rsquo;on doit \u00eatre int\u00e9ress\u00e9 par sa th\u00e8se selon laquelle, tr\u00e8s-paradoxalement, &laquo; <em>la nouvelle direction allemande constitue une menace majeure pour l&rsquo;UE<\/em> &raquo;.<\/p>\n<\/p>\n<p><p>On imagine qu&rsquo;un document de 59 000 mots scellant un accord de gouvernement indique que nombre de sujets ont \u00e9t\u00e9 pass\u00e9s en revue. Dans ce bouquet, ce qui retient particuli\u00e8rement l&rsquo;attention de Nuttall, c&rsquo;est la rubrique &laquo; <em>d\u00e9veloppement d&rsquo;un &Eacute;tat europ\u00e9en f\u00e9d\u00e9ral<\/em> &raquo;. Le principal n\u00e9gociateur des sociaux-d\u00e9mocrates SPD qui dirigent la coalition, Udo Bullmann, a expos\u00e9 que &laquo; <em>l&rsquo;\u00e9poque l&rsquo;exige et <\/em>[que] <em>les gens l&rsquo;attendent <\/em>&raquo;, cet &laquo; <em>&Eacute;tat europ\u00e9en f\u00e9d\u00e9ral<\/em> &raquo;&#8230;<\/p>\n<\/p>\n<p><p>&laquo; <em>Mouais<\/em>, commente Nuttall. <em>C&rsquo;est ce que nous verrons<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>C&rsquo;est tout vu, pour Nuttall, comme on l&rsquo;imagine. A partir de cette description des \u00e9v\u00e9nements, o&ugrave; il appara&icirc;t que la nouvelle coalition veut bruyamment une \u00e9poque tr\u00e8s-compl\u00e8tement f\u00e9d\u00e9rale, Nuttall explique pourquoi elle risque d&rsquo;obtenir son contraire sous la forme d&rsquo;une explosion. Voici le c&oelig;ur de l&rsquo;argument :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Les ambitions f\u00e9d\u00e9ralistes du nouveau gouvernement allemand susciteront des inqui\u00e9tudes dans un certain nombre de pays, dont la Pologne, dont le gouvernement a clairement indiqu\u00e9 qu&rsquo;il \u00e9tait oppos\u00e9 \u00e0 un super-&Eacute;tat europ\u00e9en. En juin dernier, j&rsquo;avais pr\u00e9dit que les ambitions f\u00e9d\u00e9ralistes de l&rsquo;UE finiraient par provoquer une rupture avec les Polonais, et ce document ne fait que rapprocher cet affrontement in\u00e9vitable. <\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>En outre, un porte-parole du bureau du premier ministre hongrois a d\u00e9clar\u00e9 que le document de la coalition allemande \u00ab\u00a0n&rsquo;est pas un programme europ\u00e9en mais un programme distinctement ouest-europ\u00e9en\u00a0\u00bb, qui est \u00ab\u00a0extr\u00eamement \u00e9loign\u00e9 de ce que nous pensons du monde et des soci\u00e9t\u00e9s dans la partie centrale de l&rsquo;Europe\u00a0\u00bb.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Il a ajout\u00e9 que le nouveau gouvernement allemand \u00ab\u00a0veut clairement des &Eacute;tats-Unis d&rsquo;Europe, mais au moins il l&rsquo;annonce ouvertement, plut\u00f4t que par un \u00e9largissement furtif des pouvoirs des institutions europ\u00e9ennes et un affaiblissement des pouvoirs des &Eacute;tats membres\u00a0\u00bb.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>C&rsquo;est un commentaire vraiment int\u00e9ressant, car l&rsquo;UE obtient g\u00e9n\u00e9ralement ce qu&rsquo;elle veut lorsqu&rsquo;elle agit subrepticement. Lorsque ses plans d&rsquo;int\u00e9gration sont pr\u00e9sent\u00e9s au grand jour, ils sont g\u00e9n\u00e9ralement rejet\u00e9s. En effet, la derni\u00e8re fois que l&rsquo;UE a expos\u00e9 ses ambitions pour une Europe f\u00e9d\u00e9rale sous la forme d&rsquo;une Constitution europ\u00e9enne, l&rsquo;id\u00e9e a \u00e9t\u00e9 rejet\u00e9e en bloc par les Fran\u00e7ais et les N\u00e9erlandais lors de r\u00e9f\u00e9rendums.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Le document de la coalition allemande souhaite \u00e9galement que l&rsquo;on s&rsquo;oriente vers une politique \u00e9trang\u00e8re europ\u00e9enne coh\u00e9rente. Il vise \u00e0 abolir le principe de l&rsquo;unanimit\u00e9 et \u00e0 le remplacer par le vote \u00e0 la majorit\u00e9 qualifi\u00e9e (VMQ), ce qui signifie que les &Eacute;tats membres n&rsquo;auront plus de droit de veto. Les &Eacute;tats membres n&rsquo;ayant donc plus de droit de veto en mati\u00e8re de politique \u00e9trang\u00e8re, cela pourrait entra&icirc;ner des pays dans des engagements \u00e9trangers qu&rsquo;ils n&rsquo;approuvent pas n\u00e9cessairement. <\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Pour atteindre ses objectifs f\u00e9d\u00e9ralistes, le nouveau gouvernement allemand veut qu&rsquo;on donne plus de pouvoirs au Parlement europ\u00e9en. Pour ce faire, il pr\u00e9voit de permettre au Parlement de prendre l&rsquo;initiative de la l\u00e9gislation, ce qui, \u00e0 l&rsquo;heure actuelle, est du ressort exclusif de la Commission europ\u00e9enne. Ce manque de pouvoir l\u00e9gislatif a conduit de nombreuses personnes \u00e0 consid\u00e9rer le Parlement europ\u00e9en comme un simple \u00ab\u00a0salon de discussion\u00a0\u00bb.  <\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Bien que le projet du gouvernement allemand de donner plus de pouvoir aux d\u00e9put\u00e9s europ\u00e9ens \u00e9lus puisse \u00eatre un pas vers une plus grande responsabilit\u00e9 d\u00e9mocratique, il pourrait \u00e9galement \u00eatre contre-productif. <\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Le Parlement europ\u00e9en est la plus f\u00e9d\u00e9raliste de toutes les institutions de l&rsquo;UE, et c&rsquo;est aussi, et de loin, la plus extr\u00e9miste. En effet, la Commission europ\u00e9enne agit souvent comme un frein \u00e0 certains exc\u00e8s du Parlement. C&rsquo;est pourquoi les conflits interinstitutionnels sont l\u00e9gion. Prenons par exemple le cas r\u00e9cent o&ugrave; le Parlement poursuit la Commission pour ne pas avoir sanctionn\u00e9 assez rapidement la Pologne et la Hongrie qui refusent de se conformer aux diktats de l&rsquo;UE.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Si les d\u00e9put\u00e9s europ\u00e9ens obtenaient gain de cause, les objectifs climatiques seraient encore plus extr\u00eames, l&rsquo;UE disposerait d\u00e9j\u00e0 d&rsquo;une arm\u00e9e permanente et s&rsquo;impliquerait dans des conflits partout dans le monde, et l&rsquo;int\u00e9gration totale serait acc\u00e9l\u00e9r\u00e9e. En outre, les pays qui s&rsquo;\u00e9carteraient des objectifs du projet s&rsquo;exposeraient \u00e0 des sanctions encore plus s\u00e9v\u00e8res. Il n&rsquo;est pas \u00e9tonnant que des d\u00e9put\u00e9s europ\u00e9ens ultra-f\u00e9d\u00e9ralistes comme l&rsquo;ancien Premier ministre belge Guy Verhofstadt acclament le nouveau gouvernement allemand<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Des clameurs d&rsquo;approbation de l&rsquo;ayatollah Verhofstadt, c&rsquo;est une r\u00e9f\u00e9rence qui nous conduit \u00e0 bien comprendre ce que Nuttall veut dire et ce que la coalition Olaf Scholz a en t\u00eate. &laquo; <em>Et qu&rsquo;en est-il des Fran\u00e7ais ? <\/em>&raquo;, interroge \u00e9galement Nuttall. Certes, Scholz a annonc\u00e9 que son premier d\u00e9placement \u00e0 l&rsquo;\u00e9tranger serait pour Paris. On n&rsquo;en attendait pas moins puisqu&rsquo;il s&rsquo;agit de faire perdurer les images d&rsquo;&Eacute;pinal qui illustrent la grande ambition europ\u00e9enne. Pour le reste, Nuttall note que la p\u00e9riode \u00e9lectorale en France n&rsquo;est gu\u00e8re propice \u00e0 ce genre d&rsquo;aventure, que m\u00eame le candidat Barnier, ancien n\u00e9gociateur europ\u00e9en du Brexit, fait campagne sur l&rsquo;id\u00e9e de reprendre des pouvoirs confisqu\u00e9s par Bruxelles, notamment concernant l&rsquo;immigration. Venir l\u00e0-dessus avec un &laquo; <em>&Eacute;tat europ\u00e9en f\u00e9d\u00e9ral<\/em> &raquo;&#8230;<\/p>\n<\/p>\n<p><p>&bull; On ajoutera que le choix probable du ministre des affaires \u00e9trang\u00e8res, pr\u00e9vue pour la dirigeante des Verts et Vice-Chanceli\u00e8re Annalena Baerbock, promet \u00e9galement quelques coups de roulis. Telle que la d\u00e9crit Tarik Cyril Amar <a href=\"https:\/\/www.rt.com\/russia\/541565-germany-relationship-foreign-ministry-baerbock\/\">sur RT.com<\/a>, on peut en attendre un durcissement allemand, et en accord sinon en position d&rsquo;influence sur  la politique de l&rsquo;UE qui ne demande que cela, dans les relations avec la Russie.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; [Cette nomination aurait] <em>des implications particuli\u00e8res pour la relation de l&rsquo;Allemagne avec la Russie. Quoi que les Verts aient pu dire en faveur du pacifisme et contre l&rsquo;OTAN, Baerbock, comme la plupart des gens de son parti aujourd&rsquo;hui, est une atlantiste assum\u00e9e qui exige une ligne plus dure envers Moscou (et P\u00e9kin aussi). Elle s&rsquo;est prononc\u00e9e \u00e0 plusieurs reprises contre le gazoduc Nord Stream 2 et, plus r\u00e9cemment, elle s&rsquo;est jointe \u00e0 ceux qui, \u00e0 tort mais de mani\u00e8re spectaculaire, imputent \u00e0 la Russie la p\u00e9nurie de gaz dans l&rsquo;Union europ\u00e9enne. Pour cela, la ministre putative a \u00e9t\u00e9 couverte d&rsquo;\u00e9loges par la bienpensance des \u00e9lites.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Baerbock se livre g\u00e9n\u00e9ralement \u00e0 une rh\u00e9torique des valeurs<\/em> [conforme au Syst\u00e8me] <em>et insiste sur le fait que l&rsquo;Europe occidentale ne doit pas subir de \u00ab\u00a0chantage\u00a0\u00bb de la part de Moscou. La qualification de \u00ab\u00a0chantage\u00a0\u00bb semble s&rsquo;appliquer \u00e0 chaque occasion o&ugrave; la Russie a la t\u00e9m\u00e9rit\u00e9 de prot\u00e9ger ou de promouvoir ses int\u00e9r\u00eats nationaux. Baerbock n&rsquo;a pas non plus conscience qu&rsquo;une UE qui s&rsquo;oppose \u00e0 Moscou \u00e0 tout bout de champ ne doit pas s&rsquo;\u00e9tonner de recevoir des r\u00e9ponses peu aimables. La r\u00e9ciprocit\u00e9 n\u00e9cessaire \u00e0 toute diplomatie ne semble pas \u00eatre \u00e9vidente pour elle<\/em>&#8230; &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>&bull; Un autre aspect de la nouvelle direction allemande est l&rsquo;annonce de la nomination d&rsquo;un g\u00e9n\u00e9ral de la Bundeswehr \u00e0 la t\u00eate d&rsquo;un nouveau service, ou \u00ab\u00a0cellule de crise\u00a0\u00bb, institu\u00e9e par cette m\u00eame direction et charg\u00e9e de la lutte contre le Covid. Le Major G\u00e9n\u00e9ral Carsten Breuer, chef du commandement territorial la Bundeswehr, n&rsquo;a aucune capacit\u00e9 virologiques ou m\u00e9dicale particuli\u00e8re et ses diff\u00e9rents commandements l&rsquo;ont conduit dans divers services op\u00e9rationnels de l&rsquo;arm\u00e9e, au minist\u00e8re de la d\u00e9fense, \u00e0 l&rsquo;OTAN, etc. Cette nomination \u00e9veille <a href=\"https:\/\/www.wsws.org\/en\/articles\/2021\/12\/01\/germ-d01.html\">chez &lsquo;<em>WSWS.org<\/em>&lsquo;<\/a> une ire particuli\u00e8rement virulente, selon l&rsquo;argument particuli\u00e8rement \u00e9vident que la lutte contre le Covid semble \u00eatre appr\u00e9ci\u00e9e par le nouveau gouvernement allemand, d&rsquo;abord comme une mission de maintien de l&rsquo;ordre plus que comme une mission sanitaire. &Eacute;coutez Peter Schwarz \u00e9ructer en m\u00e9langeant all\u00e8grement les querelles covidiennes et les indices boursiers et capitalistiques :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>La d\u00e9cision de confier la direction de la cellule de crise COVID-19 \u00e0 un g\u00e9n\u00e9ral de la Bundeswehr en activit\u00e9 ne permet qu&rsquo;une seule conclusion : la nouvelle coalition ne consid\u00e8re pas la pand\u00e9mie comme un probl\u00e8me m\u00e9dical, mais plut\u00f4t comme une question de s\u00e9curit\u00e9.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>L&rsquo;objectif de la cellule de crise n&rsquo;est pas de prot\u00e9ger la population du virus, mais de prot\u00e9ger le gouvernement de la population. Le nouveau gouvernement allemand s&rsquo;appr\u00eate \u00e0 d\u00e9clarer l&rsquo;\u00e9tat d&rsquo;urgence afin de supprimer toute r\u00e9sistance \u00e0 sa politique fond\u00e9e sur le sacrifice d&rsquo;innombrables vies pour assurer l&rsquo;augmentation des profits et du cours des actions. Il s&rsquo;agit d&rsquo;une politique qui joue \u00e0 la roulette russe avec la sant\u00e9 de toute une g\u00e9n\u00e9ration d&rsquo;enfants et d&rsquo;adolescents<\/em>.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>&bull; Apr\u00e8s ce rapide passage en revue de quelques aspects de la nouvelle \u00e9quipe, on revient \u00e0 Nuttall et \u00e0 sa conclusion concernant le projet d&rsquo;un &laquo; <em>&Eacute;tat europ\u00e9en f\u00e9d\u00e9ral<\/em> &raquo;.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Je crois sinc\u00e8rement que le navire f\u00e9d\u00e9raliste a pris le large. Ces id\u00e9es \u00e9taient en vogue dans la premi\u00e8re d\u00e9cennie du si\u00e8cle, mais plus maintenant. Il suffit de voir comment les partis eurosceptiques se sont d\u00e9velopp\u00e9s sur tout le continent au cours des 20 derni\u00e8res ann\u00e9es pour comprendre que les citoyens se lassent de l&rsquo;ing\u00e9rence de Bruxelles.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Si le gouvernement allemand tient sa parole et poursuit agressivement l&rsquo;objectif de cr\u00e9er un super-&Eacute;tat f\u00e9d\u00e9ral europ\u00e9en, cela entra&icirc;nera des tensions massives entre les membres. En effet, \u00e0 plus long terme, cela pourrait amener certains pays \u00e0 se retirer compl\u00e8tement du bloc et \u00e0 suivre leur propre voie<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Leur &lsquo;<em>Meilleur des mondes<\/em>&lsquo;<\/h3>\n<\/p>\n<p><p>De ces diverses observations sur ce que devrait \u00eatre cette nouvelle coalition post-Merkel, on peut tirer deux conclusions qui ne nous paraissent nullement sollicit\u00e9es :<\/p>\n<\/p>\n<p><p>&bull; C&rsquo;est un gouvernement \u00ab\u00a0de gauche\u00a0\u00bb qui entend durcir toutes les positions traditionnelles (si l&rsquo;on peut dire) du Syst\u00e8me : une f\u00e9d\u00e9ralisation dans le sens de la globalisation, sous la direction explicite de l&rsquo;Allemagne ; un atlantisme pur et dur, correspondant \u00e0 la position de l&rsquo;UE, mais cette fois sous la houlette affich\u00e9e de l&rsquo;Allemagne ; un antirussisme affirm\u00e9e correspondant aussi bien \u00e0 l&rsquo;OTAN qu&rsquo;\u00e0 l&rsquo;UE ; un durcissement d&rsquo;une attitude r\u00e9pressive, dans le cas du Covid comme c&rsquo;est \u00e9vident, et sans doute contre toute autre manifestation disons \u00ab\u00a0de dissidence\u00a0\u00bb ; un durcissement \u00e0 mesure dans la transformation vertueuse de l&rsquo;\u00e9conomie et de la soci\u00e9t\u00e9 face \u00e0 la catastrophe \u00e9cologique qui est un des th\u00e8mes favoris des \u00ab\u00a0conversations\u00a0\u00bb dans ces r\u00e9gions.<\/p>\n<\/p>\n<p><p>&bull; Sa volont\u00e9 affich\u00e9e, officielle sinon bruyante, d&rsquo;aller vers un &laquo; <em>&Eacute;tat europ\u00e9en f\u00e9d\u00e9ral<\/em> &raquo; appara&icirc;t \u00e0 un moment o&ugrave;, effectivement, l&rsquo;id\u00e9e du f\u00e9d\u00e9ralisme europ\u00e9en est mis en cause dans de nombreux pays, et notamment en France, &ndash; malgr\u00e9 Macron et du fait de la radicalisation impos\u00e9e par Zemmour sur la question de l&rsquo;immigration o&ugrave; les institutions europ\u00e9ennes sont en pointe pour une lib\u00e9ralisation totale. M\u00eame un Macron doit se voir naviguer au plus pr\u00e8s malgr\u00e9 ses convictions europ\u00e9ennes, tant il va \u00eatre press\u00e9 sur cette question o&ugrave; le public r\u00e9clame une plus grande duret\u00e9 et une souverainet\u00e9 retrouv\u00e9e pour la France, &ndash; l&rsquo;archi-antith\u00e8se du f\u00e9d\u00e9ralisme.<\/p>\n<\/p>\n<p><p>Nuttall n&rsquo;a finalement pas tort lorsqu&rsquo;il \u00e9crit, \u00e0 la suite de la r\u00e9action du gouvernement hongrois :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>C&rsquo;est un commentaire vraiment int\u00e9ressant, car l&rsquo;UE obtient g\u00e9n\u00e9ralement ce qu&rsquo;elle veut lorsqu&rsquo;elle agit subrepticement. Lorsque ses plans d&rsquo;int\u00e9gration sont pr\u00e9sent\u00e9s au grand jour, ils sont g\u00e9n\u00e9ralement rejet\u00e9s. En effet, la derni\u00e8re fois que l&rsquo;UE a expos\u00e9 ses ambitions pour une Europe f\u00e9d\u00e9rale sous la forme d&rsquo;une Constitution europ\u00e9enne, l&rsquo;id\u00e9e a \u00e9t\u00e9 rejet\u00e9e en bloc par les Fran\u00e7ais et les N\u00e9erlandais lors de r\u00e9f\u00e9rendums.<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>A ce dernier argument sur les r\u00e9f\u00e9rendums de 2005, on observerait que ces votes furent rattrap\u00e9s par la trahison des \u00e9lites et la d\u00e9cision de Lisbonne d&rsquo;adopter la Constitution europ\u00e9enne. L\u00e0-dessus, on objecterait aussit\u00f4t que nous ne sommes vraiment plus en 2005-2008, et un d\u00e9bat aujourd&rsquo;hui, avec r\u00e9f\u00e9rendums ou pas, sur l&rsquo;institution d&rsquo;un f\u00e9d\u00e9ralisme-maxi provoquerait effectivement des tensions extraordinaires en Europe, jusqu&rsquo;\u00e0 certainement des ruptures. En ce sens, on comprend parfaitement l&rsquo;argument de Nuttall faisant du gouvernement Scholz et de son hyper-f\u00e9d\u00e9ralisme \u00e0 visage d\u00e9couvert, &laquo; <em>une menace majeure pour l&rsquo;UE<\/em> &raquo;.<\/p>\n<\/p>\n<p><p>On le comprend d&rsquo;autant plus qu&rsquo;on en vient \u00e0 se demander quelle mouche a piqu\u00e9 la nouvelle direction pour envisager de telles outrances ? (M\u00eame chose d&rsquo;ailleurs pour la quasi-\u00ab\u00a0militarisation\u00a0\u00bb de la lutte contre le Covid, &ndash; nous sommes donc bien &laquo; <em>en guerre <\/em>&raquo; ? &ndash; qui alimente \u00e0 sati\u00e9t\u00e9 toutes les interpr\u00e9tations les plus extr\u00eames sur les \u00ab\u00a0complots\u00a0\u00bb, la \u00ab\u00a0dictature sanitaire\u00a0\u00bb, l&rsquo;\u00e9tat d&rsquo;urgence jusqu&rsquo;au \u00ab\u00a0coup d&rsquo;&Eacute;tat\u00a0\u00bb, etc.).<\/p>\n<\/p>\n<p><p>Deux explications sont possibles, qui peuvent d&rsquo;ailleurs parfaitement se compl\u00e9ter ou bien cohabiter selon les circonstances.<\/p>\n<\/p>\n<p><p>&bull; Il y a d&rsquo;une part le sentiment g\u00e9n\u00e9ral, tr\u00e8s r\u00e9pandu, tr\u00e8s reconnu et d\u00e9nonc\u00e9 en France, de l&rsquo;absence compl\u00e8te d&rsquo;une perception raisonnable et acceptable de la r\u00e9alit\u00e9, notamment des sentiments populaires, par les \u00e9lites (allemandes, europ\u00e9ennes, etc.). En Allemagne, pays extr\u00eamement conformiste et totalement align\u00e9 sur la <em>doxa <\/em>dont nous sommes berc\u00e9s, cette situation est encore plus forte qu&rsquo;ailleurs et plus susceptibles de conduire ces \u00e9lites \u00e0 des d\u00e9cisions radicales saupoudr\u00e9es de certaines mesures radicales et arbitraires \u00e0 la fois. Emmitoufl\u00e9e dans sa vertu d\u00e9mocratique et sa repentance perp\u00e9tuelle particuli\u00e8rement en vogue dans cette \u00ab\u00a0gauche\u00a0\u00bb institutionnalis\u00e9e \u00e0 la limite du wokenisme, &ndash; autre point de convergence transatlantique, &ndash; l&rsquo;Allemagne \u00ab\u00a0de gauche\u00a0\u00bb n&rsquo;h\u00e9sitera certainement pas devant des mesures int\u00e9rieures, contre sa population, rappelant la brutalit\u00e9 de certaines p\u00e9riodes d&rsquo;antan.<\/p>\n<\/p>\n<p><p>&bull; Il y a d&rsquo;autre part l&rsquo;inverse, qui ne demande pas \u00e0 \u00eatre r\u00e9alis\u00e9 en toute conscience. A c\u00f4t\u00e9 de cette certitude de leur propre vertu d&rsquo;au-dessus les divers fascismes encombrant la voie publique, on veut ici parler d&rsquo;un sentiment de panique qui affleure parfois la perception des \u00e9lites devant la possibilit\u00e9 entrevue que les conditions crisiques colossales que nous connaissons, les dissidences, les r\u00e9bellions contre la bienpensance, puissent constituer des obstacles infranchissables pour la globalisation et la moralisation du monde. Ces moments de panique donnent alors l&rsquo;obligation d&rsquo;une allure extr\u00eamement pressante aux divers projets du &lsquo;<em>Meilleur des mondes<\/em>&lsquo;, &ndash; si n\u00e9cessaire \u00ab\u00a0le meilleur\u00a0\u00bb, avec son bonheur et sa vertu, \u00e9tant impos\u00e9 \u00e0 coups de trique. Rien ne vaut la \u00ab\u00a0gauche\u00a0\u00bb-allemande pour cette sorte d&rsquo;entreprise.<\/p>\n<\/p>\n<p><p>Panique ou non, perception raisonnable-acceptable ou pas, on reste objectivement confondu qu&rsquo;une nouvelle direction dans ce pays-clef qu&rsquo;est l&rsquo;Allemagne ressorte aujourd&rsquo;hui l&rsquo;immonde serpent de mer de la f\u00e9d\u00e9ralisation-maxi de l&rsquo;Europe. On pourrait observer, pour poursuivre dans l&rsquo;objectivit\u00e9, qu&rsquo;on ne trouverait pas mieux aujourd&rsquo;hui, si l&rsquo;on va au fond des choses et des cons\u00e9quences, comme mesure suicidaire, &ndash; pour l&rsquo;Europe et tout son train qui va avec et qui d\u00e9filerait ensuite. Nous allons donc terminer sur cette id\u00e9e en observant qu&rsquo;elle correspond parfaitement \u00e0 la fameuse \u00e9quation caract\u00e9ristique du Syst\u00e8me : surpuissance-autodestruction. Par cons\u00e9quent, nous sommes bien en route vers &lsquo;<em>Le meilleur des mondes<\/em>&lsquo;, puisque galopant vers l&rsquo;autodestruction.<\/p>\n<\/p>\n<p><p><a href=\"https:\/\/www.dedefensa.org\/article\/deconstructuration-du-deconstructeur\">D\u00e9constructuration<\/a> \u00e0 l&rsquo;allemande, certes, ce qui manquait \u00e0 notre floril\u00e8ge de ces temps-devenus-fous.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e9constructuration au pas de l&rsquo;oie &bull; Merkel s&rsquo;en est all\u00e9e ou est-elle sur le point de le faire, et d\u00e9j\u00e0 l&rsquo;on commence \u00e0 l&rsquo;oublier. &bull; Dans un pays qu&rsquo;on croit r\u00e9gl\u00e9 comme du papier \u00e0 musique depuis sa r\u00e9cup\u00e9ration d&rsquo;apr\u00e8s le sanglant apocalypse nazi, la succession d&rsquo;une Kaiserin qui a r\u00e9gn\u00e9 lourdement et avec ent\u00eatement&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[14176,2752,2824,3269,21305,4633,21307,21306,19588,21304,12917,6721],"class_list":["post-79988","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-baerbock","tag-covid","tag-europeen","tag-federalisme","tag-i-g","tag-merkel","tag-militarise","tag-nittall","tag-nordstream","tag-olaf","tag-scholz","tag-spd"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79988","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79988"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79988\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79988"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79988"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79988"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}