{"id":80022,"date":"2022-01-01T18:48:42","date_gmt":"2022-01-01T18:48:42","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2022\/01\/01\/du-plomb-complotiste-dans-laile-du-mrna\/"},"modified":"2022-01-01T18:48:42","modified_gmt":"2022-01-01T18:48:42","slug":"du-plomb-complotiste-dans-laile-du-mrna","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2022\/01\/01\/du-plomb-complotiste-dans-laile-du-mrna\/","title":{"rendered":"Du plomb complotiste dans l&rsquo;aile du mRNA"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Du plomb complotiste dans l&rsquo;aile du mRNA<\/h2>\n<\/p>\n<blockquote>\n<p><p>&bull; Le docteur Robert Malone vient d&rsquo;\u00eatre \u00ab\u00a0annul\u00e9\u00a0\u00bb&lsquo; par Tweeter (compte censur\u00e9 et ferm\u00e9), <strong>attirant le plus grand int\u00e9r\u00eat et la plus grande attention sur lui<\/strong>. &bull; Il faut dire que Malone est le cr\u00e9ateur, ou l&rsquo;un des cr\u00e9ateurs <strong>de la technologie mRNA (ARN messager) dont profitent les vaccins Pfizer et Moderna<\/strong> pour attaquer le virus du Covid. &bull; Ces derniers temps, Malone a condamn\u00e9 <strong>comme tr\u00e8s dangereux l&#8217;emploi de cette m\u00e9thode (de ce vaccin) pour les jeunes enfants<\/strong>. &bull; R\u00e9sultat : on le censure, on le met \u00e0 l&rsquo;index, <strong>on en fait un opposant radical<\/strong>.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>D&rsquo;abord, question pr\u00e9liminaire du jury : le docteur Robert Malone est-il un complotiste ? Tous les vigiles transgenres du domaine parisien et associ\u00e9s se sont aussit\u00f4t mis au travail. Ce fut la comp\u00e8te anti-conspi de la \u00ab\u00a0<a href=\"https:\/\/www.dedefensa.org\/article\/la-treve-des-confiseurs\">tr\u00eave des confiseurs<\/a>\u00ab\u00a0, couronn\u00e9e par l&rsquo;intervention censureuse de l&rsquo;avant-dernier jour de l&rsquo;ann\u00e9e complotiste 2021 de Tweeter fermant le compte du docteur Malone, comme on ferme le ban. L&rsquo;approbation fut positive \u00e0 plus de 120%  chez les bienpensants d\u00e9ployant, masques en bataille et \u00e0 distance sanitaire, des raisonnements complotistes pour mettre \u00e0 raison ce complotiste qui pr\u00e9tend \u00eatre l&rsquo;inventeur du mRNA (ARN messager) caract\u00e9risant les vaxx postmodernes, Pfizer et Moderna.<\/p>\n<\/p>\n<p><p>(A ce propos, voyez notre <a href=\"https:\/\/www.dedefensa.org\/article\/la-gauchisation-systeme-de-wikipedia\">excellentissime<\/a> anti-conspi &lsquo;<em><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Robert_Malone\">Wikip\u00e9dia<\/a><\/em>&lsquo;, un bon concentr\u00e9e de toutes les attaques possibles contre Malone jusqu&rsquo;\u00e0 son \u00ab\u00a0annulation\u00a0\u00bb vertueuse par Tweeter, le coupable-h\u00e9r\u00e9tique \u00e9tant d\u00e9fini comme une b\u00e9n\u00e9diction pour &laquo; <em>des personnalit\u00e9s complotistes anti-vaccination<\/em> &raquo;, selon une logique extr\u00eamement complotiste elle-m\u00eame ; laquelle se trouve <a href=\"https:\/\/www.conspiracywatch.info\/conspiracy-news-52-2021.html\">men\u00e9e tambours battants<\/a> par &lsquo;<em>Lib\u00e9<\/em>&lsquo; et son vaccin anti-<em>FakeNews <\/em>qui &laquo; <em>souligne<\/em> &raquo;, &ndash; eh ! eh ! eh !, &ndash; que Malone &laquo; <em>travaille sur un vaccin pour le compte d&rsquo;un groupe pharmaceutique indien concurrent de Pfizer et de Moderna<\/em>&hellip; &raquo;, ce qui repr\u00e9sente un excellent argument complotiste anti-complotiste, \u00e0 partir de preuves &lsquo;<em>fact-ch\u00e9k\u00e9es<\/em>&lsquo; par des anti-complotistes complotistes.)<\/p>\n<\/p>\n<p><p>De quoi s&rsquo;agit-il ? Citons <a href=\"https:\/\/francais.rt.com\/international\/94200-twitter-suspend-compte-docteur-robert-malone-pionnier-arn-messager\">une source<\/a> ind\u00e9niablement suspecte, puisque mitonn\u00e9e quasi-directement par Poutine, dont Malone est sans doute l&rsquo;agent vaxx-007.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Ce 30 d\u00e9cembre dans l&rsquo;apr\u00e8s-midi, <a href=\"https:\/\/twitter.com\/RWMaloneMD\">le compte<\/a> du docteur Robert Malone n&rsquo;\u00e9tait plus accessible depuis plusieurs heures sur Twitter, o&ugrave; il \u00e9tait suivi par environ 516 000 followers. Robert Malone est un biologiste mol\u00e9culaire, \u00e9pid\u00e9miologiste, et sp\u00e9cialiste des maladies infectieuses ayant travaill\u00e9 sur l&rsquo;ARN messager. Il est \u00e0 l&rsquo;origine de la d\u00e9couverte de la capacit\u00e9 de celui-ci \u00e0 p\u00e9n\u00e9trer dans des cellules humaines et \u00e0 les conduire \u00e0 produire des prot\u00e9ines : une avanc\u00e9e qui a permis le d\u00e9veloppement ult\u00e9rieur des vaccins \u00e0 ARN &ndash; comme ceux contre le Covid-19 de Pfizer\/BioNTech et de Moderna. Twitter n&rsquo;a pas comment\u00e9 dans l&rsquo;imm\u00e9diat cette suspension.  <\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Sur son compte <a href=\"https:\/\/t.me\/RWMaloneMD\/1041\">Telegram<\/a>, Robert Malone a r\u00e9agi \u00e0 la nouvelle en ces termes : \u00ab\u00a0Cela signifie<\/em> [&#8230;] <em>que nous avons perdu un \u00e9l\u00e9ment essentiel dans notre combat pour emp\u00eacher que ces vaccins soient impos\u00e9s aux enfants et pour mettre fin \u00e0 la corruption de nos gouvernements, ainsi que du complexe m\u00e9dico-industriel et des industries pharmaceutiques\u00a0\u00bb.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Au cours de la pand\u00e9mie, Robert Malone est apparu comme un critique de nombre de politiques mises en &oelig;uvre afin de lutter contre la propagation du Covid-19. S&rsquo;il recommande la vaccination des populations \u00e0 risque &ndash; telles que les personnes \u00e2g\u00e9es ou celles souffrant de comorbidit\u00e9s &ndash; et a d\u00e9clar\u00e9 s&rsquo;\u00eatre personnellement fait vacciner en raison de son \u00e2ge, il estime en revanche que chez les sujets jeunes et chez les enfants, les risques de la vaccination contre le Covid-19 \u00e0 l&rsquo;aide de vaccins \u00e0 ARN l&#8217;emportent sur les avantages.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Comme le souligne &lsquo;<a href=\"https:\/\/www.liberation.fr\/checknews\/que-sait-on-de-la-nouvelle-video-de-robert-malone-pionnier-de-larn-messager-et-oppose-a-la-vaccination-des-enfants-20211222_SPGBKR5WTVASVJ2RBYYFXZXUBY\/?redirected=1\">Lib\u00e9ration<\/a>&lsquo;, Robert Malone promeut par ailleurs pour le compte du conglom\u00e9rat Reliance Life Sciences un <a href=\"https:\/\/www.youtube.com\/watch?v=_OygHCE9F2A\">vaccin anti-Covid<\/a> \u00ab\u00a0traditionnel\u00a0\u00bb, RelCovaxTM, \u00ab\u00a0concurrent\u00a0\u00bb des vaccins \u00e0 ARN messager<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>L\u00e0-dessus, toujours dans l&rsquo;ann\u00e9e covidienne-conspi 2021, mais au dernier jour de celle-ci, c&rsquo;est-\u00e0-dire hier, Malone est pass\u00e9 pour une <a href=\"https:\/\/open.spotify.com\/episode\/3SCsueX2bZdbEzRtKOCEyT\">tr\u00e8s-longue interview<\/a> du tr\u00e8s-fameux &lsquo;podcasteur&rsquo; (ainsi nomme-t-on les solistes de l&rsquo;interview radiodiffus\u00e9e sur internet) Joe Rogan. En g\u00e9n\u00e9ral assez antivaxx, Rogan, podcasteur n&deg;1 toutes cat\u00e9gories pour les interviews politiques, attire des auditeurs par millions, comme il est pr\u00e9cis\u00e9 dans la nouvelle concernant cette \u00e9mission sur &lsquo;<em><a href=\"https:\/\/www.wnd.com\/2021\/12\/dr-robert-malone-spends-3-hours-joe-rogan-twitter-ban\/\">WorldNetDaily<\/a><\/em>&lsquo;. On en donne un extrait pour la saveur de la chose. (Voir aussi des d\u00e9tails sur l&rsquo;interview lui-m\u00eame dans &lsquo;<a href=\"https:\/\/www.zerohedge.com\/covid-19\/covid-ivermectin-and-mass-formation-psychosis-dr-robert-malone-gives-blistering-interview\"><em>ZeroHedge.com<\/em><\/a>&lsquo;.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>&Agrave; la suite de son bannissement de Twitter, apparemment pour avoir contredit le r\u00e9cit du gouvernement sur le COVID-19, l&rsquo;interview tr\u00e8s attendue du Dr Robert Malone avec le podcasteur Joe Rogan <a href=\"\/%C2%BB\">a \u00e9t\u00e9 publi\u00e9e<\/a>.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>L&rsquo;inventeur du vaccin qui a jou\u00e9 un r\u00f4le crucial dans le d\u00e9veloppement de la technologie ARNm derri\u00e8re les vaccins Pfizer et Moderna a discut\u00e9 de la censure des m\u00e9dias sociaux au d\u00e9but de la discussion de trois heures sur &lsquo;The Joe Rogan Experience&rsquo;, publi\u00e9e vendredi par Spotify.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Une <a href=\"https:\/\/open.spotify.com\/episode\/0aZte37vtFTkYT7b0b04Qz\">r\u00e9cente interview<\/a> d&rsquo;un autre grand critique des vaccins et des politiques du COVID, le Dr Peter McCullough, a \u00e9t\u00e9 <strong>la plus importante jamais r\u00e9alis\u00e9e par Joe Rogan<\/strong>, attirant \u00e0 ce jour <strong>plus de 40 millions d&rsquo;auditeurs<\/strong>.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Apr\u00e8s avoir d\u00e9taill\u00e9 le r\u00f4le \u00e9minent de Malone dans le d\u00e9veloppement et la distribution des vaccins au cours des 30 derni\u00e8res ann\u00e9es, y compris sa relation personnelle avec le Dr Anthony Fauci &#8211; a observ\u00e9 que Twitter a banni mercredi \u00ab\u00a0l&rsquo;une des personnes les plus qualifi\u00e9es au monde pour parler des vaccins\u00a0\u00bb.<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Quoi que puissent dire nos petites mains censureuses et pleines de ciseaux, le cas Malone est important, parce qu&rsquo;il est l&rsquo;un des cr\u00e9ateurs du vaccin si contest\u00e9, et peut-\u00eatre le principal cr\u00e9ateur. C&rsquo;est peut-\u00eatre la raison principale qui fait se d\u00e9velopper une vague si consid\u00e9rable de <em>fact-chekings <\/em>et autres d\u00e9nonciations, \u00e0 un moment o&ugrave; vraiment la stabilit\u00e9 du soutien aux vaccins en action, et \u00e0 la vaccination en g\u00e9n\u00e9ral, se trouve en grand danger.<\/p>\n<\/p>\n<p><p>(On remarque d&rsquo;ailleurs, \u00e0 cette occasion pour notre cas car nous n&rsquo;avons pas l&rsquo;habitude de nous aventurer dans ce labyrinthe des vigilances censureuses d\u00e9velopp\u00e9es un peu partout dans la presseSyst\u00e8me, l&rsquo;esp\u00e8ce d&rsquo;enthousiasme faraud pour ce travail de censure et de d\u00e9nonciation dans les officines <em>ad hoc<\/em> de la presseSyst\u00e8me. Du moment que la vertu est du voyage, l&rsquo;enthousiasme d&rsquo;un stakhanovisme d\u00e9cha&icirc;n\u00e9 triomphe. Les fouineurs tordent et retordent les citations et les liens URL, les saupoudrant d&rsquo;un mot qui vaut par ses sous-entendus, d&rsquo;une ponctuation ad\u00e9quate et qui en dit long [la magie des trois petits points qui laissent tellement \u00e0 entendre qu&rsquo;il n&rsquo;est nul besoin de comprendre, et encore moins de savoir]. Quelqu&rsquo;un \u00e0 l&rsquo;esprit horriblement mal tourn\u00e9, que nous d\u00e9non\u00e7ons et r\u00e9futons d&rsquo;avance, pourrait dire, comme nous l&rsquo;avons peut-\u00eatre entendu : \u00ab\u00a0&lsquo;<em>LeMonde-Lib\u00e9<\/em>&lsquo; d\u00e9nonce les antivaxx et les critiques, et les complotistes ou suppos\u00e9s tels, avec autant de z\u00e8le que &lsquo;<em>Je Suis Partout<\/em>&lsquo; d\u00e9non\u00e7ait les juifs.\u00a0\u00bb)<\/p>\n<\/p>\n<p><p>Tout cela conduit \u00e0 des remarques d&rsquo;un ordre plus g\u00e9n\u00e9ral, \u00e0 la fois sur le cas Malone \u00e9largi \u00e0 la connaissance g\u00e9n\u00e9rale, \u00e0 la fois sur la pratique affectionn\u00e9e par les petits g\u00e9nies de la censure que sont les g\u00e9ants des GAFAM. On prendra les susdites remarques dans l&rsquo;ordre inverse de celui qu&rsquo;on suivi pour les pr\u00e9senter.<\/p>\n<\/p>\n<p><p>&bull; La d\u00e9cision de bloquer le compte d&rsquo;un savant aussi impliqu\u00e9 dans la cr\u00e9ation des vaccins en vogue, et qui met en question l&rsquo;universalit\u00e9 de leurs bienfaits, suscite un <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-leffet-janus\">effet-<em>Janus<\/em><\/a> consid\u00e9rable. La communication se retourne contre celui qui en a fait usage, &ndash; qui en a fait mauvais usage, car c&rsquo;est l\u00e0 que joue \u00e0 plein cet &lsquo;\u00a0\u00bbeffet-Janus\u00a0\u00bb. Les doux petits g\u00e9nies-stupides de <em>Silicon Valley<\/em>, qui croient tenir le monde dans leurs mains, qui d\u00e9bitent des \u00e9vidences moralinesques (comme l&rsquo;on dit \u00ab\u00a0chapelinesques\u00a0\u00bb) d&rsquo;une affligeante na\u00efvet\u00e9, n&rsquo;ont toujours pas compris que leur \u00ab\u00a0r\u00e9volution\u00a0\u00bb est plut\u00f4t dans l&rsquo;espace que dans l&rsquo;histoire et que, comme un orbe parfait, elle leur revient en pleine face, &ndash; ou en pleine poire.<\/p>\n<\/p>\n<p><p>Qui, dans la communication g\u00e9n\u00e9rale et globale, s&rsquo;int\u00e9ressait vraiment au docteur Malone avant qu&rsquo;il e&ucirc;t \u00e9t\u00e9 \u00ab\u00a0annul\u00e9\u00a0\u00bb ? Aujourd&rsquo;hui, tout le monde en parle et, quoi qu&rsquo;il en soit demain, le voil\u00e0 mobilis\u00e9 dans les bataillons de la dissidence. Il faut comprendre qu&rsquo;\u00e0 l&rsquo;heure de la communication comme seule-force-v\u00e9ridique du monde, tout est volatilit\u00e9, tout est insaisissabilit\u00e9, y compris pour toutes les fortunes-GAFAM des milliers de $milliards du monde ; tout vous \u00e9chappe, rien ne tient, la communication comme ce savon glissant sur le sol mouill\u00e9 comme des rochers lisses couverts de sargasses qui vont et viennent dans la mar\u00e9e de l&rsquo;aube au cr\u00e9puscule et jusqu&rsquo;\u00e0 l&rsquo;aube recommenc\u00e9e. Dans cette sorte d&rsquo;occurrence, il ne faut pas tenter de jouer au plus malin, m\u00eame lorsqu&rsquo;on est un petit g\u00e9nie-stupide. La seule fa\u00e7on de jouer est de miser sur <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-verite-de-situation-verite\">la v\u00e9rit\u00e9-de-situation<\/a>, et non pas de la tripatouiller en voulant la dissimuler.<\/p>\n<\/p>\n<p><p>&bull; D&rsquo;o&ugrave; il se trouve d\u00e9sormais que le docteur Malone est entr\u00e9 \u00ab\u00a0en dissidence\u00a0\u00bb, quel qu&rsquo;en soit son d\u00e9sir, quelle que soit la justesse de son jugement, quel que soit son d\u00e9sint\u00e9r\u00eat bien compr\u00e9hensible pour les fous du complotisme, et il joue sa partition dans ce qui, dans le travail de r\u00e9sistance de la dissidence, se constitue en antiSyst\u00e8me. (Car, on le sait, il y a beaucoup de pr\u00e9tendants qui pensent qu&rsquo;il suffit de se proclamer  pour \u00eatre choisis, et bien peu d&rsquo;\u00e9lus.)<\/p>\n<\/p>\n<p><p>Ainsi Covid poursuit-il son travail de termites, contribuant \u00e0 la politisation g\u00e9n\u00e9rale de cas qui devraient normalement relever des seuls domaines non-politis\u00e9s o&ugrave; on les voit na&icirc;tre. Et cette politisation se fait \u00e9videmment par l&rsquo;extr\u00eame, accentuant \u00e0 la fois la fracture s\u00e9parant les deux blocs d&rsquo;opposants qui ne cessent de se constituer et de s&rsquo;alimenter, et se servant de tout accident pour affirmer leur radicalit\u00e9.<\/p>\n<\/p>\n<p><p>&bull; Il y a effectivement, comme des voix de plus en plus nombreuses le proclament, une d\u00e9rive autoritaire ou tyrannique de la part des d\u00e9fenseurs du Syst\u00e8me lorsqu&rsquo;ils se regroupent au sein des gouvernements, mais cette d\u00e9rive se fait sous la pression d&rsquo;\u00e9v\u00e9nements \u00e9chappant \u00e0 tout contr\u00f4le. Cet autoritarisme se forme sans avantage direct ni m\u00eame int\u00e9r\u00eat pour ceux qui l&rsquo;activent, servant essentiellement \u00e0 fournir des arguments critiques \u00e0 leurs adversaires et \u00e0 alimenter les extr\u00e9mistes. Au d\u00e9part, Malone, personnage prestigieux, n&rsquo;est en rien un dissident ni un extr\u00e9miste ; sa position s&rsquo;est affirm\u00e9e plut\u00f4t moyenne dans la cacophonie-Covid, puisqu&rsquo;il s&rsquo;oppose au vaccin pour les enfants et nullement pour les personnes \u00e2g\u00e9es. Mais les r\u00e9actions autoritaires et tyranniques (censure, \u00ab\u00a0annulation\u00a0\u00bb par Tweeter, discr\u00e9dit et diffamation pour justifier cette \u00ab\u00a0annulation\u00a0\u00bb) le pr\u00e9cipitent dans la dissidence et dans l&rsquo;activisme <em>de facto<\/em>, par simple effet-<em>Janus <\/em>de communication.<\/p>\n<\/p>\n<p><p>L&rsquo;effet de cet \u00e9volution devrait \u00eatre de rendre les positions plus activistes, malgr\u00e9 l&rsquo;\u00e9volution d\u00e9l\u00e9t\u00e8re de ces derni\u00e8res ann\u00e9es qui semblerait conduire \u00e0 une sorte d'\u00a0\u00bbasservissement volontaire\u00a0\u00bb ; mais cet \u00ab\u00a0asservissement volontaire\u00a0\u00bb existait avant cette \u00e9volution due \u00e0 l&rsquo;affrontement du Covid, elle est mise en \u00e9vidence par le Covid, elle conduit \u00e0 augmenter les tendances activistes parall\u00e8lement \u00e0 l&rsquo;autoritarisme pour conduire \u00e0 des antagonismes non volontaires et non pr\u00e9par\u00e9s, qui brouillent compl\u00e8tement la situation. En France, cette \u00e9volution devrait appara&icirc;tre au grand jour \u00e0 l&rsquo;occasion de l&rsquo;\u00e9lection du pr\u00e9sident de la R\u00e9publique, et surtout apr\u00e8s ; aux USA, o&ugrave; la situation est d\u00e9j\u00e0 plus grave que la situation fran\u00e7aise, cette \u00e9volution se fera \u00e0 l&rsquo;occasion des \u00e9lections l\u00e9gislatives de &lsquo;<em>mid-term<\/em>&lsquo;.<\/p>\n<\/p>\n<p><p>Mis en ligne le 1<sup>er<\/sup> janvier 2022 \u00e0 18H50<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Du plomb complotiste dans l&rsquo;aile du mRNA &bull; Le docteur Robert Malone vient d&rsquo;\u00eatre \u00ab\u00a0annul\u00e9\u00a0\u00bb&lsquo; par Tweeter (compte censur\u00e9 et ferm\u00e9), attirant le plus grand int\u00e9r\u00eat et la plus grande attention sur lui. &bull; Il faut dire que Malone est le cr\u00e9ateur, ou l&rsquo;un des cr\u00e9ateurs de la technologie mRNA (ARN messager) dont profitent les&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[2826,11525,2752,21363,21361,21360,21093,3134,15353,21085],"class_list":["post-80022","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-censure","tag-complotistes","tag-covid","tag-fact-checkers","tag-melone","tag-moderna","tag-pfizer","tag-robert","tag-tweeter","tag-vaccination"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=80022"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80022\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=80022"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=80022"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=80022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}