{"id":80042,"date":"2022-01-20T09:58:44","date_gmt":"2022-01-20T09:58:44","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2022\/01\/20\/defi-cosmique\/"},"modified":"2022-01-20T09:58:44","modified_gmt":"2022-01-20T09:58:44","slug":"defi-cosmique","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2022\/01\/20\/defi-cosmique\/","title":{"rendered":"D\u00e9fi cosmique"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">D\u00e9fi cosmique<\/h2>\n<\/p>\n<p><p>20 janvier 2022 &ndash; La chronique &lsquo;du jour&rsquo; (<a href=\"https:\/\/www.dedefensa.org\/article\/deni-cosmique-il-ny-a-plus-de-pilote\">d&rsquo;hier<\/a>) de Dimitri Orlov tombe fort bien pour me relancer dans un projet pourtant \u00e9vident que j&rsquo;avais pourtant laiss\u00e9 de c\u00f4t\u00e9. J&rsquo;ai vu le film &laquo; <em>Don&rsquo;t Look Up<\/em> &raquo; assez rapidement apr\u00e8s sa diffusion-Netflix, sans doute le 26 ou le 27 d\u00e9cembre 2021 ; aussit\u00f4t, je m&rsquo;\u00e9tais chuchot\u00e9 que ce film m\u00e9ritait quelque r\u00e9flexion. Le constat imm\u00e9diat \u00e9tait effectivement qu&rsquo;il m\u00e9ritait qu&rsquo;on s&rsquo;y attach\u00e2t parce qu&rsquo;il constitue une \u00e9nigme par rapport \u00e0 la matrice (am\u00e9ricaniste) qui l&rsquo;a produit, aussi bien par son intrigue satirique que par les perspectives qu&rsquo;il donne \u00e0 cette intrigue, &ndash; tout cela, comme l&rsquo;a bien vu Orlov :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Il est int\u00e9ressant de noter que, dans son effort de mettre en \u00e9vidence tous les maux de la soci\u00e9t\u00e9 am\u00e9ricaine, ce film n&rsquo;essaie pas du tout d&rsquo;indiquer une voie vers la gu\u00e9rison et un avenir meilleur, se d\u00e9barrassant ainsi de la perspective optimiste que Hollywood consid\u00e9rait auparavant comme obligatoire : il n&rsquo;y a m\u00eame pas l&rsquo;ombre d&rsquo;une fin heureuse<\/em>&#8230; [&#8230;]<\/p>\n<\/p>\n<p><p>&raquo; <em>Avant que vous ne vous imaginiez que je suis une sorte de voix solitaire qui crie dans le d\u00e9sert, laissez-moi vous rassurer : parmi les nombreux critiques de ce film, plusieurs ont mentionn\u00e9 qu&rsquo;il leur avait laiss\u00e9 un sentiment de vide, un sentiment d&rsquo;\u00e9chec et d&rsquo;\u00e9garement d&ucirc; \u00e0 l&rsquo;absence de sens et \u00e0 la stupidit\u00e9 de tout ce qui leur \u00e9tait montr\u00e9. En effet, l&rsquo;absence totale de perspective positive et optimiste dans le film est peut-\u00eatre sans pr\u00e9c\u00e9dent dans le cin\u00e9ma am\u00e9ricain grand public, qui exige imp\u00e9rativement une fin heureuse. Encore une fois, n&rsquo;oubliez pas que le film est sorti pr\u00e9cis\u00e9ment la veille de No\u00ebl, le 24 d\u00e9cembre 2021, la f\u00eate familiale de l&rsquo;ann\u00e9e o&ugrave; l&rsquo;on se sent bien ! Qu&rsquo;est-ce que c&rsquo;est ? Un acte de terrorisme culturel ?<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>De m\u00eame, je n&rsquo;ai ressenti \u00e0 aucun moment, \u00e9galement de la m\u00eame fa\u00e7on qu&rsquo;Orlov, que ce film constitu\u00e2t un argument pour la sublime et grandissime cause \u00e9cologique, pour un effort formidable et collectif de sauvegarde de la plan\u00e8te (et du reste, c&rsquo;est-\u00e0-dire nous, les autres et moi), comme cela a \u00e9t\u00e9 en g\u00e9n\u00e9ral ressenti par les belles \u00e2mes vivant dans leur simulacre.<\/p>\n<\/p>\n<p><p>(Cette vertueuse fa\u00e7on de voir et d&rsquo;entendre a \u00e9t\u00e9 largement expos\u00e9e lors d&rsquo;une soir\u00e9e du &lsquo;<em>28 Minutes<\/em>&lsquo; de Arte qui fut une d\u00e9bauche dionysiaque, une bacchanale des satyres femelles et vertueuses du camp du Bien ; je crois [impossible de v\u00e9rifier, la Belgique est priv\u00e9e d&rsquo;acc\u00e8s aux archives, ou est-ce un complot contre moi seulement ?] qu&rsquo;il s&rsquo;agit de la soir\u00e9e du <a href=\"https:\/\/www.programme-television.org\/replay\/28-minutes\/2022-01-11-1074420460\">11 janvier<\/a>.)<\/p>\n<\/p>\n<p><p>Effectivement, si cela constituait une d\u00e9monstration <em>a contrario<\/em> et <em>ad absurdo <\/em>pour la cause \u00e9cologique, cela montrait essentiellement que rien ne pourrait \u00eatre fait avec ce Syst\u00e8me que, par ailleurs, les \u00e9colos-mondains ne cessent de ch\u00e9rir et d&rsquo;acclamer, &ndash; ces gens \u00ab\u00a0ch\u00e9rissant les causes des effets qu&rsquo;ils maudissent\u00a0\u00bb, comme disait une des versions de ce que disait Bossuet&#8230; D&rsquo;accord avec Orlov, moi-m\u00eame selon <a href=\"https:\/\/www.dedefensa.org\/article\/le-climat-phg-ddeorg\">l&rsquo;id\u00e9e plus pr\u00e9cise<\/a> que cette \u00e9ventuelle catastrophe environnementale, comme les autres, est le produit du Syst\u00e8me et ne pourrait \u00eatre \u00e9vit\u00e9e, si elle existe, que par la liquidation de ce Syst\u00e8me, &ndash; puisque l&rsquo;action du Syst\u00e8me ne serait qu&rsquo;une ni\u00e8me version de l&rsquo;incendiaire d\u00e9versant du k\u00e9ros\u00e8ne d\u00e9guis\u00e9 en eau sur l&rsquo;incendie.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Presque tous les critiques que j&rsquo;ai lus sont tomb\u00e9s dans le pi\u00e8ge de penser que ce film promeut l&rsquo;agenda \u00e9cologique \u00e0 la mode. D&rsquo;une certaine mani\u00e8re, ils ne comprennent pas que la promotion d&rsquo;un programme \u00e9cologiste par le biais d&rsquo;un film catastrophe dont la fin est absolument d\u00e9sesp\u00e9r\u00e9e et o&ugrave; toute vie sur la plan\u00e8te meurt est un non-sens \u00e9vident. Au contraire, ce film (ou, plus pr\u00e9cis\u00e9ment, sa fin apocalyptique) v\u00e9hicule un message anti-environnemental des plus franc : \u00e9tant donn\u00e9 la fin in\u00e9vitable de toute vie sur Terre, \u00e0 quoi bon essayer de sauver l&rsquo;environnement ?<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Au-del\u00e0, et ayant \u00e9cart\u00e9 toutes les autres interpr\u00e9tations (y compris, celle inratable d&rsquo;en faire une satire antiTrump : la pr\u00e9sidente, jou\u00e9e par Meryl Street, est beaucoup plus une caricature de ce qu&rsquo;aurait \u00e9t\u00e9 [et sera peut-\u00eatre ?!] Hillary Clinton \u00e0 la Maison-Blanche, que de Trump), Orlov conclut sans conclure. La fin, cette lettre de l'\u00a0\u00bb&Eacute;tat-profond\u00a0\u00bb, nous disant : \u00ab\u00a0D\u00e9sol\u00e9, les gars, nous avons merd\u00e9, tout s&rsquo;effondre et nous n&rsquo;y pouvons rien\u00a0\u00bb, est peut-\u00eatre le vrai sens du film mais il ne nous dit pas pourquoi le film a \u00e9t\u00e9 fait, &ndash; pourquoi l&rsquo;on a laiss\u00e9 faire ce film, parce qu&rsquo;il n&rsquo;est en rien dans les habitudes de l'\u00a0\u00bb&Eacute;tat-profond\u00a0\u00bb, alias le Syst\u00e8me, de nous dire qu&rsquo;il s&rsquo;est tromp\u00e9, parce qu&rsquo;il ne se trompe jamais, parce qu&rsquo;il se d\u00e9sint\u00e8grera en clamant qu&rsquo;il est plus fort et plus solide, et plus int\u00e9gr\u00e9 que jamais, car l&rsquo;on ne d\u00e9constructure pas un <a href=\"https:\/\/www.dedefensa.org\/article\/deconstructuration-du-deconstructeur\">d\u00e9constructurateur<\/a> en train de se d\u00e9constructurer ! Non mais..<\/p>\n<\/p>\n<p><p>Quelques mots de la lettre de l'\u00a0\u00bb&Eacute;tat-profond\u00a0\u00bb recueillie par Orlov :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Chers citoyens de l&rsquo;humanit\u00e9 civilis\u00e9e qui croit encore que les &Eacute;tats-Unis sont le centre du monde et la riche Shining City on the Hill (de dollars US de plus en plus sans valeur) : apparemment, nous avons tous ensemble approch\u00e9 le bord d&rsquo;un ab&icirc;me et sommes sur le point, peut-\u00eatre d\u00e8s cette ann\u00e9e, de nous y effondrer. Pourquoi cette triste fin est-elle arriv\u00e9e, malgr\u00e9 le fait que nous, vos dirigeants intr\u00e9pides, ma&icirc;tres du dollar am\u00e9ricain, serviteurs d\u00e9vou\u00e9s du Prince de ce Monde, avons tenu tous les leviers de la gouvernance mondiale entre nos mains \u00e0 partir de 1991, lorsque l&rsquo;URSS a cess\u00e9 d&rsquo;exister ?<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Comment avons-nous r\u00e9ussi \u00e0 nous planter \u00e0 ce point en seulement 30 ans ? La r\u00e9ponse est : parce que nous sommes devenus une bande de d\u00e9g\u00e9n\u00e9r\u00e9s. &Agrave; quoi ressemble notre d\u00e9g\u00e9n\u00e9rescence ? Pour plus de d\u00e9tails, voir notre film &lsquo;Don&rsquo;t Look Up&rsquo;. Il s&rsquo;agit d&rsquo;une exposition honn\u00eate du genre de monstres d\u00e9g\u00e9n\u00e9r\u00e9s que nous sommes devenus, y compris les militaires, les politiciens, les scientifiques, l&rsquo;\u00e9lite des m\u00e9dias&hellip; Nous sommes tous des monstres &ndash; des monstres d\u00e9go&ucirc;tants, d\u00e9g\u00e9n\u00e9r\u00e9s, r\u00e9pugnants!<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Comme on voit, et comme on le comprend bien en raison de son talent de satiriste, Orlov termine par une pirouette qui n&rsquo;est pas la r\u00e9solution de l&rsquo;\u00e9nigme : pourquoi, dans les locaux d&rsquo;une des puissances du syst\u00e8me hollywoodien de communication, a-t-on fait ce film qui est une parabole d\u00e9crivant l&rsquo;effondrement catastrophique du Syst\u00e8me (et du reste, nous compris) du fait de l&rsquo;activit\u00e9 catastrophique du Syst\u00e8me ? Je ne peux accepter l&rsquo;id\u00e9e d&rsquo;une volont\u00e9 d\u00e9lib\u00e9r\u00e9e, comme fait Orlov au nom de la satire, mais qui justement reste une satire.<\/p>\n<\/p>\n<p><p>Pour mon compte, ma principale r\u00e9action devant ce film fut qu&rsquo;il s&rsquo;agissait d&rsquo;une description parfaite du processus constant de schizophr\u00e9nie psychopathique dans lequel vit le Syst\u00e8me, c&rsquo;est-\u00e0-dire le monde lui-m\u00eame, dans ses pratiques, ses directions, ses puissances, avec dans ses marges incertaines une \u00ab\u00a0dissidence\u00a0\u00bb qui, &ndash; tout en poussant dans le m\u00eame sens de l&rsquo;autodestruction, bien entendu, dans la mesure de ses moyens, &ndash; ne fait que r\u00e9p\u00e9ter, incr\u00e9dule :\u00a0\u00bbMais comment peuvent-ils se conduire comme cela, vers leur perte, leur autodestruction ?\u00a0\u00bb<\/p>\n<\/p>\n<p><p>Car le plus impressionnant est effectivement cette fa\u00e7on extraordinaire, non pas de mettre en doute la nouvelle de l&rsquo;arriv\u00e9 de la com\u00e8te et de la destruction universelle qu&rsquo;elle nous promet dans les six mois, mais bien d&rsquo;accueillir cela en disant : \u00ab\u00a0Bon d&rsquo;accord, on va voir le probl\u00e8me [on va \u00ab\u00a0\u00e9valuer et aviser\u00a0\u00bb], mais en attendant il y a la question des \u00e9lections&#8230; On se reverra, certainement !\u00a0\u00bb. A aucun moment, les porteurs de la terrible nouvelle ne sont d\u00e9nigr\u00e9s, ridiculis\u00e9s, mis en cause, ni ne rencontrent le moindre scepticisme. Tout le monde prend assez vite la chose pour du comptant puis l&rsquo;\u00e9jecte sur les marges, c&rsquo;est dans six mois, et la vie continue, \u00e0 toute vitesse, selon les nouvelles du jour qui sont n\u00e9cessairement les plus importantes selon la logique m\u00e9diatique&#8230;<\/p>\n<\/p>\n<p><p>Par exemple, comme &lsquo;<em><a href=\"https:\/\/en.wikipedia.org\/wiki\/Don%27t_Look_Up\">Wikip\u00e9dia<\/a><\/em>&lsquo; nous fait le r\u00e9sum\u00e9 du film, ici un extrait o&ugrave; l&rsquo;on voit l&rsquo;entrem\u00ealement d\u00e9risoire des incidences accessoires o&ugrave; tente de s&rsquo;imbriquer la tentative de la r\u00e9alit\u00e9 catastrophique, &ndash; mais il n&rsquo;y a pas de fissure dans ce bloc de certitudes successives dans sa marche vers l&rsquo;autodestruction :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; &#8230;<em>Accompagn\u00e9es du Dr Teddy Oglethorpe, chef du Bureau de coordination de la d\u00e9fense plan\u00e9taire de la NASA, Dibiasky et Mindy<\/em> [les deux scientifiques ayant identifi\u00e9 la com\u00e8te] <em>pr\u00e9sentent leurs conclusions \u00e0 la Maison Blanche. Ils se heurtent \u00e0 l&rsquo;apathie de la pr\u00e9sidente Janie Orlean et de son fils, le chef de cabinet Jason<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>Oglethorpe incite Dibiasky et Mindy \u00e0 fuiter la nouvelle aux m\u00e9dias, ce qu&rsquo;ils font dans un talk-show fameux du matin. Lorsque les animateurs Jack Bremmer et Brie Evantee traitent le sujet de mani\u00e8re frivole, Dibiasky perd son sang-froid et fulmine \u00e0 propos de la menace, suscitant de nombreuses moqueries en ligne. Le petit ami de Dibiasky la d\u00e9nonce publiquement tandis que Mindy re\u00e7oit l&rsquo;approbation du public pour son &lsquo;look&rsquo; attractif. La nouvelle de la menace de la com\u00e8te ne retient gu\u00e8re l&rsquo;attention du public et est d\u00e9mentie par la directrice de la NASA <\/em>[alors que les techniciens de la NASA ont confirm\u00e9 l&rsquo;existence de la com\u00e8te]<em>, une donatrice importante de la pr\u00e9sidente Orlean sans aucune formation astronomique <\/em>[elle est anesth\u00e9siste]<em>. Lorsque Orlean est impliqu\u00e9e dans un scandale sexuel avec son candidat \u00e0 la Cour supr\u00eame, elle d\u00e9cide de d\u00e9tourner l&rsquo;attention et d&rsquo;am\u00e9liorer son indice de popularit\u00e9 en confirmant la menace de la com\u00e8te et en annon\u00e7ant un projet pour frapper et d\u00e9tourner la com\u00e8te \u00e0 l&rsquo;aide d&rsquo;armes nucl\u00e9aires<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Nous ne savons pas ce que signifie ce film, ce qu&rsquo;il d\u00e9nonce, pourquoi il est fait comme un \u00e9corchement, un d\u00e9piautage du fonctionnement du Syst\u00e8me par le fait des choses absolument catastrophiques qu&rsquo;il met \u00e0 nu et \u00e0 jour parall\u00e8lement. Le producteur, sc\u00e9nariste et r\u00e9alisateur lui-m\u00eame donne une explication renvoyant \u00e0 l&rsquo;hypoth\u00e8se \u00e9cologique, &ndash; la crise climatique censur\u00e9e par la presseSyst\u00e8me, quelle gal\u00e9jade ! Comme si l&rsquo;on pouvait faire l&rsquo;impasse sur Greta Thunberg, non mais ! Cette hypoth\u00e8se que nous avons \u00e9cart\u00e9e, parce que rien ne montre qu&rsquo;elle soit fond\u00e9e en aucune fa\u00e7on, sinon les belles pens\u00e9es du camp du Bien&#8230; M\u00eame s&rsquo;il a fait un film \u00e9tonnant parce qu&rsquo;iconoclaste, Adam MacKay a aussi plant\u00e9 sa tente dans le camp du Bien, comme il y a des camps de migrants et qu&rsquo;on a une garantie \u00e0 prendre en m\u00eame temps qu&rsquo;une conviction facile.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Ce film est n\u00e9 de ma terreur grandissante \u00e0 l&rsquo;\u00e9gard de la crise climatique et du fait que nous vivons dans une soci\u00e9t\u00e9 qui a tendance \u00e0 la placer au quatri\u00e8me ou cinqui\u00e8me rang des nouvelles, voire \u00e0 nier qu&rsquo;elle existe, &ndash; et \u00e0 quel point cela est horrible mais en m\u00eame temps absurdement dr\u00f4le<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Et ceci, la question pos\u00e9e : pourquoi cette com\u00e8te, une com\u00e8te, repr\u00e9sente-t-elle la parabole de la catastrophe climatique, alors que rien ne le dit express\u00e9ment ? Pourquoi pas parabole de notre folie du Covid ? Pourquoi pas parabole de notre politique hyper-psychopathique contre la Russie sollicitant l&rsquo;ach\u00e8vement par l&rsquo;an\u00e9antissement nucl\u00e9aire r\u00e9ciproque ? Pourquoi pas parabole de notre recherche d&rsquo;un quatri\u00e8me, cinqui\u00e8me, sixi\u00e8me sexe par transgenristes en folie rassembl\u00e9s dans un <em>goulag <\/em>soci\u00e9tal, \u00e0 c\u00f4t\u00e9 des migrants et de Djokovic dans les camps australiens ?<\/p>\n<\/p>\n<p><p>Voici comment le r\u00e9alisateur MacKay en est venu \u00e0 choisir la com\u00e8te pour paraboliser (l&rsquo;ai-je bien \u00e9crit ?) la crise climatique, toujours selon &lsquo;<em>Wikip\u00e9dia<\/em>&lsquo; :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>J&rsquo;ai commenc\u00e9 \u00e0 parler \u00e0 de nombreux scientifiques <\/em>[du climat]<em>. J&rsquo;ai continu\u00e9 \u00e0 chercher de bonnes nouvelles, mais je n&rsquo;en ai jamais eu. Tout ce que j&rsquo;entendais \u00e9tait pire que ce que j&rsquo;entendais dans les m\u00e9dias grand public. J&rsquo;ai donc discut\u00e9 avec<\/em> [David Sirota, sc\u00e9nariste]<em>, et nous nous sommes dit tous les deux : \u00ab\u00a0Comment est-il possible que les m\u00e9dias n&rsquo;en parlent pas ? Qu&rsquo;on repousse cette affaire en derni\u00e8re page ? Qu&rsquo;ils n&rsquo;en fassent pas leurs manchettes en premi\u00e8re page ?\u00a0\u00bb Et Sirota a juste dit avec d\u00e9sinvolture, \u00ab\u00a0C&rsquo;est comme si une com\u00e8te se dirigeait vers la Terre et qu&rsquo;elle allait tous nous d\u00e9truire et que personne ne s&rsquo;en souciait\u00a0\u00bb. Et j&rsquo;ai bondi aussit\u00f4t : \u00ab\u00a0Voil\u00e0, c&rsquo;est \u00e7a, on tient notre truc !\u00a0\u00bb. <\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Levez-vous, \u00f4 \u00ab\u00a0forces myst\u00e9rieuses, hautes &#038; sup\u00e9rieures\u00a0\u00bb !<\/h3>\n<\/p>\n<p><p>&#8230;N\u00e9anmoins, je donne au r\u00e9alisateur MacKay une chance de s&rsquo;\u00e9chapper au moins un instant de l&rsquo;\u00e9touffante concentration du camp du Bien avec, dans la premi\u00e8re citation &lsquo;<em>Wiki<\/em>&lsquo; que j&rsquo;ai faite,  son &laquo; <em>\u00e0 quel point cela est horrible <strong>mais en m\u00eame temps absurdement dr\u00f4le<\/strong><\/em> &raquo;&#8230; Sa notable pens\u00e9e conformiste se nuance d&rsquo;une remarque qui le lib\u00e8re et nous ram\u00e8ne sur le territoire incroyable de contraste entre la catastrophe et le d\u00e9risoire grotesque de l&rsquo;humain, de la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-la-tragedie-bouffe\">trag\u00e9die-bouffe <\/a>; et tout cela, dis-je, nous renfor\u00e7ant dans la perception qu&rsquo;il y a un myst\u00e8re dans l&rsquo;id\u00e9e, dans la conception et dans la r\u00e9alisation de ce film, venu du c&oelig;ur br&ucirc;lant de la communication de l'\u00a0\u00bbusine \u00e0 r\u00eaves\u00a0\u00bb du Syst\u00e8me, et pourtant d\u00e9crivant la raison g\u00e9n\u00e9rale et indubitable de l&rsquo;effondrement du Syst\u00e8me dans l&rsquo;atrocit\u00e9 satanique du Syst\u00e8me lui-m\u00eame. Venu du c&oelig;ur du simulacre du Mordor, il nous expose d&rsquo;une fa\u00e7on absolument claire la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-verite-de-situation-verite\">v\u00e9rit\u00e9-de-situation<\/a> de l&rsquo;effondrement du Syst\u00e8me.<\/p>\n<\/p>\n<p><p>Sans avoir besoin de &laquo; <em>sacrifier un jeune bouc sans tache au lever du soleil au sommet du mont Garitzim ou au temple de J\u00e9rusalem, <\/em>[&#8230;] [de me] <em>frictionner avec de la pur\u00e9e d&rsquo;ail tous les matins,<\/em> [&#8230;] [de] <em>recopier le passage sur une feuille le passage ou Jesus envoi les pourceaux poss\u00e9d\u00e9s dans la mer puis boire une infusion de ce document<\/em> &raquo; (ah, esprit fort perch\u00e9 sur le &lsquo;<em><a href=\"https:\/\/www.dedefensa.org\/article\/resister-cest-combattre-la-matrice\">forum<\/a><\/em>&lsquo; ad\u00e9quat, que vous me fatiguez, que vous me gonflez enfin) ; sans besoin, poursuis-je, de tout ce bazar qui fait anath\u00e8me sur les t\u00e9n\u00e8bres des premiers temps pour mieux savourer la lumi\u00e8re des temps pr\u00e9sents quoique temps-devenus-fous, je n&rsquo;irais pas au terme de cette exploration \u00e9tonn\u00e9e sans mentionner mon hypoth\u00e8se favorite des \u00ab\u00a0forces myst\u00e9rieuses, hautes &#038; sup\u00e9rieures\u00a0\u00bb qui agissent, font les \u00e9v\u00e9nements, interf\u00e8rent sur nos pr\u00e9tendus-actes pour mettre les leurs en bonne place, et ainsi nous conduire au terme convenable de l&rsquo;Effondrement du Syst\u00e8me (GCES). &Ocirc; esprit fort et mis \u00e0 part \u00ab\u00a0la pur\u00e9e d&rsquo;ail tous les matins\u00a0\u00bb, comment expliques-tu, comment justifies-tu l&rsquo;absolu bordel, chaos et d\u00e9sordre, barbarie \u00e9pouvantable et d\u00e9raison funeste des choses essentielles, comment expliques-tu et justifies-tu que l&rsquo;on en soit l\u00e0 o&ugrave; se trouve le monde ? L&rsquo;obscurantisme, dis-tu ? Le fascisme ? Le complotisme ? Passons outre s&rsquo;il vous pla&icirc;t et laissons l&rsquo;esprit fort &laquo; <em>jouer avec cette poussi\u00e8re<\/em> &raquo;, il s&rsquo;agit d&rsquo;affaires d&rsquo;une extr\u00eame gravit\u00e9.<\/p>\n<\/p>\n<p><p>Car c&rsquo;est un fait que certains aimeraient exp\u00e9dier \u00e0 la poubelle avec un m\u00e9pris comme seules les Lumi\u00e8res savent avoir pour toute la sagesse qui les a pr\u00e9c\u00e9d\u00e9s et dont ils sont les rejetons monstrueux qui ont trahi cette sagesse, c&rsquo;est un fait qu&rsquo;il me faut appr\u00e9hender avec ma raison acceptant l&rsquo;irrationnel comme \u00e9ternelle V\u00e9rit\u00e9 du monde le myst\u00e8re d&rsquo;un artisan du cin\u00e9ma voulant d\u00e9fendre une catastrophe \u00e0 venir \u00ab\u00a0qui fait fureur\u00a0\u00bb (la catastrophe climatique) en exposant dans sa compl\u00e9tude le pot-aux-roses des d\u00e9dales monstrueux d&rsquo;un Syst\u00e8me \u00e0 l&rsquo;agonie dont est comptable cet artisan ; lequel \u00ab\u00a0pot-aux-roses des d\u00e9dales\u00a0\u00bb constitue la cause premi\u00e8re de cette \u00ab\u00a0catastrophe\u00a0\u00bb et de toutes les autres, c&rsquo;est-\u00e0-dire la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-la-gces\">Grande Crise<\/a> soi-m\u00eame. Je sais que la phrase est longue et qu&rsquo;il faut la relire avec toute sa raison pour en distinguer la logique, mais il importe pour cela, comme \u00e9crit notre remarquable, opini\u00e2tre et sublime commentateur \u00ab\u00a0<em>J.C.<\/em>\u00a0\u00bb parlant de la raison, observer qu&rsquo;&laquo; <em>il s&rsquo;agit de la raison \u00ab\u00a0divine\u00a0\u00bb, \u00e0 mille lieues de la raison \u00ab\u00a0humaine\u00a0\u00bb (et rien qu'\u00a0\u00bbhumaine\u00a0\u00bb) des modernes<\/em> &raquo; (&lsquo;<em><a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-structure-crisique\">forum<\/a><\/em>&lsquo;).<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e9fi cosmique 20 janvier 2022 &ndash; La chronique &lsquo;du jour&rsquo; (d&rsquo;hier) de Dimitri Orlov tombe fort bien pour me relancer dans un projet pourtant \u00e9vident que j&rsquo;avais pourtant laiss\u00e9 de c\u00f4t\u00e9. J&rsquo;ai vu le film &laquo; Don&rsquo;t Look Up &raquo; assez rapidement apr\u00e8s sa diffusion-Netflix, sans doute le 26 ou le 27 d\u00e9cembre 2021 ;&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[4270,6045,3392,21391,3228,17252,21395,3756,15610,21394,21166,2668,19683,12593,7254],"class_list":["post-80042","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-autodestruction","tag-catastrophe","tag-climatique","tag-comete","tag-crise","tag-dont","tag-environnemental","tag-etat","tag-look","tag-mackay","tag-netflix","tag-orlov","tag-parabole","tag-profond","tag-up"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80042","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=80042"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80042\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=80042"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=80042"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=80042"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}