{"id":80045,"date":"2022-01-22T18:40:43","date_gmt":"2022-01-22T18:40:43","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2022\/01\/22\/lenigme-scorpio-mission-impossible\/"},"modified":"2022-01-22T18:40:43","modified_gmt":"2022-01-22T18:40:43","slug":"lenigme-scorpio-mission-impossible","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2022\/01\/22\/lenigme-scorpio-mission-impossible\/","title":{"rendered":"L&rsquo;\u00e9nigme \u2018<em>Scorpio<\/em>&lsquo;: \u2018Mission impossible\u201d?"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">L&rsquo;\u00e9nigme &lsquo;<em>Scorpio<\/em>&lsquo;: &lsquo;Mission impossible\u00a0\u00bb?<\/h2>\n<\/p>\n<p><p>22 janvier 2022 (18H30) &ndash; Comme je l&rsquo;avais d\u00e9j\u00e0 <a href=\"https:\/\/www.dedefensa.org\/article\/lespion-et-le-xxieme-siecle\">not\u00e9 ici<\/a> dans ce &lsquo;<em>Journal<\/em>&lsquo; et <a href=\"https:\/\/www.dedefensa.org\/article\/notes-sur-la-cia-face-aux-zombies-poutine\">d\u00e9velopp\u00e9 l\u00e0<\/a> dans des &lsquo;<em>Notes d&rsquo;Analyse<\/em>&lsquo;, j&rsquo;\u00e9prouve une sorte de fascination pour le film &lsquo;<em><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Scorpio_%28film%29\">Scorpio<\/a><\/em>&lsquo; de 1973. L&rsquo;intrigue est celle d&rsquo;une op\u00e9ration de \u00ab\u00a0nettoyage interne\u00a0\u00bb de la CIA, o&ugrave; l&rsquo;Agence n&rsquo;appara&icirc;t pas sous son plus bel atour ; mais plut\u00f4t comme un repaire de coups fourr\u00e9s et de trahisons en tous genres qu&rsquo;elle est en g\u00e9n\u00e9ral, et certainement qu&rsquo;elle est devenue comme si sa d\u00e9cadence accompagnait celle de l&rsquo;Am\u00e9rique et de ce que je nomme <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-bloc-bao-1\">bloc-BAO<\/a>.<\/p>\n<\/p>\n<p><p>D&rsquo;une certaine fa\u00e7on, je m&rsquo;en avise \u00e0 l&rsquo;instant de d\u00e9velopper mon sentiment intuitif, c&rsquo;est la m\u00eame sorte de fascination que j&rsquo;\u00e9prouve pour &lsquo;<em>Le Troisi\u00e8me Homme<\/em>&lsquo;. Je ne r\u00e9siste pas \u00e0 la tentation de divulguer \u00e0 nouveau l&rsquo;\u00e9motion extr\u00eame, le sentiment nostalgique et tragique, le myst\u00e8re du monde, qui exsudaient pour moi et exsude toujours de ce film, selon ma perception toujours recommenc\u00e9e ; cela qui permet de comprendre pourquoi je me tiens pr\u00eat \u00e0 retrouver dans d&rsquo;autres \u00e9v\u00e9nements et d&rsquo;autres cr\u00e9ations cette \u00e9motion intuitive. (Cet extrait, voir dans &laquo; <em><a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-le-trou-noir-du-xxeme-siecle\">Le \u00ab\u00a0Trou Noir\u00a0\u00bb<\/a><\/em>&#8230; &raquo;, &laquo; <em>Un Moment m\u00e9tahistorique<\/em> &raquo;.) :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Il faut une image \u00e0 la fois po\u00e9tique et d\u00e9cisive pour nous faire p\u00e9n\u00e9trer dans cette portion d&rsquo;univers qui nous attache et nous intrigue \u00e0 la fois, et nous angoisse d\u00e9j\u00e0, qui soit la clef pour tourner le verrou. &lsquo;Le troisi\u00e8me homme&rsquo;, ce film de 1949 de Carol Reed, avec Orson Welles, Joseph Cotten, Alida Valli et Trevor Howard, fait office de cette clef qui ouvre sur l&rsquo;interstice d&rsquo;angoisse, qui rouvre nos sens et nourrit une intuition, un instant, sur notre crise fondamentale. Le film n&rsquo;apporte rien d&rsquo;une explication, d&rsquo;un raisonnement, non, il offre un climat qui transmute l&rsquo;univers. La chose se d\u00e9roule dans la Vienne de l&rsquo;imm\u00e9diat apr\u00e8s-guerre, divis\u00e9e en quatre, ville tortur\u00e9e, bless\u00e9e, d\u00e9membr\u00e9e, \u00e9cartel\u00e9e, &ndash; sillonn\u00e9e par les patrouilles des troupes d&rsquo;occupation, o&ugrave; r\u00e8gnent la peur de l&rsquo;avenir et l&rsquo;effroi devant l&rsquo;inconnu, avec tous les stigmates et les affreuses blessures de la guerre, les ruines, les queues du rationnement, les \u00eatres louches, perdus, les femmes qui ont \u00e9t\u00e9 belles, les gamins aux joues creuses qui apprennent \u00e0 chaparder un sou, les barons d&rsquo;un autre temps transform\u00e9s en clochards et qui n&rsquo;ont gard\u00e9 de leur ancienne splendeur qu&rsquo;un manteau d&rsquo;une fourrure luxueuse et d\u00e9sormais mit\u00e9e par le temps des temp\u00eates, tous des survivants d&rsquo;on ne sait plus quoi ; le noir d&rsquo;encre de la nuit du monde, le cr\u00e9puscule de la guerre qui s&rsquo;\u00e9tend comme si cette guerre montrait toute sa st\u00e9rilit\u00e9 \u00e0 engendrer une paix ; les ombres de la nuit, d\u00e9form\u00e9es, d\u00e9mesur\u00e9ment \u00e9tir\u00e9es, des fugitifs solitaires dans les rues d\u00e9sertes, les claquements secs et renvoy\u00e9s de mur en mur, de pierre en pierre, des pas pr\u00e9cipit\u00e9s et des fuites haletantes, l&rsquo;humidit\u00e9 insipide et insolite, la neige \u00e9parse et salie, l&rsquo;extraordinaire assombrissement du monde ; la d\u00e9formation asym\u00e9trique de la cam\u00e9ra qui nous restitue une vision fantasmagorique des fa\u00e7ades des vieilles maisons de l&rsquo;Empire enfui, les pentes des rues serpentant entre des ruines \u00e9pisodiques, les pav\u00e9s rebondis et luisants d&rsquo;humidit\u00e9, tout cela encore d\u00e9form\u00e9 par les prises de vue insolites o&ugrave; l&rsquo;on imagine sans peine la patte insistante de l&rsquo;influence de Welles, les clairs-obscurs sinistres et sombres, plus obscurs que clairs, comme s&rsquo;il existait une lueur diffuse propre au couvre-feu, qui serait presque une lumi\u00e8re noire. Le film nous conte un autre univers dont on a peine \u00e0 croire qu&rsquo;il ne s&rsquo;agit pas de l&rsquo;univers<strong> vrai<\/strong> de cette p\u00e9riode&hellip;<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Si j&rsquo;en suis venu \u00e0 ce souvenir en introduction de mon propos sur &lsquo;<em>Scorpio<\/em>&lsquo;, c&rsquo;est justement parce que l&rsquo;un des passages qui me retient le plus dans ce film de 1973 se d\u00e9roule dans la m\u00eame Vienne de Reed-Welles, de 1949. La capitale de l&rsquo;Autriche qui brilla de tous ses feux imp\u00e9riaux comme l&rsquo;\u00e9lan et la maturit\u00e9 superbes d&rsquo;une civilisation sans peu d&rsquo;\u00e9gale, qui fut un peu la ville-pair de Paris dans ces ann\u00e9es terribles et sublimes qui fracturent le monde, de la fin du XIX\u00e8me si\u00e8cle aux trois-quarts de XX\u00e8me, fut aussi dans les p\u00e9riodes interlopes dont la Guerre Froide fut le sommet, un rendez-vous clandestin des espions, un lieu de bavardage secret pour les ennemis affich\u00e9s qui ont besoin de n\u00e9gocier en secret, un lieu o&ugrave; les id\u00e9ologies se m\u00e9langeaient et perdaient de leurs intransigeances pour laisser \u00e9chapper leur d\u00e9sarroi, o&ugrave; la fermet\u00e9 de la politique s&rsquo;effa\u00e7ait pour laisser filtrer les immenses incertitudes de l&rsquo;histoire jusqu&rsquo;aux hauteurs de la m\u00e9tahistoire.<\/p>\n<\/p>\n<p><p>C&rsquo;est ainsi que j&rsquo;ai <a href=\"https:\/\/www.dedefensa.org\/article\/notes-sur-la-cia-face-aux-zombies-poutine\">d\u00e9j\u00e0 confi\u00e9<\/a> ce que je retins principalement de &lsquo;<em>Scorpio<\/em>&lsquo;, qui se passe \u00e0 Vienne, o&ugrave; l&rsquo;espion de la CIA Cross (Burt Lancaster) en fuite, retrouve pour une aide ultime contre ses propres chefs son vieil ami de la guerre d&rsquo;Espagne, l&rsquo;espion du KGB Zharkov (Paul Scofield)&#8230;<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Ainsi une bonne id\u00e9e de cette crise interne du monde du renseignement, appara&icirc;t-elle dans quelques r\u00e9pliques du film &lsquo;<\/em><em><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Scorpio_%28film%29\">Scorpio<\/a><\/em><em>&lsquo; de 1973, avec un passage du film situ\u00e9 \u00e0 Vienne. Il s&rsquo;agit de la conversation entre l&rsquo;agent de la CIA Cross (Burt Lancaster), qui fuit le tueur charg\u00e9 par sa hi\u00e9rarchie de l&rsquo;\u00e9liminer, et son \u00ab\u00a0ami\u00a0\u00bb du KGB Zharkov (Paul Scofield) en poste \u00e0 Vienne et chez qui il se r\u00e9fugie un moment. Ici, il n&rsquo;est pas question de \u00ab\u00a0respect discret\u00a0\u00bb entre les deux, mais d&rsquo;une estime id\u00e9ologique bas\u00e9e sur un combat commun et une amiti\u00e9 nou\u00e9 sur le champ de bataille (tous deux ont combattu dans le camp r\u00e9publicain, pendant la guerre d&rsquo;Espagne). Les deux sentiments communs se sont transmut\u00e9s, sans souci de la coh\u00e9rence id\u00e9ologique, en une violente position antimoderne commune face aux bureaucraties qui d\u00e9vorent leurs deux services, et \u00e0 l&rsquo;arriv\u00e9e de nouvelles g\u00e9n\u00e9rations clon\u00e9es sur ces nouvelles bureaucraties.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Tout cela est simplement dit, avec des formules \u00e0 l&#8217;emporte-pi\u00e8ce, mais le climat cr\u00e9\u00e9 par l&rsquo;\u00e9change restitue absolument et intuitivement le climat de notre <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-la-gces\">Grande Crise<\/a>, dont la complexit\u00e9 d\u00e9velopp\u00e9e comme \u00e0 plaisir, sinon comme \u00e0 dessein, brouille et dissimule la simplicit\u00e9 de forme des immenses fractures de la m\u00e9tahistoire, et celle que nous subissons plus immense qu&rsquo;aucune autre<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>&#8230; Apr\u00e8s cette mise en bouche consid\u00e9rable, j&rsquo;en viens au \u00ab\u00a0plat du jour\u00a0\u00bb. Il s&rsquo;agit du resurgissement on ne peut plus actuelle (le <a href=\"https:\/\/www.rt.com\/pop-culture\/546528-mission-impossible-cia-hollywood\/\">21 janvier 2022<\/a>) de l&rsquo;\u00e9trange \u00e9nigme qu&rsquo;est le film &lsquo;<em>Scorpio<\/em>&lsquo; par rapport \u00e0 la CIA ; alors que, &ndash; autre actualit\u00e9, &ndash; Tom Cruise s&rsquo;appr\u00eate \u00e0 tourner, s&rsquo;il ne le fait d\u00e9j\u00e0, le n&deg;8 de sa &lsquo;<em>Mission impossible<\/em>&lsquo;, qui viendra en salle sous le titre probable de&#8230; &lsquo;<em>Scorpio<\/em>&lsquo;, &ndash; semble-t-il, plus ou moins coordonn\u00e9 ou sugg\u00e9r\u00e9 (le titre) par la CIA elle-m\u00eame. En effet, il s&rsquo;av\u00e8re, et je l&rsquo;ignorais compl\u00e8tement, que &lsquo;<em>Scorpio<\/em>&lsquo; est le premier film depuis la cr\u00e9ation de l&rsquo;Agence en 1947 dont certaines prises de vue ont \u00e9t\u00e9 faites au si\u00e8ge de la CIA, \u00e0 Langley, avec l&rsquo;autorisation empress\u00e9e de la CIA.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Que cela signifie ou non que le huiti\u00e8me film &lsquo;Mission : Impossible&rsquo; est soutenu par la CIA ou non, nous devrons attendre et voir. Compte tenu de l&rsquo;histoire <\/em>[de la s\u00e9rie des &lsquo;<em>Mission impossible<\/em>&lsquo;]<em>, de ses repr\u00e9sentations positives et de son \u00e9troite coop\u00e9ration avec l&rsquo;Agence, ainsi que du choix tr\u00e8s inhabituel du titre provisoire, ce ne serait pas une surprise<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Le texte (non sign\u00e9) de RT.com prend \u00e9videmment cette nouvelle du \u00ab\u00a0n&deg;8\u00a0\u00bb de &lsquo;<em>Mission Impossible<\/em>&lsquo; ainsi d\u00e9nomm\u00e9 &lsquo;<em>Scorpio<\/em>&lsquo;, comme argument imp\u00e9ratif pour revenir en grands d\u00e9tails sur les rapports du premier &lsquo;<em>Scorpio<\/em>&lsquo; et de la CIA. En effet, l&rsquo;obligeance et l&rsquo;int\u00e9r\u00eat de la CIA pour &lsquo;<em>Scorpio<\/em>&lsquo;, vraiment premier film avec des s\u00e9quences \u00e0 Langley, sont d&rsquo;autant plus \u00e9nigmatiques que la CIA y est montr\u00e9e sous son jour le plus cru, le plus brutal, le plus d\u00e9testable.<\/p>\n<\/p>\n<p><p>Certes, j&rsquo;entends d\u00e9j\u00e0 les guerriers du jour affuter le type de complot ou de faux-drapeau qui correspondrait \u00e0 cette \u00e9trange rencontre, mais vraiment, le texte qu&rsquo;on lira ci-dessous, n&rsquo;\u00e9pargne aucune hypoth\u00e8se, aucune possibilit\u00e9, de la provocation, la relation publique ou le message mena\u00e7ant, jusqu&rsquo;\u00e0 la stupidit\u00e9 bureaucratique ou la non-lecture du sc\u00e9nario avec des cafouillages de coop\u00e9ration ; au bout du compte, le constat se d\u00e9duit que l&rsquo;\u00e9nigme reste enti\u00e8re. On cite dans ce texte des archives de la CIA, des interviews, des livres, et demeure l&rsquo;\u00e9nigme, relanc\u00e9e par le film &lsquo;<em>Scorpio-2.0<\/em>&lsquo; indiquant que la CIA n&rsquo;entend nullement dissimuler le souvenir de cette premi\u00e8re coop\u00e9ration directe avec Hollywood.<\/p>\n<\/p>\n<p><p>Dans ce texte \u00e9galement, le r\u00e9alisateur du &lsquo;<em>Scorpio<\/em>&lsquo; originel, Michael Winner, parle beaucoup de la connexion &lsquo;<em>Scorpio<\/em>&lsquo;-CIA ; en des termes assez convenus et amicaux pour la CIA dans des interviews pendant le tournage, pour conserver la coop\u00e9ration de l&rsquo;Agence bien s&ucirc;r ; mais d&rsquo;une fa\u00e7on beaucoup plus ouverte et interrogative, sinon critique ou sceptique, dans son autobiographie bien des ann\u00e9es plus tard. Son sentiment est peut-\u00eatre r\u00e9sum\u00e9 par ce passage :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Winner lui-m\u00eame ne comprenait pas pourquoi on leur avait accord\u00e9 l&rsquo;acc\u00e8s, et il en a demand\u00e9 la raison \u00e0 l&rsquo;un des officiers de la CIA avec lesquels ils travaillaient, qui r\u00e9pondit : \u00ab\u00a0Je crois avoir compris que Helms <\/em>[directeur de l&rsquo;Agence \u00e0 l&rsquo;\u00e9poque] <em>voudrait rendre la CIA plus accessible\u00a0\u00bb. Dans son livre, Winner commente : \u00ab\u00a0Je n&rsquo;ai jamais compris le sens de sa r\u00e9ponse\u00a0\u00bb<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Le domaine qui est peu, sinon pas du tout mentionn\u00e9 dans l&rsquo;article est celui du contexte \u00e9v\u00e9nementiel en 1972-1973 (&lsquo;<em>Scorpio<\/em>&lsquo; fut r\u00e9alis\u00e9 en 1972 et sortit en 1973). Il s&rsquo;agit d&rsquo;une p\u00e9riode cruciale aux USA, puisque c&rsquo;est \u00e0 la mi-1972 et tout au long de l&rsquo;ann\u00e9e 1973 que se d\u00e9veloppa le scandale du Watergate <a href=\"https:\/\/www.dedefensa.org\/article\/le-president-et-quelques-generaux\">issu d&rsquo;un montage<\/a> du comit\u00e9 des chefs d&rsquo;\u00e9tat-major et autres <a href=\"https:\/\/www.dedefensa.org\/article\/trump-et-la-parallele-nixon\">ennemis de Nixon<\/a>, aboutissant \u00e0 la d\u00e9mission du pr\u00e9sident Nixon le 10 ao&ucirc;t 1974. La CIA joua un r\u00f4le certain, qui n&rsquo;a jamais \u00e9t\u00e9 clairement \u00e9clairci, mais qui fut sans aucun marqu\u00e9 par un affrontement entre Nixon et Helms. Finalement, Helms fut d\u00e9mis de ses fonction en novembre 1972 et quitta la CIA d\u00e9but 1973, d&rsquo;ailleurs pour une fonction diplomatique importante d&rsquo;ambassadeur des USA en Iran (toujours du temps du Shah).<\/p>\n<\/p>\n<p><p>Le film fut donc produit (en 1972) alors que le directeur de la CIA affrontait le pr\u00e9sident et se trouvait menac\u00e9 dans sa fonction. On peut alors sugg\u00e9rer d&rsquo;envisager l&rsquo;hypoth\u00e8se que la d\u00e9cision (de Helms) de soutenir un film anti-CIA constituait une arme, dans tous les cas un \u00e9l\u00e9ment pour de futurs affrontements autour de la CIA que Helms quittait. (On dit pourtant et certes que Helms n&rsquo;\u00e9tait pas homme \u00e0 faire des man&oelig;uvres tordues, mais plut\u00f4t <a href=\"https:\/\/www.rollingstone.com\/culture\/culture-news\/the-rise-and-fall-of-richard-helms-191224\/\">haut-fonctionnaire honorable<\/a> et l&rsquo;un de ces  tr\u00e8s &laquo; <em><a href=\"https:\/\/www.amazon.com\/Honorable-Men-My-Life-CIA\/dp\/0671228757\">Honorable Men<\/a><\/em> &raquo; selon le titre des m\u00e9moires de son successeur Colby ; mais ceux qui disent cela, je les connais, sont en g\u00e9n\u00e9ral des d\u00e9mocrates, adversaires de Nixon, &ndash; ha\u00ef presqu&rsquo;autant que Trump \u00e0 l&rsquo;\u00e9poque, je m&rsquo;en rappelle fort bien, &ndash; et leur jugement vertueux sur Helms souffre un peu de cette situation, n&rsquo;est-il pas ?)<\/p>\n<\/p>\n<p><p>Des affrontements, il y en eut en 1974-1975, lorsque la CIA connut une crise terrible devant la commission d&rsquo;enqu\u00eate du s\u00e9nateur Church. En m\u00eame temps, le directeur du contre-espionnage de la CIA, le tout-puissant et tr\u00e8s-controvers\u00e9 <a href=\"https:\/\/fr.wikipedia.org\/wiki\/James_Angleton\">James Jesus Angleton<\/a>, tr\u00e8s engag\u00e9 avec sa parano\u00efa dans des conflits internes autour de transfuges sovi\u00e9tiques, avait \u00e9t\u00e9 mis \u00e0 pied en 1974 par le successeur de Helms, <a href=\"https:\/\/en.wikipedia.org\/wiki\/William_Colby\">William Colby<\/a>. La crise de la commission Church conduisit \u00e0 la d\u00e9mission de Colby en 1976 (remplac\u00e9, &ndash; coucou, nous revoil\u00e0, &ndash; par Bush p\u00e8re jusqu&rsquo;en 1977 et la nomination de l&rsquo;amiral Stansfield Turner). Colby mourut en 1996 dans des circonstances myst\u00e9rieuses (noyade lors d&rsquo;une p\u00eache en rivi\u00e8re) et certains membres de sa famille dirent qu&rsquo;il ch\u00e9rissait et bouclait la correction d&rsquo;un manuscrit de bouquin qui ne fut pas retrouv\u00e9, &ndash; et ainsi de suite&#8230;<\/p>\n<\/p>\n<p><p>A partir de l\u00e0, ce tournant de 1972-1975, la CIA perdit toute stabilit\u00e9 et se vit de plus en plus engag\u00e9e dans des conflits, des crises et des scandales o&ugrave; sa r\u00e9putation fut tr\u00e8s fortement ternie par des actions bien contestables sinon ill\u00e9gales m\u00eame par rapport \u00e0 son propre statut et \u00e0 son histoire. Elle fit na&icirc;tre le terrorisme islamiste jusqu&rsquo;\u00e0 ce monstre qui vient jusqu&rsquo;\u00e0 nous, elle s&rsquo;impliqua dans les trafics de drogue d&rsquo;Am\u00e9rique Centrale (&lsquo;<em>Irangate<\/em>&lsquo;, Tom Cruise, encore lui, dans &lsquo;<em>American Traffic<\/em>&lsquo;) et ceux d&rsquo;Asie et d&rsquo;Afghanistan, aujourd&rsquo;hui plus puissants que jamais, elle monta des scandales financiers, et tant et tant d'\u00a0\u00bbetc\u00e9t\u00e9ras\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>Ainsi peut-on voir combien &lsquo;<em>Scorpio<\/em>&lsquo; s&rsquo;inscrit \u00e0 un moment-clef de l&rsquo;histoire de la CIA, et \u00e9galement, d&rsquo;une certaine fa\u00e7on, dans l&rsquo;histoire des USA o&ugrave; le Watergate et ses nombreux scandales-satellites ouvrirent la voie au d\u00e9veloppement d&rsquo;une superstructure g\u00e9n\u00e9rale de corruption, de bellicisme et de manipulation par-dessus la structure courante de l&rsquo;agression am\u00e9ricaniste ; cette superstructure n&rsquo;a cess\u00e9 depuis de corroder la puissance am\u00e9ricaniste, et m\u00eame de notre civilisation. Le dialogue d\u00e9senchant\u00e9 signal\u00e9 plus haut de Cross et de Zharkov dans la vieille capitale des Habsbourg intervient plus que jamais comme l&rsquo;\u00e9trange signal de la fin d&rsquo;une stabilit\u00e9 d&rsquo;une \u00e9poque ou d&rsquo;une \u00e9poque de stabilit\u00e9 des dangers, &ndash; voire, rien de moins, comme le terrible signal de la fin de la stabilit\u00e9 de la modernit\u00e9 elle-m\u00eame, et l&rsquo;entr\u00e9e dans ce qui allait devenir la Grande Crise. La m\u00eame ann\u00e9e (1973), l&#8217;embargo p\u00e9trolier des pays producteurs suivant la guerre d&rsquo;octobre confirme cette lecture.<\/p>\n<\/p>\n<p><p>J&rsquo;en viendrais donc \u00e0 penser que &lsquo;<em>Scorpio<\/em>&lsquo; et ses rapports avec la CIA, outre ce qu&rsquo;ils sont, font \u00e9galement office d&rsquo;un symbole de plus d&rsquo;une rupture qui conduit jusqu&rsquo;\u00e0 nous, avec deux piliers de la puissance US, &ndash; Hollywood et la CIA, &ndash; plac\u00e9s dans des postures incertaines, ou bien inverties c&rsquo;est selon, class\u00e9s en fonction des termes \u00e9tranges et insaisissables d&rsquo;une coop\u00e9ration de fortune par ailleurs semblant in\u00e9vitable. Cela donne \u00e0 penser que l&rsquo;on peut s&rsquo;int\u00e9resser, en passant et en souvenir, \u00e0 &lsquo;<em>Scorpio<\/em>&lsquo; comme \u00e0 bien autre chose qu&rsquo;un simple thriller d&rsquo;espionnage de plus ; mais plut\u00f4t, c&rsquo;est pour cela que j&rsquo;opterais, comme un signe parmi d&rsquo;autres mais qui a son importance, de la rupture des temps que nous mesurons aujourd&rsquo;hui dans toute leur ampleur&#8230;<\/p>\n<\/p>\n<p><p>Ci-dessous, on voit la plus grande partie de l&rsquo;article de RT.com sur l&rsquo;aventure des &lsquo;<em>Scorpio<\/em>&lsquo;, les quatre ou cinq derniers paragraphes, consacr\u00e9s \u00e0 des pr\u00e9cisions sans surprise sur &lsquo;<em>Scorpio<\/em>-2.0&prime;, n&rsquo;apportant rien au propos que j&rsquo;ai abord\u00e9 ici et n&rsquo;\u00e9tant pas repris.<\/p>\n<\/p>\n<p><h4><em>Semper Phi<\/em>, PhG<\/h4>\n<\/p>\n<p><p>_________________________<\/p>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Hollywood-CIA : de &lsquo;<em>Scorpio<\/em>&lsquo; \u00e0 &lsquo;<em>Scorpio<\/em>&lsquo;<\/h2>\n<\/p>\n<p><p>Les derni\u00e8res \u00e9ditions de <a href=\"https:\/\/www.productionweekly.com\/production-weekly-issue-1279-thursday-december-30-2021-92-listings-21-pages\/\" target=\"_blank\">Production Weekly<\/a>, &ndash; une publication hollywoodienne qui recense les projets de films et de t\u00e9l\u00e9vision en cours de production, &ndash; ont r\u00e9v\u00e9l\u00e9 un d\u00e9tail passionnant concernant &lsquo;<em>Mission : Impossible &ndash; 8<\/em>&lsquo;, actuellement en tournage. Le titre provisoire du dernier opus de la s\u00e9rie de Tom Cruise est &lsquo;<em>Scorpio<\/em>&lsquo;, un choix curieux \u00e9tant donn\u00e9 que le premier &lsquo;<em>Scorpio<\/em>&lsquo;, datant de 1973, a \u00e9t\u00e9 le premier film \u00e0 avoir \u00e9t\u00e9 autoris\u00e9 \u00e0 tourner des sc\u00e8nes au si\u00e8ge de la CIA \u00e0 Langley.<\/p>\n<\/p>\n<p><p>&lsquo;<em>Scorpio<\/em>&lsquo; est un thriller sombre et violent, avec Burt Lancaster dans le r\u00f4le de Cross, un officier et un tueur de la CIA proche de la retraite, en train de former son rempla\u00e7ant, le tueur \u00e0 gages [fran\u00e7ais] Jean Laurier, alias &lsquo;<em>Scorpio<\/em>&lsquo;, jou\u00e9 par Alain Delon. Laurier joue un double jeu, puisqu&rsquo;il est charg\u00e9 par ses traitants de la CIA d&rsquo;assassiner Cross pour verrouiller \u00e0 jamais ce que Cross sait des plus sombres &lsquo;<em>dirty tricks<\/em>&lsquo; de l&rsquo;Agence.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Ce que faisait &lsquo;<em>Scorpio<\/em>&lsquo; \u00e0 la CIA<\/h3>\n<\/p>\n<p><p>Dans le film, le patron de Cross et de Laurier, McLeod, jou\u00e9 par John Colicos, est montr\u00e9 dans une longue s\u00e9quence tourn\u00e9e \u00e0 Langley. Colicos franchit le point de contr\u00f4le de s\u00e9curit\u00e9, se rend dans l&rsquo;ancien b\u00e2timent du si\u00e8ge, franchit les portes d&rsquo;entr\u00e9e et passe sur le sceau de la CIA pos\u00e9 sur le sol du hall.<\/p>\n<\/p>\n<p><p>C&rsquo;\u00e9tait la premi\u00e8re fois que les r\u00e9alisateurs d&rsquo;Hollywood \u00e9taient autoris\u00e9s \u00e0 acc\u00e9der \u00e0 Langley, et la m\u00eame s\u00e9quence de base est ensuite apparue dans &lsquo;<em>Patriot Games<\/em>&lsquo; en 1992, &lsquo;<em>Top Chef<\/em>&lsquo; en 2010, &lsquo;<em>Argo<\/em>&lsquo; en 2012, &lsquo;Game of Pawns&rsquo; produit en sous-main par le FBI en 2015, &lsquo;<em>Jack Ryan<\/em>&lsquo; produit par Amazon en 2018 et l&rsquo;\u00e9mission de t\u00e9l\u00e9-r\u00e9alit\u00e9 &lsquo;<em>Pawn Stars<\/em>&lsquo; en 2019.  D&rsquo;autres productions soutenues par la CIA, dont le thriller psychologique &lsquo;<em>The Recruit<\/em>&lsquo; avec Al Pacino, ainsi que les s\u00e9ries t\u00e9l\u00e9vis\u00e9es &lsquo;<em>Shooter<\/em>&lsquo; et &lsquo;<em>Designated Survivor<\/em>&lsquo;, ont <a href=\"https:\/\/madeinatlantis.com\/movies_central\/2003\/the-recruit.htm\">utilis\u00e9<\/a> un d\u00e9cor du hall d&rsquo;entr\u00e9e de la CIA, avec le sceau de l&rsquo;Agence int\u00e9gr\u00e9 au sol.<\/p>\n<\/p>\n<p><p>Cette rare marque d&rsquo;authenticit\u00e9 conf\u00e8re une valeur qualitative \u00e0 ces films et s\u00e9ries t\u00e9l\u00e9vis\u00e9es, leur conf\u00e9rant un lustre que d&rsquo;autres n&rsquo;ont pu obtenir. Par exemple, la demande de Michael Bay de filmer le mur comm\u00e9moratif du hall d&rsquo;entr\u00e9e, qui comporte des \u00e9toiles en hommage aux employ\u00e9s de la CIA morts en mission, pour son film &lsquo;<em>13 Hours<\/em>&lsquo; sur Benghazi a \u00e9t\u00e9 <a href=\"https:\/\/www.spyculture.com\/documents-cia-successfully-pressured-michael-bay-to-change-benghazi-movie\/\" target=\"_blank\">rejet\u00e9e<\/a>.<\/p>\n<\/p>\n<p><p>Ainsi, le film &lsquo;<em>Scorpio<\/em>&lsquo; de 1973 a innov\u00e9 dans le domaine cin\u00e9matographique et a constitu\u00e9 un moment cl\u00e9 dans le d\u00e9veloppement de la relation entre la CIA et Hollywood, une relation qui perdure encore aujourd&rsquo;hui. Mais pourquoi la CIA a-t-elle ouvert ses portes \u00e0 un portrait d&rsquo;elle-m\u00eame aussi sombre et malveillant ?  L&rsquo;<a href=\"https:\/\/www.google.co.uk\/books\/edition\/Michael_Winner_Winner_Takes_All\/wE0mEAAAQBAJ\" target=\"_blank\">autobiographie<\/a> de Michael Winner, le r\u00e9alisateur de &lsquo;<em>Scorpio<\/em>&lsquo;, raconte qu&rsquo;ils ont m\u00eame tourn\u00e9 des sc\u00e8nes de la maison de Cross dans le film, dans la maison elle-m\u00eame du directeur d&rsquo;alors de la CIA, Richard Helms, \u00e0 Washington, DC.<\/p>\n<\/p>\n<p><p>Les documents relatifs \u00e0 &lsquo;<em>Scorpio<\/em>&lsquo; figurant dans la <a href=\"https:\/\/www.cia.gov\/readingroom\/search\/site\/scorpio\">base de donn\u00e9es<\/a> CREST de la CIA comprennent des notes internes ainsi que des copies de la couverture m\u00e9diatique de la production et de la sortie du film, ce qui montre qu&rsquo;il s&rsquo;agissait d&rsquo;un projet majeur pour l&rsquo;Agence.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Pourquoi la CIA l&rsquo;a-t-elle autoris\u00e9 ?<\/h3>\n<\/p>\n<p><p>Les premiers documents sur &lsquo;<em>Scorpio<\/em>&lsquo; ont \u00e9t\u00e9 d\u00e9couverts par l&rsquo;universitaire Simon Willmetts dans le cadre de ses recherches pour son livre &lsquo;<em>In Secrecy&rsquo;s Shadow : The OSS and CIA in Hollywood Cinema 1941-1979<\/em>&lsquo;. &Agrave; l&rsquo;\u00e9poque, la majeure partie de la base de donn\u00e9es du CREST n&rsquo;\u00e9tait pas disponible en ligne, mais Willmetts a r\u00e9ussi \u00e0 localiser plusieurs documents montrant que les r\u00e9alisateurs avaient contact\u00e9 la CIA en utilisant le titre original du film, &lsquo;<em>Danger Field<\/em>&lsquo;, beaucoup plus anodin.<\/p>\n<\/p>\n<p><p>M. Willmetts a \u00e9mis l&rsquo;hypoth\u00e8se que la CIA avait fait une gaffe et autoris\u00e9 l&rsquo;acc\u00e8s \u00e0 un film d\u00e9crivant le c\u00f4t\u00e9 mal\u00e9fique de l&rsquo;Agence sans se rendre compte de ce qu&rsquo;elle faisait. Il note que quelques ann\u00e9es auparavant, la CIA avait rejet\u00e9 une <a href=\"https:\/\/www.spyculture.com\/alfred-hitchcock-cias-first-big-mistake-hollywood\/\">demande similaire<\/a> d&rsquo;Alfred Hitchcock et des producteurs de &lsquo;<em>Topaz<\/em>&lsquo;, un film beaucoup plus favorable \u00e0 la CIA, bas\u00e9 en partie sur le r\u00e9cit r\u00e9el de l&rsquo;agent double fran\u00e7ais Philippe Thyraud de Vosjoli.<\/p>\n<\/p>\n<p><p>Dans &lsquo;<em>In Secrecy&rsquo;s Shadow<\/em>&lsquo;, Willmetts qualifie la relation de la CIA avec &lsquo;<em>Scorpio<\/em>&lsquo; de &laquo; <em>d\u00e9sastre total<\/em> &raquo;, ajoutant : &laquo; <em>Apparemment, personne n&rsquo;a pris la peine de lire le sc\u00e9nario, sinon ils se seraient rendu compte de l&rsquo;intention des r\u00e9alisateurs de d\u00e9peindre la CIA comme sinistre et amorale<\/em> &raquo;.<\/p>\n<\/p>\n<p><p>Cependant, d&rsquo;autres documents sont devenus disponibles depuis la sortie de son livre, montrant que la CIA \u00e9tait bien consciente du v\u00e9ritable contenu, tr\u00e8s sombre, du film, m\u00eame si elle crut \u00e0 tort, pendant un certain temps, que &lsquo;<em>Scorpio<\/em>&lsquo; \u00e9tait un autre film.<\/p>\n<\/p>\n<p><p>De m\u00eame, selon l&rsquo;autobiographie de Winner, le vice-pr\u00e9sident de United Artists, Arnold Picker, insista pour qu&rsquo;il soumette le sc\u00e9nario \u00e0 la CIA avant le tournage. Winner note : &laquo; <em>Il travaillait dans un certain nombre de comit\u00e9s \u00e0 Washington.  Il \u00e9tait manifestement nerveux \u00e0 l&rsquo;id\u00e9e qu&rsquo;un film montrant la CIA en train d&rsquo;assassiner des gens puisse compromettre sa position \u00e0 Washington<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Qui plus est, le r\u00e9cit de Winner sur le tournage \u00e0 Langley comprend un d\u00e9tail bizarre, &ndash; &laquo; <em>une tr\u00e8s aimable dame de la CIA<\/em> &raquo; lui apporta une boite pleine de badges avec des scorpions dessus, et lui disant &laquo; <em>Cela vous montrera que nous avons le sens de l&rsquo;humour, M. Winner !<\/em> &raquo;. Elle a ensuite distribu\u00e9 une centaine de ces badges \u00e0 l&rsquo;\u00e9quipe.<\/p>\n<\/p>\n<p><p>Ainsi, il semble bien que la CIA savait pertinemment que le film la d\u00e9peignait sous un jour que la plupart des gens consid\u00e9reraient comme n\u00e9gatif, &ndash; un service d\u00e9testable, tentant de tuer l&rsquo;un des siens par crainte de voir expos\u00e9s ses plus noirs secrets, et d\u00e9veloppant le soup\u00e7on qu&rsquo;il \u00e9tait un tra&icirc;tre. Alors pourquoi avoir autoris\u00e9 le tournage du film \u00e0 Langley ? <\/p>\n<\/p>\n<p><p>Winner lui-m\u00eame ne comprenait pas pourquoi on leur avait accord\u00e9 l&rsquo;acc\u00e8s, et il en a demand\u00e9 la raison \u00e0 l&rsquo;un des officiers de la CIA avec lesquels ils travaillaient, qui r\u00e9pondit : &laquo; <em>Je crois avoir compris que Helms voudrait rendre la CIA plus accessible<\/em>. &raquo; Dans son livre, Winner commente : &laquo; <em>Je n&rsquo;ai jamais compris le sens de sa r\u00e9ponse<\/em>. &raquo;.<\/p>\n<\/p>\n<p><p>De m\u00eame, lorsque le pr\u00e9sident du Foreign Intelligence Advisory Board du pr\u00e9sident [Nixon] <a href=\"https:\/\/www.cia.gov\/readingroom\/document\/cia-rdp88-01365r000300210001-3\">\u00e9crivit<\/a> \u00e0 la CIA pour poser plusieurs questions sur le tournage de &lsquo;<em>Scorpio<\/em>&lsquo; \u00e0 Langley, l&rsquo;une des questions \u00e9tait la suivante : &laquo; <em>Qu&rsquo;est-ce que la CIA esp\u00e8re retirer de sa coop\u00e9ration, &ndash; puisque le film a une telle orientation anti-CIA ?<\/em> &raquo;<\/p>\n<\/p>\n<p><p>La <a href=\"https:\/\/www.cia.gov\/readingroom\/docs\/CIA-RDP80M01133A001100090061-1.pdf\" target=\"_blank\">r\u00e9ponse<\/a> de la CIA \u00e0 ces questions a \u00e9t\u00e9 exceptionnellement vague, en particulier en ce qui concerne la question de savoir ce qu&rsquo;elle esp\u00e9rait obtenir en collaborant \u00e0 un tel film. Elle a affirm\u00e9 que &laquo; <em>la correspondance<\/em> [relative au tournage] <em>ne mentionne jamais<\/em> &lsquo;<em>Scorpio<\/em>&lsquo; &raquo; et que la lettre du directeur de production demandant l&rsquo;acc\u00e8s au film se contentait de d\u00e9tailler une histoire &laquo; <em>traitant de leur travail<\/em> [des agents de la CIA] <em>sur le terrain et de leur relation avec leur sup\u00e9rieur imm\u00e9diat, lequel, est-il sugg\u00e9r\u00e9, n&rsquo;est rien d&rsquo;autre qu&rsquo;un cadre de l&rsquo;Agence<\/em>. &raquo;<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">La CIA jouait-elle son jeu depuis le d\u00e9but ?<\/h3>\n<\/p>\n<p><p>Pourquoi la CIA a-t-elle jou\u00e9 \u00e0 la faible d&rsquo;esprit ? <a href=\"https:\/\/nieman.harvard.edu\/news\/2010\/05\/angus-thuermer-reporter-turned-cia-official-dies\/\" target=\"_blank\">Angus Thuermer<\/a>, assistant de Helms et principal responsable des relations publiques de la CIA, avait lu le sc\u00e9nario, il \u00e9tait au courant du changement de titre ainsi que du ton et du contenu du film. Il est clair que la d\u00e9cision des gens de la CIA de soutenir &lsquo;<em>Scorpio<\/em>&lsquo; \u00e9tait plus importante que ce qu&rsquo;ils laissaient entendre au conseil consultatif du pr\u00e9sident.<\/p>\n<\/p>\n<p><p>Une possibilit\u00e9 est offerte par plusieurs interviews donn\u00e9es par Winner pendant le tournage, qui ont toutes \u00e9t\u00e9 reprises par le syst\u00e8me de surveillance des m\u00e9dias de la CIA. Apr\u00e8s la fuite de l&rsquo;information du tournage \u00e0 Langley, l\u00a0\u00bb<em>Express<\/em>&lsquo; de Londres avait repris <a href=\"https:\/\/www.cia.gov\/readingroom\/document\/cia-rdp88-01365r000300210012-1\">l&rsquo;histoire<\/a> et Winner leur d\u00e9clara : &laquo; <em>Nous ne montrons que la CIA en train de liquider des agents qui trahissent<\/em> &raquo;, ajoutant : &laquo; <em>Les jeunes Am\u00e9ricains pensent que la CIA ne devrait pas exister, mais ils sont na\u00effs<\/em>. &raquo;  Il a poursuivi en d\u00e9crivant les officiers de la CIA comme &laquo; <em>terriblement charmants, aimables et courtois \u00e0 tout moment<\/em> &raquo;.<\/p>\n<\/p>\n<p><p>Une autre interview, qui a \u00e9galement \u00e9t\u00e9 archiv\u00e9e par le service de surveillance des m\u00e9dias de la CIA, qui s&rsquo;est beaucoup attach\u00e9 \u00e0 suivre &lsquo;<em>Scorpio<\/em>&lsquo;, est all\u00e9e au c&oelig;ur du probl\u00e8me, en demandant \u00e0 Winner si le film \u00e9tait pro-CIA ou anti-CIA.  Winner a r\u00e9pondu : &laquo; <em>Si vous admirez la CIA, je suppose que vous pensez que c&rsquo;est un film anti-CIA. Si vous le d\u00e9testez, vous direz qu&rsquo;il est pro-CIA. Je pense que le film est un portrait assez fid\u00e8le<\/em>. &raquo; Il a ajout\u00e9 : &laquo; <em>Les agents eux-m\u00eames ont \u00e9t\u00e9 utiles, et immens\u00e9ment aimables<\/em> &raquo;.<\/p>\n<\/p>\n<p><p>Alors, la CIA, &ndash; comme Winner, &ndash; voyait-elle &lsquo;<em>Scorpio<\/em>&lsquo; comme un portrait fid\u00e8le, et qui a finalement contribu\u00e9 \u00e0 normaliser les assassinats et les \u00ab\u00a0sales\u00a0\u00bb op\u00e9rations secr\u00e8tes ?  Si, comme le sugg\u00e8re Winner, il est na\u00eff de penser que la CIA ne devrait pas exister, alors le message de &lsquo;<em>Scorpio<\/em>&lsquo; est-il qu&rsquo;elle est un mal n\u00e9cessaire ?<\/p>\n<\/p>\n<p><p>[&#8230;]<\/p>\n<\/p>\n<p><h4>RT.com<\/h4><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;\u00e9nigme &lsquo;Scorpio&lsquo;: &lsquo;Mission impossible\u00a0\u00bb? 22 janvier 2022 (18H30) &ndash; Comme je l&rsquo;avais d\u00e9j\u00e0 not\u00e9 ici dans ce &lsquo;Journal&lsquo; et d\u00e9velopp\u00e9 l\u00e0 dans des &lsquo;Notes d&rsquo;Analyse&lsquo;, j&rsquo;\u00e9prouve une sorte de fascination pour le film &lsquo;Scorpio&lsquo; de 1973. L&rsquo;intrigue est celle d&rsquo;une op\u00e9ration de \u00ab\u00a0nettoyage interne\u00a0\u00bb de la CIA, o&ugrave; l&rsquo;Agence n&rsquo;appara&icirc;t pas sous son plus bel&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[3214,3104,2631,4101,3371,2622,15969,1406,2789,8400,5164,2626,21398],"class_list":["post-80045","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-burt","tag-cia","tag-de","tag-helms","tag-hollywood","tag-la","tag-lancaster","tag-nixon","tag-rupture","tag-stabilite","tag-vienne","tag-watergate","tag-winner"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80045","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=80045"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80045\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=80045"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=80045"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=80045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}