{"id":80140,"date":"2022-04-01T17:33:51","date_gmt":"2022-04-01T17:33:51","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2022\/04\/01\/castelnau-a-lassaut-de-mac-mckinsey\/"},"modified":"2022-04-01T17:33:51","modified_gmt":"2022-04-01T17:33:51","slug":"castelnau-a-lassaut-de-mac-mckinsey","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2022\/04\/01\/castelnau-a-lassaut-de-mac-mckinsey\/","title":{"rendered":"Castelnau \u00e0 l&rsquo;assaut de Mac-McKinsey"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Castelnau \u00e0 l&rsquo;assaut de Mac-McKinsey<\/h2>\n<\/p>\n<p><p>1<sup>er<\/sup>avril 2022 (17H30) &ndash; Parmi les nombreuses plumes et voix, celles qui ne sont pas acquises au pr\u00e9sident \u00ab\u00a0r\u00e9\u00e9lu d&rsquo;avance\u00a0\u00bb, qui ont pris le sentier de la guerre concernant l&rsquo;affaire McKinsey, je choisis avec entrain et ardeur celles (plume et voix) de l&rsquo;avocat R\u00e9gis de Castelnau. Celui-l\u00e0 est d\u00e9j\u00e0 illustre depuis sa bagarre lors de l&rsquo;affaire Benalla, puis confirm\u00e9 lors des divers \u00ab\u00a0bastons\u00a0\u00bb qui ont suivi avec un pouvoir qui cultive comme le Nombre d&rsquo;Or de sa post\u00e9rit\u00e9 une extraordinaire indiff\u00e9rence pour la l\u00e9gitimit\u00e9 de sa charge, et un z\u00e8le non moins extraordinaire pour l&rsquo;imposture du gredin qui a usurp\u00e9 cette charge en d\u00e9cidant de n&rsquo;en porter aucune de ses obligations&#8230; Indiff\u00e9rence, imposture, usurpateur, voil\u00e0 son plat du jour.<\/p>\n<\/p>\n<p><p>On revient \u00e0 mon hussard du barreau, plume et voix en bataille.<\/p>\n<\/p>\n<p><p>Voici sa plaidoirie&#8230; Apr\u00e8s avoir montr\u00e9 plusieurs exemples d&#8217;empressement de la justice \u00e0 se saisir d&rsquo;affaires diverses, mais pas de la dimension d&rsquo;un \u00ab\u00a0scandale d&rsquo;&Eacute;tat\u00a0\u00bb, de divers candidats et personnalit\u00e9s hors-Macronie, Castelnau nous propose un petit test \u00e0 la fin de son texte du <a href=\"https:\/\/www.vududroit.com\/2022\/03\/scandale-mckinsey-la-torpeur-selective-du-pnf\/\">30 mars 2022<\/a>, sous le titre &laquo; <em>La torpeur s\u00e9lective du PNF <\/em>[Parquet National Financier] &raquo; sur son site &lsquo;<em>VuduDroit.com<\/em>&lsquo; :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Eh bien, on va faire un petit test. Le mercredi <strong>25 janvier 2017<\/strong>au matin, le Canard encha&icirc;n\u00e9 publiait un article mettant en cause l&#8217;emploi de P\u00e9n\u00e9lope Fillon comme attach\u00e9e parlementaire. Le m\u00eame jour \u00e0 11 heures, le PNF annon\u00e7ait l&rsquo;ouverture d&rsquo;une enqu\u00eate pr\u00e9liminaire dont les investigations commenc\u00e8rent en urgence d\u00e8s le lendemain. On conna&icirc;t la suite avec les 47 jours d&rsquo;une proc\u00e9dure fulgurante, dans une urgence jamais vue auparavant dans l&rsquo;histoire de la justice fran\u00e7aise. Et la disqualification politique de Fran\u00e7ois Fillon pour permettre l&rsquo;\u00e9lection d&rsquo;Emmanuel Macron.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Le Canard encha&icirc;n\u00e9 publie ce matin <strong>30 mars <\/strong><\/em><strong>[2022]<\/strong><em>, un article assassin sur les complicit\u00e9s dont la plus que probable fraude fiscale de McKinsey a b\u00e9n\u00e9fici\u00e9 de la part des hauts fonctionnaires.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Nous verrons combien de temps il faudra aux magistrats du PNF pour sortir de leur torpeur<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Hypoth\u00e8se : c&rsquo;est tout vu&#8230; Et j&rsquo;ajouterais, histoire de se rafra&icirc;chir le gosier de la morale courante de notre-justice, que c&rsquo;est toute honte bue, et m\u00eame indisponible&#8230;<\/p>\n<\/p>\n<p><p>Poursuivons&#8230; Castelnau, homme de gauche et petit-fils du g\u00e9n\u00e9ral qui <a href=\"https:\/\/www.dedefensa.org\/article\/castelnau-par-castelnau\">pr\u00e9para <em>in extremis <\/em>Verdun<\/a>\u00e0 l&rsquo;assaut allemand, <a href=\"https:\/\/www.valeursactuelles.com\/clubvaleurs\/politique\/laffaire-mckinsey-scandale-detat\/\">signe un \u00e9dito<\/a>du 31 mars pour le site de &lsquo;<em>Valeurs Actuelles<\/em>&lsquo;, fameux hebdomadaire nettement \u00e0 droite, qui poursuit la charge men\u00e9e sur son site et dont on vient de lire la conclusion. C&rsquo;est du \u00ab\u00a0en m\u00eame temps\u00a0\u00bb gauche-droite, comme le souhaite le strat\u00e8ge Macron, une \u00ab\u00a0union sacr\u00e9e\u00a0\u00bb comme l&rsquo;on disait au temps du grand&rsquo;p\u00e8re de Castelnau.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Le scandale caus\u00e9 par les informations de la commission s\u00e9natoriale d&rsquo;enqu\u00eate sur le recours syst\u00e9matique par l&rsquo;&Eacute;tat \u00e0 des cabinets de conseil a pris de l&rsquo;ampleur. Effar\u00e9s, les Fran\u00e7ais ont appris que l&rsquo;&Eacute;tat avait eu massivement recours \u00e0 des intervenants externes, en g\u00e9n\u00e9ral des cabinets \u00e0 base anglo-saxonne, pour des missions dont l&rsquo;utilit\u00e9 ne sautait pas aux yeux, c&rsquo;est le moins que l&rsquo;on puisse dire. Le tout pour plus de 1 milliard d&rsquo;euros (!) pour la seule ann\u00e9e 2021. On ressort stup\u00e9fait de la lecture du rapport r\u00e9dig\u00e9 par la commission. Par le volume invraisemblable des achats par l&rsquo;&Eacute;tat de ces missions externes, leur fr\u00e9quente inutilit\u00e9 et l&rsquo;importance vertigineuse des r\u00e9mun\u00e9rations.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Mais le scandale a pris une autre tournure avec ce que l&rsquo;on appelle d\u00e9sormais l'\u00a0\u00bbaffaire McKinsey\u00a0\u00bb, qui d\u00e9gage des fumets particuli\u00e8rement malodorants, \u00e0 base de soup\u00e7ons de corruption, de connivences, de conflits d&rsquo;int\u00e9r\u00eats, de fraudes fiscales, de faux t\u00e9moignages et autres joyeuset\u00e9s. Qui donnent avec insistance l&rsquo;image d&rsquo;une r\u00e9publique banani\u00e8re.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Cette soci\u00e9t\u00e9 dont le si\u00e8ge social est aux &Eacute;tats-Unis a une succursale en France qui emploie 600 salari\u00e9s et fait un chiffre d&rsquo;affaires qui avoisine les 400 millions d&rsquo;euros par an. La premi\u00e8re observation que l&rsquo;on peut faire porte sur les liens personnels que les dirigeants entretiennent avec le plus haut niveau de la sph\u00e8re publique. &Agrave; base de connivences, de pantouflages juteux, d&rsquo;allers-retours r\u00e9guliers, voire de liens familiaux encombrants, l&rsquo;ensemble donnant une image particuli\u00e8rement d\u00e9plaisante<\/em>. [&#8230;]<\/p>\n<\/p>\n<p><p>&raquo; <em>Alors, si nous ne sommes pas contents, nous dit avec arrogance Emmanuel Macron, il faut aller \u00ab\u00a0au p\u00e9nal\u00a0\u00bb. Parce qu&rsquo;il sait tr\u00e8s bien que la justice ne bougera pas. Le PNF et le p\u00f4le d&rsquo;instruction financier ont contribu\u00e9 \u00e0 son \u00e9lection avec la proc\u00e9dure fulgurante lanc\u00e9e contre Fran\u00e7ois Fillon. Depuis cinq ans, son entourage et ses amis ont \u00e9t\u00e9 soigneusement pr\u00e9serv\u00e9s. Et concernant le scandale d&rsquo;&Eacute;tat majeur que constitue l&rsquo;affaire des cabinets de conseil, malgr\u00e9 les milliards d&rsquo;euros en cause, les autorit\u00e9s de poursuite, et en particulier le PNF, achevant de se d\u00e9consid\u00e9rer, restent obstin\u00e9ment muettes.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>&Eacute;videmment, aucune d\u00e9cision de culpabilit\u00e9 ne pourrait \u00eatre rendue dans les semaines qui viennent, mais ce n&rsquo;est pas le sujet. Ce qui est grave, c&rsquo;est ce silence judiciaire d\u00e9montrant que, dans la d\u00e9rive qui nourrit l&rsquo;accusation faite \u00e0 la France de devenir une r\u00e9publique banani\u00e8re, cette justice, devenue force politique autonome soutenant le syst\u00e8me Macron, porte une lourde responsabilit\u00e9<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>On ne s&#8217;embarrassera ici des cons\u00e9quences imm\u00e9diates, &ndash; judiciaires, bien entendu, avec la \u00ab\u00a0prudence\u00a0\u00bb l\u00e9gendaire de ces justiciers qui ont le respect de la hi\u00e9rarchie, &ndash; politiques \u00e9galement, tant sondagi\u00e8res qu&rsquo;\u00e9lectorales, parce que tout cela se joue dans un mouchoir chronologique, avec une presseSyst\u00e8me qui cultive le m\u00eame souci de se d\u00e9marquer du \u00ab\u00a0complotisme\u00a0\u00bb qui affleure dans chaque vision critique du pouvoir-en-place ; et d&rsquo;ailleurs, parce que je ne pr\u00e9tends surtout pas \u00eatre proph\u00e8te en cette mati\u00e8re, ni m\u00eame adepte de la comptabilit\u00e9 prospective dont on sait bien \u00e0 quelles pressions sordides elle est confront\u00e9e. Non, ce qui nous importe, c&rsquo;est l&rsquo;hypoth\u00e8se du pire, dont on sait qu&rsquo;il est toujours possible, et, dans nos temps-devenus-fous, extr\u00eamement probable sinon inratable.<\/p>\n<\/p>\n<p><p>Par cons\u00e9quent, ce qui m&rsquo;int\u00e9resse, moi, c&rsquo;est Macron r\u00e9\u00e9lu apr\u00e8s une bagarre assez sal\u00e9e, qui ira n\u00e9cessairement se nourrir \u00e0 cette vilaine affaire qui a la vertu exceptionnelle de r\u00e9sumer \u00e0 peu pr\u00e8s tout du personnage&#8230; Macron r\u00e9\u00e9lu, peut-\u00eatre ou pas dans un mouchoir de poche mais un mouchoir d\u00e9j\u00e0 souill\u00e9, et surtout dans un bruit assourdissant de casseroles multiples accroch\u00e9es \u00e0 ses basques.<\/p>\n<\/p>\n<p><p>Je conseille \u00e0 mes compatriotes, le soir de l&rsquo;\u00e9lection et pour saluer la performance de l&rsquo;imposteur-usurpateur, et ravivant en cela mes souvenirs de factieux vou\u00e9 aux g\u00e9monies, de lui donner le concert de type musique s\u00e9rielle que donnait la population alg\u00e9roise dans la p\u00e9riode proto-fasciste (d\u00e8s l&rsquo;\u00e2ge de 10 ans, au d\u00e9but \u00ab\u00a0des \u00e9v\u00e9nements\u00a0\u00bb, j&rsquo;\u00e9tais d\u00e9j\u00e0 facho, moi) ; lorsque mes compatriotes pieds-noirs, qui \u00e9taient venus lib\u00e9rer la France en 43-45, allaient chercher dans leur armurerie une ou deux casseroles de combat, et scandaient en bruit m\u00e9tallique le fameux \u00ab\u00a0ti-ti-ti-ta-ta\u00a0\u00bb (\u00ab\u00a0Al-g\u00e9-rie Fran-\u00e7aise\u00a0\u00bb) ; ils n&rsquo;ont qu&rsquo;\u00e0 l&rsquo;inverser en \u00ab\u00a0ta-ta-ti-ti-ti (\u00ab\u00a0Ma-cron d\u00e9-mi-ssion\u00a0\u00bb) du plus heureux effet au soir d&rsquo;une si belle journ\u00e9e d\u00e9mocratique ; tout un sacr\u00e9 programme dans la belle soir\u00e9e d&rsquo;une si  sublime r\u00e9\u00e9lection-<em>ReSet<\/em>.<\/p>\n<\/p>\n<p><p>Mais ce que je veux dire, au-del\u00e0 du folklore type Covid19 applaudissant les \u00ab\u00a0soignants\u00a0\u00bb, c&rsquo;est qu&rsquo;on doit ainsi mesurer les incroyables conditions de d\u00e9shonneur et d&rsquo;infamie dans lesquelles se trouvera prise notre belle R\u00e9publique, et qui marqueront la seconde \u00e9lection du bell\u00e2tre ondoyant. Sans compter, cela, que se poursuivra le vacarme de l&rsquo;<em>Ukrisis <\/em>qui sera transmut\u00e9e, comme elle est <a href=\"https:\/\/www.dedefensa.org\/article\/eh-dollar-poisson-davril\">d\u00e9j\u00e0 en train<\/a>de commencer \u00e0 le faire, d\u00e9cisivement dans cette <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-la-gces\">Grande-Crise<\/a>que nous connaissons tous. Ce jour de gloire et de f\u00eate r\u00e9publico-d\u00e9mocratique pr\u00e9sentera, je vous l&rsquo;assure, une superbe et fulgurante allure cr\u00e9pusculaire, d\u00e9moniaque mais d&rsquo;un d\u00e9mon identifi\u00e9 d\u00e9j\u00e0 par les dieux.<\/p>\n<\/p>\n<p><p>Nous aurons le troisi\u00e8me tour (les l\u00e9gislatives) qui continuera \u00e0 chauffer la foule, on imagine dans quelle atmosph\u00e8re de liesse de fureur et d&rsquo;indignation ! Et je dis, moi, m\u00eame de la part de ceux qui auront vot\u00e9 et voteront encore pour lui, fureur et indignation avec ce qu&rsquo;il leur reste des restes de leur honneur, de s&rsquo;\u00eatre contraint de voter pour lui, par trouille et par impuissance, par absence de cette audace qui vous ressuscite lorsque vous rompez enfin ces cha&icirc;nes qui vous soumettent.<\/p>\n<\/p>\n<p><p>Et alors commencera le pire du pire, la quatri\u00e8me mi-temps du match coup\u00e9 en trois ! Celle qu&rsquo;on n&rsquo;a pas pr\u00e9vue mais qu&rsquo;on devinait au fond de soi, comme in\u00e9luctable ! Car Macron, c&rsquo;est jur\u00e9, c&rsquo;est \u00e9crit, s&rsquo;il est r\u00e9\u00e9lu comme on r\u00e9cup\u00e8re une serviette souill\u00e9e parce qu&rsquo;on n&rsquo;ose pas en prendre une propre, car Macron, c&rsquo;est bien s&ucirc;r, d\u00e9clenchera aussit\u00f4t, par sa seule pr\u00e9sence inf\u00e2me, la r\u00e9volution dont personne ne voulait vraiment et que personne n&rsquo;avait l&rsquo;ardeur d&rsquo;imaginer. Macron sera le pr\u00e9sident, d\u00e8s ses premiers cent-jours, il sera l&rsquo;homme qui aura rendu possible, sinon n\u00e9cessaire, la r\u00e9volution que nous croyions tous impensable et compl\u00e8tement hors de saison.<\/p>\n<\/p>\n<p><p>Il faut faire \u00e7a, pour faire basculer les mondes : aller au bout du d\u00e9go&ucirc;t comme d&rsquo;autres vont au bout de la bruit, &ndash; ce qui revient au m\u00eame d&rsquo;ailleurs, Louis-Ferdinand en sait quelque chose, et Bardamu idem. Macron, le r\u00e9volutionnaire qui nous inventera la r\u00e9volution contre lui-m\u00eame, parce que repr\u00e9sentant le miroir dans laquelle la France, qui l&rsquo;aura r\u00e9\u00e9lu, ne supportera plus d\u00e9sormais de se voir. Ainsi meurent les civilisations, en s&rsquo;inventant des r\u00e9volutions de circonstance, philosophera gravement Vladimir Vladimirovitch Poutine tandis qu&rsquo;on entendra le rire sardonique, venu d&rsquo;outre-tombe, du singulier et tr\u00e8s-orthodoxe Vladimir Volkoff que j&rsquo;eus <a href=\"https:\/\/www.dedefensa.org\/article\/memoires-du-dehors-entre-volkoff-et-montand\">l&rsquo;heur de conna&icirc;tre<\/a>dans mes heures enflamm\u00e9es des combats de la Guerre Froide :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Philippe, je vous l&rsquo;avoue, je suis tr\u00e8s-tr\u00e8s <a href=\"https:\/\/www.amazon.fr\/Pourquoi-je-suis-moyennement-d%C3%A9mocrate\/dp\/2268042677\">moyennement d\u00e9mocrate<\/a>&hellip;<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Castelnau \u00e0 l&rsquo;assaut de Mac-McKinsey 1eravril 2022 (17H30) &ndash; Parmi les nombreuses plumes et voix, celles qui ne sont pas acquises au pr\u00e9sident \u00ab\u00a0r\u00e9\u00e9lu d&rsquo;avance\u00a0\u00bb, qui ont pris le sentier de la guerre concernant l&rsquo;affaire McKinsey, je choisis avec entrain et ardeur celles (plume et voix) de l&rsquo;avocat R\u00e9gis de Castelnau. Celui-l\u00e0 est d\u00e9j\u00e0 illustre&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[14363,2617,21493,3340,2879,4814],"class_list":["post-80140","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-14363","tag-macron","tag-mckinsey","tag-presidentielles","tag-revolution","tag-volkoff"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80140","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=80140"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80140\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=80140"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=80140"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=80140"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}