{"id":80147,"date":"2022-04-07T13:26:26","date_gmt":"2022-04-07T13:26:26","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2022\/04\/07\/greve-a-cause-dukrisis\/"},"modified":"2022-04-07T13:26:26","modified_gmt":"2022-04-07T13:26:26","slug":"greve-a-cause-dukrisis","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2022\/04\/07\/greve-a-cause-dukrisis\/","title":{"rendered":"Gr\u00e8ve \u00e0 cause d&rsquo;<em>Ukrisis<\/em>"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Gr\u00e8ve \u00e0 cause d&rsquo;<em>Ukrisis<\/em><\/h2>\n<\/p>\n<p><p>7 avril 2022 (13H30) &ndash; Dans ces temps d&rsquo;angoisse, de col\u00e8re, de frustration, j&rsquo;ai trouv\u00e9 tr\u00e8s rafraichissant et d\u00e9tendant le texte de Michael Brenner, qui pourrait aussi s&rsquo;intituler : \u00ab\u00a0Pourquoi j&rsquo;en ai marre d&rsquo;<em>Ukrisis<\/em> (et du reste)\u00a0\u00bb. Parfois, et m\u00eame souvent, j&rsquo;\u00e9prouve le m\u00eame sentiment tant le poids de l&rsquo;h\u00e9g\u00e9monie globale et globalisante des imb\u00e9ciles et de leur stupidit\u00e9 est un fardeau lourd \u00e0 porter. Je crois bien qu&rsquo;Hercule lui-m\u00eame, lui qui la ram\u00e8ne pour un rien, \u00e0 peine un globe, n&rsquo;y serait pas parvenu ; car le poids des imb\u00e9ciles et de leur idiotie que nous a l\u00e9gu\u00e9s la modernit\u00e9 ajout\u00e9 \u00e0 celui du monde, &ndash; non, d\u00e9cid\u00e9ment c&rsquo;est trop !<\/p>\n<\/p>\n<p><p>Ainsi Michael Brenner livre-t-il \u00e0 &lsquo;<em>ConsortiumNews<\/em>&lsquo; un texte intitul\u00e9 \u00ab\u00a0<em>Jerks<\/em>\u00ab\u00a0. C&rsquo;est un terme aux multiples traductions, allant de \u00ab\u00a0secousse\u00a0\u00bb (de mon temps, le jerk avait suivi le rock, le twist et le madison) \u00e0 \u00ab\u00a0connard\u00a0\u00bb. Le traducteur automatique a choisi \u00ab\u00a0secousses\u00a0\u00bb pour le titre et a g\u00e9n\u00e9ralis\u00e9 la traduction \u00ab\u00a0imb\u00e9cile\u00a0\u00bb dans le texte (avec parfois une incursion vers \u00ab\u00a0con\u00a0\u00bb et \u00ab\u00a0connasse\u00a0\u00bb).<\/p>\n<\/p>\n<p><p>J&rsquo;ai pens\u00e9 audacieusement qu&#8217;employer les deux pour le titre donnait une signification assez \u00e9l\u00e9gante, &ndash; \u00ab\u00a0Secousses d&rsquo;imb\u00e9ciles\u00a0\u00bb [&lsquo;<em>Jerks of jerks<\/em>&lsquo; ?], &ndash; comme si l&rsquo;imb\u00e9cilit\u00e9 r\u00e9gnant d&rsquo;une mani\u00e8re totalement h\u00e9g\u00e9monique dans et sous l&rsquo;Empire am\u00e9ricaniste en mode complet de d\u00e9mence crisique, pouvait \u00eatre figur\u00e9e comme une immense secousse sismique \u00e9branlant le monde jusqu&rsquo;\u00e0 ce qu&rsquo;enfin la GrandeCrise fasse son office, ce qu&rsquo;elle doit faire, &ndash; proclamant du haut des cieux, avec une fureur carnassi\u00e8re et sublime : \u00ab\u00a0Caltez volailles !\u00a0\u00bb, \u00ab\u00a0<a href=\"https:\/\/www.babelio.com\/livres\/Paraz-Le-Gala-des-vaches-Valsez-saucisse-Le-menuet-d\/4739\">Valsez saucisses !<\/a>\u00ab\u00a0. Ainsi aurions-nous cette dimension symbolique n\u00e9cessaire pour cligner de l&rsquo;&oelig;il vers la m\u00e9tahistoire qui est ma compagne favorite, car \u00e9videmment cette image irait bien dans le sens de la symbolique po\u00e9tique et m\u00e9taphysique : la tellurique de l&rsquo;imb\u00e9cillit\u00e9 secouant le monde pour faire enfin \u00e9clater la GrandeCrise ! Dieu ne pouvait mieux trouver&#8230;<\/p>\n<\/p>\n<p><p>Bref : on peut se moquer et caricaturer sarcastiquement, on n&rsquo;en reste pas moins po\u00e8te et philosophe aspirant aux plus grandes hauteurs.<\/p>\n<\/p>\n<p><p>Ainsi Brenner nous signifie qu&rsquo;il en a marre et qu&rsquo;il \u00ab\u00a0fait gr\u00e8ve\u00a0\u00bb. Depuis <em>Ukrisis<\/em>, effectivement, l&rsquo;imb\u00e9cillit\u00e9 d\u00e9mente du simulacre d&rsquo;adolescent aux r\u00eaveries humides a pris des envol\u00e9es insupportables. Tout le monde a ressenti cela, et notamment votre serviteur, le 4 mars 2022, o&ugrave; il m&rsquo;a fallu consacrer <a href=\"https:\/\/www.dedefensa.org\/article\/ukrisis-1-face-a-la-folie-et-au-systeme\">un texte<\/a> \u00e0 ma situation de commentateur, de \u00ab\u00a0soldat de la communication\u00a0\u00bb bombard\u00e9 dans ses tranch\u00e9es de toutes choses improbables, mensong\u00e8res, orient\u00e9es, foldingues, &lsquo;<em>fakenewseuses<\/em>&lsquo;, avec de quoi vous d\u00e9courager \u00e0 mort&#8230; C&rsquo;\u00e9tait &laquo; <em>Ukrisis-1 : Face \u00e0 la folie et au Syst\u00e8me<\/em> &raquo;, avec cette description de d\u00e9part, qui n&rsquo;a fait que s&rsquo;aggraver, empirer, et tout et tout, comme une pierre qui roule, et qui roule, &lsquo;<em>rolling stone<\/em>&lsquo; de leur sublime n\u00e9ant :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Il importe d\u00e9sormais de s&rsquo;adapter, et je parle ici, de nous et de moi, \u00e0 &lsquo;dde.org&rsquo;, comme doit le faire tout organe de communication. Avec la guerre de l&rsquo;Ukraine, la communication est d\u00e9sormais la \u00ab\u00a0communication-devenue-folle\u00a0\u00bb, ce qui correspond \u00e0 notre expression de ces \u00ab\u00a0temps-devenus-fous\u00a0\u00bb pour d\u00e9signer l&rsquo;actuelle s\u00e9quence temporelle. La &lsquo;subcrise&rsquo; ukrainienne devenue quasiment la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-la-gces\">Grande Crise<\/a> tout court a d\u00e9clench\u00e9 ce nouveau degr\u00e9, extraordinaire d&rsquo;abondance et de puissance, dans la folie de la communication, bien au-del\u00e0 de la (des) propagande(s)<\/em>. &raquo; <\/p>\n<\/p>\n<\/blockquote>\n<p><p>Voici donc <a href=\"https:\/\/consortiumnews.com\/2022\/04\/06\/jerks\/\">le texte<\/a> de Brenner, que j&rsquo;ai, ici et l\u00e0, retouch\u00e9 un peu, mani\u00e8re de faire, malgr\u00e9 la qualit\u00e9 en g\u00e9n\u00e9ral de la traduction automatique. (Pour mon compte, voyez &lsquo;<em><a href=\"https:\/\/www.deepl.com\/translator\">Deepl\/com<\/a><\/em>&lsquo;, vraiment excellent.) Et, au fait, en plus de l&rsquo;excellente d\u00e9marche qui habite ce texte, qui est comme une r\u00e9volte contre la \u00ab\u00a0communication-devenue-folle\u00a0\u00bb, il y a une excellente initiative de &lsquo;<em>ConsortiumNews<\/em>&lsquo;, qu&rsquo;il faut saluer parce qu&rsquo;\u00e9tendant consid\u00e9rablement le champ de la presse dissidente, je veux dire dans le sens donn\u00e9 \u00e0 l&rsquo;initiative&#8230; &lsquo;<em>ConsortiumNews<\/em>&lsquo; offre d\u00e9sormais la possibilit\u00e9 de faire traduire automatiquement ses textes <a href=\"https:\/\/consortiumnews.com\/2022\/04\/03\/consortium-news-now-in-104-languages\/\">en 104 langues<\/a> ! Venue de citoyens am\u00e9ricains (point trop am\u00e9ricanistes) qui nous ont tant habitu\u00e9s \u00e0 nous imposer leur sabir d\u00a0\u00bb<em><a href=\"https:\/\/en.wikipedia.org\/wiki\/International_English\">international english<\/a><\/em>&lsquo;, il faut saluer.<\/p>\n<\/p>\n<p><p>C&rsquo;est ce qui m&rsquo;a donn\u00e9 l&rsquo;id\u00e9e, tombant sur Brenner et l&rsquo;aspect inhabituel de la chose, de faire traduire automatiquement son texte par un seul clic sur un bouton &lsquo;<em>translate<\/em>&lsquo; orange plac\u00e9 \u00e0 gauche sur la page du site, de le lire tranquille, d&rsquo;y trouver mon agr\u00e9ment, de le reprendre, de le retravailler un peu, &ndash; et voil\u00e0 le travail ! Avec une forte signification sur ces \u00ab\u00a0temps-devenus-fous\u00a0\u00bb et sa <em>fucking<\/em> &lsquo;communication-devenue-folle&rsquo;, je salue amicalement &lsquo;<em>ConsortiumNews<\/em>&lsquo;, qui fait avancer le <em>schmilblick<\/em> de la presse antiSyst\u00e8me, des dissidents de tous les pays.<\/p>\n<\/p>\n<p><p>Place \u00e0 Brenner, taillant une croupi\u00e8re aux imb\u00e9ciles et aux connards qui nous dirigent dans notre chute finale. C&rsquo;est encore la meilleure voie pour en \u00eatre quitte, car l\u00e0-bas, au bout du chemin, le ridicule tue encore pour crime de d\u00e9shonneur&#8230;<\/p>\n<\/p>\n<p><h4>PhG, <em>Semper Phi<\/em><\/h4>\n<\/p>\n<p><p>_________________________<\/p>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Secousses d&rsquo;imb\u00e9ciles<\/h2>\n<\/p>\n<blockquote>\n<p><p>Michael Brenner explique pourquoi il s&rsquo;abstiendra de tout autre \u00e9crit sur les sujets de l&rsquo;Ukraine et des relations des &Eacute;tats-Unis avec la Russie, la Chine ou les &icirc;les Salomon.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Il n&rsquo;y aura plus rien de moi au sujet de l&rsquo;Ukraine ; ni sur nos relations avec la Russie, la Chine ou les &Icirc;les Salomon.  <\/p>\n<\/p>\n<p><p>Plusieurs raisons expliquent cette abstention.<\/p>\n<\/p>\n<p><p>Premi\u00e8rement, j&rsquo;ai dit \u00e0 peu pr\u00e8s tout ce que j&rsquo;avais \u00e0 dire sur les probl\u00e8mes macro\u00e9conomiques et je ne vois aucune raison de r\u00e9p\u00e9ter ou d&rsquo;examiner les \u00e9v\u00e9nements quotidiens que d&rsquo;autres font extr\u00eamement bien. (<a href=\"https:\/\/www.moonofalabama.org\/\">Moon of Alabama<\/a> ; <a href=\"https:\/\/www.youtube.com\/channel\/UCwGpHa6rMLjSSCBlckm5khw\">Alexander Mercouris<\/a> sur YouTube). <\/p>\n<\/p>\n<p><p>Deuxi\u00e8mement, il est manifestement \u00e9vident que notre soci\u00e9t\u00e9 n&rsquo;est pas capable de tenir un discours honn\u00eate, logique et raisonnablement inform\u00e9 sur des questions importantes. Au lieu de cela, nous faisons l&rsquo;exp\u00e9rience de la fantaisie, de la fabrication, de la stupidit\u00e9 et de la fulmination. Sur un plan plus personnel, cette impression est renforc\u00e9e par des messages de personnes que j&rsquo;ai connues et respect\u00e9es me disant que je suis \u00e0 la solde du pr\u00e9sident russe Vladimir Poutine, \u00ab\u00a0fou\u00a0\u00bb, \u00ab\u00a0un peu trop intelligent\u00a0\u00bb, \u00ab\u00a0Furtwaengler fan\u00a0\u00bb (Netrebko = Furtwaengler = Hitler), \u00ab\u00a0bolchevique de placard\u00a0\u00bb, \u00ab\u00a0marchand de conspiration\u00a0\u00bb, \u00ab\u00a0n&rsquo;a jamais rencontr\u00e9 de paie\u00a0\u00bb (Quid ? Ne me demandez pas) et\/ou \u00ab\u00a0a franchi une ligne\u00a0\u00bb, &ndash; rouge, ambre, vert ou n&rsquo;importe quelle autre putain de couleur. <\/p>\n<\/p>\n<p><p>Troisi\u00e8mement, il va de soi que nos dirigeants nationaux, \u00e9lus ou nomm\u00e9s, sont \u00e9galement incapables de d\u00e9lib\u00e9ration sobre, d&rsquo;honn\u00eatet\u00e9 intellectuelle (avec eux-m\u00eames comme avec nous), de logique \u00e9l\u00e9mentaire, voire de reconnaissance des r\u00e9alit\u00e9s factuelles. Par cons\u00e9quent, le comportement qui en r\u00e9sulte d\u00e9fie toute analyse rationnelle. La pierre angulaire de ces d\u00e9sordres est venue du discours d\u00e9cal\u00e9 du pr\u00e9sident am\u00e9ricain Joe Biden sur Varsovie et de la tentative b\u00e2cl\u00e9e qui a suivi pour nettoyer le g\u00e2chis.<\/p>\n<\/p>\n<p><p>Franchement, un pr\u00e9sident des &Eacute;tats-Unis doit \u00eatre assez idiot pour parler d&rsquo;\u00e9liminer le chef d&rsquo;un gouvernement ennemi fort et volontaire. Le pr\u00e9sident John F. Kennedy est descendu dans ce tunnel sombre et a pay\u00e9 de sa vie, &ndash; et Castro ne poss\u00e9dait pas 3 800 ogives nucl\u00e9aires (il a ensuite d&ucirc; les emprunter au premier ministre sovi\u00e9tique Nikita Khrouchtchev). Le changement de r\u00e9gime \u00e0 Moscou, bien s&ucirc;r, a \u00e9t\u00e9 l&rsquo;objectif de l&rsquo;administration depuis le premier jour ; comme un r\u00eave humide d&rsquo;un adolescent fantasmant de couper le n&oelig;ud gordien d&rsquo;un coup de baguette magique? Mais seul un chef t\u00e9m\u00e9raire et irresponsable proclame cette intention tout en rendant visite au voisin hostile de sa cible. Ainsi, il a \u00e9t\u00e9 laiss\u00e9 \u00e0 notre ambassadeur \u00e0 l&rsquo;OTAN, puis au secr\u00e9taire d&rsquo;&Eacute;tat am\u00e9ricain Antony Blinken, puis au responsable des relations publiques du d\u00e9partement d&rsquo;&Eacute;tat de \u00ab\u00a0revenir en arri\u00e8re\u00a0\u00bb.  <\/p>\n<\/p>\n<p><p>[En relation: <em><a href=\"https:\/\/consortiumnews.com\/2022\/03\/27\/can-russia-escape-the-us-trap\/\">Biden confirme pourquoi les &Eacute;tats-Unis avaient besoin de cette guerre<\/a><\/em> ]<\/p>\n<\/p>\n<p><p>L&rsquo;utilisation habituelle de ce terme d\u00e9bile lui-m\u00eame est un indicateur de notre vanit\u00e9 et de notre arrogance. Ce n&rsquo;est pas une excuse, ni un aveu d&rsquo;erreur. Ce que cela signifie vraiment, c&rsquo;est : \u00ab\u00a0Regardez. J&rsquo;ai gliss\u00e9 en disant ce que je pense vraiment, &ndash; peut-\u00eatre le d\u00e9calage horaire; mais maintenant celui-ci me cause des br&ucirc;lures d&rsquo;estomac. Alors, d\u00e9tendons-nous et effa\u00e7ons simplement tout \u00e7a de notre m\u00e9moire\u00a0\u00bb. <\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Revenir en arri\u00e8re<\/h3>\n<\/p>\n<p><p>Pourtant, vous ne pouvez pas simplement effacer des choses comme \u00e7a. Les gens au-del\u00e0 de la presseSyst\u00e8me l&rsquo;ont entendu &ndash; comme le type \u00e0 qui vous passez la patate chaude. Pour ajouter l&rsquo;injure \u00e0 l&rsquo;insulte, Biden nous a dit le lendemain (ainsi qu&rsquo;au \u00ab\u00a0tueur\u00a0\u00bb\/\u00a0\u00bbcriminel de guerre\u00a0\u00bb Poutine) qu&rsquo;il n&rsquo;avait pas vraiment \u00ab\u00a0fait marche arri\u00e8re\u00a0\u00bb ; c&rsquo;\u00e9tait plut\u00f4t une sorte de \u00ab\u00a0retour en arri\u00e8re\u00a0\u00bb, vous voyez ? <\/p>\n<\/p>\n<p><p>Au cours de sa promenade, il a fait plusieurs arr\u00eats aux stands pour \u00e9mettre des accusations selon lesquelles le gang de Poutine en Ukraine \u00e9tait les m\u00eames Russes qui ont r\u00e9prim\u00e9 les Hongrois en 1956, les Tch\u00e8ques en 1968 et les Afghans dans les ann\u00e9es 1980. C&rsquo;\u00e9tait dans leur ADN, dit-il, recopiant ainsi James Clapper et Wendy Sherman, entre autres.<\/p>\n<\/p>\n<p><p>Bien s&ucirc;r, si cette logique impeccable nous \u00e9tait appliqu\u00e9e, il devrait lier son gouvernement aux Am\u00e9ricains qui ont ethniquement nettoy\u00e9 les 10 millions d&rsquo;indig\u00e8nes de son territoire, conquis le Mexique et vol\u00e9 la moiti\u00e9 de son territoire, caus\u00e9 la mort de 400 000 des Philippins qui se sont rebell\u00e9s contre le joug imp\u00e9rial yankee, ont incendi\u00e9 Hambourg\/Dresde\/Tokyo, bombard\u00e9 Hiroshima et Nagasaki, sem\u00e9 la mort et la destruction au Vietnam, financ\u00e9 et fourni des \u00ab\u00a0escadrons de la mort\u00a0\u00bb \u00e0 travers l&rsquo;Am\u00e9rique centrale, envahi ill\u00e9galement l&rsquo;Irak avec les lourdes cons\u00e9quences que nous subissons toujours endurant, a \u00e9t\u00e9 un complice actif dans le massacre de Houthis, a commis des atrocit\u00e9s \u00e0 Abu Ghraib, Camp Bucca, Guantanamo et des \u00ab\u00a0sites noirs\u00a0\u00bb de la CIA.<\/p>\n<\/p>\n<p><p>Et, il y a quelques mois \u00e0 peine, Biden a personnellement vol\u00e9 8 milliards de dollars appartenant aux Afghans affam\u00e9s dont nous occupions le pays au motif sp\u00e9cieux que nous allions les escorter jusqu&rsquo;au paradis du lait &#038; du miel qu&rsquo;est la d\u00e9mocratie. <\/p>\n<\/p>\n<p><p>[Connexe: <em><a href=\"https:\/\/consortiumnews.com\/2022\/04\/04\/bidens-punishment-of-desperate-afghanistan\/\">la punition de Biden contre l&rsquo;Afghanistan d\u00e9sesp\u00e9r\u00e9<\/a><\/em> ]<\/p>\n<\/p>\n<p><p>C&rsquo;est un dossier qui devrait inciter \u00e0 la prudence avant de lancer des demandes de proc\u00e8s pour crimes de guerre. L\u00e0 encore, \u00e9tant oint par le ciel en tant que nation sauveuse de l&rsquo;humanit\u00e9, nous n&rsquo;avons pas besoin de dire \u00ab\u00a0d\u00e9sol\u00e9\u00a0\u00bb, &ndash; ou m\u00eame de revenir en arri\u00e8re.  <\/p>\n<\/p>\n<p><p>Quoi qu&rsquo;il en soit, de retour de sa promenade, Biden s&rsquo;est vu demander s&rsquo;il avait trouv\u00e9 la solution \u00e0 l&rsquo;affaire \u00ab\u00a0d\u00e9barrassons-nous de Poutine\u00a0\u00bb. \u00ab\u00a0Qu&rsquo;est-ce que tu racontes ? fut sa r\u00e9ponse. Il n&rsquo;y a rien \u00e0 reculer ou \u00e0 corriger n&rsquo;importe quelle d\u00e9marche. Je maintiens ce que j&rsquo;ai dit \u00e0 Varsovie : &lsquo;Personne ne me d\u00e9barrassera donc de ce pr\u00eatre encombrant !'\u00a0\u00bb<\/p>\n<\/p>\n<p><p>Pour d\u00e9crire avec pr\u00e9cision ce genre de vaudeville, nous devons revenir au vocabulaire familier de la rue. Pour \u00eatre franc, Biden d\u00e9couvrait simplement son \u00ab\u00a0imb\u00e9cile\u00a0\u00bb int\u00e9rieur.<\/p>\n<\/p>\n<p><p>C&rsquo;est un terme \u00e9motif unique avec des connotations et des images in\u00e9gal\u00e9es. Ses synonymes ne sont pas \u00ab\u00a0stupide, ignorant, idiot, gaffeur, sourd\u00a0\u00bb. Vous pouvez \u00eatre tout ou partie de ces choses ainsi qu&rsquo;un imb\u00e9cile, &ndash;  OU m\u00eame, ne pas \u00eatre n\u00e9cessairement un imb\u00e9cile. De plus, vous pouvez \u00eatre intelligent, inform\u00e9, beau-parleur et non-imb\u00e9cile ou imb\u00e9cile. Exemples : l&rsquo;omnipr\u00e9sent Michael McFaul, l&rsquo;homme d&rsquo;Obama \u00e0 Moscou, est par excellence de ce type, une  r\u00e9f\u00e9rence pour appr\u00e9cier tous les autres. Le s\u00e9nateur am\u00e9ricain Ted Cruz, qui auditionne actuellement pour une nomination \u00e0 un poste de bouffon \u00e0 la Cour Supr\u00eame am\u00e9ricaine, est un mod\u00e8le alternatif pour ceux qui pr\u00e9f\u00e8rent savourer l&rsquo;audition des imb\u00e9ciles form\u00e9s \u00e0 Harvard.<\/p>\n<\/p>\n<p><p>En revanche, Victoria Nuland est une id\u00e9ologue et une provocatrice impitoyable, mesquine, dogmatique et impolie sans vergogne. Mais ce n&rsquo;est pas une imb\u00e9cile (une connasse). D&rsquo;un autre c\u00f4t\u00e9, consid\u00e9rons Tony Blinken. Il a un grand potentiel et a fait des progr\u00e8s remarquables dans cette direction au cours des derniers mois, mais a peut-\u00eatre besoin d&rsquo;un peu plus d&rsquo;assaisonnement pour \u00e9tablir pleinement ses r\u00e9f\u00e9rences ; ou bien, faire une s\u00e9lection parmi le d\u00e9fil\u00e9 de sommit\u00e9s, d&rsquo;aspirants et d&rsquo;anciens \u00ab\u00a0experts\u00a0\u00bb &#8211; en particulier, ceux de l&rsquo;arm\u00e9e\/du renseignement dont l&rsquo;\u00e9tonnant divorce d&rsquo;avec la r\u00e9alit\u00e9 met en lumi\u00e8re nos \u00e9checs en s\u00e9rie dans l&rsquo;utilisation coercitive de la force durant toutes ces longues ann\u00e9es &mdash; qui polluent les ondes radiophoniques et t\u00e9l\u00e9visuelles. <\/p>\n<\/p>\n<p><p>(L&rsquo;esp\u00e8ce &lsquo;imb\u00e9cile&rsquo; n&rsquo;est pas limit\u00e9e aux &Eacute;tats-Unis. Sa prolif\u00e9ration  dans des lieux agr\u00e9ables \u00e0 l&rsquo;\u00e9tranger a vu des sp\u00e9cimens de premier ordre appara&icirc;tre dans un certain nombre de pays : par exemple, le Premier ministre britannique Boris Johnson avec ses acolytes, la ministre des Affaires \u00e9trang\u00e8res Liz Truss et le secr\u00e9taire d&rsquo;&Eacute;tat \u00e0 la D\u00e9fense Ben Wallace.)<\/p>\n<\/p>\n<p><p>Les imb\u00e9ciles ont tendance \u00e0 avoir un comportement erratique, des pens\u00e9es d\u00e9cousues, une grande tol\u00e9rance \u00e0 l&rsquo;incoh\u00e9rence, incapables de soutenir un projet et sujets aux accidents. Ils prosp\u00e8rent dans des soci\u00e9t\u00e9s nihilistes et narcissiques comme la n\u00f4tre o&ugrave; la g\u00eane n&rsquo;existe pas. L&rsquo;imb\u00e9cile (ou connard) a une pr\u00e9f\u00e9rence naturelle pour un processus de d\u00e9cision fluide et une politique ambigu\u00eb. Cela lui \u00e9pargne le besoin de discipliner ses propres pens\u00e9es, de peser syst\u00e9matiquement ses choix et de s&rsquo;engager \u00e0 poursuivre une ligne d&rsquo;action d\u00e9finie.<\/p>\n<\/p>\n<p><p>Ces circonstances, bien s&ucirc;r, jouent \u00e9galement \u00e0 l&rsquo;avantage des acolytes qui connaissent l&rsquo;esprit de la chose, ont un objectif fixe de suivisme et sont pr\u00eats \u00e0 les promouvoir en dehors de toute d\u00e9lib\u00e9ration formelle. Dans un gouvernement comme celui de Biden o&ugrave; les deux types pr\u00e9dominent, il n&rsquo;y a donc aucune pression interne pour qu&rsquo;un pr\u00e9sident d\u00e9j\u00e0 faible se ressaisisse et redresse les choses. <\/p>\n<\/p>\n<p><p>Exemple : le lendemain du jour o&ugrave; Biden a entam\u00e9 une conversation t\u00e9l\u00e9phonique cordiale avec le pr\u00e9sident chinois Xi Jinping o&ugrave; il exprime le d\u00e9sir d&rsquo;\u00e9viter un conflit grave et r\u00e9affirme l&rsquo;engagement continu des &Eacute;tats-Unis envers le principe d'\u00a0\u00bbUne Seule Chine\u00a0\u00bb, les responsables du D\u00e9partement d&rsquo;&Eacute;tat rencontrent leurs homologues ta\u00efwanais \u00e0 Vienne pour arranger de nouvelles ventes d&rsquo;armes et la promotion de l&rsquo;adh\u00e9sion de Taiwan aux agences sp\u00e9cialis\u00e9es de l&rsquo;ONU.<\/p>\n<\/p>\n<p><p>Cela a &lsquo;annul\u00e9&rsquo; la confiance qui restait entre P\u00e9kin et Washington. Pourtant, les hauts fonctionnaires ne s&#8217;embarrassaient nullement de voir l&rsquo;\u00e9vidence. Quelques mois plus tard, Blinken et Nuland demandaient au ministre des Affaires \u00e9trang\u00e8res Wang Yi de<\/p>\n<p>a) r\u00e9duire les importations de gaz liqu\u00e9fi\u00e9 afin que davantage de cette mati\u00e8re soit disponible pour l&rsquo;Allemagne qui venait de fermer NordStream II, et<\/p>\n<p>b) de se joindre \u00e0 la campagne de sanctions contre son proche alli\u00e9 et partenaire, la Russie, sinon les &Eacute;tats-Unis se f\u00e2cheraient.<\/p>\n<\/p>\n<p><p>Cela apr\u00e8s un an de d\u00e9nonciations, de sanctions et de menaces, &ndash; y compris des mesures encourageant l&rsquo;ind\u00e9pendance de Taiwan. Comme on pouvait s&rsquo;y attendre, Yi n&rsquo;a pas m\u00e2ch\u00e9 ses mots en rejetant du revers de la main les propositions am\u00e9ricaines et a profit\u00e9 de l&rsquo;occasion pour faire entendre aux deux imb\u00e9ciles de tr\u00e8s s\u00e9v\u00e8res v\u00e9rit\u00e9s sur les m\u00e9faits am\u00e9ricains. Le point g\u00e9n\u00e9ral \u00e0 souligner est que le mod\u00e8le de d\u00e9finition d&rsquo;un imb\u00e9cile inclut un m\u00e9pris des \u00e9v\u00e9nements pass\u00e9s et de la teneur des relations pass\u00e9es &ndash; il\/elle consid\u00e8re la vie comme une s\u00e9rie d&rsquo;\u00e9pisodes distincts non encombr\u00e9s par ce qu&rsquo;on nomme \u00ab\u00a0l&rsquo;histoire\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>Ce comportement absurde peut \u00eatre compris comme une manifestation, au plus haut niveau du gouvernement am\u00e9ricain, de l&rsquo;attitude \u00ab\u00a0J&rsquo;ai besoin, je veux : le monde est l\u00e0 pour s&rsquo;ex\u00e9cuter\u00a0\u00bb, qui impr\u00e8gne notre culture narcissique. Comportement immature mais f\u00e9cond dans sa production, et l&rsquo;encouragement faite aux imb\u00e9ciles de poursuivre leurs entreprises.<\/p>\n<\/p>\n<p><p>Les pitreries des imb\u00e9ciles seraient amusantes \u00e0 observer, pour ceux qui ont un sens de l&rsquo;humour sardonique de toutes les fa\u00e7ons, si les circonstances n&rsquo;\u00e9taient pas si p\u00e9rilleuses. Ainsi, essayer d&rsquo;analyser les conditions kal\u00e9idoscopiques qu&rsquo;ils produisent est profond\u00e9ment frustrant et d\u00e9courageant. J&rsquo;abandonne. Cela ne fera aucune diff\u00e9rence dans un sens ou dans l&rsquo;autre. Cela permettrait une visite tranquille \u00e0 Montevideo pour \u00e9couter la soprano russe Anna Netrebko chanter &lsquo;<em>Un bel d&igrave;, vedremo<\/em>&lsquo; (&lsquo;Un beau jour, nous verrons\u00a0\u00bb).<\/p>\n<\/p>\n<p><p>[Connexe : <em><a href=\"https:\/\/consortiumnews.com\/2022\/03\/05\/war-conflict-enemies-of-truth\/\">guerre, conflit et ennemis de la v\u00e9rit\u00e9<\/a><\/em> ]<\/p>\n<\/p>\n<p><p>Enfin, apr\u00e8s avoir distribu\u00e9 les remarques ci-dessus, la question de la poursuite des commentaires pourrait bien devenir sans objet alors que le public se r\u00e9duit tr\u00e8s rapidement, \u00e0 la mesure des reportages fond\u00e9s sur les faits dans les r\u00e9dactions fi\u00e9vreuses de CNN et du<em> New York Times.<\/em> <\/p>\n<\/p>\n<p><h4>Michael Brenner<\/h4><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gr\u00e8ve \u00e0 cause d&rsquo;Ukrisis 7 avril 2022 (13H30) &ndash; Dans ces temps d&rsquo;angoisse, de col\u00e8re, de frustration, j&rsquo;ai trouv\u00e9 tr\u00e8s rafraichissant et d\u00e9tendant le texte de Michael Brenner, qui pourrait aussi s&rsquo;intituler : \u00ab\u00a0Pourquoi j&rsquo;en ai marre d&rsquo;Ukrisis (et du reste)\u00a0\u00bb. Parfois, et m\u00eame souvent, j&rsquo;\u00e9prouve le m\u00eame sentiment tant le poids de l&rsquo;h\u00e9g\u00e9monie globale&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[1235,21239,5091,12681,21499,4357,5520],"class_list":["post-80147","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-biden","tag-brenner","tag-caricature","tag-consortiumnews","tag-jerk","tag-michael","tag-nuland"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80147","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=80147"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80147\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=80147"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=80147"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=80147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}