{"id":80176,"date":"2022-04-30T08:27:13","date_gmt":"2022-04-30T08:27:13","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2022\/04\/30\/paul-craig-roberts-aime-t-il-les-genocides\/"},"modified":"2022-04-30T08:27:13","modified_gmt":"2022-04-30T08:27:13","slug":"paul-craig-roberts-aime-t-il-les-genocides","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2022\/04\/30\/paul-craig-roberts-aime-t-il-les-genocides\/","title":{"rendered":"Paul Craig Roberts aime-t-il les g\u00e9nocides ?"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Paul Craig Roberts aime-t-il les g\u00e9nocides ?<\/h2>\n<\/p>\n<p><p>&#8230;Ou peut-\u00eatre pense-t-il, comme le Bundeskanzler Olaf Scholz, petit-fils de Fritz von Scholz, lieutenant-g\u00e9n\u00e9ral SS qui a supervis\u00e9 le massacre des Juifs en Pologne et en Ukraine, qu&rsquo;un g\u00e9nocide est une blague ? Voyons voir&hellip;<\/p>\n<\/p>\n<p><p>Un lecteur m&rsquo;a demand\u00e9 de commenter <a href=\"https:\/\/www.paulcraigroberts.org\/2022\/04\/14\/the-kremlin-has-missed-the-opportunity-to-end-the-provocations-of-russia-that-are-bringing-the-world-to-nuclear-war\/\">un r\u00e9cent billet<\/a>de Roberts intitul\u00e9 &laquo; <em>Le Kremlin a manqu\u00e9 l&rsquo;occasion de mettre fin aux provocations de la Russie qui am\u00e8nent le monde \u00e0 la guerre nucl\u00e9aire<\/em> &raquo;. J&rsquo;y ai donc jet\u00e9 un coup d&rsquo;&oelig;il. Au d\u00e9but, cela m&rsquo;a mis en col\u00e8re, mais seulement pendant un moment, parce qu&rsquo;il n&rsquo;y a aucune possibilit\u00e9 de pr\u00e9judice r\u00e9el \u00e0 cause de son gribouillage : ses conseils non sollicit\u00e9s au <em><u>&laquo;<\/u> Kremlin <\/em>&raquo; passeront inaper\u00e7us et ne seront donc pas pris en compte. Cela m&rsquo;a plut\u00f4t rendu triste. J&rsquo;avais une haute opinion de Roberts, mais il n&rsquo;est plus qu&rsquo;un vieil homme d\u00e9sorient\u00e9 qui, comme notre ami Brendan, a rat\u00e9 une excellente occasion de raccrocher et de dispara&icirc;tre. J&rsquo;essaie ici d&rsquo;\u00eatre gentil et poli.<\/p>\n<\/p>\n<p><p>Roberts a jug\u00e9 bon d&rsquo;\u00e9crire que &laquo;<em> si la Russie avait frapp\u00e9 l&rsquo;Ukraine avec une attaque conventionnelle d\u00e9vastatrice et globale, la guerre se serait termin\u00e9e avant d&rsquo;avoir commenc\u00e9 <\/em>&raquo; et, apr\u00e8s quelques r\u00e9flexions suppl\u00e9mentaires, que &laquo;<em> l&rsquo;\u00e9chec de la Russie \u00e0 impressionner l&rsquo;Occident par un exercice \u00e9crasant de la force militaire en Ukraine signifie qu&rsquo;une nouvelle \u00e9tape a \u00e9t\u00e9 franchie vers l&rsquo;armageddon nucl\u00e9aire <\/em>&raquo;. Et il poursuit en disant : &laquo;<em> L&rsquo;incapacit\u00e9 du Kremlin \u00e0 \u00eatre proactif et son refus d&rsquo;\u00e9liminer la cinqui\u00e8me colonne de Washington des cercles dirigeants de la Russie seront les marques de la d\u00e9faite russe. <\/em>&raquo;<\/p>\n<\/p>\n<p><p>Vraiment ? Non, pas vraiment.<\/p>\n<\/p>\n<p><p>Je ne devrais pas faire de suppositions sur ce que vous ou Roberts savez ou ne savez pas sur l&rsquo;Ukraine ou &laquo;<em> le Kremlin <\/em>&raquo;, je vais donc simplement \u00e9noncer l&rsquo;\u00e9vidence.<\/p>\n<\/p>\n<p><p>Il n&rsquo;y a pas de diff\u00e9rence facilement perceptible entre les Russes et les Ukrainiens : m\u00eame culture, m\u00eame langue, m\u00eame religion et m\u00eame histoire. En tant qu&rsquo;&Eacute;tat, la R\u00e9publique socialiste sovi\u00e9tique d&rsquo;Ukraine est un &Eacute;tat en faillite ; en tant que territoire, elle fait partie de la Russie. Par cons\u00e9quent, une attaque g\u00e9n\u00e9ralis\u00e9e contre l&rsquo;Ukraine serait essentiellement une attaque contre la Russie elle-m\u00eame. Apparemment, Roberts pense que les Russes devraient tuer des millions d&rsquo;autres Russes afin d&rsquo;impressionner l&rsquo;Occident. C&rsquo;est vraiment mignon, vous savez, cette sorte de manie g\u00e9nocidaire, mais compl\u00e8tement impossible.<\/p>\n<\/p>\n<p><p>La complexit\u00e9 de l&rsquo;op\u00e9ration sp\u00e9ciale russe en Ukraine consistait \u00e0 s\u00e9parer la population civile (qui devait \u00eatre \u00e9vacu\u00e9e) et les militaires ukrainiens r\u00e9guliers (qui devaient avoir la possibilit\u00e9 de se rendre pacifiquement) des bataillons nazis (qui devaient \u00eatre tu\u00e9s au combat ou captur\u00e9s, condamn\u00e9s par un tribunal et fusill\u00e9s). Ce n&rsquo;est pas quelque chose qui peut \u00eatre fait rapidement.<\/p>\n<\/p>\n<p><p>Il y a d&rsquo;autres raisons, moins importantes mais n\u00e9anmoins tr\u00e8s significatives, de proc\u00e9der lentement :<\/p>\n<\/p>\n<p><p>1. Il existe un groupe assez important d&rsquo;Ukrainiens qui voulaient que l&rsquo;Ukraine fasse partie de l&rsquo;Europe, et non de la Russie. Ils quittent actuellement le territoire ukrainien, principalement pour la Pologne, et cela, du point de vue russe, est une chose merveilleuse parce que l&rsquo;Ukraine n&rsquo;est pas l&rsquo;Europe, c&rsquo;est la Russie, et ceux qui croient que c&rsquo;est l&rsquo;Europe ou qui veulent que ce soit l&rsquo;Europe devraient avoir une chance d&rsquo;aller dans l&rsquo;Europe de leurs r\u00eaves et d&rsquo;y rester pour toujours, aidant ainsi la situation d\u00e9mographique g\u00e9n\u00e9rale d\u00e9sastreuse de l&rsquo;Europe et la p\u00e9nurie sp\u00e9cifique de personnes blanches. C&rsquo;est pour cette raison qu&rsquo;il a \u00e9t\u00e9 important de maintenir la fronti\u00e8re occidentale de l&rsquo;Ukraine ouverte aux migrants en partance, m\u00eame si cela permet aux armes et aux mercenaires de s&rsquo;infiltrer (pour que les Russes les fassent sauter).<\/p>\n<\/p>\n<p><p>2. La volont\u00e9 des Europ\u00e9ens d&rsquo;absorber des millions et des millions de migrants ukrainiens, alors qu&rsquo;ils rechignent \u00e0 accepter un nombre comparable de migrants du Moyen-Orient ou d&rsquo;Afrique du Nord, illustre leur racisme fondamental. En l&rsquo;\u00e9tat actuel des choses, les deux tiers du monde sont soit neutres, soit soutiennent la Russie dans ses efforts pour reconqu\u00e9rir l&rsquo;Ukraine ; \u00e0 mesure que le message selon lequel l&rsquo;UE et l&rsquo;OTAN sont essentiellement des organisations de supr\u00e9macistes blancs se r\u00e9pand dans le monde, de plus en plus de pays passeront de la neutralit\u00e9 au soutien sans que la Russie ait \u00e0 lever le petit doigt pour les convaincre. De ce point de vue, il est vraiment utile que beaucoup d&rsquo;Ukrainiens aiment dessiner des croix gamm\u00e9es sur les monuments et crier des slogans nazis tels que &laquo;<em> Slava Ukraini <\/em>&raquo; (du mill\u00e9sime des collaborateurs nazis de la Seconde Guerre mondiale) et &laquo;<em> Ukraina ponad use<\/em> &raquo; (la version ukrainienne de &laquo;<em> Ukraine \u00fcber alles <\/em>&raquo;).<\/p>\n<\/p>\n<p><p>3. La Russie a un grand et prosp\u00e8re avenir en tant que pays riche, bien \u00e9duqu\u00e9, civilis\u00e9, vaste et riche en ressources, mais cet avenir n&rsquo;a rien \u00e0 voir avec l&rsquo;Europe ou le reste de l&rsquo;Occident, qui vont s&rsquo;effondrer. Le fait que la Russie ait \u00e9t\u00e9 assez \u00e9troitement int\u00e9gr\u00e9e \u00e0 l&rsquo;Occident depuis que Pierre le Grand a transf\u00e9r\u00e9 la capitale \u00e0 Saint-P\u00e9tersbourg a compliqu\u00e9 sa transition pour s&rsquo;\u00e9loigner de l&rsquo;Occident et se tourner vers l&rsquo;Est. Les sanctions occidentales, la russophobie rampante et l&rsquo;application de la culture d&rsquo;annulation \u00e0 la culture russe ont rendu cette transition in\u00e9vitable aux yeux de la plupart des Russes, mais le processus prend du temps. Il ne serait pas utile que les tensions avec l&rsquo;Occident diminuent pr\u00e9matur\u00e9ment ou que les sanctions anti-russes soient lev\u00e9es avant qu&rsquo;elles ne soient rendues compl\u00e8tement inutiles. Par ailleurs, le refus de l&rsquo;Occident d&rsquo;acheter de l&rsquo;\u00e9nergie, des m\u00e9taux, des engrais et d&rsquo;autres produits essentiels russes acc\u00e9l\u00e8re le calendrier de son effondrement, ce qui, pour la Russie, est \u00e9galement positif.<\/p>\n<\/p>\n<p><p>4. Imm\u00e9diatement apr\u00e8s le d\u00e9but de l&rsquo;op\u00e9ration sp\u00e9ciale russe en Ukraine, une grande partie des cinqui\u00e8mes colonnes restantes ont quitt\u00e9 la Russie pour d&rsquo;autres pays. Ils n&rsquo;avaient d\u00e9j\u00e0 plus d&rsquo;impact sur la politique russe, mais ils exer\u00e7aient encore une certaine influence dans la culture et l&rsquo;\u00e9ducation, et leur d\u00e9part a \u00e9t\u00e9 tr\u00e8s bien accueilli. &Eacute;tant donn\u00e9 le soutien absolument \u00e9crasant de l&rsquo;opinion publique russe \u00e0 l&rsquo;op\u00e9ration sp\u00e9ciale, les lib\u00e9raux qui se sont prononc\u00e9s contre celle-ci se sont ainsi retir\u00e9s de la vie publique russe, laissant la place \u00e0 de nouveaux talents et \u00e0 du sang neuf. Il s&rsquo;agit \u00e9galement d&rsquo;un processus qui doit suivre son cours et ne doit pas \u00eatre pr\u00e9cipit\u00e9.<\/p>\n<\/p>\n<p><p>5. L&rsquo;op\u00e9ration sp\u00e9ciale a permis \u00e0 la Russie de d\u00e9montrer la sup\u00e9riorit\u00e9 \u00e9crasante de ses forces arm\u00e9es vis-\u00e0-vis de l&rsquo;OTAN. Toutes les armes que l&rsquo;Occident a r\u00e9ussi \u00e0 infiltrer en Ukraine sont soit d\u00e9truites par des tirs de missiles, soit accumul\u00e9es dans des hangars apr\u00e8s avoir \u00e9t\u00e9 abandonn\u00e9es par les troupes ukrainiennes qui battent en retraite ou se rendent. Aucun des Stingers, Javelins ou autres d\u00e9chets militaires obsol\u00e8tes n&rsquo;a fait une grande diff\u00e9rence. L&rsquo;Occident ne peut pas faire grand-chose de significatif pour entraver les progr\u00e8s prudents et mesur\u00e9s de la Russie en Ukraine. Une fois de plus, le temps joue en faveur de la Russie : il faudra encore quelques mois pour que l&rsquo;Occident se rende compte que tous ces milliards d\u00e9pens\u00e9s pour l&rsquo;aide \u00e0 l&rsquo;Ukraine sont all\u00e9s dans un trou noir sans qu&rsquo;il y ait de r\u00e9sultat.<\/p>\n<\/p>\n<p><p>6. Enfin, il y a ce que la Russie doit faire en plus de s&rsquo;occuper de la situation dans l'(ancienne) Ukraine, c&rsquo;est-\u00e0-dire d\u00e9manteler l&rsquo;OTAN. Cela n\u00e9cessitera une sorte de petit projet de d\u00e9monstration : prendre le contr\u00f4le d&rsquo;un petit membre insignifiant de l&rsquo;OTAN et regarder tous les autres membres de l&rsquo;OTAN s&rsquo;enfuir au lieu d&rsquo;entrer en guerre contre la Russie. Le mythe de l&rsquo;OTAN en tant qu&rsquo;organisation d\u00e9fensive (par opposition \u00e0 offensive) serait dissip\u00e9 et l&rsquo;OTAN n&rsquo;existerait plus. Le pays d\u00e9monstrateur pourrait \u00eatre la Lituanie, par exemple : Pierre le Grand a achet\u00e9 les Baltes \u00e0 la Su\u00e8de pour 1000 pi\u00e8ces d&rsquo;argent lors du trait\u00e9 de Nystad, le 10 septembre 1721, c&rsquo;est donc un territoire russe. Contrairement \u00e0 l&rsquo;Ukraine, qui est immense, la Lituanie est minuscule et la campagne enti\u00e8re serait termin\u00e9e en une semaine environ. Mais si la Finlande ou la Su\u00e8de souhaitent se porter volontaires pour jouer le r\u00f4le de victime exemplaire en tentant d&rsquo;adh\u00e9rer \u00e0 l&rsquo;OTAN, ce serait \u00e9galement tr\u00e8s bien. La s\u00e9curit\u00e9 de la Finlande est garantie par son engagement de neutralit\u00e9, sur la base duquel la Russie (l&rsquo;URSS \u00e0 l&rsquo;\u00e9poque) a retir\u00e9 sa base militaire du sol finlandais. Si la Finlande d\u00e9cidait de revenir sur ce trait\u00e9, elle perdrait sa s\u00e9curit\u00e9.<\/p>\n<\/p>\n<p><p>Roberts semble croire que le refus de la Russie de d\u00e9truire l&rsquo;Ukraine par une force \u00e9crasante rend la guerre nucl\u00e9aire plus probable parce qu&rsquo;elle &laquo;<em> donne \u00e0 Washington le contr\u00f4le du choix<\/em> &raquo;<em>.<\/em> La position sup\u00e9rieure de la Russie par rapport \u00e0 toute provocation nucl\u00e9aire potentielle est le sujet d&rsquo;un autre article, mais je vous assure qu&rsquo;elle n&rsquo;a absolument rien \u00e0 voir avec &laquo;<em> le contr\u00f4le du choix par Washington <\/em>&raquo;, car comment diable Washington choisirait-il un suicide national \u00e0 propos de l&rsquo;Ukraine ? La th\u00e8se selon laquelle &laquo;<em> l&rsquo;\u00e9chec de la Russie \u00e0 d\u00e9truire rapidement l&rsquo;Ukraine augmente la probabilit\u00e9 d&rsquo;une guerre nucl\u00e9aire <\/em>&raquo; est&hellip; je cherche un mot ici&hellip; stupide.<\/p>\n<\/p>\n<p><p>22 avril 2022,  <a href=\"http:\/\/thesaker.is\/does-paul-craig-roberts-like-genocide\/\">Saker Blog<\/a>, &ndash; Traduction du <em><a href=\"https:\/\/lesakerfrancophone.fr\/paul-craig-roberts-aime-t-il-les-genocides\">Sakerfrancophone<\/a><\/em><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Paul Craig Roberts aime-t-il les g\u00e9nocides ? &#8230;Ou peut-\u00eatre pense-t-il, comme le Bundeskanzler Olaf Scholz, petit-fils de Fritz von Scholz, lieutenant-g\u00e9n\u00e9ral SS qui a supervis\u00e9 le massacre des Juifs en Pologne et en Ukraine, qu&rsquo;un g\u00e9nocide est une blague ? Voyons voir&hellip; Un lecteur m&rsquo;a demand\u00e9 de commenter un r\u00e9cent billetde Roberts intitul\u00e9 &laquo; Le&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[29],"tags":[4750,8601,3004,2668,3140,4728,13670],"class_list":["post-80176","post","type-post","status-publish","format-standard","hentry","category-les-carnets-de-dimitri-orlov-1","tag-craig","tag-lettonie","tag-nucleaire","tag-orlov","tag-paul","tag-roberts","tag-ukrisis"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=80176"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80176\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=80176"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=80176"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=80176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}