{"id":80195,"date":"2022-05-16T17:30:49","date_gmt":"2022-05-16T17:30:49","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2022\/05\/16\/rapsit-usa2022-the-road-to-hell\/"},"modified":"2022-05-16T17:30:49","modified_gmt":"2022-05-16T17:30:49","slug":"rapsit-usa2022-the-road-to-hell","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2022\/05\/16\/rapsit-usa2022-the-road-to-hell\/","title":{"rendered":"RapSit-USA2022\u00a0: \u2018<em>The Road to Hell<\/em>&lsquo;\u00a0?"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">RapSit-USA2022 : &lsquo;<em>The Road to Hell<\/em>&lsquo; ?<\/h2>\n<\/p>\n<p><p>Nous pensons d&rsquo;une fa\u00e7on de plus en plus insistante, &ndash; on le lit dans nombre de nos textes, &ndash; que ce qui doit \u00eatre observ\u00e9 avec attention pour en venir au brasier central de la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-la-gces\">GrandeCrise<\/a> ne se trouve ni \u00e0 Moscou, ni dans les champs de l&rsquo;Ukraine ni m\u00eame dans dans les gratte-ciels d&rsquo;une &laquo; <em>arrogance d\u00e9sinvolte<\/em> &raquo; de Bruxelles, mais bien s&ucirc;r outre-Atlantique. Tout ce qui s&rsquo;y d\u00e9roule d\u00e9ferle vers la m\u00eame issue, y compris l&rsquo;extraordinaire aveuglement de l&rsquo;\u00e9cume de l&rsquo;\u00e9lite am\u00e9ricaniste, dans le chef de ce Congr\u00e8s votant sans y rien comprendre et, vraiment, s&rsquo;y fichant compl\u00e8tement sinon l&rsquo;ivresse d&rsquo;un instant pour des piles de $milliards d&rsquo;armement pour l&rsquo;Ukraine<\/p>\n<\/p>\n<p><p>Nous avons donc choisi comme titre de cet \u00e9pisode o&ugrave; nous alimentons un peu plus la connaissance g\u00e9n\u00e9rale de l&rsquo;effondrement am\u00e9ricaniste la fameuse chanson de Chris Rea, &lsquo;<em><a href=\"https:\/\/en.wikipedia.org\/wiki\/The_Road_to_Hell\">The Road to Hell<\/a><\/em>&lsquo;, de l&rsquo;ann\u00e9e tragique de1989 entamant l&rsquo;ultime \u00e9tape de l&rsquo;aventure am\u00e9ricaniste. Le chanteur y annon\u00e7ait le chaos complet o&ugrave; nous nous trouvons aujourd&rsquo;hui.<\/p>\n<\/p>\n<p><p>L&rsquo;historien Victor Davis Hanson, sp\u00e9cialiste des guerres antiques pour \u00e9clairer nos conflits actuels, r\u00e9put\u00e9 pour ses opinions de conservateur \u00ab\u00a0ultra-dur\u00a0\u00bb mais retranch\u00e9 dans l&rsquo;enseignement des P\u00e8res Fondateurs, nous convie donc \u00e0 &laquo; <em><a href=\"https:\/\/www.zerohedge.com\/political\/victor-davis-hanson-imagine-unimaginable\">Imaginer l&rsquo;inimaginable<\/a><\/em> &raquo;. Hanson pense que les cinq prochains mois, menant aux \u00e9lections de novembre 2022, seront un v\u00e9ritable carnage social et psychologique parcouru de <a href=\"https:\/\/www.zerohedge.com\/political\/greenwald-demented-and-selective-game-instantly-blaming-political-opponents-mass\">tueries improbables<\/a>, au bout duquel \u00e9mergeront deux factions irr\u00e9m\u00e9diablement confort\u00e9es dans leur haines, chacune l&rsquo;une de l&rsquo;autre, dans un pays immense, dirig\u00e9 par une \u00e9lite de zombies ivres d&rsquo;<em>hybris<\/em>, s&rsquo;enfon\u00e7ant dans la sauvagerie. (Voyez <a href=\"https:\/\/sonar21.com\/proud-to-be-an-american-in-philadelphia\/\">une vid\u00e9o symbolique<\/a> qu&rsquo;a retrouv\u00e9e Larry Johnson, montrant les rues de Philadelphie montrant des zombies d\u00e9mocratiques, les montrant marchant en une \u00e9trange position courb\u00e9e&#8230;)<\/p>\n<\/p>\n<p><p>Quelques extraits du texte de Hanson:<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Les Am\u00e9ricains entrent maintenant dans un territoire inexplor\u00e9 et r\u00e9volutionnaire. Ils pourraient \u00eatre t\u00e9moins, au cours des cinq prochains mois, de choses qui, autrefois, auraient sembl\u00e9 inimaginables<\/em>. [&hellip;]<\/p>\n<\/p>\n<p><p>&raquo; <em>Les fondements traditionnels du syst\u00e8me am\u00e9ricain, &ndash; une \u00e9conomie stable, une ind\u00e9pendance \u00e9nerg\u00e9tique, de vastes exc\u00e9dents alimentaires, des universit\u00e9s sacr\u00e9es, un syst\u00e8me judiciaire professionnel, des forces de l&rsquo;ordre et un syst\u00e8me de justice p\u00e9nale cr\u00e9dible, &ndash; sont en train de se dissoudre.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Les prix de l&rsquo;essence et du diesel atteignent des niveaux historiques. L&rsquo;inflation est \u00e0 son plus haut niveau depuis 40 ans. Les voitures et les maisons neuves sont inabordables. Le rem\u00e8de n\u00e9cessaire, \u00e0 savoir des taux d&rsquo;int\u00e9r\u00eat \u00e9lev\u00e9s et une politique mon\u00e9taire restrictive, sera presque aussi grave que la maladie qu&rsquo;est l&rsquo;hyperinflation.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Il n&rsquo;y a plus de fronti\u00e8re Sud.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Attendez-vous \u00e0 ce que plus d&rsquo;un million de ressortissants \u00e9trangers d\u00e9ferlent cet \u00e9t\u00e9 sur les &Eacute;tats-Unis sans contr\u00f4le, test COVID ou vaccination. Aucun n&rsquo;aura \u00e0 se soucier des cons\u00e9quences d&rsquo;une infraction \u00e0 la loi am\u00e9ricaine sur l&rsquo;immigration.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>La police est sous-financ\u00e9e et de plus en plus d\u00e9sengag\u00e9e. Les procureurs de district lib\u00e8rent d\u00e9lib\u00e9r\u00e9ment des criminels violents sans charges. (La semaine derni\u00e8re, 10 000 personnes ont litt\u00e9ralement vu un homme d\u00e9rang\u00e9, arm\u00e9 d&rsquo;un couteau, attaquer le com\u00e9dien Dave Chappelle sur la sc\u00e8ne du Hollywood Bowl, et le procureur du comt\u00e9 de Los Angeles a refus\u00e9 de porter plainte). Les meurtres et les agressions montent en fl\u00e8che. Les car-jackings et les vols avec effraction sont d\u00e9sormais des \u00e9v\u00e9nements normaux dans les grandes villes.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>La criminalit\u00e9 est d\u00e9sormais essentiellement une affaire politique. L&rsquo;id\u00e9ologie, la race et la politique d\u00e9terminent si la loi est m\u00eame appliqu\u00e9e.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Les rayons des supermarch\u00e9s se vident et les viandes sont d\u00e9sormais hors de port\u00e9e de millions d&rsquo;Am\u00e9ricains. Un pr\u00e9sident am\u00e9ricain, &ndash; une premi\u00e8re, &ndash; met en garde contre les p\u00e9nuries alimentaires. Le lait maternis\u00e9 a disparu de nombreux rayons.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>La politique ressemble aux derniers jours violents de la R\u00e9publique romaine. Une fuite ill\u00e9gale d&rsquo;un possible renversement imminent de l&rsquo;arr\u00eat &lsquo;Roe v. Wade&rsquo; <\/em>[1972]<em> par la Cour Supr\u00eame, qui permettrait aux \u00e9lecteurs des &Eacute;tats de fixer leurs propres lois sur l&rsquo;avortement <\/em>[au lieu de suivre la loi f\u00e9d\u00e9rale]<em>, a cr\u00e9\u00e9 une hyst\u00e9rie nationale.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Jamais un pr\u00e9sident n&rsquo;avait tacitement approuv\u00e9 des foules de manifestants se pr\u00e9sentant au domicile des juges de la Cour supr\u00eame pour les invectiver et les intimider afin qu&rsquo;ils modifient leur vote.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Il n&rsquo;y a plus de libert\u00e9 d&rsquo;expression sur les campus.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Le m\u00e9rite dispara&icirc;t. L&rsquo;admission, l&#8217;embauche, la promotion, la r\u00e9tention, le classement et l&rsquo;avancement d\u00e9pendent de plus en plus de l&rsquo;adh\u00e9sion aux bonnes orthodoxies ou de l&rsquo;appartenance \u00e0 la bonne cat\u00e9gorie raciale, sexuelle ou ethnique.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Lorsque le nouveau commissariat du campus aura fini d&rsquo;absorber les derniers vestiges des \u00e9coles scientifiques, math\u00e9matiques, d&rsquo;ing\u00e9nierie, m\u00e9dicales et professionnelles, l&rsquo;Am\u00e9rique glissera vers une m\u00e9diocrit\u00e9 permanente et un d\u00e9clin irr\u00e9versible du niveau de vie.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Que s&rsquo;est-il pass\u00e9 ?<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Rappelez-vous que toutes ces catastrophes sont auto-induites. Ce sont des choix, pas une fatalit\u00e9&#8230; <\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Bien entendu, tout cela se profile sur le fond de l&rsquo;immense crise <em>Ukrisis <\/em>dont divers signes nous montrent qu&rsquo;elle est en train de p\u00e9n\u00e9trer dans les structures de l&#8217;empire en cours de d\u00e9sint\u00e9gration, de constituer une crise pour l&#8217;empire lui-m\u00eame, acc\u00e9l\u00e9rant irr\u00e9sistiblement la d\u00e9sint\u00e9gration, <a href=\"https:\/\/www.dedefensa.org\/article\/un-tournant-furieux-aux-usa\">renfor\u00e7ant le lien<\/a> qu&rsquo;on a souvent mis en \u00e9vidence entre les crises ext\u00e9rieures et les crises int\u00e9rieures<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepblue\" style=\"color:#0f3955; font-size:1.25em\">USA &#038; <em>Ukrisis<\/em> : coup de fil<\/h3>\n<\/p>\n<p><p>Il y a d&rsquo;abord l&rsquo;affaire du coup de t\u00e9l\u00e9phone de Austin (secr\u00e9taire \u00e0 la d\u00e9fense, USA) \u00e0 Shoigou (ministre de la d\u00e9fense) ; ou plut\u00f4t, devrions-nous dire, enfin les Russes acceptant de prendre les appels t\u00e9l\u00e9phoniques de leurs \u00ab\u00a0coll\u00e8gues\u00a0\u00bb am\u00e9ricanistes du Pentagone. On sait que cela fait plusieurs mois que les \u00ab\u00a0coll\u00e8gues\u00a0\u00bb russes refusent de d\u00e9crocher le t\u00e9l\u00e9phone, &ndash; depuis le 11 f\u00e9vrier pour le pr\u00e9sident du comit\u00e9 des chefs d&rsquo;\u00e9tat-major US (g\u00e9n\u00e9ral Milley) cherchant \u00e0 parler au g\u00e9n\u00e9ral Gerasimov ; depuis le 18 f\u00e9vrier pour Austin appelant en vain Shoigou. Ce refus des Russes <a href=\"https:\/\/www.dedefensa.org\/article\/les-desarrois-du-pentagone\">inqui\u00e9tait particuli\u00e8rement<\/a> le Pentagone. Pour autant, il ne para&icirc;t pas \u00e9vident que les retrouvailles soient particuli\u00e8rement rassurantes&#8230;<\/p>\n<\/p>\n<p><p>Tout la monde a not\u00e9 qu&rsquo;Austin avait demand\u00e9 \u00e0 Shoigou un \u00ab\u00a0cessez-le-feu imm\u00e9diat\u00a0\u00bb en Ukraine, &ndash; demande qui s&rsquo;est heurt\u00e9, semble-t-il,  \u00e0 un manque d&rsquo;int\u00e9r\u00eat du \u00ab\u00a0coll\u00e8gue\u00a0\u00bb russe. Larry Johnson se charge <a href=\"https:\/\/sonar21.com\/the-art-of-disinformation-western-lies-about-the-war-in-ukraine\/\">de nous expliquer, ci-apr\u00e8s<\/a>, ce que cette demande a de particuli\u00e8rement surprenante \u00e0 l&rsquo;heure o&ugrave; la volaille de la communication du <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-bloc-bao-1\">bloc-BAO<\/a> c\u00e9l\u00e8bre les exploits des arm\u00e9es et de l&rsquo;h\u00e9ro\u00efsme ukrainiens.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p> &laquo; <em>Si vous voulez savoir comment se d\u00e9roule la guerre en Ukraine, il vous suffit de prendre note d&rsquo;une seule \u00ab\u00a0nouvelle\u00a0\u00bb aujourd&rsquo;hui<\/em> [13 mai]<em> : le secr\u00e9taire \u00e0 la d\u00e9fense Lloyd Austin <a href=\"https:\/\/www.cnn.com\/2022\/05\/13\/politics\/austin-shoigu-call\/index.html\">a appel\u00e9<\/a> son homologue russe :<\/em><\/p>\n<\/p>\n<p><p><em>\u00ab\u00a0Le secr\u00e9taire am\u00e9ricain \u00e0 la D\u00e9fense, Lloyd Austin, s&rsquo;est entretenu avec son homologue russe pour la premi\u00e8re fois depuis l&rsquo;invasion russe de l&rsquo;Ukraine, a annonc\u00e9 vendredi le Pentagone.<\/em><\/p>\n<\/p>\n<p><p><em>\u00ab\u00a0L&rsquo;appel a dur\u00e9 environ une heure et a \u00e9t\u00e9 effectu\u00e9 \u00e0 la demande de M. Austin, qui a profit\u00e9 de ce premier appel entre les deux hommes en 84 jours pour exhorter le ministre de la D\u00e9fense Sergei Shoigu \u00e0 mettre en &oelig;uvre un &lsquo;cessez-le-feu imm\u00e9diat&rsquo;, selon un bref compte rendu de l&rsquo;appel. La derni\u00e8re conversation entre les deux hommes remonte au 18 f\u00e9vrier, une semaine avant que la Russie ne lance son invasion de l&rsquo;Ukraine.\u00a0\u00bb [CNN]<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Si la Russie \u00e9tait en train de perdre ou d&rsquo;\u00eatre compl\u00e8tement bloqu\u00e9e en Ukraine, on pourrait s&rsquo;attendre \u00e0 ce que Shoigu soit celui qui appelle Austin et implore sa piti\u00e9. Eh bien, ce n&rsquo;est pas ce qui s&rsquo;est pass\u00e9. C&rsquo;est Austin qui a pass\u00e9 l&rsquo;appel, apparemment sans se soucier de son r\u00e9cent appel public \u00e0 affaiblir la Russie. Pourquoi Austin demanderait-il instamment \u00e0 Shoigu de mettre en &oelig;uvre un \u00ab\u00a0cessez-le-feu imm\u00e9diat\u00a0\u00bb si la Russie se fait botter le cul ? Le fait que la Russie se fasse botter le cul par l&rsquo;Ukraine est exactement ce qu&rsquo;Austin a appel\u00e9 de ses v&oelig;ux. Vous vous souvenez ?<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0Nous voulons voir la Russie affaiblie au point qu&rsquo;elle ne puisse plus faire le genre de choses qu&rsquo;elle a faites en envahissant l&rsquo;Ukraine&#8230;\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Si la Russie est accul\u00e9e est dans les cordes, pourquoi arr\u00eater la bagarre ? On arr\u00eate le combat quand c&rsquo;est son gars qui se fait tabasser, non ?&#8230; <\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>&#8230; Nous ajouterons, nous, qu&rsquo;il nous para&icirc;t \u00e9galement remarquable que le contenu de la conversation officiellement communiqu\u00e9 du c\u00f4t\u00e9-Pentagone comprenne cette demande d&rsquo;un cessez-le-feu. (Les Russes ont ensuite confirm\u00e9 la conversation t\u00e9l\u00e9phonique sans entrer dans les d\u00e9tails.)  La publicit\u00e9 de cette demande est effectivement absurde ou bien humiliante par rapport \u00e0 la <em>narrative <\/em>de la guerre.\/.. Elle est incompr\u00e9hensible, en un sens ! A moins que&#8230;,<\/p>\n<\/p>\n<p><p>&#8230; A moins, bien entendu, que le Pentagone ne fasse l\u00e0 que poursuive sa politique des messages crypt\u00e9s, de celui qui n&rsquo;a rien \u00e0 faire de cette guerre, qui ne cherche qu&rsquo;\u00e0 la freiner \u00e0 cause de sa dangerosit\u00e9 extr\u00eame, qui ne cesse d&rsquo;en dire du mal, par l&rsquo;interm\u00e9diaire de mauvaises nouvelles directes ou indirectes&#8230; Dire que le Pentagone veut un \u00ab\u00a0cessez-le-feu imm\u00e9diat\u00a0\u00bb contre toute la propagande triomphante du camp-BAO, c&rsquo;est dire certes que tout ne va pas si bien, mais c&rsquo;est peut-\u00eatre dire surtout qu&rsquo;il (le Pentagone) voudrait bien qu&rsquo;on arr\u00eate ; message plut\u00f4t pour Biden que pour Poutine, tandis que les fantaisies d&rsquo;Austin-\u00e0-Kiev sur la r\u00e9duction en bouillie de la Russie \u00e9tait une in\u00e9vitable ob\u00e9issance aux ordres supr\u00eame du bredouillant commandant-en-chef&#8230;<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepblue\" style=\"color:#0f3955; font-size:1.25em\">USA et <em>Ukrisis <\/em>: l&rsquo;\u00e9tonnant NYT<\/h3>\n<\/p>\n<p><p>L\u00e0-dessus, passons aux nouvelles par un autre canal, cette fois-ci en nous int\u00e9ressant au \u00ab\u00a0journal-de-r\u00e9f\u00e9rence\u00a0\u00bb du monde et des salons globalis\u00e9s. Nous parlons du New York &lsquo;<em>Times<\/em>&lsquo;, dit NYT, la &lsquo;<em>Grey Lady<\/em>&lsquo; toujours empress\u00e9e aux consignes du <em>DeepState<\/em><\/p>\n<\/p>\n<p><p>Il s&rsquo;agit d&rsquo;un <a href=\"https:\/\/original.antiwar.com\/john-v-walsh\/2022\/05\/12\/ny-times-shifts-pro-war-narrative-documents-failure-of-us-in-ukraine\/\">texte int\u00e9ressant<\/a>, de commentaire et d&rsquo;appr\u00e9ciation d&rsquo;articles de la semaine derni\u00e8re du NYT. Ce texte est de John V. Walsh, auteur et contributeur r\u00e9gulier du site &lsquo;<em>Antiwar.com<\/em>&lsquo;, et de divers autres m\u00e9dias &lsquo;en ligne&rsquo; (&lsquo;<em>Asia Times<\/em>&lsquo;, San Francisco &lsquo;<em>Chronicle<\/em>&lsquo; &lsquo;<em>UNZ Review<\/em>&lsquo;, et jusqu&rsquo;il y a peu professeur de physiologie et de neuroscience). Walsh et &lsquo;<em>Antiwar.com<\/em>&lsquo; forment une association s\u00e9rieuse, \u00e0 laquelle on peut donner un cr\u00e9dit assez grand par rapport aux incertitudes de la r\u00e9alit\u00e9 confront\u00e9e aux simulacres.<\/p>\n<\/p>\n<p><p>La <a href=\"https:\/\/reseauinternational.net\/le-new-york-times-change-son-discours-pro-guerre-et-decrit-lechec-des-etats-unis-en-ukraine\/\">version fran\u00e7aise<\/a> de l&rsquo;article ici donn\u00e9e vient de &lsquo;<em>R\u00e9seau International<\/em>&lsquo; :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Le New York Times a un job \u00e0 faire &ndash; et il l&rsquo;a fait de mani\u00e8re spectaculaire au cours des derniers mois. Le Times est un pr\u00e9curseur, de l&rsquo;avis de cet auteur, le pr\u00e9curseur dans l&rsquo;\u00e9laboration de la narrative am\u00e9ricaine de la guerre en Ukraine, une narrative con\u00e7ue pour maintenir l&rsquo;optimisme, donner \u00e0 la guerre un objectif moral \u00e9lev\u00e9 et justifier les milliards incalculables d\u00e9vers\u00e9s par les contribuables dans la guerre par procuration de Joe Biden contre la Russie. Jour apr\u00e8s jour, page apr\u00e8s page, avec des mots et des images, le Times explique \u00e0 tous, y compris aux politiciens et aux leaders d&rsquo;opinion de bas niveau, ce qu&rsquo;il faut penser de la guerre en Ukraine.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Ainsi, lorsque le Times affirme que les choses ne vont pas bien pour les &Eacute;tats-Unis et leur homme \u00e0 Kiev, Volodymyr Zelenski, il s&rsquo;agit d&rsquo;une histoire du type \u00ab\u00a0incident de parcours\u00a0\u00bb. Cela fonctionne lorsque certaines v\u00e9rit\u00e9s inconfortables sont devenues ind\u00e9niables. Telle \u00e9tait la nature de l&rsquo;article <a href=\"https:\/\/www.nytimes.com\/2022\/05\/10\/world\/europe\/ukraine-russia-donbas.html?smid=url-copy\" target=\"_blank\">publi\u00e9<\/a> en premi\u00e8re page le 11 mai, intitul\u00e9 \u00ab\u00a0Les Russes tiennent une grande partie de l&rsquo;Est, malgr\u00e9 les revers\u00a0\u00bb<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>Encore, ce titre contre-narrative tend-il \u00e0 adoucir l&rsquo;am\u00e8re v\u00e9rit\u00e9. Le premier paragraphe de l&rsquo;article le dit plus nettement : \u00ab\u00a0Noy\u00e9e dans le brouillard des combats quotidiens, la r\u00e9alit\u00e9 g\u00e9ographique est que la Russie a gagn\u00e9 du terrain\u00a0\u00bb.  Pas \u00ab\u00a0tenir\u00a0\u00bb le terrain mais \u00ab\u00a0gagner\u00a0\u00bb du terrain. Pas vraiment de quoi remonter le moral des troupes<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>Le Times poursuit : \u00ab\u00a0Le minist\u00e8re russe de la D\u00e9fense a d\u00e9clar\u00e9 mardi que ses forces dans l&rsquo;est de l&rsquo;Ukraine avaient progress\u00e9 jusqu&rsquo;\u00e0 la fronti\u00e8re entre Donetsk et Lougansk, les deux provinces russophones o&ugrave; les s\u00e9paratistes soutenus par Moscou combattent l&rsquo;arm\u00e9e ukrainienne depuis huit ans\u00a0\u00bb. Il nous rappelle ici que les premiers coups de feu de cette guerre n&rsquo;ont pas \u00e9t\u00e9 tir\u00e9s le 24 f\u00e9vrier, comme le veut la narrative, mais il y a huit longues ann\u00e9es dans le Donbass. Pour ceux qui basent leur soutien \u00e0 la guerre sur \u00ab\u00a0qui a tir\u00e9 le premier coup de feu\u00a0\u00bb, c&rsquo;est un rappel cinglant que leur vision \u00ab\u00a0morale\u00a0\u00bb se perd dans un angle mort consid\u00e9rable<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>Le Times pr\u00e9cise : \u00ab\u00a0..la prise du Donbass, combin\u00e9e au succ\u00e8s pr\u00e9coce de l&rsquo;invasion russe dans la prise de parties du sud de l&rsquo;Ukraine jouxtant la p\u00e9ninsule de Crim\u00e9e&#8230; donne au Kremlin un \u00e9norme levier dans toute n\u00e9gociation future pour mettre fin au conflit.\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Il poursuit : \u00ab\u00a0Et les Russes jouissent de l&rsquo;avantage suppl\u00e9mentaire de la domination navale en mer Noire, la seule route maritime pour le commerce ukrainien, qu&rsquo;ils ont paralys\u00e9e par un embargo qui pourrait finir par affamer l&rsquo;Ukraine \u00e9conomiquement et qui contribue d\u00e9j\u00e0 \u00e0 une <a href=\"https:\/\/www.nytimes.com\/2022\/04\/30\/business\/economy\/global-food-prices-ukraine.html?searchResultPosition=2\" target=\"_blank\">p\u00e9nurie mondiale de c\u00e9r\u00e9ales<\/a>\u00ab\u00a0. Encore des mauvaises nouvelles<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>Plus encore, \u00ab\u00a0La Russie a pratiquement atteint l&rsquo;un de ses principaux objectifs : s&#8217;emparer d&rsquo;un pont terrestre reliant le territoire russe \u00e0 la p\u00e9ninsule de Crim\u00e9e\u00a0\u00bb. Et puis, \u00ab\u00a0Le dernier bastion de la r\u00e9sistance ukrainienne dans cette zone, \u00e0 l&rsquo;usine sid\u00e9rurgique Azovstal de Marioupol, a \u00e9t\u00e9 r\u00e9duit \u00e0 quelques centaines de soldats affam\u00e9s, d\u00e9sormais confin\u00e9s pour la plupart dans des bunkers\u00a0\u00bb. Ouch !<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Enfin, tournant son attention vers l&rsquo;\u00e9conomie, le Times \u00e9crit : \u00ab\u00a0La guerre a &lsquo;soumis l&rsquo;\u00e9conomie ukrainienne \u00e0 un stress \u00e9norme, avec la lourde d\u00e9vastation des infrastructures et des capacit\u00e9s de production&rsquo;, [selon une analyse conjoncturelle des milieux bancaires]. On estime que 30 \u00e0 50% des entreprises ukrainiennes ont ferm\u00e9 leurs portes, que 10% de la population a fui le pays et que 15% suppl\u00e9mentaires sont d\u00e9plac\u00e9s \u00e0 l&rsquo;int\u00e9rieur du pays\u00a0\u00bb. Soit un grand total d&rsquo;un quart de la population d\u00e9plac\u00e9e.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Cette triste histoire d&rsquo;\u00e9chec, de mis\u00e8re et de mort est entrecoup\u00e9e par un verbiage consid\u00e9rable, quelques anecdotes du front et le t\u00e9moignage d&rsquo;Avril Haines, directrice du renseignement national, dont l&rsquo;appr\u00e9ciation est prudente mais sombre. Mais tout cela lu avec r\u00e9flexion, on conclut qu&rsquo;un grand \u00e9chec menace l&rsquo;aventure ukrainienne<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>Ainsi, dans la panique, les &Eacute;tats-Unis continuent de jeter des montagnes d&rsquo;argent sur le probl\u00e8me, environ 63 milliards de dollars si l&rsquo;on inclut la r\u00e9cente infusion d&rsquo;environ 40 milliards de dollars sur le point d&rsquo;\u00eatre autoris\u00e9s par le S\u00e9nat et d\u00e9j\u00e0 adopt\u00e9e par la Chambre avec seulement 57 votes n\u00e9gatifs, tous r\u00e9publicains. (Et c&rsquo;est l\u00e0 que se trouve une autre observation d&rsquo;importance, celle de la disparition de l&rsquo;aile antiguerre du parti d\u00e9mocrate et de sa renaissance parmi les r\u00e9publicains populistes du type-<a href=\"https:\/\/youtu.be\/mhDfMfV7Zf0\" target=\"_blank\">Tucker Carlson<\/a>, qui ont rejoint les libertaires du GOP sur cette question)<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>Mais pourquoi ce brusque changement de ton de la part du Times. Inattention des garde-chiourmes \u00e9ditoriaux ? Cela ne semble pas \u00eatre le cas, car le m\u00eame jour, nous avons droit \u00e0 un <a href=\"https:\/\/www.nytimes.com\/2022\/05\/11\/opinion\/russia-ukraine-war-america.html\" target=\"_blank\">article d&rsquo;opinion<\/a> intitul\u00e9 : \u00ab\u00a0L&rsquo;Am\u00e9rique et ses alli\u00e9s veulent saigner la Russie. Ils ne devraient vraiment pas s&rsquo;y risquer\u00a0\u00bb. Cet article sugg\u00e8re qu&rsquo;il est temps pour les &Eacute;tats-Unis d&rsquo;agiter le drapeau blanc<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>L&rsquo;article se conclut ainsi :<\/em><\/p>\n<\/p>\n<p><p><em>&raquo;  \u00ab\u00a0Mais plus la guerre est longue, plus les dommages caus\u00e9s \u00e0 l&rsquo;Ukraine sont importants et plus le risque d&rsquo;escalade est grand. Un r\u00e9sultat militaire d\u00e9cisif dans l&rsquo;est de l&rsquo;Ukraine pourrait s&rsquo;av\u00e9rer insaisissable. Pourtant, l&rsquo;issue moins dramatique d&rsquo;une impasse persistante n&rsquo;est gu\u00e8re mieux. La prolongation ind\u00e9finie de la guerre, comme en Syrie, est trop dangereuse avec des participants dot\u00e9s de l&rsquo;arme nucl\u00e9aire<\/em>.<\/p>\n<\/p>\n<p><p>&raquo;  <em>\u00ab\u00a0Les efforts diplomatiques devraient \u00eatre la pi\u00e8ce ma&icirc;tresse d&rsquo;une nouvelle strat\u00e9gie pour l&rsquo;Ukraine. Au lieu de cela, les fronti\u00e8res de la guerre sont \u00e9tendues et la guerre elle-m\u00eame est pr\u00e9sent\u00e9e comme une lutte entre la d\u00e9mocratie et l&rsquo;autocratie, dans laquelle le Donbass est la <a href=\"https:\/\/www.rferl.org\/a\/ukraine-pelosi-surprise-visit-zelenskiy-mariupol\/31829116.html\/t_blank\" target=\"_blank\">fronti\u00e8re de la libert\u00e9<\/a>. Ce n&rsquo;est pas seulement une extravagance d\u00e9clamatoire. C&rsquo;est de l&rsquo;inconscience. Les risques n&rsquo;ont gu\u00e8re besoin d&rsquo;\u00eatre \u00e9nonc\u00e9s\u00a0\u00bb<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>Il semble que certains membres de l&rsquo;\u00e9lite de la politique \u00e9trang\u00e8re et d&rsquo;autres enceintes de l&rsquo;&Eacute;tat profond aient commenc\u00e9 \u00e0 voir le d\u00e9sastre imminent de la guerre par procuration contre la Russie men\u00e9e par Biden, Nuland, Blinken et le reste de la cabale neocon. La perspective d&rsquo;un holocauste nucl\u00e9aire au bout de cette route pourrait suffire \u00e0 les tirer de leur torpeur. Ils semblent vouloir arr\u00eater le train qu&rsquo;ils ont mis en marche avant qu&rsquo;il ne se jette dans le pr\u00e9cipice. Il n&rsquo;est pas certain qu&rsquo;ils y parviennent. Mais il est clair que nous devons chasser du pouvoir les responsables de cette dangereuse d\u00e9b\u00e2cle &ndash; avant qu&rsquo;il ne soit trop tard<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><h3 class=\"subtitleset_c.deepblue\" style=\"color:#0f3955; font-size:1.25em\">Repli isolationniste, populiste &#038; libertarien ?<\/h3>\n<\/p>\n<p><p>On notera qu&rsquo;\u00e0 c\u00f4t\u00e9 du constat direct d&rsquo;un certain d\u00e9couragement, sinon une alarme ressemblant \u00e0 une panique d'\u00a0\u00bbune partie du <em>DeepState<\/em>\u00a0\u00bb devant les r\u00e9els d\u00e9veloppements de la guerre d&rsquo;Ukraine qui pousseraient Austin \u00e0 sugg\u00e9rer \u00e0 Shoigou un \u00ab\u00a0cessez-le-feu imm\u00e9diat\u00a0\u00bb, Welch signale l&rsquo;amorce d&rsquo;un complet renversement en cours dans les deux grands partis, &ndash; et ceci expliquant en bonne part cela, \u00e9tablissant un lien de plus entre crises ext\u00e9rieures et crises int\u00e9rieures&#8230;<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Et c&rsquo;est l\u00e0 que se trouve une autre observation d&rsquo;importance, celle de la disparition de l&rsquo;aile antiguerre du parti d\u00e9mocrate et de sa renaissance parmi les r\u00e9publicains populistes du type-<a href=\"https:\/\/youtu.be\/mhDfMfV7Zf0\" target=\"_blank\">Tucker Carlson<\/a>, qui ont rejoint les libertaires du GOP sur cette question. <\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Ainsi, la formule belliciste-<em>neocon <\/em>dominant au sein des r\u00e9publicains du GOP depuis G.W. Bush et 9\/11 (2000-2001) en face d&rsquo;une certaine formule antiguerre active \u00e0 l&rsquo;aile gauche du parti d\u00e9mocrates, suivie par une certaine confusion dans ces formules au long des administrations Obama-Trump, tend \u00e0 rencontrer un possible complet renversement, avec les populistes trumpistes rejoignant les libertariens pour donner un fort courant antiguerre au sein du GOP (peut-\u00eatre, &ndash; hypoth\u00e8se prudente face aux verrouillages des appareils des partis dans les processus d\u00e9mocratiques, &ndash; pourrait-on s&rsquo;en apercevoir en novembre prochain) tandis que les d\u00e9mocrates s&rsquo;enfoncent dans un bellicisme hyst\u00e9rique<\/p>\n<\/p>\n<p><p>Ainsi en viendrait-on \u00e0 une sorte de fin de cycle ?  En effet, la tendance antiguerre, appuy\u00e9e sur un solide isolationnisme, \u00e9tait tr\u00e8s forte lors de la guerre du Kosovo o&ugrave; la principale opposition \u00e0 cette guerre venait de cette faction au sein du GOP. C&rsquo;est justement durant cette guerre qu&rsquo;\u00e9clata au sein d&rsquo;un internet acqu\u00e9rant ses galons de source d&rsquo;information essentielle <a href=\"https:\/\/www.dedefensa.org\/article\/notre-samizdat-globalise\">le succ\u00e8s d\u00a0\u00bb<em>Antiwar.com<\/em>&lsquo;<\/a>, alors men\u00e9 par l&rsquo;\u00e9toile des libertariens que fut Justin Raimondo jusqu&rsquo;\u00e0 sa mort. Les d\u00e9mocrates (ceux qui avaient un sentiment antiguerre) se trouvaient encalmin\u00e9s dans le gang Clinton, avec la redoutable &lsquo;<a href=\"https:\/\/www.dedefensa.org\/article\/hillary-et-ses-harpies-ou-le-feminisme-guerrier\">Harpie-<em>neocon<\/em><\/a>&lsquo; Hillary, qui convainquit, revolver au poing, le pauvre Bill encore tout aur\u00e9ol\u00e9 de sa destitution manqu\u00e9e pour la pi\u00e8tre histoire de petit cul que fut l&rsquo;affaire Lewinsky, de lancer la guerre contre le Kosovo. L&rsquo;attaque du 11 septembre fit basculer d&rsquo;ivresse le GOP dans la <em><a href=\"https:\/\/www.dedefensa.org\/article\/aux-sources-du-virtualisme\">fantasy-neocon<\/a> <\/em>et les folies-imp\u00e9riales ; les d\u00e9mocrates se refirent un vernis vertueux d&rsquo;anti-guerre avant de lancer leur propre formule, &ndash; <a href=\"https:\/\/www.dedefensa.org\/article\/hysteries-en-menage-neocons-et-r2p\">hyst\u00e9rie-R2P<\/a> &ndash; contre la Syrie, la Libye et avec la moralinesque formule &lsquo;<em>regime change<\/em>&lsquo;.<\/p>\n<\/p>\n<p><p>Tout cela confirme qu&rsquo;on se trouve aux USA dans une s\u00e9quence d&rsquo;intense bouillonnement, o&ugrave; les troubles int\u00e9rieurs qui se sont install\u00e9s en mode paroxystique depuis le printemps 2020 (mort de George Floyd, BLM et le reste) seraient peut-\u00eatre sur la voie d&rsquo;\u00eatre compl\u00e9t\u00e9s par les effets d&rsquo;<em>Ukrisis <\/em>au niveau des repr\u00e9sentations des partis. Pour une fois, le syst\u00e8me d\u00e9mocratique pourrait avoir une certaine utilit\u00e9 : en imposant l&rsquo;\u00e9tape des \u00e9lections <em>mid-term<\/em> \u00e0 propos de laquelle les uns et les autres atteignent des sommets d&rsquo;exacerbation (surtout les d\u00e9mocrates, qui sont sans doute \u00e0 la base de la fuite sur le travail pr\u00e9paratoire d&rsquo;un jugement qui touche un \u00e9l\u00e9ment central de la \u00ab\u00a0r\u00e9volution LGTBQ+\u00a0\u00bb), il nous, il leur impose de r\u00e9gler quelques comptes qui pousseront un peu plus le syst\u00e8me de l&rsquo;am\u00e9ricanisme dans ses ultimes retranchements.<\/p>\n<\/p>\n<p><p>Mis en ligne le 16 mai 2022 \u00e0 17h45<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>RapSit-USA2022 : &lsquo;The Road to Hell&lsquo; ? Nous pensons d&rsquo;une fa\u00e7on de plus en plus insistante, &ndash; on le lit dans nombre de nos textes, &ndash; que ce qui doit \u00eatre observ\u00e9 avec attention pour en venir au brasier central de la GrandeCrise ne se trouve ni \u00e0 Moscou, ni dans les champs de l&rsquo;Ukraine&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[21],"tags":[13665,2798,4141,18647,2866,2906,6109,3256,16622,2852,13670,2804,21584,3257],"class_list":["post-80195","post","type-post","status-publish","format-standard","hentry","category-breves-de-crise","tag-austin","tag-cessez-le-feu","tag-elections","tag-hanson","tag-johnson","tag-larry","tag-mid-term","tag-new","tag-shoigou","tag-times","tag-ukrisis","tag-usa","tag-walch","tag-york"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=80195"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80195\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=80195"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=80195"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=80195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}