{"id":80260,"date":"2022-07-08T18:15:37","date_gmt":"2022-07-08T18:15:37","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2022\/07\/08\/la-grandecrise-jour-apres-jour\/"},"modified":"2022-07-08T18:15:37","modified_gmt":"2022-07-08T18:15:37","slug":"la-grandecrise-jour-apres-jour","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2022\/07\/08\/la-grandecrise-jour-apres-jour\/","title":{"rendered":"La GrandeCrise, jour apr\u00e8s jour"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepblue\" style=\"color:#0f3955; font-size:2em\">La GrandeCrise, jour apr\u00e8s jour<\/h2>\n<\/p>\n<blockquote>\n<p><p>&bull; Jamais certes, autant que dans tel texte, il n&rsquo;a \u00e9t\u00e9 autant question de ce que nous d\u00e9signons comme la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-la-gces\">GrandeCrise<\/a> (reprenant la \u00ab\u00a0Grande Crise d&rsquo;Effondrement  du Syst\u00e8me, ou <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-la-gces\">GCES<\/a>). &bull; Certes, il y a des \u00e9v\u00e9nements sp\u00e9cifiques aujourd&rsquo;hui pour s&rsquo;y int\u00e9resser, et c&rsquo;est notamment le d\u00e9part du Premier ministre UK, BoJo, dit Boris Johnson. &bull; <strong>Le \u00ab\u00a0Parti Globaliste de la Guerre\u00a0\u00bb perd ainsi son esp\u00e8ce de \u00ab\u00a0fou de Guerre\u00a0\u00bb<\/strong> comme on dit \u00ab\u00a0fou du Roi\u00a0\u00bb, ou bien \u00ab\u00a0fou du Dieu-Guerre\u00a0\u00bb, <strong>sorte de clown au milieu du cirque-BAO, qui leur en remontrait \u00e0 tous<\/strong>. &bull; Les Grandes Arm\u00e9es du Camp du Bien perdent donc ainsi leur plus courageux combattant, toujours pr\u00eat \u00e0 offrir sa poitrine au tir de <em>FakeNews<\/em> et de propagande de l&rsquo;\u00e9pouvantable Poutine. &bull; Bref, BoJo sera oubli\u00e9 dans deux semaines, mais <strong>il n&rsquo;est pas s&ucirc;r que l&rsquo;effet de son d\u00e9part ne se fasse sentir bien plus longtemps<\/strong>. &bull; Pour autant, il n&rsquo;y eut pas que BoJo : il y a l&rsquo;\u00e9norme crise europ\u00e9enne (inflation, \u00e9nergie, circulation alimentaire et autre), la Hollande avec ses agriculteurs, la fronti\u00e8re Sud du Texas en feu, etc. &bull; <strong>Qui nous dira de quoi vraiment est faite cette GrandeCrise ?<\/strong><\/p>\n<\/p>\n<\/blockquote>\n<p><p>8 juillet 2022 &ndash; Depuis quelques mois d&rsquo;un processus acc\u00e9l\u00e9r\u00e9 d&rsquo;effondrement \u00e0 partir de l&rsquo;explosion-<em>Ukrisis <\/em>d&rsquo;un monde en attente d&rsquo;un d\u00e9tonateur, chaque jour on pourrait \u00e9crire un texte comme celui-ci qui pr\u00e9tendrait tenir lieu de chronique catastrophique du susdit effondrement. Chaque jour nous d\u00e9signe des points nouveaux ou diff\u00e9rentes que l&rsquo;on pourrait nommer \u00ab\u00a0subcrises\u00a0\u00bb (\u00ab\u00a0sous-crises\u00a0\u00bb en un sens), en plus des diff\u00e9rents centres constants de la GrandeCrise qui ne cessent d&rsquo;interagir selon une formule homoth\u00e9tique changeante et plastique.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepblue\" style=\"color:#0f3955; font-size:1.25em\">Quelques points du jour<\/h3>\n<\/p>\n<p><p> On peut faire une comptabilit\u00e9 rapide ; on pr\u00e9cisera ensuite l&rsquo;un ou l&rsquo;autre point, parfois deux points sur le m\u00eame point pour en \u00e9largir la port\u00e9e&#8230;<\/p>\n<\/p>\n<p><p>&bull; La guerre en Ukraine et <em>Ukrisis <\/em>bien entendu, o&ugrave; les Russes ont atteint l&rsquo;objectif de la compl\u00e8te lib\u00e9ration des deux r\u00e9publiques auto-proclam\u00e9e du Donbass mais se tiennent pr\u00eats pour la suite.<\/p>\n<\/p>\n<p><p>&bull; A cet \u00e9gard, les mots de Poutine, devant la &lsquo;<em>Douma<\/em>&lsquo;, hier, ne ferme pas la porte \u00e0 la n\u00e9gociations mais sont surtout d&rsquo;une <a href=\"https:\/\/www.rt.com\/russia\/558593-putin-russia-hasnt-started-yet\/\">extr\u00eame fermet\u00e9<\/a> pour la suite : \u00ab\u00a0Si vous voulez poursuivre la bagarre, vous n&rsquo;avez encore rien vu&#8230;\u00a0\u00bb.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Nous ne refusons pas de n\u00e9gocier la paix, mais ceux qui refusent doivent savoir que plus ils tiennent cette position,  plus il sera difficile de n\u00e9gocier<\/em> &raquo;&#8230; &laquo; <em>Nous les entendons dire aujourd&rsquo;hui qu&rsquo;ils veulent notre d\u00e9faite sur le champ de bataille. Eh bien, que puis-je dire ? Qu&rsquo;ils essaient donc ! Nous n&rsquo;avons m\u00eame pas encore vraiment commenc\u00e9<\/em> [\u00e0 nous battre avec tous nos moyens]&#8230; &raquo;.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>&bull; La Hollande gronde, en r\u00e9volte contre l&rsquo;Europe ! La \u00ab\u00a0folie n\u00e9erlandaise\u00a0\u00bb venue d&rsquo;une directive du type \u00ab\u00a0<em>serial-devastation<\/em>\u00a0\u00bb de la Commission Europ\u00e9enne. La consigne ressemblant \u00e0 des campagnes de type-nazie ou -stalinienne heureusement habill\u00e9es de vertus postmodernes (venue du Commissaire Europ\u00e9en et n\u00e9anmoins de nationalit\u00e9 hollandaise Timmermans), &ndash; de <a href=\"https:\/\/reseauinternational.net\/pays-bas-une-ferme-neerlandaise-sur-trois-doit-etre-fermee-ou-expropriee\/\">\u00ab\u00a0liquider\u00a0\u00bb 30%<\/a> des agriculteurs n\u00e9erlandais dans une grande offensive finale \u00ab\u00a0pour devenir Vert\u00a0\u00bb, sorte de fa\u00e7on de rajeunir, de r\u00e9duction de la production d&rsquo;azote pour l&rsquo;UE contre 10% des agriculteur europ\u00e9ens \u00e0 la trappe, \u00e0 la guillotine&#8230; Une col\u00e8re r\u00e9volutionnaire sans pr\u00e9c\u00e9dent enflamme la Hollande, pays apais\u00e9, performant, cit\u00e9 en exemple pour ses \u00e9lites ultra-europ\u00e9iste (quant au peuple c&rsquo;est \u00e0 voir, selon le &lsquo;Non&rsquo; au r\u00e9f\u00e9rendum sur la constitution europ\u00e9enne du 31 mai 2005).<\/p>\n<\/p>\n<p><p>&bull; Tout cela, avec le cas hollandais comme exemple de l'\u00a0\u00bbart op\u00e9ratif\u00a0\u00bb-UE, r\u00e9duit drastiquement la production et la circulation des biens consommables (gigantesques barrages sur les routes alors que les \u00e9changes de ces m\u00eames denr\u00e9es dans le monde sont en crise profonde \u00e0 cause d&rsquo;<em>Ukrisis&#8230; <\/em>hyper-\u00ab\u00a0<em>serial-devastation<\/em>\u00ab\u00a0.)<\/p>\n<\/p>\n<p><p>&bull; Aux USA, parmi d&rsquo;innombrables myriades d&rsquo;autres crises, on voit dans quelle situation d&rsquo;urgence catastrophique <a href=\"https:\/\/www.dedefensa.org\/article\/rapsit-usa2022-le-texas-officiellement-envahi\">se trouve le Texas<\/a> face \u00e0 l&rsquo;immigration ill\u00e9gale, et le Texas officiellement d\u00e9sign\u00e9 par un juge comme \u00e9tant en \u00e9tat d&rsquo;\u00eatre confront\u00e9 \u00e0 une invasion qui devrait impliquer une r\u00e9action de type militaire. La Fronti\u00e8re  Sud est litt\u00e9ralement en feu, avec le franchissement, noy\u00e9s dans la masse des migrants, de bandes de narcotrafiquants, de mafieux, de terroristes.<\/p>\n<\/p>\n<p><p>&bull; Cette crise sur la fronti\u00e8re Sud n&rsquo;est qu&rsquo;une d\u00e9monstration de plus de la paralysie par impuissance s\u00e9nile et presque par indolence de Washington, &lsquo;D.C.-la-folle&rsquo;, &ndash; paralysie par impuissance s\u00e9nile qui n&rsquo;a jamais aussi grande et pesante dans toute l&rsquo;histoire des &Eacute;tats-Unis.<\/p>\n<\/p>\n<p><p>&bull; La crise aux &Eacute;tats-Unis s&rsquo;accompagne d\u00e9sormais, si l&rsquo;on veut s&rsquo;en venir pour ces cas au concept d'\u00a0\u00bbanglosph\u00e8re\u00a0\u00bb (voir plus loin), par la crise ouverte par le d\u00e9part prochain de Boris de Johnson, dit BoJo, du 10 Downing Street. L&rsquo;un des plus prompts \u00e0 dire sa peine et ses regrets est l&rsquo;ami-Zelenski, ce qui place cette chute politique dans <a href=\"https:\/\/www.rt.com\/news\/558602-boris-johnson-ukraine-sad\/\">le droit fil d&rsquo;<em>Ukrisis<\/em><\/a>.<\/p>\n<\/p>\n<p><p>&bull; &Eacute;l\u00e9ment de r\u00e9flexion, comme on dit \u00ab\u00a0\u00e9l\u00e9ment de langage\u00a0\u00bb : un, exercice naval conjoint, avec notamment les marines du Venezuela, de l&rsquo;Iran et de la Russie,  dans des eayx vraiment tr\u00e8s proches de celles des &Eacute;tats-Unis et de leur c\u00f4te, style-\u00ab\u00a0flaque dans l&rsquo;arri\u00e8re-cour\u00a0\u00bb de l&rsquo;espace Monroe. Selon &lsquo;<em><a href=\"https:\/\/reseauinternational.net\/venezuela-la-russie-liran-et-la-chine-organiseront-des-manoeuvres-a-quelques-dizaines-de-kilometres-des-etats-unis\/\">R\u00e9seauInternational<\/a><\/em>&lsquo;, relayant les sites insupportables-inadmissibles, et propagateurs \u00e0 tr\u00e8s-grande vitesse de <em>FakeNews<\/em> et autres ragots d&rsquo;arri\u00e8re-cour, &lsquo;<em>Al Qabar<\/em>&lsquo; et l&rsquo;Iranien &lsquo;<em>PressTV<\/em>&lsquo;, on lit ceci (on allonge un peu pour faire de la pub) :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p><em>&laquo; &Agrave; la mi-ao&ucirc;t, les eaux du Venezuela vont accueillir les des forces navales de plusieurs pays, dont l&rsquo;Iran, la Russie et la Chine &raquo;. <\/em><em>C&rsquo;est ce qu&rsquo;a rapport\u00e9 le think tank &laquo; Center for a Free and Safe Society &raquo;.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Selon le site Web du journalisme politique conservateur am\u00e9ricain &laquo; Washington Free Beacon &raquo;, le groupe de r\u00e9flexion &laquo; Center for a Free and Secure Society &raquo; a indiqu\u00e9 dans son rapport : &laquo; De tels exercices de guerre montrent que les ennemis de l&rsquo;Am\u00e9rique du monde entier &laquo; se pr\u00e9parent \u00e0 annoncer haut et fort que la r\u00e9gion est pr\u00eate \u00e0 accepter une force multipolaire &raquo;.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>&Agrave; son \u00e9gard, l&rsquo;arm\u00e9e russe s&rsquo;appr\u00eate \u00e0 envoyer pour la premi\u00e8re fois ses unit\u00e9s navales \u00e0 cet exercice conjoint.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Par ailleurs, les forces de la Russie, de l&rsquo;Iran et de la Chine organisent un tel exercice \u00e0 quelques dizaines de kilom\u00e8tres des fronti\u00e8res maritimes des &Eacute;tats-Unis d&rsquo;Am\u00e9rique et dans leur arri\u00e8re-cour sud-am\u00e9ricaine.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Aussi, c&rsquo;est la premi\u00e8re fois dans l&rsquo;histoire que des unit\u00e9s de la marine iranienne vont participer \u00e0 un exercice militaire \u00e0 quelques dizaines de kilom\u00e8tres des eaux am\u00e9ricaines dans l&rsquo;h\u00e9misph\u00e8re occidental.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Les &Eacute;tats-Unis ont toujours vu l&rsquo;Am\u00e9rique latine et les Cara\u00efbes comme leur arri\u00e8re-cour et sont extr\u00eamement sensibles \u00e0 l&rsquo;\u00e9gard du d\u00e9ploiement militaire d&rsquo;autres pays dans cette r\u00e9gion.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Pendant la guerre froide, en 1962, les &Eacute;tats-Unis sont all\u00e9s au seuil d&rsquo;une guerre nucl\u00e9aire d\u00e9vastatrice \u00e0 cause du d\u00e9ploiement d&rsquo;anciens syst\u00e8mes de missiles sovi\u00e9tiques \u00e0 Cuba et ont m\u00eame donn\u00e9 \u00e0 Moscou un ultimatum d&rsquo;\u00e9ventuelle attaque nucl\u00e9aire.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0L&rsquo;exercice imminent des pays rivaux des &Eacute;tats-Unis dans l&rsquo;h\u00e9misph\u00e8re occidental de la plan\u00e8te est l&rsquo;un des signes les plus \u00e9vidents que l&rsquo;Alliance des gouvernements opposants \u00e0 Washington en Am\u00e9rique latine tente de renforcer ses relations avec la Russie, la Chine et l&rsquo;Iran. <\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>&bull; L&rsquo;explosion, aussit\u00f4t <a href=\"https:\/\/www.rt.com\/news\/558600-minotaur-icbm-explodes-test-launch\/\">apr\u00e8s son lancement<\/a>, d&rsquo;une fus\u00e9e  &lsquo;<em>Minotaur<\/em>&lsquo; II+ confirme une crise s\u00e9rieuse des capacit\u00e9s de la puissance US dans ce domaine (entre d&rsquo;autres) des missiles strat\u00e9giques de hautes performances. (Apr\u00e8s <a href=\"https:\/\/www.rt.com\/news\/558115-hypersonic-test-fail-pentagon\/\">le nouvel \u00e9chec<\/a> d&rsquo;un test d&rsquo;un missile hypersonique en cours de d\u00e9veloppement.) Le &lsquo;<em>Minotaur<\/em>&lsquo; II+ est l&rsquo;engin d&rsquo;essai du futur ICBM LGM-35A destin\u00e9 \u00e0 remplacer les &lsquo;<em>Minuteman<\/em>&lsquo; III datant de 1970. Dans ces temps de grande confrontation o&ugrave; la qualit\u00e9 et la capacit\u00e9 de la puissance nucl\u00e9aire strat\u00e9gique joue un r\u00f4le \u00e9norme, c&rsquo;est un motif de grave pr\u00e9occupation pour le Pentagone.<\/p>\n<\/p>\n<p><p>&bull; On pourrait ajouter, comme dernier \u00e9l\u00e9ment de crise  l&rsquo;assassinat de l&rsquo;ancien Premier ministre japonais Abe, en pleine r\u00e9union publique \u00e9lectorale. L&#8217;emploi de la violence et du terrorisme \u00e0-la-Soros pour l&rsquo;expression d\u00e9mocratique que propage le bloc-BAO n&rsquo;est pas sans porter ses fruits&#8230; Ou bien, comme &lsquo;<em>WhatDoesItMeans<\/em>&lsquo; l&rsquo;explique dans son <a href=\"https:\/\/www.whatdoesitmean.com\/index3970.htm\">style intens\u00e9ment exotique<\/a>, liant cet \u00e9v\u00e9nement au pr\u00e9c\u00e9dent (et au suivant&#8230;)<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; &#8230;<em>Ensuite, un \u00e9v\u00e9nement \u00ab\u00a0de sang et de feu\u00a0\u00bb s&rsquo;est produit lorsque le leader colonial occidental, l&rsquo;ancien Premier ministre japonais Shinzo Abe, a \u00e9t\u00e9 assassin\u00e9 par un tir de fusil de chasse trafiqu\u00e9. Tous ces \u00e9v\u00e9nements \u00e9taient des an\u00e9antissements dus \u00e0 la \u00ab\u00a0Col\u00e8re de Dieu\u00a0\u00bb, suivis d&rsquo;un autre \u00e9v\u00e9nement d&rsquo;une \u00ab\u00a0merveilles dans les cieux\u00a0\u00bb qui a vu une fus\u00e9e am\u00e9ricaine Minotaur II+ exploser quelques secondes apr\u00e8s son lancement sur une base de la Space Force en Californie<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><h3 class=\"subtitleset_c.deepblue\" style=\"color:#0f3955; font-size:1.25em\">Des trous dans l'\u00a0\u00bbAnglosph\u00e8re\u00a0\u00bb<\/h3>\n<\/p>\n<p><p>Mais il nous semble assur\u00e9 qu&rsquo;il faut s&rsquo;arr\u00eater au cas de  BoJo, le Premier Ministre Johnson, qui est sur la voie de s&rsquo;en aller, compl\u00e8tement d\u00e9savou\u00e9 par son parti conservateur. BoJo s&rsquo;est fait un peu pri\u00e9, annon\u00e7ant d&rsquo;abord qu&rsquo;il resterait malgr\u00e9 les d\u00e9missions en s\u00e9rie et les pressions conservatrices, puis acceptant de c\u00e9der la pr\u00e9sidence du parti, puis <a href=\"https:\/\/francais.rt.com\/international\/99753-royaume-uni-boris-johnson-annonce-demission-chef-parti-conservateur\">acceptant de partir<\/a> quand un nouveau Premier ministre sera d\u00e9sign\u00e9. Il a fait donc une d\u00e9claration pour saluer son d\u00e9part et proclamer la grandeur de l&rsquo;&oelig;uvre accomplie par lui-m\u00eame, selon l&rsquo;habitude du truculent Bojo.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>\u00ab\u00a0Il est clair que le parti conservateur souhaite un nouveau chef, un nouveau Premier ministre\u00a0\u00bb, a-t-il d\u00e9clar\u00e9 devant le 10 Downing Street, avant de faire savoir qu&rsquo;il allait rester en poste \u00ab\u00a0jusqu&rsquo;\u00e0 ce qu&rsquo;un rempla\u00e7ant soi nomm\u00e9\u00a0\u00bb. \u00ab\u00a0Je suis tr\u00e8s fier des r\u00e9alisations de ce gouvernement : nous avons fait passer le Brexit\u00a0\u00bb, a-t-il lanc\u00e9 lors de son discours, se f\u00e9licitant \u00e9galement du soutien de son gouvernement \u00e0 l&rsquo;Ukraine et de son action face au Covid<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>L&rsquo;annonce intervient alors que pr\u00e8s de 60 d\u00e9parts ont \u00e9t\u00e9 annonc\u00e9s au sein du gouvernement depuis le 5 juillet, dont cinq ministres, un exode d&rsquo;une rapidit\u00e9 sans pr\u00e9c\u00e9dent dans l&rsquo;histoire politique britannique. Le m\u00e9contentement couvait depuis des mois, nourri par le scandale des f\u00eates ill\u00e9gales \u00e0 Downing Street pendant le confinement anti-Covid<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Il est bien s&ucirc;r que ce d\u00e9part va faire de tr\u00e8s nombreuses vagues, d&rsquo;autant que BoJo, lors de ces cinq derniers mois, a pris une place majeure, sinon la place de direction de l'\u00a0\u00bballiance\u00a0\u00bb du bloc-BAO en soutien de l&rsquo;Ukraine de Zelenski. M\u00eame les USA ont \u00e9t\u00e9 largement d\u00e9pass\u00e9s, Biden n&rsquo;y comprenant pas grand&rsquo;chose, secou\u00e9 comme une plume par les passages en rafales de BoJo, n&rsquo;entendant pas grand&rsquo;chose des discours tonitruants, fa\u00e7on-Churchill, du Britannique.<\/p>\n<\/p>\n<p><p>Les Russes, eux, font preuve  comme \u00e0 leur habitude d&rsquo;une franchise sans retenue ni complexe du type \u00ab\u00a0Il ne nous aimait pas, nous ne l&rsquo;aimions pas\u00a0\u00bb ; franchise s&rsquo;exprimant avec un verbe arrondi par le porte-parole de Poutine, et de fa\u00e7on bien plus incisive par la belle Zakharova, porte-parole de Lavrov, qui nous donne en plus une visions large et bien faite de la signification de l&rsquo;\u00e9v\u00e9nement pour le bloc-BAO.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Interrog\u00e9 sur la crise politique au Royaume-Uni, le porte-parole du Kremlin a expliqu\u00e9 que Moscou esp\u00e9rait que \u00ab\u00a0des gens plus professionnels et en mesure de prendre des d\u00e9cisions \u00e0 travers le dialogue arriveront au pouvoir en Grande-Bretagne\u00a0\u00bb. Avant d&rsquo;ajouter que le Premier ministre britannique \u00ab\u00a0ne nous aime pas beaucoup et nous non plus\u00a0\u00bb. La porte-parole de la diplomatie russe, Maria Zakharova, voit, elle, dans la situation au Royaume-Uni la preuve que les \u00ab\u00a0r\u00e9gimes lib\u00e9raux<\/em> [occidentaux] <em>sont dans une profonde crise politique, id\u00e9ologique et \u00e9conomique\u00a0\u00bb<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Effectivement, selon nous c&rsquo;est Zakharova qui parle d&rsquo;or. La chute de BoJo, quelle(s) qu&rsquo;en soie(nt) la(les) cause(s) exacte(s), appara&icirc;t dans la symbolique de la communication comme un coup tr\u00e8s dur port\u00e9 aux ennemis de la Russie et aux soutiens de Zelenski. Bojo \u00e9tait \u00e0 cet \u00e9gard un exalt\u00e9, m\u00eame si d&rsquo;une exaltation au d\u00e9part surjou\u00e9e mais finalement qui parvenait \u00e0 la convaincre lui-m\u00eame de la justesse de sa cause, gobant tous les bobards comme autant de porridge du matin. Pour le reste, BoJo se prenant pour Churchill, mais un Churchill \u00e0 l&rsquo;envers : pas celui qui a sacrifi\u00e9 l&#8217;empire britannique \u00e0 des &lsquo;<em>special relationships<\/em>&lsquo;-bidon avec les USA, &ndash; grande na\u00efvet\u00e9, immense <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-laffectivisme-postmoderne\">affectivisme<\/a> du Churchill anglais avec sa m\u00e8re am\u00e9ricaine, lorsqu&rsquo;il pensait USA, homme d&rsquo;&Eacute;tat si puissant d&rsquo;\u00e9nergie par ailleurs ; non, un n\u00e9o-Churchill qui, en quelque sorte, ambitionnait de r\u00e9inventer l&#8217;empire au bon soin des communications, en s&rsquo;imposant comme leader de l&rsquo;antirussisme, avec Zelenski dans son sac \u00e0 dos et Biden tra&icirc;nant en marmonnant \u00e0 quelques pas en arri\u00e8re.<\/p>\n<\/p>\n<p><p>Seulement, il y a l&rsquo;Angleterre, celle qui souffre et peine, et re\u00e7oit en pleine poire les cons\u00e9quences indirectes des sanctions les plus puissantes et les plus b\u00eates du monde. Le parti conservateur, en fait, n&rsquo;a pas pardonn\u00e9 \u00e0 BoJo ses ambitions n\u00e9ocoloniales qui, par le biais de l&rsquo;Ukraine et de ses sanctions, plongent le Royaume-Uni dans une terrible situation \u00e9conomique. Le parti est compos\u00e9 de notables de cantons \u00e9lectoraux et de comptables des potentialit\u00e9s \u00e9lectorales. Brutal, s&ucirc;r de lui, grande gueule jusqu&rsquo;\u00e0 rendre sourd, BoJo \u00e9tait mal pli\u00e9 dans cet arrangement, malgr\u00e9 son abattage extraordinaire, sa superbe indiff\u00e9rence aux mensonges, comme on dit &lsquo;<em>superb isolation<\/em>&lsquo; par rapport \u00e0 la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-verite-de-situation-verite\">v\u00e9rit\u00e9-de-situation<\/a>.<\/p>\n<\/p>\n<p><p>Larry Johnson (aucun lien de parent\u00e9, pr\u00e9cise-t-il avec une plume ironique <a href=\"https:\/\/sonar21.com\/europe-catches-major-blowback-in-failed-attempt-to-confront-russia\/\">dans son texte<\/a>) ne passe rien \u00e0 Boris Johnson.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>C&rsquo;est \u00e0 Boris Johnson (aucun lien de parent\u00e9), du Royaume-Uni, que l&rsquo;on doit le plus grand spectacle de clowns du cirque. L&rsquo;\u00e9conomie britannique est sur le point de rejouer <a href=\"https:\/\/www.theguardian.com\/business\/2022\/jul\/02\/dashboard-of-decline-seven-charts-that-explain-britains-economic-crisis?amp;amp;amp;amp\">le naufrage du Titanic<\/a> :<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0Le Royaume-Uni glisse vers une r\u00e9cession. Il y a seulement six mois, on s&rsquo;attendait \u00e0 une forte reprise, mais l&rsquo;impact de la pand\u00e9mie, le lent retour aux sch\u00e9mas de travail pr\u00e9-Covid et l&rsquo;inflation galopante provoqu\u00e9e par l&rsquo;invasion de l&rsquo;Ukraine ont d\u00e9prim\u00e9 l&rsquo;\u00e9conomie.<\/em><\/p>\n<\/p>\n<p><p>&raquo; \u00ab\u00a0<em>La semaine derni\u00e8re, le gouverneur de la Banque d&rsquo;Angleterre, Andrew Bailey, a averti que les Britanniques risquaient de subir une r\u00e9cession plus profonde et plus longue que les autres grandes nations industrialis\u00e9es. Il a \u00e9galement d\u00e9clar\u00e9 que l&rsquo;inflation serait plus s\u00e9v\u00e8re et persistante.\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Au lieu de rester \u00e0 la maison et d&rsquo;essayer au moins de faire semblant de s&rsquo;attaquer aux probl\u00e8mes politiques croissants, Boris a enrichi son compte de fid\u00e9lisation par des voyages \u00e0 Kiev afin de passer du temps avec son nouvel amour fou, Zelenski le com\u00e9dien. Cette n\u00e9gligence de Boris \u00e0 l&rsquo;\u00e9gard du front int\u00e9rieur a atteint son paroxysme aujourd&rsquo;hui, alors qu&rsquo;il est confront\u00e9 \u00e0 un tsunami de d\u00e9missions au sein de son cabinet. Boris a imit\u00e9 \u00e0 merveille Helen Keller en refusant cat\u00e9goriquement de reconna&icirc;tre l&rsquo;\u00e9rosion dramatique du soutien ou d&rsquo;entendre les appels \u00e0 la d\u00e9mission de son propre \u00e9quipage. Il tr\u00e9buche, du moins pour l&rsquo;instant, irascible et t\u00eatu. Nous n&rsquo;avons pas \u00e9t\u00e9 t\u00e9moins d&rsquo;un tel niveau d&rsquo;auto-illusion depuis qu&rsquo;Hitler, terr\u00e9 dans son bunker, d\u00e9pla\u00e7ait des arm\u00e9es imaginaires pour tenter d&rsquo;arr\u00eater les Sovi\u00e9tiques.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Selon la presse, Boris se prend pour une r\u00e9incarnation de Winston Churchill&#8230; <\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Johnson (Larry) embraye aussit\u00f4t, du d\u00e9part imminent de BoJo \u00e0 la crise majeure qui affecte toute l&rsquo;Europe-UE. Il \u00e9tend le champ des catastrophiques erreurs, ajoutant au r\u00e9gime-boomerang des sanctions antirusses la grande marche impos\u00e9e au pas de charge par l&rsquo;UE et son &lsquo;<em>Green ReSet<\/em>&lsquo; de passage imm\u00e9diat et sans attendre \u00e0 l&rsquo;\u00e9conomie du futur de l&rsquo;humanit\u00e9.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Depuis les \u00e9checs r\u00e9p\u00e9t\u00e9s de &lsquo;<a href=\"https:\/\/en.wikipedia.org\/wiki\/Wile_E._Coyote_and_the_Road_Runner\">Wild E. Coyote<\/a>&lsquo; pour attraper &lsquo;Road Runner&rsquo;, nous n&rsquo;avons jamais vu de d\u00e9b\u00e2cles comme celles qui se d\u00e9roulent actuellement au Royaume-Uni et en Europe \u00e0 la suite de leurs efforts malavis\u00e9s pour d\u00e9truire la Russie. L&rsquo;\u00e9conomie allemande est au bord du pr\u00e9cipice. Avec une \u00e9conomie qui d\u00e9pend de l&rsquo;importation de p\u00e9trole et de gaz en provenance de Russie, le Premier ministre allemand Olaf Scholz a pens\u00e9 que ce serait une bonne id\u00e9e de se couper de son principal fournisseur. Qu&rsquo;y a-t-il de mal \u00e0 cela ?<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Aux Pays-Bas, le gouvernement a d\u00e9clar\u00e9 une guerre \u00e9conomique \u00e0 ses agriculteurs (inspir\u00e9 par le d\u00e9sir du gouvernement de se mettre au pas du &lsquo;Green ReSet&rsquo;) et a \u00e9t\u00e9 surpris de d\u00e9couvrir que ses agriculteurs produisent de la nourriture. Qui l&rsquo;aurait cru ? Regardez les rayons des \u00e9piceries :<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Des \u00e9tag\u00e8res vides dans les supermarch\u00e9s n\u00e9erlandais de Kampen apr\u00e8s la&#8230; Ils voulaient se mettre au vert mais maintenant ils ont faim, face aux rayons d\u00e9garnis des grandes surface. Apparemment, tous les produits alimentaires ne viennent pas emball\u00e9s par Amazon<\/em>&#8230; &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Enfin, Johnson (Larry) introduit sa Grande Intuition que lui inspire la chute de BoJo. Il y voir une pr\u00e9misse de plus en plus \u00e9vidente d&rsquo;une autre chute, facilit\u00e9 par la fragilit\u00e9 fantomatique du personnage et son extraordinaire impopularit\u00e9, celles du pr\u00e9sident Biden. A partir <a href=\"https:\/\/sonar21.com\/getting-rid-of-joe-biden-possible-scenarios\/\">de l&rsquo;extrait ci-dessous<\/a>, qui introduit l&rsquo;hypoth\u00e8se, Johnson d\u00e9veloppe les diff\u00e9rents cas de figure bas\u00e9s sur la probabilit\u00e9, selon lui, d&rsquo;un d\u00e9part anticip\u00e9 de Biden, soit par d\u00e9mission, soi par destitution selon le 25<sup>\u00e8me<\/sup> Amendement (impossibilit\u00e9 par le pr\u00e9sident de continuer \u00e0 assurer son mandat \u00e0 cause de mauvaise sant\u00e9 mentale et physique) ; c&rsquo;est-\u00e0-dire la perspective d&rsquo;une gigantesque crise constitutionnelle mettant enfin un peu de d\u00e9sordre cosmique dans l&rsquo;\u00e9parpillement des d\u00e9sordres du syst\u00e8me de l&rsquo;am\u00e9ricanisme.<\/p>\n<\/p>\n<p><p>Selon lui, une course-poursuite est lanc\u00e9e, pour les d\u00e9mocrates, pour obtenir le d\u00e9part de Biden avant la mise en, place, le 1<sup>er<\/sup> janvier 2023, d&rsquo;un Congr\u00e8s domin\u00e9 par les r\u00e9publicains suite \u00e0 leur \u00e9crasante victoire probable des <em>mid-terms<\/em>. Dans tous les cas, on tombe sur l&rsquo;hypoth\u00e8se d&rsquo;une pr\u00e9sidente Harris totalement incapable d&rsquo;assumer ses fonctions, cherchant un vice-pr\u00e9sident (VP) pour la prendre par la main, &ndash; <\/p>\n<p>&bull; \u00e9voquant m\u00eame l&rsquo;id\u00e9e que ce soit Obama si le d\u00e9part de Biden \u00e9tait avant le 1<sup>er<\/sup> janvier 2023 (mais il y aurait alors l&rsquo;imbroglio constitutionnel qu&rsquo;un pr\u00e9sident ne peut assumer plus de deux mandats alors qu&rsquo;un Obama VP, avec d\u00e9j\u00e0 deux mandats, serait en position de devenir pr\u00e9sident si Harris s&rsquo;en allait) ;<\/p>\n<p>&bull; ou bien \u00e9voquant l&rsquo;id\u00e9e, cette circonstance survenant apr\u00e8s le 1<sup>er<\/sup> janvier 2023, que les r\u00e9publicains forceraient \u00e0 la d\u00e9signation, par automatisme constitutionnel ou par vote des Chambres, d&rsquo;un VP r\u00e9publicain aupr\u00e8s d&rsquo;Harris !<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Alors que le Premier ministre britannique, Boris Johnson, se dirige vers la sortie, il convient de se demander si Joe Biden ira au bout de son mandat ou s&rsquo;il sera contraint de prendre sa retraite. Alors que l&rsquo;on s&rsquo;attend de plus en plus \u00e0 ce que les R\u00e9publicains balaient la Chambre des repr\u00e9sentants et reprennent le S\u00e9nat des &Eacute;tats-Unis, il convient de se demander si les D\u00e9mocrates veulent r\u00e9duire leurs pertes avant les \u00e9lections et laisser tomber Joe Biden ou s&rsquo;ils vont l&rsquo;encourager \u00e0 d\u00e9missionner avant que les organes l\u00e9gislatifs contr\u00f4l\u00e9s par les R\u00e9publicains ne prennent le contr\u00f4le en janvier<\/em>&#8230; &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Tout cela est, de la part de Johnson (Larry) farci d&rsquo;hypoth\u00e8ses qui seraient consid\u00e9r\u00e9es comme compl\u00e8tement farfelues en d&rsquo;autres temps, mais qui ont aujourd&rsquo;hui, dans ces temps absolument farfelues, beaucoup d&rsquo;assise et de cr\u00e9dit. Une id\u00e9e domine, qui ressort de ces textes et qui est certainement tr\u00e8s int\u00e9ressante : la chute de BoJo porte un tr\u00e8s rude coup \u00e0 la puissante direction anglo-saxonne de la croisade antirusses, simplement parce que le comp\u00e8re am\u00e9ricaniste d&rsquo;habitude si omnipr\u00e9sent et imp\u00e9ratif, est aujourd&rsquo;hui comme un tr\u00e8s puissant coq sans temp\u00eate, qui continue de bouger dans tous les sens et de pousser des cocoricos par on sait o&ugrave;, mais qui ne voit rien, qui n&rsquo;entend rien, qui ne comprend rien, qui tourne-fou.<\/p>\n<\/p>\n<p><p>Ainsi en est-il aujourd&rsquo;hui de l'\u00a0\u00bbanglosph\u00e8re\u00a0\u00bb, dont on pensait il y a encore trois jours, qu&rsquo;elle dominait tout et dirigeait tout, et dont on pourrait \u00eatre conduit \u00e0 d\u00e9couvrir qu&rsquo;il s&rsquo;agissait essentiellement d&rsquo;une dynamique ressuscit\u00e9e par le BoJo clownesque et un peu fou, qui avait r\u00e9ussi \u00e0 convaincre ses partenaires-employ\u00e9s, tous clownesques et un peu fous \u00e9galement, que la dynamique anglo-saxonne \u00e9tait plus puissante que jamais. Le fait est que le d\u00e9part de Boris Johnson est v\u00e9ritablement un coup tr\u00e8s dur pour l&rsquo;anglosaxonisme, et pour toute la coalition antirusse du <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-bloc-bao-1\">bloc-BAO<\/a>.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">La <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-la-gces\">GrandeCrise<\/a>, c&rsquo;est chaque jour<\/h3>\n<\/p>\n<p><p>Comme dit plus haut, cette id\u00e9e sur laquelle nous revenons parce qu&rsquo;elle illustre chaque jour depuis le 24 f\u00e9vrier particuli\u00e8rement, et parce qu&rsquo;elle repr\u00e9sente la Grande &Eacute;nigme de la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-la-gces\">GrandeCrise<\/a>, en m\u00eame temps qu&rsquo;elle en constitue le mode de fonctionnement circulaire et tourbillonnaire&#8230; Cette phrase : \u00ab\u00a0chaque jour on pourrait \u00e9crire un texte comme celui-ci qui pr\u00e9tendrait tenir lieu de chronique catastrophique du susdit effondrement\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>La GrandeCrise est comme un incendie dont ne voit ni le commencement, ni la fin, qui tourbillonne effectivement, qui court de place en place de domaine diff\u00e9rent \u00e0 un autre domaine diff\u00e9rent ; \u00ab\u00a0<em>Ils n&rsquo;en mouraient pas tous mais tous \u00e9taient touch\u00e9s<\/em>\u00ab\u00a0, comme si chaque \u00ab\u00a0subcrise\u00a0\u00bb dans la crise \u00e9tait un de ces animaux de la fable du grand crisologue avant-gardiste et futurologue que fut Jean de La Fontaine &#8230;. La GrandeCrise a la vertu d&rsquo;\u00eatre une Seule \u00ab\u00a0Lecture pour Tous\u00a0\u00bb : ce que vous ne comprenez pas aussit\u00f4t, la subcrise que vous ne comprenez pas aussit\u00f4t, liez-la \u00e0 la GrandeCrise et attendez pour d\u00e9couvrir son identit\u00e9 les \u00e9v\u00e9nements qui suivent pour comprendre quel sorte lien relie la premi\u00e8re \u00e0 la seconde comme l&rsquo;on dit \u00ab\u00a0de quel bois se chauffe cette subcrise\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>En effet, tout est li\u00e9, globalis\u00e9, influenc\u00e9, rien n&rsquo;\u00e9chappe \u00e0 ce tourbillon central qui, aujourd&rsquo;hui, est le centre d&rsquo;un monde en cours de d\u00e9sint\u00e9gration. C&rsquo;est le grand tour de la globalisation, son pi\u00e8ge affreux, sa blague terrible : la seule chose qui s&rsquo;est vraiment globalis\u00e9e, c&rsquo;est la crise&#8230;Le probl\u00e8me du commentateur aujourd&rsquo;hui, de celui qui se voit confier la mission de \u00ab\u00a0voir\u00a0\u00bb pour aussit\u00f4t \u00ab\u00a0appr\u00e9hender\u00a0\u00bb et \u00ab\u00a0classer\u00a0\u00bb dans l&rsquo;ordre du d\u00e9sordre crisique, c&rsquo;est qu&rsquo;il n&rsquo;y a aucune r\u00e9f\u00e9rence crisique stable.<\/p>\n<\/p>\n<p><p>La guerre, la catastrophe \u00e9conomique, les folies du futurisme archa\u00efque (C.S. Lewis \u00e9crivait sur le transhumanisme d\u00e8s 1944), le d\u00e9chirement identitaire, les r\u00e8gles g\u00e9ostrat\u00e9giques, les grands mouvements collectifs, tout cela est ensemble boulevers\u00e9, roulant de subcrise en subcrise, baissant le feu puis explosant soudain sans jamais s&rsquo;\u00e9teindre ni se d\u00e9faire compl\u00e8tement, pr\u00eat \u00e0 recommencer. C&rsquo;est-\u00e0-dire qu&rsquo;on est bien contraint finalement \u00e0 reconna&icirc;tre qu&rsquo;il existe un ordre, un rangement paradoxal dans cet immense chaos, une direction et une coordination dans ce d\u00e9sordre \u00e9pouvantable.<\/p>\n<\/p>\n<p><p>Plus que jamais nous devons reconna&icirc;tre comme faisant partie d&rsquo;une influence majeure, d&rsquo;un \u00e9v\u00e9nement ext\u00e9rieur et au-dessus de nous, qui nous domine et nous emporte sans-dessus-dessous, mais en m\u00eame temps qui nous maintient et nous contient, et nous range, et nous pr\u00e9pare \u00e0 des alignements nouveaux, lorsque les plan\u00e8tes auront pris leur place dans les cieux. Nous reprenons ici cette observation que nous faisions il y a quelques temps (<a href=\"https:\/\/www.dedefensa.org\/article\/rien-ne-se-perd-rien-ne-se-cree-tout-se-defait\">3 mai 2022<\/a>), o&ugrave; nous reprenions en la d\u00e9formant, en la retournant compl\u00e8tement, en l&rsquo;ouvrant spirituellement l\u00e0 o&ugrave; elle se ferme mat\u00e9riellement, la formule de Lavoisier&#8230;<\/p>\n<\/p>\n<p><p>&laquo; <em>Rien ne se perd, rien ne se cr\u00e9e, tout se d\u00e9fait<\/em> &raquo; : notre &laquo; <em>Retour aux sources<\/em> &raquo; passe n\u00e9cessairement par une remise en ordre qui appara&icirc;t d&rsquo;abord comme un immense d\u00e9sordre incompr\u00e9hensible, tant la perversit\u00e9 du \u00ab\u00a0<a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-le-dechainement-de-la-matiere\">d\u00e9cha&icirc;nement de la Mati\u00e8re<\/a>\u00a0\u00bb avait habitu\u00e9 nos esprits \u00e0 cette \u00e9pouvantable catastrophe (la modernit\u00e9) comme \u00e9tant l&rsquo;ultime ach\u00e8vement de notre destin. Le d\u00e9sordre du monde et de la GrandeCrise, c&rsquo;est la voie d&rsquo;une formidable remise en ordre, puisque pour faire d\u00e9cisivement, il fait d&rsquo;abord tout d\u00e9faire&#8230;<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Mais Lavoisier parlait de chimie et de mati\u00e8re ; je parle et nous parlons de m\u00e9tahistoire et des hommes passant du statut d&rsquo;acteurs respectueux de l&rsquo;auteur \u00e0 celui de figurants laiss\u00e9s \u00e0 eux-m\u00eames, ne connaissant plus rien des intentions de l&rsquo;auteur et s&rsquo;agitant dans des entreprises sans aucun rapport avec le destin central, m\u00eame s&rsquo;ils s&rsquo;imaginent le d\u00e9cider. Ainsi, et si je suis cette logique, n&rsquo;envisageons-nous pas que le milieu clos ainsi d\u00e9crit par Lavoisier permet la transformation en quelque chose d&rsquo;autre, de plus utile, de plus \u00ab\u00a0performant\u00a0\u00bb, etc., qui satisfasse l&rsquo;auteur ; mais bien que le milieu clos permet de d\u00e9faire toutes les grossi\u00e8res pr\u00e9tendues-r\u00e9alisations qui nous sont d\u00e9bit\u00e9es par les figurants qui se prennent pour l&rsquo;auteur.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>C&rsquo;est un jugement difficile \u00e0 exprimer que celui qui d\u00e9nie aux hommes, dans la p\u00e9riode pr\u00e9sente, la moindre influence structur\u00e9e et d\u00e9cisive sur le cours des choses. Pourtant je ne puis l&rsquo;exprimer diff\u00e9remment : il s&rsquo;agit bien de cette situation comme un constat objectif, o&ugrave; l&rsquo;influence des hommes, malgr\u00e9 la disposition d&rsquo;immenses moyens de puissance mais un esprit trop atrophi\u00e9 et terroris\u00e9 pour en disposer, ne renvoie plus \u00e0 aucune structure harmonieuse et \u00e9quilibr\u00e9e ni ne suscite plus aucune d\u00e9cision remarquable et utile. La production extraordinaire de d\u00e9sordre sous l&rsquo;impulsion d&rsquo;une pens\u00e9e d\u00e9niant le r\u00e9el jusqu&rsquo;\u00e0 pr\u00e9tendre le remplacer par une pure cr\u00e9ation d&rsquo;un esprit faussaire, propose une suite de simulacres de plus en plus d\u00e9termin\u00e9s par l&rsquo;hybris et le narcissisme des cr\u00e9atures, et de moins en moins avec les \u00e9v\u00e9nements r\u00e9glant la v\u00e9rit\u00e9 du monde.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Comme la nature dont elle fait partie, l&rsquo;histoire a horreur du vide, y compris celui qui lui fait d\u00e9truire le pass\u00e9 \u00e0 mesure que le pr\u00e9sent pr\u00e9tend exister sans lui ; elle se fait donc m\u00e9tahistoire et passe la main aux \u00e9v\u00e9nements de la destin\u00e9e du monde, pour qu&rsquo;ils fassent l&rsquo;&oelig;uvre divine dont ils ont la charge. Ainsi reprennent-ils \u00e0 leur compte la <a href=\"https:\/\/www.dedefensa.org\/article\/valsez-mensonges\">pr\u00e9tention<\/a> absurde des neocons : il suffit de changer un seul mot et d&rsquo;en ajouter quelques autres, d\u00e9couvrant alors jusqu&rsquo;\u00e0 quelle extr\u00e9mit\u00e9 la pr\u00e9tention humaine a pu s&rsquo;aventurer.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0Nous sommes <\/em>[l&rsquo;<strong>\u00e9v\u00e9nement<\/strong>]<em> maintenant et quand nous agissons nous cr\u00e9ons notre propre r\u00e9alit\u00e9<\/em> [qui dit la v\u00e9rit\u00e9-de-situation]<em>. Et alors que vous \u00e9tudierez cette r\u00e9alit\u00e9, &ndash; judicieusement, si vous voulez, &ndash; nous agirons de nouveau, cr\u00e9ant d&rsquo;autres nouvelles r\u00e9alit\u00e9s, que vous pourrez \u00e0 nouveau \u00e9tudier, et c&rsquo;est ainsi que continuerons les choses. Nous sommes <\/em>[les cr\u00e9ateurs] <em>de l&rsquo;histoire&#8230; Et vous, vous tous, il ne vous restera qu&rsquo;\u00e0 \u00e9tudier ce que <\/em>[l&rsquo;<strong>\u00e9v\u00e9nement <\/strong>a] [cr\u00e9\u00e9]<em>.\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Retour aux sources&#8230;<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>La GrandeCrise, jour apr\u00e8s jour &bull; Jamais certes, autant que dans tel texte, il n&rsquo;a \u00e9t\u00e9 autant question de ce que nous d\u00e9signons comme la GrandeCrise (reprenant la \u00ab\u00a0Grande Crise d&rsquo;Effondrement du Syst\u00e8me, ou GCES). &bull; Certes, il y a des \u00e9v\u00e9nements sp\u00e9cifiques aujourd&rsquo;hui pour s&rsquo;y int\u00e9resser, et c&rsquo;est notamment le d\u00e9part du Premier ministre&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[1235,21647,4911,9713,6723,3203,2866,2906,8169,13670],"class_list":["post-80260","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-biden","tag-bojo","tag-destitution","tag-evenements","tag-green","tag-hollande","tag-johnson","tag-larry","tag-reset","tag-ukrisis"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=80260"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80260\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=80260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=80260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=80260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}