{"id":80282,"date":"2022-07-29T19:18:43","date_gmt":"2022-07-29T19:18:43","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2022\/07\/29\/vogue-en-zelenskistan\/"},"modified":"2022-07-29T19:18:43","modified_gmt":"2022-07-29T19:18:43","slug":"vogue-en-zelenskistan","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2022\/07\/29\/vogue-en-zelenskistan\/","title":{"rendered":"\u2018<em>Vogue<\/em>&lsquo; en Zelenskistan"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">&lsquo;<em>Vogue<\/em>&lsquo; en Zelenskistan<\/h2>\n<\/p>\n<p><p>29 juillet 2022 (19H15) &ndash; Il faut bien dire que le reportage photographique du prestigieux &lsquo;<em>Vogue Magazine&rsquo;<\/em> sur le couple Zelenski a repr\u00e9sent\u00e9 une \u00e9tape importante dans la manufacture de la r\u00e9alit\u00e9 de la guerre en Zelenskistan. Paradoxalement, ce ne fut pas une image guerri\u00e8re mais une image de communication, affirmant le triomphe d&rsquo;une culture, d&rsquo;une fa\u00e7on d&rsquo;\u00eatre et une fa\u00e7on de voir ; paradoxalement, au contraire, ce fut une image guerri\u00e8re au plus haut degr\u00e9, un cri qui aurait tant aim\u00e9 \u00eatre tendre et po\u00e9tique de ralliement autour du Zelenskistan, pour la victoire finale.<\/p>\n<\/p>\n<p><p>Auparavant, &ndash; avant que &lsquo;<em>Vogue<\/em>&lsquo; ne vomisse sa diarrh\u00e9e et ach\u00e8ve d&rsquo;envoyer aux enfers cette prestigieuse publication qui fut si longtemps le porte-drapeau de la vraie et grande Haute Couture, sur la ligne Paris-New York, de Lauren Bacall \u00e0 Jacques Fath, &ndash; Zelenski avait trac\u00e9 les lignes de sa doctrine ultime, culminant dans ce reportage du Courage inspir\u00e9 en t-shirt de combat tenant dans ses bras l&rsquo;H\u00e9ro\u00efsme incarn\u00e9e en mannequin-r\u00e9volutionnaire de la modernit\u00e9. Zelenski s&rsquo;\u00e9tait adress\u00e9 \u00e0 Piers Morgan, de la BBC je crois, pour lancer <a href=\"https:\/\/www.rt.com\/news\/559736-zelensky-piers-morgan-inflation\/\">cette diatribe superbe<\/a> : \u00ab\u00a0ce que nous faisons (<a href=\"https:\/\/www.msn.com\/fr-ch\/news\/other\/zelensky-et-son-\u00e9pouse-olena-s-affichent-en-une-de-vogue\/ar-AAZZDR7\">Olena et moi<\/a>), c&rsquo;est un ultime effort jusqu&rsquo;\u00e0 la victoire, faites donc un effort de votre c\u00f4t\u00e9, un petit effort tout de m\u00eame, du c\u00f4t\u00e9 du fric, vous voyez\u00a0\u00bb&#8230;<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>S&rsquo;adressant \u00e0 Morgan lors d&rsquo;une interview t\u00e9l\u00e9vis\u00e9e r\u00e9cemment enregistr\u00e9e, Zelenski a rappel\u00e9 aux Am\u00e9ricains exc\u00e9d\u00e9s par le flot d&rsquo;aide vers l&rsquo;Ukraine, &ndash; plus de 56 milliards de dollars depuis f\u00e9vrier, &ndash; que les deux pays \u00ab\u00a0se battent pour des valeurs absolument communes\u00a0\u00bb.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0La guerre en Ukraine est toujours la guerre contre ces valeurs qui sont profess\u00e9es aux &Eacute;tats-Unis et en Europe\u00a0\u00bb, a-t-il dit \u00e0 Morgan, selon un article du New York Post. \u00ab\u00a0Nous donnons nos vies pour vos valeurs et la s\u00e9curit\u00e9 commune du monde\u00a0\u00bb. \u00ab\u00a0Par cons\u00e9quent, l&rsquo;inflation n&rsquo;est rien, le Covid n&rsquo;est rien\u00a0\u00bb, a-t-il poursuivi. \u00ab\u00a0Ces choses sont secondaires. La chose la plus importante est de survivre et de pr\u00e9server sa vie, sa famille et son pays. Par cons\u00e9quent, pour l&rsquo;instant, nous faisons ce travail, mais l&rsquo;Occident doit nous aider.\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Kiev a d\u00e9clar\u00e9 qu&rsquo;il avait besoin d&rsquo;une aide \u00e9trang\u00e8re jusqu&rsquo;\u00e0 65 milliards de dollars cette ann\u00e9e pour rester \u00e0 flot, tandis que les conseillers de Zelenski ont demand\u00e9 des envois d&rsquo;armes de plus en plus massifs \u00e0 l&rsquo;Occident&#8230; Au d\u00e9but du mois, le ministre ukrainien de la d\u00e9fense, Alexey Reznikov, a d\u00e9clar\u00e9 que l&rsquo;arm\u00e9e ukrainienne avait besoin d&rsquo;au moins 100 syst\u00e8mes d&rsquo;artillerie \u00e0 obus et fus\u00e9es guid\u00e9es HIMARS de fabrication am\u00e9ricaine, &ndash; soit environ un tiers du stock total des Etats-Unis, &ndash; pour mener une \u00ab\u00a0contre-offensive efficace\u00a0\u00bb contre les forces russes.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Zelenski a d\u00e9clar\u00e9 \u00e0 Morgan qu&rsquo;il esp\u00e9rait un soutien illimit\u00e9 de la part de l&rsquo;Occident, d\u00e9clarant que \u00ab\u00a0l&rsquo;aide ne sera pas suffisante tant que la guerre ne sera pas termin\u00e9e, et tant que nous ne gagnerons pas\u00a0\u00bb.<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Ainsi se comprend-il que le reportage de &lsquo;<em>Vogue Magazine<\/em>&lsquo; correspond si vous voulez en force de frappe psychologique de communication, \u00e0 cent autre HIMARS, \u00e0 placer aupr\u00e8s des cent vrais HIMARS que Mr. et Mme Z. attendent impatiemment dans le courrier courant du Pentagone. Il y en a qui n&rsquo;ont pas compris, ni le sens du combat, ni la forme du combat men\u00e9 par le couple Zelenski en cette occurrence, avec la noblesse et la bravoure d\u00e9sint\u00e9ress\u00e9e  de Cond\u00e9-Nast, le puissant propri\u00e9taire et \u00e9diteur, entre tant d&rsquo;autres merveilles du capitalisme am\u00e9ricaniste de grand luxe, de &lsquo;<em>Vogue Magazine<\/em>&lsquo;.<\/p>\n<\/p>\n<p><p>Parmi ces gens qui ne comprennent rien \u00e0 cette man&oelig;uvre de si grand style que Patton lui-m\u00eame en serait rest\u00e9 interdit, il y a l&rsquo;infernale Caitline Johnstone, la plus inacceptable &lsquo;journaliste-voyou&rsquo; de toute la presse de r\u00e9crimination, retardatrice, diffamatoire, plac\u00e9e vainement en position d&rsquo;obstacle sur les rails du Progr\u00e8s &lsquo;En-Marche&rsquo;. Caitline a \u00e9crit une <a href=\"https:\/\/caitlinjohnstone.com\/2022\/07\/27\/the-phoniest-most-pr-intensive-war-of-all-time\/\">colonne rageuse<\/a> et pleine de sarcasmes et de ressentiment en nous pr\u00e9sentant &laquo; <em>The Phoniest, Most PR-Intensive War Of All Time<\/em> &raquo;, &ndash; et nous exposant en quelques paragraphes son analyse faussaire, jalouse, pleine de mauvais sentiments&#8230;<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Le pr\u00e9sident et la premi\u00e8re dame d&rsquo;Ukraine ont <a href=\"https:\/\/www.yahoo.com\/lifestyle\/president-zelenskyy-first-lady-zelenska-193937295.html\"> pos\u00e9 pour une s\u00e9ance photo romantique<\/a>, pour &lsquo;Vogue Magazine&rsquo;, o&ugrave; le pr\u00e9sident Volodymyr Zelenski <a href=\"https:\/\/www.independent.co.uk\/life-style\/olena-zelenska-marriage-vogue-interview-b2131738.html\">s&rsquo;exprime de fa\u00e7on po\u00e9tique<\/a> sur son amour pour sa femme bien-aim\u00e9e.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Maintenant, je sais ce que vous pensez : o&ugrave; Zelenski prend-il le temps pour une s\u00e9ance photo avec &lsquo;Vogue&rsquo; au milieu de son programme charg\u00e9 d&rsquo;apparitions de relations publiques pour d&rsquo;autres grandes institutions occidentales ?<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Je veux dire que c&rsquo;est apr\u00e8s tout le m\u00eame Volodymyr Zelenski qui a \u00e9t\u00e9 si occup\u00e9 \u00e0 faire des apparitions vid\u00e9o pour <a href=\"https:\/\/www.grammy.com\/news\/ukraine-president-volodymyr-zelensky-speech-2022-grammys\">les Grammy Awards<\/a>, le <a href=\"https:\/\/edition.cnn.com\/2022\/05\/18\/entertainment\/cannes-volodymyr-zelensky\/index.html\">Festival de Cannes<\/a> , le <a href=\"https:\/\/www.c-span.org\/video\/?520500-1\/ukrainian-president-zelensky-addresses-world-economic-forum-davos\">Forum \u00e9conomique mondial<\/a> et sans doute \u00e9galement <a href=\"https:\/\/www.theguardian.com\/world\/2022\/jun\/04\/bilderberg-reconvenes-in-person-after-two-year-pandemic-gap\">le groupe Bilderberg<\/a>. Il a aussi rencontr\u00e9 des c\u00e9l\u00e9brit\u00e9s comme les acteurs <a href=\"https:\/\/www.hollywoodreporter.com\/movies\/movie-news\/ben-stiller-meets-with-ukraine-president-volodymyr-zelensky-youre-my-hero-1235168754\/\">Ben Stiller<\/a> et <a href=\"https:\/\/archive.ph\/MrGei\">Sean Penn<\/a>, <a href=\"https:\/\/eprimefeed.com\/latest-news\/bono-and-the-edge-met-with-zelensky-and-sing-in-the-kiev-subway\/82035\/\">Bono et Edge<\/a> du groupe U2. C&rsquo;est une tourn\u00e9e de relations publiques si bien agenc\u00e9e qu&rsquo;il pourrait aussi bien la terminer par une discussion sur l&rsquo;importance strat\u00e9gique de l&rsquo;artillerie \u00e0 longue port\u00e9e avec <a href=\"https:\/\/www.youtube.com\/watch?v=vSYadh2xmcI\">Elmo<\/a> en chantant avec lui &lsquo;Sesame Street&rsquo;.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Ah oui, au fait n&rsquo;y a-t-il pas une guerre ou quelque chose dans ce genre actuellement en Ukraine ? On aurait pu penser qu&rsquo;il devrait \u00eatre probablement un peu occup\u00e9 avec \u00e7a \u00e9galement.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Bref, dites que je suis folle si vous voulez, mais je commence \u00e0 soup\u00e7onner qu&rsquo;il pourrait y avoir un effort concert\u00e9 pour manipuler la fa\u00e7on dont nous pensons la guerre en Ukraine. En fait, j&rsquo;irais m\u00eame jusqu&rsquo;\u00e0 dire que c&rsquo;est la guerre la plus agressivement g\u00e9r\u00e9e par la manipulation de la perception que nous avons jamais connue<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Je pense qu&rsquo;elle, Caitline Johnstone, n&rsquo;a pas bien compris \u00e0 quoi nous avons affaire, et peut-\u00eatre bien que moi, pas davantage. La guerre de relations publiques que m\u00e8ne le couple des Z. avec le reportage photos de &lsquo;<em>Vogue Magazine<\/em>&lsquo; n&rsquo;est pas une affaire ukrainienne ou d&rsquo;une de ces contr\u00e9es approximatives alentour. Il s&rsquo;agit d&rsquo;une tr\u00e8s-grande strat\u00e9gie de l&rsquo;&Eacute;poque d&rsquo;Apr\u00e8s, une fois r\u00e9gl\u00e9 leur compte aux troupes en d\u00e9route des <em>moujiks <\/em>de l&rsquo;Est. C&rsquo;est une version magnifi\u00e9e, amplifi\u00e9e jusqu&rsquo;\u00e0 l&rsquo;extr\u00eame de la Grande Guerre Cin\u00e9matographique que conduisirent les USA le si\u00e8cle dernier, &ndash; pendant victorieux de la Grande Guerre Patriotique que les <em>moujiks <\/em>en d\u00e9route crurent avoir remport\u00e9 en ces m\u00eames autres temps.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">La Grande Guerre Canonique<\/h3>\n<\/p>\n<p><p>Il est vrai, je l&rsquo;avoue, que cette affaire m&rsquo;a remis en m\u00e9moire une autre occurrence dans le monde de la communication, en remontant aux origines des ann\u00e9es 1940, &ndash; et de ce fait, me renvoyant \u00e0 un texte intitul\u00e9 &laquo; <em>Debord \u00e0 Hollywood<\/em> &raquo; (du <a href=\"https:\/\/www.dedefensa.org\/article\/debord-a-hollywood\">4 janvier 2018<\/a>)&#8230; Du coup, mon d\u00e9veloppement devient bien plus s\u00e9rieux car nous sommes l\u00e0 aux racines m\u00eame de l&rsquo;entreprise de la cr\u00e9ation de l&rsquo;\u00e9v\u00e9nement, devenu <em>narrative<\/em>, nourrie de l&rsquo;image, avec les acteurs de \u00ab\u00a0la guerre\u00a0\u00bb pris chez les vrais acteurs (Z. n&rsquo;en est-il pas un, justement ?), et la <em>narrative <\/em>devenant grande superproduction hollywoodienne :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Le professeur George H. Roeder Jr., qui est professeur of liberal art, dont l&rsquo;image du cin\u00e9matographe fait partie, et nullement historien, nous pr\u00e9sente la Deuxi\u00e8me Guerre mondiale sous les traits d&rsquo;une \u00ab\u00a0<a href=\"https:\/\/yalebooks.yale.edu\/book\/9780300062915\/censored-war\">guerre censur\u00e9e<\/a>\u00a0\u00bb ; mais bien au-del\u00e0 de cet aspect somme toute conjoncturel, il nous instruit dans ses remarques introductives de ceci qui r\u00e9sume notre propos \u00e0 merveille : \u00ab\u00a0La Deuxi\u00e8me Guerre mondiale fut le premier film dans lequel chaque Am\u00e9ricain pouvait avoir un r\u00f4le.<\/em> [&#8230;] <em>La Deuxi\u00e8me Guerre mondiale offrit \u00e0 chaque citoyen<\/em> [am\u00e9ricain] <em>le double r\u00f4le de spectateur et de participant\u00a0\u00bb. George H. Roeder Jr. nous dit bien plus de la r\u00e9elle substance de l&rsquo;\u00e9v\u00e9nement de la Deuxi\u00e8me Guerre mondiale, de sa puissance et de son influence sur la psychologie am\u00e9ricaniste<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Ainsi la mise en sc\u00e8ne de cette Grande Guerre Cin\u00e9matographique fut-elle confi\u00e9e, du c\u00f4t\u00e9 continental-USA, loin du front bien entendu, \u00e0 une formidable pl\u00e9iade de grands formats d&rsquo;Hollywood, des metteurs en sc\u00e8ne (dont certains all\u00e8rent r\u00e9ellement au front, comme John Ford ou John Huston) aux grandes stars des studios (dont certaines all\u00e8rent r\u00e9ellement dans les bombardiers de l&rsquo;USAAF, comme James Stewart et Clark Gable). Les parenth\u00e8ses indiquent bien qu&rsquo;il n&rsquo;y eut pas que des saltimbanques dans cette affaire et qu&rsquo;il y eut m\u00eame du courage, mais l&rsquo;ensemble reste un immense spectacle, du Debord-sur-Potomac, o&ugrave; la mobilisation de Hollywood, puis de toute la communication, de tout ce qui faisait image contribua \u00e0 une <em>narrative <\/em>strat\u00e9gique.<\/p>\n<\/p>\n<p><p>La Grande Guerre Cin\u00e9matographique devint alors la Grande Guerre de la Communication, et de la Communication devenue divinit\u00e9, &ndash; bref, la Grande Guerre Canonique et n&rsquo;en parlons plus. Elle devait peser sur tout ce qui suivit, r\u00e9gler nos comportements, notre bienpensance, notre progressisme, &ndash; enfin ! De notre fa\u00e7on-d&rsquo;\u00eatre, passer \u00e0 notre fa\u00e7on-de-devenir&#8230;<\/p>\n<\/p>\n<p><p>Ainsi le rapt fut-il accompli en toute innocence, je veux dire avec les habituels traits inscrits par la psychologie US dans le conflit, apr\u00e8s le conflit et jusqu&rsquo;\u00e0 nous, avec <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-notre-psychologie\">ses caract\u00e8res<\/a> que nous avons d\u00e9j\u00e0 tant et de fois pr\u00e9sent\u00e9s de l&rsquo;<a href=\"http:\/\/www.dedefensa.org\/article\/linculpabilite-et-la-psychologie-americaniste-1\">inculpabilit\u00e9<\/a> et de l&rsquo;<a href=\"http:\/\/www.dedefensa.org\/article\/apres-linculpabilite-lindefectibilite\">ind\u00e9fectibilit\u00e9<\/a>&#8230; Ainsi les choses se pass\u00e8rent-elles gr\u00e2ce \u00e0 la Grande Guerre Canonique :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>On voit notamment, dans ce texte, comment on pourrait consid\u00e9rer effectivement la Deuxi\u00e8me Guerre mondiale du point de vue am\u00e9ricaniste, comme l&rsquo;\u00e9crit le professeur Roeder Jr., comme un v\u00e9ritable spectacle o&ugrave; chaque Am\u00e9ricain serait \u00e0 la fois spectateur et acteur, et spectacle \u00e9videmment hollywoodien comme du Debord avant son heure. Il se serait agi ainsi d&rsquo;atteindre \u00e0 une certaine perfection du st\u00e9r\u00e9otype hollywoodien o&ugrave; la production de \u00ab\u00a0l&rsquo;usine \u00e0 r\u00eaves\u00a0\u00bb se confondrait avec son consommateur, faisant du \u00ab\u00a0r\u00eave\u00a0\u00bb \u00e0 pr\u00e9tention expansionniste une r\u00e9alit\u00e9 d\u00e9sormais intangible :<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>La Deuxi\u00e8me Guerre mondiale fut le premier film dans lequel chaque Am\u00e9ricain pouvait avoir un r\u00f4le<\/em>. [&#8230;] <em>La Deuxi\u00e8me Guerre mondiale offrit \u00e0 chaque citoyen<\/em>[am\u00e9ricain] <em>le double r\u00f4le de spectateur et de participant<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>&raquo; <em>Pour cette raison, la Deuxi\u00e8me Guerre mondiale fut confisqu\u00e9e, avec la complicit\u00e9 aveugle d&rsquo;un Churchill (on cite dans le texte l&rsquo;admonestation de De Gaulle \u00e0 l&rsquo;intention d&rsquo;un Churchill g\u00ean\u00e9, qui ne r\u00e9pond pas, &ndash; parce que Churchill c\u00e8de toutes les commandes de la guerre aux USA alors qu&rsquo;\u00e0 cette \u00e9poque <\/em>[novembre 1942]<em> l&rsquo;Angleterre assume l&rsquo;essentiel de l&rsquo;effort de guerre \u00e0 l&rsquo;Ouest) ; d&rsquo;une mani\u00e8re plus g\u00e9n\u00e9rale, pour parler du sort de la machine de guerre allemande en soi, la Deuxi\u00e8me Guerre mondiale fut confisqu\u00e9e au d\u00e9triment des Russes, comme ces derniers ont pu s&rsquo;en apercevoir ces derni\u00e8res ann\u00e9es o&ugrave; le r\u00f4le de l&rsquo;URSS\/Russie dans la d\u00e9faite de l&rsquo;Allemagne a \u00e9t\u00e9 minor\u00e9e, et parfois ni\u00e9e dans des conditions invraisemblables de falsification historique. On voit ainsi, avec ce dernier exemple, combien l&rsquo;op\u00e9ration de \u00ab\u00a0rapt\u00a0\u00bb r\u00e9alis\u00e9 par les USA en 1941-1945 constitue le socle de la falsification historique soutenant la politique russe actuelle des USA (et du bloc-BAO, surtout des anciens pays-satellites de l&rsquo;URSS). Elle ne cesse d&rsquo;\u00eatre \u00ab\u00a0authentifi\u00e9e\u00a0\u00bb par les productions hollywoodiennes, comme ce film de Spielberg, &lsquo;Il faut sauver le soldat Ryan&rsquo;, o&ugrave; les Am\u00e9ricains sont seuls \u00e0 d\u00e9barquer le 6 juin 1944 et o&ugrave; les indig\u00e8nes se r\u00e9v\u00e8lent \u00eatre des sauvages sans le moindre int\u00e9r\u00eat, connus sous le nom de \u00ab\u00a0les Fran\u00e7ais\u00a0\u00bb. L&rsquo;arrogance, le m\u00e9pris pour le reste du monde, la certitude de la sup\u00e9riorit\u00e9, etc., tous ces travers <\/em>[&#8230;] <em>sont d\u00e9j\u00e0 l\u00e0, ils font partie de la recette et de la tambouille qui continuent \u00e0 nous \u00eatre servies.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>(Voil\u00e0 donc bien le supr\u00e9macisme, &ndash; non pas \u00ab\u00a0blanc\u00a0\u00bb comme on se le barbouille aujourd&rsquo;hui pour les besoins de la cause postmoderne et soci\u00e9tale en cours, mais bien supr\u00e9macisme am\u00e9ricaniste, ou anglosaxoniste quand les Britts parviennent \u00e0 se maintenir sur leur path\u00e9tique strapontin. Les &lsquo;blacks&rsquo; du Congr\u00e8s comme les dames f\u00e9ministes d&rsquo;Hollywood s&rsquo;arrangent aussi bien de ce supr\u00e9macisme-l\u00e0, dans leur vie courante, avec les privil\u00e8ges et le sentiment de puissance que cette vie am\u00e9ricaniste r\u00e9serv\u00e9e aux \u00e9lites-Syst\u00e8me leur fournit.)<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Retour sur &laquo; <em>&lsquo;Vogue&rsquo; en Zelenskistan<\/em> &raquo;<\/h3>\n<\/p>\n<p><p>Ce que je veux dire enfin c&rsquo;est qu&rsquo;avec cette &lsquo;<em>Ukrisis<\/em>&lsquo; nous avons une tentative assez similaire, mais dont les concepteurs et les acteurs sont si us\u00e9s, si mauvais, bouffis et bouff\u00e9s par des montagnes de fric et de corruptions, et un simulacre pouss\u00e9 jusqu&rsquo;\u00e0 son extr\u00eame o&ugrave; il \u00e9clate comme un ballon trop gonfl\u00e9, gav\u00e9 de <em>narrative <\/em>et de mensonges, avec une <a href=\"https:\/\/www.rt.com\/russia\/559386-foreign-agent-registration-document\/\">arm\u00e9e de lobbyistes<\/a> bien sup\u00e9rieure aux effectifs sur le front, en Ukraine&#8230;<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>En juillet 2021, 11 entreprises bas\u00e9es aux &Eacute;tats-Unis \u00e9taient enregistr\u00e9es comme lobbyistes pour des clients ukrainiens au titre du FARA<\/em> [la Loi sur l&rsquo;Enregistrement des Agents &Eacute;trangers]. <em>Au cours de l&rsquo;ann\u00e9e 2021, ces influenceurs ont tent\u00e9 de faire pression sur Washington pour qu&rsquo;on liquide Nord Stream 2, qu&rsquo;on augmente les livraisons d&rsquo;aide d&rsquo;armement \u00e0 Kiev et qu&rsquo;on affecte toujours plus de forces am\u00e9ricaines et de l&rsquo;OTAN le long de la fronti\u00e8re russe.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Ce faisant, ils ont \u00e9tabli plus de 10 000 contacts avec des l\u00e9gislateurs, des groupes de r\u00e9flexion et des journalistes. C&rsquo;est un chiffre stup\u00e9fiant si l&rsquo;on consid\u00e8re que le lobby saoudien &#8211; l&rsquo;un des plus importants et des plus influents aux &Eacute;tats-Unis &#8211; n&rsquo;a eu que 2 834 interactions avec ces \u00e9l\u00e9ments au cours de la m\u00eame p\u00e9riode<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Mais le plus important, ce fut et c&rsquo;est toujours le sc\u00e9nario, le script, le casting, la mise en sc\u00e8ne, et tout cela aussi horriblement mauvais que ces mati\u00e8res furent excellemment bonnes durant la Grande Guerre Canonique de 1941-1945. Ainsi peut-on penser qu&rsquo;avec <em>Ukrisis<\/em>, nous arrivons au terme d&rsquo;un cycle dans l&rsquo;Art Simulatoire de la guerre r\u00e9alis\u00e9 \u00e0 l&rsquo;aide de l&rsquo;image et tout ce qui gravite autour. Du sommet sans \u00e9gal de 1941-45, nous arrivons au reportage photo de &lsquo;<em>Vogue Magazine<\/em>&lsquo; des \u00e9poux Zelenski.<\/p>\n<\/p>\n<p><p>Les \u00ab\u00a0Am\u00e9ricains\u00a0\u00bb, qu&rsquo;on avait fait \u00e0 leur grande joie patriotique sinon \u00e0 leur enthousiasme hollywoodien acteurs et spectateurs de la Grande Guerre Canonique, ne sont certainement en l&rsquo;occurrence, pas plus qu&rsquo;acteurs de rien du tout, et ils ne sont spectateurs que du d\u00e9sordre, de la crasse et de l&rsquo;incivilit\u00e9 dans leurs propres rues. Ils n&rsquo;ont plus rien \u00e0 battre de ces agitations d&rsquo;ils ne savent plus o&ugrave;, ni dans quel but sinon celui, probable, que les protagonistes puissent mettre assez de $millions de c\u00f4t\u00e9 pour se retirer dans les &icirc;les des divers Ca\u00efmans des diverses Mers des Sargasses et des Cara\u00efbes.<\/p>\n<\/p>\n<p><p>C&rsquo;est-\u00e0-dire que nos organisateurs et nos influenceurs ne trimbalent pas le quart du dixi\u00e8me de la moiti\u00e9 du brio et de la dext\u00e9rit\u00e9 de leurs pr\u00e9d\u00e9cesseurs d&rsquo;il y a trois-quarts de si\u00e8cle. Ils sont effroyablement conventionnels, eux-m\u00eames beaucoup trop bienpensants, bien autant que les ouailles qu&rsquo;ils tentent d&rsquo;enr\u00e9gimenter&#8230; Enfin, comparez un Zelenski, &ndash; par exemple parce que j&rsquo;ai une tendresse pour elle et alors qu&rsquo;elle n&rsquo;a aucun r\u00f4le dans les \u00e9v\u00e9nements \u00e9voqu\u00e9s, &ndash; \u00e0 une Evita Peron, petite actrice douteuse devenue sublime parce que sublim\u00e9e par son r\u00f4le jusqu&rsquo;\u00e0 mourir d&rsquo;un cancer en pleine beaut\u00e9 en priant &laquo; <em>Don&rsquo;t Cry for Me, Argentina <\/em>&raquo;&#8230; Je fais cette comparaison pour exalter ce qu&rsquo;on peut trouver d&rsquo;humainement sublime m\u00eame dans les aventures les plus douteuses. Croyez-vous s\u00e9rieusement qu&rsquo;on fera, dans quarante ans, un spectacle avec un Zelenski exhortant les Ukrainiens \u00e0 cette retenue : \u00ab\u00a0&Ocirc; Ukrainiens, ne pleurez pas pour moi\u00a0\u00bb ?<\/p>\n<\/p>\n<p><p>Je crois pouvoir avancer que ce spectacle du &laquo; <em>&lsquo;Vogue&rsquo; en Zelenskistan<\/em> &raquo; est le symbole final de l&rsquo;effondrement d&rsquo;un syst\u00e8me, &ndash; un syst\u00e8me du Syst\u00e8me, &ndash; devenu totalement impuissant dans l&rsquo;activit\u00e9 pour laquelle il fut cr\u00e9\u00e9 du montage-de-simulacre. M\u00eame l&rsquo;infamie et le mensonge, pour montrer quelque efficacit\u00e9, exigent une certaine capacit\u00e9 de talent, presque de l&rsquo;art, pour que les menteurs et les simulateurs parviennent \u00e0 montrer quelque chose d&rsquo;une certaine sinc\u00e9rit\u00e9 dans leur pratique d\u00e9testable. Nous n&rsquo;avons m\u00eame plus \u00e7a. Nous n&rsquo;avons plus que des menteurs et des simulateurs au c&oelig;ur sec et \u00e0 l&rsquo;\u00e2me vide.<\/p>\n<\/p>\n<p><p>Je crois que m\u00eame le Diable, dont ils sont \u00e9videmment les cr\u00e9atures, n&rsquo;\u00e9prouvent plus \u00e0 leur encontre qu&rsquo;un tr\u00e8s-profond m\u00e9pris teint\u00e9 d&rsquo;une lassitude certaine.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&lsquo;Vogue&lsquo; en Zelenskistan 29 juillet 2022 (19H15) &ndash; Il faut bien dire que le reportage photographique du prestigieux &lsquo;Vogue Magazine&rsquo; sur le couple Zelenski a repr\u00e9sent\u00e9 une \u00e9tape importante dans la manufacture de la r\u00e9alit\u00e9 de la guerre en Zelenskistan. Paradoxalement, ce ne fut pas une image guerri\u00e8re mais une image de communication, affirmant le&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[13826,6120,2631,3532,7501,2645,3371,9692,3851,5713,2766,3965,13670,2829],"class_list":["post-80282","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-caitline","tag-campagne","tag-de","tag-deuxieme","tag-evita","tag-guerre","tag-hollywood","tag-johnstone","tag-mondiale","tag-publiques","tag-relations","tag-simulacre","tag-ukrisis","tag-zelenski"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=80282"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80282\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=80282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=80282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=80282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}