{"id":80291,"date":"2022-08-02T09:14:31","date_gmt":"2022-08-02T09:14:31","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2022\/08\/02\/aout-22-monte-le-grondement-des-tambours\/"},"modified":"2022-08-02T09:14:31","modified_gmt":"2022-08-02T09:14:31","slug":"aout-22-monte-le-grondement-des-tambours","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2022\/08\/02\/aout-22-monte-le-grondement-des-tambours\/","title":{"rendered":"Ao\u00fbt-22, monte le grondement des tambours&#8230;"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Ao&ucirc;t-22, monte le grondement des tambours&#8230;<\/h2>\n<\/p>\n<p><p>02 ao&ucirc;t 2022 (09H15) &ndash; On ne fera pas ici un compte-rendu pr\u00e9cis, ni une prospective non moins d\u00e9taill\u00e9e de la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-verite-de-situation-verite\">v\u00e9rit\u00e9-de-situation<\/a> qui concerne plusieurs situations crisiques en cours de conflagration. Ce n&rsquo;est ni mon habitude, ni dans ma capacit\u00e9, moins encore selon un penchant qui est de garder une distance vis-\u00e0-vis de ce qui est pressant et tend \u00e0 emplir l&rsquo;esprit de confusion, l&rsquo;\u00e2me d&rsquo;\u00e9motions imp\u00e9rieuses et la plume de phrases imp\u00e9ratives.<\/p>\n<\/p>\n<p><p>La seule certitude que nous donnent ces premiers jours d&rsquo;ao&ucirc;t 2022 est que la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-la-gces\">GrandeCrise<\/a> poursuit sa charge, tambour battant.  Cette image des \u00ab\u00a0tambours d&rsquo;ao&ucirc;t 2022\u00a0\u00bb ne cesse de s&rsquo;imposer au jugement comme un sentiment imp\u00e9rieux, une image terrible et se suffisant \u00e0 elle-m\u00eame, par contraste avec toute description significative. Vous devez avoir \u00e0 l&rsquo;esprit simplement cette formule citant un livre fameux sous forme d&rsquo;une analogie, de &lsquo;<em>L&rsquo;extension du domaine de la crise<\/em>&lsquo;. Bien entendu, tout se lit et se lie \u00e0 partir de la matrice commune de la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-la-gces\">GrandeCrise<\/a>. La diagonale est un avatar monstrueux <em>d&rsquo;Ukrisis<\/em>, elle court de l&rsquo;Ukraine \u00e0 Ta\u00efwan et continue d&#8217;embraser le monde en successifs \u00ab\u00a0d\u00e9parts de feu\u00a0\u00bb (ce vocabulaire des grands incendies de for\u00eat du temps des canicules !).<\/p>\n<\/p>\n<p><p><a href=\"https:\/\/news.antiwar.com\/2022\/08\/01\/pelosi-to-visit-taiwan-despite-risk-of-provoking-china\/\">Quoi que fasse<\/a> la &lsquo;vieille dame indigne&rsquo; \u00e0 qui est venue cette id\u00e9e, nullement saugrenue puisque logique selon le d\u00e9veloppement de la folie en-cours, de pr\u00e9tendre visiter les amis de Ta\u00efwan, la Chine est invit\u00e9e avec la plus grande fermet\u00e9 \u00e0 entrer dans le sabbat infernal, <a href=\"https:\/\/www.rt.com\/news\/560039-china-us-pelosi-taiwan\/\">et elle y entre<\/a>. Quels que soient les tenants et les causes de l&rsquo;\u00e9pisode, et je subodore qu&rsquo;ils devraient para&icirc;tre d\u00e9risoires et sans vaste plan pr\u00e9par\u00e9 par rapport \u00e0 l&rsquo;effet obtenu, les aboutissants et les cons\u00e9quences sont que l&rsquo;immense Chine est d\u00e9sormais, <a href=\"https:\/\/www.rt.com\/news\/560032-us-predicts-chinese-military-provocations\/\">presque \u00e0 \u00e9galit\u00e9<\/a> avec la Russie, au c&oelig;ur du bouleversement du monde. Les &Eacute;tats-Unis tiennent parfaitement leur r\u00f4le de boutefeu, d&rsquo;allumer partout les susdits d\u00e9parts de feu alimentant monstrueusement le brasier qui d\u00e9vore l&rsquo;ordre devenu d\u00e9sordre du monde.<\/p>\n<\/p>\n<p><p>&laquo; <em>Le caract\u00e8re ind\u00e9pendant et belliqueux de Mme Pelosi est toutefois mieux r\u00e9sum\u00e9 par un antagonisme de plusieurs d\u00e9cennies avec la Chine<\/em>&#8230; &raquo;, \u00e9crit un de ses ennemis habituels, le commentateur r\u00e9publicain Mark Miller, qui se &laquo; <em>trouve en terrain inconnu, <a href=\"https:\/\/www.dedefensa.org\/article\/rapsit-usa2022-pelosi-joe-le-chinetoque-dogfight-a-la-folie\">ici, en \u00e9tant d&rsquo;accord <\/a><\/em>&raquo; avec tous les actes qu&rsquo;elle pose. C&rsquo;est-\u00e0-dire qu&rsquo;un cas individuel est intervenu, \u00e0 cet instant pr\u00e9cis o&ugrave; la m\u00e8che tra&icirc;nait par terre pr\u00eate \u00e0 \u00eatre allum\u00e9e, pour faire jaillir la flamme qu&rsquo;il faut, sans plan pr\u00e9con\u00e7u j&rsquo;en suis persuad\u00e9 et je le r\u00e9p\u00e8te. D\u00e9sormais Biden et son Covid \u00e0 r\u00e9p\u00e9tition, le Pentagone <a href=\"https:\/\/www.rt.com\/news\/560010-us-carrier-pelosi-taiwan\/\">avec son porte-avions<\/a> USS &lsquo;<em>Ronald Reagan<\/em>&lsquo;, le Congr\u00e8s et le <em>DeepState<\/em>, tous suivent un peu en zig-zag parce qu&rsquo;il faut bien couvrir \u00ab\u00a0Madame <em>Speaker<\/em>\u00ab\u00a0, troisi\u00e8me dans la succession de l&rsquo;autorit\u00e9 supr\u00eame derri\u00e8re un pr\u00e9sident en <em>dementia senile <\/em>et une vice-pr\u00e9sidente dont le talent oratoire est celui d&rsquo;une \u00ab\u00a0salade de mots\u00a0\u00bb relev\u00e9e d&rsquo;\u00e9clats de rire incompr\u00e9hensibles.<\/p>\n<\/p>\n<p><p>Tout cela signifie que Dame Pelosi fait ce qu&rsquo;il lui pla&icirc;t, aucune autorit\u00e9 r\u00e9elle ne la bride, elle est elle-m\u00eame sa propre autorit\u00e9 et donc celle des USA m\u00eame si certains <a href=\"https:\/\/www.rt.com\/news\/560038-blinken-pelosi-taiwan-own-decision\/\">rechignent<\/a> et <a href=\"https:\/\/original.antiwar.com\/buchanan\/2022\/08\/01\/is-taiwans-independence-worth-war\/\">ruent dans les brancards<\/a>. Elle fait ce qu&rsquo;elle entend faire, avec l&rsquo;\u00e9cho qu&rsquo;on lui voit, et c&rsquo;est la chose essentielle et irr\u00e9versible.  Je dis alors simplement que, quoi qu&rsquo;il arrive, que Pelosi pose ou non le pied sur le sol de Ta\u00efwan, je suis conduit \u00e0 juger comme acquise &lsquo;<em>L&rsquo;extension du domaine de la crise<\/em>&lsquo;.<\/p>\n<\/p>\n<p><p>Et il faut bien mesurer, gentils europ\u00e9ens qui ch\u00e9rissent tant l&rsquo;alli\u00e9 transatlantique, ce que cela signifie&#8230; Les USA sont une puissance sans culture ni vision holistique du monde, sinon leur exceptionnalisme compl\u00e8tement auto-concentr\u00e9e. Par cons\u00e9quent, ils arrangent les crises du monde, surtout quand ils en sont la source (cas quasiment exclusif), selon le bon vouloir de leur pouvoir imp\u00e9ratif. (Actuellement, leur \u00a0\u00bb pouvoir imp\u00e9ratif \u00a0\u00bb entre un pr\u00e9sident d\u00e9ment-Covid, une vice-pr\u00e9sident &lsquo;<em>Word Salade<\/em>&lsquo; et Dame Pelosi en excursion asiatique&#8230;) Cela signifie qu&rsquo;ils sont conduits \u00e0 ne voir qu&rsquo;une crise \u00e0 la fois, m\u00eame et surtout s&rsquo;ils en sont la source. Cela signifie qu&rsquo;on <a href=\"https:\/\/www.rt.com\/news\/559993-eu-taiwan-crisis-ukraine\/\">se demande aujourd&rsquo;hui<\/a> :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Les &Eacute;tats-Unis pourraient ne plus accorder la priorit\u00e9 \u00e0 l&rsquo;Ukraine, <\/em>[disent des] <em> m\u00e9dias&#8230;<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Un conflit entre la Chine et Ta\u00efwan pourrait d\u00e9tourner l&rsquo;attention de Washington de Kiev, et cela pr\u00e9occupe l&rsquo;UE<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Et ainsi, dans le plus \u00e9trange et <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-la-tragedie-bouffe\">tragique-bouffe<\/a> des cas, l&rsquo;UE pourrait se retrouver laiss\u00e9e \u00e0 elle-m\u00eame dans un conflit catastrophique avec la Russie, avec la perspective d&rsquo;un automne de fureur et de r\u00e9volution populaires sur ses propres territoires. C&rsquo;est vraiment le <em>Great ReSet<\/em> d&rsquo;une sorte unique de b\u00eatise cosmique et sortie du fond des \u00e2ges et des cavernes du Neandertal.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ao&ucirc;t-22, monte le grondement des tambours&#8230; 02 ao&ucirc;t 2022 (09H15) &ndash; On ne fera pas ici un compte-rendu pr\u00e9cis, ni une prospective non moins d\u00e9taill\u00e9e de la v\u00e9rit\u00e9-de-situation qui concerne plusieurs situations crisiques en cours de conflagration. Ce n&rsquo;est ni mon habitude, ni dans ma capacit\u00e9, moins encore selon un penchant qui est de garder&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[1235,3977,2752,2719,6140,2871,13670],"class_list":["post-80291","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-biden","tag-chine","tag-covid","tag-grandecrise","tag-pelosi","tag-taiwan","tag-ukrisis"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=80291"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80291\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=80291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=80291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=80291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}