{"id":80317,"date":"2022-08-27T16:34:49","date_gmt":"2022-08-27T16:34:49","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2022\/08\/27\/rapsit-usa2022-novembre-du-crepuscule\/"},"modified":"2022-08-27T16:34:49","modified_gmt":"2022-08-27T16:34:49","slug":"rapsit-usa2022-novembre-du-crepuscule","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2022\/08\/27\/rapsit-usa2022-novembre-du-crepuscule\/","title":{"rendered":"RapSit-USA2022 : Novembre du cr\u00e9puscule"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">RapSit-USA2022 : Novembre du cr\u00e9puscule<\/h2>\n<\/p>\n<p><p>Nous ne cessons pas de r\u00e9p\u00e9ter combien, \u00e0 notre sens, les \u00e9lections dites-<em>midterm <\/em>du 8 novembre prochain sont d&rsquo;une importance essentielle pour les USA, donc pour nous en Europe, donc pour la situation du monde. Plus encore que <a href=\"https:\/\/www.dedefensa.org\/article\/rapsit-usa2022-referendum-sur-trump\">les appr\u00e9ciations politiques<\/a>sur la future composition du Congr\u00e8s, qui deviennent incertaines alors qu&rsquo;elles semblaient devoir \u00eatre assur\u00e9es il y a encore quelques semaines, il y a l&rsquo;\u00e9tat d&rsquo;esprit, le climat r\u00e9gnant aux USA.<\/p>\n<\/p>\n<p><p>Les appr\u00e9ciations politiques ne rendent pas compte de ce climat. Elles se concentrent sur les luttes politiciennes, comme actuellement entre les mandarins du parti r\u00e9publicain et Trump avec sa r\u00e9putation de populiste \u00e9tranger au monde politique washingtonien. Tout cela est tellement travers\u00e9 de simulacres et de manipulations de la communication qu&rsquo;il est difficile de se faire une id\u00e9e pr\u00e9cise de la dynamique en cours. On admet alors que la situation politique, ou plut\u00f4t politicienne, cit\u00e9e plus haut n&rsquo;a gu\u00e8re d&rsquo;importance et ne nous dit rien de fondamental sur l&rsquo;\u00e9volution des choses ; en fait, elle se transforme, se transmue d\u00e8s lors qu&rsquo;elle est confront\u00e9e \u00e0 la r\u00e9alit\u00e9, c&rsquo;est-\u00e0-dire aux \u00e9v\u00e9nements politiques o&ugrave; la r\u00e9alit\u00e9 du climat entre en jeu, pour le pire ou le meilleur c&rsquo;est selon.<\/p>\n<\/p>\n<p><p>Les \u00e9lections aux USA de 2022 est l&rsquo;une des plus \u00e9normes de ces occasions, essentiellement parce qu&rsquo;un \u00e9l\u00e9phant est entr\u00e9 dans le magasin de porcelaines et refuse d&rsquo;en sortir. La seule vertu certaine qu&rsquo;on peut reconna&icirc;tre \u00e0 Trump, c&rsquo;est bien d&rsquo;\u00eatre cet \u00e9l\u00e9phant, cela qui fait qu&rsquo;effectivement les \u00e9lections et le jeu politique auxquelles elles contraignent ont une importance capitale et totalement impr\u00e9visibles dans le champ du chambardement et du d\u00e9s\u00e9quilibre. On l&rsquo;a vu \u00e0 plusieurs occasions depuis 2015-2016, c&rsquo;est-\u00e0-dire depuis son arriv\u00e9e, alors qu&rsquo;en 2022 tant de potentialit\u00e9s explosives se sont accumul\u00e9es :<\/p>\n<\/p>\n<p><p>&bull; Personne ne pr\u00e9voyait, ni m\u00eame ne pouvait pr\u00e9voir la victoire de Trump. L&rsquo;\u00e9v\u00e9nement allait contre tous les alignements et les rangements de la politique. Il a eu lieu, exactement comme Michael Moore, pourtant ennemi de Trump, le d\u00e9finissait <a href=\"https:\/\/www.dedefensa.org\/article\/une-election-entre-survie-et-cocktail-molotov\">en octobre 2016<\/a>, comme un \u00ab\u00a0cocktail Molotov humain\u00a0\u00bb, impliquant sa victoire contre tous les sondages, et une victoire rendant compte du climat g\u00e9n\u00e9ral :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Au cours de son interview, Moore a d\u00e9clar\u00e9 que les Am\u00e9ricains consid\u00e9raient Trump comme un \u00ab\u00a0cocktail Molotov humain\u00a0\u00bb. \u00ab\u00a0&Agrave; travers le Midwest et \u00e0 travers la Rustbelt, je comprends pourquoi beaucoup de gens sont en col\u00e8re\u00a0\u00bb, a-t-il d\u00e9clar\u00e9. \u00ab\u00a0Et ils voient Donald Trump comme leur cocktail Molotov humain qu&rsquo;ils vont pouvoir aller jeter \u00e0 la gueule de notre syst\u00e8me politique en allant dans l&rsquo;isoloir le 8 novembre\u00a0\u00bb. \u00ab\u00a0Je pense qu&rsquo;ils aiment l&rsquo;id\u00e9e de faire exploser le syst\u00e8me.\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Moore, qui a pr\u00e9cis\u00e9 qu&rsquo;il ne votera pas pour Trump, a d\u00e9clar\u00e9 que les gens ne pr\u00eatent plus attention aux m\u00e9dias ou aux \u00ab\u00a0gens au pouvoir\u00a0\u00bb. \u00ab\u00a0Les gens ne font pas confiance aux m\u00e9dias, ils ne les \u00e9coutent pas, et pour une bonne raison, &ndash; parce que les m\u00e9dias les ont laiss\u00e9s tomber. Les riches et les puissants les ont laiss\u00e9s tomber. Beaucoup d&rsquo;entre eux avaient l&rsquo;habitude de voter pour les riches et les puissants et ils ne vont plus le faire\u00a0\u00bb<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>&bull; Durant sa pr\u00e9sidence, Trump fut constamment sous la pression de ses adversaires et face \u00e0 la trahison de la plupart des grandes administrations. Cela provoqua l&rsquo;effet de renforcer sa stature de populiste hors-Syst\u00e8me sinon antiSyst\u00e8me, sans vraiment tester les politiques qu&rsquo;il \u00e9tait capable de mettre en &oelig;uvre, et s&rsquo;il \u00e9tait capable de les mettre en &oelig;uvre. (On sait tout de m\u00eame, et ce n&rsquo;est pas \u00e0 son avantage, qu&rsquo;il fit des choix d\u00e9sastreux pour certains des postes les plus importants de son cabinet et des principales agences.) Ainsi, \u00e0 d\u00e9faut d&rsquo;un homme d&rsquo;&Eacute;tat on eut un v\u00e9ritable Mythe que l&rsquo;opposition d\u00e9mocrate (aid\u00e9e en sous-mains par les RINO, ou r\u00e9publicains anti-Trump) s&#8217;employa \u00e0 sans cesse renforcer en lui pr\u00eatant des capacit\u00e9s de \u00ab\u00a0nuisance\u00a0\u00bb (et leurs \u00ab\u00a0nuisances\u00a0\u00bb sont ce qui fait vertu dans l&rsquo;autre camp) qu&rsquo;il n&rsquo;a certainement pas.<\/p>\n<\/p>\n<p><p>Ainsi se poursuivit et se renfor\u00e7a cette atmosph\u00e8re d&rsquo;intense hostilit\u00e9, de climat d&rsquo;antagonisme, aliment\u00e9 par les forces elles-m\u00eames (d\u00e9mocrates et r\u00e9publicains) qui doivent absolument s&rsquo;en \u00e9carter pour esp\u00e9rer pouvoir continuer leurs habituels arrangements. Ce \u00ab\u00a0climat\u00a0\u00bb cr\u00e9\u00e9 par ceux qui doivent s&rsquo;\u00e9carter pour leurs propres int\u00e9r\u00eats, \u00e9clate notamment dans cette sc\u00e8ne extraordinaire du 5 novembre 2020, lorsqu&rsquo;un pr\u00e9sentateur de MSNBC (imit\u00e9 bient\u00f4t par les autres cha&icirc;nes) coupe net la retransmission d&rsquo;une intervention officielle du pr\u00e9sident sortant affirmant qu&rsquo;il y a eu des fraudes dans l&rsquo;\u00e9lection, le pr\u00e9sentateur laissant voir en quelques mots d&rsquo;un intol\u00e9rable et incroyable m\u00e9pris que \u00ab\u00a0ce type ne fait et ne peut que mentir\u00a0\u00bb. Ce moment exceptionnel est consid\u00e9r\u00e9 par <a href=\"https:\/\/www.tvlibertes.com\/i-media-n406-defaire-le-parti-des-medias-avec-martial-bild\">Martial Bild<\/a> et Philippe Millau, dans leur livre &lsquo;<em><a href=\"https:\/\/www.tvlibertes.com\/produit\/martial-bild-philippe-milliau-defaire-le-parti-des-medias\">D\u00e9faire le parti des m\u00e9dias<\/a><\/em>&lsquo;, comme le moment d&rsquo;un \u00ab\u00a0coup d&rsquo;&Eacute;tat m\u00e9diatique\u00a0\u00bb contre le pouvoir politique, &ndash; mais l\u00e0 aussi il s&rsquo;agit paradoxalement, la surpuissance entra&icirc;nant l&rsquo;autodestruction, du d\u00e9cha&icirc;nement du \u00ab\u00a0climat\u00a0\u00bb des choses contre la ma&icirc;trise du jeu politicien, par pure haine (de Trump), donc par pur <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-laffectivisme-postmoderne\">affectivisme<\/a>.<\/p>\n<\/p>\n<p><p>&bull; Ce qui suivit, l&rsquo;entre-deux de Trump \u00e0 Biden, ne fit qu&rsquo;accro&icirc;tre la vigueur de la confrontation, le d\u00e9cha&icirc;nement de la haine, des deux c\u00f4t\u00e9s d&rsquo;ailleurs, c&rsquo;est-\u00e0-dire, pour ce qui nous importe, dans le m\u00eame sens d&rsquo;une poursuite du d\u00e9sordre et d&rsquo;une incapacit\u00e9 des structures traditionnelles des politiciens \u00e0 reprendre le contr\u00f4le de la situation. Ainsi nous promettait-on que la pr\u00e9sidence Biden serait une remise en ordre, un \u00ab\u00a0r\u00e9-alignement\u00a0\u00bb des \u00e9l\u00e9ments du d\u00e9sordre caus\u00e9 par Trump, et ce fut exactement le contraire. Certes, la personnalit\u00e9 de Biden, sa sant\u00e9 fragile qui ne l&rsquo;exon\u00e8re d&rsquo;aucun de ses d\u00e9fauts, son \u00e9tonnante capacit\u00e9 \u00e0 ne rien faire qui pourrait d\u00e9favoriser le d\u00e9sordre (&laquo; <em>Il ne faut jamais sous-estimer la capacit\u00e9 de Joe \u00e0 foutre la merde<\/em> &raquo;, disait aimablement mais fort justement l&rsquo;ancien pr\u00e9sident Obama, lorsque Biden \u00e9tait son vice-pr\u00e9sident), ont constitu\u00e9 un facteur d\u00e9terminant dans l&rsquo;\u00e9chec de la tentative des structures du Syst\u00e8me et du <em>DeepState <\/em>de reprendre la main pour remettre en place les normes de fonctionnement.<\/p>\n<\/p>\n<p><p>&bull; Quoi qu&rsquo;il en soit, on se retrouve \u00e0 la faveur (?) des \u00e9lections-<em>midterms <\/em>exactement dans la m\u00eame situation qu&rsquo;en 2016, au moment o&ugrave; toutes les pr\u00e9visions rationnelles naviguent sur un oc\u00e9an bien connu de l&rsquo;ancien temps, tandis que les variations \u00ab\u00a0climatiques\u00a0\u00bb interviennent dans un autre monde, sur un autre oc\u00e9an, dans des temps nouveaux dont aucun des strat\u00e8ges chevronn\u00e9s des partis politiques n&rsquo;arrive, non seulement \u00e0 \u00eatre quitte mais m\u00eame \u00e0 seulement admettre son existence. <\/p>\n<\/p>\n<p><p>Selon cette analyse de la situation am\u00e9ricaine \u00e0 dix semaines des \u00e9lections &#8211;<em>midterms<\/em>, il nous a paru que la reprise de deux textes successifs de James Howard Kunstler, celui du 22 ao&ucirc;t et celui du 26 ao&ucirc;t, constituait une parfaite illustration de ce \u00ab\u00a0climat\u00a0\u00bb dont nous parlons, bien plus qu&rsquo;une analyse calibr\u00e9e de l&rsquo;un ou l&rsquo;autre \u00ab\u00a0expert\u00a0\u00bb qui se sont r\u00e9v\u00e9l\u00e9s ces derni\u00e8res ann\u00e9es \u00eatre des \u00ab\u00a0machines \u00e0 erreurs\u00a0\u00bb. Par ailleurs, les textes de Kunstler ont la qualit\u00e9 litt\u00e9raire de faire ressortir l&rsquo;extr\u00eame tension, et par cons\u00e9quent l&rsquo;extr\u00eame gravit\u00e9 de la crise du syst\u00e8me de l&rsquo;am\u00e9ricanisme qui est, dans nos organes de communication tendance presseSyst\u00e8me, quasi-compl\u00e8tement ignor\u00e9e. La perception de la situation des USA aujourd&rsquo;hui se r\u00e9sume aux livraisons d&rsquo;armement \u00e0 l&rsquo;Ukraine, &ndash; par ailleurs <a href=\"https:\/\/www.dedefensa.org\/article\/ukrisiset-le-simulacre-de-larmement\">complet simulacre<\/a>bien entendu, &ndash; comme signe de l'\u00a0\u00bbexceptionnalit\u00e9\u00a0\u00bb in\u00e9branlable de l&#8217;empire resplendissant. Kunstler est un antidote contre la sottise et l&rsquo;aveuglement de ce jugement.<\/p>\n<\/p>\n<p><p>L&rsquo;int\u00e9r\u00eat de mettre ces deux textes ensemble est que le premier nous brosse un tableau color\u00e9 des \u00e9v\u00e9nements qui, depuis les Clinton et la fin de la Guerre Froide, ont abouti \u00e0 la situation actuelle ; et que le second est le compl\u00e9ment indispensable, nous d\u00e9crivant ce que Kunstler ressent de la situation pr\u00e9sente, avec notamment un appel h\u00e9ro\u00efque \u00e0 la r\u00e9sistance et \u00e0 la restauration de la dignit\u00e9.<\/p>\n<\/p>\n<p><h4><em>dedefensa.org<\/em><\/h4>\n<\/p>\n<p><p>_________________________<\/p>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Le pays des fous<\/h2>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepblue\" style=\"color:#0f3955; font-size:1.25em\">Le suicide \u00e9conomique et culturel n&rsquo;est pas la seule option&#8230;<\/h3>\n<\/p>\n<p><p>Lors d&rsquo;une r\u00e9union d&rsquo;amis par une chaude soir\u00e9e ce week-end, quelqu&rsquo;un a demand\u00e9 : Pensez-vous que ce qui se passe est d&ucirc; \u00e0 l&rsquo;incomp\u00e9tence ou \u00e0 la malveillance ? Les &Eacute;tats-Unis sont certainement en train de d\u00e9raper vers un grand et traumatisant retour en arri\u00e8re, avec un niveau de vie beaucoup plus bas pour la plupart des citoyens, au milieu d&rsquo;un tas d&rsquo;institutions bris\u00e9es. Mais il en va de m\u00eame pour toutes les autres nations de la civilisation occidentale. Si ce n&rsquo;est pas g\u00e9r\u00e9 par des forces malignes, comme <em>der Schwabenklaus <\/em>et ses mirlitons du WEF, alors cela ressemble \u00e0 une sorte de d\u00e9molition contr\u00f4l\u00e9e. La grande question qui plane sur les \u00e9lections de 2022 est donc la suivante : L&rsquo;Am\u00e9rique doit-elle se suicider ?<\/p>\n<\/p>\n<p><p>Qu&rsquo;est-ce qui a provoqu\u00e9 la maladie mentale de la gauche ? Qu&rsquo;est-ce qui a transform\u00e9 le parti d\u00e9mocrate en parti du chaos ? Il semblait plut\u00f4t sain d&rsquo;esprit en 1996 lorsque le pr\u00e9sident Bill Clinton a d\u00e9clar\u00e9, &ndash; \u00e0 la surprise g\u00e9n\u00e9rale, &ndash; dans son discours sur l&rsquo;\u00e9tat de l&rsquo;Union que &laquo; l&rsquo;\u00e8re du grand gouvernement est termin\u00e9e &raquo;. Bien s&ucirc;r, peu de gens ont compris \u00e0 l&rsquo;\u00e9poque \u00e0 quel point les Clinton \u00e9taient l\u00e2chement corrompus, d&rsquo;autant plus que Hillary a lanc\u00e9 sa propre carri\u00e8re politique une fois le tour de Bill termin\u00e9. Peu de gens, j&rsquo;ose le dire, pensaient \u00e0 l&rsquo;\u00e9poque qu&rsquo;Hillary finirait par \u00e9clipser Bill en termes d&rsquo;influence ; depuis, on a fini par admettre que la premi\u00e8re dame agissait comme la m\u00e9galomane d\u00e9mente qu&rsquo;elle s&rsquo;est r\u00e9v\u00e9l\u00e9e \u00eatre.<\/p>\n<\/p>\n<p><p>Dieu seul sait ce qui s&rsquo;est pass\u00e9 dans ce mariage shakespearien&#8230; mais le parti d\u00e9mocrate, dans les ann\u00e9es Hillary post\u00e9rieures \u00e0 2000, a d\u00e9couvert que son existence m\u00eame exigeait que le gouvernement devienne de plus en plus gros, car l&rsquo;\u00e9conomie am\u00e9ricaine, &ndash; l&rsquo;\u00e9conomie r\u00e9elle, sur le terrain, en dehors de la salle des miroirs de la financiarisation de Wall Street, &ndash; \u00e9tait en train de d\u00e9p\u00e9rir avec la d\u00e9localisation de l&rsquo;industrie et il fallait quelque chose pour la remplacer. Et, soit dit en passant, pr\u00e9cisons que le parti r\u00e9publicain a encourag\u00e9 tout cela, malgr\u00e9 les grondements passagers de ses \u00ab\u00a0ren\u00e9gats\u00a0\u00bb du Tea Party.<\/p>\n<\/p>\n<p><p>Pardonnez-moi \u00e0 ce stade de r\u00e9p\u00e9ter ma th\u00e9orie de l&rsquo;histoire maintes fois \u00e9nonc\u00e9e : <em>Les choses arrivent parce qu&rsquo;elles semblent \u00eatre une bonne id\u00e9e sur le moment<\/em>. La d\u00e9localisation semblait \u00eatre une bonne id\u00e9e \u00e0 l&rsquo;\u00e9poque. Refiler toutes ces usines sales et polluantes \u00e0 d&rsquo;autres pays, et payer les indig\u00e8nes trois dollars par jour pour qu&rsquo;ils fabriquent tous les produits dont nous avons besoin. En plus, on payait ces produits avec des bons du Tr\u00e9sor am\u00e9ricain. Quel racket ! Mais ensuite, toutes les activit\u00e9s en Am\u00e9rique se sont transform\u00e9es en racket, &ndash; c&rsquo;est-\u00e0-dire gagner de l&rsquo;argent de mani\u00e8re malhonn\u00eate, &ndash; jusqu&rsquo;\u00e0 devenir le milieu \u00e9conomique totalitaire du pays. M\u00eame les deux entreprises les plus nobles de notre soci\u00e9t\u00e9, l&rsquo;\u00e9ducation et la m\u00e9decine, se sont d\u00e9shonor\u00e9es en s&rsquo;enrichissant sans vergogne.<\/p>\n<\/p>\n<p><p>Il s&rsquo;est pass\u00e9 quelque chose d&rsquo;\u00e9trange \u00e0 partir de 2004, lorsqu&rsquo;un certain Barack Obama est mont\u00e9 sur sc\u00e8ne lors de la convention d\u00e9mocrate qui a d\u00e9sign\u00e9 cette superbe coupe de cheveux \u00e0 la recherche d&rsquo;un cerveau appel\u00e9e John Kerry. La nouvelle star a illumin\u00e9 la convention en se pr\u00e9sentant comme un grand rassembleur. Et quatre ans plus tard, il a ridiculis\u00e9 Hillary, l&#8217;emp\u00eachant de saisir son tour suppos\u00e9 in\u00e9luctable, &ndash; et son triomphe supr\u00eame en per\u00e7ant le plafond de verre,  &ndash; en tant que pr\u00e9sidente. D&rsquo;o&ugrave; venait-il ? Cet organisateur communautaire qui battait le pav\u00e9 avec un sourire \u00e0 1000 watts ?<\/p>\n<\/p>\n<p><p>R\u00e9trospectivement, Barack Obama semble avoir \u00e9t\u00e9 fabriqu\u00e9 \u00e0 partir d&rsquo;une cabale marxiste fumeuse de l&rsquo;extr\u00eame gauche qui infestait les sous-sols du parti d\u00e9mocrate. Il est arriv\u00e9 \u00e0 bord en 2009, juste au moment o&ugrave; toute cette financiarisation squelettique a fait exploser les banques et lanc\u00e9 l&rsquo;\u00e8re des op\u00e9rations de sauvetage gouvernementales qui ont alourdi le fardeau d\u00e9j\u00e0 ing\u00e9rable des &Eacute;tats-Unis de quantit\u00e9s inimaginables de dettes. Le r\u00e9publicain George Bush II a \u00e9t\u00e9 bl\u00e2m\u00e9 pour tout cela et Obama a continu\u00e9 \u00e0 aggraver la situation.<\/p>\n<\/p>\n<p><p>Barack Obama a \u00e9t\u00e9 le troph\u00e9e du Grand Chelem du lib\u00e9ralisme, la pierre angulaire de la grande croisade pour les droits civiques : un pr\u00e9sident noir, preuve de la droiture morale de l&rsquo;Am\u00e9rique. Il n&rsquo;a pratiquement rien fait pour changer les conditions qui avaient d\u00e9truit l&rsquo;Am\u00e9rique noire, &ndash; \u00e0 savoir les politiques paternalistes qui ont bris\u00e9 les familles, &ndash; mais il a fait bonne figure alors que le pays vacillait sur le plan \u00e9conomique. Et remarquez que son minist\u00e8re de la justice, sous la direction du procureur g\u00e9n\u00e9ral Eric Holder, a r\u00e9ussi \u00e0 \u00e9viter de poursuivre quiconque, \u00e0 l&rsquo;exception du vampire des pr\u00eats hypoth\u00e9caires Angelo Mozilo, pour tous les crimes bancaires de l&rsquo;\u00e9poque. Pendant ce temps, le pr\u00e9sident Obama <em>s&rsquo;est occup\u00e9<\/em>d&rsquo;Hillary en la nommant secr\u00e9taire d&rsquo;&Eacute;tat, dans cette fonction d&rsquo;o&ugrave; elle a fait rentrer des dizaines de millions de dollars dans les coffres de la Fondation Clinton. Des mouvements fluides. En fin de compte, Obama est rest\u00e9 une \u00e9nigme, passant le flambeau \u00e0 Son In\u00e9vitabilit\u00e9 Hillary en 2016, &ndash; qu&rsquo;elle a commenc\u00e9 \u00e0 \u00e9teindre compl\u00e8tement en surestimant son propre charme politique, &ndash; elle n&rsquo;en avait aucun, &ndash; et en sous-estimant l&rsquo;attrait de son adversaire, le Golem dor\u00e9 de la Grandeur, Donald Trump.<\/p>\n<\/p>\n<p><p>L&rsquo;\u00e9tonnante victoire de Trump a apparemment d\u00e9sorient\u00e9 l&rsquo;esprit d&rsquo;Hillary. Elle aurait \u00e9t\u00e9 trop ivre le soir de l&rsquo;\u00e9lection pour se pr\u00e9senter sur le podium et prononcer l&rsquo;insupportable discours reconnaissant la victoire de son adversaire. Mais l&rsquo;op\u00e9ration de collusion russe [le &lsquo;<em>Russiagate<\/em>&lsquo;] qu&rsquo;elle avait mis en musique des mois plus t\u00f4t avait d\u00e9j\u00e0 mis en branle une grande machine \u00e0 vengeance que les partisans du DOJ, du FBI, de la CIA et du D\u00e9partement d&rsquo;&Eacute;tat ont fait tourner pendant toute la dur\u00e9e du mandat de Trump \u00e0 la Maison Blanche, jusqu&rsquo;\u00e0 l&rsquo;apog\u00e9e des fraudes \u00e9lectorales orchestr\u00e9es de 2020, installant \u00e0 la Maison-Blanche la coquille vide de Barack Obama, une doublure connue sous le nom de \u00ab\u00a0Joe Biden\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>Les pathologies amalgam\u00e9es du r\u00e8gne de Barack Obama &#8211; qui comprend la naissance de royaume de <em>Wokery <\/em>[*], la croisade jacobine-marxiste visant \u00e0 saccager la culture et l&rsquo;\u00e9conomie, &ndash; et la soif psychotique de vengeance d&rsquo;Hillary Clinton ont transform\u00e9 les D\u00e9mocrates en Parti du Chaos, pr\u00e9sidant au suicide de l&rsquo;Am\u00e9rique, et de la civilisation occidentale avec elle. Cela, bien s&ucirc;r, induit la question : Qui dirige exactement Barack Obama ? Je ne pr\u00e9tends pas le savoir \u00e0 ce stade. Beaucoup de gens que je connais sont s&ucirc;rs qu&rsquo;il s&rsquo;agit d&rsquo;une clique bancaire internationale. Ce qui ne colle pas, c&rsquo;est le manque total de charme politique de cette suppos\u00e9e clique bancaire. Personne dans la soci\u00e9t\u00e9 occidentale n&rsquo;est pour eux, dans le sens o&ugrave; ils offrent un programme de salut avec soit les d\u00e9sordres de la culture Woke, soit les d\u00e9sordres du globalisme \u00e9conomique qui s&rsquo;effondre.<\/p>\n<\/p>\n<p><p>Les myst\u00e8res abondent maintenant, et ils sont d\u00e9concertants \u00e0 l&rsquo;extr\u00eame. Comment la soci\u00e9t\u00e9 polie et rationnelle qu&rsquo;est le Canada a-t-elle pu tomber sous l&#8217;emprise grotesque de ce Justin Trudeau ?  De m\u00eame que l&rsquo;Australie et la Nouvelle-Z\u00e9lande, apparemment touch\u00e9es par la m\u00eame d\u00e9mence ? Idem pour les Europ\u00e9ens, qui ont suivi la campagne absurde de l&rsquo;Am\u00e9rique visant \u00e0 faire de l&rsquo;Ukraine une zone de guerre, et qui sont maintenant confront\u00e9s \u00e0 un hiver sans combustible pour l&rsquo;industrie ou le chauffage domestique, &ndash; et peut-\u00eatre \u00e0 une descente vers un nouveau m\u00e9di\u00e9valisme. Peut-\u00eatre que l&#8217;embrouille du Covid a institu\u00e9 tout cela, elle les a juste pouss\u00e9s au terme. (Et ils apprendront bient\u00f4t quelle arnaque mortelle c&rsquo;\u00e9tait, surtout la fonction &quot;vaccin&quot;).<\/p>\n<\/p>\n<p><p>Personnellement, je pense que nous sous-estimons les tendances de l&rsquo;histoire en tant que telle. La tendance actuelle se r\u00e9sume dans l&rsquo;ensemble des circonstances qui s&rsquo;ajoutent \u00e0 une Longue Urgence, alias &lsquo;<em><a href=\"https:\/\/trendsandtrackrecords.com\/the-fourth-turning-theory-2020s-and-beyond\/\">The Fourth Turning<\/a><\/em>&lsquo;, alias &lsquo;<em>The Long Descent<\/em>&lsquo; de  <a href=\"https:\/\/en.wikipedia.org\/wiki\/John_Michael_Greer\">J.M. Greer<\/a>. En clair, nous sortons de la fiesta techno-industrielle des quelque 200 derni\u00e8res ann\u00e9es et entrons dans le territoire inexplor\u00e9 de ce qui va suivre, ce qui est \u00e0 l&rsquo;origine de l&rsquo;immense anxi\u00e9t\u00e9 de notre \u00e9poque. Notre mod\u00e8le \u00e9conomique pour toutes les fonctions est bris\u00e9, principalement parce que la situation des combustibles fossiles est devenue si incertaine. Cela nous rend fous. Comprenez cela et vous aurez suffisamment de mat\u00e9riel mental et bon \u00e9tat de fonctionnement pour rester sain d&rsquo;esprit.<\/p>\n<\/p>\n<p><p>Le suicide est loin d&rsquo;\u00eatre la seule option. R\u00e9sistez \u00e0 ceux qui veulent vous y entra&icirc;ner. Nous allons continuer d&rsquo;une mani\u00e8re ou d&rsquo;une autre. Nous allons passer \u00e0 travers ce goulot d&rsquo;\u00e9tranglement. Laissez les fous enterrer les fous. Gardez les yeux ouverts, gardez le c&oelig;ur ouvert, et gardez votre poudre s\u00e8che.<\/p>\n<\/p>\n<p><h4>Howard J. Kunstler, <a href=\"https:\/\/kunstler.com\/clusterfuck-nation\/crazyland-2\/\">22 ao&ucirc;t 2022<\/a><\/h4>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Un vent mauvais<\/h2>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepblue\" style=\"color:#0f3955; font-size:1.25em\">Quelque chose est en train d&rsquo;arriver&#8230; Tout le monde le sent<\/h3>\n<\/p>\n<p><p>Quelque chose d&rsquo;inqui\u00e9tant flotte dans la brise de la fin de l&rsquo;\u00e9t\u00e9 alors que notre pays, et la soci\u00e9t\u00e9 occidentale avec lui, bascule dans la saison des t\u00e9n\u00e8bres croissantes. Le sentez-vous ? La mort est dans l&rsquo;air, et pas dans le mode vaudeville habituel d&rsquo;Halloween, avec les zombies de pelouse qui caquettent et les squelettes \u00e0 chapeau haut-de-forme qui font des claquettes. Ce n&rsquo;est pas une plaisanterie.<\/p>\n<\/p>\n<p><p>Nous n&rsquo;avons jamais \u00e9t\u00e9 aussi peu pr\u00e9par\u00e9s \u00e0 une calamit\u00e9 qui se d\u00e9roule au vu et au su de tous, et cela parce que les gens qui dirigent les choses ont fait en sorte que cela se produise dans des actes combin\u00e9s de m\u00e9chancet\u00e9 et de stupidit\u00e9. Apr\u00e8s des d\u00e9cennies de simple racket, arrangeant les choses de mani\u00e8re \u00e0 mettre en faillite quiconque tombe gravement malade, les soins de sant\u00e9 corporatis\u00e9s pr\u00e9sident maintenant \u00e0 une moisson de mort induite par la m\u00e9decine, en pr\u00e9tendant b\u00eatement qu&rsquo;il n&rsquo;y a rien \u00e0 voir.<\/p>\n<\/p>\n<p><p>Les gens le voient maintenant et en parlent, et rien ne les emp\u00eachera de d\u00e9couvrir exactement ce qui s&rsquo;est pass\u00e9, ni d&rsquo;exprimer leur col\u00e8re apr\u00e8s coup. L&rsquo;architecte en chef de cette d\u00e9b\u00e2cle \u00e9pique, le Dr Anthony Fauci, le capitaine Queeg de la sant\u00e9 publique am\u00e9ricaine, a annonc\u00e9 son d\u00e9part de la sc\u00e8ne &laquo; pour \u00e9crire le prochain chapitre de ma carri\u00e8re &raquo;. Il n&rsquo;a pas pr\u00e9cis\u00e9 ce que cela pourrait \u00eatre. Je pense que le titre du poste est : plaidoirie de d\u00e9fense. Ce sera une \u00e9tape importante dans l&rsquo;histoire de l&rsquo;humanit\u00e9 que d&rsquo;assister au proc\u00e8s de la Science elle-m\u00eame, si elle vit assez longtemps. Qu&rsquo;est-ce qui nous attend pour prendre sa place ? Des vizirs avec des baguettes et des chapeaux pointus ? Des bourdons chevauchant des balais contre une lune froide et sans vie ? Une principaut\u00e9 de magie noire ? Une descente aux enfers ?<\/p>\n<\/p>\n<p><p>L&rsquo;interruption m\u00e9dicale de la vie \u00e0 grande \u00e9chelle accompagne l&rsquo;effort actuel pour provoquer le suicide de la culture et de la nation, &ndash; toujours plus de d\u00e9pravation et de folie orchestr\u00e9es. Les institutions sont retourn\u00e9es contre nous comme des lance-flammes. Le FBI pourrait bien d\u00e9foncer votre porte dans sa qu\u00eate de suppression de la dissidence. Les compositeurs de l&rsquo;intoxication mentale officielle ne dorment jamais, s&rsquo;assurant que vous ne saurez pas o&ugrave; se trouve le bout de quelque chose de la v\u00e9rit\u00e9. Vos l\u00e9gislateurs aveugles viennent de d\u00e9cider l&rsquo;engagement de 87 000 nouveaux agents du fisc [**] pour vos fesses, comme si c&rsquo;\u00e9tait une bonne id\u00e9e. Les tribunaux existent pour prot\u00e9ger le Parti, mais de quel parti s&rsquo;agit-il ? (Quelle importance, \u00e0 ce stade ? dit Hillary Clinton.) Allez vous plaindre de ces pr\u00e9tendus droits constitutionnels ailleurs, comme sur Twitter et Facebook, o&ugrave; ils peuvent \u00eatre effac\u00e9s d\u00e8s que vous appuyez sur le bouton \u00ab\u00a0Post\u00a0\u00bb. Vous serez bient\u00f4t mort, de toutes les fa\u00e7ons.<\/p>\n<\/p>\n<p><p>Nous avons entendu ad nauseam que les initi\u00e9s de Washington DC, les habitants de ce demi-mythique Deep State dans la zone m\u00e9tropolitaine la plus riche de tout le pays, regardent de haut le reste de l&rsquo;Am\u00e9rique. Pourquoi cela ? Je vais vous le dire. Parce que la conf\u00e9d\u00e9ration d&rsquo;escrocs de D.C. s&rsquo;est engraiss\u00e9e sur votre souffrance alors qu&rsquo;elle a syst\u00e9matiquement d\u00e9truit et pill\u00e9 le reste de l&rsquo;Am\u00e9rique, et mis la classe moyenne en perdition. Ils vivent dans un confort fabuleux de vos b\u00eatises et de votre ruine. Leur m\u00e9pris pour vous se d\u00e9veloppe sur votre effondrement tragique comme un champignon sur un arbre autrefois puissant qui se serait effondr\u00e9. Ils ont pr\u00e9valu dans ce monde et pas vous. Vous \u00eates \u00e0 &lsquo;<em><a href=\"https:\/\/en.wikipedia.org\/wiki\/Palookaville_(film)\">Palookaville<\/a><\/em>&lsquo;, en route pour l&rsquo;ossuaire, et donc ils sont meilleurs que vous, ha ha ha.<\/p>\n<\/p>\n<p><p>Il y a un autre c\u00f4t\u00e9 de cette vie, au cas o&ugrave; tout cela vous aurait d\u00e9moralis\u00e9. C&rsquo;est le c\u00f4t\u00e9 o&ugrave; les \u00eatres humains disent des choses qui correspondent \u00e0 la r\u00e9alit\u00e9, o&ugrave; les gens pensent ce qu&rsquo;ils disent et utilisent le langage comme s&rsquo;il avait \u00e9volu\u00e9 pour d\u00e9crire les choses et les actions avec une certaine exactitude, &ndash; comme ceci est ceci et cela est cela&#8230; et non l&rsquo;inverse ou le contraire. C&rsquo;est le c\u00f4t\u00e9 de la vie o&ugrave; faire semblant n&rsquo;est pas la meilleure utilisation de l&rsquo;intelligence humaine. Je sais, de nos jours, il est difficile d&rsquo;imaginer ce c\u00f4t\u00e9 de la vie, mais il est en fait toujours l\u00e0, attendant d&rsquo;\u00eatre r\u00e9anim\u00e9.<\/p>\n<\/p>\n<p><p>Le r\u00e9gime qui a mis notre monde sens dessus dessous dans sa qu\u00eate satanique de confort et de pouvoir sera mis \u00e0 nu et jug\u00e9, sinon par des juges officiels, du moins par un consensus imparable. Le public endolori fera l&rsquo;inventaire de ce qui a \u00e9t\u00e9 perdu et commencera \u00e0 reconstruire un \u00e9chafaudage de vie partag\u00e9e qui r\u00e9compense la fid\u00e9lit\u00e9 \u00e0 la fa\u00e7on dont les choses fonctionnent r\u00e9ellement. Ce sera un passage difficile pour sortir de ce qui s&rsquo;apparente \u00e0 une prise d&rsquo;otages. Il y aura des frictions et du feu. Vous ne serez pas \u00e0 l&rsquo;aise, mais vous serez intr\u00e9pides. Vous n&rsquo;aurez certainement pas un parcours facile et vous ne serez pas heureux de cela. Vous aurez, au moins, un souvenir restaur\u00e9 de ce que c&rsquo;\u00e9tait que de lutter honorablement pour une vie digne d&rsquo;\u00eatre v\u00e9cue.<\/p>\n<\/p>\n<p><p>Nous sommes en ce moment dans le creuset de tout cela, o&ugrave; tout est chauff\u00e9 \u00e0 blanc. Ne pliez pas et ne vous dissolvez pas. Passez au travers. Soyez des hommes et des femmes (il n&rsquo;y a vraiment rien entre les deux, et ne tombez pas dans les pi\u00e8tres incitations \u00e0 en douter). Vous \u00eates fr\u00e8res et s&oelig;urs dans une entreprise qui m\u00e9rite d&rsquo;\u00eatre sauv\u00e9e et vous avez une histoire qui m\u00e9rite d&rsquo;\u00eatre d\u00e9fendue. Croyez-le.<\/p>\n<\/p>\n<p><h4>Howard J. Kunstler, <a href=\"https:\/\/kunstler.com\/clusterfuck-nation\/an-ill-wind\/\">26 ao&ucirc;t 2022<\/a><\/h4>\n<\/p>\n<p><h2 class=\"titleset_c.deepblue\" style=\"color:#0f3955; font-size:1.25em\">Notes [Ndlr]<\/h2>\n<\/p>\n<p><p>[*] On appr\u00e9ciera le mot que, pour notre compte, nous rencontrons pour la premi\u00e8re fois, de &lsquo;<em>Wockery<\/em>&lsquo; \u00e0 partir de &lsquo;<em>Woke<\/em>&lsquo;. La proximit\u00e9 avec &lsquo;Moquerie&rsquo; est \u00e0 la gloire des deux langues.<\/p>\n<\/p>\n<p><p>[**] En m\u00eame temps que le recrutement de 87 000 agents, il faut pr\u00e9ciser que ces fonctionnaires seront autoris\u00e9s \u00e0 \u00eatre arm\u00e9s et que l&rsquo;administration des imp\u00f4ts a l&rsquo;autorisation d&rsquo;ouvrir des camps de d\u00e9tention pour \u00ab\u00a0mauvais payeurs\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>Mis en migne le 27 ao&ucirc;t 2022 \u00e0 16H00<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>RapSit-USA2022 : Novembre du cr\u00e9puscule Nous ne cessons pas de r\u00e9p\u00e9ter combien, \u00e0 notre sens, les \u00e9lections dites-midterm du 8 novembre prochain sont d&rsquo;une importance essentielle pour les USA, donc pour nous en Europe, donc pour la situation du monde. Plus encore que les appr\u00e9ciations politiquessur la future composition du Congr\u00e8s, qui deviennent incertaines alors&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[21],"tags":[3228,2631,2651,4141,8118,9842,6208,3014,2639],"class_list":["post-80317","post","type-post","status-publish","format-standard","hentry","category-breves-de-crise","tag-crise","tag-de","tag-du","tag-elections","tag-lamericanisme","tag-midterm","tag-obama","tag-systeme","tag-trump"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80317","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=80317"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80317\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=80317"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=80317"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=80317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}